{"id":43416,"date":"2023-08-02T16:13:44","date_gmt":"2023-08-02T16:13:44","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/02\/decreto-1661-de-2011\/"},"modified":"2023-08-02T16:13:44","modified_gmt":"2023-08-02T16:13:44","slug":"decreto-1661-de-2011","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/02\/decreto-1661-de-2011\/","title":{"rendered":"DECRETO 1661 DE 2011"},"content":{"rendered":"\n<p>DECRETO 1661 DE 2011 \u00a0 \u00a0\u00a0<\/p>\n<p>(mayo 23) \u00a0 \u00a0<\/p>\n<p>D.O. 48.078, mayo 23 de 2011 \u00a0 \u00a0<\/p>\n<p>por el cual se nombran miembros \u00a0principales y suplentes en la Junta Directiva de la C\u00e1mara de Comercio de \u00a0Ibagu\u00e9. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, en ejercicio de \u00a0las facultades constitucionales y legales, en especial de las conferidas por el \u00a0numeral 13 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica, \u00a0art\u00edculo 80 del Decreto ley 410 de \u00a01971 y el Decreto 898 de 2002, \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que de acuerdo con lo dispuesto en el art\u00edculo 80 del \u00a0C\u00f3digo de Comercio, el Gobierno Nacional estar\u00e1 representado en las Juntas \u00a0Directivas de las C\u00e1maras de Comercio hasta en una tercera parte de cada Junta. \u00a0 \u00a0<\/p>\n<p>Que el art\u00edculo 12 del Decreto 898 de 2002, \u00a0establece que las Juntas Directivas de las C\u00e1maras de Comercio se integrar\u00e1n \u00a0teniendo en cuenta el n\u00famero de comerciantes con matr\u00edcula vigente al 31 de \u00a0diciembre del a\u00f1o inmediatamente anterior al que se realice la elecci\u00f3n, de la \u00a0siguiente manera: \u00a0 \u00a0<\/p>\n<p>1. Las C\u00e1maras de Comercio que tengan hasta 15.000 \u00a0comerciantes, seis (6) miembros principales y seis (6) suplentes personales. \u00a0 \u00a0<\/p>\n<p>2. Las C\u00e1maras de Comercio con m\u00e1s de 15.000 y hasta \u00a030.000 comerciantes, nueve (9) miembros principales y nueve (9) miembros \u00a0suplentes personales. \u00a0 \u00a0<\/p>\n<p>3. Las C\u00e1maras de Comercio con m\u00e1s de 30.000 comerciantes, \u00a0doce (12) miembros principales y doce (12) miembros suplentes personales. \u00a0 \u00a0<\/p>\n<p>Que de conformidad con las normas citadas y seg\u00fan cuadro \u00a0suministrado por la Superintendencia de Industria y Comercio, la Representaci\u00f3n \u00a0del Gobierno Nacional en la Junta Directiva de la C\u00e1mara de Comercio de Ibagu\u00e9, \u00a0corresponde a un total de tres (3) miembros principales y tres (3) miembros \u00a0suplentes, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. N\u00f3mbrase al doctor Jaime Barreto Quiroga, \u00a0identificado con la c\u00e9dula de ciudadan\u00eda n\u00famero 14228896 de Ibagu\u00e9, como \u00a0Miembro Principal en representaci\u00f3n del Gobierno Nacional en la Junta Directiva \u00a0de la C\u00e1mara de Comercio de Ibagu\u00e9. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. N\u00f3mbrase al doctor Javier Guzm\u00e1n D\u00edaz, \u00a0identificado con la c\u00e9dula de ciudadan\u00eda n\u00famero 14217811, como Miembro Suplente \u00a0del doctor Jaime Barreto, en representaci\u00f3n del Gobierno Nacional en la Junta \u00a0Directiva de la C\u00e1mara de Comercio de Ibagu\u00e9. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00b0. N\u00f3mbrase al doctor Ricardo Gartner Escobar, \u00a0identificado con la c\u00e9dula de ciudadan\u00eda n\u00famero 80411969 de Bogot\u00e1, como \u00a0Miembro Principal en representaci\u00f3n del Gobierno Nacional en la Junta Directiva \u00a0de la C\u00e1mara de Comercio de Ibagu\u00e9. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 4\u00b0. N\u00f3mbrase al doctor Wilson Meza Rinc\u00f3n, \u00a0identificado con la c\u00e9dula de ciudadan\u00eda n\u00famero 91225996 de Bucaramanga, como \u00a0Miembro Suplente del doctor Ricardo Gartner, en representaci\u00f3n del Gobierno \u00a0Nacional en la Junta Directiva de la C\u00e1mara de Comercio de Ibagu\u00e9. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 5\u00b0. N\u00f3mbrase al doctor Nelson Norbey Quintero \u00a0Melo, identificado con la c\u00e9dula de ciudadan\u00eda n\u00famero 93356867 de Ibagu\u00e9, como \u00a0Miembro Principal en representaci\u00f3n del Gobierno Nacional en la Junta Directiva \u00a0de la C\u00e1mara de Comercio de Ibagu\u00e9. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 6\u00b0. N\u00f3mbrase al doctor Francisco Bejarano \u00a0Rodr\u00edguez, identificado con la c\u00e9dula de ciudadan\u00eda n\u00famero 79856226, como \u00a0Miembro Suplente del doctor Nelson Norbey Quintero, en representaci\u00f3n del \u00a0Gobierno Nacional en la Junta Directiva de la C\u00e1mara de Comercio de Ibagu\u00e9. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 7\u00b0. Los nuevos Directivos nombrados, deber\u00e1n \u00a0posesionarse ante la Junta Directiva de la respectiva C\u00e1mara de Comercio. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 8\u00b0. El presente decreto rige a partir de la fecha \u00a0de su publicaci\u00f3n y deroga las disposiciones que le sean contrarias. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese, comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 23 de mayo de 2011. \u00a0 \u00a0<\/p>\n<p>JUAN MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>El Ministro de Comercio, Industria y Turismo, \u00a0 \u00a0<\/p>\n<p>Sergio D\u00edaz-Granados Guida. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 1661 DE 2011 \u00a0 \u00a0\u00a0 (mayo 23) \u00a0 \u00a0 D.O. 48.078, mayo 23 de 2011 \u00a0 \u00a0 por el cual se nombran miembros \u00a0principales y suplentes en la Junta Directiva de la C\u00e1mara de Comercio de \u00a0Ibagu\u00e9. \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, en ejercicio de \u00a0las facultades constitucionales y legales, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-43416","post","type-post","status-publish","format-standard","hentry","category-decretos-2011"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/43416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=43416"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/43416\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=43416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=43416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=43416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}