{"id":43548,"date":"2023-08-02T16:16:30","date_gmt":"2023-08-02T16:16:30","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/02\/decreto-2591-de-2011\/"},"modified":"2023-08-02T16:16:30","modified_gmt":"2023-08-02T16:16:30","slug":"decreto-2591-de-2011","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/02\/decreto-2591-de-2011\/","title":{"rendered":"DECRETO 2591 DE 2011"},"content":{"rendered":"\n<p>DECRETO 2591 DE 2011 \u00a0 \u00a0\u00a0<\/p>\n<p>(julio 19) \u00a0 \u00a0<\/p>\n<p>D.O. 48.135, \u00a0julio 19 de 2011 \u00a0 \u00a0<\/p>\n<p>por el cual se \u00a0ordena la publicaci\u00f3n del Proyecto de Acto Legislativo n\u00famero 216 de 2011 \u00a0C\u00e1mara &#8211; 020 de 2011 Senado, \u201cpor el cual se reforma el numeral 4 del art\u00edculo \u00a0235, el art\u00edculo 250 y el numeral 1 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica\u201d \u00a0(Primera Vuelta). \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, en \u00a0cumplimiento de lo dispuesto por el art\u00edculo 375 de la Constituci\u00f3n Pol\u00edtica, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que el honorable Congreso de la Rep\u00fablica, \u00a0remiti\u00f3 a la Presidencia de la Rep\u00fablica, para el tr\u00e1mite pertinente, el \u00a0Proyecto de Acto Legislativo n\u00famero 216 de 2011 C\u00e1mara, 020 de 2011 Senado, \u00a0\u201cpor el cual se reforma el numeral 4 del art\u00edculo 235, el art\u00edculo 250 y el \u00a0numeral 1 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica\u201d \u00a0(Primera Vuelta). \u00a0 \u00a0<\/p>\n<p>Que con oficio de fecha 27 de de abril de \u00a02011, dirigido al Presidente de la C\u00e1mara de Representantes, los Representantes \u00a0a la C\u00e1mara Carlos Arturo Correa Mojica, Gustavo Hern\u00e1n Puentes D\u00edaz, Camilo \u00a0Andr\u00e9s Abril Jaimes, Miguel G\u00f3mez Mart\u00ednez, Carlos Germ\u00e1n Navas Talero, \u00a0Hernando Alfonso Prada Gil, Rub\u00e9n Dar\u00edo Rodr\u00edguez G\u00f3ngora, Juan Carlos Salazar \u00a0Uribe, Germ\u00e1n Var\u00f3n Cotrino y Jorge Enrique Rozo \u00a0Rodr\u00edguez, presentan ante la Secretaria General de la C\u00e1mara de Representantes \u00a0en su condici\u00f3n de autores, el Proyecto de Acto Legislativo, \u201cpor el cual se \u00a0reforma el art\u00edculo 250 de la Constituci\u00f3n Pol\u00edtica\u201d, \u00a0quedando radicado con el n\u00famero 216 con su correspondiente exposici\u00f3n de \u00a0motivos conforme a lo establecido en el art\u00edculo 139 de la Ley 5\u00aa de 1992, con el \u00a0fin de iniciar su tr\u00e1mite legislativo constitucional. \u00a0 \u00a0<\/p>\n<p>Que el Secretario General de la honorable \u00a0C\u00e1mara de Representantes con fecha 27 de abril de 2011, pasa al Despacho del \u00a0se\u00f1or Presidente de la C\u00e1mara de Representantes el Proyecto de Acto Legislativo \u00a0n\u00famero 216 de 2011 C\u00e1mara, \u201cpor el cual se reforma el art\u00edculo 250 de la Constituci\u00f3n Pol\u00edtica\u201d y \u00a0a su vez la Presidencia de la C\u00e1mara de Representantes reparte a la Comisi\u00f3n \u00a0Primera Constitucional Permanente, envi\u00e1ndose copia del mismo a la Imprenta \u00a0Nacional para su publicaci\u00f3n de acuerdo con el art\u00edculo 144 de la Ley 5\u00aa de 1992, \u00a0quedando publicado en la Gaceta del Congreso n\u00famero 206 del 27 de \u00a0abril de 2011. \u00a0 \u00a0<\/p>\n<p>Que el 28 de abril de 2001 la Mesa Directiva \u00a0de la Comisi\u00f3n Primera Constitucional Permanente, designa como ponentes para \u00a0primer debate a los Representantes Gustavo Puentes y Carlos Correa \u00a0(Coordinadores), Camilo Abril, Miguel G\u00f3mez, Rub\u00e9n Dar\u00edo Rodr\u00edguez, Juan Carlos \u00a0Salazar, Germ\u00e1n Var\u00f3n, Jorge E. Rozo, Alfonso Prada y Germ\u00e1n Navas Talero. \u00a0 \u00a0<\/p>\n<p>Que el 3 de mayo de 2011, el Presidente de la \u00a0Comisi\u00f3n Primera Constitucional Permanente de la C\u00e1mara de Representantes \u00a0recibe el informe de ponencia para primer debate el Proyecto de Acto \u00a0Legislativo n\u00famero 216 de 2011 C\u00e1mara, \u201cpor el cual se reforma el art\u00edculo 250 de la Constituci\u00f3n Pol\u00edtica\u201d, \u00a0quedando su publicaci\u00f3n en la Gaceta del Congreso n\u00famero 226 del \u00a03 de mayo de 2011, anunciado para discusi\u00f3n y votaci\u00f3n el d\u00eda 3 de mayo de \u00a02011, seg\u00fan consta en el Acta n\u00famero 58 de esa misma fecha. \u00a0 \u00a0<\/p>\n<p>Que el 4 de mayo de 2011 comienza la discusi\u00f3n \u00a0y votaci\u00f3n del Proyecto de Acto Legislativo n\u00famero 216 de 2011 C\u00e1mara, \u201cpor el \u00a0cual se reforma el art\u00edculo 250 de la Constituci\u00f3n Pol\u00edtica\u201d. \u00a0Se somete a consideraci\u00f3n y votaci\u00f3n la proposici\u00f3n con que termina el informe \u00a0de ponencia, siendo aprobado por unanimidad. Posteriormente la Presidencia \u00a0concede el uso de la palabra al Viceministro de Justicia, quien deja ver la \u00a0importancia para el Gobierno del proyecto y hace una breve explicaci\u00f3n. La \u00a0Presidencia concede la palabra a uno de los Representantes quien manifiesta se \u00a0debe hacer una modificaci\u00f3n a los art\u00edculos 251 y 235 de la Constituci\u00f3n y adem\u00e1s \u00a0presenta una proposici\u00f3n sustitutiva al art\u00edculo 1\u00b0 de la ponencia. La \u00a0Presidencia somete a consideraci\u00f3n y votaci\u00f3n del articulado del proyecto (4 \u00a0art\u00edculos), los cuales son aprobados. La Presidencia somete a consideraci\u00f3n y \u00a0votaci\u00f3n el nuevo t\u00edtulo \u201cpor la cual se reforma la Constituci\u00f3n Pol\u00edtica\u201d, \u00a0siendo aprobado por unanimidad. Se somete a consideraci\u00f3n y votaci\u00f3n para que \u00a0este proyecto tenga un segundo debate, lo que se aprueba por unanimidad. \u00a0Seguidamente se nombran Ponentes a los Representantes Gustavo Puentes y Carlos \u00a0Correa como Coordinadores, Camilo Abril, Miguel G\u00f3mez, Rub\u00e9n Dar\u00edo Rodr\u00edguez, Juan \u00a0Carlos Salazar, Germ\u00e1n Var\u00f3n, Jorge E. Rozo, Alfonso Prada, Germ\u00e1n Navas Talero \u00a0y Carlos Edward Osorio Aguiar. \u00a0 \u00a0<\/p>\n<p>Que el 11 de mayo de 2011, se recibe la \u00a0ponencia para segundo debate y pliego de modificaciones del Proyecto de Acto \u00a0Legislativo n\u00famero 216 de 2011 C\u00e1mara, \u201cpor la cual se reforma la Constituci\u00f3n \u00a0Pol\u00edtica\u201d. \u00a0 \u00a0<\/p>\n<p>Que la Secretar\u00eda General de la C\u00e1mara de \u00a0Representantes el d\u00eda 11 de mayo de 2011, recibe para su respectiva publicaci\u00f3n \u00a0en la Gaceta del Congreso n\u00famero 249 del mi\u00e9rcoles 11 de mayo de \u00a02011, el informe de ponencia para segundo debate al Proyecto de Acto \u00a0Legislativo n\u00famero 216 de 2011 C\u00e1mara. Igualmente en la misma Gaceta se \u00a0publica el pliego de modificaciones al Proyecto de Acto Legislativo n\u00famero 216 \u00a0de 2011 C\u00e1mara, por el cual se reforma el numeral 4 del art\u00edculo 235, el \u00a0art\u00edculo 250 y el numeral 1 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica, \u00a0lo mismo que el texto aprobado en la Comisi\u00f3n Primera de la honorable C\u00e1mara de \u00a0Representantes del Proyecto de Acto legislativo n\u00famero 216 de 2011 C\u00e1mara, por \u00a0el cual se reforma la Constituci\u00f3n Pol\u00edtica. \u00a0 \u00a0<\/p>\n<p>Que la Secretar\u00eda General en Sustanciaci\u00f3n de \u00a0ponencia de segundo debate de fecha 18 de mayo de 2011, informa que en Sesi\u00f3n \u00a0Plenaria de la honorable C\u00e1mara de Representantes, fue aprobado en segundo \u00a0debate el texto definitivo sin modificaciones del Proyecto de Acto Legislativo \u00a0n\u00famero 216 de 2011 C\u00e1mara, \u201cpor el cual se reforma el numeral 4 del art\u00edculo \u00a0235, el art\u00edculo 250 y el numeral 1 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica\u201d. \u00a0Lo anterior de conformidad con el art\u00edculo 5\u00b0 del Acto Legislativo n\u00famero 01 de \u00a02009, seg\u00fan consta en el Acta de Sesi\u00f3n Plenaria n\u00famero 62 de mayo 17 de 2011, \u00a0previo su anuncio en d\u00eda 11 de mayo de los corrientes, seg\u00fan Acta de Sesi\u00f3n \u00a0Plenaria n\u00famero 61. El texto definitivo de Plenaria en C\u00e1mara qued\u00f3 publicado \u00a0en la Gaceta del Congreso n\u00famero 286 del viernes, 20 de mayo de \u00a02011. \u00a0 \u00a0<\/p>\n<p>Que con fecha 18 de mayo de 2011 el Presidente \u00a0de la C\u00e1mara de Representantes, de conformidad con el art\u00edculo 183 de la Ley 5\u00aa de 1992, remite \u00a0el Expediente del Proyecto de Acto Legislativo n\u00famero 216 de 2011 C\u00e1mara, \u201cpor \u00a0el cual se reforma el numeral 4 del art\u00edculo 235, el art\u00edculo 250 y el numeral \u00a01 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica\u201d. \u00a0 \u00a0<\/p>\n<p>Que la Jefe Secci\u00f3n de Leyes del Senado de la \u00a0Rep\u00fablica, en Sustanciaci\u00f3n de Tr\u00e1nsito a Senado de la Rep\u00fablica, con fecha 18 \u00a0de mayo de 2011, recibe de la C\u00e1mara de Representantes, el expediente del \u00a0Proyecto de Acto Legislativo n\u00famero 216 de 2011 C\u00e1mara, 020 de 2011 Senado, \u00a0\u201cpor el cual se reforma el numeral 4 del art\u00edculo 235, el art\u00edculo 250 y el numeral \u00a01 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica\u201d. \u00a0 \u00a0<\/p>\n<p>Que el 19 de mayo de 2011 la Comisi\u00f3n Primera \u00a0Constitucional Permanente del Senado de la Rep\u00fablica, recibe el expediente del \u00a0Proyecto de Acto Legislativo n\u00famero 020 de 2011 Senado, 216 de 2011 C\u00e1mara, \u00a0\u201cpor el cual se reforma el numeral 4 del art\u00edculo 235, el art\u00edculo 250 y el \u00a0numeral 1 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica\u201d. \u00a0 \u00a0<\/p>\n<p>Que el 19 de mayo de 2011, la Comisi\u00f3n Primera \u00a0Constitucional Permanente del Senado de la Rep\u00fablica, la Mesa Directiva como \u00a0consta en el Acta MD-33, designa como ponentes de este proyecto a los Senadores \u00a0Jorge Eduardo Londo\u00f1o (Coordinador), Roberto Gerl\u00e9in \u00a0Echeverr\u00eda, Jes\u00fas Ignacio Garc\u00eda Valencia, Carlos Enrique Soto Jaramillo, Hemel Hurtado Angulo, Luis Carlos Avellaneda Tarazona, con \u00a0cinco (5) d\u00edas de t\u00e9rmino para rendir el correspondiente informe. \u00a0 \u00a0<\/p>\n<p>Que el 25 de mayo de 2011, la Comisi\u00f3n Primera \u00a0Constitucional Permanente del Senado de la Rep\u00fablica, recibe un documento de \u00a0parte del Secretario General del Senado de la Rep\u00fablica donde remite un \u00a0impedimento negado el 17 de mayo de 2011, en Sesi\u00f3n Plenaria de la C\u00e1mara de \u00a0Representantes donde se discuti\u00f3 esta iniciativa. \u00a0 \u00a0<\/p>\n<p>Que el 31 de mayo de 2011, la Secretar\u00eda de la \u00a0Comisi\u00f3n Primera Constitucional Permanente del Senado, recibe ponencia para \u00a0primer debate de esta iniciativa suscrita por todos los ponentes. Esta ponencia \u00a0se env\u00eda a Leyes de Senado para su publicaci\u00f3n en la Gaceta del Congreso n\u00famero \u00a0336 del martes, 31 de mayo de 2011. \u00a0 \u00a0<\/p>\n<p>Que el 1\u00b0 de junio de 2011, la Secretar\u00eda de \u00a0la Comisi\u00f3n Primera Constitucional Permanente del Senado, acorde al art\u00edculo 8\u00b0 \u00a0del Acto Legislativo 01 de 2003 y por instrucciones de la Presidencia, la \u00a0Secretar\u00eda informa que en la pr\u00f3xima sesi\u00f3n se discutir\u00e1 y votar\u00e1 esta \u00a0iniciativa para primer debate. \u00a0 \u00a0<\/p>\n<p>Que el 2 de junio de 2011 se da lectura por \u00a0Secretar\u00eda de la Comisi\u00f3n Primera Constitucional Permanente del Senado, la \u00a0proposici\u00f3n con que termina el informe de ponencia suscrito por la totalidad de \u00a0los ponentes y mediante votaci\u00f3n nominal es aprobado el t\u00edtulo y su respectivo \u00a0tr\u00e1nsito a la Plenaria del Senado. Seguidamente la Presidencia designa como \u00a0ponentes para segundo debate a los Senadores Jorge Eduardo Londo\u00f1o Ulloa \u00a0(Coordinador), Roberto Gerl\u00e9in Echeverr\u00eda, Jes\u00fas \u00a0Ignacio Garc\u00eda Valencia, Carlos Enrique Soto Jaramillo, Hemel \u00a0Hurtado Angulo y Luis Carlos Avellaneda Tarazona, con cinco (5) d\u00edas de t\u00e9rmino \u00a0para rendir el correspondiente informe. \u00a0 \u00a0<\/p>\n<p>Que el 8 de junio de 2011 la Secretar\u00eda de la \u00a0Comisi\u00f3n Primera Constitucional Permanente recibe ponencia para segundo debate \u00a0del Proyecto de Acto Legislativo n\u00famero 20 de 2011 Senado, 216 de 2011 C\u00e1mara, \u00a0previa autorizaci\u00f3n de la Presidencia y Secretar\u00eda de la Comisi\u00f3n, se env\u00eda a \u00a0la Secci\u00f3n de Leyes de Senado para su respectiva publicaci\u00f3n en la Gaceta \u00a0del Congreso n\u00famero 394 del mi\u00e9rcoles, 8 de junio de 2011. \u00a0 \u00a0<\/p>\n<p>Que con oficio de fecha 15 de junio de 2001 el \u00a0Presidente del Senado de la Rep\u00fablica, remite al Presidente de la C\u00e1mara de \u00a0Representantes el expediente del Proyecto de Acto Legislativo n\u00famero 020 de 2011 \u00a0Senado, 216 de 2011 C\u00e1mara, \u201cpor el cual se reforma el numeral 4 del art\u00edculo \u00a0235, el art\u00edculo 250 y el numeral 1 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica\u201d, \u00a0donde informa que en Sesi\u00f3n Plenaria del Senado de la Rep\u00fablica fue aprobado el \u00a0d\u00eda 14 de junio de 2011, con el fin de que el citado proyecto siga su curso \u00a0legal y reglamentario. Dicho proyecto qued\u00f3 publicado en la Gaceta del \u00a0Congreso n\u00famero 423 del d\u00eda martes 14 de junio de 2011. \u00a0 \u00a0<\/p>\n<p>Que en Sustanciaci\u00f3n de la Comisi\u00f3n Accidental \u00a0de Mediaci\u00f3n de la Secretar\u00eda General de la C\u00e1mara de Representantes, informa \u00a0que en Sesi\u00f3n Plenaria de la honorable C\u00e1mara de Representantes de fecha 16 de \u00a0junio de 2011, fue considerado y aprobado el informe de la Comisi\u00f3n Accidental \u00a0de Mediaci\u00f3n el Proyecto de Acto Legislativo n\u00famero 216 de 2011 C\u00e1mara, 020 de \u00a02011 Senado, \u201cpor el cual se reforma el numeral 4 del art\u00edculo 235, el art\u00edculo \u00a0250 y el numeral 1 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica\u201d \u00a0(Primera Vuelta). Lo anterior seg\u00fan consta en el Acta de Sesi\u00f3n Plenaria n\u00famero \u00a073 de junio 16 de 2011, previo su anuncio el d\u00eda 15 de junio de 2011, seg\u00fan \u00a0Acta de Sesi\u00f3n plenaria n\u00famero 72. \u00a0 \u00a0<\/p>\n<p>Que en m\u00e9rito de lo expuesto: \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Ord\u00e9nese la publicaci\u00f3n del Texto \u00a0Definitivo del Proyecto de Acto Legislativo n\u00famero 216 de 2011 C\u00e1mara, 020 de \u00a02011 Senado, \u201cpor el cual se reforma el numeral 4 del art\u00edculo 235, el art\u00edculo \u00a0250 y el numeral 1 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica\u201d \u00a0(Primera Vuelta), el cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>ACTO LEGISLATIVO N\u00daMERO \u00a0 \u00a0<\/p>\n<p>(Primera Vuelta) \u00a0 \u00a0<\/p>\n<p>por el cual se reforma el numeral 4 del \u00a0art\u00edculo 235, el art\u00edculo 250 y el numeral 1 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica. \u00a0 \u00a0<\/p>\n<p>El Congreso de Colombia \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. El numeral 4 del art\u00edculo 235 de la Constituci\u00f3n Pol\u00edtica quedar\u00e1 \u00a0as\u00ed: \u00a0 \u00a0<\/p>\n<p>(\u2026) \u00a0 \u00a0<\/p>\n<p>4. Juzgar, previa acusaci\u00f3n del Fiscal General \u00a0de la Naci\u00f3n, del Vicefiscal General de la Naci\u00f3n o \u00a0de sus delegados de la unidad de fiscal\u00edas ante la Corte Suprema de Justicia, a \u00a0los Ministros del Despacho, al Procurador General, al Defensor del Pueblo, a \u00a0los Agentes del Ministerio P\u00fablico ante la Corte, ante el Consejo de Estado y \u00a0ante los Tribunales; a los Directores de los Departamentos Administrativos, al \u00a0Contralor General de la Rep\u00fablica, a los Embajadores y jefe de misi\u00f3n diplom\u00e1tica \u00a0o consular, a los Gobernadores, a los Magistrados de Tribunales y a los \u00a0Generales y Almirantes de la Fuerza P\u00fablica, por los hechos punibles que se les \u00a0imputen. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. El art\u00edculo 250 de la Constituci\u00f3n Pol\u00edtica \u00a0tendr\u00e1 un par\u00e1grafo 2\u00b0 del siguiente tenor: \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo 2\u00b0. Atendiendo la naturaleza del \u00a0bien jur\u00eddico y la menor lesividad de la conducta \u00a0punible, el legislador podr\u00e1 asignarle el ejercicio de la acci\u00f3n penal a la \u00a0v\u00edctima o a otras autoridades distintas a la Fiscal\u00eda General de la Naci\u00f3n. En \u00a0todo caso, la Fiscal\u00eda General de la Naci\u00f3n podr\u00e1 actuar en forma preferente. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00b0. El numeral 1 del art\u00edculo 251 de la Constituci\u00f3n Pol\u00edtica \u00a0quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>1. Investigar y acusar, si hubiere lugar, \u00a0directamente o por conducto del Vicefiscal General de \u00a0la Naci\u00f3n o de sus delegados de la unidad de fiscal\u00edas ante la Corte Suprema de \u00a0Justicia, a los altos servidores que gocen de fuero Constitucional, con las \u00a0excepciones previstas en la Constituci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 4\u00b0. El presente acto legislativo rige \u00a0a partir de la fecha de su promulgaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>El Presidente del honorable Senado de la \u00a0Rep\u00fablica, \u00a0 \u00a0<\/p>\n<p>Armando Benedetti Villaneda. \u00a0 \u00a0<\/p>\n<p>El Secretario General del honorable Senado de \u00a0la Rep\u00fablica, \u00a0 \u00a0<\/p>\n<p>Emilio Ram\u00f3n Otero Dajud. \u00a0 \u00a0<\/p>\n<p>El Presidente de la honorable C\u00e1mara de \u00a0Representantes, \u00a0 \u00a0<\/p>\n<p>Carlos Alberto Zuluaga \u00a0D\u00edaz. \u00a0 \u00a0<\/p>\n<p>El Secretario General de la honorable C\u00e1mara \u00a0de Representantes, \u00a0 \u00a0<\/p>\n<p>Jes\u00fas Alfonso Rodr\u00edguez Camargo. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. El presente decreto rige a partir \u00a0de la fecha de su publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 19 de julio de 2011. \u00a0 \u00a0<\/p>\n<p>JUAN MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>El Ministro del Interior y de Justicia, \u00a0 \u00a0<\/p>\n<p>Germ\u00e1n Vargas Lleras. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 2591 DE 2011 \u00a0 \u00a0\u00a0 (julio 19) \u00a0 \u00a0 D.O. 48.135, \u00a0julio 19 de 2011 \u00a0 \u00a0 por el cual se \u00a0ordena la publicaci\u00f3n del Proyecto de Acto Legislativo n\u00famero 216 de 2011 \u00a0C\u00e1mara &#8211; 020 de 2011 Senado, \u201cpor el cual se reforma el numeral 4 del art\u00edculo \u00a0235, el art\u00edculo 250 y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-43548","post","type-post","status-publish","format-standard","hentry","category-decretos-2011"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/43548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=43548"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/43548\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=43548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=43548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=43548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}