{"id":43640,"date":"2023-08-02T16:17:01","date_gmt":"2023-08-02T16:17:01","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/02\/decreto-3320-de-2011\/"},"modified":"2023-08-02T16:17:01","modified_gmt":"2023-08-02T16:17:01","slug":"decreto-3320-de-2011","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/02\/decreto-3320-de-2011\/","title":{"rendered":"DECRETO 3320 DE 2011"},"content":{"rendered":"\n<p>DECRETO 3320 DE 2011 \u00a0 \u00a0<\/p>\n<p>(septiembre 8 ) \u00a0 \u00a0<\/p>\n<p>D.O. 48.186, septiembre 8 de 2011 \u00a0 \u00a0<\/p>\n<p>por el cual se efect\u00faa un nombramiento. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, en \u00a0ejercicio de las facultades constitucionales que le confiere el numeral 1 del \u00a0art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica. \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. N\u00f3mbrese a partir de la fecha, al \u00a0doctor Federico Alonso Rengifo V\u00e9lez, identificado con la c\u00e9dula de ciudadan\u00eda \u00a0n\u00famero 14998551 de Cali, como Director de Departamento Administrativo -1190 del \u00a0Departamento Administrativo de la Presidencia de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. El presente decreto rige a partir \u00a0de la fecha de su expedici\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese, comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 8 de septiembre de \u00a02011. \u00a0 \u00a0<\/p>\n<p>JUAN MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 3320 DE 2011 \u00a0 \u00a0 (septiembre 8 ) \u00a0 \u00a0 D.O. 48.186, septiembre 8 de 2011 \u00a0 \u00a0 por el cual se efect\u00faa un nombramiento. \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, en \u00a0ejercicio de las facultades constitucionales que le confiere el numeral 1 del \u00a0art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica. \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-43640","post","type-post","status-publish","format-standard","hentry","category-decretos-2011"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/43640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=43640"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/43640\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=43640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=43640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=43640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}