{"id":47613,"date":"2023-08-16T18:03:43","date_gmt":"2023-08-16T18:03:43","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-183-de-2014\/"},"modified":"2023-08-16T18:03:43","modified_gmt":"2023-08-16T18:03:43","slug":"decreto-183-de-2014","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-183-de-2014\/","title":{"rendered":"DECRETO 183 DE 2014"},"content":{"rendered":"\n<p>DECRETO 183 DE 2014<\/p>\n<p>\u00a0(febrero 7)<\/p>\n<p>\u00a0D.O. 49.057, febrero 7 de 2014<\/p>\n<p>por el cual se fijan las escalas de remuneraci\u00f3n correspondientes a las distintas categor\u00edas de empleos de la Auditoria General de la Rep\u00fablica y se dictan otras disposiciones.<\/p>\n<p>Nota: Derogado por el Decreto 1094 de 2015, art\u00edculo 18.<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, en desarrollo de las normas generales se\u00f1aladas en la Ley 4\u00aa de 1992,<\/p>\n<p>DECRETA:<\/p>\n<p>Art\u00edculo 1\u00b0. Asignaciones b\u00e1sicas. A partir del 1\u00b0 de enero de 2014, f\u00edjanse las siguientes escalas de asignaci\u00f3n b\u00e1sica mensual para los empleos de la Auditor\u00eda General de la Rep\u00fablica:<\/p>\n<p>\u00a0Grado<\/p>\n<p>Directivo<\/p>\n<p>\u00a0Asesor<\/p>\n<p>Profesional<\/p>\n<p>\u00a0T\u00e9cnico<\/p>\n<p>Asistencial<\/p>\n<p>\u00a01<\/p>\n<p>5.700.726<\/p>\n<p>\u00a05.384.344<\/p>\n<p>2.273.922<\/p>\n<p>\u00a01.538.848<\/p>\n<p>913.352<\/p>\n<p>\u00a02<\/p>\n<p>5.917.222<\/p>\n<p>\u00a05.910.182<\/p>\n<p>2.866.065<\/p>\n<p>\u00a01.652.652<\/p>\n<p>1.127.650<\/p>\n<p>\u00a03<\/p>\n<p>6.634.215<\/p>\n<p>4.019.120<\/p>\n<p>1.351.921<\/p>\n<p>\u00a04<\/p>\n<p>7.290.866<\/p>\n<p>4.590.560<\/p>\n<p>1.423.641<\/p>\n<p>\u00a05<\/p>\n<p>1.548.586<\/p>\n<p>\u00a06<\/p>\n<p>1.958.224<\/p>\n<p>Par\u00e1grafo. Las asignaciones b\u00e1sicas mensuales de las escalas se\u00f1aladas en el presente art\u00edculo corresponden a empleos de car\u00e1cter permanente y de tiempo completo.<\/p>\n<p>Art\u00edculo 2\u00b0. Auditor General de la Rep\u00fablica. El Auditor General de la Rep\u00fablica devengar\u00e1 la misma asignaci\u00f3n b\u00e1sica y gastos de representaci\u00f3n que percibe el Contralor General de la Rep\u00fablica.<\/p>\n<p>Par\u00e1grafo 1\u00b0. Establ\u00e9cese para el Auditor General de la Rep\u00fablica una prima de alta gesti\u00f3n, equivalente a la diferencia entre los ingresos laborales totales anuales percibidos por el Contralor General de la Rep\u00fablica y los ingresos laborales totales anuales del Auditor General, sin que en ning\u00fan caso los supere.<\/p>\n<p>Se entiende que los ingresos laborales totales anuales percibidos por el Contralor General de la Rep\u00fablica son los constituidos por la asignaci\u00f3n b\u00e1sica, los gastos de representaci\u00f3n, la prima de navidad y la prima especial de servicios.<\/p>\n<p>La prima de alta gesti\u00f3n de que trata el presente art\u00edculo, se pagar\u00e1 mensualmente, reemplaza en su totalidad y deja sin efecto legal cualquier otra prima, con excepci\u00f3n de la prima de navidad, y no se tendr\u00e1 en cuenta para la determinaci\u00f3n de la remuneraci\u00f3n de otros servidores o empleados de la Auditoria General de la Rep\u00fablica.<\/p>\n<p>Par\u00e1grafo 2\u00b0. La prima de alta gesti\u00f3n a que se refiere el presente art\u00edculo constituir\u00e1 factor salarial solo para efecto del ingreso base de cotizaci\u00f3n del Sistema General de Pensiones y, de acuerdo con la Ley 797 de 2003, para el Sistema General de Seguridad Social en Salud.<\/p>\n<p>Art\u00edculo 3\u00b0. Auditor Auxiliar. A partir del 1\u00b0 de enero de 2014, el Auditor Auxiliar de la Auditor\u00eda General de la Rep\u00fablica tendr\u00e1 derecho a una remuneraci\u00f3n mensual de catorce millones ciento ochenta y dos mil treinta y tres pesos ($14.182.033) moneda corriente, distribuida as\u00ed:<\/p>\n<p>Concepto<\/p>\n<p>Valor mensual<\/p>\n<p>Asignaci\u00f3n B\u00e1sica<\/p>\n<p>7.276.124<\/p>\n<p>Gastos de Representaci\u00f3n<\/p>\n<p>1.812.628<\/p>\n<p>Prima de Alta Gesti\u00f3n<\/p>\n<p>1.455.223<\/p>\n<p>Prima T\u00e9cnica<\/p>\n<p>3.638.058<\/p>\n<p>Las primas t\u00e9cnica y de alta gesti\u00f3n no constituyen factor salarial para ning\u00fan efecto legal.<\/p>\n<p>Art\u00edculo 4\u00b0. Prima de alta gesti\u00f3n. Los siguientes empleos podr\u00e1n percibir mensualmente una prima de alta gesti\u00f3n hasta por el veinte por ciento (20%) de la asignaci\u00f3n b\u00e1sica mensual, conforme a la resoluci\u00f3n del Auditor General de la Rep\u00fablica, en la cual se establecer\u00e1n los criterios de remuneraci\u00f3n de la gesti\u00f3n, con base en el desempe\u00f1o global de las respectivas dependencias, la cual no constituye factor salarial para ning\u00fan efecto legal:<\/p>\n<p>\u2022 Auditor Delegado<\/p>\n<p>\u2022 Secretario General<\/p>\n<p>\u2022 Director de Oficina<\/p>\n<p>\u2022 Gerente Seccional<\/p>\n<p>\u2022 Director<\/p>\n<p>Par\u00e1grafo. En aplicaci\u00f3n de este art\u00edculo no se podr\u00e1n exceder, en ning\u00fan caso, las apropiaciones presupuestales vigentes.<\/p>\n<p>Art\u00edculo 5\u00b0. Prima t\u00e9cnica. Los siguientes empleos tendr\u00e1n derecho a percibir mensualmente una prima t\u00e9cnica autom\u00e1tica equivalente al cincuenta por ciento (50%) de la asignaci\u00f3n b\u00e1sica mensual, la cual no constituye factor salarial para ning\u00fan efecto legal:<\/p>\n<p>\u2022 Auditor Delegado<\/p>\n<p>\u2022 Secretario General<\/p>\n<p>\u2022 Director de Oficina<\/p>\n<p>\u2022 Gerente Seccional<\/p>\n<p>\u2022 Director<\/p>\n<p>Art\u00edculo 6\u00b0. Bonificaci\u00f3n por servicios prestados. La bonificaci\u00f3n por servicios prestados a que tienen derecho los empleados que trabajan en la Auditor\u00eda General de la Rep\u00fablica ser\u00e1 equivalente al cincuenta por ciento (50%) de la asignaci\u00f3n total mensual que corresponda al empleado en la fecha en que se cause el derecho a percibirla, siempre que no devengue una asignaci\u00f3n b\u00e1sica mensual superior a dos (2) salarios m\u00ednimos.<\/p>\n<p>Para los dem\u00e1s empleados, la bonificaci\u00f3n por servicios prestados ser\u00e1 equivalente al treinta y cinco por ciento (35%) de la asignaci\u00f3n total mensual.<\/p>\n<p>Art\u00edculo 7\u00b0. Auxilio de transporte. Los empleados de la Auditor\u00eda General de la Rep\u00fablica tendr\u00e1n derecho a un auxilio de transporte en la misma forma, t\u00e9rminos y cuant\u00eda que el Gobierno Nacional determine para los particulares.<\/p>\n<p>No tendr\u00e1 derecho al auxilio de transporte el empleado que se encuentre en disfrute de vacaciones, en uso de licencia, suspendido en el ejercicio del cargo o cuando la Auditor\u00eda facilite este servicio.<\/p>\n<p>Art\u00edculo 8\u00b0. Subsidio de alimentaci\u00f3n. A partir del 1\u00b0 de enero de 2014, los empleados de la Auditor\u00eda General de la Rep\u00fablica que tengan una asignaci\u00f3n mensual no superior a un mill\u00f3n trescientos treinta y tres mil cuatrocientos sesenta y siete pesos ($1.333.467) moneda corriente, tendr\u00e1n derecho al pago de subsidio de alimentaci\u00f3n por la suma de cuarenta y siete mil quinientos cincuenta y un pesos ($47.551) moneda corriente.<\/p>\n<p>No se tendr\u00e1 derecho al subsidio de alimentaci\u00f3n cuando el empleado se encuentre en disfrute de vacaciones, en uso de licencia, suspendido en el ejercicio del cargo o cuando la entidad suministre la alimentaci\u00f3n al empleado.<\/p>\n<p>Par\u00e1grafo. Los empleados de la Auditoria General de la Rep\u00fablica no podr\u00e1n recibir de la entidad fiscalizada el pago de este subsidio en dinero ni el suministro gratuito de la alimentaci\u00f3n.<\/p>\n<p>Art\u00edculo 9\u00b0. Vi\u00e1ticos. Para determinar el valor de los vi\u00e1ticos se tendr\u00e1 en cuenta la remuneraci\u00f3n mensual y los gastos de representaci\u00f3n que devengue el empleado, de conformidad con la reglamentaci\u00f3n que adopte el Gobierno Nacional.<\/p>\n<p>Art\u00edculo 10. Gastos de traslado. Los gastos de traslado a que se refiere el art\u00edculo 11 del Decreto n\u00famero 344 de 1981 y las normas que lo modifiquen o sustituyan se reconocer\u00e1n por la Auditor\u00eda General de la Rep\u00fablica.<\/p>\n<p>Art\u00edculo 11. Horas extras. Para efectos del pago de horas extras o del reconocimiento de descanso compensatorio en la Auditor\u00eda General de la Rep\u00fablica, se tendr\u00e1 en cuenta lo siguiente:<\/p>\n<p>a) El empleado deber\u00e1 pertenecer al grado 01 del nivel t\u00e9cnico o hasta el grado 05 del nivel asistencial;<\/p>\n<p>b) En ning\u00fan caso, podr\u00e1n pagarse m\u00e1s de cincuenta (50) horas extras mensuales;<\/p>\n<p>c) Para los empleados p\u00fablicos que desempe\u00f1en el cargo de Auxiliar Operativo con funciones de conductor tendr\u00e1n derecho al pago hasta de ochenta (80) horas extras mensuales;<\/p>\n<p>d) En todo caso, la autorizaci\u00f3n para laborar en horas extras solo podr\u00e1 otorgarse cuando exista disponibilidad presupuestal.<\/p>\n<p>Art\u00edculo 12. Liquidaci\u00f3n de pensiones. Las pensiones de los empleados de la Auditoria General de la Rep\u00fablica se liquidar\u00e1n sobre los mismos factores que constituyen el ingreso base de cotizaci\u00f3n, establecidos por el Decreto n\u00famero 691 de 1994, modificado por el art\u00edculo 1\u00b0 del Decreto n\u00famero 1158 de 1994, dentro de los l\u00edmites dispuestos por el art\u00edculo 5\u00b0 de la Ley 797 de 2003.<\/p>\n<p>Art\u00edculo 13. Quinquenio. Para los empleados que ingresen a la Auditor\u00eda General de la Rep\u00fablica con posterioridad a la publicaci\u00f3n de la Ley 106 de 1993 o se vinculen con soluci\u00f3n de continuidad el quinquenio no constituir\u00e1 factor salarial para ning\u00fan efecto legal.<\/p>\n<p>Art\u00edculo 14. L\u00edmite de remuneraci\u00f3n. En ning\u00fan caso, la remuneraci\u00f3n total de los empleados a quienes se les aplica este decreto podr\u00e1 exceder la que corresponde al Auditor General de la Rep\u00fablica por todo concepto.<\/p>\n<p>Art\u00edculo 15. Prestaciones sociales. Los empleados de la Auditor\u00eda General de la Rep\u00fablica tendr\u00e1n derecho a disfrutar de las prestaciones establecidas para los empleados de la Contralor\u00eda General de la Rep\u00fablica, no reguladas en el presente decreto.<\/p>\n<p>Art\u00edculo 16. Prohibiciones. Ninguna autoridad podr\u00e1 establecer o modificar el r\u00e9gimen salarial o prestacional estatuido por las normas del presente decreto, en concordancia con lo establecido en el art\u00edculo 10 de la Ley 4\u00aa de 1992. Cualquier disposici\u00f3n en contrario carecer\u00e1 de todo efecto y no crear\u00e1 derechos adquiridos.<\/p>\n<p>Nadie podr\u00e1 desempe\u00f1ar simult\u00e1neamente m\u00e1s de un empleo p\u00fablico ni recibir m\u00e1s de una asignaci\u00f3n que provenga del Tesoro P\u00fablico o de empresas o instituciones en las que tenga parte mayoritaria el Estado. Except\u00faanse las asignaciones de que trata el art\u00edculo 19 de la Ley 4\u00aa de 1992.<\/p>\n<p>Art\u00edculo 17. Competencia para conceptuar. El Departamento Administrativo de La Funci\u00f3n P\u00fablica es el \u00f3rgano competente para conceptuar en materia salarial y prestacional. Ning\u00fan otro \u00f3rgano puede arrogarse esta competencia.<\/p>\n<p>Art\u00edculo 18. Vigencia. El presente decreto rige a partir de la fecha de su publicaci\u00f3n, deroga el Decreto n\u00famero 1013 de 2013 y surte efectos fiscales a partir del 1\u00b0 de enero de 2014.<\/p>\n<p>Publ\u00edquese y c\u00famplase.<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 7 de febrero de 2014.<\/p>\n<p>JUAN MANUEL SANTOS CALDER\u00d3N<\/p>\n<p>El Ministro de Hacienda y Cr\u00e9dito P\u00fablico,<\/p>\n<p>Mauricio C\u00e1rdenas Santamar\u00eda.<\/p>\n<p>La Directora del Departamento Administrativo de la Funci\u00f3n P\u00fablica,<\/p>\n<p>Elizabeth Rodr\u00edguez Taylor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 183 DE 2014 \u00a0(febrero 7) \u00a0D.O. 49.057, febrero 7 de 2014 por el cual se fijan las escalas de remuneraci\u00f3n correspondientes a las distintas categor\u00edas de empleos de la Auditoria General de la Rep\u00fablica y se dictan otras disposiciones. Nota: Derogado por el Decreto 1094 de 2015, art\u00edculo 18. El Presidente de la Rep\u00fablica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[],"class_list":["post-47613","post","type-post","status-publish","format-standard","hentry","category-decretos-2014"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/47613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=47613"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/47613\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=47613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=47613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=47613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}