{"id":48839,"date":"2023-08-16T20:47:24","date_gmt":"2023-08-16T20:47:24","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-1304-de-2015\/"},"modified":"2023-08-16T20:47:24","modified_gmt":"2023-08-16T20:47:24","slug":"decreto-1304-de-2015","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-1304-de-2015\/","title":{"rendered":"DECRETO 1304 DE 2015"},"content":{"rendered":"\n<p>DECRETO 1304 DE 2015 \u00a0 \u00a0\u00a0<\/p>\n<p>(junio 18) \u00a0 \u00a0<\/p>\n<p>D.O. 49.547, junio 18 de \u00a02015 \u00a0 \u00a0<\/p>\n<p>por el cual se da \u00a0cumplimiento al fallo proferido por el Consejo de Estado, y se designa un \u00a0notario en interinidad en el C\u00edrculo Notarial de Medell\u00edn, Antioquia. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, \u00a0en ejercicio de sus facultades constitucionales y legales, en especial de las \u00a0que le confieren el art\u00edculo 131 de la Constituci\u00f3n Pol\u00edtica, y \u00a05 del Decreto ley 2163 \u00a0de 1970. \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que el doctor Oscar Rodr\u00edguez Baquero \u00a0interpuso demanda de nulidad electoral, bajo el radicado \u00a025000-23-41-000-2014-00005-00 de la cual conoci\u00f3 por reparto la Subsecci\u00f3n B &#8211; Secci\u00f3n Primera del Tribunal Administrativo \u00a0de Cundinamarca, con el fin de que se declarara la \u00a0nulidad de los art\u00edculos 2\u00b0, 3\u00b0 y 4\u00b0 del Decreto \u00a01859 de agosto 29 de 2013, por medio del cual el Gobierno nacional nombr\u00f3 \u00a0como Notario en propiedad en la Notar\u00eda Treinta y Uno (31) del C\u00edrculo de \u00a0Medell\u00edn al doctor Carlos Eduardo Sevilla Cadavid. \u00a0 \u00a0<\/p>\n<p>Que la Subsecci\u00f3n \u00a0B-Secci\u00f3n Primera del Tribunal Administrativo de Cundinamarca, \u00a0en fallo del 22 de mayo de 2014, neg\u00f3 las pretensiones de la demanda y el \u00a0Consejo de Estado, Secci\u00f3n Quinta, mediante fallo del 8 de octubre de 2014, \u00a0proferido dentro de la demanda de nulidad electoral, bajo el radicado \u00a025000-23-41-000-2014-00005-01, al resolver la impugnaci\u00f3n presentada por el \u00a0demandante, revoc\u00f3 la sentencia de 22 de mayo de 2014 y declar\u00f3 \u201cla nulidad del Decreto \u00a0n\u00famero 1859 de 29 de agosto de 2013, proferido por \u201c&#8230; el Gobierno \u00a0nacional en cabeza del se\u00f1or Presidente de la Rep\u00fablica\u2026\u201d mediante el cual \u00a0nombr\u00f3 en propiedad como Notario 31 del c\u00edrculo notarial de Medell\u00edn, al se\u00f1or \u00a0Carlos Eduardo Sevilla Cadavid\u201d. \u00a0 \u00a0<\/p>\n<p>Que con el \u00fanico prop\u00f3sito de dar \u00a0cumplimiento al fallo en menci\u00f3n, se proceder\u00e1 a dejar sin efectos el Decreto \u00a01859 de 29 de agosto de 2013. \u00a0 \u00a0<\/p>\n<p>Que mediante Acuerdo 029 del 15 de diciembre \u00a0de 2011, el Consejo Superior de la Carrera Notarial conform\u00f3 listas de \u00a0elegibles para proveer en propiedad cargos de notario en diferentes c\u00edrculos \u00a0notariales del pa\u00eds. Sin embargo, dichas listas tuvieron vigencia hasta el 18 \u00a0de diciembre del a\u00f1o 2013. \u00a0 \u00a0<\/p>\n<p>Que mediante Decreto \u00a02054 del 16 de octubre de 2014, se reglament\u00f3 el numeral 3 del art\u00edculo 178 \u00a0del Decreto ley 960 de \u00a01970. \u00a0 \u00a0<\/p>\n<p>Que el art\u00edculo 4\u00b0 del Decreto \u00a0Reglamentario 2054 de 2014 establece como causales de vacancia, \u201c1. Muerte, \u00a02. Renuncia aceptada, 3. Destituci\u00f3n del cargo, 4. Retiro forzoso por cumplir \u00a0la edad de 65 a\u00f1os, 5. Declaratoria de abandono del cargo. 6. Ejercicio de \u00a0cargo p\u00fablico no autorizado por la ley\u201d. \u00a0 \u00a0<\/p>\n<p>Que mediante documento del 9 de junio de \u00a02015 el Secretario T\u00e9cnico del Consejo Superior de la Carrera Notarial \u00a0certific\u00f3 que la nulidad de un Decreto de nombramiento en el cargo de notario \u00a0no se encuentra dentro de las causales contenidas en el Decreto \u00a0Reglamentario 2054 de 2014, para el ejercicio del derecho de preferencia. \u00a0 \u00a0<\/p>\n<p>Que el Secretario T\u00e9cnico del Consejo \u00a0Superior de la Carrera Notarial, mediante documento del 9 de junio de 2015, \u00a0certific\u00f3 que \u201cmediante Acuerdo 01 de \u00a09 de abril de 2015, el Consejo Superior convoc\u00f3, fij\u00f3 las bases y el cronograma \u00a0del concurso de m\u00e9ritos p\u00fablico y abierto para el nombramiento de notarios en \u00a0propiedad e ingreso a la carrera Notarial. (&#8230;) que la Notar\u00eda Treinta y Uno \u00a0(31) del C\u00edrculo de Medell\u00edn &#8211; Antioquia de conformidad con lo establecido en \u00a0el art\u00edculo 1\u00b0 del mencionado Acuerdo 01 de 2015, fue convocada a concurso. \u00a0(&#8230;)\u201d y que \u201cpara dar \u00a0cumplimiento al fallo del Consejo de Estado de fecha 8 de octubre de 2014 y \u00a0proveer la vacante de la Notar\u00eda Treinta y Uno (31) del C\u00edrculo de Medell\u00edn &#8211; \u00a0Antioquia se debe nombrar a un notario en interinidad\u201d. \u00a0 \u00a0<\/p>\n<p>Que mediante documento del 9 de junio de \u00a02015 y para los fines se\u00f1alados en el art\u00edculo 1\u00b0 del Decreto 2874 de 1994, \u00a0la Superintendencia de Notariado y Registro emiti\u00f3 concepto previo sobre la \u00a0viabilidad de efectuar la designaci\u00f3n en interinidad en la Notar\u00eda Treinta y \u00a0Uno (31) del C\u00edrculo de Medell\u00edn \u201c&#8230; \u00a0con ocasi\u00f3n del cumplimiento del fallo de 8 de octubre de 2014 proferido por el \u00a0Consejo de Estado, Secci\u00f3n Quinta, la improcedencia del ejercicio de derecho de \u00a0preferencia y el que la notar\u00eda fue convocada a concurso mediante Acuerdo 1 de \u00a09 de abril de 2015\u201d. \u00a0 \u00a0<\/p>\n<p>Que mientras se provee el cargo en \u00a0propiedad, se hace necesario nombrar una persona en calidad de interinidad como \u00a0Notario Treinta y uno (31) del C\u00edrculo de Medell\u00edn, designando a un profesional \u00a0calificado, que cumpla con los requisitos legales establecidos para el citado \u00a0cargo. \u00a0 \u00a0<\/p>\n<p>Que de acuerdo con lo anterior, la Directora \u00a0de Administraci\u00f3n Notarial de la Superintendencia de Notariado y Registro, \u00a0mediante certificado del 9 de junio de 2015 inform\u00f3 que: \u201cCon fundamento en las facultades otorgadas \u00a0por el numeral 3 del art\u00edculo 25 del Decreto \u00a02723 del 29 de diciembre de 2014 y con fundamento en lo establecido en el \u00a0art\u00edculo 2\u00b0 Decreto 2874 de 1994, \u00a0emite concepto favorable para la designaci\u00f3n de notario, una vez revisada la \u00a0documentaci\u00f3n aportada por el doctor \u00c9dinson Arcila Ram\u00edrez, identificado con la c\u00e9dula de ciudadan\u00eda \u00a0n\u00famero 16266038 de Palmira, respecto de la cual se establece que el citado \u00a0profesional cumple con las calidades exigidas por la ley para el ejercicio de \u00a0la funci\u00f3n notarial en c\u00edrculos de primera categor\u00eda, en interinidad\u201d. \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Cumplimiento. Dar cumplimiento a la Sentencia de 8 de octubre de \u00a02014, proferida por el Consejo de Estado, Secci\u00f3n Quinta, mediante la cual \u00a0declar\u00f3 la nulidad del Decreto \u00a0n\u00famero 1859 de 29 de agosto de 2013 y en consecuencia, dejar sin efectos el \u00a0nombramiento efectuado al doctor Carlos Eduardo Sevilla Cadavid, \u00a0identificado con la c\u00e9dula de ciudadan\u00eda n\u00famero 76311959, como Notario Treinta \u00a0y uno (31) del C\u00edrculo de Medell\u00edn en propiedad, efectuado mediante dicho decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. Nombramiento. N\u00f3mbrase en calidad de \u00a0interino al doctor \u00c9dinson Arcila \u00a0Ram\u00edrez, identificado con la c\u00e9dula de ciudadan\u00eda n\u00famero 16266038, como Notario \u00a0Treinta y Uno (31) del C\u00edrculo de Medell\u00edn, Antioquia. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00b0. Acreditaci\u00f3n de documentos. Para tomar posesi\u00f3n del cargo, el \u00a0doctor \u00c9dinson Arcila \u00a0Ram\u00edrez, deber\u00e1 acreditar ante la Superintendencia de Notariado y Registro la \u00a0documentaci\u00f3n de ley. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 4\u00b0. Vigencia. El presente decreto rige a partir de la fecha de su \u00a0publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese, comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 18 de junio de \u00a02015. \u00a0 \u00a0<\/p>\n<p>JUAN MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>El Ministro de Justicia y del Derecho, \u00a0 \u00a0<\/p>\n<p>Yesid Reyes Alvarado. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 1304 DE 2015 \u00a0 \u00a0\u00a0 (junio 18) \u00a0 \u00a0 D.O. 49.547, junio 18 de \u00a02015 \u00a0 \u00a0 por el cual se da \u00a0cumplimiento al fallo proferido por el Consejo de Estado, y se designa un \u00a0notario en interinidad en el C\u00edrculo Notarial de Medell\u00edn, Antioquia. \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-48839","post","type-post","status-publish","format-standard","hentry","category-decretos-2015"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/48839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=48839"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/48839\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=48839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=48839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=48839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}