{"id":48935,"date":"2023-08-16T20:47:30","date_gmt":"2023-08-16T20:47:30","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-1602-de-2015\/"},"modified":"2023-08-16T20:47:30","modified_gmt":"2023-08-16T20:47:30","slug":"decreto-1602-de-2015","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-1602-de-2015\/","title":{"rendered":"DECRETO 1602 DE 2015"},"content":{"rendered":"\n<p>DECRETO \u00a01602 DE 2015 \u00a0 \u00a0<\/p>\n<p>(agosto 10) \u00a0 \u00a0<\/p>\n<p>D.O. 49.600, agosto 10 de \u00a02015 \u00a0 \u00a0<\/p>\n<p>por \u00a0el cual se reglamenta el numeral 3 del art\u00edculo 476 del Estatuto \u00a0Tributario. \u00a0 \u00a0<\/p>\n<p>Nota: Ver Decreto 1625 de 2016, \u00a0Decreto \u00danico Reglamentario en Materia Tributaria. \u00a0 \u00a0<\/p>\n<p>El Presidente de la \u00a0Rep\u00fablica de Colombia, en ejercicio de sus facultades constitucionales, en \u00a0especial las que le confiere el numeral 11 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica, \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que el Decreto n\u00famero \u00a01242 de 2013 modific\u00f3 el r\u00e9gimen jur\u00eddico de las inversiones colectivas en \u00a0el mercado de valores y sustituy\u00f3 la parte 3 del Decreto n\u00famero \u00a02555 de 2010. \u00a0 \u00a0<\/p>\n<p>Que a diferencia del r\u00e9gimen \u00a0anterior de las carteras colectivas en el cual todas las actividades \u00a0relacionadas con las carteras colectivas eran desarrolladas por una sola \u00a0entidad \u2013la administradora de la cartera colectiva\u2013, en el nuevo r\u00e9gimen de \u00a0fondos de inversi\u00f3n colectiva pueden intervenir varios actores, entre los \u00a0cuales se destacan, la entidad administradora, el gestor profesional externo \u00a0(local o extranjero), el distribuidor especializado cuando se haya optado por \u00a0actividades separadas y el custodio de valores, el cual es obligatorio. \u00a0 \u00a0<\/p>\n<p>Que de conformidad con lo \u00a0previsto en el numeral 3 del art\u00edculo 476 del Estatuto Tributario, se \u00a0encuentran excluidos del impuesto sobre las ventas, (IVA) entre otros \u00a0servicios, las comisiones percibidas por las sociedades fiduciarias por la \u00a0administraci\u00f3n de fondos comunes, las comisiones recibidas por los \u00a0comisionistas de bolsa por la administraci\u00f3n de fondos de valores, las \u00a0comisiones recibidas por las sociedades administradoras de inversi\u00f3n. \u00a0 \u00a0<\/p>\n<p>Que el art\u00edculo 3.1.3.1.1. \u00a0del Decreto n\u00famero \u00a02555 de 2010 establece las actividades que en ejercicio de la actividad de \u00a0administraci\u00f3n de los fondos de inversi\u00f3n colectiva se podr\u00e1n o deber\u00e1n \u00a0contratar con terceros en los siguientes t\u00e9rminos: \u00a0 \u00a0<\/p>\n<p>\u201cArt\u00edculo 3.1.3.1.1. Actividades. En el \u00a0ejercicio de la administraci\u00f3n de los fondos de inversi\u00f3n colectiva, la sociedad \u00a0administradora de fondos de inversi\u00f3n colectiva podr\u00e1 contratar a terceros para \u00a0que estos ejecuten las actividades de gesti\u00f3n y distribuci\u00f3n de fondos de \u00a0inversi\u00f3n colectiva en los t\u00e9rminos de la presente parte del presente decreto. \u00a0 \u00a0<\/p>\n<p>Con \u00a0respecto a la actividad de custodia de valores, esta deber\u00e1 ser contratada con \u00a0las entidades mencionadas en el art\u00edculo 2.22.2.1.1 del presente decreto. \u00a0 \u00a0<\/p>\n<p>Que de acuerdo con en el \u00a0art\u00edculo 1\u00b0 del Decreto 1848 de 2013, \u00a0los fondos de inversi\u00f3n colectiva previstos en la Parte 3 del Decreto n\u00famero \u00a02555 de 2010 reemplazaron a los fondos de que trata el art\u00edculo 23-1 del \u00a0Estatuto Tributario, entre los cuales se encuentran los fondos comunes y los \u00a0fondos de valores. En este sentido, se hace necesario precisar que el cambio de \u00a0r\u00e9gimen no tuvo impacto alguno para efectos de la exclusi\u00f3n del impuesto sobre \u00a0las ventas (IVA) en las comisiones que perciban las entidades administradoras, \u00a0como las sociedades fiduciarias, sociedades comisionistas de bolsa y sociedades \u00a0de administraci\u00f3n de inversiones, por las actividades relacionadas con la \u00a0administraci\u00f3n de fondos de inversi\u00f3n colectiva, la cual incluye la \u00a0administraci\u00f3n, gesti\u00f3n, distribuci\u00f3n y la custodia. \u00a0 \u00a0<\/p>\n<p>Que cumplida la formalidad \u00a0prevista en el numeral 8 del art\u00edculo 8\u00b0 del C\u00f3digo de Procedimiento \u00a0Administrativo y de lo Contencioso Administrativo en relaci\u00f3n con el texto del \u00a0presente decreto, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Administraci\u00f3n de fondos de inversi\u00f3n colectiva. Para efectos de \u00a0lo dispuesto en el numeral 3 del art\u00edculo 476 del Estatuto \u00a0Tributario, la actividad de administraci\u00f3n all\u00ed prevista comprende las \u00a0actividades de administraci\u00f3n, gesti\u00f3n, distribuci\u00f3n y custodia de fondos de \u00a0inversi\u00f3n colectiva en los t\u00e9rminos de la Parte 3 del Decreto n\u00famero \u00a02555 de 2010 y del Libro 37 de la Parte 2 del Decreto n\u00famero \u00a02555 de 2010, realizadas por las sociedades comisionistas de bolsa, las \u00a0sociedades fiduciarias y las sociedades administradoras de inversi\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. Vigencia y derogatorias. El presente decreto rige a partir de su \u00a0publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D.C., a 10 \u00a0de agosto de 2015. \u00a0 \u00a0<\/p>\n<p>JUAN MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>El Ministerio de Hacienda y \u00a0Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p>Mauricio \u00a0C\u00e1rdenas Santamar\u00eda. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO \u00a01602 DE 2015 \u00a0 \u00a0 (agosto 10) \u00a0 \u00a0 D.O. 49.600, agosto 10 de \u00a02015 \u00a0 \u00a0 por \u00a0el cual se reglamenta el numeral 3 del art\u00edculo 476 del Estatuto \u00a0Tributario. \u00a0 \u00a0 Nota: Ver Decreto 1625 de 2016, \u00a0Decreto \u00danico Reglamentario en Materia Tributaria. \u00a0 \u00a0 El Presidente de la \u00a0Rep\u00fablica de Colombia, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-48935","post","type-post","status-publish","format-standard","hentry","category-decretos-2015"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/48935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=48935"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/48935\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=48935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=48935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=48935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}