{"id":49160,"date":"2023-08-16T20:50:30","date_gmt":"2023-08-16T20:50:30","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-2145-de-2015\/"},"modified":"2023-08-16T20:50:30","modified_gmt":"2023-08-16T20:50:30","slug":"decreto-2145-de-2015","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-2145-de-2015\/","title":{"rendered":"DECRETO 2145 DE 2015"},"content":{"rendered":"\n<p>DECRETO 2145 DE 2015 \u00a0 \u00a0<\/p>\n<p>(noviembre 4) \u00a0 \u00a0<\/p>\n<p>D.O. 49.686, noviembre 4 de 2015 \u00a0 \u00a0<\/p>\n<p>por el cual se modifica la estructura del Departamento \u00a0Administrativo de la Presidencia de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>Nota 1: Derogado por el Decreto 672 de 2017, \u00a0art\u00edculo 54. \u00a0 \u00a0<\/p>\n<p>Nota 2: Modificado por el Decreto 724 de 2016. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, \u00a0en ejercicio de sus facultades constitucionales y legales, en especial las que \u00a0le confiere el numeral 16 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica y \u00a0el art\u00edculo 54 de la Ley 489 de 1998, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>CAP\u00cdTULO I \u00a0 \u00a0<\/p>\n<p>Estructura del Departamento Administrativo \u00a0de la Presidencia de la Rep\u00fablica \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. El art\u00edculo 4\u00b0 del Decreto n\u00famero \u00a01649 de 2014, quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201cArt\u00edculo 4\u00b0. Integraci\u00f3n \u00a0del Sector Administrativo. De conformidad con las normas vigentes el Sector \u00a0Administrativo de la Presidencia de la Rep\u00fablica est\u00e1 integrado por el \u00a0Departamento Administrativo de la Presidencia de la Rep\u00fablica y las siguientes \u00a0entidades adscritas: \u00a0 \u00a0<\/p>\n<p>1. Agencia \u00a0Colombiana para la Reintegraci\u00f3n de Personas y Grupos Alzados en Armas. \u00a0 \u00a0<\/p>\n<p>2. Unidad \u00a0Nacional para la Gesti\u00f3n del Riesgo de Desastres. \u00a0 \u00a0<\/p>\n<p>3. Agencia \u00a0Presidencial de Cooperaci\u00f3n Internacional de Colombia &#8211; APC Colombia. \u00a0 \u00a0<\/p>\n<p>4. Agencia \u00a0Nacional Inmobiliaria Virgilio Barco Vargas. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. El art\u00edculo 5\u00b0 del Decreto n\u00famero \u00a01649 de 2014, quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201cArt\u00edculo 5\u00b0. Estructura. \u00a0La estructura del Departamento Administrativo de la Presidencia de la Rep\u00fablica \u00a0ser\u00e1 la siguiente: \u00a0 \u00a0<\/p>\n<p>1. Despacho del Presidente de la Rep\u00fablica \u00a0 \u00a0<\/p>\n<p>2. Despacho del Vicepresidente de la \u00a0Rep\u00fablica \u00a0 \u00a0<\/p>\n<p>3. Despacho del Director del Departamento \u00a0 \u00a0<\/p>\n<p>3.1 Direcci\u00f3n de Gesti\u00f3n General \u00a0 \u00a0<\/p>\n<p>3.1.1 Oficina de Planeaci\u00f3n \u00a0 \u00a0<\/p>\n<p>3.1.2 Oficina de Control Interno \u00a0 \u00a0<\/p>\n<p>3.2 Direcci\u00f3n de Gobierno y \u00c1reas \u00a0Estrat\u00e9gicas \u00a0 \u00a0<\/p>\n<p>3.3 Secretar\u00eda Privada \u00a0 \u00a0<\/p>\n<p>3.3.1 Secretar\u00eda para la Seguridad \u00a0Presidencial \u00a0 \u00a0<\/p>\n<p>3.3.2 Casa Militar \u00a0 \u00a0<\/p>\n<p>3.3.3 Direcci\u00f3n de Eventos \u00a0 \u00a0<\/p>\n<p>3.3.4 Direcci\u00f3n de Discursos \u00a0 \u00a0<\/p>\n<p>3.4 Secretar\u00eda Jur\u00eddica \u00a0 \u00a0<\/p>\n<p>3.5 Secretar\u00eda de Transparencia \u00a0 \u00a0<\/p>\n<p>3.6 Consejer\u00eda Presidencial para la Equidad \u00a0de la Mujer \u00a0 \u00a0<\/p>\n<p>3.7 Direcci\u00f3n para Asuntos Pol\u00edticos \u00a0 \u00a0<\/p>\n<p>3.8 Direcci\u00f3n para las Regiones \u00a0 \u00a0<\/p>\n<p>3.9 Subdirecci\u00f3n de Operaciones \u00a0 \u00a0<\/p>\n<p>3.9.1 Oficina de Control Interno \u00a0Disciplinario \u00a0 \u00a0<\/p>\n<p>3.9.2 \u00c1rea Administrativa \u00a0 \u00a0<\/p>\n<p>3.9.3 \u00c1rea Financiera \u00a0 \u00a0<\/p>\n<p>3.9.4 \u00c1rea de Contratos \u00a0 \u00a0<\/p>\n<p>3.9.5 \u00c1rea de Talento Humano \u00a0 \u00a0<\/p>\n<p>3.9.6 \u00c1rea de Tecnolog\u00edas y Sistemas de \u00a0Informaci\u00f3n \u00a0 \u00a0<\/p>\n<p>4. Despacho Ministro Consejero para el \u00a0Sector Privado, Competitividad y Equidad \u00a0 \u00a0<\/p>\n<p>4.1 Consejer\u00eda Presidencial para la Primera \u00a0Infancia \u00a0 \u00a0<\/p>\n<p>4.2 Consejer\u00eda Presidencial del Sistema de \u00a0Competitividad e Innovaci\u00f3n \u00a0 \u00a0<\/p>\n<p>4.3 Direcci\u00f3n para el Sector Privado \u00a0 \u00a0<\/p>\n<p>4.4 Direcci\u00f3n del Sistema Nacional de \u00a0Juventud \u201cColombia Joven\u201d. \u00a0 \u00a0<\/p>\n<p>5. Despacho Ministro Consejero para el \u00a0Posconflicto, Derechos Humanos y Seguridad \u00a0 \u00a0<\/p>\n<p>5.1 Consejer\u00eda Presidencial para los \u00a0Derechos Humanos \u00a0 \u00a0<\/p>\n<p>5.2 Direcci\u00f3n para la Acci\u00f3n Integral contra \u00a0Minas Antipersonales \u00a0 \u00a0<\/p>\n<p>5.3 Direcci\u00f3n de Seguridad \u00a0 \u00a0<\/p>\n<p>5.4 Direcci\u00f3n para el Posconflicto \u00a0 \u00a0<\/p>\n<p>6. Despacho Ministro Consejero de \u00a0Comunicaciones \u00a0 \u00a0<\/p>\n<p>6.1 Direcci\u00f3n para la Estrategia de \u00a0Comunicaci\u00f3n \u00a0 \u00a0<\/p>\n<p>6.2 Direcci\u00f3n para la Relaci\u00f3n con los \u00a0Medios \u00a0 \u00a0<\/p>\n<p>7. Oficina del Alto Comisionado para la Paz \u00a0 \u00a0<\/p>\n<p>7.1 Direcci\u00f3n Tem\u00e1tica \u00a0 \u00a0<\/p>\n<p>8. \u00d3rganos de Asesor\u00eda y Coordinaci\u00f3n \u00a0 \u00a0<\/p>\n<p>8.1 Comit\u00e9 Ejecutivo de la Presidencia \u00a0 \u00a0<\/p>\n<p>8.2 Comit\u00e9 de Coordinaci\u00f3n del Sistema de \u00a0Control Interno \u00a0 \u00a0<\/p>\n<p>8.3 Comisi\u00f3n de Personal \u00a0 \u00a0<\/p>\n<p>Para el apoyo de las funciones asignadas al \u00a0Vicepresidente de la Rep\u00fablica se contar\u00e1 con las siguientes direcciones: \u00a0 \u00a0<\/p>\n<p>9. Direcci\u00f3n para Proyectos Especiales. \u00a0 \u00a0<\/p>\n<p>10. Direcci\u00f3n para la Coordinaci\u00f3n de \u00a0Infraestructura \u00a0 \u00a0<\/p>\n<p>11. Direcci\u00f3n para la Coordinaci\u00f3n de \u00a0Vivienda. \u00a0 \u00a0<\/p>\n<p>CAP\u00cdTULO II \u00a0 \u00a0<\/p>\n<p>Funciones de las dependencias \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00b0. Modif\u00edcase el numeral 24 y \u00a0adici\u00f3nanse los numerales 25 y 26 al art\u00edculo 8\u00b0 del Decreto n\u00famero \u00a01649 de 2014, en las funciones del Despacho del Director del Departamento, \u00a0as\u00ed: \u00a0 \u00a0<\/p>\n<p>24. Asesorar al Presidente de la Rep\u00fablica \u00a0en la relaci\u00f3n con las regiones y en especial en la implementaci\u00f3n de \u00a0programas, planes y proyectos en estas. \u00a0 \u00a0<\/p>\n<p>25. Orientar y coordinar la ruta de acceso \u00a0de Colombia a la Organizaci\u00f3n para la Cooperaci\u00f3n y Desarrollo Econ\u00f3mico \u00a0(OCDE). \u00a0 \u00a0<\/p>\n<p>26. Ejercer las dem\u00e1s funciones que le sean \u00a0asignadas y que correspondan a la naturaleza de la Dependencia. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 4\u00b0. Direcci\u00f3n de Gesti\u00f3n General. Son funciones de la Direcci\u00f3n de \u00a0Gesti\u00f3n General: \u00a0 \u00a0<\/p>\n<p>1. Orientar, coordinar y monitorear el \u00a0cumplimiento del Plan Estrat\u00e9gico y del Plan de Acci\u00f3n institucional de las \u00a0dependencias misionales del Departamento. \u00a0 \u00a0<\/p>\n<p>2. Asesorar al Director del Departamento en \u00a0la formulaci\u00f3n de la pol\u00edtica o planes de acci\u00f3n del Sector y asistirlo en las \u00a0funciones de direcci\u00f3n, coordinaci\u00f3n y control que le corresponden. \u00a0 \u00a0<\/p>\n<p>3. Dirigir la elaboraci\u00f3n de los informes y \u00a0estudios especiales que sobre el desarrollo de los planes y programas del \u00a0sector deban presentarse. \u00a0 \u00a0<\/p>\n<p>4. Velar por la aplicaci\u00f3n del Plan de \u00a0Desarrollo Administrativo y otros planes espec\u00edficos del sector administrativo. \u00a0 \u00a0<\/p>\n<p>5. Coordinar con las \u00a0dem\u00e1s dependencias del Departamento Administrativo de la Presidencia de la \u00a0Rep\u00fablica y con aquellas entidades que se requiera, los aspectos log\u00edsticos \u00a0inherentes a la ejecuci\u00f3n del gobierno y las \u00e1reas estrat\u00e9gicas. \u00a0 \u00a0<\/p>\n<p>6. Preparar para el \u00a0Director del Departamento, en colaboraci\u00f3n con las dem\u00e1s dependencias \u00a0pertinentes, los informes y estudios que aquel solicite y coordinar la \u00a0elaboraci\u00f3n de los informes peri\u00f3dicos que debe presentar el Departamento \u00a0Administrativo a las diferentes entidades del Estado. \u00a0 \u00a0<\/p>\n<p>7. Asistir al \u00a0Director del Departamento en sus relaciones con otras autoridades cuando este \u00a0lo requiera. \u00a0 \u00a0<\/p>\n<p>8. Representar al \u00a0Director del Departamento en las actividades oficiales que este le se\u00f1ale. \u00a0 \u00a0<\/p>\n<p>9. Asistir al \u00a0Director del Departamento en el ejercicio de sus funciones de direcci\u00f3n, \u00a0coordinaci\u00f3n y control del Departamento Administrativo de la Presidencia de la \u00a0Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>10. Asistir a las \u00a0juntas, consejos u otros cuerpos colegiados a las que haya sido delegado. \u00a0 \u00a0<\/p>\n<p>11. Establecer los \u00a0lineamientos a seguir por parte de las dependencias del Departamento \u00a0Administrativo de la Presidencia de la Rep\u00fablica en materia de cooperaci\u00f3n \u00a0internacional. \u00a0 \u00a0<\/p>\n<p>12. Liderar, \u00a0coordinar y acompa\u00f1ar las iniciativas de cooperaci\u00f3n internacional presentadas \u00a0por las dependencias del Departamento Administrativo de la Presidencia de la \u00a0Rep\u00fablica en el marco de sus competencias. \u00a0 \u00a0<\/p>\n<p>13. Derogado por el Decreto 724 de 2016, \u00a0art\u00edculo 16. Actuar como \u00a0Secretario T\u00e9cnico del Comit\u00e9 Ejecutivo de la Presidencia. \u00a0 \u00a0<\/p>\n<p>14. Ejercer las \u00a0dem\u00e1s funciones que le sean delegadas o asignadas por el Director del \u00a0Departamento y que correspondan a la naturaleza de la Dependencia. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 5\u00b0. Oficina de Planeaci\u00f3n. Son funciones \u00a0de la Oficina de Planeaci\u00f3n: \u00a0 \u00a0<\/p>\n<p>1. Orientar y \u00a0coordinar el desarrollo de los procesos de planeaci\u00f3n, de acuerdo con los \u00a0lineamientos del Director del Departamento Administrativo de la Presidencia de \u00a0la Rep\u00fablica y el Director de Gesti\u00f3n General. \u00a0 \u00a0<\/p>\n<p>2. Asesorar al \u00a0Director del Departamento y al Director de Gesti\u00f3n General en la definici\u00f3n, \u00a0coordinaci\u00f3n, adopci\u00f3n y seguimiento de las pol\u00edticas sectoriales. \u00a0 \u00a0<\/p>\n<p>3. Elaborar y hacer \u00a0seguimiento al Plan Estrat\u00e9gico Institucional y Sectorial en coordinaci\u00f3n con \u00a0las dependencias del Departamento Administrativo de la Presidencia de la \u00a0Rep\u00fablica y las entidades adscritas al sector. \u00a0 \u00a0<\/p>\n<p>4. Coordinar con las \u00a0dependencias de la entidad, la formulaci\u00f3n y seguimiento del Plan Operativo \u00a0Anual del Departamento Administrativo de la Presidencia de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>5. Dise\u00f1ar \u00a0metodolog\u00edas para construir indicadores que permitan medir y evaluar la gesti\u00f3n \u00a0y resultados del Departamento Administrativo de la Presidencia de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>6. Dar concepto de \u00a0viabilidad a los proyectos de inversi\u00f3n del Departamento Administrativo de la \u00a0Presidencia de la Rep\u00fablica y de las entidades adscritas del sector. \u00a0 \u00a0<\/p>\n<p>7. Asesorar y apoyar \u00a0a las dependencias del Departamento Administrativo de la Presidencia de la \u00a0Rep\u00fablica y entidades del sector, en la formulaci\u00f3n y desarrollo de los \u00a0proyectos de inversi\u00f3n. \u00a0 \u00a0<\/p>\n<p>8. Elaborar y \u00a0consolidar en coordinaci\u00f3n con el \u00c1rea Financiera el anteproyecto de \u00a0presupuesto de la entidad y del sector para su presentaci\u00f3n al Ministerio de \u00a0Hacienda y Cr\u00e9dito P\u00fablico. \u00a0 \u00a0<\/p>\n<p>9. Adelantar los \u00a0tr\u00e1mites necesarios, con el apoyo del \u00c1rea Financiera, para la consecuci\u00f3n de \u00a0cr\u00e9dito interno y externo que a juicio del Director del Departamento sean \u00a0requeridos para el cumplimiento y desarrollo de sus proyectos y programas. \u00a0 \u00a0<\/p>\n<p>10. Coordinar con \u00a0las dependencias del Departamento Administrativo de la Presidencia de la \u00a0Rep\u00fablica y sus entidades adscritas, con base en las directrices del Ministerio \u00a0de Hacienda y Cr\u00e9dito P\u00fablico y el Departamento Nacional de Planeaci\u00f3n, la \u00a0programaci\u00f3n del Marco de Gastos de Mediano Plazo y realizar los tr\u00e1mites \u00a0correspondientes. \u00a0 \u00a0<\/p>\n<p>11. Realizar los \u00a0tr\u00e1mites presupuesta les de gastos de inversi\u00f3n del Departamento Administrativo \u00a0de la Presidencia de la Rep\u00fablica y del sector ante el Ministerio de Hacienda y \u00a0Cr\u00e9dito P\u00fablico y el Departamento Nacional de Planeaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>12. Efectuar el \u00a0seguimiento a la ejecuci\u00f3n de los programas, planes y proyectos financiados con \u00a0recursos del presupuesto nacional, con fuente de cooperaci\u00f3n internacional \u00a0reembolsable y no reembolsable. \u00a0 \u00a0<\/p>\n<p>13. Administrar el \u00a0Sistema Integrado de Gesti\u00f3n de la Presidencia de la Rep\u00fablica, acorde con los \u00a0procesos establecidos para tal fin. \u00a0 \u00a0<\/p>\n<p>14. Coordinar y \u00a0elaborar los estudios organizacionales necesarios para la implementaci\u00f3n, \u00a0dise\u00f1o y actualizaci\u00f3n de sistemas de mejoramiento de gesti\u00f3n de la entidad. \u00a0 \u00a0<\/p>\n<p>15. Formular \u00a0herramientas metodol\u00f3gicas que faciliten la definici\u00f3n, mejoramiento y \u00a0actualizaci\u00f3n de los procesos de la entidad. \u00a0 \u00a0<\/p>\n<p>16. Coordinar la \u00a0elaboraci\u00f3n y env\u00edo del Informe de gesti\u00f3n de la Presidencia de la Rep\u00fablica y \u00a0del sector ante el Congreso de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>17. Coordinar y \u00a0adelantar los tr\u00e1mites para la incorporaci\u00f3n al presupuesto del Departamento \u00a0Administrativo de la Presidencia de la Rep\u00fablica de los recursos de Cooperaci\u00f3n \u00a0Internacional, t\u00e9cnica y financiera no reembolsable. \u00a0 \u00a0<\/p>\n<p>18. Las dem\u00e1s que \u00a0correspondan con la naturaleza de la dependencia. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 6\u00b0. Oficina de Control Interno. Son \u00a0funciones de la Oficina de Control Interno: \u00a0 \u00a0<\/p>\n<p>1. Planear, dirigir \u00a0y organizar la verificaci\u00f3n y evaluaci\u00f3n del Sistema de Control Interno. \u00a0 \u00a0<\/p>\n<p>2. Verificar que el \u00a0Sistema de Control Interno est\u00e9 formalmente establecido dentro de la \u00a0organizaci\u00f3n y que su ejercicio sea intr\u00ednseco al desarrollo de las funciones \u00a0de todos los cargos y, en particular, de aquellos que tengan responsabilidad de \u00a0mando. \u00a0 \u00a0<\/p>\n<p>3. Verificar que los \u00a0controles definidos para los procesos y actividades de la organizaci\u00f3n, se \u00a0cumplan por los responsables de su ejecuci\u00f3n y en especial, que las \u00e1reas o \u00a0empleados encargados de la aplicaci\u00f3n del r\u00e9gimen disciplinario ejerzan \u00a0adecuadamente esta funci\u00f3n. \u00a0 \u00a0<\/p>\n<p>4. Verificar que los \u00a0controles asociados con todas y cada una de las actividades de la organizaci\u00f3n, \u00a0est\u00e9n adecuadamente definidos, sean apropiados y se mejoren permanentemente, de \u00a0acuerdo con la evoluci\u00f3n de la entidad. \u00a0 \u00a0<\/p>\n<p>5. Velar por el \u00a0cumplimiento de las leyes, normas, pol\u00edticas, procedimientos, planes, \u00a0programas, proyectos y metas de la organizaci\u00f3n y recomendar los ajustes \u00a0necesarios. \u00a0 \u00a0<\/p>\n<p>6. Servir de apoyo a \u00a0los directivos en el proceso de toma de decisiones, a fin que se obtengan los \u00a0resultados esperados. \u00a0 \u00a0<\/p>\n<p>7. Verificar los \u00a0procesos relacionados con el manejo de los recursos, bienes y los sistemas de \u00a0informaci\u00f3n de la entidad y recomendar los correctivos que sean necesarios. \u00a0 \u00a0<\/p>\n<p>8. Fomentar en toda \u00a0la organizaci\u00f3n la formaci\u00f3n de una cultura de control que contribuya al \u00a0mejoramiento continuo en el cumplimiento de la misi\u00f3n institucional. \u00a0 \u00a0<\/p>\n<p>9. Evaluar y \u00a0verificar la aplicaci\u00f3n de los mecanismos de participaci\u00f3n ciudadana, que en \u00a0desarrollo del mandato constitucional y legal, dise\u00f1e la entidad \u00a0correspondiente. \u00a0 \u00a0<\/p>\n<p>10. Mantener \u00a0permanentemente informados a los directivos acerca del estado del control \u00a0interno dentro de la entidad, dando cuenta de las debilidades detectadas y de \u00a0las fallas en su cumplimiento. \u00a0 \u00a0<\/p>\n<p>11. Verificar que se \u00a0implanten las medidas respectivas recomendadas. \u00a0 \u00a0<\/p>\n<p>12. Presentar los \u00a0informes que le solicite el Director del Departamento y el Director de Gesti\u00f3n \u00a0General en relaci\u00f3n con los asuntos a su cargo. \u00a0 \u00a0<\/p>\n<p>13. Coordinar y \u00a0consolidar las respuestas a los requerimientos presentados por los organismos \u00a0de control, respecto de la gesti\u00f3n del Departamento Administrativo. \u00a0 \u00a0<\/p>\n<p>14. Reportar al \u00a0Director del Departamento Administrativo de la Presidencia de la Rep\u00fablica, as\u00ed \u00a0como a los organismos de control, los posibles actos de corrupci\u00f3n e \u00a0irregularidades que haya encontrado en el ejercicio de sus funciones. \u00a0 \u00a0<\/p>\n<p>15. Publicar cada \u00a0cuatro meses en la p\u00e1gina de la entidad, un informe pormenorizado del estado \u00a0del control interno de la entidad. \u00a0 \u00a0<\/p>\n<p>16. Las dem\u00e1s que le \u00a0asigne el Director del Departamento Administrativo de la Presidencia de la \u00a0Rep\u00fablica, de acuerdo con el car\u00e1cter de sus funciones y el Decreto n\u00famero \u00a01826 de 1994. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 7\u00b0. Direcci\u00f3n de Gobierno y \u00c1reas Estrat\u00e9gicas. Son \u00a0funciones de la Direcci\u00f3n de Gobierno y \u00c1reas Estrat\u00e9gicas: \u00a0 \u00a0<\/p>\n<p>1. Asesorar al \u00a0Director del Departamento en la implementaci\u00f3n de pol\u00edticas y estrategias \u00a0gubernamentales, a cargo de los ministerios, departamentos administrativos y \u00a0dem\u00e1s entidades. \u00a0 \u00a0<\/p>\n<p>2. Apoyar al \u00a0Director del Departamento en la implementaci\u00f3n y seguimiento de las prioridades \u00a0del Presidente de la Rep\u00fablica en \u00e1reas y proyectos estrat\u00e9gicos. \u00a0 \u00a0<\/p>\n<p>3. Asesorar y \u00a0apoyar, por instrucciones del Director del Departamento, a las entidades \u00a0gubernamentales para la efectiva ejecuci\u00f3n de las prioridades del Presidente de \u00a0la Rep\u00fablica, en las \u00e1reas que dependan de estas entidades. \u00a0 \u00a0<\/p>\n<p>4. Apoyar al \u00a0Director del Departamento en la coordinaci\u00f3n de la ejecuci\u00f3n del gobierno con \u00a0los diferentes Ministerios y Departamentos Administrativos. \u00a0 \u00a0<\/p>\n<p>5. Proponer, al \u00a0Director del Departamento, mecanismos de articulaci\u00f3n y coordinaci\u00f3n entre las \u00a0diferentes entidades que tienen a su cargo tr\u00e1mites que inciden en la \u00a0estructuraci\u00f3n y ejecuci\u00f3n de las prioridades del Presidente de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>6. Asesorar al \u00a0Director del Departamento en la coordinaci\u00f3n, implementaci\u00f3n de mecanismos para \u00a0la ejecuci\u00f3n y rendici\u00f3n de cuentas del gobierno y preparar los documentos y \u00a0registros que se requieran. \u00a0 \u00a0<\/p>\n<p>7. Numeral modificado por el Decreto 724 de 2016, \u00a0art\u00edculo 13. Hacer seguimiento a los \u00a0compromisos de las audiencias otorgadas por el Presidente de la Rep\u00fablica, y \u00a0preparar un informe peri\u00f3dico para el Director del Departamento de la \u00a0Presidencia de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>Texto inicial del \u00a0numeral 7: \u201cHacer seguimiento a \u00a0los compromisos de las audiencias otorgadas por el Presidente de la Rep\u00fablica, \u00a0y preparar un informe peri\u00f3dico al Comit\u00e9 Ejecutivo de la Presidencia.\u201d. \u00a0 \u00a0<\/p>\n<p>8. Apoyar al \u00a0Director del Departamento en la coordinaci\u00f3n de la gesti\u00f3n de los temas \u00a0misionales a cargo de las dependencias del Departamento que este le asigne. \u00a0 \u00a0<\/p>\n<p>9. Asesorar al \u00a0Director del Departamento en la fijaci\u00f3n de las pol\u00edticas, estrategias e \u00a0implementaci\u00f3n de indicadores encaminados a fortalecer la eficiencia de la \u00a0Administraci\u00f3n P\u00fablica y el servicio a los ciudadanos, en coordinaci\u00f3n con las \u00a0entidades estatales cuyas funciones tengan relaci\u00f3n con el tema. \u00a0 \u00a0<\/p>\n<p>10. Coordinar con el Departamento Nacional de Planeaci\u00f3n, el \u00a0fortalecimiento de los indicadores de seguimiento al Plan Nacional de \u00a0Desarrollo. \u00a0 \u00a0<\/p>\n<p>11. Apoyar, de \u00a0acuerdo con las instrucciones del Director del Departamento, a las entidades \u00a0del gobierno nacional en la formulaci\u00f3n de las pol\u00edticas p\u00fablicas. \u00a0 \u00a0<\/p>\n<p>12. Ejercer las \u00a0dem\u00e1s funciones que le sean delegadas o asignadas por el Director del Departamento \u00a0y que correspondan a la naturaleza de la Dependencia\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 8\u00b0. Derogado por el Decreto 724 de 2016, \u00a0art\u00edculo 16. Direcci\u00f3n para las Regiones. Son funciones de \u00a0la Direcci\u00f3n para las Regiones: \u00a0 \u00a0<\/p>\n<p>1. Asesorar al Director del Departamento en relaci\u00f3n con \u00a0pol\u00edticas, planes y programas que el gobierno nacional debe adelantar en las \u00a0regiones. \u00a0 \u00a0<\/p>\n<p>2. Coordinar la realizaci\u00f3n de espacios de interacci\u00f3n y \u00a0di\u00e1logo permanente entre los ciudadanos, las autoridades de orden territorial y \u00a0el gobierno nacional, seg\u00fan las directrices del Director del Departamento. \u00a0 \u00a0<\/p>\n<p>3. Coordinar con la Direcci\u00f3n de Gobierno y \u00c1reas \u00a0Estrat\u00e9gicas la ejecuci\u00f3n de pol\u00edticas, planes y proyectos estrat\u00e9gicos del \u00a0gobierno nacional en territorio, atendiendo las directrices del Director del \u00a0Departamento. \u00a0 \u00a0<\/p>\n<p>4. Proponer los planes y proyectos necesarios para la \u00a0efectiva comunicaci\u00f3n entre las entidades territoriales y el gobierno nacional \u00a0e implementar los mecanismos de gesti\u00f3n y coordinaci\u00f3n entre el gobierno \u00a0nacional y los gobiernos territoriales, seg\u00fan las directrices del Presidente de \u00a0la Rep\u00fablica o del Director del Departamento. \u00a0 \u00a0<\/p>\n<p>5. Efectuar el seguimiento a las tareas y compromisos \u00a0que se deriven de la agenda del Presidente de la Rep\u00fablica en las entidades \u00a0territoriales. \u00a0 \u00a0<\/p>\n<p>6. Coordinar con las dem\u00e1s dependencias del Departamento \u00a0Administrativo de la Presidencia de la Rep\u00fablica y con aquellas entidades que \u00a0se requiera, los aspectos log\u00edsticos, y de tecnolog\u00eda y comunicaciones \u00a0inherentes a la interacci\u00f3n que se adelante con las entidades territoriales. \u00a0 \u00a0<\/p>\n<p>7. Preparar los documentos y registros que se requieran \u00a0para la interacci\u00f3n con las entidades territoriales, seg\u00fan las directrices del \u00a0Presidente de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>8. Coordinar y apoyar a las entidades competentes, en la \u00a0implementaci\u00f3n de las pol\u00edticas, programas y proyectos a ejecutar por parte del \u00a0gobierno nacional en las regiones. \u00a0 \u00a0<\/p>\n<p>9. Las dem\u00e1s que le correspondan de acuerdo con la \u00a0naturaleza de la dependencia y las que le sean asignadas por el Presidente de \u00a0la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 9\u00b0. \u00a0Modif\u00edcase el art\u00edculo 19 del Decreto n\u00famero \u00a01649 de 2014 en relaci\u00f3n con la denominaci\u00f3n y las funciones del Despacho \u00a0Ministro Consejero para el Gobierno y el Sector Privado, el cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201cArt\u00edculo 19. Despacho Ministro Consejero para el Sector \u00a0Privado, Competitividad y Equidad. Son funciones del Despacho del \u00a0Ministro Consejero para el Sector Privado, Competitividad y Equidad: \u00a0 \u00a0<\/p>\n<p>1. Asesorar al \u00a0Presidente de la Rep\u00fablica en las actividades relacionadas con el Sector \u00a0Privado y el Sistema Nacional de Competitividad. \u00a0 \u00a0<\/p>\n<p>2. Servir como \u00a0vocero del gobierno en los asuntos que determine el Presidente de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>3. Asesorar en el \u00a0seguimiento y la ejecuci\u00f3n de las pol\u00edticas e instrucciones impartidas por el Presidente \u00a0de Rep\u00fablica y el gobierno nacional, en materia de coordinaci\u00f3n entre el sector \u00a0p\u00fablico y el privado. \u00a0 \u00a0<\/p>\n<p>4. Recomendar la \u00a0implementaci\u00f3n de los mecanismos de gesti\u00f3n y coordinaci\u00f3n entre los sectores \u00a0p\u00fablico y privado, de acuerdo con las instrucciones que imparte el Presidente \u00a0de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>5. Coordinar a los \u00a0actores gubernamentales que intervengan en la implementaci\u00f3n de la gesti\u00f3n \u00a0p\u00fablica-privada, y adelantar el seguimiento de las actividades concertadas. \u00a0 \u00a0<\/p>\n<p>6. Asesorar al \u00a0Presiente de la Rep\u00fablica en las \u00e1reas y temas estrat\u00e9gicos que requieran de la \u00a0formulaci\u00f3n de pol\u00edticas p\u00fablicas con la participaci\u00f3n del sector privado. \u00a0 \u00a0<\/p>\n<p>7. Asesorar en \u00a0materia de ciencia, tecnolog\u00eda e innovaci\u00f3n, y recomendar mecanismos de \u00a0coordinaci\u00f3n entre las entidades p\u00fablicas y privadas que cumplan estas \u00a0funciones. \u00a0 \u00a0<\/p>\n<p>8. Asesorar en \u00a0materia de competitividad y promoci\u00f3n de la inversi\u00f3n extranjera en el pa\u00eds, y \u00a0recomendar mecanismos de concertaci\u00f3n entre las entidades p\u00fablicas y privadas \u00a0que cumplan estas funciones. \u00a0 \u00a0<\/p>\n<p>9. Asesorar en los \u00a0asuntos econ\u00f3micos que por decisi\u00f3n expresa del Presidente de la Rep\u00fablica le \u00a0sean encomendados, rendir los informes que le sean solicitados y presentar las \u00a0recomendaciones para la implementaci\u00f3n de las pol\u00edticas en la materia. \u00a0 \u00a0<\/p>\n<p>10. Coadyuvar con la \u00a0Consejer\u00eda Presidencial para la Primera Infancia en la coordinaci\u00f3n con las \u00a0entidades competentes los procesos de formulaci\u00f3n de pol\u00edticas y programas para \u00a0la primera infancia. \u00a0 \u00a0<\/p>\n<p>11. Liderar el \u00a0Sistema Nacional de las Juventudes y velar por el cumplimiento de las funciones \u00a0del mismo establecidas en la normatividad vigente. \u00a0 \u00a0<\/p>\n<p>12. Las dem\u00e1s que le \u00a0correspondan de acuerdo con la naturaleza de la dependencia y las que le sean \u00a0asignadas por el Presidente de la Rep\u00fablica y el Director del Departamento \u00a0Administrativo de la Presidencia de la Rep\u00fablica\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 10. \u00a0Modif\u00edcase el numeral 7 del art\u00edculo 40 del Decreto n\u00famero \u00a01649 de 2014, en relaci\u00f3n con una funci\u00f3n de la Subdirecci\u00f3n de \u00a0Operaciones, la cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201c7. Liderar y \u00a0establecer los procedimientos para garantizar la atenci\u00f3n de Peticiones, \u00a0Quejas, Reclamos y Sugerencias para la atenci\u00f3n al usuario\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 11. \u00a0Modif\u00edcase en el \u00c1rea Administrativa la funci\u00f3n se\u00f1alada en el numeral 3 del \u00a0art\u00edculo 44 del Decreto n\u00famero \u00a01649 de 2014, la cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201c3. Elaborar, en \u00a0coordinaci\u00f3n con el \u00c1rea Financiera, el Plan de Adquisiciones y sus \u00a0modificaciones, de acuerdo con la programaci\u00f3n que realicen las \u00e1reas y \u00a0efectuar el seguimiento a su ejecuci\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 12. \u00a0Modif\u00edcase el numeral 1 y 2 del art\u00edculo 45 del Decreto n\u00famero \u00a01649 de 2014 en relaci\u00f3n con las funciones del \u00c1rea Financiera, los cuales \u00a0quedar\u00e1n as\u00ed: \u00a0 \u00a0<\/p>\n<p>1. Ejecutar los \u00a0planes y programas relacionados con el manejo financiero, incluidos los \u00a0procesos presupuestales, contables y de pagadur\u00eda. \u00a0 \u00a0<\/p>\n<p>2. Coordinar y \u00a0controlar las actividades de pagadur\u00eda, presupuesto y contabilidad del \u00a0Departamento Administrativo de la Presidencia de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 13. \u00a0Modif\u00edcase el numeral 4 del art\u00edculo 47 del Decreto n\u00famero \u00a01649 de 2014 en relaci\u00f3n con una funci\u00f3n del \u00c1rea de Talento Humano, la \u00a0cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201c4. Dise\u00f1ar, \u00a0dirigir, administrar y evaluar los programas de formaci\u00f3n, capacitaci\u00f3n, \u00a0incentivos, bienestar, salud ocupacional y desarrollo de los servidores \u00a0p\u00fablicos del Departamento, de acuerdo con lo previsto en la ley y en el Plan \u00a0Nacional de Formaci\u00f3n y Capacitaci\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 14. \u00a0Modif\u00edcase el art\u00edculo 48 del Decreto n\u00famero \u00a01649 de 2014 en relaci\u00f3n con la denominaci\u00f3n del \u00c1rea de Informaci\u00f3n y \u00a0Sistemas la cual se denominar\u00e1 \u201c\u00c1rea de Tecnolog\u00eda y Sistemas de Informaci\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 15. Asignaci\u00f3n de funciones. Las \u00a0dependencias que conforman la estructura interna del Departamento \u00a0Administrativo de la Presidencia de la Rep\u00fablica, adem\u00e1s de las funciones \u00a0se\u00f1aladas en el Decreto n\u00famero \u00a01649 de 2015 y en el presente decreto, deber\u00e1n cumplir las funciones que le \u00a0sean asignadas por el Presidente de la Rep\u00fablica y por el Director del \u00a0Departamento Administrativo de la Presidencia de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>Igualmente, las \u00a0funciones que adelanten las dependencias del Departamento Administrativo de la \u00a0Presidencia de la Rep\u00fablica relacionadas con la gesti\u00f3n para obtener \u00a0cooperaci\u00f3n internacional, deber\u00e1n cumplirse atendiendo los lineamientos establecidos \u00a0por la Direcci\u00f3n de Gesti\u00f3n General del Departamento y en coordinaci\u00f3n con la \u00a0Agencia Presidencial de Cooperaci\u00f3n Internacional de Colombia (APC). \u00a0 \u00a0<\/p>\n<p>CAP\u00cdTULO III \u00a0 \u00a0<\/p>\n<p>Disposiciones \u00a0generales \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 16. Planta de Personal. El Gobierno \u00a0nacional en ejercicio de sus competencias constitucionales y legales proceder\u00e1 \u00a0a modificar la planta de personal del Departamento Administrativo de la \u00a0Presidencia de la Rep\u00fablica, de conformidad con la modificaci\u00f3n de estructura \u00a0prevista en el presente decreto. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 17. Derogatorias y vigencia. El presente decreto \u00a0rige a partir de la fecha de su publicaci\u00f3n, modifica en lo pertinente los \u00a0art\u00edculos 4\u00b0, 5\u00b0, 8\u00b0, 19, 40, 44, 45, 47 y 48 del Decreto n\u00famero \u00a01649 de 2014 y deroga los art\u00edculos 22, 23, 24, 41 y 42 del mismo decreto. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y \u00a0c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. \u00a0C., a 4 de noviembre de 2015. \u00a0 \u00a0<\/p>\n<p>JUAN MANUEL SANTOS \u00a0CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>El Ministro de \u00a0Hacienda y Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p>Mauricio C\u00e1rdenas Santamar\u00eda. \u00a0 \u00a0<\/p>\n<p>La Directora del \u00a0Departamento Administrativo de la Presidencia de la Rep\u00fablica, \u00a0 \u00a0<\/p>\n<p>Mar\u00eda Lorena Guti\u00e9rrez Botero. \u00a0 \u00a0<\/p>\n<p>La Directora del \u00a0Departamento Administrativo de la Funci\u00f3n P\u00fablica, \u00a0 \u00a0<\/p>\n<p>Liliana Caballero Dur\u00e1n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 2145 DE 2015 \u00a0 \u00a0 (noviembre 4) \u00a0 \u00a0 D.O. 49.686, noviembre 4 de 2015 \u00a0 \u00a0 por el cual se modifica la estructura del Departamento \u00a0Administrativo de la Presidencia de la Rep\u00fablica. \u00a0 \u00a0 Nota 1: Derogado por el Decreto 672 de 2017, \u00a0art\u00edculo 54. \u00a0 \u00a0 Nota 2: Modificado por el Decreto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-49160","post","type-post","status-publish","format-standard","hentry","category-decretos-2015"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=49160"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49160\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=49160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=49160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=49160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}