{"id":49339,"date":"2023-08-16T20:50:42","date_gmt":"2023-08-16T20:50:42","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-2463-de-2015\/"},"modified":"2023-08-16T20:50:42","modified_gmt":"2023-08-16T20:50:42","slug":"decreto-2463-de-2015","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-2463-de-2015\/","title":{"rendered":"DECRETO 2463 DE 2015"},"content":{"rendered":"\n<p>DECRETO 2463 DE 2015 \u00a0 \u00a0\u00a0<\/p>\n<p>(diciembre 17) \u00a0 \u00a0<\/p>\n<p>D.O. 49.729, diciembre \u00a017 de 2015 \u00a0 \u00a0<\/p>\n<p>por el cual se \u00a0confiere la condecoraci\u00f3n \u201cJos\u00e9 Ignacio de M\u00e1rquez al M\u00e9rito Judicial\u201d para el \u00a0a\u00f1o 2015. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, \u00a0en ejercicio de sus facultades constitucionales y legales, en especial las \u00a0conferidas por la Ley 4\u00aa de 1913 y el \u00a0art\u00edculo 10 del Decreto 1258 de 1970, \u00a0y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que el Decreto \u00a01258 del 27 de julio de 1970, cre\u00f3 la condecoraci\u00f3n \u201cJos\u00e9 Ignacio de M\u00e1rquez al M\u00e9rito Judicial\u201d, para exaltar las \u00a0virtudes y servicios de los funcionarios y empleados de la Rama Jurisdiccional \u00a0y del Ministerio P\u00fablico, como est\u00edmulo a la honestidad, consagraci\u00f3n, \u00a0perseverancia y superaci\u00f3n de estos servidores del Estado. \u00a0 \u00a0<\/p>\n<p>Que de acuerdo a lo dispuesto en el art\u00edculo \u00a0segundo del mismo decreto, la condecoraci\u00f3n \u201cJos\u00e9 Ignacio de M\u00e1rquez al M\u00e9rito Judicial\u201d, se otorga en las \u00a0categor\u00edas oro, plata y bronce. \u00a0 \u00a0<\/p>\n<p>Que el art\u00edculo 155 de la Ley 270 de 1996, \u00a0determina que \u201cLos funcionarios y \u00a0empleados que se distingan en la prestaci\u00f3n de sus servicios, en los t\u00e9rminos \u00a0del reglamento, se har\u00e1n acreedores a los est\u00edmulos y distinciones que \u00a0determine la Sala Administrativa del Consejo Superior de la Judicatura, el \u00a0superior funcional podr\u00e1 postular los funcionarios y empleados que considere \u00a0candidatos id\u00f3neos para hacerse acreedores a estas distinciones (&#8230;)\u201d. \u00a0 \u00a0<\/p>\n<p>Que el numeral 27 del art\u00edculo 85 de la \u00a0misma ley, consagra que corresponde a la Sala Administrativa del Consejo \u00a0Superior de la Judicatura: \u201cAprobar \u00a0los reconocimientos y distinciones que se otorguen a los funcionarios de la \u00a0Rama Judicial por servicios excepcionales prestados a favor de la \u00a0administraci\u00f3n de justicia\u201d. \u00a0 \u00a0<\/p>\n<p>Que por su parte, la Sala Administrativa del \u00a0Consejo Superior de la Judicatura, mediante Acuerdos PSAA11-7711 de 2011, PSAA11-8712 \u00a0de 2011 y PSAA13-9908 de 2013, reglament\u00f3 la concesi\u00f3n de est\u00edmulos y \u00a0distinciones a los servidores de la Rama Judicial; estableciendo en su art\u00edculo \u00a012 del primer Acuerdo mencionado, que \u201cLa \u00a0Sala Administrativa del Consejo Superior de la Judicatura enviar\u00e1 al Presidente \u00a0de la Rep\u00fablica la relaci\u00f3n de las personas que se han hecho acreedoras a la \u00a0condecoraci\u00f3n honor\u00edfica \u201cJos\u00e9 Ignacio de M\u00e1rquez al M\u00e9rito Judicial\u201d y su \u00a0categor\u00eda, para que se expida el Decreto Ejecutivo de que trata el art\u00edculo 10 \u00a0del Decreto 1258 de 1970\u201d. \u00a0 \u00a0<\/p>\n<p>Que conforme a los criterios se\u00f1alados en el \u00a0art\u00edculo 4\u00b0 del Acuerdo PSAA 13-9908 de 2013, las Salas Administrativas de los \u00a0Consejos Seccionales de la Judicatura y las Direcciones Ejecutiva y Seccionales \u00a0de Administraci\u00f3n Judicial, as\u00ed como las distintas dependencias de la Sala \u00a0Administrativa del Consejo Superior de la Judicatura, esto es, la Presidencia \u00a0de la Sala, los despachos de los Magistrados y los Directores de las distintas \u00a0Unidades han postulado a los empleados del nivel administrativo acreedores a \u00a0dicha distinci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Que en este sentido, la Sala Administrativa \u00a0del Consejo Superior de la Judicatura a trav\u00e9s de la Resoluci\u00f3n PSAR 15-307 del \u00a016 de diciembre de 2015 otorg\u00f3 la condecoraci\u00f3n \u201cJos\u00e9 Ignacio de M\u00e1rquez al M\u00e9rito Judicial\u201d, en la categor\u00eda \u00a0bronce, aprobando las designaciones conforme al reglamento, teniendo en cuenta \u00a0las certificaciones allegadas por la Sala Administrativa de los Consejos \u00a0Seccionales de la Judicatura y las Direcciones Ejecutiva y Seccionales de Administraci\u00f3n \u00a0Judicial y las motivaciones de las postulaciones y designaciones. \u00a0 \u00a0<\/p>\n<p>Que de conformidad con el art\u00edculo 10 del Decreto \u00a01258 de julio 27 de 1970, modificado t\u00e1citamente por los art\u00edculos 85 \u00a0numeral 27 y 155 de la Ley 270 de 1996, en \u00a0concordancia con el art\u00edculo 12 del Acuerdo PSAA11-7711 de 2011, le corresponde \u00a0a la Sala Administrativa del Consejo Superior de la Judicatura indicar las \u00a0personas dignas de condecoraci\u00f3n, la \u00edndole de esta y su categor\u00eda, as\u00ed como \u00a0informar al Presidente de la Rep\u00fablica, para su otorgamiento mediante decreto \u00a0ejecutivo. \u00a0 \u00a0<\/p>\n<p>Que el Decreto \u00a01258 de julio 27 de 1970, en su art\u00edculo 13 establece que la imposici\u00f3n de \u00a0las condecoraciones la har\u00e1 el Presidente de la Rep\u00fablica o la persona que \u00e9l \u00a0designe, en ceremonia solemne. \u00a0 \u00a0<\/p>\n<p>Que en m\u00e9rito de lo expuesto, se otorgar\u00e1 la \u00a0condecoraci\u00f3n \u201cJos\u00e9 Ignacio de M\u00e1rquez \u00a0al M\u00e9rito Judicial\u201d, a los servidores de la Rama Judicial que han sido \u00a0propuestos por la Sala Administrativa del Consejo Superior de la Judicatura. \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Otorgamiento de la condecoraci\u00f3n en la categor\u00eda \u201cBronce\u201d. Otorgar la \u00a0Condecoraci\u00f3n \u201cJos\u00e9 Ignacio de M\u00e1rquez \u00a0al M\u00e9rito Judicial\u201d, en la categor\u00eda \u201cBronce\u201d por su dedicaci\u00f3n continua, su pulcritud y prestancia, \u00a0mereciendo ser se\u00f1alados como ejemplo de devoci\u00f3n en el servicio, a: \u00a0 \u00a0<\/p>\n<p>Luz Marina Veloza \u00a0Jim\u00e9nez \u00a0 \u00a0<\/p>\n<p>Directora Unidad de Desarrollo y An\u00e1lisis \u00a0Estad\u00edstico \u00a0 \u00a0<\/p>\n<p>Sala Administrativa del Consejo Superior de \u00a0la Judicatura \u00a0 \u00a0<\/p>\n<p>Rosana Paola Zuluaga \u00a0Monta\u00f1a \u00a0 \u00a0<\/p>\n<p>Directora Unidad Centro de Documentaci\u00f3n \u00a0Judicial \u00a0 \u00a0<\/p>\n<p>Sala Administrativa del Consejo Superior de \u00a0la Judicatura \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. Reconocimiento Acad\u00e9mico. Los designados tendr\u00e1n derecho al \u00a0reconocimiento acad\u00e9mico que determine la Sala Administrativa del Consejo \u00a0Superior de la Judicatura, conforme lo establece el art\u00edculo 2\u00b0 del Acuerdo \u00a0PSAA 13-9908 de 2013, expedido por la Sala Administrativa del Consejo Superior \u00a0de la Judicatura. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00b0. Vigencia. El presente decreto rige a partir de la fecha de su \u00a0publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese, comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 17 de diciembre de \u00a02015. \u00a0 \u00a0<\/p>\n<p>JUAN MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>El Ministro de Justicia y del Derecho, \u00a0 \u00a0<\/p>\n<p>Yesid Reyes Alvarado. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 2463 DE 2015 \u00a0 \u00a0\u00a0 (diciembre 17) \u00a0 \u00a0 D.O. 49.729, diciembre \u00a017 de 2015 \u00a0 \u00a0 por el cual se \u00a0confiere la condecoraci\u00f3n \u201cJos\u00e9 Ignacio de M\u00e1rquez al M\u00e9rito Judicial\u201d para el \u00a0a\u00f1o 2015. \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, \u00a0en ejercicio de sus facultades constitucionales y legales, en especial [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-49339","post","type-post","status-publish","format-standard","hentry","category-decretos-2015"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=49339"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49339\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=49339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=49339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=49339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}