{"id":49384,"date":"2023-08-16T21:29:30","date_gmt":"2023-08-16T21:29:30","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-4-de-2016\/"},"modified":"2023-08-16T21:29:30","modified_gmt":"2023-08-16T21:29:30","slug":"decreto-4-de-2016","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-4-de-2016\/","title":{"rendered":"DECRETO 4 DE 2016"},"content":{"rendered":"\n<p>DECRETO 04 DE 2016 \u00a0 \u00a0<\/p>\n<p>(enero 5) \u00a0 \u00a0<\/p>\n<p>D.O. 49.746, enero 5 de \u00a02016 \u00a0 \u00a0<\/p>\n<p>por el cual se \u00a0hace un nombramiento provisional en la planta de personal del Ministerio de \u00a0Relaciones Exteriores. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, \u00a0en ejercicio de sus facultades constitucionales y legales y, en especial, de \u00a0las que le confieren el numeral 2 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica, \u00a0el art\u00edculo 2.2.2.7.3. del Decreto 1083 de 2015 \u00a0y los art\u00edculos 60 y 61 del Decreto Ley 274 de \u00a02000 \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. N\u00f3mbrase provisionalmente a la doctora Mar\u00eda \u00a0del Pilar Mira Pont\u00f3n, identificada con c\u00e9dula de ciudadan\u00eda n\u00famero 52997130, \u00a0en el cargo de Segundo Secretario de Relaciones Exteriores, C\u00f3digo 2114, Grado \u00a015, de la planta global del Ministerio de Relaciones Exteriores, adscrito a la \u00a0Embajada de Colombia ante el Gobierno del Reino Unido de Gran Breta\u00f1a e Irlanda \u00a0del Norte. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. Las erogaciones que ocasione el \u00a0cumplimiento del presente decreto, se pagar\u00e1n con cargo a los presupuestos del \u00a0Ministerio de Relaciones Exteriores y su Fondo Rotatorio. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00b0. El presente decreto rige a \u00a0partir de la fecha de su expedici\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese, comun\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 5 de enero de 2016. \u00a0 \u00a0<\/p>\n<p>JUAN MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>La Ministra de Relaciones Exteriores, \u00a0 \u00a0<\/p>\n<p>Mar\u00eda \u00c1ngela Holgu\u00edn Cu\u00e9llar. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 04 DE 2016 \u00a0 \u00a0 (enero 5) \u00a0 \u00a0 D.O. 49.746, enero 5 de \u00a02016 \u00a0 \u00a0 por el cual se \u00a0hace un nombramiento provisional en la planta de personal del Ministerio de \u00a0Relaciones Exteriores. \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, \u00a0en ejercicio de sus facultades constitucionales y legales y, en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-49384","post","type-post","status-publish","format-standard","hentry","category-decretos-2016"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=49384"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49384\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=49384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=49384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=49384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}