{"id":49429,"date":"2023-08-16T21:30:03","date_gmt":"2023-08-16T21:30:03","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-158-de-2016\/"},"modified":"2023-08-16T21:30:03","modified_gmt":"2023-08-16T21:30:03","slug":"decreto-158-de-2016","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-158-de-2016\/","title":{"rendered":"DECRETO 158 DE 2016"},"content":{"rendered":"\n<p>DECRETO 158 DE 2016 \u00a0 \u00a0\u00a0<\/p>\n<p>(febrero 1\u00b0) \u00a0 \u00a0<\/p>\n<p>D.O. 49.773, febrero 1\u00b0 \u00a0de 2016 \u00a0 \u00a0<\/p>\n<p>por el cual se \u00a0modifica la planta de personal del Ministerio de Educaci\u00f3n Nacional \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de Colombia, \u00a0en ejercicio de las facultades constitucionales y legales, en especial las que \u00a0le confiere el numeral 14 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica y \u00a0el art\u00edculo 115 de la Ley 489 de 1998, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que el Ministerio de Educaci\u00f3n Nacional \u00a0present\u00f3 el estudio t\u00e9cnico que dispone el art\u00edculo 46 de la Ley 909 de 2004, \u00a0modificado por el art\u00edculo 228 del Decreto ley 019 de \u00a02012 y los art\u00edculos 2.2.12.1 a 1.2.12.3 del Decreto 1083 de 2015, \u00a0con el fin de modificar su planta de personal, el cual obtuvo concepto \u00a0favorable del Departamento Administrativo de la Funci\u00f3n P\u00fablica. \u00a0 \u00a0<\/p>\n<p>Que para los fines de este decreto, la \u00a0Direcci\u00f3n General del Presupuesto P\u00fablico Nacional del Ministerio de Hacienda y \u00a0Cr\u00e9dito P\u00fablico otorg\u00f3 la viabilidad presupuestal. \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo expuesto, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Supresi\u00f3n de cargos. Se suprimen de la planta de personal del \u00a0Ministerio de Educaci\u00f3n Nacional los siguientes cargos: \u00a0 \u00a0<\/p>\n<p>N\u00famero de cargos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Dependencia y denominaci\u00f3n del \u00a0 \u00a0empleo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>C\u00f3digo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Grado \u00a0\u00a0<\/p>\n<p>Despacho Ministra \u00a0\u00a0<\/p>\n<p>1 (Uno) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Profesional Universitario \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>2044 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>10 \u00a0\u00a0<\/p>\n<p>Despacho Viceministerio \u00a0 \u00a0de Educaci\u00f3n Superior \u00a0\u00a0<\/p>\n<p>1 (Uno) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Asesor \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1020 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>07 \u00a0\u00a0<\/p>\n<p>Planta Global \u00a0\u00a0<\/p>\n<p>1 (Uno) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Profesional Universitario \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>2044 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>08 \u00a0\u00a0<\/p>\n<p>1 (Uno) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>T\u00e9cnico Administrativo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>3124 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>17 \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. Creaci\u00f3n de cargo. Se crea en la Planta de Personal del \u00a0Ministerio de Educaci\u00f3n Nacional el siguiente cargo: \u00a0 \u00a0<\/p>\n<p>N\u00famero de cargos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Dependencia y denominaci\u00f3n del \u00a0 \u00a0empleo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>C\u00f3digo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Grado \u00a0\u00a0<\/p>\n<p>Despacho Ministra \u00a0\u00a0<\/p>\n<p>1 (Uno) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Asesor \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>1020 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>18 \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00b0. Provisi\u00f3n del empleo. La provisi\u00f3n del empleo creado mediante el \u00a0presente decreto se efectuar\u00e1 conforme a las disposiciones previstas en la Ley 909 de 2004 y el Decreto 1083 de 2015, \u00a0en lo que resulte aplicable. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 4\u00b0. Vigencia. El presente decreto rige a partir de la fecha de su \u00a0publicaci\u00f3n y modifica en lo pertinente los Decretos 4674 de 2006 y 1826 de 2012. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 1\u00b0 de febrero de \u00a02016. \u00a0 \u00a0<\/p>\n<p>JUAN MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>El Ministro de Hacienda y Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p>Mauricio C\u00e1rdenas \u00a0Santamar\u00eda. \u00a0 \u00a0<\/p>\n<p>La Ministra de Educaci\u00f3n Nacional, \u00a0 \u00a0<\/p>\n<p>Gina Mar\u00eda Parody D\u00b4Echeona. \u00a0 \u00a0<\/p>\n<p>La Directora del Departamento Administrativo \u00a0de la Funci\u00f3n P\u00fablica, \u00a0 \u00a0<\/p>\n<p>Liliana Caballero Dur\u00e1n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 158 DE 2016 \u00a0 \u00a0\u00a0 (febrero 1\u00b0) \u00a0 \u00a0 D.O. 49.773, febrero 1\u00b0 \u00a0de 2016 \u00a0 \u00a0 por el cual se \u00a0modifica la planta de personal del Ministerio de Educaci\u00f3n Nacional \u00a0 \u00a0 El Presidente de la Rep\u00fablica de Colombia, \u00a0en ejercicio de las facultades constitucionales y legales, en especial las que \u00a0le confiere [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-49429","post","type-post","status-publish","format-standard","hentry","category-decretos-2016"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=49429"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49429\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=49429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=49429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=49429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}