{"id":49534,"date":"2023-08-16T21:30:11","date_gmt":"2023-08-16T21:30:11","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-353-de-2016\/"},"modified":"2023-08-16T21:30:11","modified_gmt":"2023-08-16T21:30:11","slug":"decreto-353-de-2016","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-353-de-2016\/","title":{"rendered":"DECRETO 353 DE 2016"},"content":{"rendered":"\n<p>DECRETO \u00a0353 DE 2016 \u00a0 \u00a0\u00a0<\/p>\n<p>(marzo 1\u00b0) \u00a0 \u00a0<\/p>\n<p>D.O. 49.802, marzo 1\u00b0 de 2016 \u00a0 \u00a0<\/p>\n<p>por el cual se modifica parcialmente el Decreto 2555 de 2010, \u00a0en lo relacionado con la emisi\u00f3n y colocaci\u00f3n de bonos hipotecarios para la \u00a0financiaci\u00f3n de vivienda a largo plazo. \u00a0 \u00a0<\/p>\n<p>El \u00a0Presidente de la Rep\u00fablica de Colombia, en ejercicio de sus facultades \u00a0constitucionales y legales, en especial de las conferidas en los numerales 11 y \u00a025 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica y \u00a0el literal b) del art\u00edculo 4\u00b0 de la Ley 964 de 2005, y en \u00a0concordancia con el art\u00edculo 9\u00b0 de la Ley 546 de 1999, \u00a0modificado parcialmente por el art\u00edculo 48 de la Ley 1753 de 2015, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que el \u00a0art\u00edculo 9\u00b0 de la Ley 546 de 1999 \u00a0autorizaba a los establecimientos de cr\u00e9dito la emisi\u00f3n de bonos hipotecarios \u00a0denominados en UVR, con el fin de facilitar el fondeo y emisi\u00f3n de cr\u00e9ditos \u00a0hipotecarios. \u00a0 \u00a0<\/p>\n<p>Que la Ley 1753 de 2015, por \u00a0la cual se expide el Plan Nacional de Desarrollo 2014- 2018 \u201cTodos por un Nuevo \u00a0Pa\u00eds\u201d, en el art\u00edculo 48 modific\u00f3 el inciso primero del art\u00edculo 9\u00b0 de la Ley 546 de 1999, en el \u00a0sentido de autorizar a los establecimientos de cr\u00e9dito la emisi\u00f3n de bonos \u00a0hipotecarios sin distinci\u00f3n en su denominaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Que de \u00a0acuerdo a lo anterior, en desarrollo de dicho mandato legal y con el fin de dar \u00a0homogeneidad al tratamiento de las emisiones y colocaciones de los bonos \u00a0hipotecarios denominados en pesos y en UVR, se hace necesario modificar la \u00a0regulaci\u00f3n actual sobre la materia. \u00a0 \u00a0<\/p>\n<p>Que el \u00a0Consejo Directivo de la Unidad Administrativa Especial Unidad de Proyecci\u00f3n \u00a0Normativa y Estudios de Regulaci\u00f3n Financiera-URF, aprob\u00f3 por unanimidad el \u00a0contenido del presente decreto, mediante Acta n\u00famero 015 del 30 de noviembre de \u00a02015. \u00a0 \u00a0<\/p>\n<p>Que en m\u00e9rito \u00a0de lo expuesto, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a01\u00b0. Modif\u00edquese el segundo inciso del art\u00edculo 6.5.1.1.1 del Decreto 2555 de 2010, \u00a0el cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201cLos bonos \u00a0hipotecarios son t\u00edtulos valores de contenido crediticio, que estar\u00e1n respaldados \u00a0por cr\u00e9ditos hipotecarios otorgados bajo cualquiera de los sistemas de \u00a0amortizaci\u00f3n en UVR o en pesos aprobados por la Superintendencia Financiera de \u00a0Colombia\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a02\u00b0. Modif\u00edquese el art\u00edculo 6.5.1.2.1 del Decreto 2555 de 2010, \u00a0el cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201cArt\u00edculo \u00a06.5.1.2.1. Del monto de emisi\u00f3n. El \u00a0monto de la emisi\u00f3n de bonos hipotecarios deber\u00e1 estar expresado en unidades de \u00a0valor real UVR y\/o en pesos. Se entiende por UVR lo establecido en el art\u00edculo \u00a03\u00b0 de la Ley 546 de 1999\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a03\u00b0. Modif\u00edquese el art\u00edculo 6.5.1.2.4 del Decreto 2555 de 2010, \u00a0el cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201cArt\u00edculo \u00a06.5.1.2.4. Valor nominal, inversi\u00f3n \u00a0m\u00ednima y fraccionamiento. El valor nominal de los bonos hipotecarios \u00a0ser\u00e1 de 10.000 UVR o su equivalente en pesos. La inversi\u00f3n m\u00ednima inicial de \u00a0los bonos hipotecarios corresponder\u00e1 a su valor nominal. Los bonos hipotecarios \u00a0ser\u00e1n fraccionables en cupones anuales\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a04\u00b0. Modif\u00edquese el art\u00edculo 6.5.1.2.6 del Decreto 2555 de 2010, \u00a0el cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201cArt\u00edculo \u00a06.5.1.2.6. Intereses de los bonos \u00a0hipotecarios. Los bonos hipotecarios pagar\u00e1n a su tenedor intereses \u00a0calculados a la tasa fija pactada sobre el valor nominal expresado en UVR o en \u00a0pesos, de acuerdo con la periodicidad establecida en el prospecto de emisi\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a05\u00b0. Modif\u00edquese el primer inciso del art\u00edculo 6.5.1.4.3 del Decreto 2555 de 2010, \u00a0el cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201cLos bonos \u00a0hipotecarios que correspondan a determinada emisi\u00f3n, identificada con su serie \u00a0y a\u00f1o, se amortizar\u00e1n extraordinariamente, en forma total o parcial, por el \u00a0valor en t\u00e9rminos de UVR o pesos que reciba el administrador de la cartera, \u00a0\u00fanicamente cuando:\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a06\u00b0. Modif\u00edquese el numeral 1 y el par\u00e1grafo del art\u00edculo 6.5.1.4.4 del Decreto 2555 de 2010, \u00a0los cuales quedar\u00e1n as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201c1. El \u00a0emisor informar\u00e1 mediante acta de prorrateo al dep\u00f3sito centralizado de valores \u00a0donde est\u00e9n depositados los bonos hipotecarios, respecto del valor de los pagos \u00a0recibidos de los deudores hipotecarios, identificando a qu\u00e9 emisi\u00f3n y serie \u00a0pertenecen los bonos hipotecarios cuyo subyacente fue objeto de prepago. Para \u00a0ello tendr\u00e1 en cuenta los prepagos recibidos en el respectivo periodo por los \u00a0deudores de vivienda y las fechas de aplicaci\u00f3n del prorrateo\u201d. \u00a0 \u00a0<\/p>\n<p>\u201cPar\u00e1grafo. \u00a0Para el caso de los bonos hipotecarios en UVR la amortizaci\u00f3n \u00a0extraordinaria a prorrata s\u00f3lo se podr\u00e1 hacer sobre unidades de UVR enteras. El \u00a0emisor acumular\u00e1 los valores resultantes de prepagos, cuando la cantidad de los \u00a0mismos no alcance a completar una unidad entera de UVR, y los trasladar\u00e1 a los \u00a0inversionistas, de acuerdo con el procedimiento previsto en este art\u00edculo, en \u00a0los procesos de prorrateo subsiguientes\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a07\u00b0. Modif\u00edquense los numerales 1, 3 y 4 y el par\u00e1grafo del art\u00edculo 6.5.1.4.5 \u00a0del Decreto 2555 de 2010, \u00a0los cuales quedar\u00e1n as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201c1. El \u00a0emisor informar\u00e1 mediante acta de sorteo al dep\u00f3sito centralizado de valores \u00a0donde est\u00e9n depositados los bonos hipotecarios, respecto del valor de los pagos \u00a0recibidos de los deudores hipotecarios, identificando a qu\u00e9 emisi\u00f3n y serie \u00a0pertenecen los bonos hipotecarios cuyo subyacente fue objeto de prepago. Para \u00a0ello tendr\u00e1 en cuenta los prepagos recibidos en el respectivo periodo por los \u00a0deudores de vivienda y la fecha de aplicaci\u00f3n del sorteo\u201d. \u00a0 \u00a0<\/p>\n<p>\u201c3. El \u00a0dep\u00f3sito centralizado de valores proceder\u00e1 a sortear, entre los bonos \u00a0hipotecarios que correspondan a la misma emisi\u00f3n, serie y a\u00f1o de los cr\u00e9ditos, \u00a0el n\u00famero de unidades enteras de UVR o el valor en pesos informado por el \u00a0emisor\u201d. \u00a0 \u00a0<\/p>\n<p>\u201c4. Inmediatamente \u00a0concluya el sorteo, el emisor pondr\u00e1 a disposici\u00f3n del dep\u00f3sito centralizado de \u00a0valores el monto en pesos o el equivalente en dinero de las UVR sorteadas, para \u00a0que este lo entregue al tenedor favorecido por el sorteo, con lo que se \u00a0entender\u00e1 que el emisor ha amortizado los bonos hipotecarios correspondientes\u201d. \u00a0 \u00a0<\/p>\n<p>\u201cPar\u00e1grafo. \u00a0Para el caso de los bonos hipotecarios en UVR los sorteos s\u00f3lo podr\u00e1n \u00a0realizarse sobre unidades enteras de UVR. El emisor acumular\u00e1 los valores \u00a0resultantes de prepagos, cuando la cantidad de los mismos no alcance a \u00a0completar una unidad entera de UVR, y los trasladar\u00e1 a los inversionistas, de \u00a0acuerdo con lo previsto en este art\u00edculo, en los sorteos subsiguientes\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a08\u00b0. Modif\u00edquese el art\u00edculo 6.5.1.5.1 del Decreto 2555 de 2010, \u00a0el cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201cArt\u00edculo \u00a06.5.1.5.1. Administrador de cartera. En \u00a0desarrollo de lo previsto en el numeral 5 del art\u00edculo 9\u00b0 de la Ley 546 de 1999, el \u00a0emisor, o quien haya asumido la obligaci\u00f3n de pagar los bonos hipotecarios, \u00a0deber\u00e1 suscribir un contrato de administraci\u00f3n de los cr\u00e9ditos financiados a \u00a0trav\u00e9s de estos, a favor de los tenedores, el cual deber\u00e1 estar contenido en el \u00a0prospecto de colocaci\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a09\u00b0. Modif\u00edquese el segundo inciso del literal i) del art\u00edculo 6.5.1.5.2 del Decreto 2555 de 2010, \u00a0el cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201cPara el efecto, el administrador de la cartera informar\u00e1 a los \u00a0tenedores de bonos hipotecarios a trav\u00e9s de la p\u00e1gina de Internet o mediante \u00a0aviso publicado en las p\u00e1ginas econ\u00f3micas de un diario de amplia circulaci\u00f3n, \u00a0con una antelaci\u00f3n no inferior a tres (3) d\u00edas h\u00e1biles a la fecha prevista para \u00a0el sorteo, (i) que se va a realizar una amortizaci\u00f3n extraordinaria de \u00a0determinada cantidad de UVR y\/o pesos de los bonos hipotecarios en circulaci\u00f3n, \u00a0(ii) la respectiva emisi\u00f3n, serie y a\u00f1o afectada con el prepago, (iii) que la \u00a0amortizaci\u00f3n extraordinaria es obligatoria para los Tenedores de Bonos \u00a0hipotecarios, (iv) fecha, lugar y hora en que se realizar\u00e1 el sorteo, o si es \u00a0el caso, la forma en que se realizar\u00e1 el procedimiento de prorrateo, (v) \u00a0per\u00edodo en el cual se pagar\u00e1 el valor resultante de la amortizaci\u00f3n \u00a0extraordinaria\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a010. Modif\u00edquense los literales e) y f) del numeral I del art\u00edculo 6.5.1.6.1 del \u00a0Decreto 2555 de 2010, \u00a0los cuales quedar\u00e1n as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201ce) Valor \u00a0nominal e inversi\u00f3n m\u00ednima de los bonos hipotecarios, expresado en UVR y\/o en \u00a0pesos. \u00a0 \u00a0<\/p>\n<p>f) Monto total de la emisi\u00f3n, expresado en UVR y\/o en \u00a0pesos\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a011. Modif\u00edquense los numerales 1, 3, 6 y 7 del literal r) del numeral XI del \u00a0art\u00edculo 6.5.1.6.1 del Decreto 2555 de 2010, \u00a0los cuales quedar\u00e1n as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201c1. Estado \u00a0de Situaci\u00f3n Financiera o Balance General, Estado de Resultados, Estado de \u00a0Cambios en el Patrimonio y Estado de Flujos de Efectivo, para los tres (3) \u00a0\u00faltimos a\u00f1os. \u00a0 \u00a0<\/p>\n<p>3. Estado de Situaci\u00f3n Financiera o Balance General y Estado \u00a0de Resultados a corte del trimestre calendario inmediatamente anterior a la \u00a0fecha de presentaci\u00f3n de la documentaci\u00f3n completa debidamente diligenciada, \u00a0presentado en forma comparativa con el correspondiente al mismo corte del a\u00f1o \u00a0anterior, y anexos de informaci\u00f3n financiera de acuerdo con los formatos \u00a0establecidos por la Superintendencia Financiera de Colombia. \u00a0 \u00a0<\/p>\n<p>6. Estados financieros consolidados a corte del \u00faltimo \u00a0ejercicio anual aprobado con sus correspondientes notas, para aquellas entidades \u00a0que posean m\u00e1s del cincuenta por ciento (50%) del capital de otros entes \u00a0econ\u00f3micos. \u00a0 \u00a0<\/p>\n<p>7. Certificaci\u00f3n de todos los estados financieros incluidos \u00a0en el prospecto, de conformidad con lo establecido en el art\u00edculo 37 de la Ley 222 de 1995, seg\u00fan \u00a0el cual el representante legal y contador p\u00fablico bajo cuya responsabilidad se \u00a0hubieren preparado los estados financieros, deber\u00e1n certificar aquellos que se \u00a0pongan a disposici\u00f3n de los asociados o de terceros. La certificaci\u00f3n consiste \u00a0en declarar que se han verificado previamente las afirmaciones contenidas en \u00a0ellos, conforme al reglamento y que las mismas se han tomado fielmente de los \u00a0libros, incluyendo adem\u00e1s las respectivas firmas. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a012. Modif\u00edquese el numeral 1 del literal d) del numeral XII del art\u00edculo \u00a06.5.1.6.1 del Decreto 2555 de 2010, \u00a0el cual quedar\u00e1 as\u00ed: \u00a0 \u00a0<\/p>\n<p>\u201c1. Informe \u00a0trimestral: Estado de Situaci\u00f3n Financiera o Balance General y Estados de \u00a0Resultados en los formatos establecidos por la Superintendencia Financiera de \u00a0Colombia para el trimestre calendario inmediatamente anterior a la fecha de \u00a0presentaci\u00f3n de la documentaci\u00f3n completa debidamente diligenciada, comparado \u00a0con el correspondiente al mismo corte del a\u00f1o anterior. Los estados financieros \u00a0deben estar certificados de conformidad con lo establecido en el art\u00edculo 37 de \u00a0la Ley 222 de 1995\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a013. Vigencia. El presente \u00a0decreto rige a partir de la fecha de su publicaci\u00f3n y modifica los art\u00edculos \u00a06.5.1.1.1, 6.5.1.2.1, 6.5.1.2.4, 6.5.1.2.6, 6.5.1.4.3, 6.5.1.4.4, 6.5.1.4.5, \u00a06.5.1.5.1, 6.5.1.5.2 y 6.5.1.6.1 del Decreto 2555 de 2010. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese \u00a0y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en \u00a0Bogot\u00e1, D. C., a 1\u00b0 de marzo de 2016. \u00a0 \u00a0<\/p>\n<p>JUAN \u00a0MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>El \u00a0Ministro de Hacienda y Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p>Mauricio C\u00e1rdenas Santamar\u00eda. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO \u00a0353 DE 2016 \u00a0 \u00a0\u00a0 (marzo 1\u00b0) \u00a0 \u00a0 D.O. 49.802, marzo 1\u00b0 de 2016 \u00a0 \u00a0 por el cual se modifica parcialmente el Decreto 2555 de 2010, \u00a0en lo relacionado con la emisi\u00f3n y colocaci\u00f3n de bonos hipotecarios para la \u00a0financiaci\u00f3n de vivienda a largo plazo. \u00a0 \u00a0 El \u00a0Presidente de la Rep\u00fablica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-49534","post","type-post","status-publish","format-standard","hentry","category-decretos-2016"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=49534"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49534\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=49534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=49534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=49534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}