{"id":49635,"date":"2023-08-16T21:30:18","date_gmt":"2023-08-16T21:30:18","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-624-de-2016\/"},"modified":"2023-08-16T21:30:18","modified_gmt":"2023-08-16T21:30:18","slug":"decreto-624-de-2016","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-624-de-2016\/","title":{"rendered":"DECRETO 624 DE 2016"},"content":{"rendered":"\n<p>DECRETO 624 DE 2016 \u00a0 \u00a0\u00a0<\/p>\n<p>(abril \u00a018) \u00a0 \u00a0<\/p>\n<p>D.O. 49.848, abril 18 de 2016 \u00a0 \u00a0<\/p>\n<p>por el cual \u00a0se crea y reglamenta la Mesa Permanente de Concertaci\u00f3n con las Centrales \u00a0Sindicales CUT, CGT, CTC y la Fecode para la Reparaci\u00f3n Colectiva al Movimiento \u00a0Sindical. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica de \u00a0Colombia, en ejercicio de sus facultades constitucio\u00adnales y legales, en \u00a0especial de las conferidas en el art\u00edculo 3\u00b0 del Convenio 98 de la OIT aprobado \u00a0mediante la Ley 27 de 1976, en \u00a0concordancia con lo se\u00f1alado en los art\u00edculos 13, 25 y 192 de la Ley 1448 de 2011, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que la Constituci\u00f3n Pol\u00edtica, en \u00a0el Cap\u00edtulo I \u201cDe los Derechos Fundamentales\u201d del T\u00edtulo II \u201cDe los \u00a0Derechos, las Garant\u00edas y los Deberes\u201d, art\u00edculo 39, reconoce que \u201cLos \u00a0trabajadores y empleadores tienen derecho a constituir sindicatos o \u00a0asociaciones, sin inter\u00advenci\u00f3n del Estado. Su reconocimiento jur\u00eddico se \u00a0producir\u00e1 con la simple inscripci\u00f3n del acta de constituci\u00f3n. \u2016 La \u00a0estructura interna y el funcionamiento de los sindicatos y orga\u00adnizaciones \u00a0sociales y gremiales se sujetar\u00e1n al orden legal y a los principios \u00a0democr\u00e1ticos. \u2016 La cancelaci\u00f3n o la suspensi\u00f3n de la personer\u00eda jur\u00eddica solo \u00a0procede por v\u00eda judicial. \u2016 Se reconoce a los \u00a0representantes sindicales el fuero y las dem\u00e1s garant\u00edas necesarias para el \u00a0cumplimiento de su gesti\u00f3n. \u2016 No \u00a0gozan del derecho de asociaci\u00f3n sindical los miembros de la Fuerza P\u00fablica\u201d. \u00a0 \u00a0<\/p>\n<p>Que en su art\u00edculo 55, la Carta \u00a0Pol\u00edtica prev\u00e9 que \u201cSe garantiza el derecho de nego\u00adciaci\u00f3n colectiva para \u00a0regular las relaciones laborales, con las excepciones que se\u00f1ale la ley. \u2016 Es \u00a0deber del Estado promover la concertaci\u00f3n y los dem\u00e1s medios para la soluci\u00f3n \u00a0pac\u00edfica de los conflictos colectivos de trabajo\u201d. \u00a0 \u00a0<\/p>\n<p>Que en virtud de lo establecido \u00a0en el art\u00edculo 56 del mismo texto Constitucional \u201cSe garantiza el derecho de \u00a0huelga, salvo en los servicios p\u00fablicos esenciales definidos por el legislador. \u00a0\u2016 La ley reglamentar\u00e1 este derecho. \u2016 Una \u00a0comisi\u00f3n permanente integrada por el Gobierno, por representantes de los \u00a0empleadores y de los trabajadores, fomentar\u00e1 las buenas relaciones laborales, \u00a0contribuir\u00e1 a la soluci\u00f3n de los conflictos colectivos de tra\u00adbajo y concertar\u00e1 \u00a0las pol\u00edticas salariales y laborales. La ley reglamentar\u00e1 su composici\u00f3n y \u00a0funcionamiento\u201d. \u00a0 \u00a0<\/p>\n<p>Que el Estado colombiano ha \u00a0adoptado, suscrito y ratificado declaraciones, convenios y tratados \u00a0internacionales que hacen parte del bloque de constitucionalidad, que reconocen \u00a0los derechos humanos de los trabajadores y las trabajadoras y protegen las \u00a0libertades sindicales. \u00a0 \u00a0<\/p>\n<p>Que en virtud de lo establecido \u00a0en el art\u00edculo 3\u00b0 del Convenio 98 de la OIT aprobado mediante la Ley 27 de 1976 \u201cPor \u00a0la cual se aprueba el Convenio Internacional del Traba\u00adjo, relativo a la \u00a0aplicaci\u00f3n de los principios del Derecho de Sindicaci\u00f3n y de Negociaci\u00f3n \u00a0colectiva, adoptado por la Conferencia General de la Organizaci\u00f3n Internacional \u00a0del Trabajo (Ginebra 1949)\u201d, el Estado colombiano ratifica que crear\u00e1 los \u00a0organismos ade\u00adcuados a las condiciones nacionales, cuando ello sea necesario, \u00a0para garantizar el respeto al derecho de sindicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Que la Ley 1448 de 2011, \u201cpor \u00a0la cual se dictan medidas de atenci\u00f3n, asistencia y repa\u00adraci\u00f3n integral a las \u00a0v\u00edctimas del conflicto armado interno y se dictan otras disposiciones\u201d, se \u00a0desarrolla en el marco de la justicia transicional y conforme a su art\u00edculo 3\u00b0, \u00a0se consideran v\u00edctimas \u201c(&#8230;) aquellas personas que individual o \u00a0colectivamente hayan sufrido un da\u00f1o por hechos ocurridos a partir del 1\u00ba de \u00a0enero de 1985, como consecuencia de infracciones al Derecho Internacional \u00a0Humanitario o de violaciones graves y manifiestas a las normas internacionales \u00a0de Derechos Humanos, ocurridas con ocasi\u00f3n del conflicto armado interno\u201d. \u00a0 \u00a0<\/p>\n<p>Que \u00a0la Ley 1448 de 2011 \u00a0reconoce de manera expresa situaciones de victimizaci\u00f3n que afectaron a sujetos \u00a0colectivos de un modo diferente a las vulneraciones de derechos de personas \u00a0individuales. En este sentido, el art\u00edculo 151 de la citada ley establece que \u00a0dentro del Programa de Reparaci\u00f3n Colectiva se debe tener en cuenta cualquiera \u00a0de los siguientes eventos: \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u201ca) El da\u00f1o ocasionado \u00a0por la violaci\u00f3n de los derechos colectivos. \u00a0 \u00a0\u00a0<\/p>\n<p>b) La violaci\u00f3n grave \u00a0y manifiesta de los derechos individuales de los miembros de los colectivos. \u00a0 \u00a0<\/p>\n<p>c) El impacto colectivo \u00a0de la violaci\u00f3n de derechos individuales\u201d. \u00a0 \u00a0<\/p>\n<p>Que el art\u00edculo 152 \u00a0de la Ley 1448 de 2011 \u00a0reconoce la existencia de dos tipos de sujetos susceptibles de ser reparados \u00a0colectivamente, a saber: \u00a0 \u00a0<\/p>\n<p>\u201c1. Grupos y \u00a0organizaciones sociales y pol\u00edticos. \u00a0 \u00a0<\/p>\n<p>2. Comunidades \u00a0determinadas a partir de un reconocimiento jur\u00eddico, pol\u00edtico o social que se \u00a0haga del colectivo, o en raz\u00f3n de la cultura, la zona o el territorio en el que \u00a0habitan o un prop\u00f3sito com\u00fan\u201d. \u00a0 \u00a0<\/p>\n<p>Que la reparaci\u00f3n \u00a0colectiva es una herramienta que la Ley 1448 de 2011 ha \u00a0brindado al pa\u00eds, dirigida al reconocimiento y dignificaci\u00f3n de los sujetos \u00a0colectivos, a la recuperaci\u00f3n psicosocial, a la inclusi\u00f3n ciudadana de los \u00a0grupos y organizaciones sociales y pol\u00edticos y de las comunidades como sujetos \u00a0plenos de derecho, a la reconstrucci\u00f3n del tejido social y de la confianza de \u00a0la sociedad en el Estado en las zonas y territorios afectados por el conflicto \u00a0armado, al fortalecimiento de la institucionalidad del Estado Social de Derecho \u00a0para la consecuci\u00f3n de la reconciliaci\u00f3n nacional y la convivencia pac\u00edfica. \u00a0 \u00a0<\/p>\n<p>Que es obligaci\u00f3n del \u00a0Estado Colombiano ofrecer especiales garant\u00edas y medidas de protecci\u00f3n a los \u00a0grupos expuestos a mayor riesgo de padecer las violaciones de derechos \u00a0descritas en el art\u00edculo 3\u00b0 de la Ley 1448 de 2011, \u00a0entre los que se encuentran los miembros de organizaciones sindicales, en los \u00a0t\u00e9rminos del art\u00edculo 13 de la referida ley. \u00a0 \u00a0<\/p>\n<p>Que en el marco de la \u00a0Ley 1448 de 2011, el \u00a0Gobierno nacional se encuentra ejecutando la fase de acercamiento al Movimiento \u00a0Sindical, mediante la interlocuci\u00f3n permanente con las centrales sindicales \u00a0Confederaci\u00f3n General del Trabajo (CGT), Central Unitaria de Tra\u00adbajadores \u00a0(CUT) y Confederaci\u00f3n de Trabajadores de Colombia (CTC) y con la Federaci\u00f3n \u00a0Colombiana de Trabajadores de la Educaci\u00f3n (Fecode), a trav\u00e9s de encuentros \u00a0regionales. \u00a0 \u00a0<\/p>\n<p>Que en el \u00a0acercamiento al Movimiento Sindical desarrollado en el marco de la Ley 1448 de 2011, los \u00a0presidentes de las referidas centrales sindicales manifestaron la necesidad de \u00a0que el Gobierno nacional realice acciones afirmativas que permitan dar \u00a0sostenibilidad a la decisi\u00f3n de reparar al sindicalismo colombiano por las \u00a0violaciones sufridas en el conflicto armado y, con ocasi\u00f3n del D\u00eda Nacional de \u00a0la Memoria y la Solidaridad con las V\u00edctimas del Conflicto Armado, solicitaron \u00a0al Presidente de la Rep\u00fablica la conformaci\u00f3n de una Mesa Permanente de \u00a0Concertaci\u00f3n con las Centrales Sindicales CUT, CGT, CTC y la Fecode para la \u00a0Reparaci\u00f3n Colectiva al Movimiento Sindical. \u00a0 \u00a0<\/p>\n<p>Que la creaci\u00f3n de la \u00a0Mesa Permanente de Concertaci\u00f3n con las Centrales Sindicales CUT, CGT, CTC y la \u00a0Fecode para la Reparaci\u00f3n Colectiva al Movimiento Sindical guarda coherencia \u00a0con el mandato del art\u00edculo 149, literal d), de la Ley 1448 de 2011 que \u00a0establece la obligaci\u00f3n del Estado de adoptar garant\u00edas de no repetici\u00f3n, como \u201cla \u00a0prevenci\u00f3n de vio\u00adlaciones contempladas en el art\u00edculo 3\u00ba de la presente Ley, \u00a0para lo cual, ofrecer\u00e1 especiales medidas de prevenci\u00f3n a los grupos expuestos \u00a0a mayor riesgo como mujeres, ni\u00f1os, ni\u00f1as y adolescentes, adultos mayores, \u00a0l\u00edderes sociales, miembros de organizaciones sindicales, defensores de derechos \u00a0humanos y v\u00edctimas de desplazamiento forzado, que propendan superar \u00a0estereotipos que favorecen la discriminaci\u00f3n, en especial contra la mujer y la \u00a0violencia contra ella en el marco del conflicto armado\u201d . \u00a0 \u00a0<\/p>\n<p>Que la Ley 1448 de 2011 \u00a0reconoce de manera expresa en su art\u00edculo 192 que \u201ces deber del Estado \u00a0garantizar la participaci\u00f3n efectiva de las v\u00edctimas en el dise\u00f1o, implementaci\u00f3n, \u00a0ejecuci\u00f3n y sentimiento (sic) al cumplimiento de la ley y los planes, proyectos \u00a0y programas que se creen con ocasi\u00f3n de la misma. Para esto se deber\u00e1 hacer uso \u00a0de los mecanismos democr\u00e1ticos previstos en la Constituci\u00f3n y la ley, para lo cual \u00a0deber\u00e1, entre otros: \u2016 Garantizar la \u00a0disposici\u00f3n de los medios e instrumentos necesarios para (&#8230;) el dise\u00f1o de \u00a0espacios de participaci\u00f3n adecuados para la efectiva participaci\u00f3n de las \u00a0v\u00edctimas en los niveles nacional, departamental y municipal\u201d. \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de lo \u00a0expuesto, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Creaci\u00f3n. \u00a0Cr\u00e9ase la Mesa Permanente de Concertaci\u00f3n con las Centrales Sindicales CUT, \u00a0CGT, CTC y la Fecode para la Reparaci\u00f3n Colectiva al Movimiento Sindical, \u00a0escenario de interlocuci\u00f3n y negociaci\u00f3n, bajo la coordinaci\u00f3n de la Unidad \u00a0Administrativa Especial para la Atenci\u00f3n y Reparaci\u00f3n Integral a las V\u00edctimas. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. Objeto. \u00a0La Mesa Permanente de Concertaci\u00f3n con las Centrales Sindicales CUT, CGT, CTC y \u00a0la Fecode para la Reparaci\u00f3n Colectiva al Movimiento Sindical tendr\u00e1 por objeto \u00a0evaluar las condiciones institucionales necesarias y servir de espacio de \u00a0interlo\u00adcuci\u00f3n y negociaci\u00f3n para que el proceso de reparaci\u00f3n colectiva al \u00a0Movimiento Sindical sea s\u00f3lido, sostenible y duradero y las medidas de \u00a0reparaci\u00f3n integral contribuyan de manera efectiva al goce efectivo de los \u00a0derechos y libertades sindicales. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 3\u00b0. Integraci\u00f3n. \u00a0La Mesa Permanente de Concertaci\u00f3n con las Centrales Sin\u00addicales CUT, CGT, CTC \u00a0y la Fecode para la Reparaci\u00f3n Colectiva al Movimiento Sindical estar\u00e1 \u00a0integrada por los siguientes miembros plenos: \u00a0 \u00a0<\/p>\n<p>a) En representaci\u00f3n \u00a0del Gobierno nacional: \u00a0 \u00a0<\/p>\n<p>1. El\/la Ministro(a) \u00a0del Interior o su delegado(a). \u00a0 \u00a0<\/p>\n<p>2. El\/la Ministro(a) \u00a0de Hacienda y Cr\u00e9dito P\u00fablico o su delegado(a). \u00a0 \u00a0<\/p>\n<p>3. El\/la Ministro(a) \u00a0de Justicia y del Derecho o su delegado(a). \u00a0 \u00a0<\/p>\n<p>4. El\/la Ministro(a) \u00a0del Trabajo o su delegado(a). \u00a0 \u00a0<\/p>\n<p>5. El\/la Ministro(a) \u00a0de Educaci\u00f3n Nacional o su delegado(a). \u00a0 \u00a0<\/p>\n<p>6. El\/la Director(a) \u00a0del Departamento Nacional de Planeaci\u00f3n o su delegado(a). \u00a0 \u00a0<\/p>\n<p>7. El\/la Director(a) \u00a0del Departamento Administrativo para la Prosperidad Social o su delegado(a). \u00a0 \u00a0<\/p>\n<p>8. El\/la Director (a) \u00a0de la Unidad Administrativa Especial para la Atenci\u00f3n y Reparaci\u00f3n Integral a \u00a0las V\u00edctimas o su delegado(a), quien la presidir\u00e1. \u00a0 \u00a0<\/p>\n<p>b) El\/la Defensor (a) \u00a0del Pueblo o su delegado (a). \u00a0 \u00a0<\/p>\n<p>e) En representaci\u00f3n \u00a0del Movimiento Sindical: \u00a0 \u00a0<\/p>\n<p>1. Dos (2) representantes de la Central \u00a0Unitaria de Trabajadores (CUT). \u00a0 \u00a0<\/p>\n<p>2. Dos (2) representantes de la Confederaci\u00f3n \u00a0General del Trabajo (CGT). \u00a0 \u00a0<\/p>\n<p>3. Dos (2) representantes de la Confederaci\u00f3n \u00a0de Trabajadores de Colombia (CTC). \u00a0 \u00a0<\/p>\n<p>4. Dos (2) representantes de la Federaci\u00f3n \u00a0Colombiana de Trabajadores de la Educaci\u00f3n (Fecode). \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. En virtud de lo establecido en la Ley 489 de 1998, en \u00a0representaci\u00f3n del Gobierno solo podr\u00e1n ser delegados para participar en la \u00a0Mesa Permanente de Concertaci\u00f3n con las Centrales Sindicales CUT, CGT, CTC y la \u00a0Fecode para la Reparaci\u00f3n Colectiva al Movimiento Sindical, los empleados \u00a0p\u00fablicos de los niveles directivo y asesor vinculados a cada entidad que \u00a0cuenten con capacidad para tomar decisiones. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 4\u00b0. Secretar\u00eda T\u00e9cnica. \u00a0La Secretar\u00eda T\u00e9cnica ser\u00e1 ejercida por (1) un delegado del Gobierno nacional y \u00a0un (1) delegado de las centrales sindicales, quienes ser\u00e1n elegidos por la Mesa \u00a0en Pleno. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 5\u00b0. Funciones de la Secretar\u00eda \u00a0t\u00e9cnica. La Secretar\u00eda T\u00e9cnica tendr\u00e1 entre sus funciones convocar a los \u00a0integrantes para el desarrollo de las sesiones de la Mesa Perma\u00adnente de \u00a0Concertaci\u00f3n con las Centrales Sindicales CUT, CGT, CTC y la Fecode para la \u00a0Reparaci\u00f3n Colectiva al Movimiento Sindical, e invitar ocasionalmente a los \u00a0representantes de las diferentes entidades del Estado que la Mesa por \u00a0unanimidad considere. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 6\u00b0. Invitados. Cuando la Mesa \u00a0lo considere necesario, podr\u00e1 invitar a un repre\u00adsentante de la Organizaci\u00f3n \u00a0Internacional del Trabajo (OIT), a un representante de la Oficina en Colombia \u00a0del Alto Comisionado de las Naciones Unidas para los Derechos Humanos o a \u00a0representantes del sector empresarial designados por las asociaciones \u00a0nacionales gremiales m\u00e1s representativas de los distintos sectores econ\u00f3micos \u00a0del pa\u00eds. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 7\u00b0. Garant\u00edas para el funcionamiento \u00a0de la mesa. El Gobierno nacional, a trav\u00e9s de la Unidad Administrativa Especial \u00a0para la Atenci\u00f3n y Reparaci\u00f3n Integral a las V\u00edctimas, el Ministerio del \u00a0Trabajo y\/o las dem\u00e1s entidades vinculadas a la Mesa, proveer\u00e1 las condiciones \u00a0log\u00edsticas mediante las cuales la Mesa Permanente de Concertaci\u00f3n con las \u00a0Centrales Sindicales CUT, CGT, CTC y la Fecode para la Reparaci\u00f3n Colectiva al \u00a0Movi\u00admiento Sindical ejercer\u00e1 sus funciones. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 8\u00b0. Tipo de apoyo. La \u00a0financiaci\u00f3n destinada a garantizar el funcionamiento de la Mesa Permanente de \u00a0Concertaci\u00f3n con las Centrales Sindicales CUT, CGT, CTC y la Fecode para la \u00a0Reparaci\u00f3n Colectiva al Movimiento Sindical comprender\u00e1 el apoyo log\u00edstico para \u00a0la realizaci\u00f3n de las sesiones de la Mesa. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 9\u00b0. Funciones. La Mesa \u00a0Permanente de Concertaci\u00f3n con las Centrales Sindi\u00adcales CUT, CGT, CTC y la \u00a0Fecode para la Reparaci\u00f3n Colectiva al Movimiento Sindical tendr\u00e1 las \u00a0siguientes funciones de consulta: \u00a0 \u00a0<\/p>\n<p>1. Contribuir a la consolidaci\u00f3n de una \u00a0cultura de respeto y reconocimiento al sindicalismo y al fortalecimiento del \u00a0Movimiento Sindical, como un actor clave en el funcionamiento de la democracia, \u00a0as\u00ed como de la defensa de los derechos de los trabajadores y las libertades \u00a0sindicales y de la vigencia del Estado Social de Derecho. \u00a0 \u00a0<\/p>\n<p>2. Acompa\u00f1ar la implementaci\u00f3n del proceso de \u00a0reparaci\u00f3n colectiva al Movimiento Sindical, tendiente a la formulaci\u00f3n y \u00a0ejecuci\u00f3n de las medidas de reparaci\u00f3n dentro del Plan Integral de Reparaci\u00f3n \u00a0Colectiva. \u00a0 \u00a0<\/p>\n<p>3. Apoyar el dise\u00f1o y formulaci\u00f3n de \u00a0proyectos, planes y programas para la construcci\u00f3n e implementaci\u00f3n de la pol\u00edtica \u00a0p\u00fablica de reparaci\u00f3n colectiva al Movimiento Sindical, con enfoque \u00a0transformador y diferencial que contribuya a la garant\u00eda del goce efectivo de \u00a0los derechos y libertades sindicales. \u00a0 \u00a0<\/p>\n<p>4. Formular recomendaciones tendientes a \u00a0garantizar las medidas de reparaci\u00f3n esta\u00adblecidas en el Plan Integral de \u00a0Reparaci\u00f3n Colectiva. \u00a0 \u00a0<\/p>\n<p>5. Propender por la participaci\u00f3n de los \u00a0miembros del Movimiento Sindical en el proceso de reparaci\u00f3n colectiva. \u00a0 \u00a0<\/p>\n<p>6. Crear las comisiones o grupos de trabajo \u00a0que considere necesarios para el desarrollo de las propuestas de reparaci\u00f3n \u00a0colectiva. \u00a0 \u00a0<\/p>\n<p>7. Determinar la creaci\u00f3n de grupos de \u00a0trabajo con expertos que estime convenientes para el estudio de asuntos \u00a0espec\u00edficos relacionados con su objeto. \u00a0 \u00a0<\/p>\n<p>8. Darse su propio reglamento, lo que \u00a0incluye, entre otros aspectos, lo referente a la elaboraci\u00f3n de las actas, el \u00a0manejo y dep\u00f3sito de las mismas y la determinaci\u00f3n de las funciones de la \u00a0Secretar\u00eda T\u00e9cnica adicionales a las establecidas en el presente decreto. \u00a0 \u00a0<\/p>\n<p>9. Crear una comisi\u00f3n o mesa de trabajo que \u00a0d\u00e9 seguimiento al cumplimiento de los acuerdos y avances del proceso de \u00a0reparaci\u00f3n colectiva al Movimiento Sindical. \u00a0 \u00a0<\/p>\n<p>10. Las dem\u00e1s que se consideren necesarias \u00a0para el cabal cumplimiento del objeto de la Mesa. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 10. Informes. Para garantizar \u00a0el resultado de la labor que cumplir\u00e1 la Mesa Permanente de Concertaci\u00f3n con \u00a0las Centrales Sindicales CUT, CGT, CTC y la Fecode para la Reparaci\u00f3n Colectiva \u00a0al Movimiento Sindical, por intermedio de su Secretar\u00eda T\u00e9cnica, dentro de los \u00a0sesenta (60) d\u00edas calendario siguientes al inicio de cada semestre, se \u00a0entregar\u00e1 a los integrantes de la Mesa un informe sobre la gesti\u00f3n de esta \u00a0durante el semestre inmediatamente anterior. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 11. Vigencia. Este Decreto rige \u00a0a partir de la fecha de su publicaci\u00f3n y tendr\u00e1 vigencia durante el t\u00e9rmino de \u00a0la Ley 1448 de 2011. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., 18 de abril de 2016. \u00a0 \u00a0<\/p>\n<p>JUAN MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>El Ministro del Interior, Juan Fernando \u00a0Cristo Bustos. \u00a0 \u00a0<\/p>\n<p>El Ministro del Trabajo, Luis Eduardo \u00a0Garz\u00f3n. \u00a0 \u00a0<\/p>\n<p>La Directora del Departamento Administrativo \u00a0para la Prosperidad Social, Tatiana Orozco de la Cruz \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 624 DE 2016 \u00a0 \u00a0\u00a0 (abril \u00a018) \u00a0 \u00a0 D.O. 49.848, abril 18 de 2016 \u00a0 \u00a0 por el cual \u00a0se crea y reglamenta la Mesa Permanente de Concertaci\u00f3n con las Centrales \u00a0Sindicales CUT, CGT, CTC y la Fecode para la Reparaci\u00f3n Colectiva al Movimiento \u00a0Sindical. \u00a0 \u00a0 El Presidente de la Rep\u00fablica de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-49635","post","type-post","status-publish","format-standard","hentry","category-decretos-2016"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=49635"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49635\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=49635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=49635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=49635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}