{"id":49890,"date":"2023-08-16T21:37:32","date_gmt":"2023-08-16T21:37:32","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-1228-de-2016\/"},"modified":"2023-08-16T21:37:32","modified_gmt":"2023-08-16T21:37:32","slug":"decreto-1228-de-2016","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-1228-de-2016\/","title":{"rendered":"DECRETO 1228 DE 2016"},"content":{"rendered":"\n<p>DECRETO \u00a01228 DE 2016 \u00a0 \u00a0\u00a0<\/p>\n<p>(julio 29) \u00a0 \u00a0<\/p>\n<p>D.O. 49.949, julio 29 de 2016 \u00a0 \u00a0<\/p>\n<p>por el cual se establece la planta de personal de la Agencia de \u00a0Renovaci\u00f3n del Territorio, (ART). \u00a0 \u00a0<\/p>\n<p>Nota: Modificado por el Decreto 1224 de 2020, \u00a0por el Decreto 2108 de 2019 \u00a0y por el Decreto 2097 de 2016. \u00a0 \u00a0<\/p>\n<p>El \u00a0Presidente de la Rep\u00fablica de Colombia, en ejercicio de las facultades \u00a0constitucionales y legales, en especial las que le confiere el art\u00edculo 115 de \u00a0la Ley 489 de 1998, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que \u00a0mediante el Decreto\u2013ley 2366 \u00a0de 2015, se cre\u00f3 la Agencia de Renovaci\u00f3n del Territorio, (ART), y se \u00a0determin\u00f3 su objeto y estructura. \u00a0 \u00a0<\/p>\n<p>Que se \u00a0requiere adoptar la planta de personal para el debido y correcto funcionamiento \u00a0de la Agencia de Renovaci\u00f3n del Territorio, (ART), para lo cual el Ministerio \u00a0de Agricultura y Desarrollo Rural present\u00f3 al Departamento Administrativo de la \u00a0Funci\u00f3n P\u00fablica el estudio t\u00e9cnico de que trata el art\u00edculo 46 de la Ley 909 de 2004, \u00a0modificado por el art\u00edculo 228 del Decreto 019 de 2012, \u00a0obteniendo el concepto t\u00e9cnico favorable de ese Departamento. \u00a0 \u00a0<\/p>\n<p>Que para \u00a0los fines de este decreto, la Direcci\u00f3n General del Presupuesto P\u00fablico \u00a0Nacional del Ministerio de Hacienda y Cr\u00e9dito P\u00fablico otorg\u00f3 la viabilidad \u00a0presupuestal correspondiente. \u00a0 \u00a0<\/p>\n<p>Que en \u00a0virtud de lo anterior, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a01\u00b0. Las funciones propias de la Agencia de Renovaci\u00f3n del Territorio, (ART), \u00a0ser\u00e1n cumplidas por la planta de personal que a continuaci\u00f3n se establece: \u00a0 \u00a0<\/p>\n<p>N\u00b0. de Cargos \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Denominaci\u00f3n del cargo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>C\u00f3digo \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Grado \u00a0\u00a0<\/p>\n<p>Despacho del \u00a0 \u00a0Director \u00a0\u00a0<\/p>\n<p>1 (Uno) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Director General de Agencia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>E3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>05 \u00a0\u00a0<\/p>\n<p>1 (Uno) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Experto \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>G3 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>08 \u00a0\u00a0<\/p>\n<p>1 (Uno) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>T\u00e9cnico Asistencial \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>O1 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>12 \u00a0\u00a0<\/p>\n<p>Planta Global \u00a0\u00a0<\/p>\n<p>1(Uno) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Secretario General de Agencia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>E6 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>03 \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a02\u00b0. El presente decreto rige a partir de la fecha de su publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese \u00a0y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en \u00a0Bogot\u00e1, D. C., a 29 de julio de 2016. \u00a0 \u00a0<\/p>\n<p>JUAN \u00a0MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>El \u00a0Ministro de Hacienda y Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p>Mauricio C\u00e1rdenas Santamar\u00eda. \u00a0 \u00a0<\/p>\n<p>El \u00a0Ministerio de Agricultura y Desarrollo Rural, \u00a0 \u00a0<\/p>\n<p>Aurelio Iragorri Valencia. \u00a0 \u00a0<\/p>\n<p>La \u00a0Directora del Departamento Administrativo de la Funci\u00f3n P\u00fablica, \u00a0 \u00a0<\/p>\n<p>Liliana \u00a0Caballero Dur\u00e1n. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO \u00a01228 DE 2016 \u00a0 \u00a0\u00a0 (julio 29) \u00a0 \u00a0 D.O. 49.949, julio 29 de 2016 \u00a0 \u00a0 por el cual se establece la planta de personal de la Agencia de \u00a0Renovaci\u00f3n del Territorio, (ART). \u00a0 \u00a0 Nota: Modificado por el Decreto 1224 de 2020, \u00a0por el Decreto 2108 de 2019 \u00a0y por el Decreto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-49890","post","type-post","status-publish","format-standard","hentry","category-decretos-2016"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=49890"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/49890\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=49890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=49890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=49890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}