{"id":50267,"date":"2023-08-16T21:37:50","date_gmt":"2023-08-16T21:37:50","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-1995-de-2016\/"},"modified":"2023-08-16T21:37:50","modified_gmt":"2023-08-16T21:37:50","slug":"decreto-1995-de-2016","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/16\/decreto-1995-de-2016\/","title":{"rendered":"DECRETO 1995 DE 2016"},"content":{"rendered":"\n<p>DECRETO \u00a01995 DE 2016 \u00a0 \u00a0\u00a0<\/p>\n<p>(diciembre \u00a07) \u00a0 \u00a0<\/p>\n<p>D.O. \u00a050.080, diciembre 7 de 2016 \u00a0 \u00a0<\/p>\n<p>por el cual se crea la Comisi\u00f3n de Seguimiento, Impulso y Verificaci\u00f3n a \u00a0la Implementaci\u00f3n del Acuerdo Final, suscrito entre el Gobierno nacional y las \u00a0Farc-EP el 24 de noviembre de 2016. \u00a0 \u00a0<\/p>\n<p>Nota: Modificado por el Decreto 1417 de 2018. \u00a0 \u00a0<\/p>\n<p>El \u00a0Presidente de la Rep\u00fablica de Colombia, en ejercicio de sus facultades \u00a0constitucionales y legales y, en especial, de las conferidas por el art\u00edculo 8\u00b0 \u00a0de la Ley 418 de 1997, con \u00a0sus modificaciones y reformas actualmente vigentes, y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que el \u00a0art\u00edculo 22 de la Constituci\u00f3n Pol\u00edtica \u00a0establece que la paz es un derecho y un deber de obligatorio cumplimiento. \u00a0 \u00a0<\/p>\n<p>Que de \u00a0conformidad con el numeral 4 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica, \u00a0corresponde al Presidente de la Rep\u00fablica como Jefe de Estado, Jefe de Gobierno \u00a0y Suprema Autoridad Administrativa, conservar en todo el territorio el orden \u00a0p\u00fablico y restablecerlo donde fuere turbado. \u00a0 \u00a0<\/p>\n<p>Que el \u00a0art\u00edculo 10 de la Ley 418 de 1997 \u00a0establece que la direcci\u00f3n de todo proceso de paz corresponde exclusivamente al \u00a0Presidente de la Rep\u00fablica como responsable de la preservaci\u00f3n del orden \u00a0p\u00fablico en toda la Naci\u00f3n. Adem\u00e1s, indica que quienes a nombre del Gobierno \u00a0participen en los di\u00e1logos y acuerdos de paz, lo har\u00e1n de conformidad con las \u00a0instrucciones que \u00e9l les imparta. \u00a0 \u00a0<\/p>\n<p>Que el \u00a0art\u00edculo 8\u00b0 de la Ley 418 de 1997, \u00a0modificado por la Ley 1779 de 2016, \u00a0establece que los \u201cacuerdos y su contenido ser\u00e1n los que a juicio del Gobierno \u00a0sean necesarios para adelantar el proceso de paz y su cumplimiento ser\u00e1 \u00a0verificado por las instancias nacionales o internacionales que para el efecto y \u00a0de com\u00fan acuerdo designen las partes\u201d. \u00a0 \u00a0<\/p>\n<p>Que en la misma \u00a0l\u00ednea, el par\u00e1grafo segundo de dicho art\u00edculo se\u00f1ala que las \u201cpartes acordar\u00e1n \u00a0mecanismos de verificaci\u00f3n conjunta de los acuerdos, di\u00e1logos o acercamientos y \u00a0de considerarlo conveniente podr\u00e1n acudir a instituciones o personas de la vida \u00a0nacional o internacional para llevar a cabo dicha verificaci\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>Que en la \u00a0b\u00fasqueda de una paz estable y duradera y la terminaci\u00f3n definitiva del \u00a0conflicto armado, el Gobierno nacional suscribi\u00f3, el 24 de noviembre de 2016, \u00a0con el grupo armado Fuerzas Armadas Revolucionarias de Colombia, Ej\u00e9rcito del \u00a0Pueblo (Farc-EP) un nuevo Acuerdo Final para la Terminaci\u00f3n del Conflicto y la \u00a0Construcci\u00f3n de una Paz Estable y Duradera. \u00a0 \u00a0<\/p>\n<p>Que el \u00a0punto 6 de dicho acuerdo trata sobre la implementaci\u00f3n, verificaci\u00f3n y \u00a0refrendaci\u00f3n e indica que la implementaci\u00f3n de los acuerdos alcanzados en el \u00a0proceso de paz deber\u00e1 efectuarse de buena fe, atendiendo a la reciprocidad en \u00a0el cumplimiento de las obligaciones aceptadas por las partes, promoviendo la \u00a0integraci\u00f3n de las poblaciones, comunidades, territorios y regiones en el pa\u00eds, \u00a0en particular de las m\u00e1s afectadas por el conflicto y las que han vivido en \u00a0condiciones de pobreza y marginalidad. \u00a0 \u00a0<\/p>\n<p>Que en el \u00a0mismo punto 6 del Acuerdo Final, y para garantizar el efectivo cumplimiento de \u00a0lo pactado, se acord\u00f3 crear una Comisi\u00f3n de Seguimiento, Impulso y Verificaci\u00f3n \u00a0a la Implementaci\u00f3n del Acuerdo Final (CSIVI), encargada, entre otros, del \u00a0seguimiento a los componentes del acuerdo. \u00a0 \u00a0<\/p>\n<p>Que el \u00a0mismo punto aclara que el Gobierno nacional ser\u00e1 el responsable de la correcta \u00a0implementaci\u00f3n de los acuerdos alcanzados en el proceso de conversaciones de \u00a0Paz. \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Creaci\u00f3n y \u00a0objetivo. Cr\u00e9ase la Comisi\u00f3n de Seguimiento, Impulso y Verificaci\u00f3n a la \u00a0Implementaci\u00f3n del Acuerdo Final (CSIVI), como la instancia conjunta entre el \u00a0Gobierno nacional y las Farc-EP en proceso de reincorporaci\u00f3n a la vida legal, \u00a0encargada del seguimiento, impulso y verificaci\u00f3n conjunta de la implementaci\u00f3n \u00a0del Acuerdo final para la terminaci\u00f3n \u00a0del conflicto y la construcci\u00f3n de una paz estable y duradera, y de la \u00a0resoluci\u00f3n de las diferencias que puedan surgir entre las partes firmantes del \u00a0mencionado acuerdo. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a02\u00b0. Modificado por el Decreto 1417 de 2018, \u00a0art\u00edculo 1\u00ba. Composici\u00f3n y acompa\u00f1amiento. De conformidad con el punto 6.1 del Acuerdo Final \u00a0para la terminaci\u00f3n del conflicto y la construcci\u00f3n de una paz estable y \u00a0duradera suscrito entre el Gobierno nacional y las FARC-EP, el 22 de \u00a0noviembre de 2016, la Comisi\u00f3n de Seguimiento Impulso y Verificaci\u00f3n a la \u00a0Implementaci\u00f3n del Acuerdo Final (CSIVI), estar\u00e1 integrada por tres \u00a0representantes del Gobierno nacional y tres representantes de los exintegrantes \u00a0de FARC-EP, en proceso de reincorporaci\u00f3n. Los representantes del Gobierno \u00a0nacional ser\u00e1n de alto nivel y ser\u00e1n designados por el Presidente de la \u00a0Rep\u00fablica. Los representantes de los exintegrantes de las FARC-EP, en proceso \u00a0de reincorporaci\u00f3n ser\u00e1n designados por la Fuerza Alternativa Revolucionaria \u00a0del Com\u00fan \u2013Farc. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo \u00a01\u00b0. Acompa\u00f1amiento. La CSIVI \u00a0contar\u00e1 con el acompa\u00f1amiento permanente de un delegado\/a de cada uno de los \u00a0pa\u00edses garantes, Cuba y Noruega, durante la implementaci\u00f3n del Acuerdo Final \u00a0suscrito el 24 de noviembre de 2016. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo \u00a02\u00b0. Apoyo t\u00e9cnico. Los integrantes de la CSIVI, en su calidad de representantes \u00a0de los exintegrantes de las FARC-EP en proceso de reincorporaci\u00f3n, podr\u00e1n con \u00a0sujeci\u00f3n a la ley y dem\u00e1s normas pertinentes acudir a la cooperaci\u00f3n \u00a0internacional para generar las condiciones y medios necesarios para el \u00a0ejercicio de sus funciones. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo \u00a03\u00b0. Componente internacional de verificaci\u00f3n de la CSIVI. El mecanismo de \u00a0verificaci\u00f3n de los acuerdos tendr\u00e1 un componente internacional, el cual \u00a0funcionar\u00e1 de acuerdo a los criterios establecidos en el subpunto 6.3.1 del \u00a0Acuerdo Final de Paz. \u00a0 \u00a0<\/p>\n<p>De \u00a0conformidad con el subpunto 6.3.2 del Acuerdo Final de Paz, el mecanismo de \u00a0verificaci\u00f3n estar\u00e1 compuesto por una instancia de Notables, una Secretar\u00eda \u00a0T\u00e9cnica y un Apoyo t\u00e9cnico, tales instancias tendr\u00e1n las funciones definidas en \u00a0dicho subpunto. \u00a0 \u00a0<\/p>\n<p>Conc. Decreto 720 de 2022. \u00a0Decreto 451 de 2020. \u00a0 \u00a0<\/p>\n<p>Texto inicial del art\u00edculo 2\u00ba: \u201cComposici\u00f3n. De conformidad con lo previsto en el punto 6.1. del Acuerdo final para la terminaci\u00f3n del \u00a0conflicto y la construcci\u00f3n de una Paz estable y duradera Suscrito entre \u00a0el Gobierno nacional y las Farc-EP el 22 de noviembre de 2016, la Comisi\u00f3n de \u00a0Seguimiento, impulso y verificaci\u00f3n a la implementaci\u00f3n del Acuerdo Final \u00a0(CSIVI), estar\u00e1 integrada por tres representantes del Gobierno nacional y tres \u00a0representantes de las Farc-EP en proceso de reincorporaci\u00f3n a la vida legal, o \u00a0del partido pol\u00edtico que surja de su tr\u00e1nsito a la vida legal. Los \u00a0representantes del Gobierno nacional ser\u00e1n de alto nivel y ser\u00e1n designados por \u00a0el Presidente de la Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Acompa\u00f1amiento. La CSIVI contar\u00e1 \u00a0con el acompa\u00f1amiento durante el cese al fuego y de hostilidades bilateral y \u00a0definitivo y la dejaci\u00f3n de armas (D+180), de un delegado\/a de cada uno de los \u00a0pa\u00edses garantes, Cuba y Noruega, as\u00ed como de un delegado\/a de cada uno de los \u00a0pa\u00edses acompa\u00f1antes, Chile y Venezuela.\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a03\u00b0. Funciones. Sin perjuicio de \u00a0las funciones y competencias establecidas a las diferentes autoridades \u00a0p\u00fablicas, la Comisi\u00f3n de Seguimiento, Impulso y Verificaci\u00f3n a la \u00a0Implementaci\u00f3n del Acuerdo Final (CSIVI), cumplir\u00e1 las siguientes funciones: \u00a0 \u00a0<\/p>\n<p>1. \u00a0Resolver cualquier diferencia de interpretaci\u00f3n o cualquier situaci\u00f3n \u00a0imprevista que surja entre las partes firmantes respecto del Acuerdo Final, que \u00a0no puedan ser resueltas por los mecanismos acordados en el punto \u00a0correspondiente, cuando existan. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. \u00a0Los pa\u00edses garantes podr\u00e1n contribuir a facilitar la soluci\u00f3n de las \u00a0diferencias cuando as\u00ed se requiera. \u00a0 \u00a0<\/p>\n<p>2. Servir \u00a0de espacio para el manejo de cualquier situaci\u00f3n o diferencia entre las partes \u00a0que puedan presentarse tras la firma del Acuerdo Final, que no sean de \u00a0competencia del Mecanismo de Monitoreo y Verificaci\u00f3n de Naciones Unidas. \u00a0 \u00a0<\/p>\n<p>3. Hacer \u00a0recomendaciones al listado de medidas de implementaci\u00f3n temprana que presente \u00a0el Gobierno nacional. \u00a0 \u00a0<\/p>\n<p>4. Definir \u00a0la agenda y abordar los temas se\u00f1alados en el numeral 6.1.11. del Acuerdo Final \u00a0sobre la implementaci\u00f3n prioritaria. \u00a0 \u00a0<\/p>\n<p>5. \u00a0Discutir y aprobar el Plan Marco para la implementaci\u00f3n del Acuerdo Final sobre \u00a0la base del borrador que ser\u00e1 presentado por el Gobierno nacional, que ser\u00e1 \u00a0incorporado por el Consejo Nacional de la Pol\u00edtica Econ\u00f3mica y Social a trav\u00e9s \u00a0de un documento Conpes. \u00a0 \u00a0<\/p>\n<p>6. Constatar que el \u00a0contenido de todos los proyectos de decreto, ley o acto legislativo que sean \u00a0necesarios para implementar el Acuerdo Final, correspondan a lo acordado, antes \u00a0de que sean expedidos por el Presidente de la Rep\u00fablica o presentados ante el \u00a0Congreso, seg\u00fan sea el caso. Para estos efectos, se tendr\u00e1 en cuenta el listado \u00a0no exhaustivo de proyectos incluidos en el Acuerdo Final. Lo anterior sin \u00a0perjuicio de las competencias del Congreso de la Rep\u00fablica. (Nota: El Consejo de \u00a0Estado en sentencia del 2 de marzo de 2018, decret\u00f3 la medida cautelar de suspensi\u00f3n provisional de los \u00a0efectos de este numeral. Exp. 11001-03-24-000-2017-00240-00. \u00a0Secci\u00f3n 1\u00aa. C. P. Oswaldo Giraldo L\u00f3pez.). \u00a0 \u00a0<\/p>\n<p>7. \u00a0Proponer al Gobierno nacional conforme a lo establecido en el Acuerdo Final los \u00a0borradores de normas que se consideren necesarias para la implementaci\u00f3n del \u00a0Acuerdo Final, sin perjuicio de las facultades ordinarias del Congreso de la \u00a0Rep\u00fablica. \u00a0 \u00a0<\/p>\n<p>8. \u00a0Promover, en coordinaci\u00f3n con las autoridades competentes, la recepci\u00f3n de \u00a0fondos procedentes de la cooperaci\u00f3n internacional, los organismos \u00a0multilaterales y el sector privado para la implementaci\u00f3n del Acuerdo Final los \u00a0cuales se agregar\u00e1n a los fondos dispuestos por el Gobierno para esos fines. \u00a0 \u00a0<\/p>\n<p>9. Mantener \u00a0interlocuci\u00f3n con las agencias, estados y organizaciones cooperantes que \u00a0contribuyan econ\u00f3micamente a la implementaci\u00f3n del Acuerdo Final y\/o que formen \u00a0parte del acompa\u00f1amiento internacional de la misma. \u00a0 \u00a0<\/p>\n<p>10. \u00a0Solicitar informes de seguimiento y ejecuci\u00f3n sobre los distintos programas y \u00a0proyectos que se ejecuten con recursos de cooperaci\u00f3n internacional, en el \u00a0marco de la implementaci\u00f3n del Acuerdo Final. \u00a0 \u00a0<\/p>\n<p>11. Numeral modificado por el Decreto 1417 de 2018, \u00a0art\u00edculo 2\u00ba. Establecer los criterios y requerimientos t\u00e9cnicos \u00a0del componente de acompa\u00f1amiento internacional encaminados a garantizar el \u00a0apoyo e impulso de la ejecuci\u00f3n y monitoreo de los planes, programas y \u00a0actividades para la implementaci\u00f3n del Acuerdo Final en los t\u00e9rminos del \u00a0subpunto 6.4, as\u00ed como los criterios para el establecimiento de una instancia \u00a0de integraci\u00f3n para el cumplimiento de las actividades espec\u00edficas del \u00a0acompa\u00f1amiento internacional. \u00a0 \u00a0<\/p>\n<p>Texto \u00a0inicial del numeral 11: \u201cEstablecer los criterios y requerimientos del \u00a0acompa\u00f1amiento internacional a la implementaci\u00f3n en cada uno de los puntos del \u00a0Acuerdo Final, as\u00ed como los criterios para el establecimiento de una instancia \u00a0de integraci\u00f3n para el cumplimiento de las actividades espec\u00edficas del \u00a0acompa\u00f1amiento internacional.\u201d. \u00a0 \u00a0<\/p>\n<p>12. \u00a0Verificar y hacer seguimiento al cumplimiento de todos los componentes del \u00a0Acuerdo Final, respetando lo establecido en el punto 6.4. sobre acompa\u00f1amiento \u00a0internacional, y sin perjuicio de las funciones del Mecanismo de Monitoreo y \u00a0Verificaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>13. Hacer \u00a0seguimiento y verificar el cumplimiento de los compromisos establecidos en la \u00a0l\u00ednea de tiempo del Acuerdo Final, sin afectar las competencias de las ramas \u00a0del poder p\u00fablico y de los \u00f3rganos del Estado. \u00a0 \u00a0<\/p>\n<p>14. \u00a0Presentar informes peri\u00f3dicos y diferenciales de los avances de la \u00a0implementaci\u00f3n del Acuerdo Final. As\u00ed mismo, de manera ocasional, generar\u00e1 \u00a0reportes tem\u00e1ticos, especializados o territoriales relacionados con los \u00a0componentes del Acuerdo Final. \u00a0 \u00a0<\/p>\n<p>15. \u00a0Presentar al Consejo Nacional de Reconciliaci\u00f3n y Convivencia los avances en la \u00a0implementaci\u00f3n, y recibir del Consejo toda la informaci\u00f3n que quiera aportarle. \u00a0 \u00a0<\/p>\n<p>16. \u00a0Analizar los informes tem\u00e1ticos y peri\u00f3dicos presentados por el componente de \u00a0acompa\u00f1amiento internacional del Acuerdo Final, en cada uno de los puntos del \u00a0mismo. \u00a0 \u00a0<\/p>\n<p>17. \u00a0Mantener contacto permanente con los notables que integran el Componente \u00a0Internacional de Verificaci\u00f3n, con el fin de coordinar recomendaciones de \u00a0soluci\u00f3n para los puntos de discusi\u00f3n y controversia que se adviertan en la \u00a0implementaci\u00f3n del Acuerdo Final. \u00a0 \u00a0<\/p>\n<p>18. \u00a0Recibir y analizar las observaciones de los notables que integran el Componente \u00a0Internacional de Verificaci\u00f3n de la CSIVI, relacionadas con la implementaci\u00f3n \u00a0del Acuerdo Final. \u00a0 \u00a0<\/p>\n<p>19. \u00a0Establecer el alcance y los criterios de funcionamiento a que debe sujetarse el \u00a0Instituto Kroc de Estudios Internacionales de Paz de la Universidad de Notre Dame, EE.UU., en el apoyo t\u00e9cnico que debe prestar a \u00a0los notables, con el fin de recolectar, analizar y preparar la informaci\u00f3n \u00a0necesaria para emitir los pronunciamientos p\u00fablicos a que se refiere el punto \u00a06.3.2. del Acuerdo Final. \u00a0 \u00a0<\/p>\n<p>20. \u00a0Seleccionar el secretario t\u00e9cnico del Componente Internacional de Verificaci\u00f3n \u00a0de la Comisi\u00f3n de Seguimiento, Impulso y Verificaci\u00f3n a la Implementaci\u00f3n del \u00a0Acuerdo Final (CSIVI), as\u00ed como establecer los protocolos a que debe ajustarse \u00a0para la verificaci\u00f3n de la implementaci\u00f3n del Acuerdo. \u00a0 \u00a0<\/p>\n<p>21. \u00a0Recibir insumos de las distintas instancias encargadas de la implementaci\u00f3n del \u00a0Acuerdo Final as\u00ed como de organizaciones, universidades, centros de \u00a0investigaci\u00f3n, observatorios tanto nacionales como territoriales. \u00a0 \u00a0<\/p>\n<p>22. Numeral modificado por el Decreto 1417 de 2018, \u00a0art\u00edculo 2\u00ba. Establecer los par\u00e1metros para la revisi\u00f3n \u00a0anual del Plan Marco de Implementaci\u00f3n del Acuerdo Final, con el fin de \u00a0recomendar los ajustes a que haya lugar. \u00a0 \u00a0<\/p>\n<p>Texto \u00a0inicial del numeral 22: \u201cRevisar anualmente el Plan Marco para la Implementaci\u00f3n \u00a0del Acuerdo Final y recomendar los ajustes a que haya lugar.\u201d. \u00a0 \u00a0<\/p>\n<p>23. \u00a0Organizar, para el ejercicio de sus funciones, comisiones tem\u00e1ticas y \u00a0territoriales que permitan la participaci\u00f3n ciudadana. \u00a0 \u00a0<\/p>\n<p>24. \u00a0Recomendar al se\u00f1or Presidente de la Rep\u00fablica la finalizaci\u00f3n del \u00a0funcionamiento del componente de verificaci\u00f3n internacional al que se refiere \u00a0el punto 6.3.5 del Acuerdo Final, previa evaluaci\u00f3n de su conveniencia y \u00a0necesidad. \u00a0 \u00a0<\/p>\n<p>25. \u00a0Mantener interlocuci\u00f3n con la Instancia de Alto Nivel de los Pueblos \u00c9tnicos. \u00a0 \u00a0<\/p>\n<p>26. \u00a0Conceptuar sobre la pr\u00f3rroga de las licencias de inter\u00e9s p\u00fablico clase \u201cC\u201d para \u00a0el funcionamiento de las emisoras a las que se refiere el punto 6.5. del \u00a0Acuerdo Final. \u00a0 \u00a0<\/p>\n<p>27. Numeral adicionado por el Decreto 1417 de 2018, \u00a0art\u00edculo 3\u00ba. Proponer las acciones y medidas de car\u00e1cter administrativo y \u00a0de diversa \u00edndole, que se requieran para el adecuado cumplimiento del Acuerdo \u00a0Final de Paz; sin que ello constituya un requisito previo para el ejercicio de \u00a0las iniciativas gubernamental y legislativa. \u00a0 \u00a0<\/p>\n<p>28. Numeral adicionado por el Decreto 1417 de 2018, \u00a0art\u00edculo 3\u00ba. Acordar un plan espec\u00edfico de seguimiento, impulso y \u00a0verificaci\u00f3n de todas las acciones y medidas que se hayan adoptado o se adopten \u00a0para la implementaci\u00f3n del Acuerdo Final. Para dichos efectos, se podr\u00e1n \u00a0constituir y poner en marcha comisiones especializadas que contar\u00e1n con la \u00a0participaci\u00f3n de los delegados de las partes que conforman la CSIVI. \u00a0 \u00a0<\/p>\n<p>29. Numeral adicionado por el Decreto 1417 de 2018, \u00a0art\u00edculo 3\u00ba. Analizar los informes que, con una periodicidad no inferior a \u00a0tres meses, le rindan las comisiones especializadas de que trata el numeral 2, \u00a0con el fin de acordar las medidas y acciones que sean pertinentes para \u00a0garantizar la adecuada implementaci\u00f3n del Acuerdo Final. \u00a0 \u00a0<\/p>\n<p>30. Numeral adicionado por el Decreto 1417 de 2018, \u00a0art\u00edculo 3\u00ba. Impulsar el cumplimiento del Plan Marco de Implementaci\u00f3n y \u00a0del Acuerdo Final de Paz en el marco del tr\u00e1nsito de cambio de Gobierno. \u00a0 \u00a0<\/p>\n<p>31. Numeral adicionado por el Decreto 1417 de 2018, \u00a0art\u00edculo 3\u00ba. Fortalecer los mecanismos de interlocuci\u00f3n y coordinaci\u00f3n con \u00a0el mecanismo de verificaci\u00f3n de la CSIVI, a trav\u00e9s de la expedici\u00f3n de \u00a0protocolos y recomendaciones que desarrollen los criterios orientadores \u00a0establecidos en el subpunto 6.3.1 del Acuerdo Final para la Terminaci\u00f3n del \u00a0Conflicto y la Construcci\u00f3n de una Paz Estable y Duradera. \u00a0 \u00a0<\/p>\n<p>32. Numeral adicionado por el Decreto 1417 de 2018, \u00a0art\u00edculo 3\u00ba. La CSIVI, en cuanto instancia de seguimiento, verificaci\u00f3n e \u00a0impulso a la implementaci\u00f3n del Acuerdo Final, debe actuar como mecanismo de \u00a0interlocuci\u00f3n y coordinaci\u00f3n con los componentes de acompa\u00f1amiento y \u00a0verificaci\u00f3n internacional, en especial con su Secretar\u00eda T\u00e9cnica y los \u00a0Notables, as\u00ed como con la Misi\u00f3n Pol\u00edtica de Verificaci\u00f3n de las Naciones \u00a0Unidas. \u00a0 \u00a0<\/p>\n<p>33. Numeral adicionado por el Decreto 1417 de 2018, \u00a0art\u00edculo 3\u00ba. Impulsar mecanismos pedag\u00f3gicos y de participaci\u00f3n ciudadana en \u00a0el orden territorial, de acuerdo con lo establecido en el Decreto ley 885 de \u00a02017, mediante el cual se crea el Consejo Nacional de Paz, Reconciliaci\u00f3n y \u00a0Convivencia (CNPRC), as\u00ed como los respectivos Consejos Regionales, entendidos \u00a0como las instancias de seguimiento e impulso a la implementaci\u00f3n presididas por \u00a0los Alcaldes y Gobernadores. \u00a0 \u00a0<\/p>\n<p>34. Numeral adicionado por el Decreto 1417 de 2018, \u00a0art\u00edculo 3\u00ba. Seleccionar, de mutuo acuerdo y con apego a los protocolos y \u00a0lineamientos establecidos por la CSIVI, la Secretar\u00eda T\u00e9cnica del mecanismo de \u00a0verificaci\u00f3n del Acuerdo Final. \u00a0 \u00a0<\/p>\n<p>35. \u00a0Recomendar al Gobierno nacional las medidas necesarias para dar cumplimiento al \u00a0Plan Plurianual de Inversiones del Plan Nacional de Desarrollo de que trata el \u00a0art\u00edculo 3\u00b0 del Acto Legislativo n\u00famero 1 de 2016, en desarrollo de lo \u00a0establecido en el documento Conpes de \u201cLineamientos \u00a0para la articulaci\u00f3n del Plan Marco de Implementaci\u00f3n del Acuerdo Final con los \u00a0instrumentos de planeaci\u00f3n, programaci\u00f3n y seguimiento a pol\u00edticas p\u00fablicas del \u00a0orden nacional y territorial\u201d. \u00a0 \u00a0<\/p>\n<p>36. Numeral adicionado \u00a0por el Decreto 1417 de 2018, \u00a0art\u00edculo 3\u00ba. Fomentar los mecanismos de participaci\u00f3n y veedur\u00eda ciudadanas \u00a0a trav\u00e9s de la recolecci\u00f3n y an\u00e1lisis de los informes y recomendaciones de las \u00a0organizaciones de la sociedad civil y del sector privado para la implementaci\u00f3n \u00a0del Acuerdo Final. Lo anterior, con el fin de evaluar y adoptar las medidas \u00a0necesarias para garantizar el cumplimiento de lo acordado. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. \u00a0La CSIVI ejercer\u00e1 sus funciones respetando lo establecido en el Acuerdo Final \u00a0en relaci\u00f3n con el acompa\u00f1amiento internacional y sin perjuicio de las \u00a0funciones del Mecanismo de Monitoreo y Verificaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a04\u00b0. Modificado por el Decreto 1417 de 2018, \u00a0art\u00edculo 4\u00ba. Secretar\u00eda \u00a0T\u00e9cnica de la CSIVI. La CSIVI tendr\u00e1 una \u00a0Secretar\u00eda T\u00e9cnica a cargo de sendos delegados del Gobierno nacional y de los \u00a0exintegrantes de FARC-EP, en proceso de reincorporaci\u00f3n. Ser\u00e1 responsable de la \u00a0organizaci\u00f3n de las agendas de las sesiones de la CSIVI, de la coordinaci\u00f3n \u00a0t\u00e9cnica de las comisiones y actividades, y de la preparaci\u00f3n de las actas de \u00a0las sesiones, as\u00ed como de aquellas labores que expresamente le conf\u00ede la CSIVI. \u00a0 \u00a0<\/p>\n<p>Texto inicial del art\u00edculo 4\u00ba: \u201cSecretar\u00eda T\u00e9cnica. Igualmente \u00a0tendr\u00e1 una Secretar\u00eda T\u00e9cnica conformada de com\u00fan acuerdo entre el Gobierno \u00a0nacional y las Farc-EP para producir los informes peri\u00f3dicos y cumplir \u00a0cualquier otra tarea que requiera.\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a05\u00b0. Modificado por el Decreto 1417 de 2018, \u00a0art\u00edculo 5\u00ba. Sesiones. La CSIVI para su funcionamiento tendr\u00e1 las siguientes \u00a0clases de sesiones: \u00a0 \u00a0<\/p>\n<p>1. Sesiones exclusivas. La CSIVI realizar\u00e1, \u00a0de manera peri\u00f3dica, sesiones con los representantes de los dos componentes que \u00a0la conforman y su respectiva secretar\u00eda t\u00e9cnica. \u00a0 \u00a0<\/p>\n<p>2. Sesiones t\u00e9cnicas. La CSIVI realizar\u00e1, \u00a0de acuerdo a sus necesidades, sesiones con los delegados de ambos componentes \u00a0que la conforman, para tratar materias espec\u00edficas, rendir informes y formular \u00a0recomendaciones a las sesiones exclusivas. \u00a0 \u00a0<\/p>\n<p>3. Sesiones ampliadas. La CSIVI realizar\u00e1, \u00a0de manera peri\u00f3dica, sesiones con los representantes y delegados de los dos \u00a0componentes que la conforman; a las cuales podr\u00e1n ser invitados funcionarios, \u00a0as\u00ed como representantes de organizaciones de la sociedad civil y de la \u00a0comunidad internacional con el fin de abordar las tem\u00e1ticas que se consideren \u00a0necesarias para garantizar el seguimiento, impulso y verificaci\u00f3n a la \u00a0Implementaci\u00f3n del Acuerdo Final. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. \u00a0A todas las sesiones de que trata el presente art\u00edculo podr\u00e1n asistir delegados \u00a0de los pa\u00edses garantes o acompa\u00f1antes, para lo cual se les brindar\u00e1 \u00a0oportunamente la informaci\u00f3n requerida. Igualmente podr\u00e1n asistir, mediante \u00a0invitaci\u00f3n especial, representantes, o delegados de entidades p\u00fablicas, de \u00a0organizaciones de la sociedad civil, de las entidades territoriales, del \u00a0Consejo Nacional de Reincorporaci\u00f3n, del Consejo Nacional para la \u00a0Reconciliaci\u00f3n y la Convivencia, de la Instancia especial para el seguimiento \u00a0del enfoque de g\u00e9nero y garant\u00eda de los derechos de las mujeres, y de la Instancia \u00a0Especial de Alto Nivel de los Pueblos \u00c9tnicos. \u00a0 \u00a0<\/p>\n<p>Texto \u00a0inicial del art\u00edculo 5\u00ba: \u201cSesiones \u00a0ampliadas. La CSIVI realizar\u00e1, de manera peri\u00f3dica, sesiones ampliadas a \u00a0las que podr\u00e1 invitar al Consejo Nacional para la Reconciliaci\u00f3n y la \u00a0Convivencia de que trata el punto 2.2.4 del Acuerdo Final, y a cualquier \u00a0representaci\u00f3n de la sociedad civil que se convenga. \u00a0 \u00a0<\/p>\n<p>A las \u00a0reuniones de la Comisi\u00f3n de Seguimiento, Impulso y Verificaci\u00f3n a la \u00a0Implementaci\u00f3n del Acuerdo Final (CSIVI), podr\u00e1n ser invitados servidores y \u00a0representantes del Gobierno nacional, de los entes territoriales, del Consejo \u00a0Nacional de Reincorporaci\u00f3n, los voceros de las Farc-EP en el Congreso, de los \u00a0partidos pol\u00edticos, as\u00ed como cualquier miembro de la sociedad civil o de las \u00a0organizaciones sociales que se estime necesario, de acuerdo con los temas \u00a0espec\u00edficos a tratar.\u201d. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a06\u00b0. Instancia Especial para el seguimiento \u00a0al enfoque de g\u00e9nero y garant\u00eda de los derechos de las mujeres en la \u00a0implementaci\u00f3n del Acuerdo Final. Se crear\u00e1 una instancia especial \u00a0conformada por representantes de 6 organizaciones de mujeres colombianas \u00a0nacionales y territoriales que tendr\u00e1 interlocuci\u00f3n permanente con la CSIVI. \u00a0 \u00a0<\/p>\n<p>En el \u00a0marco de la CSIVI se definir\u00e1 su composici\u00f3n y funcionamiento en consulta con \u00a0las organizaciones de mujeres. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a07\u00b0. Instancia Especial de Alto Nivel \u00a0de los Pueblos \u00c9tnicos. Se crear\u00e1 una Instancia Especial de Alto Nivel \u00a0con Pueblos \u00c9tnicos para el Seguimiento de la Implementaci\u00f3n del Acuerdo Final, \u00a0que se acordar\u00e1 entre el Gobierno nacional, las Farc- EP en proceso de tr\u00e1nsito \u00a0a la vida legal, y las organizaciones representativas de los pueblos \u00e9tnicos. \u00a0La instancia tendr\u00e1 las funciones de actuar como consultora, representante e \u00a0interlocutora de primer orden de la CSIVI. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a08\u00b0. Gastos. Los Gastos que \u00a0ocasione el funcionamiento de la Comisi\u00f3n ser\u00e1n cubiertos por el Fondo de \u00a0Programas Especiales para la Paz. Estos gastos deber\u00e1n contar de manera previa \u00a0con la autorizaci\u00f3n del ordenador del gasto de dicho Fondo, quien constar\u00e1 que \u00a0correspondan a aquellos estrictamente necesarios para el cumplimiento de las \u00a0funciones de la CSIVI. \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Adicionado por el Decreto 1417 de 2018, \u00a0art\u00edculo 6\u00ba. La financiaci\u00f3n de los gastos de funcionamiento de la Comisi\u00f3n \u00a0podr\u00e1 provenir tambi\u00e9n de cooperaci\u00f3n internacional, o de cualquier otra fuente \u00a0establecida de com\u00fan acuerdo entre las partes, o por la ley. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a09\u00b0. Duraci\u00f3n y lugar de reuni\u00f3n. \u00a0La duraci\u00f3n de la CSIVI podr\u00e1 ser hasta de 10 a\u00f1os. La Comisi\u00f3n tendr\u00e1 un \u00a0per\u00edodo de funcionamiento hasta enero de 2019, fecha a partir de la cual los \u00a0integrantes de la Comisi\u00f3n decidir\u00e1n sobre su prorroga. La CSIVI se reunir\u00e1 y \u00a0sesionar\u00e1 en Bogot\u00e1, D. C., pero inicialmente podr\u00e1 hacerlo en La Habana. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo \u00a010. El presente decreto rige a partir de la fecha de su publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese \u00a0y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en \u00a0Bogot\u00e1, D. C., a 7 de diciembre de 2016. \u00a0 \u00a0<\/p>\n<p>JUAN \u00a0MANUEL SANTOS CALDER\u00d3N \u00a0 \u00a0<\/p>\n<p>El \u00a0Director del Departamento Administrativo de la Rep\u00fablica, \u00a0 \u00a0<\/p>\n<p>Luis Guillermo V\u00e9lez Cabrera. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO \u00a01995 DE 2016 \u00a0 \u00a0\u00a0 (diciembre \u00a07) \u00a0 \u00a0 D.O. \u00a050.080, diciembre 7 de 2016 \u00a0 \u00a0 por el cual se crea la Comisi\u00f3n de Seguimiento, Impulso y Verificaci\u00f3n a \u00a0la Implementaci\u00f3n del Acuerdo Final, suscrito entre el Gobierno nacional y las \u00a0Farc-EP el 24 de noviembre de 2016. \u00a0 \u00a0 Nota: Modificado por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-50267","post","type-post","status-publish","format-standard","hentry","category-decretos-2016"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/50267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=50267"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/50267\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=50267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=50267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=50267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}