{"id":57546,"date":"2023-08-23T22:06:51","date_gmt":"2023-08-23T22:06:51","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/23\/decreto-1269-de-2023\/"},"modified":"2023-08-23T22:06:51","modified_gmt":"2023-08-23T22:06:51","slug":"decreto-1269-de-2023","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2023\/08\/23\/decreto-1269-de-2023\/","title":{"rendered":"DECRETO 1269 DE 2023"},"content":{"rendered":"\n<p>DECRETO \u00a01269 DE 2023 \u00a0 \u00a0\u00a0<\/p>\n<p>(julio 31) \u00a0 \u00a0<\/p>\n<p>D.O. 52.473, julio 31 de 2023 \u00a0 \u00a0<\/p>\n<p>por el cual se adoptan medidas \u00a0en el Sector Educaci\u00f3n, en el marco del Estado de Emergencia Econ\u00f3mica, Social \u00a0y Ecol\u00f3gica declarado en el departamento de La Guajira. \u00a0 \u00a0<\/p>\n<p>El Presidente de la Rep\u00fablica \u00a0de Colombia, en ejercicio de las facultades constitucionales y legales, en \u00a0especial las conferidas por el art\u00edculo 215 de la Constituci\u00f3n Pol\u00edtica, \u00a0en concordancia con la Ley 137 de 1994 y en \u00a0desarrollo del Decreto \u00a01085 del 2 de julio de 2023, \u201cpor el cual se declara el Estado de \u00a0Emergencia Econ\u00f3mica, Social y Ecol\u00f3gica en el departamento de La Guajira\u201d, \u00a0y \u00a0 \u00a0<\/p>\n<p>CONSIDERANDO: \u00a0 \u00a0<\/p>\n<p>Que en los t\u00e9rminos del \u00a0art\u00edculo 215 de la Constituci\u00f3n Pol\u00edtica, \u00a0el presidente de la Rep\u00fablica con la firma de todos los ministros, en caso de \u00a0que sobrevengan hechos distintos de los previstos en los art\u00edculos 212 y 213 de la Constituci\u00f3n Pol\u00edtica, \u00a0que perturben o amenacen perturbar en forma grave e inminente el orden \u00a0econ\u00f3mico, social y ecol\u00f3gico del pa\u00eds, o que constituyan grave calamidad \u00a0p\u00fablica, podr\u00e1 declarar el Estado de Emergencia Econ\u00f3mica, Social y Ecol\u00f3gica. \u00a0 \u00a0<\/p>\n<p>Que, seg\u00fan la misma norma \u00a0constitucional, una vez declarado el estado de Emergencia Econ\u00f3mica, Social y \u00a0Ecol\u00f3gica, el presidente, con la firma de todos los ministros, podr\u00e1 dictar \u00a0decretos con fuerza de ley destinados exclusivamente a conjurar la crisis y a \u00a0impedir la extensi\u00f3n de sus efectos. \u00a0 \u00a0<\/p>\n<p>Que estos decretos deber\u00e1n \u00a0referirse a materias que tengan relaci\u00f3n directa y espec\u00edfica con el estado de \u00a0Emergencia Econ\u00f3mica, Social y Ecol\u00f3gica, y podr\u00e1n, en forma transitoria, \u00a0establecer nuevos tributos o modificar los existentes. \u00a0 \u00a0<\/p>\n<p>Que mediante el Decreto \u00a01085 del 2 de julio de 2023 se declar\u00f3 el estado de emergencia econ\u00f3mica, \u00a0social y ecol\u00f3gica en el departamento de La Guajira, tanto en el \u00e1rea urbana \u00a0como en la rural, por el t\u00e9rmino de treinta (30) d\u00edas, con el fin de conjurar \u00a0la Emergencia Social, Econ\u00f3mica y Ecol\u00f3gica que afecta a esa regi\u00f3n, por causa \u00a0de la grave crisis humanitaria y el estado de cosas inconstitucional declarado \u00a0por la Corte Constitucional en Sentencia T-302 del \u00a08 de mayo de 2017, y que se estructura, fundamentalmente, en la falta de \u00a0acceso a servicios b\u00e1sicos vitales, materializada en causas m\u00faltiples, tales \u00a0como: i) la escasez de agua potable para el consumo humano; ii) la crisis \u00a0alimentaria por dificultades para el acceso f\u00edsico y econ\u00f3mico a los alimentos; \u00a0iii) los efectos del cambio clim\u00e1tico acentuado por los climas c\u00e1lido des\u00e9rtico \u00a0y c\u00e1lido \u00e1rido que predominan en el territorio y que viene afectando \u00a0profundamente las fuentes de agua; iv) la crisis energ\u00e9tica y la falta de \u00a0infraestructura el\u00e9ctrica id\u00f3nea y adecuada en especial en las zonas rurales, a \u00a0pesar de que la Guajira cuenta con el m\u00e1s alto potencial para la generaci\u00f3n de \u00a0energ\u00eda e\u00f3lica y solar del pa\u00eds; v) la baja cobertura para el acceso a los \u00a0servicios de salud, en especial en zonas rurales; vi) la baja cobertura en el \u00a0sector de educaci\u00f3n, con altos \u00edndices de deserci\u00f3n escolar, infraestructura de \u00a0baja calidad y malas condiciones laborales para los educadores; situaciones que \u00a0son m\u00e1s notorias en la zona rural, en donde las comunidades ind\u00edgenas atienden \u00a0clases en condiciones precarias, vii) as\u00ed como otros problemas de orden social, \u00a0econ\u00f3micos y pol\u00edticos que inciden en la situaci\u00f3n de emergencia humanitaria y \u00a0que se describen en el presente decreto. \u00a0 \u00a0<\/p>\n<p>Que el Decreto \u00a01085 del 2 de julio de 2023 precisa que la grave crisis humanitaria y el \u00a0estado de cosas inconstitucional que afecta al departamento de La Guajira, se \u00a0ha venido agravado de forma inusitada e irresistible, adquiriendo dimensiones \u00a0insospechadas que a futuro y corto plazo se muestran a\u00fan m\u00e1s desastrosas, \u00a0adem\u00e1s de los factores descritos, por los efectos da\u00f1inos del fen\u00f3meno del ni\u00f1o \u00a0cuyas condiciones ya est\u00e1n presentes en Colombia y que se espera que se \u00a0fortalezcan e intensifiquen gradualmente hasta el invierno del hemisferio norte \u00a02023-24. \u00a0 \u00a0<\/p>\n<p>Que en el mismo decreto \u00a0declaratorio se destaca que, si bien la honorable Corte Constitucional ha \u00a0sostenido que la declaratoria del Estado de Emergencia debe basarse en hechos \u00a0sobrevinientes que perturben o amenacen perturbar el orden econ\u00f3mico, social o \u00a0ecol\u00f3gico, la misma Corporaci\u00f3n, en la Sentencia C-386 de 2017, \u00a0reiterando lo ya expresado en la Sentencia C-135 de 2009, ha \u00a0precisado que es posible declarar un Estado de Emergencia cuando se trate de un \u00a0fen\u00f3meno que existe previamente, pero cuya agravaci\u00f3n repentina e imprevisible \u00a0justifica la declaratoria del Estado de Emergencia. As\u00ed, en la Sentencia C-135 de 2009 \u00a0explic\u00f3 la Corte que: \u201cla agravaci\u00f3n r\u00e1pida e inusitada de un fen\u00f3meno ya \u00a0existente puede tener el car\u00e1cter de sobreviniente y extraordinario por ocurrir \u00a0de manera inopinada y anormal\u201d. \u00a0 \u00a0<\/p>\n<p>Que dentro de las razones \u00a0generales tenidas en cuenta para la adopci\u00f3n de la declaratoria de emergencia \u00a0se incluyeron en el decreto, entre otras, las siguientes: \u00a0 \u00a0<\/p>\n<p>\u201cQue las medidas, planes y \u00a0programas adecuados ofrecidos por las entidades del orden nacional y \u00a0territorial, a trav\u00e9s de los mecanismos ordinarios existentes, para garantizar \u00a0el acceso a servicios b\u00e1sicos, alimentos y seguridad a las poblaciones m\u00e1s \u00a0vulnerables de La Guajira, han resultado insuficientes para contener la de por \u00a0s\u00ed ya situaci\u00f3n dram\u00e1tica para la poblaci\u00f3n vulnerable del departamento de La \u00a0Guajira (ni\u00f1os y ni\u00f1as de las comunidades ind\u00edgenas, personas mayores de edad, \u00a0mujeres en gestaci\u00f3n, entre otros)\u201d. \u00a0 \u00a0<\/p>\n<p>\u201cQue el acta de la inspecci\u00f3n realizada \u00a0por la Corte Constitucional del 17 al 25 de abril de 2023, evidencia la \u00a0persistencia y agravaci\u00f3n de un fen\u00f3meno ya existente de vulneraci\u00f3n de \u00a0derechos fundamentales, al cual est\u00e1 expuesta la poblaci\u00f3n m\u00e1s vulnerable del \u00a0departamento de La Guajira y el cual no ha podido ni puede ser conjurado a \u00a0trav\u00e9s de las potestades ordinarias de que goza el Gobierno nacional, siendo \u00a0necesario acudir al mecanismo contemplado en el art\u00edculo 215 de la Constituci\u00f3n Pol\u00edtica, \u00a0adem\u00e1s que se trata de situaciones diferentes a las que se refieren los \u00a0art\u00edculos 212 y 213 de la Constituci\u00f3n Pol\u00edtica\u201d. \u00a0 \u00a0<\/p>\n<p>\u201cQue de la mano con los \u00a0programas de seguridad alimentaria con enfoque diferencial que se requieren en \u00a0el departamento de La Guajira, tambi\u00e9n es indispensable acelerar el \u00a0mejoramiento de la cobertura y calidad de la educaci\u00f3n y en particular de la \u00a0etnoeducaci\u00f3n. Tal y como se ha explicado por el Observatorio de Educaci\u00f3n del \u00a0Caribe Colombiano de la Universidad del Norte, en el informe \u201cuna mirada a la \u00a0educaci\u00f3n en el departamento de la Guajira\u201d, del a\u00f1o 2022, los bajos niveles de \u00a0cobertura en educaci\u00f3n en La Guajira, se explican por el alto porcentaje de \u00a0poblaci\u00f3n ind\u00edgena all\u00ed existente, la cual durante muchos a\u00f1os ha sido excluida \u00a0sistem\u00e1ticamente de la participaci\u00f3n en la vida del departamento y la naci\u00f3n\u201d. \u00a0 \u00a0<\/p>\n<p>\u201cQue, contar con una adecuada \u00a0infraestructura, recursos suficientes y focalizados, herramientas tecnol\u00f3gicas, \u00a0transporte escolar, educadores suficientes y debidamente formados de acuerdo \u00a0con los requerimientos \u00e9tnicos diversos, son enfoques que \u00a0propenden por un aprendizaje adecuado y competitivo, en particular, para la \u00a0poblaci\u00f3n que reside en zonas rurales de dif\u00edcil acceso del departamento de La \u00a0Guajira; siendo necesario acelerar y reforzar los programas de gobierno \u00a0dispuestos para el efecto. Se suma a lo dicho mejorar las pol\u00edticas dirigidas a \u00a0lograr una alimentaci\u00f3n escolar sana y suficiente que resulta de mayor \u00a0importancia para los educandos, siendo tales aspectos los que incidan en lograr \u00a0niveles de calidad en la ense\u00f1anza y el aprendizaje\u201d. \u00a0 \u00a0<\/p>\n<p>\u201cQue el 16 de junio de 2023, la \u00a0Comisi\u00f3n Intersectorial de Seguridad Alimentaria y Nutricional (CISAN), con la \u00a0participaci\u00f3n del Ministerio de Agricultura y Desarrollo Rural, el Ministro de \u00a0Salud y Protecci\u00f3n Social, Ministerio de Educaci\u00f3n Nacional, Ministerio de \u00a0Ambiente y Desarrollo Sostenible, Ministerio de Vivienda, Ciudad y Territorio, \u00a0el Departamento Nacional de Planeaci\u00f3n, el Departamento Administrativo de la \u00a0Presidencia de la Rep\u00fablica, el Departamento Administrativo para la Prosperidad \u00a0Social (DPS), el Instituto Colombiano de Bienestar Familiar (ICBF), estableci\u00f3 \u00a0como recomendaci\u00f3n hacer (&#8230;) un llamado desde la CISAN de una declaraci\u00f3n de \u00a0emergencia para La Guajira\u201d. \u00a0 \u00a0<\/p>\n<p>\u201cQue no obstante las m\u00faltiples \u00a0acciones adelantadas por autoridades locales del departamento de La Guajira y \u00a0por el Gobierno nacional, el cat\u00e1logo de medidas ofrecidas por la legislaci\u00f3n \u00a0ordinaria ha resultado insuficientes para enfrentar la crisis humanitaria que \u00a0sufre el departamento y para conjurarla. Y muy por el contrario la crisis \u00a0humanitaria se ha venido agravando de forma inusitada e inopinada, resultando \u00a0imposible para el Gobierno nacional darle el manejo que corresponde a trav\u00e9s de \u00a0los mecanismos ordinarios existentes, por cuanto se trata de mecanismos, en su \u00a0mayor\u00eda de orden administrativo, que no permiten enfrentar, con celeridad e \u00a0inmediatez, una crisis de las dimensiones que viene afectando al departamento \u00a0de La Guajira. Esta crisis humanitaria, si bien se proyecta sobre gran parte de \u00a0la poblaci\u00f3n, afecta excesivamente, de forma grave y sostenida, los derechos \u00a0fundamentales y sociales de la poblaci\u00f3n m\u00e1s vulnerable del departamento, en \u00a0particular de los ni\u00f1os y ni\u00f1as, mujeres gestantes y de la poblaci\u00f3n mayor adulta\u201d. \u00a0 \u00a0<\/p>\n<p>\u201cQue, en consecuencia, es \u00a0necesario, adecuado y proporcional acudir al fortalecimiento de los mecanismos \u00a0que garanticen la supervivencia de las personas afectadas, y que est\u00e1n \u00a0sufriendo graves perjuicios en el ejercicio de sus derechos, con el fin de \u00a0ofrecerles alternativas para llevar una vida digna mientras se resuelven de \u00a0manera definitiva sus necesidades b\u00e1sicas y, a m\u00e1s mediano y largo plazo en la \u00a0medida de lo posible la superaci\u00f3n de la emergencia, en los siguientes \u00a0sectores:\u201d. \u00a0 \u00a0<\/p>\n<p>\u201ce) Sector educaci\u00f3n \u00a0 \u00a0<\/p>\n<p>Que, con el fin de optimizar la \u00a0prestaci\u00f3n del servicio educativo, frente a la grave crisis humanitaria en La \u00a0Guajira, se considera necesario adoptar medidas de orden legislativo que \u00a0permitan acelerar el mejoramiento de la cobertura y calidad del aprendizaje y \u00a0en particular de la etnoeducaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Que el Gobierno analizar\u00e1 las \u00a0pol\u00edticas y programas relacionados con infraestructura, recursos e inversi\u00f3n, \u00a0alimentaci\u00f3n, agua potable, herramientas tecnol\u00f3gicas, transporte escolar, \u00a0calidad y cantidad de educadores con enfoque diferencial, con el fin de \u00a0determinar el alcance de las medidas que en el sector deben adoptarse para \u00a0contribuir a superar la situaci\u00f3n de crisis. \u00a0 \u00a0<\/p>\n<p>Que, adicionalmente, el \u00a0mejoramiento del servicio educativo de que trata el p\u00e1rrafo anterior puede \u00a0generar la adopci\u00f3n de otras medidas inherentes y necesarias para garantizar su \u00a0oportuna y adecuada prestaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Que a partir de este escenario \u00a0se hace imperativo adoptar medidas en el territorio para ampliar la prestaci\u00f3n \u00a0del servicio del Programa de Alimentaci\u00f3n Escolar, incluso durante el receso \u00a0acad\u00e9mico, como mecanismo movilizador inmediato que contribuye en el bienestar, \u00a0la permanencia y la seguridad alimentaria de los ni\u00f1os, ni\u00f1as, adolescentes y \u00a0j\u00f3venes, matriculados en el sistema educativo oficial\u201d. \u00a0 \u00a0<\/p>\n<p>Que desde el Sector Educaci\u00f3n, \u00a0a trav\u00e9s de la estrategia de alimentaci\u00f3n escolar, se contribuye en gran medida \u00a0a contrarrestar la grave situaci\u00f3n que enfrenta la ni\u00f1ez en el departamento de \u00a0La Guajira, la cual, conforme se se\u00f1ala en el Decreto 1085 de 2023, \u00a0muestra el siguiente panorama: \u00a0 \u00a0<\/p>\n<p>\u201cQue el an\u00e1lisis de la carga de \u00a0mortalidad en menores de cinco a\u00f1os para el periodo 2017-2022 muestra que del \u00a0total de muertes por desnutrici\u00f3n que se presentaron en el pa\u00eds (n=1935), el \u00a022,5% (n=435) ocurri\u00f3 en el departamento de La Guajira. Con respecto a \u00a0Infecci\u00f3n Respiratoria Aguda (IRA) del total de muertes en el pa\u00eds (n=2.862) el \u00a07,5% (n=216) se present\u00f3 en La Guajira y para Enfermedad Diarreica de las 1.052 \u00a0muertes del pa\u00eds, en La Guajira ocurrieron 178 muertes que equivale al 16,9%\u201d. \u00a0 \u00a0<\/p>\n<p>\u201cQue el Instituto Colombiano de \u00a0Bienestar Familiar (ICBF), indic\u00f3 que el seguimiento nutricional realizado a \u00a0ni\u00f1os y ni\u00f1as menores de 5 a\u00f1os atendidos por el Instituto, en el primer \u00a0trimestre de 2023, en servicios de educaci\u00f3n inicial se identificaron 2095 \u00a0ni\u00f1os y ni\u00f1as en riesgo de desnutrici\u00f3n y 177 con desnutrici\u00f3n aguda. En el \u00a0mismo per\u00edodo, al analizar los usuarios atendidos en la estrategia de atenci\u00f3n \u00a0y prevenci\u00f3n de la desnutrici\u00f3n del ICBF, se report\u00f3 la atenci\u00f3n a 1.748 ni\u00f1os \u00a0y ni\u00f1as en riesgo de desnutrici\u00f3n y a 69 con desnutrici\u00f3n aguda\u201d. \u00a0 \u00a0<\/p>\n<p>\u201cQue el Departamento \u00a0Administrativo para la Prosperidad Social (DPS) se\u00f1al\u00f3 que, de acuerdo con lo \u00a0expuesto en detalle por el ICBF, para junio del 2023 persisten las muertes de \u00a0ni\u00f1os y ni\u00f1as menores de 5 a\u00f1os por causas asociadas a la desnutrici\u00f3n en el \u00a0departamento de La Guajira; existe una tendencia hacia el aumento de la tasa de \u00a0mortalidad por desnutrici\u00f3n de dicha poblaci\u00f3n y de la detecci\u00f3n del riesgo de \u00a0desnutrici\u00f3n o desnutrici\u00f3n aguda, lo cual genera una situaci\u00f3n grave e \u00a0insostenible en detrimento del inter\u00e9s superior de los ni\u00f1os y ni\u00f1as de La \u00a0Guajira\u201d. \u00a0 \u00a0<\/p>\n<p>Que el Sector Educaci\u00f3n se \u00a0encuentra liderado por el Ministerio de Educaci\u00f3n Nacional, y dentro de sus \u00a0entidades adscritas se encuentra, entre otras, la Unidad Administrativa \u00a0Especial de Alimentaci\u00f3n Escolar-Alimentos para Aprender (UApA), creada en \u00a0virtud de lo dispuesto en el art\u00edculo 189 de la Ley 1955 de 2019, y \u00a0que cuenta con autonom\u00eda administrativa, personer\u00eda jur\u00eddica y patrimonio \u00a0independiente. \u00a0 \u00a0<\/p>\n<p>Que de acuerdo con la Ley 1955 de 2019, \u00a0art\u00edculo 189, y el Decreto 218 de 2020, \u00a0la Unidad Administrativa Especial de Alimentaci\u00f3n Escolar-Alimentos para \u00a0Aprender (UApA) tiene dentro de sus objetivos fijar y desarrollar la pol\u00edtica \u00a0en materia de alimentaci\u00f3n escolar y, respecto del Programa de Alimentaci\u00f3n \u00a0Escolar (PAE), debe (i) fortalecer los esquemas de financiaci\u00f3n; (ii) ampliar \u00a0su cobertura y garantizar la continuidad con criterios t\u00e9cnicos de \u00a0focalizaci\u00f3n, entre otros, para que se adelante la ejecuci\u00f3n directa por parte \u00a0de las entidades territoriales certificadas, quienes tienen la obligaci\u00f3n de \u00a0incorporar la diversidad de costumbres alimentarias, las condiciones de mercado \u00a0de cada regi\u00f3n y su contexto, y la infraestructura de las instituciones \u00a0educativas, entre otros. \u00a0 \u00a0<\/p>\n<p>Que el precitado Decreto 218 de 2020, \u00a0mediante el cual se adopt\u00f3 la estructura interna y la planta de personal y se \u00a0fijaron las funciones de la Unidad Administrativa Especial de Alimentaci\u00f3n \u00a0Escolar-Alimentos para Aprender, establece dentro de sus funciones la de (i) \u201cGestionar \u00a0los recursos y adelantar las acciones para fortalecer la financiaci\u00f3n del \u00a0Programa de Alimentaci\u00f3n Escolar en todo el territorio nacional y ampliar su \u00a0cobertura (&#8230;)\u201d, (ii) \u201cDistribuir a las entidades territoriales, los recursos \u00a0del Presupuesto General de la Naci\u00f3n destinados a cofinanciar la operaci\u00f3n del \u00a0Programa de Alimentaci\u00f3n Escolar, atendiendo los criterios de focalizaci\u00f3n que \u00a0fije el Consejo Directivo\u201d y (iii) \u201cHacer seguimiento a la ejecuci\u00f3n de los \u00a0recursos asignados para el desarrollo del programa de Alimentaci\u00f3n Escolar\u201d. \u00a0 \u00a0<\/p>\n<p>Que las entidades territoriales \u00a0certificadas, de conformidad con lo establecido en la Ley 715 de 2001, \u00a0tienen la competencia de administrar el servicio educativo en su jurisdicci\u00f3n, \u00a0garantizando su adecuada prestaci\u00f3n en condiciones de cobertura, calidad y \u00a0eficiencia. \u00a0 \u00a0<\/p>\n<p>Que la Unidad Administrativa \u00a0Especial de Alimentaci\u00f3n Escolar-Alimentos para Aprender-asigna recursos en el \u00a0departamento de La Guajira a cuatro (4) Entidades Territoriales Certificadas en \u00a0Educaci\u00f3n (ETC), como son: el departamento de La Guajira, Maicao, Uribia y \u00a0Riohacha para cofinanciar el PAE y estas, a su vez, adelantan los tr\u00e1mites \u00a0internos para garantizar el Programa en sus territorios; en el caso de La \u00a0Guajira, el Gobierno nacional cofinancia mayoritariamente la operaci\u00f3n del \u00a0Programa. \u00a0 \u00a0<\/p>\n<p>Que mediante la Ley 2299 \u00a0del 10 de julio de 2023, se adiciona y efect\u00faan unas modificaciones al \u00a0Presupuesto General de la Naci\u00f3n para la vigencia fiscal 2023, adicionando para \u00a0la Secci\u00f3n: 2246 de la Unidad Administrativa Especial de Alimentaci\u00f3n Escolar \u00a0la suma de $250.000.000.000 correspondiente a adici\u00f3n de inversi\u00f3n \u00a02201-Programa \u201cCalidad, Cobertura y Fortalecimiento de la educaci\u00f3n oficial, \u00a0preescolar, b\u00e1sica y media. En tal virtud, a efectos de que se incorporen los \u00a0recursos en los presupuestos de las entidades territoriales, es necesario \u00a0agotar los tr\u00e1mites de que trata la normativa que m\u00e1s adelante se relaciona. \u00a0As\u00ed mismo, mediante el Decreto \u00a01234 del 25 de julio de 2023 se liquid\u00f3 la Ley 2299 \u00a0del 10 de julio de 2023, que adiciona y efect\u00faa unas modificaciones al \u00a0Presupuesto General de la Naci\u00f3n de la vigencia fiscal 2023. \u00a0 \u00a0<\/p>\n<p>Que le corresponde a la Unidad \u00a0Administrativa Especial de Alimentaci\u00f3n Escolar en el marco de sus \u00a0competencias, efectuar la distribuci\u00f3n y asignaci\u00f3n de recursos que cofinancien \u00a0el PAE en el territorio, correspondi\u00e9ndole contribuir a cofinanciar el PAE en \u00a0las ETC de La Guajira (departamento), Uribia, Riohacha y Maicao. \u00a0 \u00a0<\/p>\n<p>Que el Decreto 111 de 1996 \u00a0\u201cPor el cual se compila la Ley 38 de 1989, la Ley 179 de 1994 y la Ley 225 de 1995 que \u00a0conforman el Estatuto Org\u00e1nico del Presupuesto\u201d, normativa presupuestal \u00a0aplicable seg\u00fan lo establecido en el art\u00edculo 109 del precitado decreto, ha \u00a0dispuesto una serie de requisitos para ejecutar los recursos por parte de las \u00a0entidades territoriales, dentro de los cuales se encuentra la incorporaci\u00f3n de \u00a0estos al presupuesto de la correspondiente entidad, generando para los \u00a0gobernadores y alcaldes una actuaci\u00f3n o actividad administrativa de acudir a \u00a0las asambleas departamentales y a los concejos distritales o municipales para \u00a0atender tal exigencia, lo que demanda atender t\u00e9rminos propios de estos \u00f3rganos \u00a0colegiados, los cuales, de acuerdo a la programaci\u00f3n de sus sesiones tienen la \u00a0posibilidad de definir los temas que se tratan a su interior o pueden \u00a0simplemente no aprobar la propuesta de presupuesto. Dentro de los estatutos \u00a0municipales, por ejemplo, se establece la necesidad de que el anteproyecto de \u00a0presupuesto sea presentado al \u00f3rgano deliberativo correspondiente, como el \u00a0concejo municipal o la asamblea departamental, para que se discuta y se apruebe \u00a0el presupuesto para su ejecuci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Que, de acuerdo con lo \u00a0anterior, para adicionar recursos al presupuesto, cualquiera sea su \u00a0procedencia, se debe considerar lo siguiente: 1) La adici\u00f3n se har\u00e1 conforme a \u00a0lo establecido en la norma org\u00e1nica presupuestal de la entidad territorial la \u00a0cual no debe diferir sustancialmente de lo contemplado al respecto en los \u00a0art\u00edculos 81 y 82 del Decreto 111 de 1996. \u00a02) Para adicionar el recurso al presupuesto, el contador municipal debe \u00a0certificar que el mismo est\u00e1 disponible en la caja, es decir que el recurso se \u00a0incorpora al presupuesto una vez recibido por parte de la entidad territorial y \u00a0no antes. \u00a0 \u00a0<\/p>\n<p>3) La facultad para efectuar la \u00a0adici\u00f3n es de la corporaci\u00f3n administrativa a iniciativa del Ejecutivo; esto \u00a0significa que, en principio, el Ejecutivo no puede hacer directamente la \u00a0adici\u00f3n de recursos al presupuesto. 4) El Ejecutivo puede adicionar recursos al \u00a0presupuesto directamente (mediante decreto) \u00fanicamente si el concejo le otorga \u00a0facultades precisas y pro tempere para ello. 5) El recurso puede ingresar a las \u00a0cuentas del departamento y\/o municipio antes que al presupuesto, es decir que \u00a0no hay obligatoriedad de adicionar el recurso inmediatamente es recibido; no \u00a0obstante, para efectuar compromisos con cargo a dichos recursos los mismos se \u00a0deben incorporar al presupuesto, en otras palabras el recurso se puede recibir \u00a0sin que previamente se haya incorporado al presupuesto, pero no se puede \u00a0ejecutar (comprometer) sin que est\u00e9 presupuestado. \u00a0 \u00a0<\/p>\n<p>Que de acuerdo a lo \u00a0anteriormente enunciado, se ha, identificado que en los tr\u00e1mites presupuestales \u00a0en el orden territorial existen limitaciones de tipo administrativo que impiden \u00a0la asignaci\u00f3n oportuna, eficiente y urgente de los recursos, por lo que es \u00a0necesario adoptar medidas que las superen y permitan materializar de forma \u00a0oportuna y eficiente la atenci\u00f3n y prestaci\u00f3n del Programa de Alimentaci\u00f3n \u00a0Escolar (PAE) y contribuir a la garant\u00eda del derecho humano a la alimentaci\u00f3n \u00a0de los ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes vinculados al sistema educativo \u00a0oficial. \u00a0 \u00a0<\/p>\n<p>Que la Corte Constitucional en \u00a0Sentencia C-434 \u00a0del 12 de julio de 2017, en la cual efectu\u00f3 la revisi\u00f3n constitucional del Decreto \u00a0Legislativo 733 de 2017, se\u00f1al\u00f3: \u201cLa Constituci\u00f3n establece, como regla \u00a0general, que no se podr\u00e1 hacer erogaci\u00f3n o gasto alguno con cargo al tesoro \u00a0p\u00fablico, ni trasferir cr\u00e9ditos que no se hallen incluidos en el presupuesto de \u00a0gastos decretados por el Congreso, \u201cpor las asambleas departamentales, o por \u00a0los concejos distritales o municipales (art. 345 C. P.) As\u00ed mismo, de manera espec\u00edfica, \u00a0los art\u00edculos 346 y 347 de la Carla Pol\u00edtica prev\u00e9n que el presupuesto de \u00a0rentas y ley de apropiaciones deber\u00e1 ser aprobado por el Congreso de la \u00a0Rep\u00fablica. [&#8230;] sin embargo, el Constituyente tambi\u00e9n hizo la salvedad de que \u00a0las citadas reglas en materia presupuestal tienen aplicaci\u00f3n en tiempos de paz \u00a0o normalidad institucional, de modo que, en estados de excepci\u00f3n, se deja \u00a0abierta la posibilidad de que otro centro de producci\u00f3n normativa y, en \u00a0espec\u00edfico, el Ejecutivo, quien en tales situaciones se convierte en legislador \u00a0transitorio, intervenga el presupuesto general de la Naci\u00f3n, cambie la \u00a0destinaci\u00f3n de algunas rentas, reasigne partidas y realice operaciones \u00a0presupuestales, con el prop\u00f3sito de destinar recursos para la superaci\u00f3n del \u00a0estado de excepci\u00f3n.\u201d. \u00a0 \u00a0<\/p>\n<p>Que ante la premura con la que \u00a0se requieren los recursos y la necesidad urgente de su ejecuci\u00f3n, la \u00a0flexibilizaci\u00f3n de los requisitos previstos en el Estatuto Org\u00e1nico del \u00a0Presupuesto (Decreto 111 de 1996) \u00a0y dem\u00e1s normas que lo adicionen o modifiquen, viene a ser una herramienta \u00a0indispensable, proporcional y adecuada para contribuir con la adopci\u00f3n de las \u00a0medidas para conjurar la crisis o impedir la extensi\u00f3n de los efectos en el \u00a0marco de la declaratoria de la Emergencia Econ\u00f3mica, Social y Ecol\u00f3gica en el \u00a0departamento de La Guajira. \u00a0 \u00a0<\/p>\n<p>Que la medida que se adopta en \u00a0el presente decreto legislativo permitir\u00e1 que no se suspenda el complemento \u00a0alimentario brindado por el Programa de Alimentaci\u00f3n Escolar (PAE) durante el \u00a0calendario escolar en las entidades territoriales certificadas en educaci\u00f3n del \u00a0departamento de La Guajira, a trav\u00e9s de la asignaci\u00f3n de recursos adicionales a \u00a0las ETC conforme al reporte de informaci\u00f3n en el Sistema Integrado de Matr\u00edcula \u00a0(SIMAT) con corte a 30 de junio de 2023, para la atenci\u00f3n de m\u00e1s de 83.684 \u00a0estudiantes por 85 d\u00edas calendario acad\u00e9mico por parte de la Secretar\u00eda de \u00a0Educaci\u00f3n Departamental, y 40.333 estudiantes por el Distrito de Riohacha \u00a0durante 85 d\u00edas de calendario acad\u00e9mico. Adicionalmente, se pretende lograr con \u00a0ello un impacto positivo con el aumento de la cobertura en m\u00e1s de 20.000 \u00a0estudiantes adicionales en las entidades territoriales de Maicao y Uribia por \u00a0lo que resta del calendario acad\u00e9mico, asegurando un complemento a m\u00e1s de \u00a0214.000 estudiantes en todo el departamento de La Guajira, adem\u00e1s de garantizar \u00a0la atenci\u00f3n con una canasta para preparar en casa en el receso escolar de fin \u00a0de a\u00f1o para cerca de 260.000 estudiantes matriculados en el departamento. \u00a0 \u00a0<\/p>\n<p>Que de conformidad con la \u00a0Sentencia T-457 \u00a0del 27 de noviembre de 2018 de la Sala Quinta de Revisi\u00f3n de la honorable \u00a0Corte Constitucional: \u201c(i) la alimentaci\u00f3n escolar es una garant\u00eda de acceso y \u00a0permanencia de los ni\u00f1os, ni\u00f1as y adolescentes en el sistema educativo, \u00a0reconocida en el marco jur\u00eddico colombiano; (ii) uno de sus principales \u00a0objetivos consiste en garantizar la asistencia a las aulas en condiciones \u00a0dignas, sin que los estudiantes se vean expuestos al hambre y la desnutrici\u00f3n \u00a0y, por ende, se evite la deserci\u00f3n escolar; igualmente, contribuye al \u00a0crecimiento y desarrollo f\u00edsico y psicol\u00f3gico adecuado; propende por el nivel \u00a0de salud m\u00e1s alto posible; potencia la atenci\u00f3n de los menores de edad para el \u00a0aprendizaje y aumenta la matr\u00edcula escolar [&#8230;]\u201d. \u00a0 \u00a0<\/p>\n<p>Que por las anteriores \u00a0motivaciones y ante la insuficiencia de las atribuciones ordinarias del \u00a0Gobierno nacional, se requiere hacer frente a las circunstancias imprevistas y \u00a0detonantes del Estado de Emergencia Econ\u00f3mica, Social y Ecol\u00f3gica en el \u00a0departamento de La Guajira, lo que obliga a adoptar medidas extraordinarias \u00a0adicionales que permitan conjurar los efectos que viene sufriendo una poblaci\u00f3n \u00a0de especial protecci\u00f3n, vulnerable como lo son los ni\u00f1os, ni\u00f1as y adolescentes \u00a0y j\u00f3venes, en especial, los vinculados al sistema educativo oficial. \u00a0 \u00a0<\/p>\n<p>En m\u00e9rito de expuesto, \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1\u00b0. Medida relacionada \u00a0con el Programa de Alimentaci\u00f3n Escolar (PAE). Con ocasi\u00f3n al estado de \u00a0Emergencia Econ\u00f3mica, Social y Ecol\u00f3gica en el departamento de La Guajira \u00a0declarado mediante el Decreto \u00a01085 del 2 de julio de 2023, se adopta como medida en relaci\u00f3n con la \u00a0ejecuci\u00f3n del Programa de Alimentaci\u00f3n Escolar (PAE), que las Entidades \u00a0Territoriales Certificadas en Educaci\u00f3n encargadas de la prestaci\u00f3n del \u00a0Programa de Alimentaci\u00f3n Escolar (PAE) en el departamento de La Guajira, \u00a0mediante acto administrativo expedido por su representante legal, podr\u00e1n \u00a0incorporar hasta el 31 de diciembre de 2023 a sus respectivos presupuestos los \u00a0recursos asignados desde el Presupuesto General de la Naci\u00f3n (PGN) para la \u00a0operaci\u00f3n y prestaci\u00f3n del servicio. \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 2\u00b0. Vigencia. El \u00a0presente decreto rige a partir de la fecha de su publicaci\u00f3n. \u00a0 \u00a0<\/p>\n<p>Publ\u00edquese y c\u00famplase. \u00a0 \u00a0<\/p>\n<p>Dado en Bogot\u00e1, D. C., a 31 de \u00a0julio de 2023. \u00a0 \u00a0<\/p>\n<p>GUSTAVO PETRO URREGO. \u00a0 \u00a0<\/p>\n<p>El Ministro del Interior, \u00a0 \u00a0<\/p>\n<p>Luis Fernando Velasco Chaves. \u00a0 \u00a0<\/p>\n<p>El Ministro de Relaciones \u00a0Exteriores, \u00a0 \u00a0<\/p>\n<p>\u00c1lvaro Leyva Dur\u00e1n. \u00a0 \u00a0<\/p>\n<p>El Ministro de Hacienda y \u00a0Cr\u00e9dito P\u00fablico, \u00a0 \u00a0<\/p>\n<p>Ricardo Bonilla Gonz\u00e1lez. \u00a0 \u00a0<\/p>\n<p>El Ministro de Justicia y del \u00a0Derecho, \u00a0 \u00a0<\/p>\n<p>N\u00e9stor Iv\u00e1n Osuna Pati\u00f1o. \u00a0 \u00a0<\/p>\n<p>El Ministro de Defensa \u00a0Nacional, \u00a0 \u00a0<\/p>\n<p>Iv\u00e1n Vel\u00e1squez G\u00f3mez. \u00a0 \u00a0<\/p>\n<p>La Ministra de Agricultura y \u00a0Desarrollo Rural, \u00a0 \u00a0<\/p>\n<p>Jhenifer Mojica Fl\u00f3rez. \u00a0 \u00a0<\/p>\n<p>El Ministro de Salud y \u00a0Protecci\u00f3n Social, \u00a0 \u00a0<\/p>\n<p>Guillermo Alfonso Jaramillo \u00a0Mart\u00ednez. \u00a0 \u00a0<\/p>\n<p>La Ministra de Trabajo, \u00a0 \u00a0<\/p>\n<p>Gloria In\u00e9s Ram\u00edrez R\u00edos. \u00a0 \u00a0<\/p>\n<p>La Ministra de Minas y Energ\u00eda, \u00a0 \u00a0<\/p>\n<p>Irene V\u00e9lez Torres. \u00a0 \u00a0<\/p>\n<p>El Ministro de Comercio, \u00a0Industria y Turismo, \u00a0 \u00a0<\/p>\n<p>Dar\u00edo Germ\u00e1n Uma\u00f1a Mendoza. \u00a0 \u00a0<\/p>\n<p>La Ministra de Educaci\u00f3n \u00a0Nacional, \u00a0 \u00a0<\/p>\n<p>Aurora Vergara Figueroa. \u00a0 \u00a0<\/p>\n<p>La Ministra de Ambiente y \u00a0Desarrollo Sostenible, \u00a0 \u00a0<\/p>\n<p>Mar\u00eda Susana Muhamad Gonz\u00e1lez. \u00a0 \u00a0<\/p>\n<p>La Ministra de Vivienda, Ciudad \u00a0y Territorio, \u00a0 \u00a0<\/p>\n<p>Martha Catalina Velasco \u00a0Campuzano. \u00a0 \u00a0<\/p>\n<p>El Ministro de Tecnolog\u00edas de \u00a0la Informaci\u00f3n y las Comunicaciones, \u00a0 \u00a0<\/p>\n<p>\u00d3scar Mauricio Lizcano Arango. \u00a0 \u00a0<\/p>\n<p>La Ministra de Transporte (e), \u00a0 \u00a0<\/p>\n<p>Mar\u00eda Constanza Garc\u00eda \u00a0Alicastro. \u00a0 \u00a0<\/p>\n<p>El Ministro de Cultura (e), \u00a0 \u00a0<\/p>\n<p>Jorge Ignacio Zorro S\u00e1nchez. \u00a0 \u00a0<\/p>\n<p>La Ministra del Deporte, \u00a0 \u00a0<\/p>\n<p>Astrid Bibiana Rodr\u00edguez \u00a0Cort\u00e9s. \u00a0 \u00a0<\/p>\n<p>La Ministra de Ciencia, \u00a0Tecnolog\u00eda e Innovaci\u00f3n, \u00a0 \u00a0<\/p>\n<p>\u00c1ngela Yesenia Olaya Requene. \u00a0 \u00a0<\/p>\n<p>La Ministra de Igualdad y \u00a0Equidad, \u00a0 \u00a0<\/p>\n<p>Francia Elena M\u00e1rquez Mina. \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO \u00a01269 DE 2023 \u00a0 \u00a0\u00a0 (julio 31) \u00a0 \u00a0 D.O. 52.473, julio 31 de 2023 \u00a0 \u00a0 por el cual se adoptan medidas \u00a0en el Sector Educaci\u00f3n, en el marco del Estado de Emergencia Econ\u00f3mica, Social \u00a0y Ecol\u00f3gica declarado en el departamento de La Guajira. \u00a0 \u00a0 El Presidente de la Rep\u00fablica \u00a0de Colombia, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[],"class_list":["post-57546","post","type-post","status-publish","format-standard","hentry","category-decretos-2023"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/57546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=57546"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/57546\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=57546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=57546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=57546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}