{"id":58653,"date":"2025-08-20T12:53:57","date_gmt":"2025-08-20T17:53:57","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/?p=58653"},"modified":"2025-08-20T12:54:00","modified_gmt":"2025-08-20T17:54:00","slug":"decreto-875-de-2025","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/2025\/08\/20\/decreto-875-de-2025\/","title":{"rendered":"DECRETO 875 DE 2025"},"content":{"rendered":"\n<p>DECRETO 875 DE 2025<\/p>\n\n\n\n<p>(julio 31)<\/p>\n\n\n\n<p>D.O. 53.200, agosto 2 de 2025<\/p>\n\n\n\n<p>por el cual se adiciona la Secci\u00f3n 6 al Cap\u00edtulo 1, T\u00edtulo V, Parte 2, Libro 2 del Decreto n\u00famero 1073 de 2015 Decreto \u00danico Reglamentario del Sector Administrativo de Minas y Energ\u00eda, en relaci\u00f3n con la creaci\u00f3n del Sistema Nacional de Seguridad Minera (SNSM) contenido en el art\u00edculo 24 de la Ley 2250 de 2022.<\/p>\n\n\n\n<p>El Presidente de la Rep\u00fablica de Colombia, en uso de sus atribuciones constitucionales y legales, en particular las conferidas en el numeral 11 del art\u00edculo 189 de la Constituci\u00f3n Pol\u00edtica, el art\u00edculo 43 de la Ley 489 de 1998, el par\u00e1grafo 2\u00b0 del art\u00edculo 24 de la Ley 2250 de 2022, y<\/p>\n\n\n\n<p>CONSIDERANDO:<\/p>\n\n\n\n<p>Que la Ley 2250 del 11 de julio de 2022, \u201cpor medio de la cual se establece un marco jur\u00eddico especial en materia de Legalizaci\u00f3n y Formalizaci\u00f3n Minera, as\u00ed como para su financiamiento, comercializaci\u00f3n y se establece una normatividad especial en materia ambiental\u201d, en su art\u00edculo 24 dispuso la creaci\u00f3n del Sistema Nacional de Seguridad Minera (SNSM), con el objetivo de fortalecer la seguridad minera en el territorio nacional.<\/p>\n\n\n\n<p>Que el art\u00edculo 24 de la referida ley establece que, en el marco del citado Sistema y a trav\u00e9s de la Comisi\u00f3n Nacional de Seguridad Minera (CNSM), se articular\u00e1 y coordinar\u00e1 con el Sistema Nacional de Gesti\u00f3n del Riesgo de Desastres y los dem\u00e1s sistemas, \u00f3rganos e instancias relacionadas con seguridad minera, la elaboraci\u00f3n, implementaci\u00f3n y seguimiento de la Agenda Nacional de Seguridad Minera. As\u00ed mismo, determin\u00f3 que las distintas instancias regionales, departamentales y territoriales de los sistemas que se coordinan con la Comisi\u00f3n Nacional, se articular\u00e1n con las Comisiones Regionales de Seguridad Minera (CRSM), con el objetivo de fortalecer la seguridad minera.<\/p>\n\n\n\n<p>Que el citado precepto establece que las Comisiones Regionales promover\u00e1n la implementaci\u00f3n de la Agenda Regional Seguridad Minera, la cual se articular\u00e1 con la Agenda Nacional, en el marco del Sistema Nacional de Seguridad Minera (SNSM).<\/p>\n\n\n\n<p>Que el par\u00e1grafo 2\u00b0 del citado art\u00edculo 24 establece que el Gobierno nacional reglamentar\u00e1 la organizaci\u00f3n, articulaci\u00f3n y funcionamiento del Sistema Nacional de Seguridad Minera (SNSM), y se\u00f1ala adem\u00e1s que, las erogaciones que se causen con ocasi\u00f3n de la implementaci\u00f3n y ejecuci\u00f3n del Sistema deber\u00e1n consultar la situaci\u00f3n fiscal de la naci\u00f3n, la disponibilidad de recursos y ajustarse al Marco Fiscal de Mediano Plazo y dem\u00e1s normas org\u00e1nicas de Presupuesto.<\/p>\n\n\n\n<p>Que se hace necesario reglamentar el Sistema Nacional de Seguridad Minera (SNSM), para garantizar su adecuada implementaci\u00f3n, de conformidad con los principios constitucionales y del derecho administrativo y por lo tanto, se requiere expedir el acto administrativo que defina la organizaci\u00f3n, articulaci\u00f3n y funcionamiento del Sistema Nacional de Seguridad Minera (SNSM), tal como lo establece el art\u00edculo 24 de la Ley 2250 del 2022, con el fin de permitir el desarrollo de acciones dirigidas a la reducci\u00f3n de la alta siniestralidad que se presenta en el territorio nacional en el sector minero.<\/p>\n\n\n\n<p>Que en aplicaci\u00f3n de los principios de coordinaci\u00f3n y articulaci\u00f3n, se concert\u00f3 de manera especial con la Unidad Nacional para la Gesti\u00f3n del Riesgo de Desastres y se adelantaron mesas de trabajo con la Agencia Nacional de Miner\u00eda (ANM) y el Ministerio del Trabajo, encaminadas a la construcci\u00f3n participativa de la presente reglamentaci\u00f3n. Lo anterior, teniendo en cuenta lo establecido en la Resoluci\u00f3n n\u00famero 3710 de 2019 del Ministerio de Trabajo \u201cpor la cual se restructuran las Comisiones Nacionales Sectoriales de Seguridad y Salud en el Trabajo, se crean otras y se dictan disposiciones generales para su funcionamiento\u201d, que desarrolla en su Cap\u00edtulo 8 la Comisi\u00f3n Nacional de Seguridad y Salud en el Trabajo del Sector Minero, cuyo organismo t\u00e9cnico y operativo tiene, entre otras funciones, \u201cBrindar apoyo al Gobierno nacional para el desarrollo normativo de la medidas de prevenci\u00f3n de riesgos laborales en el sector minero\u201d.<\/p>\n\n\n\n<p>Que, en el marco del art\u00edculo 24 de la Ley 2250 de 2022, el Sistema Nacional de Seguridad Minera deber\u00e1 estar coordinado con el Sistema Nacional de Gesti\u00f3n de Riesgos de Desastres, para lo cual se deber\u00e1 atender a lo dispuesto en el Decreto n\u00famero 2157 de 2017 que reglamenta el art\u00edculo 42 de la Ley 1523 de 2012, estableciendo el marco regulatorio dirigido a los responsables de realizar el Plan de Gesti\u00f3n del Riesgo de Desastres de las Entidades P\u00fablicas y Privadas (PGRDEPP) como mecanismo para la planeaci\u00f3n de la gesti\u00f3n del riesgo de desastres.<\/p>\n\n\n\n<p>Que en virtud de lo anterior, el Sistema Nacional de Seguridad Minera se articular\u00e1 con lo establecido en la Pol\u00edtica de Gesti\u00f3n del Riesgo de Desastres para el Sector Minero Energ\u00e9tico adoptada mediante Resoluci\u00f3n n\u00famero 40411 de 2021 y que tiene por objeto: \u201cFortalecer las actividades del SME mediante el desarrollo de los procesos de conocimientos, reducci\u00f3n del riesgo y manejo de desastres, as\u00ed como incorporar aspectos de gobernanza para la GRO en el sector, promoviendo la sostenibilidad, confiabilidad, resiliencia y competitividad del sector y de los territorios donde se ubica\u201d (sic).<\/p>\n\n\n\n<p>Que en cumplimiento de lo dispuesto por el numeral 8 del art\u00edculo 8\u00b0 de la Ley 1437 de 2011, en concordancia con lo se\u00f1alado en el art\u00edculo 2.1.2.1.14 del Decreto n\u00famero 1081 de 2015, el presente acto administrativo se public\u00f3 en la p\u00e1gina web del Ministerio de Minas y Energ\u00eda, en tres oportunidades, desde el 8 de junio hasta el 23 de junio de 2023, desde el 20 de noviembre hasta el 23 de noviembre de 2023 y desde el 2 hasta el 20 de diciembre de 2024 y los comentarios recibidos fueron analizados y resueltos en la matriz establecida para el efecto, e incorporados en el presente decreto en lo que se consider\u00f3 pertinente.<\/p>\n\n\n\n<p>Que, con base en lo establecido en el art\u00edculo 2.2.2.30.5. del Decreto n\u00famero 1074 de 2015, la Direcci\u00f3n de Formalizaci\u00f3n Minera del Ministerio de Minas y Energ\u00eda respondi\u00f3 el cuestionario establecido por la Superintendencia de Industria y Comercio (SIC) para efectos de evaluar la incidencia de las medidas a adoptar en la libre competencia de los mercados, concluyendo la no afectaci\u00f3n en este aspecto.<\/p>\n\n\n\n<p>Que, en m\u00e9rito de lo expuesto,<\/p>\n\n\n\n<p>DECRETA:<\/p>\n\n\n\n<p>Art\u00edculo 1\u00b0. Objeto. Adicionar la Secci\u00f3n 6 al Cap\u00edtulo 1, Titulo V, Parte 2, Libro 2 del Decreto n\u00famero 1073 de 2015 Decreto \u00danico Reglamentario del Sector Administrativo de Minas y Energ\u00eda, en relaci\u00f3n con la creaci\u00f3n del Sistema Nacional de Seguridad Minera (SNSM) contenido en el art\u00edculo 24 de la Ley 2250 de 2022, as\u00ed:<\/p>\n\n\n\n<p>SECCI\u00d3N 6<\/p>\n\n\n\n<p>SISTEMA NACIONAL DE SEGURIDAD MINERA (SNSM).<\/p>\n\n\n\n<p>SUBSECCI\u00d3N 6.1<\/p>\n\n\n\n<p>GENERALIDADES DEL SISTEMA NACIONAL DE SEGURIDAD MINERA.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.1.1. Sistema Nacional de Seguridad Minera (SNSM). El Sistema Nacional de Seguridad Minera (SNSM) es el conjunto de pol\u00edticas, instrumentos, componentes, procesos y proyectos, enfocados a fortalecer la seguridad minera en el territorio nacional. Este Sistema lo conforman:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El conjunto de entidades p\u00fablicas cuyas competencias est\u00e9n relacionadas con el dise\u00f1o, implementaci\u00f3n, seguimiento, fiscalizaci\u00f3n y control de las actividades asociadas a la seguridad minera.<\/li>\n\n\n\n<li>Las compa\u00f1\u00edas y\/o empresas cuyo objeto este orientado a la gesti\u00f3n, control, prevenci\u00f3n y protecci\u00f3n en el \u00e1mbito de seguridad minera, as\u00ed como la academia, podr\u00e1n asesorar en el desarrollo de estrategias, generaci\u00f3n y suministro de informaci\u00f3n para la toma de decisiones de pol\u00edtica relacionadas con la seguridad en el sector minero.<\/li>\n\n\n\n<li>Los titulares y los dem\u00e1s explotadores mineros autorizados, as\u00ed como los beneficiarios de las Autorizaciones Temporales, que son la poblaci\u00f3n objeto llamada a actuar con precauci\u00f3n, responsabilidad, autoconservaci\u00f3n y autoprotecci\u00f3n en el desarrollo de sus labores bajo lo dispuesto en la normativa vigente.<\/li>\n<\/ol>\n\n\n\n<p>Par\u00e1grafo. El Ministerio de Minas y Energ\u00eda, en su rol de coordinaci\u00f3n liderar\u00e1 las acciones necesarias para el cabal desarrollo y funcionamiento del Sistema Nacional de Seguridad Minera (SNSM).<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.1.2 Objeto del Sistema Nacional de Seguridad Minera (SNSM). El Sistema Nacional de Seguridad Minera (SNSM) coordinar\u00e1 y articular\u00e1 interinstitucionalmente a las entidades p\u00fablicas del orden nacional y territorial, a trav\u00e9s de estrategias encaminadas a fortalecer la seguridad minera en el territorio nacional.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.1.3. Objetivos del Sistema Nacional de Seguridad Minera (SNSM). Son objetivos del Sistema Nacional de Seguridad Minera (SNSM), los siguientes:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Articular las instancias del Sistema Nacional de Seguridad Minera (SNSM) con el prop\u00f3sito de hacer seguimiento a las acciones contempladas en la Pol\u00edtica Nacional de Seguridad Minera, impactando positivamente en la reducci\u00f3n de la accidentabilidad y la enfermedad laboral en el sector minero colombiano.<\/li>\n\n\n\n<li>Fortalecer la seguridad minera en el territorio nacional mediante la identificaci\u00f3n de peligros y control de riesgos en el marco del Sistema de Gesti\u00f3n de Seguridad y Salud en el Trabajo, en concordancia con lo dispuesto por el Decreto n\u00famero 1072 de 2015.<\/li>\n\n\n\n<li>Generar espacios de coordinaci\u00f3n con los actores del Sistema para la elaboraci\u00f3n, implementaci\u00f3n y articulaci\u00f3n de las Agendas de que trata el art\u00edculo 24 de la Ley 2250 de 2022.<\/li>\n\n\n\n<li>Definir las estrategias de identificaci\u00f3n, intervenci\u00f3n y control de los peligros asociados a la actividad minera, que fortalezcan la cultura de la prevenci\u00f3n en el sector.<\/li>\n\n\n\n<li>Promover la innovaci\u00f3n, transferencia tecnol\u00f3gica, adopci\u00f3n de buenas pr\u00e1cticas y nuevas tecnolog\u00edas para el fortalecimiento de la seguridad minera a nivel nacional.<\/li>\n\n\n\n<li>Fortalecer la sistematizaci\u00f3n, optimizaci\u00f3n e intercambio de informaci\u00f3n en el sector minero, relacionada con las emergencias, incidentes, accidentes de trabajo y enfermedades laborales diagnosticadas, por parte de las entidades competentes, para identificar sus causas generadoras, lo cual servir\u00e1 de insumo para la toma de decisiones.<\/li>\n\n\n\n<li>Coordinar con el Sistema Nacional de Gesti\u00f3n del Riesgo de Desastres, la Comisi\u00f3n Nacional de Seguridad y Salud en el Trabajo del Sector Minero (CNSST), las Direcciones Territoriales del Ministerio del Trabajo y el Grupo de Seguridad y Salvamento Minero de la Agencia Nacional de Miner\u00eda (ANM) o quien haga sus veces, los procesos de gesti\u00f3n del riesgo propios de la actividad minera, la implementaci\u00f3n de mecanismos de control y el cumplimiento de los requisitos legales, as\u00ed como las dem\u00e1s acciones encaminadas al cumplimiento de los objetivos del SNSM.<\/li>\n<\/ol>\n\n\n\n<p>Los precitados objetivos son enunciativos por lo cual el Sistema Nacional de Seguridad Minera podr\u00e1 desarrollar objetivos adicionales siempre y cuando est\u00e9n enmarcados en fortalecer la seguridad minera y la cultura de la prevenci\u00f3n.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.1.4. Principios generales. El Sistema Nacional de Seguridad Minera (SNSM)se regir\u00e1 adem\u00e1s de los principios constitucionales y del derecho administrativo, por los siguientes:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Principio de seguimiento y mejora continua: Los integrantes del Sistema deben realizar seguimiento continuo a su implementaci\u00f3n y funcionamiento, propiciando el fortalecimiento en la seguridad minera y la gesti\u00f3n de los riesgos del sector minero. De igual manera, deben establecer estrategias que permitan la mejora continua del Sistema, implementando acciones dirigidas a la reducci\u00f3n de la alta siniestralidad que se presenta en el sector.<\/li>\n\n\n\n<li>Principio de innovaci\u00f3n: los actores de este Sistema crear\u00e1n servicios o procesos novedosos que permitan obtener informaci\u00f3n relevante para la toma de decisiones y la b\u00fasqueda de alternativas tecnol\u00f3gicas encaminadas a fortalecer la cultura de la prevenci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.1.5. Componentes de planificaci\u00f3n del Sistema Nacional de Seguridad Minera. Se tendr\u00e1n la Agenda Nacional de Seguridad Minera como instrumento del Gobierno nacional y la Agenda Regional de Seguridad Minera constituida por las agendas departamentales, como instrumento regional, para efectos de organizaci\u00f3n, planificaci\u00f3n y operatividad del Sistema.<\/p>\n\n\n\n<p>La agenda departamental se constituir\u00e1 con los temas que cada departamento tenga como prioridad para los asuntos de seguridad minera y se consolidar\u00e1n en la agenda regional, seg\u00fan aplique, de acuerdo con las jurisdicciones establecidas en el art\u00edculo 2.2.5.1.6.2.13. de este decreto para las Comisiones Regionales de Seguridad Minera.<\/p>\n\n\n\n<p>Estas agendas estar\u00e1n enfocadas en desarrollar, de manera coordinada, las pol\u00edticas, programas y acciones prioritarias con el prop\u00f3sito de garantizar la gesti\u00f3n de la seguridad minera en el territorio nacional o en las regiones y tendr\u00e1n entre otras l\u00edneas estrat\u00e9gicas: el fortalecimiento de buenas pr\u00e1cticas en la gesti\u00f3n del riesgo, la formulaci\u00f3n e implementaci\u00f3n de pol\u00edticas p\u00fablicas relacionadas con los aspectos de seguridad del sector minero, la optimizaci\u00f3n de la informaci\u00f3n relacionada con los indicadores de los accidentes de trabajo y la enfermedad laboral en la miner\u00eda, la promoci\u00f3n de la cultura de la prevenci\u00f3n y del trabajo seguro en el sector minero, as\u00ed como las l\u00edneas propias de cada regi\u00f3n de acuerdo con las particularidades del territorio.<\/p>\n\n\n\n<p>Par\u00e1grafo. Estas agendas ser\u00e1n revisadas y ajustadas cada cuatro (4) a\u00f1os o de manera extraordinaria cuando sea necesario y as\u00ed lo definan las respectivas comisiones.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.1.6. Informaci\u00f3n para el Sistema Nacional de Seguridad Minera. La informaci\u00f3n relacionada con los indicadores de accidentabilidad y enfermedad laboral del sector minero que las entidades p\u00fablicas desarrollan, procesan, almacenan y comunican, deber\u00e1n estar disponibles para su uso por parte del Sistema Nacional de Seguridad Minera, garantizando que su contenido est\u00e9 actualizado y sea funcional. Las entidades productoras y usuarias de la informaci\u00f3n deben garantizar la observancia de las limitaciones de acceso y uso referidas al derecho de h\u00e1beas data, privacidad, defensa jur\u00eddica del Estado y en general, todos aquellos temas a los que la ley les haya otorgado el car\u00e1cter de reserva.<\/p>\n\n\n\n<p>Par\u00e1grafo. Lo anterior, sin perjuicio que a futuro se puedan crear herramientas o sistemas que permitan la optimizaci\u00f3n de la informaci\u00f3n relacionada con la seguridad minera.<\/p>\n\n\n\n<p>SUBSECCI\u00d3N 6.2.<\/p>\n\n\n\n<p>Organizaci\u00f3n y funcionamiento del Sistema Nacional de Seguridad Minera (SNSM).<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.1. Organizaci\u00f3n General del Sistema Nacional de Seguridad Minera. El Sistema Nacional de Seguridad Minera (SNSM) contar\u00e1 con las siguientes instancias de coordinaci\u00f3n y seguimiento:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Comisi\u00f3n Nacional de Seguridad Minera (CNSM).<\/li>\n\n\n\n<li>Comit\u00e9 T\u00e9cnico.<\/li>\n\n\n\n<li>Comisiones Regionales de Seguridad Minera.<\/li>\n<\/ol>\n\n\n\n<p>Las funciones asignadas a la Comisi\u00f3n Nacional de Seguridad Minera y al comit\u00e9 o instancias que hacen parte del Sistema Nacional de Seguridad Minera, se desarrollar\u00e1n con cargo a los recursos de las entidades que los conforman, seg\u00fan el presupuesto asignado para cada vigencia fiscal.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.2. Comisi\u00f3n Nacional de Seguridad Minera (CNSM). Cr\u00e9ase la Comisi\u00f3n Nacional de Seguridad Minera (CNSM), cuyo objetivo es el direccionamiento estrat\u00e9gico y la coordinaci\u00f3n del Sistema Nacional de Seguridad Minera (SNSM). La Comisi\u00f3n tambi\u00e9n armonizar\u00e1 las pol\u00edticas relacionadas con la seguridad en el sector minero.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.3. Integrantes de la Comisi\u00f3n Nacional de Seguridad Minera (CNSM). La Comisi\u00f3n Nacional de Seguridad Minera (CNSM) ser\u00e1 presidida por el Ministro de Minas y Energ\u00eda y estar\u00e1 integrada por:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El Ministro de Minas y Energ\u00eda o su delegado.<\/li>\n\n\n\n<li>El Ministro del Trabajo o su delegado.<\/li>\n\n\n\n<li>El Ministro de Salud y la Protecci\u00f3n Social o su delegado.<\/li>\n\n\n\n<li>El Presidente de la Agencia Nacional de Miner\u00eda o su delegado.<\/li>\n\n\n\n<li>El Director de la Unidad Nacional para la Gesti\u00f3n del Riesgo de Desastres (UNGRD) o su delegado.<\/li>\n<\/ol>\n\n\n\n<p>Par\u00e1grafo. La Comisi\u00f3n podr\u00e1 invitar a sus sesiones a representantes de entidades p\u00fablicas o privadas, de los gremios del sector minero, de la Federaci\u00f3n de Aseguradores Colombianos (Fasecolda), universidades con programas de formaci\u00f3n relacionados con ciencias de la tierra y seguridad minera y a representantes de organismos nacionales e internacionales especializados, con presencia en los territorios y podr\u00e1 apoyarse con expertos cuando lo estime conveniente. El Ministro de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n o su delegado, el Presidente de la Industria Militar (Indumil) o su delegado y el Director General del Servicio Nacional de Aprendizaje SENA o su delegado ser\u00e1n invitados permanentes de la Comisi\u00f3n Nacional de Seguridad Minera.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.4. Funciones de la Comisi\u00f3n Nacional de Seguridad Minera (CNSM). Esta Comisi\u00f3n tendr\u00e1 entre otras, las siguientes funciones:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Elaborar la Agenda Nacional de Seguridad Minera.<\/li>\n\n\n\n<li>Coordinar y articular con las instancias nacionales y regionales y especialmente con el Sistema Nacional de Gesti\u00f3n del Riesgo, la ejecuci\u00f3n de estrategias, acciones y proyectos tendientes a la implementaci\u00f3n y seguimiento de la Agenda Nacional de Seguridad Minera en el territorio.<\/li>\n\n\n\n<li>Dise\u00f1ar y proponer estrategias, elementos de pol\u00edtica p\u00fablica y l\u00edneas de actuaci\u00f3n referentes a la seguridad del sector minero en el territorio nacional.<\/li>\n\n\n\n<li>Proponer la generaci\u00f3n de estrategias encaminadas a fortalecer la cultura de prevenci\u00f3n y del conocimiento de los riesgos propios de la actividad minera.<\/li>\n\n\n\n<li>Apoyar la implementaci\u00f3n de la Pol\u00edtica Nacional de Seguridad Minera en el territorio nacional.<\/li>\n\n\n\n<li>Coordinar los diferentes actores estrat\u00e9gicos del Sistema Nacional de Seguridad Minera (SNSM), en el orden nacional y regional, para plantear acciones en b\u00fasqueda de la disminuci\u00f3n de los accidentes de trabajo y la enfermedad laboral.<\/li>\n\n\n\n<li>Establecer las l\u00edneas estrat\u00e9gicas para la formulaci\u00f3n e implementaci\u00f3n de un Plan de Acci\u00f3n Anual que conduzca a la optimizaci\u00f3n de los recursos t\u00e9cnicos, humanos y econ\u00f3micos orientados a la ejecuci\u00f3n y cumplimiento de la Agenda Nacional de Seguridad Minera.<\/li>\n\n\n\n<li>Conformar y reglamentar el comit\u00e9 t\u00e9cnico para el desarrollo del referido Plan de Acci\u00f3n.<\/li>\n\n\n\n<li>Gestionar la conformaci\u00f3n de las Comisiones Regionales de Seguridad Minera (CRSM).<\/li>\n\n\n\n<li>Expedir su propio reglamento.<\/li>\n\n\n\n<li>Las dem\u00e1s que le correspondan por su naturaleza para dar cumplimiento al objeto con el que fue creada.<\/li>\n<\/ol>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.5. Sesiones. La Comisi\u00f3n Nacional de Seguridad Minera (CNSM) se reunir\u00e1 dos (2) veces al a\u00f1o en condiciones de normalidad y de manera extraordinaria cuando sea citada por la Secretar\u00eda T\u00e9cnica, de acuerdo con el reglamento interno que lo regula. Esta Comisi\u00f3n sesionar\u00e1 con m\u00e1s de la mitad de sus miembros que tienen voto y decidir\u00e1 por mayor\u00eda simple de estos.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.6. Comit\u00e9 T\u00e9cnico. Ser\u00e1 una instancia de articulaci\u00f3n dentro del Sistema Nacional de Seguridad Minera (SNSM), definido por la Comisi\u00f3n Nacional y tendr\u00e1 por objeto impulsar la ejecuci\u00f3n de pol\u00edticas, programas, proyectos y estrategias, as\u00ed como fortalecer la seguridad minera en el pa\u00eds, divulgar los resultados de los an\u00e1lisis realizados y las lecciones aprendidas. Este Comit\u00e9 considerar\u00e1, entre otros, los temas que a continuaci\u00f3n se describen:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Comportamiento de la siniestralidad y la enfermedad laboral en la actividad minera.<\/li>\n\n\n\n<li>Investigaci\u00f3n de la causalidad de incidentes, accidentes de trabajo y enfermedades laborales en la actividad minera.<\/li>\n\n\n\n<li>Generaci\u00f3n de competencias laborales, capacitaci\u00f3n y profesionalizaci\u00f3n del recurso humano vinculado a la actividad minera.<\/li>\n\n\n\n<li>An\u00e1lisis del seguimiento y control en temas de seguridad en la actividad minera.<\/li>\n\n\n\n<li>Transferencia de tecnolog\u00eda, innovaci\u00f3n y conocimiento relacionado con la seguridad y salud en el trabajo en el sector minero.<\/li>\n\n\n\n<li>Identificaci\u00f3n y generaci\u00f3n de estrategias para la gesti\u00f3n del cambio comportamental hacia la cultura de la prevenci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.7. Integrantes del Comit\u00e9 T\u00e9cnico. El Comit\u00e9 T\u00e9cnico estar\u00e1 conformado por los siguientes miembros:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Por parte del Ministerio de Minas y Energ\u00eda:<\/li>\n<\/ol>\n\n\n\n<p>a. Un delegado t\u00e9cnico minero de la Direcci\u00f3n de Formalizaci\u00f3n Minera o quien haga sus veces.<\/p>\n\n\n\n<p>b. Un delegado t\u00e9cnico minero de la Direcci\u00f3n de Miner\u00eda Empresarial o quien haga sus veces.<\/p>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li>Por parte del Ministerio del Trabajo:<\/li>\n<\/ol>\n\n\n\n<p>a. Un delegado t\u00e9cnico de la Direcci\u00f3n de Riesgos Laborales o quien haga sus veces.<\/p>\n\n\n\n<p>b. Un delegado t\u00e9cnico de la Direcci\u00f3n de Inspecci\u00f3n, vigilancia, control y gesti\u00f3n territorial o quien haga sus veces.<\/p>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>Por parte del Ministerio de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n, un delegado t\u00e9cnico del Viceministerio de Conocimiento, Innovaci\u00f3n y Productividad o quien haga sus veces.<\/li>\n\n\n\n<li>Por parte del Ministerio de Salud y Protecci\u00f3n Social, un delegado t\u00e9cnico de la Subdirecci\u00f3n de Riesgos Laborales o quien haga sus veces.<\/li>\n\n\n\n<li>Por parte de la Agencia Nacional de Miner\u00eda, o quien haga sus veces:<\/li>\n<\/ol>\n\n\n\n<p>a. Un delegado t\u00e9cnico de la Vicepresidencia de Seguimiento, Control y Seguridad Minera, o quien haga sus veces.<\/p>\n\n\n\n<p>b. Dos delegados t\u00e9cnicos del Grupo de Seguridad y Salvamento Minero, o quien haga sus veces.<\/p>\n\n\n\n<ol start=\"6\" class=\"wp-block-list\">\n<li>Por parte de la Unidad Nacional para la Gesti\u00f3n del Riego de Desastres (UNGRD) un delegado t\u00e9cnico, o quien haga sus veces.<\/li>\n\n\n\n<li>Un delegado de los Centros Especializados en formaci\u00f3n de Miner\u00eda del Servicio Nacional de Aprendizaje (SENA), o quien haga sus veces.<\/li>\n<\/ol>\n\n\n\n<p>Par\u00e1grafo. El Comit\u00e9 podr\u00e1 invitar a sus sesiones a los representantes de entidades p\u00fablicas o privadas, de los gremios del sector minero, de la Federaci\u00f3n de Aseguradores Colombianos (Fasecolda), de la academia con programas de formaci\u00f3n relacionados con ciencias de la tierra y seguridad minera, de los gremios y\/o asociaciones del sector minero y a representantes de organismos nacionales e internacionales especializados con presencia en los territorios y podr\u00e1 apoyarse con expertos cuando lo estime conveniente.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.8. Funciones del Comit\u00e9 T\u00e9cnico. El Comit\u00e9 T\u00e9cnico tendr\u00e1 las siguientes funciones:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Gestionar e implementar las estrategias, acciones y proyectos definidos en la Agenda Nacional de Seguridad Minera.<\/li>\n\n\n\n<li>Elaborar los an\u00e1lisis y documentos de car\u00e1cter t\u00e9cnico que se requieran por parte de la Comisi\u00f3n Nacional.<\/li>\n\n\n\n<li>Apoyar a la Comisi\u00f3n Nacional en el dise\u00f1o y elaboraci\u00f3n del Plan de Acci\u00f3n Anual para la implementaci\u00f3n de la Agenda Nacional de Seguridad Minera.<\/li>\n\n\n\n<li>Expedir su propio reglamento.<\/li>\n\n\n\n<li>Las dem\u00e1s asignadas por la Comisi\u00f3n Nacional de Seguridad Minera, en el marco de su objeto.<\/li>\n<\/ol>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.9. Sesiones. Con el fin de realizar seguimiento a las acciones establecidas en el Plan de Acci\u00f3n Anual, el Comit\u00e9 T\u00e9cnico se deber\u00e1 reunir cada tres (3) meses en condiciones de normalidad y de manera extraordinaria cuando sea citado por la Secretar\u00eda T\u00e9cnica, conforme con lo indicado en su reglamento interno. Este Comit\u00e9 sesionar\u00e1 con m\u00e1s de la mitad de sus miembros y decidir\u00e1 por mayor\u00eda simple.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.10. Secretar\u00eda T\u00e9cnica. La Secretar\u00eda T\u00e9cnica de la Comisi\u00f3n Nacional de Seguridad Minera (CNSM) y del Comit\u00e9 T\u00e9cnico estar\u00e1 a cargo del Ministerio de Minas y Energ\u00eda, a trav\u00e9s de la Direcci\u00f3n de Formalizaci\u00f3n Minera o quien haga sus veces, con el apoyo de la autoridad minera.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.11. Funciones de la Secretar\u00eda T\u00e9cnica. Ser\u00e1n funciones de la Secretar\u00eda T\u00e9cnica, las siguientes:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Convocar a las sesiones de la Comisi\u00f3n Nacional de Seguridad Minera y del Comit\u00e9 T\u00e9cnico.<\/li>\n\n\n\n<li>Coordinar las actividades de apoyo necesarias para adelantar las sesiones de la Comisi\u00f3n Nacional de Seguridad Minera y del Comit\u00e9 T\u00e9cnico.<\/li>\n\n\n\n<li>Recibir y dar tr\u00e1mite a las iniciativas y propuestas presentadas por los integrantes de la Comisi\u00f3n Nacional de Seguridad Minera, el Comit\u00e9 T\u00e9cnico y los invitados.<\/li>\n\n\n\n<li>Servir de enlace y brindar apoyo t\u00e9cnico, administrativo y operativo para la coordinaci\u00f3n de las entidades que integran la Comisi\u00f3n Nacional de Seguridad Minera y el Comit\u00e9 T\u00e9cnico.<\/li>\n\n\n\n<li>Elaborar y custodiar las actas y dem\u00e1s documentaci\u00f3n relacionada.<\/li>\n\n\n\n<li>Hacer seguimiento al cumplimiento de las decisiones, acuerdos y compromisos adquiridos al interior de la Comisi\u00f3n Nacional de Seguridad Minera y el Comit\u00e9 T\u00e9cnico.<\/li>\n\n\n\n<li>Las dem\u00e1s asignadas por la Comisi\u00f3n Nacional de Seguridad Minera, en el marco de su objeto.<\/li>\n<\/ol>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.12. Comisiones Regionales de Seguridad Minera (CRSM). Cr\u00e9ase estas Comisiones como instancias encargadas del direccionamiento estrat\u00e9gico y la coordinaci\u00f3n de las acciones a nivel regional del Sistema Nacional de Seguridad Minera (SNSM).<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.13. Integrantes de las Comisiones Regionales de Seguridad Minera (CRSM). Las Comisiones Regionales de Seguridad Minera (CRSM), tendr\u00e1n su jurisdicci\u00f3n alineada con la distribuci\u00f3n realizada por la Autoridad Minera en sus Puntos de Atenci\u00f3n Regional y estar\u00e1n conformadas por los siguientes miembros:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Los Gobernadores de los departamentos de la jurisdicci\u00f3n regional en donde haya actividad minera, o sus delegados.<\/li>\n\n\n\n<li>Tres delegados por jurisdicci\u00f3n regional, de los alcaldes de los municipios que presenten mayores cifras de accidentalidad en la actividad minera. Estos podr\u00e1n ser seleccionados cada dos a\u00f1os, de acuerdo con los reportes de siniestralidad que remita el Comit\u00e9 T\u00e9cnico a la Comisi\u00f3n Nacional de Seguridad.<\/li>\n\n\n\n<li>Un delegado de los Directores territoriales del Ministerio del Trabajo.<\/li>\n\n\n\n<li>Un delegado de los secretarios de salud departamental.<\/li>\n\n\n\n<li>Un delegado t\u00e9cnico minero de la Direcci\u00f3n de Formalizaci\u00f3n Minera por parte del Ministerio de Minas y Energ\u00eda o quien haga sus veces.<\/li>\n\n\n\n<li>El Coordinador del Punto de Atenci\u00f3n Regional de la Autoridad Minera o el gestor de la estaci\u00f3n o punto de apoyo de Salvamento Minero, de acuerdo con su competencia y jurisdicci\u00f3n.<\/li>\n\n\n\n<li>Un delegado de los Coordinadores departamentales de Gesti\u00f3n del Riesgo de Desastres.<\/li>\n<\/ol>\n\n\n\n<p>Par\u00e1grafo 1\u00b0. Las Comisiones Regionales de Seguridad Minera (CRSM) tendr\u00e1n autonom\u00eda para sesionar en el municipio donde consideren dentro de la regi\u00f3n y de acuerdo con las particularidades del territorio se podr\u00e1n constituir Comisiones Regionales para un solo departamento. En todo caso, en lo que respecta a la toma de decisi\u00f3n de los integrantes de que tratan los numerales 1 y 2 del presente art\u00edculo, deber\u00e1n unificar su posici\u00f3n en un solo voto; es decir, un voto por Gobernaciones y un voto por alcald\u00edas.<\/p>\n\n\n\n<p>Par\u00e1grafo 2\u00b0. Las Comisiones Regionales de Seguridad Minera (CRSM) podr\u00e1n invitar a sus sesiones a representantes de entidades p\u00fablicas o privadas, gremios y\/o asociaciones del sector minero con presencia en los territorios, academia con programas de formaci\u00f3n relacionados con ciencias de la tierra y seguridad minera y a representantes de organismos nacionales e internacionales especializados en seguridad y podr\u00e1n apoyarse con expertos cuando lo estimen conveniente. En todo caso, estas comisiones contar\u00e1n con la participaci\u00f3n permanente del Director Territorial del Servicio Nacional de Aprendizaje (SENA), o su delegado.<\/p>\n\n\n\n<p>Par\u00e1grafo 3\u00b0. Para las delegaciones de que tratan los numerales 3, 4 y 5, cada entidad, seg\u00fan sus competencias, deber\u00e1 informar por escrito la designaci\u00f3n de sus representantes, la cual se realizar\u00e1 teniendo en cuenta la experiencia, los conocimientos t\u00e9cnicos y normativos. As\u00ed mismo, la Agencia Nacional de Miner\u00eda y la Unidad Nacional para la Gesti\u00f3n del Riesgo de Desastres, deber\u00e1n hacer lo propio para los numerales 6 y 7.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.14. Funciones de las Comisiones Regionales de Seguridad Minera (CRSM).<\/p>\n\n\n\n<p>Son funciones de las Comisiones Regionales de Seguridad Minera (CRSM), las siguientes:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Elaborar, adoptar, dirigir y coordinar la implementaci\u00f3n de la Agenda Regional de Seguridad Minera en articulaci\u00f3n con la Agenda Nacional, en el marco del SNSM.<\/li>\n\n\n\n<li>Establecer un plan de acci\u00f3n anual que conduzca al logro de los objetivos trazados en la Agenda Regional de Seguridad Minera.<\/li>\n\n\n\n<li>Generar los espacios de articulaci\u00f3n y coordinaci\u00f3n a nivel regional para la implementaci\u00f3n de la Agenda Nacional de Seguridad Minera en el territorio.<\/li>\n\n\n\n<li>Articular a los diferentes actores estrat\u00e9gicos del Sistema Nacional de Seguridad Minera (SNSM), en el orden regional, para implementar acciones en b\u00fasqueda de la disminuci\u00f3n de los accidentes de trabajo y la enfermedad laboral en el sector minero.<\/li>\n\n\n\n<li>Realizar seguimiento a la implementaci\u00f3n del plan de acci\u00f3n anual y a la Agenda Regional de Seguridad Minera, generados a partir del presente decreto.<\/li>\n\n\n\n<li>Expedir su propio reglamento.<\/li>\n\n\n\n<li>Las dem\u00e1s que se requieran en el marco de su objeto.<\/li>\n<\/ol>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.15. Sesiones. Las Comisiones Regionales se reunir\u00e1n cuatro (4) veces al a\u00f1o o de acuerdo con lo que la Comisi\u00f3n de manera aut\u00f3noma considere, y extraordinariamente cuando sea necesario, conforme a lo dispuesto en el reglamento interno. Esta Comisi\u00f3n sesionar\u00e1 con m\u00e1s de la mitad de sus miembros y decidir\u00e1 por mayor\u00eda simple de estos.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.16. Secretar\u00eda t\u00e9cnica de las Comisiones Regionales de Seguridad Minera. La Secretar\u00eda T\u00e9cnica de las Comisiones Regionales de Seguridad Minera estar\u00e1 a cargo de la Agencia Nacional de Miner\u00eda o quien haga sus veces a trav\u00e9s del Punto de Atenci\u00f3n Regional respectivo o a la oficina o dependencia que la autoridad minera designe, con el apoyo del Ministerio de Minas y Energ\u00eda.<\/p>\n\n\n\n<p>Art\u00edculo 2.2.5.1.6.2.17. Funciones de las Secretar\u00edas T\u00e9cnicas de las Comisiones Regionales de Seguridad Minera (CRSM). Ser\u00e1n funciones de las Secretar\u00edas T\u00e9cnicas de la Comisiones Regionales de Seguridad Minera (CRSM), las siguientes:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Convocar a las sesiones de la Comisi\u00f3n Regional de Seguridad Minera.<\/li>\n\n\n\n<li>Coordinar las actividades de apoyo necesarias para adelantar las sesiones de la Comisi\u00f3n Regional.<\/li>\n\n\n\n<li>Recibir y dar tr\u00e1mite a las iniciativas y propuestas presentadas por los integrantes de la Comisi\u00f3n Regional de Seguridad Minera y los invitados.<\/li>\n\n\n\n<li>Servir de enlace y brindar apoyo t\u00e9cnico, administrativo y operativo para la coordinaci\u00f3n de las entidades que integran la Comisi\u00f3n Regional de Seguridad Minera.<\/li>\n\n\n\n<li>Elaborar y custodiar las actas y dem\u00e1s documentaci\u00f3n relacionada.<\/li>\n\n\n\n<li>Hacer seguimiento al cumplimiento de las decisiones, acuerdos y compromisos adquiridos al interior de la Comisi\u00f3n Regional de Seguridad Minera.<\/li>\n\n\n\n<li>Las dem\u00e1s asignadas por la Comisi\u00f3n Regional de Seguridad Minera, en el marco de su objeto.<\/li>\n<\/ol>\n\n\n\n<p>Art\u00edculo 2\u00b0. Vigencia. El presente decreto rige a partir de la fecha de su publicaci\u00f3n en el Diario Oficial.<\/p>\n\n\n\n<p>Publ\u00edquese y c\u00famplase.<\/p>\n\n\n\n<p>31 de julio de 2025.<\/p>\n\n\n\n<p>GUSTAVO PETRO URREGO<\/p>\n\n\n\n<p>El Ministro de Salud y Protecci\u00f3n Social,<\/p>\n\n\n\n<p>Guillermo Alfonso Jaramillo Mart\u00ednez.<\/p>\n\n\n\n<p>El Ministro del Trabajo,<\/p>\n\n\n\n<p>Antonio Eresmid Sanguino P\u00e1ez.<\/p>\n\n\n\n<p>El Ministro de Minas y Energ\u00eda,<\/p>\n\n\n\n<p>Edwin Palma Egea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DECRETO 875 DE 2025 (julio 31) D.O. 53.200, agosto 2 de 2025 por el cual se adiciona la Secci\u00f3n 6 al Cap\u00edtulo 1, T\u00edtulo V, Parte 2, Libro 2 del Decreto n\u00famero 1073 de 2015 Decreto \u00danico Reglamentario del Sector Administrativo de Minas y Energ\u00eda, en relaci\u00f3n con la creaci\u00f3n del Sistema Nacional de Seguridad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89],"tags":[],"class_list":["post-58653","post","type-post","status-publish","format-standard","hentry","category-decretos-2025"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/58653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/comments?post=58653"}],"version-history":[{"count":1,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/58653\/revisions"}],"predecessor-version":[{"id":58654,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/posts\/58653\/revisions\/58654"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/media?parent=58653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/categories?post=58653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/decretos\/wp-json\/wp\/v2\/tags?post=58653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}