{"id":1068,"date":"2020-11-24T19:15:17","date_gmt":"2020-11-24T19:15:17","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-996-de-2005\/"},"modified":"2020-11-24T19:15:17","modified_gmt":"2020-11-24T19:15:17","slug":"ley-996-de-2005","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-996-de-2005\/","title":{"rendered":"LEY 996 DE 2005"},"content":{"rendered":"<p>LEY 996 DE 2005            <\/a><\/p>\n<p>&nbsp;<\/p>\n<p><\/font><\/p>\n<p align=\"center\"><b><font size=\"2\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"http:\/\/dmsjuridica.com\/CODIGOS\/LEGISLACION\/LEYES\/2019\/dms.png\" width=\"138\" height=\"103\"align=\"center\"><\/font><\/p>\n<p>&nbsp;<\/font><\/p>\n<p><\/b><\/p>\n<p align=\"center\"><b><font size=\"6\">LEY 996 DE 2005<\/font><\/b><\/p>\n<p align=\"center\">(noviembre 24 DE 2005)<\/p>\n<p align=\"center\"><i>Por medio de la cual se reglamenta la elecci\u00f3n de Presidente de la Rep\u00fablica, de conformidad con el art\u00edculo <A hrefx=\"CONS_P91.htm#152\">152<\/A> literal f) de la Constituci\u00f3n Pol\u00edtica de Colombia, y de acuerdo con lo establecido en el Acto Legislativo <A hrefx=\"ACL02004.htm#1\">02<\/A> de 2004, y se dictan otras disposiciones.<\/i><\/p>\n<p><i><b>*Notas de Vigencia*<\/b><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD align=\"justify\"><i><font size=\"2\">Ley declarada EXEQUIBLE por la Corte Constitucional mediante       <b><a \"SC802_06.htm\" hrefx=\"..\/..\/Sentencias\/C-802-06.rtf\">Sentencia C-802-06<\/a><\/b> de 27 de septiembre de 2006, Magistrado Ponente Dr. Manuel Jos\u00e9 Cepeda Espinosa. &quot;La Corte debe examinar si la<b> Ley 996 de 2005 <\/b>adolece o no de un vicio de inconstitucionalidad, al haber sido sancionada por el Ministro Delegatario el mismo d\u00eda de publicaci\u00f3n del <b><a hrefx=\"..\/..\/decretos\/2005\/D4241de2005.htm\">Decreto 4241 de 2005<\/a><\/b>, mediante el cual el Presidente de la Rep\u00fablica le deleg\u00f3 tal atribuci\u00f3n.&quot;<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\">La Corte Constitucional mediante <b><a S\"C115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra, efectu\u00f3 el Control constitucional al Proyecto de Ley Estatutaria N\u00b0 216\/05 Senado, N\u00b0 235-C\u00e1mara.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\">En esta Sentencia la Corte declar\u00f3 exequible el Proyecto de Ley &quot;por haber sido expedido conforme al procedimiento constitucional previsto&quot;   <\/font>   <\/i>   <\/TD><\/TR>  <\/TABLE><DIV><\/p>\n<p align=\"justify\"><i><b><font size=\"1\">*CONCORDANCIAS*<\/font><\/b><\/i><\/p>\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\" dir=\"ltr\">\n<tr>\n<td><font face=\"Arial\"><b><a hrefx=\"..\/..\/decretos\/2012\/0734.htm\"><font size=\"1\">Decreto 734 de 2012<\/font><\/a><\/b><\/font><\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/DIV> <\/p>\n<p align=\"center\"><b>EL CONGRESO DE COLOMBIA<\/b><\/p>\n<p align=\"center\"><b>DECRETA:<\/b><\/p>\n<p align=\"center\"><b><A name=\"TITULO I\">TITULO I. <\/A><\/b><\/p>\n<p align=\"center\"><b>DISPOSICIONES GENERALES. <\/b> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><A name=1><b><font face=\"Arial\">A<\/font><font size=\"2\" face=\"Arial\">RT\u00cdCULO 1o<\/font><\/b><font face=\"Arial\" size=\"2\">. <\/font> <\/A><font size=\"2\" face=\"Arial\"><i><b>OBJETO DE LA LEY.<\/b><\/i> La presente ley tiene como prop\u00f3sito definir el marco legal dentro del cual debe desarrollarse el debate electoral a la Presidencia de la Rep\u00fablica, o cuando el Presidente de la Rep\u00fablica en ejercicio aspire a la reelecci\u00f3n, o el Vicepresidente de la Rep\u00fablica aspire a la elecci\u00f3n presidencial, garantizando la igualdad de condiciones para los candidatos que re\u00fanan los requisitos de ley. Igualmente se reglamenta la Participaci\u00f3n en pol\u00edtica de los servidores p\u00fablicos y las garant\u00edas a la oposici\u00f3n.<\/font><\/p>\n<p align=\"justify\"><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><\/p>\n<p align=\"justify\"><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><b><A name=2>ART\u00cdCULO 2o. <\/A><\/b>CAMPA\u00d1A PRESIDENCIAL. <i><b>*Art\u00edculo CONDICIONALMENTE exequible* <\/b><\/i>Se entiende por campa\u00f1a presidencial el conjunto de actividades realizadas con el prop\u00f3sito de divulgar el proyecto pol\u00edtico y obtener apoyo electoral a favor de alguno de los candidatos.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">La campa\u00f1a presidencial tendr\u00e1 una duraci\u00f3n de cuatro (4) meses contados con anterioridad a la fecha de las elecciones de la primera vuelta, m\u00e1s el t\u00e9rmino establecido para la realizaci\u00f3n de la segunda vuelta, si fuere el caso.<\/font><\/p>\n<p align=\"justify\"><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><\/p>\n<p align=\"justify\"><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado CONDICIONALMENTE EXEQUIBLE, salvo el&nbsp; aparte tachado del texto original que se declara INEXEQUIBLE, por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra. <\/font> <\/i> <\/TD><\/TR>  <\/TABLE><\/p>\n<p align=\"justify\"><i><b><font size=\"2\" face=\"Arial\">*Texto original del Proyecto de Ley*<\/font><\/b><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\"><b>ART\u00cdCULO 2.<\/b> Campa\u00f1a presidencial. *Aparte tachado INEXEQUIBLE* Se entiende por campa\u00f1a presidencial el conjunto de actividades realizadas con el prop\u00f3sito de divulgar el proyecto pol\u00edtico y obtener apoyo electoral a favor de alguno de los candidatos de la Presidencia de la Rep\u00fablica. <\/font> <\/i> <\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">La campa\u00f1a presidencial tendr\u00e1 una duraci\u00f3n de cuatro (4) meses contados con anterioridad a la fecha de las elecciones de la primera vuelta, m\u00e1s el t\u00e9rmino establecido para la realizaci\u00f3n de la segunda vuelta, si fuere el caso.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><A name=3><b>ART\u00cdCULO 3o.<\/b> <\/A><i><b>ACTIVIDADES DE LA CAMPA\u00d1A PRESIDENCIAL. *Art\u00edculo CONDICIONALMENTE exequible* <\/b><\/i>Se entiende por actividades de campa\u00f1a presidencial, la promoci\u00f3n pol\u00edtica y la propaganda electoral a favor de un candidato a la Presidencia de la Rep\u00fablica. La promoci\u00f3n pol\u00edtica hace referencia a la divulgaci\u00f3n de la propuesta de gobierno o proyecto pol\u00edtico del candidato. La propaganda electoral es el conjunto de actividades pol\u00edticas realizadas con la finalidad directa de convocar a los electores a votar en favor de un candidato.<\/font><\/p>\n<p align=\"justify\"><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><\/p>\n<p align=\"justify\"><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado CONDICIONALMENTE EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra, &quot;en el entendido que las actividades de campa\u00f1a se realizar\u00e1n en las mismas condiciones se\u00f1aladas en el art\u00edculo anterior &quot;.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><A name=4><b>ART\u00cdCULO 4o<i>. <\/i><\/b> <\/A><i><b>LEGISLACI\u00d3N ESPECIAL. *Art\u00edculo CONDICIONALMENTE exequible* <\/b><\/i>El Presidente o el Vicepresidente de la Rep\u00fablica que manifiesten su inter\u00e9s de participar en la campa\u00f1a presidencial o se inscriban como candidatos en la elecci\u00f3n presidencial, estar\u00e1n sujetos a las condiciones que para estos efectos consagra la Constituci\u00f3n Pol\u00edtica y la presente ley de manera expl\u00edcita para ellos, en raz\u00f3n a su doble condici\u00f3n de funcionarios p\u00fablicos y candidatos.<\/font><\/p>\n<p><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado CONDICIONALMENTE EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra, &quot;en el entendido que la manifestaci\u00f3n de inter\u00e9s es la regulada en el art\u00edculo <A       hrefx=\"L0996005.htm#9\">9<\/A>\u00ba y que desde ese momento, el Presidente o el Vicepresidente quedan sujetos a las restricciones y prohibiciones contenidas en los art\u00edculos <A       hrefx=\"L0996005.htm#25\">25<\/A>, <A       hrefx=\"L0996005.htm#26\">26<\/A>, <A       hrefx=\"L0996005.htm#27\">27<\/A>, <A       hrefx=\"L0996005.htm#29\">29<\/A>, <A       hrefx=\"L0996005.htm#30\">30<\/A>, <A       hrefx=\"L0996005.htm#31\">31<\/A>, <A       hrefx=\"L0996005.htm#32\">32<\/A>, <A       hrefx=\"L0996005.htm#33\">33<\/A>, <A       hrefx=\"L0996005.htm#38\">38<\/A>, y <A       hrefx=\"L0996005.htm#40\">40<\/A> del Proyecto de Ley&quot;.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b><A name=\"TITULO II\">TITULO II. <\/A><\/b><\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b>REGLAMENTACI\u00d3N ESPECIAL DE LA CAMPA\u00d1A PRESIDENCIAL. <\/b> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b><A name=\"CAPITULO I\">CAPITULO I. <\/A><\/b><\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b>SELECCI\u00d3N DE CANDIDATOS. <\/b> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><A name=5><b>ART\u00cdCULO 5o.<i> <\/i><\/b> <\/A><i><b>SELECCI\u00d3N DE CANDIDATOS A LA PRESIDENCIA POR PARTE DE LOS PARTIDOS, MOVIMIENTOS POL\u00cdTICOS O ALIANZAS. <\/b><\/i>El Consejo Nacional Electoral dispondr\u00e1 lo pertinente para que todos los partidos, movimientos pol\u00edticos o alianzas que deseen realizar consultas populares para la escogencia de su candidato, las adelanten en todo el territorio nacional.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">El proceso de selecci\u00f3n de los candidatos corresponde a la autonom\u00eda interna de los partidos y movimientos pol\u00edticos, quienes podr\u00e1n decidir en todo momento en su convenci\u00f3n, congreso o asamblea general si este proceso se adelanta mediante consulta popular u otro mecanismo democr\u00e1tico de selecci\u00f3n interna.<\/font><\/p>\n<p align=\"justify\"><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><\/p>\n<p align=\"justify\"><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><b><A name=6>ART\u00cdCULO 6o.<\/A><i> PARTICIPACI\u00d3N DEL PRESIDENTE Y EL VICEPRESIDENTE EN LOS MECANISMOS DE SELECCI\u00d3N DE CANDIDATOS DE LOS PARTIDOS O MOVIMIENTOS POL\u00cdTICOS. <\/i><\/b> El Presidente y el Vicepresidente de la Rep\u00fablica cuando aspiren a la elecci\u00f3n presidencial, podr\u00e1n participar en los mecanismos de selecci\u00f3n de candidatos de los partidos o movimientos pol\u00edticos.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Cuando el Presidente o el Vicepresidente, respectivamente, se sometan a consultas populares, asambleas, congresos o convenciones de partidos o movimientos pol\u00edticos, podr\u00e1n realizar proselitismo pol\u00edtico para dicha elecci\u00f3n durante el (1) mes anterior a la realizaci\u00f3n del evento, si as\u00ed lo decide. Durante el per\u00edodo de campa\u00f1a, el Presidente o el Vicepresidente, respectivamente, quedar\u00e1 sujeto a las regulaciones que contempla la presente ley para los per\u00edodos de campa\u00f1a presidencial.<\/font><\/p>\n<p align=\"justify\"><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE, salvo los apartes tachados del texto original que se declaran INEXEQUIBLES por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><\/p>\n<p><i><b><font size=\"2\" face=\"Arial\">*Texto original del Proyecto de Ley*<\/font><\/b><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\"><b>ART\u00cdCULO 6.<\/b> *Apartes tachados INEXEQUIBLES* Participaci\u00f3n del Presidente y el Vicepresidente en los mecanismos de selecci\u00f3n de candidatos de los partidos o movimientos pol\u00edticos.&nbsp; El Presidente y el Vicepresidente de la Rep\u00fablica cuando aspiren a la elecci\u00f3n presidencial, podr\u00e1n participar en los mecanismos de selecci\u00f3n de candidatos de los partidos o movimientos pol\u00edticos.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Cuando el Presidente o el Vicepresidente, respectivamente, se sometan a consultas populares, asambleas, congresos o convenciones d e partidos o movimientos pol\u00edticos, podr\u00e1n realizar proselitismo pol\u00edtico para dicha elecci\u00f3n durante el (1) mes anterior a la realizaci\u00f3n del evento, si as\u00ed lo decide. Durante el per\u00edodo de campa\u00f1a, el Presidente o el Vicepresidente, respectivamente, quedar\u00e1 sujeto a las regulaciones que contempla la presente ley para los per\u00edodos de campa\u00f1a presidencial.       Los dem\u00e1s candidatos a dicha elecci\u00f3n, dispondr\u00e1n del mismo tiempo para realizar su campa\u00f1a, de acuerdo con las regulaciones internas de sus partidos.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">En cualquier momento, el Presidente de la Rep\u00fablica podr\u00e1 asistir a eventos internos de los partidos o movimientos pol\u00edticos, o movimientos sociales o grupos significativos de ciudadanos, e incluso participar en aquellos eventos en los cuales se decidan las reglas de juego para la selecci\u00f3n de candidatos o se adopten decisiones sobre el candidato oficial de dicho partido o movimiento, o se seleccione o elija el mismo.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\"><font face=\"Arial\" size=\"2\"><b><A name=\"CAPITULO II\">CAPITULO II. <\/A><\/b><\/font><\/p>\n<p align=\"center\"><font face=\"Arial\" size=\"2\"><b>INSCRIPCI\u00d3N DE CANDIDATURAS. <\/b> <\/font> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><b><A name=7>ART\u00cdCULO 7o.<\/A><i> DERECHO DE INSCRIPCI\u00d3N DE CANDIDATOS A LA PRESIDENCIA DE LA REP\u00daBLICA.<\/i><\/b> Los partidos y movimientos pol\u00edticos con personer\u00eda jur\u00eddica, podr\u00e1n inscribir, individualmente o en alianzas, candidato a la Presidencia de la Rep\u00fablica. La inscripci\u00f3n deber\u00e1 ser avalada para los mismos efectos, por el respectivo representante legal del partido o movimiento.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Los movimientos sociales o grupos significativos de ciudadanos tendr\u00e1n derecho a inscribir candidato a la Presidencia de la Rep\u00fablica. Para estos efectos, dichos movimientos y grupos acreditar\u00e1n ante la Registradur\u00eda Nacional del Estado Civil, un n\u00famero de firmas equivalente al tres por ciento (3%) del n\u00famero total de votos v\u00e1lidos depositados en las anteriores elecciones a la Presidencia de la Rep\u00fablica.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Estas firmas deber\u00e1n acreditarse ante la Registradur\u00eda General del Estado Civil por lo menos treinta (30) d\u00edas antes de iniciar el per\u00edodo de inscripci\u00f3n de candidatos a la Presidencia de la Rep\u00fablica. Esta entidad deber\u00e1 certificar el n\u00famero de firmas requerido ocho (8) d\u00edas antes de iniciarse el citado per\u00edodo de inscripci\u00f3n de candidatos.<\/font><\/p>\n<p align=\"justify\"><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><\/p>\n<p align=\"justify\"><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD height=\"47\"><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><b><A name=8>ART\u00cdCULO 8o. <\/A>PER\u00cdODO DE INSCRIPCI\u00d3N A LA PRESIDENCIA DE LA REP\u00daBLICA. <\/b>*<i><b>Art\u00edculo CONDICIONALMENTE exequible*<\/b><\/i> La inscripci\u00f3n de los candidatos a la Presidencia de la Rep\u00fablica con su f\u00f3rmula vicepresidencial se iniciar\u00e1 con cuatro (4) meses de anterioridad a la fecha de votaci\u00f3n de la primera vuelta de la elecci\u00f3n presidencial y, se podr\u00e1 adelantar durante los treinta (30) d\u00edas siguientes.<\/font><\/p>\n<p> <font face=\"Arial\" size=\"2\">Las inscripciones podr\u00e1n modificarse dentro de los cinco (5) d\u00edas h\u00e1biles siguientes a la fecha de cierre de la inscripci\u00f3n.<\/font> <font face=\"Arial\" size=\"2\">PAR\u00c1GRAFO.<b> <\/b>La Registradur\u00eda Nacional del Estado Civil reglamentar\u00e1 la materia.<\/font><\/p>\n<p><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado CONDICIONALMENTE EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra, &quot;en el&nbsp; entendido que cuando los partidos o movimientos pol\u00edticos&nbsp; opten por escoger candidatos de conformidad con el inciso tercero del art\u00edculo <A       hrefx=\"CONS_P91.htm#107\">107<\/A> de la Constituci\u00f3n, se aplicar\u00e1 para la inscripci\u00f3n del candidato, el t\u00e9rmino consagrado en las normas electorales vigentes contado a partir del d\u00eda de la elecci\u00f3n de miembros del Congreso&nbsp; de la Rep\u00fablica&quot;.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><A name=9><b>ART\u00cdCULO 9o.<\/b> <\/A><b><i>DECLARACI\u00d3N DEL PRESIDENTE QUE ASPIRA SER CANDIDATO A LA ELECCI\u00d3N PRESIDENCIAL. *Art\u00edculo CONDICIONALMENTE exequible* <\/i><\/b>El Presidente o el Vicepresidente de la Rep\u00fablica que aspiren a la elecci\u00f3n presidencial, de conformidad con las calidades establecidas en la Constituci\u00f3n Pol\u00edtica, deber\u00e1n declarar p\u00fablicamente y por escrito su inter\u00e9s de presentarse como candidatos, seis (6) meses antes de la votaci\u00f3n en primera vuelta. Copia del escrito deber\u00e1 depositarse en la Registradur\u00eda Nacional del Estado Civil.<\/font><\/p>\n<p><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado CONDICIONALMENTE EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra, &quot;en el entendido que desde ese momento, el Presidente o el Vicepresidente quedan sujetos a las restricciones y prohibiciones contenidas en los art\u00edculos <A       hrefx=\"L0996005.htm#25\">25<\/A>, <A       hrefx=\"L0996005.htm#26\">26<\/A>, <A       hrefx=\"L0996005.htm#27\">27<\/A>, <A       hrefx=\"L0996005.htm#29\">29<\/A>, <A       hrefx=\"L0996005.htm#30\">30<\/A>, <A       hrefx=\"L0996005.htm#31\">31<\/A>, <A       hrefx=\"L0996005.htm#32\">32<\/A>, <A       hrefx=\"L0996005.htm#33\">33<\/A>, <A       hrefx=\"L0996005.htm#38\">38<\/A>, y <A       hrefx=\"L0996005.htm#40\">40<\/A> del Proyecto de Ley&quot;.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b><A name=\"CAPITULO III\">CAPITULO III. <\/A><\/b><\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b>ACCESO A LA FINANCIACI\u00d3N ESTATAL PREVIA. <\/b> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Arial\" size=\"2\"><A name=10><b>ART\u00cdCULO 10.<i> <\/i><\/b> <\/A><i><b>CONDICIONES DE LEY.<\/b><\/i> Los candidatos inscritos a la Presidencia de la Rep\u00fablica que cumplan los siguientes requisitos, podr\u00e1n acceder a financiaci\u00f3n estatal previa a la fecha de las elecciones:<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">1. Haber sido inscrito por un partido o movimiento pol\u00edtico con personer\u00eda jur\u00eddica, o alianza de estos, que hayan obtenido el cuatro por ciento (4%) de los votos de Senado o un porcentaje igual de los votos de la C\u00e1mara de Representantes sumados nacionalmente, en la elecci\u00f3n al Congreso de la Rep\u00fablica realizada con anterioridad a la fecha de inscripci\u00f3n de candidatos a la Presidencia de la Rep\u00fablica. Ello debe ser certificado por el Consejo Nacional Electoral en los ocho (8) d\u00edas siguientes a la realizaci\u00f3n de las elecciones para el Congreso, de acuerdo con el conteo de votos realizado el d\u00eda de elecciones.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">2. Ser inscrito por un movimiento social o grupo significativo de ciudadanos respaldado por un n\u00famero de firmas v\u00e1lidas equivalentes al tres por ciento (3%) del n\u00famero total de votos depositados en las anteriores elecciones a la Presidencia de la Rep\u00fablica, certificadas por la Registradur\u00eda Nacional del Estado Civil.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">La financiaci\u00f3n estatal de los candidatos que no re\u00fanan estos requisitos, se realizar\u00e1 exclusivamente a trav\u00e9s de la reposici\u00f3n de votos.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><b>PAR\u00c1GRAFO.<\/b> La financiaci\u00f3n estatal previa est\u00e1 compuesta por un anticipo del Estado, que comprende una parte para la financiaci\u00f3n de la propaganda electoral y otra para la financiaci\u00f3n de otros gastos de campa\u00f1a, tal y como se reglamenta en la presente ley.<\/font><\/p>\n<p><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b><A name=\"CAPITULO IV\">CAPITULO IV. <\/A><\/b><\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b>FINANCIACI\u00d3N DE LAS CAMPA\u00d1AS PRESIDENCIALES FINANCIACI\u00d3N ESTATAL. <\/b> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b><A name=11>ART\u00cdCULO 11. <\/A><i>FINANCIACI\u00d3N PREPONDERANTEMENTE ESTATAL DE LAS CAMPA\u00d1AS PRESIDENCIALES.<\/i><\/b> El Estado financiar\u00e1 preponderantemente las campa\u00f1as presidenciales de los partidos y movimientos pol\u00edticos, lo mismo que las de los movimientos sociales y grupos significativos de ciudadanos que inscriban candidatos a la Presidencia de la Rep\u00fablica, y re\u00fanan los requisitos de ley:<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">a) Los candidatos que re\u00fanan los requisitos de ley para acceder a los beneficios de la financiaci\u00f3n estatal previa, tendr\u00e1n derecho a:<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">&#8211; Recibir, en primera vuelta, a t\u00edtulo de anticipo aportes estatales igualitarios equivalentes a cuatro mil ochenta millones de pesos ($4.080.000.000). De estos aportes, dos mil ochocientos millones de pesos ($2.800.000.000) ser\u00e1n destinados a la financiaci\u00f3n de la propaganda pol\u00edtica de las campa\u00f1as presidenciales, los restantes mil doscientos ochenta millones de pesos ($1.280.000.000) ser\u00e1n para otros gastos de campa\u00f1a.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">Los recursos para la propaganda pol\u00edtica los entregar\u00e1 el Ministerio de Hacienda y Cr\u00e9dito P\u00fablico a las Campa\u00f1as Presidenciales de los candidatos a los que se refiere el presente literal, al igual que los recursos para los otros gastos de campa\u00f1a, dentro de los diez (10) d\u00edas siguientes a la certificaci\u00f3n expedida por el Consejo Nacional Electoral que establece el lleno de los requisitos previstos en el art\u00edculo anterior y la aceptaci\u00f3n de la p\u00f3liza o garant\u00eda correspondiente.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">&#8211; Los candidatos que accedan a la segunda vuelta, si la hubiere, recibir\u00e1n como anticipo aportes estatales igualitarios, equivalentes a dos mil cuatrocientos cincuenta millones de pesos ($2.450.000.000), los cuales se destinar\u00e1n a la financiaci\u00f3n de la propaganda pol\u00edtica en un cincuenta por ciento (50%) y el saldo en otros gastos de campa\u00f1a, que se entregar\u00e1n diez (10) d\u00edas despu\u00e9s del d\u00eda de las elecciones de primera vuelta.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">&#8211; Recibir v\u00eda reposici\u00f3n de votos una suma equivalente al n\u00famero de votos v\u00e1lidos depositados multiplicado por mil setecientos cinco pesos por voto ($1.705). Ning\u00fan candidato podr\u00e1 recibir suma superior al monto de lo efectivamente gastado y aprobado por el Consejo Nacional Electoral, menos los aportes del sector privado y el anticipo dado por el Estado, en caso de que hubiera tenido acceso a \u00e9l. Igualmente, en la segunda vuelta, si la hubiere, los candidatos recibir\u00e1n una suma equivalente a ochocientos cincuenta y dos pesos ($852) por votos v\u00e1lidos depositados. Tanto en la primera como en la segunda vuelta no se podr\u00e1n exceder los topes de las campa\u00f1as, establecidos en la presente ley.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">Para tener derecho a la reposici\u00f3n de votos los candidatos deber\u00e1n obtener en la elecci\u00f3n para Presidente de la Rep\u00fablica, al menos una votaci\u00f3n igual o superior al cuatro por ciento (4%) de los votos v\u00e1lidos depositados. Quien no consiga este porcentaje m\u00ednimo, no tendr\u00e1 derecho a la financiaci\u00f3n estatal de la campa\u00f1a por el sistema de reposici\u00f3n de votos, y deber\u00e1 devolver el monto de la financiaci\u00f3n estatal previa en su totalidad. Estos montos de recursos, ser\u00e1n asegurados mediante p\u00f3liza o garant\u00eda a favor del Estado, expedida por una entidad financiera privada, o en su defecto el partido que avale al candidato podr\u00e1 pignorar los recursos ciertos para la financiaci\u00f3n que le corresponda en los a\u00f1os subsiguientes, como garant\u00eda por el monto recibido, siempre y cuando con ellas cancele las obligaciones contra\u00eddas. En el caso de que el candidato haya sido inscrito por movimientos sociales o grupos significativos de ciudadanos, la garant\u00eda o p\u00f3liza deber\u00e1 ser respalda por los promotores del grupo hasta por el monto que se deba devolver;<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">b) La financiaci\u00f3n de las campa\u00f1as de los candidatos que no cumplan con los requisitos establecidos en el art\u00edculo diez (10) de esta ley para acceder a la financiaci\u00f3n estatal previa de las campa\u00f1as presidenciales, se regir\u00e1 por las siguientes reglas:<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">1. El Estado, a trav\u00e9s de la Registradur\u00eda Nacional del Estado Civil, financiar\u00e1 v\u00eda reposici\u00f3n de votos los gastos de campa\u00f1a, en caso de que obtenga al menos el cuatro por ciento (4%) de los votos v\u00e1lidos depositados.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">2. El valor de la reposici\u00f3n por voto v\u00e1lido ser\u00e1 de tres mil cuatrocientos setenta y ocho pesos ($3.478).<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">3. Los partidos o movimientos pol\u00edticos, movimientos sociales y grupos significativos de ciudadanos que hayan inscrito candidato a la Presidencia de la Rep\u00fablica, y en cuya votaci\u00f3n no logren por lo menos el cuatro por ciento (4%) del total de los votos v\u00e1lidos, no tendr\u00e1n derecho a la reposici\u00f3n de gastos de campa\u00f1a por voto.<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">PAR\u00c1GRAFO 1o. Los candidatos que re\u00fanan los requisitos de ley para acceder a los beneficios de la financiaci\u00f3n estatal previa, tambi\u00e9n podr\u00e1n solicitar un monto adicional al anticipo de hasta el diez por ciento (10%) del tope establecido para la campa\u00f1a presidencial, para utilizarlos en propaganda electoral en radio, prensa escrita o televisi\u00f3n, los cuales estar\u00e1n garantizados a satisfacci\u00f3n del Ministerio de Hacienda y Cr\u00e9dito P\u00fablico y regulados bajo los mismos par\u00e1metros establecidos para el anticipo destinado a otros gastos de campa\u00f1a.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">PAR\u00c1GRAFO 2o. <i><b>*CONDICIONALMENTE exequible*<\/b><\/i> El candidato presidencial que haya accedido a la financiaci\u00f3n estatal previa y retire su nombre o desista de su candidatura antes de las elecciones en primera vuelta, deber\u00e1 devolver la totalidad de los recursos recibidos de parte del Estado, dentro de los quince (15) d\u00edas siguientes a su retiro. De no ser as\u00ed, el Ministerio de Hacienda y Cr\u00e9dito P\u00fablico y la Registradur\u00eda Nacional del Estado Civil, proceder\u00e1n judicialmente contra el candidato, su campa\u00f1a presidencial, el Gerente de su campa\u00f1a, los integrantes del Comit\u00e9 Financiero de su campa\u00f1a y los Partidos o Movimientos Pol\u00edticos que lo hayan inscrito.<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE, salvo los apartes tachados del texto original que se declaran INEXEQUIBLES, y el par\u00e1grafo segundo que se condiciona, por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra. <\/font> <\/i> <\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Condiciona la Corte el par\u00e1grafo 2o. &quot;en el entendido que el Ministerio de Hacienda y Cr\u00e9dito P\u00fablico y la Registradur\u00eda del Estado Civil est\u00e1n obligados a hacer efectiva la p\u00f3liza o garant\u00eda correspondiente al candidato presidencial&nbsp; a favor del Estado&quot;.<\/font><\/i><\/TD><\/TR>  <\/TABLE><\/p>\n<p><i><b><font size=\"2\" face=\"Arial\">*Texto original del Proyecto de Ley*<\/font><\/b><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\"><b>ART\u00cdCULO 11.<\/b> *Apartes tachados INEXEQUIBLES* Financiaci\u00f3n preponderantemente estatal de las campa\u00f1as presidenciales. El Estado financiar\u00e1 preponderantemente las campa\u00f1as presidenciales de los partidos y movimientos pol\u00edticos, lo mismo que las de los movimientos sociales y grupos significativos de ciudadanos que inscriban candidatos a la Presidencia de la Rep\u00fablica, y re\u00fanan los requisitos de ley.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">a) Los candidatos que re\u00fanan los requisitos de ley para acceder a los beneficios de la financiaci\u00f3n estatal previa, tendr\u00e1n derecho a:<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">&#8211; Recibir, en primera vuelta, a t\u00edtulo de anticipo aportes estatales igualitarios equivalentes a cuatro mil ochenta millones de pesos ($4.080&#39;000.000). De estos aportes, dos mil ochocientos millones de pesos ($2.800&#39;000.000) ser\u00e1n destinados a la financiaci\u00f3n de la propaganda pol\u00edtica de las campa\u00f1as presidenciales, los restantes mil doscientos ochenta millones de pesos ($1.280&#39;000.000) ser\u00e1n para otros gastos de campa\u00f1a.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Los recursos para la propaganda pol\u00edtica los entregar\u00e1 el Ministerio de Hacienda y Cr\u00e9dito P\u00fablico a las Campa\u00f1as Presidenciales de los candidatos a los que se refiere el presente literal, en \u00f3rdenes de servicio pagaderas a la fecha, al igual que los recursos para los otros gastos de campa\u00f1a, dentro de los diez (10) d\u00edas siguientes a la certificaci\u00f3n expedida por el Consejo Nacional Electoral que establece el lleno de los requisitos previstos en el art\u00edculo anterior y la aceptaci\u00f3n de la p\u00f3liza o garant\u00eda correspondiente.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">&#8211; Los candidatos que accedan a la segunda vuelta, si la hubiere, recibir\u00e1n como anticipo aportes estatales igualitarios, equivalentes a dos mil cuatrocientos cincuenta millones de pesos ($2.450&#39;000.000), los cuales se destinar\u00e1n a la financiaci\u00f3n de la propaganda pol\u00edtica en un cincuenta por ciento (50%) y el saldo en otros gastos de campa\u00f1a, que se entregar\u00e1n diez (10) d\u00edas despu\u00e9s del d\u00eda de las elecciones de primera vuelta. <\/font> <\/i> <\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">&#8211; Recibir v\u00eda reposici\u00f3n de votos una suma equivalente al n\u00famero de votos v\u00e1lidos depositados multiplicado por mil setecientos cinco pesos por voto ($1.705). Ning\u00fan candidato podr\u00e1 recibir suma superior al monto de lo efectivamente gastado y aprobado por el Consejo Nacional Electoral, menos los aportes del sector privado y el anticipo dado por el Estado, en caso de que hubiera tenido acceso a \u00e9l. Igualmente, en la segunda vuelta, si la hubiere, los candidatos recibir\u00e1n una suma equivalente a ochocientos cincuenta y dos pesos ($852) por votos v\u00e1lidos depositados. Tanto en la primera como en la segunda vuelta no se podr\u00e1n exceder los topes de las campa\u00f1as, establecidos en la presente ley.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Para tener derecho a la reposici\u00f3n de votos los candidatos deber\u00e1n obtener en la elecci\u00f3n para Presidente de la Rep\u00fablica, al menos una votaci\u00f3n igual o superior al cuatro por ciento (4%) de los votos v\u00e1lidos depositados. Quien no consiga este porcentaje m\u00ednimo, no tendr\u00e1 derecho a la financiaci\u00f3n estatal de la campa\u00f1a por el sistema de reposici\u00f3n de votos, y deber\u00e1 devolver el monto de la financiaci\u00f3n estatal previa en su totalidad. Estos montos de recursos, ser\u00e1 asegurado mediante p\u00f3liza o garant\u00eda a favor del Estado, expedida por una entidad financiera privada, o en su defecto el partido que avale al candidato podr\u00e1 pignorar los recursos ciertos para la financiaci\u00f3n que le corresponda en los a\u00f1os subsiguientes, como garant\u00eda por el monto recibido, siempre y cuando con ellas cancele las obligaciones contra\u00eddas. En el caso de que el candidato haya sido inscrito por movimientos sociales o grupos significativos de ciudadanos, la garant\u00eda o p\u00f3liza deber\u00e1 ser respalda por los promotores del grupo hasta por el monto que se deba devolver.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">En caso de que el candidato no obtenga el porcentaje de votos v\u00e1lidos aqu\u00ed establecido y deba hacerse efectiva la p\u00f3liza o garant\u00eda, el Estado a trav\u00e9s del Ministerio de Hacienda y Cr\u00e9dito P\u00fablico y la Registradur\u00eda Nacional del Estado Civil, repetir\u00e1 contra el partido o movimiento pol\u00edtico que aval\u00f3 el candidato, contra el candidato, contra el tesorero, el gerente de campa\u00f1a y los integrantes del comit\u00e9 financiero de la campa\u00f1a presidencial, quienes se inscribir\u00e1n como tales al momento de la inscripci\u00f3n del gerente de campa\u00f1a; todos ellos ser\u00e1n deudores solidarios del monto de financiaci\u00f3n estatal entregado a la campa\u00f1a;<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">b) La financiaci\u00f3n de las campa\u00f1as de los candidatos que no cumplan con los requisitos establecidos en el art\u00edculo diez (10) de esta ley para acceder a la financiaci\u00f3n estatal previa de las campa\u00f1as presidenciales, se regir\u00e1 por las siguientes reglas:<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">1. El Estado, a trav\u00e9s de la Registradur\u00eda Nacional del Estado Civil, financiar\u00e1 v\u00eda reposici\u00f3n de votos los gastos de campa\u00f1a, en caso de que obtenga al menos el cuatro por ciento (4%) de los votos v\u00e1lidos depositados.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">2. El valor de la reposici\u00f3n por voto v\u00e1lido ser\u00e1 de tres mil cuatrocientos setenta y ocho pesos ($3.478).<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">3. Los partidos o movimientos pol\u00edticos, movimientos sociales y grupos significativos de ciudadanos que hayan inscrito candidato a la Presidencia de la Rep\u00fablica, y en cuya votaci\u00f3n no logren por lo menos el cuatro por ciento (4%) del total de los votos v\u00e1lidos, no tendr\u00e1n derecho a la reposici\u00f3n de gastos de campa\u00f1a por voto.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Par\u00e1grafo 1\u00ba. Los candidatos que re\u00fanan los requisitos de ley para acceder a los beneficios de la financiaci\u00f3n estatal previa, tambi\u00e9n podr\u00e1n solicitar un monto adicional al anticipo de hasta el diez por ciento (10%) del tope establecido para la campa\u00f1a presidencial, para utilizarlos en propaganda electoral en radio, prensa escrita o televisi\u00f3n, los cuales estar\u00e1n garantizados a satisfacci\u00f3n del Ministerio de Hacienda y Cr\u00e9dito P\u00fablico y regulados bajo los mismos par\u00e1metros establecidos para el anticipo destinado a otros gastos de campa\u00f1a.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Par\u00e1grafo 2\u00ba. El candidato presidencial que haya accedido a la financiaci\u00f3n estatal previa y retire su nombre o desista de su candidatura antes de las elecciones en primera vuelta, deber\u00e1 devolver la totalidad de los recursos recibidos de parte del Estado, dentro de los quince (15) d\u00edas siguientes a su retiro. De no ser as\u00ed, el Ministerio de Hacienda y Cr\u00e9dito P\u00fablico y la Registradur\u00eda Nacional del Estado Civil, proceder\u00e1n judicialmente contra el candidato, su campa\u00f1a presidencial, el Gerente de su campa\u00f1a, los integrantes del Comit\u00e9 Financiero de su campa\u00f1a y los Partidos o Movimientos Pol\u00edticos que lo hayan inscrito.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><A name=12><b>ART\u00cdCULO 12.<\/b> <\/A><i><b>TOPES DE CAMPA\u00d1A. *CONDICIONALMENTE exequible*<\/b><\/i> El tope de gastos de las campa\u00f1as presidenciales del a\u00f1o 2006 ser\u00e1 de diez mil millones de pesos ($10.000.000.000) para la primera vuelta. Para la segunda vuelta presidencial, si la hubiere, el tope ser\u00e1 de seis mil millones de pesos ($6.000.000.000)El monto fijado como tope de campa\u00f1a comprende la sumatoria, tanto de los recursos aportados por el Estado, como los aportados por los particulares.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Los candidatos que no cumplan con los requisitos para acceder a la financiaci\u00f3n estatal previa de la campa\u00f1a presidencial y que no alcancen el n\u00famero de votos necesarios para acceder a la reposici\u00f3n de votos por parte del Estado, financiar\u00e1n sus campa\u00f1as en un ciento por ciento (100%) con aportes o donaciones de particulares.<\/font><\/p>\n<p><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><b><i><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/i><\/b><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado CONDICIONALMENTE EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra, &quot;en el entendido que cuando se trata de candidatos que no sean el Presidente de la Rep\u00fablica o el Vicepresidente, el tope de gastos de las campa\u00f1as presidenciales del a\u00f1o 2006 ser\u00e1 el establecido en la Resoluci\u00f3n 670 de 2001 del Consejo Nacional Electoral para las elecciones del a\u00f1o 2002&quot;.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <font face=\"Arial\" size=\"2\"><b><A name=13>ART\u00cdCULO 13.<\/A><\/b> los valores se\u00f1alados en pesos en la presente ley, se reajustar\u00e1n anualmente de acuerdo con el aumento del \u00edndice de precios al consumidor certificado por el departamento administrativo nacional de estad\u00edstica, DANE.<\/font><\/p>\n<p><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><b><A name=14>ART\u00cdCULO 14.<i> <\/i> <\/A><i>MONTO M\u00c1XIMO DE LAS CONTRIBUCIONES O DONACIONES POR PARTE DE PARTICULARES. <\/i><\/b>El veinte por ciento (20%) del tope de los gastos de las campa\u00f1as presidenciales podr\u00e1 ser financiado por personas naturales; sin embargo, las campa\u00f1as presidenciales no podr\u00e1n recibir aportes o donaciones individuales de personas naturales sino hasta el dos por ciento (2%) del monto fijado como tope de la campa\u00f1a.<\/font><\/p>\n<p><font face=\"Arial\" size=\"2\">Los aportes de los candidatos y sus familiares hasta el cuarto grado de consanguinidad, segundo de afinidad o primero civil no podr\u00e1n superar en conjunto el cuatro por ciento (4%) del monto fijado como tope por el Consejo Nacional Electoral.<\/font><\/p>\n<p><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><i><font size=\"2\" face=\"Arial\">&#8211; Art\u00edculo declarado EXEQUIBLE, salvo los apartes tachados del texto original que se declaran INEXEQUIBLES, por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><\/p>\n<p><i><b><font size=\"2\" face=\"Arial\">*Texto original del Proyecto de Ley*<\/font><\/b><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\"><b>ART\u00cdCULO 14.<\/b> *Apartes tachados INEXEQUIBLES* Monto m\u00e1ximo de las contribuciones o donaciones por parte de particulares. El veinte por ciento (20%) del tope de los gastos de las campa\u00f1as presidenciales podr\u00e1 ser financiado por personas naturales o jur\u00eddicas       de derecho privado; sin embargo, las campa\u00f1as presidenciales no podr\u00e1n recibir aportes o donaciones individuales de personas naturales sino hasta el dos por ciento (2%) del monto fijado como tope de la campa\u00f1a, ni de personas jur\u00eddicas sino hasta el cuatro por ciento (4%) del mismo tope. Las contribuciones y donaciones de personas jur\u00eddicas pertenecientes a un mismo grupo empresarial, no podr\u00e1n superar en conjunto el cinco por ciento (5%) del monto fijado como tope.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">La Superintendencia de Sociedades expedir\u00e1 el documento p\u00fablico en el que se relacione qu\u00e9 personas jur\u00eddicas constituyen un grupo empresarial.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Los aportes de los candidatos y sus familiares hasta el cuarto grado de consaguinidad, segundo de afinidad o primero civil no podr\u00e1n superar en conjunto el cuatro por ciento (4%) del monto fijado como tope por el Consejo Nacional Electoral.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><b><A name=15>ART\u00cdCULO 15.<i> <\/i> <\/A><i>MANEJO DE LOS RECURSOS DE LAS CAMPA\u00d1AS PRESIDENCIALES. <\/i><\/b>Los recursos de las campa\u00f1as presidenciales se recibir\u00e1n y administrar\u00e1n a trav\u00e9s de una cuenta \u00fanica y exclusiva para tal objetivo, tanto para la recepci\u00f3n de los aportes y donaciones, y gastos de reposici\u00f3n del Estado, como para los gastos de la misma campa\u00f1a presidencial. Esta estar\u00e1 exenta del impuesto a las transacciones bancarias. La Superintendencia Bancaria establecer\u00e1 un r\u00e9gimen especial de control y vigilancia que garantice la transparencia de los movimientos de dichas cuentas.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">PAR\u00c1GRAFO. Las campa\u00f1as presidenciales podr\u00e1n acordar con la entidad financiera que seleccionen para abrir la citada cuenta, la apertura de las subcuentas que consideren necesarias para organizar la distribuci\u00f3n o gasto de los recursos en las distintas \u00e1reas de trabajo en las que est\u00e9 organizada la campa\u00f1a presidencial.<\/font><\/p>\n<p><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><A name=16><b>ART\u00cdCULO 16.<i> <\/i><\/b> <\/A><i><b>GERENTE DE CAMPA\u00d1A. <\/b><\/i>El candidato presidencial deber\u00e1 designar un gerente de campa\u00f1a, encargado de administrar todos los recursos de la campa\u00f1a. El gerente de campa\u00f1a ser\u00e1 el responsable de todas las actividades propias de la financiaci\u00f3n de la campa\u00f1a pol\u00edtica, y los gastos de la misma. El gerente de campa\u00f1a deber\u00e1 ser designado dentro de los tres (3) d\u00edas siguientes a la inscripci\u00f3n de la candidatura presidencial, mediante declaraci\u00f3n juramentada del candidato, que deber\u00e1 registrarse en el mismo t\u00e9rmino ante el Consejo Nacional Electoral.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">El gerente de campa\u00f1a ser\u00e1 el representante oficial de la campa\u00f1a presidencial ante el Consejo Nacional Electoral para todos los efectos relacionados con la financiaci\u00f3n de la campa\u00f1a pol\u00edtica y la posterior presentaci\u00f3n de informes, cuentas y reposici\u00f3n de los gastos de la campa\u00f1a. El gerente podr\u00e1 designar unos subgerentes en cada departamento o municipio, seg\u00fan lo considere. Estos ser\u00e1n sus delegados para la respectiva entidad territorial. Ning\u00fan servidor p\u00fablico o ciudadano extranjero podr\u00e1 ser designado como gerente de campa\u00f1a.<\/font><\/p>\n<p align=\"justify\"><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><\/p>\n<p align=\"justify\"><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><A name=17><b>ART\u00cdCULO 17.<i> <\/i><\/b> <\/A><i><b>LIBROS DE CONTABILIDAD Y SOPORTES. <\/b><\/i>Los responsables de la rendici\u00f3n de cuentas de la respectiva campa\u00f1a deber\u00e1n llevar el libro mayor de balances, el diario columnario y al menos un libro auxiliar, los cuales ser\u00e1n registrados ante la Organizaci\u00f3n Electoral al momento de la inscripci\u00f3n de los candidatos. Igualmente llevar\u00e1n una lista de las contribuciones, donaciones y cr\u00e9ditos, con la identificaci\u00f3n, direcci\u00f3n y tel\u00e9fono, de las personas naturales que realizaron la contribuci\u00f3n o donaci\u00f3n.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Esta documentaci\u00f3n podr\u00e1 ser revisada por el Consejo Nacional Electoral para verificar el cumplimiento de las normas sobre financiaci\u00f3n de las campa\u00f1as.<\/font><\/p>\n<p><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE, salvo los apartes tachados del texto original que se declaran INEXEQUIBLES, por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><\/p>\n<p><i><b><font size=\"2\" face=\"Arial\">*Texto original del Proyecto de Ley*<\/font><\/b><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\"><b>ART\u00cdCULO 17.<\/b> *Apartes tachados INEXEQUIBLES* Libros de contabilidad y soportes. Los responsables de la rendici\u00f3n de cuentas de la respectiva campa\u00f1a deber\u00e1n llevar el libro mayor de balances, el diario columnario y al menos un libro auxiliar, los cuales ser\u00e1n registrados ante la Organizaci\u00f3n Electoral al momento de la inscripci\u00f3n de los candidatos. Igualmente llevar\u00e1n una lista de las contribuciones, donaciones y cr\u00e9ditos, con la identificaci\u00f3n, direcci\u00f3n y tel\u00e9fono, de las personas naturales o jur\u00eddicas que realizaron la contribuci\u00f3n o donaci\u00f3n, en las actas en que se aprob\u00f3 el aporte cuando se trate de personas jur\u00eddicas.<\/font><\/i><\/TD><\/TR>  <TR>    <TD align=\"justify\"><i><font size=\"2\" face=\"Arial\">Esta documentaci\u00f3n podr\u00e1 ser revisada por el Consejo Nacional Electoral para verificar el cumplimiento de las normas sobre financiaci\u00f3n de las campa\u00f1as. .<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><A name=18><b>ART\u00cdCULO 18.<\/b> <\/A><i><b>SISTEMA DE AUDITORIA. <\/b><\/i>Con el objeto de garantizar el adecuado control interno en el manejo de los ingresos y gastos de la campa\u00f1a presidencial, los partidos, movimientos pol\u00edticos con personer\u00eda jur\u00eddica, movimientos sociales y grupos significativos de ciudadanos, que inscriban candidatos, crear\u00e1n y acreditar\u00e1n ante el Consejo Nacional Electoral un sistema de auditoria interna como condici\u00f3n para iniciar la recepci\u00f3n de los aportes y contribuciones de los particulares y\/o de recibir los recursos de financiaci\u00f3n estatal.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">El auditor ser\u00e1 solidariamente responsable del manejo que se haga de los ingresos y gastos de la campa\u00f1a, as\u00ed como de los recursos de financiaci\u00f3n estatal, si no informa al Consejo Nacional Electoral sobre las irregularidades que se cometan.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">El Consejo Nacional Electoral, por conducto del Fondo de Financiaci\u00f3n de partidos y campa\u00f1as electorales, tendr\u00e1 a su cargo la realizaci\u00f3n de la auditoria externa sobre los recursos de financiaci\u00f3n de los partidos y movimientos pol\u00edticos con personer\u00eda jur\u00eddica y de las campa\u00f1as electorales, de que trata el art\u00edculo <A hrefx=\"L0130_94.htm#49\">49<\/A> de la <i> <b><a hrefx=\"L0130_94.htm\">Ley 130 de 1994<\/a><\/b><\/i>.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\">Dicho sistema deber\u00e1 garantizar una cobertura nacional y ser\u00e1 contratado con cargo al porcentaje del monto global de las apropiaciones presupuestales destinadas a la financiaci\u00f3n estatal, que fije el Consejo Nacional Electoral. El valor del contrato se determinar\u00e1 hasta por una suma m\u00e1xima equivalente a dicho porcentaje y el pago se har\u00e1 con base en las cuentas o informes efectivamente auditados. El objeto del contrato deber\u00e1 comenzar a ejecutarse desde el inicio de la campa\u00f1a electoral, conforme al t\u00e9rmino definido en esta ley.<\/font><\/p>\n<p> <font face=\"Arial\" size=\"2\">El sistema de auditoria externa ser\u00e1 reglamentado por el Consejo Nacional Electoral.<\/font><\/p>\n<p><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><A name=19><b>ART\u00cdCULO 19.<\/b> <\/A><i><b>RESPONSABLES DE LA RENDICI\u00d3N DE CUENTAS.<\/b><\/i> El gerente de campa\u00f1a ser\u00e1 el responsable de la rendici\u00f3n p\u00fablica de informes de cuentas de las campa\u00f1as en las que participen. El candidato presidencial, el gerente, el tesorero y el auditor de las campa\u00f1as, responder\u00e1n solidariamente por la oportuna presentaci\u00f3n de los informes contables y por el debido cumplimiento del r\u00e9gimen de financiaci\u00f3n de campa\u00f1as. Cualquier modificaci\u00f3n en la designaci\u00f3n del gerente, el tesorero o el auditor de las campa\u00f1as ser\u00e1 informada a la autoridad electoral.<\/font><\/p>\n<p align=\"justify\"><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><\/p>\n<p align=\"justify\"><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <font face=\"Arial\" size=\"2\"><A name=20><b>ART\u00cdCULO 20.<i> <\/i><\/b> <\/A><i><b>REGLAMENTACI\u00d3N.<\/b><\/i> El Consejo Nacional Electoral reglamentar\u00e1 lo referente al sistema \u00fanico de informaci\u00f3n sobre contabilidad electoral, presentaci\u00f3n de cuentas, per\u00edodo de evaluaci\u00f3n de informes, contenido de informes, publicidad de los informes, sistema de auditoria y revisor\u00eda fiscal.<\/font><\/p>\n<p align=\"justify\"><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><\/p>\n<p align=\"justify\"><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">&#8211; Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\"><A name=21><b>ART\u00cdCULO 21.<\/b> <\/A><i><b>VIGILANCIA DE LA CAMPA\u00d1A Y SANCIONES. *CONDICIONALMENTE exequible* <\/b><\/i>El Consejo Nacional Electoral podr\u00e1 adelantar en todo momento, auditorias o revisor\u00edas sobre los ingresos y gastos de la financiaci\u00f3n de las campa\u00f1as. Con base en dichos monitoreos o a solicitud de parte, podr\u00e1 iniciar investigaciones sobre el estricto cumplimiento de las normas sobre financiaci\u00f3n aqu\u00ed estipuladas. De comprobarse irregularidades en el financiamiento se impondr\u00e1n sanciones de acuerdo con la valoraci\u00f3n que hagan de las faltas, en el siguiente orden:<\/font><\/p>\n<p><font face=\"Arial\" size=\"2\">1. Multas entre el uno por ciento (1%) y el diez por ciento (10%) de los recursos desembolsados por parte del Estado para la respectiva campa\u00f1a.<\/font><\/p>\n<p><font face=\"Arial\" size=\"2\">2.<i><b> *CONDICIONALMENTE exequible*<\/b><\/i> Congelaci\u00f3n de los giros respectivos.<\/font><\/p>\n<p><i><font face=\"Arial\" size=\"2\" ><b>*Nota Jurisprudencia*<\/b><\/font><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Numeral declarado CONDICIONALMENTE EXEQUIBLE, e inexequible el aparte tachado del texto original, por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra, &quot;en el entendido que la congelaci\u00f3n procede una vez concluida la campa\u00f1a, en el momento de la reposici\u00f3n de votos&quot;.<\/font><\/i><\/TD><\/TR>  <\/TABLE><\/p>\n<p><i><b><font size=\"2\" face=\"Arial\">*Texto original del Proyecto de Ley*<\/font><\/b><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border><TR><TD><i><font size=\"2\" face=\"Arial\">2. *Aparte tachado INEXEQUIBLE* Congelaci\u00f3n de los giros respectivos para el desarrollo de la campa\u00f1a.<\/font><\/i><\/TD><\/TR><\/TABLE> <font face=\"Arial\" size=\"2\">3. En caso de sobrepasar el tope de recursos permitidos, bien por recibir donaciones privadas mayores a las autorizadas, o por superar los topes de gastos, se podr\u00e1 imponer la devoluci\u00f3n parcial o total de los recursos entregados.<\/font> <font face=\"Arial\" size=\"2\">4. En el caso del ganador de las elecciones presidenciales, el Congreso podr\u00e1 decretar la p\u00e9rdida del cargo seg\u00fan el procedimiento contemplado para las investigaciones y juicios por indignidad pol\u00edtica.<\/font> <font face=\"Arial\" size=\"2\">PAR\u00c1GRAFO. La denuncia por violaci\u00f3n de los topes de campa\u00f1a deber\u00e1 ser presentada dentro de los treinta (30) d\u00edas siguientes a la fecha de la elecci\u00f3n presidencial.<\/font><\/p>\n<p><i><b><font size=\"2\" face=\"Arial\">Texto original del Proyecto de Ley:<\/font><\/b><\/i><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>    <TR>    <TD><i><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/i><\/TD><\/TR>  <TR>    <TD><\/p>\n<p align=\"justify\"><i><font size=\"2\" face=\"Arial\">Art\u00edculo declarado CONDICIONALMENTE EXEQUIBLE por la Corte Constitucional mediante <b><a \"SC115305.htm\" hrefx=\"..\/..\/Sentencias\/C-1153-05.rtf\">Sentencia C-1153-05<\/a><\/b> de 11 de noviembre de 2005, Magistrado Ponente Dr. Marco Gerardo Monroy Cabra, &quot;en el entendido&nbsp; que el Consejo Nacional Electoral debe establecer previamente los criterios para apreciar la gravedad de la falta a imponer la sanci\u00f3n correspondiente, con aplicaci\u00f3n del procedimiento previsto en las normas vigentes que regulan a dicho Consejo&quot;.<\/font><\/i><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b><A name=\"CAPITULO V\">CAPITULO V. <\/A><\/b><\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b>ACCESO A MEDIOS DE COMUNICACI\u00d3N SOCIAL. <\/b> <\/font> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Arial\" size=\"2\"><b><A name=22>ART\u00cdCULO 22. <\/A><i>ACCESO EQUITATIVO A ESPACIOS EN LOS MEDIOS DE COMUNICACI\u00d3N SOCIAL QUE USAN EL ESPECTRO ELECTROMAGN\u00c9TICO. *CONDICIONALMENTE exequible* <\/i><\/b>En el per\u00edodo comprendido entre los sesenta (60) d\u00edas anteriores a la elecci\u00f3n presidencial y ocho (8) d\u00edas antes a la misma, el Estado har\u00e1 uso durante un (1) mes del Espectro Electromagn\u00e9tico destinado a los concesionarios y operadores privados de radio y televisi\u00f3n en un espacio diario de dos (2) minutos en televisi\u00f3n en horario \u00abtriple A\u00bb y cuatro (4) minutos diarios en radio en el horario de mayor audiencia, para que los candidatos divulguen sus tesis y programas de gobierno. El Consejo Nacional Electoral determinar\u00e1 por sorteo la distribuci\u00f3n de estos espacios entre los distintos candidatos, durante los d\u00edas h\u00e1biles de la semana. Estos programas se emitir\u00e1n hasta ocho d\u00edas antes de la fecha de votaci\u00f3n.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">Los costos de producci\u00f3n de estos programas, ser\u00e1n asumidos respectivamente por cada una de las campa\u00f1as presidenciales.<\/font><\/p>\n<p align=\"justify\"><font face=\"Arial\" size=\"2\">PAR\u00c1GRAFO<b>.<\/b> En el caso del servicio de televisi\u00f3n, la Comisi\u00f3n Nacional de Televisi\u00f3n reservar\u00e1 dichos espacios, previo concepto del Consejo Nacional Electoral. En el caso del servicio de radiodifusi\u00f3n, dicha reserva deber\u00e1 ser hecha por el Ministerio de Comunicaciones, en los mismos t\u00e9rminos.<\/font><\/p>\n<p align=\"justify\"><i><b><font face=\"Arial\" size=\"2\">*Nota Vigencia*<\/font><\/b><\/i><\/p>\n<table border=\"1\" width=\"100%\" id=\"table1\" cellspacing=\"0\" cellpadding=\"6\">\n<tr>\n<td>\n<p align=\"justify\"><i><font face=\"Arial\" size=\"2\">* El nombre, objeto, y funciones del Ministerio de Comunicaciones fueron redefinidos por los art\u00edculos<a class=\"hlk\" target=\"_blank\" rel=\"noopener\">17<\/a> y<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LEY 996 DE 2005 &nbsp; &nbsp; LEY 996 DE 2005 (noviembre 24 DE 2005) Por medio de la cual se reglamenta la elecci\u00f3n de Presidente de la Rep\u00fablica, de conformidad con el art\u00edculo 152 literal f) de la Constituci\u00f3n Pol\u00edtica de Colombia, y de acuerdo con lo establecido en el Acto Legislativo 02 de 2004, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-1068","post","type-post","status-publish","format-standard","hentry","category-leyes-2005"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/1068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/comments?post=1068"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/1068\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/media?parent=1068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/categories?post=1068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/tags?post=1068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}