{"id":1115,"date":"2020-11-24T19:24:06","date_gmt":"2020-11-24T19:24:06","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-1048-de-2006\/"},"modified":"2020-11-24T19:24:06","modified_gmt":"2020-11-24T19:24:06","slug":"ley-1048-de-2006","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-1048-de-2006\/","title":{"rendered":"LEY 1048 DE 2006"},"content":{"rendered":"<p>LEY 1048 DE 2006            <\/a><\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><b><font size=\"2\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"http:\/\/dmsjuridica.com\/CODIGOS\/LEGISLACION\/LEYES\/2019\/dms.png\" width=\"138\" height=\"103\"align=\"center\"><\/p>\n<p align=\"center\"><b><font size=\"6\">&nbsp;LEY 1048 DE 2006<\/font><\/b><\/p>\n<p align=\"center\"><b><font size=\"2\">(julio 26)<\/font><\/b><\/p>\n<p align=\"center\"><b><font size=\"2\">Diario Oficial No. 46.341 de 26 de julio de 2006<\/font><\/b><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\"><b><font size=\"2\">CONGRESO DE LA REP\u00daBLICA<\/font><\/b><\/p>\n<p align=\"center\"><font size=\"2\">Por medio de la cual la Naci\u00f3n se asocia a la celebraci\u00f3n de los 40 a\u00f1os de la fundaci\u00f3n de la Comisar\u00eda Especial y actual departamento del Guain\u00eda y se dictan otras disposiciones.<\/font><\/p>\n<p><DIV>                     Application.addTitle(&#8216;Open a simple window&#8217;, &#8216;open_window1&#8217;)                      <\/p>\n<div class=\"listing\" style=\"display:none\" id=\"open_window1_codediv\">          var win = new Window({className: &quot;dialog&quot;, width:400, height:170, zIndex: 100, resizable: true, title: &quot;Buscar en este documento&quot;, showEffect:Effect.BlindDown, hideEffect: Effect.SwitchOff, draggable:true, wiredDrag: true}) win.getContent().innerHTML= &quot;<\/p>\n<div style=\"padding:10px\">\n<div align=\"left\"><font face=\"Arial\" color=\"#FFFFFF\" size=\"3\"><b>Busqueda:<\/b><\/font><\/p>\n<p><font size=\"2\">Nota: Esta funci\u00f3n solo sirve en el navegador Internet Explorer versi\u00f3n 6.0 en adelante. &#8211; No funciona en exploradores como Mozilla Firefox y Google Chrome, para la B\u00fasqueda tener en cuenta las tildes.<\/font><\/div>\n<\/div>\n<p>&quot; win.setStatusBar(&quot;DMS Ediciones e Investigaciones&quot;); win.showCenter();                                        <\/p><\/div>\n<p>.dvhdr1 {background:#F3F0E7;font-family:arial;font-size:12px;font-weight:bold;border:1px solid #C8BA92;padding:5px;width:150px; } .dvbdy1 {background:#FFFFFF;font-family:arial;font-size:12px;border-left:1px solid #C8BA92;border-right:1px solid #C8BA92;border-bottom:1px solid #C8BA92;padding:5px;width:150px; }  .dogvdvbdy {width:300;background:#FFFFFF;border-left:1px solid #C4D5E3;border-right:1px solid #C4D5E3;border-bottom:1px solid #C4D5E3;padding:10px; } .dogvdvhdr {width:300;background:#C4D5E3;border:1px solid #C4D5E3;font-weight:bold;padding:10px; }<\/p>\n<div class=\"Section1\">\n<table cellpadding=\"0\" cellspacing=\"0\" width=\"257\" height=\"19\">\n<tr>\n<td height=\"19\" width=\"91\" valign=\"top\">\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"left\"><font size=\"2\" face=\"Arial\"><b>var isReady = false;function doSaveAs(){if (document.execCommand){if (isReady){document.execCommand(&#8220;SaveAs&#8221;);}}else{alert(&#8216;Esta opcion solo funciona con Internet Exlorer 4.0 o posteriores.&#8217;);}}function downloadme(x){document.execCommand(&#8216;SaveAs&#8217;,&#8221;,x);}<\/b><b><a hrefx=\"javascript:downloadme();\"> <a style=\"text-decoration: none\" hrefx=\"javascript:downloadme();\">Guardar<\/a><\/b><\/font> <font size=\"2\" face=\"Arial\">&nbsp;<\/font><\/td>\n<td height=\"19\" width=\"85\" valign=\"top\">\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"left\"><b><a style=\"text-decoration: none\" hrefx=\"javascript:print()\"><font size=\"2\" face=\"Arial\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"printer.png\" width=\"16\" height=\"16\"> Imprimir <\/font><\/a><\/b><\/td>\n<td height=\"19\" width=\"81\" valign=\"top\"><b><font size=\"2\" face=\"Arial\">&nbsp;            <a style=\"text-decoration: none\" hrefx=\"javascript:new_window('http:\/\/www.dmsjuridica.com\/semana juridica\/envioCorreos\/envio.php?url=')\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"email_open.png\" width=\"16\" height=\"16\"> E-Mail<\/a><\/font><\/b><\/td>\n<\/tr>\n<\/table>\n<p align=\"center\"><b><font size=\"2\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"http:\/\/dmsjuridica.com\/CODIGOS\/LEGISLACION\/LEYES\/2019\/dms.png\" width=\"138\" height=\"103\"align=\"center\"><\/p>\n<p><\/font><\/b><\/p>\n<p align=\"center\"><font size=\"6\"><b>LEY 1049 DE 2006<\/b><\/font><\/p>\n<p align=\"center\"><b><font size=\"2\">(julio 26)<\/font><\/b><\/p>\n<p align=\"center\"><b><font size=\"2\">Diario Oficial No. 46.341 de 26 de julio de 2006<\/font><\/b><\/p>\n<div>&nbsp;<\/div>\n<p align=\"center\"><b><font size=\"2\">CONGRESO DE LA REP\u00daBLICA<\/font><\/b><\/p>\n<p align=\"center\"><font size=\"2\">Por medio de la cual la Naci\u00f3n se asocia y rinde homenaje al municipio de Cartago, en el departamento del Valle, con motivo de la celebraci\u00f3n de los cuatrocientos sesenta y cuatro (464) a\u00f1os de su fundaci\u00f3n, exalta la capacidad creadora y el esp\u00edritu de su gente y se dictan otras disposiciones.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"center\"><b><font size=\"2\">EL CONGRESO DE COLOMBIA<\/font><\/b><\/p>\n<p align=\"center\"><b><font size=\"2\">DECRETA<\/font><\/b><font size=\"2\">:<\/font><\/p>\n<p align=\"justify\"><a name=\"1\"><b><font size=\"2\">ART\u00cdCULO 1o.<\/font><\/b><\/a><font size=\"2\"> La Naci\u00f3n se asocia a la conmemoraci\u00f3n y rinde p\u00fablico homenaje, al Municipio de Cartago, en el Departamento del Valle, con motivo de la conmemoraci\u00f3n de los cuatrocientos sesenta y cuatro (464) a\u00f1os de su fundaci\u00f3n, ocurrida el 9 de agosto de 1540, y exalta la memoria de su fundador, el Conquistador y Mariscal de Campo Jorge Robledo.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"justify\"><a name=\"2\"><b><font size=\"2\">ART\u00cdCULO 2o.<\/font><\/b><\/a><font size=\"2\"> El Gobierno Nacional y el Congreso de la Rep\u00fablica rendir\u00e1n honores al Municipio de Cartago, en la fecha que las autoridades locales se\u00f1alen para el efecto, y har\u00e1n presencia con comisiones integradas por miembros del Gobierno Nacional y el Congreso de la Rep\u00fablica.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"justify\"><a name=\"3\"><b><font size=\"2\">ART\u00cdCULO 3o.<\/font><\/b><\/a><font size=\"2\"> Decl\u00e1rense monumento nacional y parte del patrimonio cultural de Colombia los siguientes inmuebles, situados en el Municipio de Cartago:<\/font><\/p>\n<p> <font size=\"2\">Iglesia San Jer\u00f3nimo<\/font> <font size=\"2\">Iglesia Santa Ana<\/font> <font size=\"2\">Iglesia San Francisco<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"justify\"><a name=\"4\"><b><font size=\"2\">ART\u00cdCULO 4o.<\/font><\/b><\/a><font size=\"2\"> Con el fin de promocionar y exaltar la labor desarrollada por los artesanos del Bordado de Cartago y para mantener viva esta tradici\u00f3n, as\u00ed como el evento conocido como \u201cFamilias que Cantan\u201d, el Ministerio de Cultura, en asocio de la Alcald\u00eda Municipal, reconocer\u00e1 a los artesanos del bordado y a los artistas que participan en el evento musical, los est\u00edmulos consagrados en el art\u00edculo <b><a hrefx=\"L0397_97.HTM#18\">18<\/a><\/b> de la Ley 397 de 1997, de conformidad con autonom\u00eda y competencia del Ministerio.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"justify\"><a name=\"5\"><b><font size=\"2\">ART\u00cdCULO 5o.<\/font><\/b><\/a><font size=\"2\"> En cumplimiento del art\u00edculo <b><a hrefx=\"L0715001.HTM#102\">102<\/a><\/b> de la Ley 715 de 2001, autor\u00edcese al Gobierno Nacional para asignar, en el presupuesto general de la Naci\u00f3n las partidas necesarias, a fin de adelantar las siguientes obras de inter\u00e9s social y de beneficio para la comunidad del Municipio de Cartago:<\/font><\/p>\n<p> <font size=\"2\">Construcci\u00f3n de la Terminal de Transportes del Municipio de Cartago.<\/font> <font size=\"2\">Adecuaci\u00f3n y remodelacion de la Iglesia Guadalupe, patrimonio hist\u00f3rico y monumento nacional.<\/font> <\/p>\n<p align=\"justify\"><font size=\"2\">Adecuaci\u00f3n y remodelacion del Estadio de Cartago y construcci\u00f3n de canchas deportivas.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"justify\"><a name=\"6\"><b><font size=\"2\">ART\u00cdCULO 6o.<\/font><\/b><\/a><font size=\"2\"> Las autorizaciones de gasto otorgadas al Gobierno Nacional en virtud de esta ley, se incorporar\u00e1n en los Presupuestos Generales de la Naci\u00f3n, de acuerdo con las normas org\u00e1nicas en materia presupuestal, en primer lugar, reasignando los recursos hoy existentes en cada \u00f3rgano ejecutor, sin que ello implique un aumento del presupuesto. Y en segundo lugar, de acuerdo con las disponibilidades que se produzcan en cada vigencia fiscal.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"justify\"><a name=\"7\"><b><font size=\"2\">ART\u00cdCULO 7o.<\/font><\/b><\/a><font size=\"2\"> Las entidades financieras y de fomento de naturaleza p\u00fablica de Colombia, en el \u00e1mbito de sus competencias, podr\u00e1n establecer condiciones especiales de financiamiento para proyectos o programas propuestos por empresarios, cooperativas, asociaci\u00f3n de peque\u00f1os productores, microempresarios, mujeres cabeza de hogar, asociaciones de tercera edad y j\u00f3venes, que tengan como finalidad desarrollar empresas en los campos de artesan\u00edas y ladrilleras en la ciudad de Cartago.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"justify\"><a name=\"8\"><b><font size=\"2\">ART\u00cdCULO 8o.<\/font><\/b><\/a><font size=\"2\"> Autor\u00edcese al Gobierno Nacional para incluir, a partir de la vigencia de la presente ley, a Cartago en el Mapa Tur\u00edstico de la Regi\u00f3n y a incluir al Municipio dentro de las caravanas tur\u00edsticas que programe el Ministerio de Comercio, Industria y Turismo.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p> <a name=\"9\"><b><font size=\"2\">ART\u00cdCULO 9o.<\/font><\/b><\/a><font size=\"2\"> La presente ley rige a partir de su sanci\u00f3n.<\/font><\/p>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">La Presidenta del honorable Senado de la Rep\u00fablica,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">CLAUDIA BLUM DE BARBERI.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">El Secretario General del honorable Senado de la Rep\u00fablica,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">EMILIO RAM\u00d3N OTERO DAJUD.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">El Presidente de la honorable C\u00e1mara de Representantes,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">JULIO E. GALLARDO ARCHBOLD.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">El Secretario General de la honorable C\u00e1mara de Representantes,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">ANGELINO LIZCANO RIVERA.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">REPUBLICA DE COLOMBIA \u2013 GOBIERNO NACIONAL<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">Publ\u00edquese y c\u00famplase.<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">Dada en Bogot\u00e1, D. C., a 26 de julio de 2006.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\">\u00c1LVARO URIBE V\u00c9LEZ.<\/font><\/b><\/p>\n<div>&nbsp;<\/div>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">El Ministro de Hacienda y Cr\u00e9dito P\u00fablico,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">ALBERTO CARRASQUILLA BARRERA.<\/font><\/p>\n<div>&nbsp;<\/div>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">La Ministra de Cultura,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">ELVIRA CUERVO DE JARAMILLO.<\/font><\/div>\n<p>&nbsp;<\/DIV> <\/p>\n<p align=\"center\"><b><font size=\"2\">EL CONGRESO DE LA REP\u00daBLICA<\/font><\/b><\/p>\n<p align=\"center\"><b><font size=\"2\">DECRETA<\/font><\/b><font size=\"2\">:<\/font><\/p>\n<p align=\"justify\"><A name=1><b><font size=\"2\">ART\u00cdCULO 1o.<\/font><\/b><\/A><font size=\"2\"> La Naci\u00f3n se asocia a la celebraci\u00f3n de los cuarenta a\u00f1os de fundaci\u00f3n del departamento de Guain\u00eda y rinde homenaje a la memoria de sus fundadores mediante reconocimiento p\u00fablico y ceremonia especial en la cual se har\u00e1 la respectiva entrega e imposici\u00f3n de las condecoraciones a los homenajeados.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><A name=2><b><font size=\"2\">ART\u00cdCULO 2o.<\/font><\/b><\/A><font size=\"2\"> Autor\u00edzase al Gobierno Nacional para que, bajo los principios de coordinaci\u00f3n, concurrencia y subsidiaridad, incluya, dentro del Presupuesto General de la Naci\u00f3n vigencia 2006, apropiaciones presupuestales que permitan la realizaci\u00f3n de las siguientes obras de inter\u00e9s social:<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">Construcci\u00f3n del Centro departamental de discapacitados en el municipio de In\u00edrida.<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">Construcci\u00f3n del Centro de atenci\u00f3n al ni\u00f1o especial en el municipio de In\u00edrida.<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">Construcci\u00f3n y dotaci\u00f3n del Centro de Adulto Mayor.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><A name=3><b><font size=\"2\">ART\u00cdCULO 3o.<\/font><\/b><\/A><font size=\"2\"> A partir de la entrada en vigencia de la presente ley, decl\u00e1rase patrimonio cultural y arqueol\u00f3gico de la Naci\u00f3n, los Cerros de Mavicure (Leyenda de la Princesa In\u00edrida), el Fuerte de San Felipe y los petroglifos ubicados en Caranacoa r\u00edo Guain\u00eda, Merey r\u00edo Atabapo, Tonina r\u00edo Guain\u00eda, Raudal Guacamaya r\u00edo Gua\u00edn\u00eda, Raudal Guarinuma r\u00edo Guain\u00eda, Coco Viejo r\u00edo In\u00edrida, Campo Alegre r\u00edo Cuyar\u00ed y Raudal Pi\u00f1a Ca\u00f1o Yar\u00ed.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\"><A name=4><b><font size=\"2\">ART\u00cdCULO 4o.<\/font><\/b><\/A><font size=\"2\"> La presente ley rige a partir de su promulgaci\u00f3n, sanci\u00f3n y deroga todas las disposiciones que le sean contrarias.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">La Presidenta del honorable Senado de la Rep\u00fablica,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">CLAUDIA BLUM DE BARBERI.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">El Secretario General del honorable Senado de la Rep\u00fablica,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">EMILIO RAM\u00d3N OTERO DAJUD.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">El Presidente de la honorable C\u00e1mara de Representantes,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">JULIO E. GALLARDO ARCHBOLD.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">El Secretario General de la honorable C\u00e1mara de Representantes,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">ANGELINO LIZCANO RIVERA.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">REPUBLICA DE COLOMBIA \u2013 GOBIERNO NACIONAL<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">Publ\u00edquese y c\u00famplase.<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">Dada en Bogot\u00e1, D. C., a 26 de julio de 2006.<\/font><\/p>\n<p> <DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\">\u00c1LVARO URIBE V\u00c9LEZ.<\/font><\/b><\/p>\n<p> <DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">El Ministro de Hacienda y Cr\u00e9dito P\u00fablico,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">ALBERTO CARRASQUILLA BARRERA.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">La Ministra de Cultura,<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\">ELVIRA CUERVO DE JARAMILLO.<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LEY 1048 DE 2006 &nbsp; &nbsp;LEY 1048 DE 2006 (julio 26) Diario Oficial No. 46.341 de 26 de julio de 2006 &nbsp; CONGRESO DE LA REP\u00daBLICA Por medio de la cual la Naci\u00f3n se asocia a la celebraci\u00f3n de los 40 a\u00f1os de la fundaci\u00f3n de la Comisar\u00eda Especial y actual departamento del Guain\u00eda y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1115","post","type-post","status-publish","format-standard","hentry","category-leyes-2006"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/1115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/comments?post=1115"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/1115\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/media?parent=1115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/categories?post=1115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/tags?post=1115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}