{"id":3742,"date":"2023-11-10T20:05:45","date_gmt":"2023-11-10T20:05:45","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2023\/11\/10\/ley-9-de-1971\/"},"modified":"2023-11-10T20:05:45","modified_gmt":"2023-11-10T20:05:45","slug":"ley-9-de-1971","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2023\/11\/10\/ley-9-de-1971\/","title":{"rendered":"LEY 9 DE 1971"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>LEY 9 DE 1971 \u00a0<\/p>\n<p>(septiembre 22 \u00a0 DE 1971)<\/p>\n<p>\u00a0 \u00a0 por la cual se fomentan los Colegios Cooperativos para la educaci\u00f3n popular.<\/p>\n<p>El Congreso de Colombia<\/p>\n<p>DECRETA \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1. Con el objeto de hacer efectiva la democracia de participaci\u00f3n en el \u00a0 \u00a0 sector educativo, de crear nuevas oportunidades educativas a favor de los \u00a0 \u00a0 sectores populares y de abaratar los costos de la educaci\u00f3n, el Gobierno, a \u00a0 \u00a0 trav\u00e9s del Ministerio de Educaci\u00f3n Nacional y la Superintendencia Nacional de \u00a0 \u00a0 Cooperativas, fomentar\u00e1 los Institutos docentes de car\u00e1cter cooperativo o \u00a0 \u00a0 mutuario.<\/p>\n<p>Art\u00edculo 2. Los beneficios y derechos consagrados en la presente Ley son \u00a0 \u00a0 exclusivamente aplicables a los institutos docentes de propiedad de una \u00a0 \u00a0 cooperativa o mutualidad, cuyos socios, al menos en un ochenta por ciento (80%), \u00a0 \u00a0 sean las personas de quienes dependen econ\u00f3micamente los alumnos matriculados, \u00a0 \u00a0 inscritos o que cursen estudios en el respectivo plantel.<\/p>\n<p>Art\u00edculo 3. Los establecimientos a que se refiere la presente Ley tendr\u00e1n, entre \u00a0 \u00a0 otros, los siguientes beneficios:<\/p>\n<p>\u00a0 \u00a0 1. El Banco Popular, el Instituto de Financiamiento Cooperativo, el Fondo de \u00a0 \u00a0 Progreso Educativo y, en general, las entidades p\u00fablicas dedicadas al cr\u00e9dito \u00a0 \u00a0 educativo tendr\u00e1n una l\u00ednea especial de cr\u00e9dito para su financiaci\u00f3n. \u00a0<\/p>\n<p>2. Se les dar\u00e1 prelaci\u00f3n en el otorgamiento de auxilios oficiales, en dinero y \u00a0 \u00a0 en dotaci\u00f3n, materiales y equipos. \u00a0<\/p>\n<p>3. Se les prestar\u00e1 asesor\u00eda t\u00e9cnica, cooperativa y pedag\u00f3gica para su \u00a0 \u00a0 constituci\u00f3n y funcionamiento. \u00a0<\/p>\n<p>4. El Instituto de Cr\u00e9dito Territorial, el Instituto Colombiano de \u00a0 \u00a0 Construcciones Escolares, el Banco Central Hipotecario y las compa\u00f1\u00edas de \u00a0 \u00a0 seguros desarrollar\u00e1n planes preferenciales de construcci\u00f3n y dotaci\u00f3n a favor \u00a0 \u00a0 de ellos. \u00a0<\/p>\n<p>5. Gozar\u00e1n de tarifas m\u00ednimas para la utilizaci\u00f3n de servicios p\u00fablicos, como \u00a0 \u00a0 energ\u00eda el\u00e9ctrica, agua, luz, tel\u00e9fono, alcantarillado y aseo. \u00a0<\/p>\n<p>6. Tendr\u00e1n derecho a utilizar en horas libres los campos de instalaciones \u00a0 \u00a0 deportivas de los institutos oficiales de educaci\u00f3n.\u00a0<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 4. La inspecci\u00f3n y vigilancia de los institutos de que trata la \u00a0 \u00a0 presente Ley estar\u00e1 a cargo del Ministerio de Educaci\u00f3n Nacional y de la \u00a0 \u00a0 Superintendencia Nacional de Cooperativas, cada uno dentro de su respectiva \u00a0 \u00a0 competencia.<\/p>\n<p>Art\u00edculo 5. Para el cumplimiento de las funciones encomendadas al Ministerio de \u00a0 \u00a0 Educaci\u00f3n Nacional en esta Ley, se crear\u00e1n en dicho Ministerio, o en uno de los \u00a0 \u00a0 organismos a \u00e9l adscritos, una divisi\u00f3n especializada.<\/p>\n<p>Art\u00edculo 6. La Naci\u00f3n, los Departamentos y los Municipios, previo concepto \u00a0 \u00a0 favorable del Consejo Superior de Educaci\u00f3n, podr\u00e1n ceder a cooperativas o \u00a0 \u00a0 mutualidades de padres de familia que se organicen de acuerdo con lo previsto en \u00a0 \u00a0 la presente Ley, algunos de los planteles nacionales, departamentales, \u00a0 \u00a0 distritales o municipales, as\u00ed como terrenos, edificios o locales, con el objeto \u00a0 \u00a0 de establecer institutos pilotos que fomenten la democracia de participaci\u00f3n en \u00a0 \u00a0 el sector educativo.<\/p>\n<p>Art\u00edculo 7. Autor\u00edzase al Gobierno para hacer las apropiaciones, efectuar los \u00a0 \u00a0 traslados y abrir los cr\u00e9ditos y contracr\u00e9ditos al Presupuesto Nacional, \u00a0 \u00a0 necesarios para el debido cumplimiento de esta Ley.<\/p>\n<p>Art\u00edculo 8. Esta Ley rige desde su promulgaci\u00f3n. \u00a0<\/p>\n<p>Dada en Bogot\u00e1, D.C., a 6 de septiembre de 1971.<\/p>\n<p>\u00a0 \u00a0 El Presidente del Senado, \u00a0<\/p>\n<p>EDUARDO ABUCHAIBE OCHOA. \u00a0<\/p>\n<p>El Presidente de la C\u00e1mara de \u00a0 \u00a0 Representantes, \u00a0<\/p>\n<p>GILBERTO SALAZAR RAM\u00cdREZ. \u00a0<\/p>\n<p>El Secretario del Senado, \u00a0<\/p>\n<p>Amauty \u00a0 \u00a0 Guerrero. \u00a0<\/p>\n<p>El Secretario de la C\u00e1mara de Representantes, \u00a0<\/p>\n<p>Eusebio Cabrales Pineda.<\/p>\n<p>\u00a0 \u00a0 Rep\u00fablica de Colombia.-Gobierno Nacional.<\/p>\n<p>\u00a0 \u00a0 Bogot\u00e1, D.C., 22 de septiembre de 1971.<\/p>\n<p>\u00a0 \u00a0 Publ\u00edquese y ejec\u00fatese,<\/p>\n<p>\u00a0 \u00a0 MISAEL PASTRANA BORRERO<\/p>\n<p>\u00a0 \u00a0 El Ministro de Hacienda y Cr\u00e9dito P\u00fablico, \u00a0<\/p>\n<p>Rodrigo Llorente Mart\u00ednez. \u00a0<\/p>\n<p>El \u00a0 \u00a0 Ministro de Trabajo y Seguridad Social, \u00a0<\/p>\n<p>Crisp\u00edn Villaz\u00f3n de Armas. \u00a0<\/p>\n<p>El Ministro \u00a0 \u00a0 de Educaci\u00f3n Nacional, \u00a0<\/p>\n<p>Luis Carlos Gal\u00e1n Sarmiento. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 LEY 9 DE 1971 \u00a0 (septiembre 22 \u00a0 DE 1971) \u00a0 \u00a0 por la cual se fomentan los Colegios Cooperativos para la educaci\u00f3n popular. El Congreso de Colombia DECRETA \u00a0 \u00a0 Art\u00edculo 1. Con el objeto de hacer efectiva la democracia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[112],"tags":[],"class_list":["post-3742","post","type-post","status-publish","format-standard","hentry","category-leyes-1971"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/3742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/comments?post=3742"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/3742\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/media?parent=3742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/categories?post=3742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/tags?post=3742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}