{"id":3833,"date":"2024-02-06T21:52:02","date_gmt":"2024-02-06T21:52:02","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2024\/02\/06\/ley-6-de-1973\/"},"modified":"2024-02-06T21:52:02","modified_gmt":"2024-02-06T21:52:02","slug":"ley-6-de-1973","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2024\/02\/06\/ley-6-de-1973\/","title":{"rendered":"LEY 6 DE 1973"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>LEY 6 DE 1973<\/p>\n<p>\u00a0 \u00a0 (abril 2)<\/p>\n<p>\u00a0 \u00a0 por la cual se crean est\u00edmulos tributarios para las sociedades an\u00f3nimas, se \u00a0 \u00a0 aumentan las excepciones personales y se dictan otras disposiciones en materia \u00a0 \u00a0 tributaria.<\/p>\n<p>\u00a0 \u00a0 El Congreso de Colombia,<\/p>\n<p>\u00a0 \u00a0 DECRETA: \u00a0 \u00a0<\/p>\n<p>Art\u00edculo 1. La tarifa del impuesto b\u00e1sico de renta de las sociedades colectivas, \u00a0 \u00a0 ordinarias de minas, sociedades de hecho, comunidades ordinarias organizadas y \u00a0 \u00a0 de las corporaciones o asociaciones y fundaciones ser\u00e1 del cuatro por ciento \u00a0 \u00a0 (4%) sobre las renta l\u00edquida gravable hasta $60.000.00 y del seis por ciento \u00a0 \u00a0 (6%) sobre el exceso de $60.000.00 de la renta l\u00edquida gravable.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 2. La tarifa del impuesto b\u00e1sico de renta de las sociedades de \u00a0 \u00a0 responsabilidad limitada, en comandita simple y de hecho, que participen de la \u00a0 \u00a0 naturaleza de las anteriores ser\u00e1 del cuatro por ciento (4%) sobre los primeros \u00a0 \u00a0 $60.000.00 de la renta l\u00edquida gravable, del seis por ciento (6%) sobre el \u00a0 \u00a0 exceso de $60.000.00 y hasta $100.000.00 de la renta liquida gravable; del ocho \u00a0 \u00a0 por ciento (8%) sobre el exceso de cien mil pesos ($100.000.00) y hasta \u00a0 \u00a0 trescientos mil pesos ($300.000.00) de la renta l\u00edquida gravable; del doce por \u00a0 \u00a0 ciento (12%) sobre el exceso de trescientos mil pesos ($300.000.00) y hasta \u00a0 \u00a0 quinientos mil pesos ($500.000.00) de la renta l\u00edquida gravable, y del diecis\u00e9is \u00a0 \u00a0 por ciento (16%) sobre la renta l\u00edquida gravable que exceda de quinientos mil \u00a0 \u00a0 pesos ($500.000.00) hasta un mill\u00f3n ($1.000.000.00) sobre la renta l\u00edquida \u00a0 \u00a0 gravable y del veinte por ciento (20%) sobre la renta l\u00edquida gravable que \u00a0 \u00a0 exceda de un mill\u00f3n ($1.000.000.00).<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 3. La escala del patrimonio b\u00e1sico para el exceso de utilidades y la \u00a0 \u00a0 tarifa para el impuesto correspondiente, a que se refieren los art\u00edculos 82 y 83 \u00a0 \u00a0 de la 81 de 1960, y art\u00edculo 227 del Decreto 437 de 1961 ser\u00e1n las siguientes:<\/p>\n<p>\u00a0 \u00a0 Patrimonio b\u00e1sico para el exceso de utilidades.<\/p>\n<p>\u00a0 \u00a0 50% cuando el patrimonio b\u00e1sico sea superior a $200.000.00 y no pase de $ \u00a0 \u00a0 300.000.00;<\/p>\n<p>\u00a0 \u00a0 40% cuando el patrimonio b\u00e1sico sea superior a $300.000.00 y no pase de \u00a0 \u00a0 $400.000.00, 35% cuando el patrimonio b\u00e1sico sea superior a $ 400.000.00 y no \u00a0 \u00a0 pase de $500.000.00; 30% cuando el patrimonio b\u00e1sico sea superior a $500.000.00 \u00a0 \u00a0 y no pase de $600.000.00; 28% cuando el patrimonio b\u00e1sico sea superior a \u00a0 \u00a0 $600.000.00 y no pase de $1.000.000.00, 26% cuando el patrimonio b\u00e1sico sea \u00a0 \u00a0 superior a $1.000.000.00.<\/p>\n<p>\u00a0 \u00a0 Tarifas de exceso de utilidades.<\/p>\n<p>\u00a0 \u00a0 10% del exceso de utilidades que representen hasta el 10% del patrimonio b\u00e1sico.<\/p>\n<p>\u00a0 \u00a0 20% del exceso de utilidades que representen m\u00e1s del 10% sin pasar del 24% del \u00a0 \u00a0 patrimonio b\u00e1sico.<\/p>\n<p>\u00a0 \u00a0 30% del exceso de utilidades que represente m\u00e1s del 24% sin pasar del 26% del \u00a0 \u00a0 patrimonio b\u00e1sico.<\/p>\n<p>\u00a0 \u00a0 40% del exceso de utilidades que representen m\u00e1s del 28% sin pasar del 35% del<\/p>\n<p>\u00a0 \u00a0 patrimonio b\u00e1sico.<\/p>\n<p>\u00a0 \u00a0 45% del exceso de utilidades que represente m\u00e1s del 35% sin pasar del 40% del \u00a0 \u00a0 patrimonio b\u00e1sico.<\/p>\n<p>\u00a0 \u00a0 50% del exceso de utilidades que represente m\u00e1s del 40% sin pasar del 50% del \u00a0 \u00a0 patrimonio b\u00e1sico.<\/p>\n<p>\u00a0 \u00a0 Par\u00e1grafo 1. No habr\u00e1 lugar al pago del impuesto de exceso de utilidades \u00a0 \u00a0 respecto de los contribuyentes que inviertan la suma correspondiente a dicho \u00a0 \u00a0 gravamen dentro del a\u00f1o en que se presenta la declaraci\u00f3n respectiva, con base \u00a0 \u00a0 en su liquidaci\u00f3n privada, en C\u00e9dulas del Banco Central Hipotecario, Bonos de \u00a0 \u00a0 Instituto de Cr\u00e9dito Territorial, Bonos o Acciones de nuevas emisiones \u00a0 \u00a0 efectuadas por sociedades an\u00f3nimas.<\/p>\n<p>\u00a0 \u00a0 Bonos de Corporaciones financieras, Unidades del Fondo Nacional de inversiones, \u00a0 \u00a0 ensanches de la propia empresa y otras inversiones que se\u00f1ale el Consejo de \u00a0 \u00a0 Pol\u00edtica Econ\u00f3mica y social.<\/p>\n<p>\u00a0 \u00a0 Par\u00e1grafo 2. La inversi\u00f3n autorizada en el par\u00e1grafo primero deber\u00e1 mantenerse \u00a0 \u00a0 por un per\u00edodo no inferior a un a\u00f1o.<\/p>\n<p>\u00a0 \u00a0 Par\u00e1grafo 3. Modificase el art\u00edculo 81 de la Ley 81 de 1960 en los siguientes \u00a0 \u00a0 t\u00e9rminos: no est\u00e1n sometidos al impuesto complementario de exceso de utilidades \u00a0 \u00a0 las rentas de personas naturales o jur\u00eddicas, cuyo patrimonio b\u00e1sico no pase de \u00a0 \u00a0 doscientos mil pesos ($200.000.00).<\/p>\n<p>\u00a0 \u00a0 Par\u00e1grafo 4. En caso de diferencia entre la liquidaci\u00f3n definitiva y la privada \u00a0 \u00a0 se har\u00e1n los ajustes correspondientes y podr\u00e1 efectuarse la inversi\u00f3n \u00a0 \u00a0 sustitutiva de que trata el par\u00e1grafo primero de este art\u00edculo dentro del plazo \u00a0 \u00a0 que el contribuyente tiene para el pago del gravamen resultante de la \u00a0 \u00a0 liquidaci\u00f3n definitiva.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 4. El art\u00edculo 12 de la Ley 81 de 1960 quedar\u00e1 as\u00ed:<\/p>\n<p>\u00a0 \u00a0 Las Corporaciones o Asociaciones y las Fundaciones est\u00e1n sometidas al impuesto \u00a0 \u00a0 b\u00e1sico sobre la renta, establecido por el art\u00edculo 1 de esta Ley, pero solo en \u00a0 \u00a0 el caso de que obtengan utilidades con fines de lucro, o sea, cuando perciban \u00a0 \u00a0 rentas que, en todo o en parte, puedan ser distribuidas como utilidad a personas \u00a0 \u00a0 naturales, en cualquier tiempo o en el momento de su liquidaci\u00f3n, bien \u00a0 \u00a0 directamente o por intermedio de otras personas jur\u00eddicas.<\/p>\n<p>\u00a0 \u00a0 As\u00ed mismo, en el caso de que las instituciones a que este art\u00edculo se refiere \u00a0 \u00a0 persigan fines de lucro a sus asociados se les gravar\u00e1 de la misma manera como a \u00a0 \u00a0 los socios de las sociedades de personas, conforme a lo establecido en el \u00a0 \u00a0 literal b) del art\u00edculo 26 de la Ley 81 de 1960.<\/p>\n<p>\u00a0 \u00a0 Par\u00e1grafo 1. Las Corporaciones o Asociaciones y las fundaciones sometidas por la \u00a0 \u00a0 Ley a la inspecci\u00f3n del Gobierno Nacional, para quedar exentas del impuesto \u00a0 \u00a0 sobre la renta, deben acreditar su registro en la oficina encargada de dicha \u00a0 \u00a0 inspecci\u00f3n o vigilancia.<\/p>\n<p>\u00a0 \u00a0 Par\u00e1grafo 2. Derogase el art\u00edculo 30 de la Ley 81 de 1960.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 5. Toda sociedad an\u00f3nima podr\u00e1 constituir, adem\u00e1s de las reservas \u00a0 \u00a0 autorizadas por la Ley, una reserva extraordinaria de capitalizaci\u00f3n econ\u00f3mica \u00a0 \u00a0 hasta del 10% anual de sus utilidades l\u00edquidas o sea de las mismas que sirven de \u00a0 \u00a0 base para la apropiaci\u00f3n de la reserva legal, con el fin de invertirla en bienes \u00a0 \u00a0 de producci\u00f3n o cancelaci\u00f3n de pasivos originados en la adquisici\u00f3n de los \u00a0 \u00a0 mismos bienes.\u00a0<\/p>\n<p>\u00a0 \u00a0 Esta reserva se considerar\u00e1 exenta del impuesto sobre la renta, siempre que se \u00a0 \u00a0 compruebe que ha sido efectivamente apropiada, contabilizada y destinada para \u00a0 \u00a0 los fines indicados en este art\u00edculo durante el a\u00f1o inmediatamente siguiente a \u00a0 \u00a0 aqu\u00e9l en que se hubiere constituido.<\/p>\n<p>\u00a0 \u00a0 Si por cualquier circunstancia, todo o parte de la reserva a que se refiere este \u00a0 \u00a0 art\u00edculo se repartiere a los accionistas, en el a\u00f1o en que tal hecho suceda, se \u00a0 \u00a0 tendr\u00e1 como renta gravable, tanto de la compa\u00f1\u00eda como de los socios, la \u00a0 \u00a0 totalidad de las reservas aceptadas como rentas exentas y que se repartan, \u00a0 \u00a0 cualesquiera que fueren los a\u00f1os en que se hubieren constituido.<\/p>\n<p>\u00a0 \u00a0 Par\u00e1grafo 2. Toda sociedad de responsabilidad limitada, en comandita simple o \u00a0 \u00a0 por acciones, colectivas y las fundaciones con \u00e1nimo de lucro tendr\u00e1n derecho a \u00a0 \u00a0 la reserva a que se refiere este art\u00edculo, siempre y cuando se someta \u00a0 \u00a0 voluntariamente a la vigilancia de la Superintendecia respectiva.<\/p>\n<p>\u00a0 \u00a0 Par\u00e1grafo 3. La reserva establecida en el art\u00edculo 5 de la presente ley es \u00a0 \u00a0 sustitutiva de la reserva de fomento econ\u00f3mico establecida en el art\u00edculo 109 de \u00a0 \u00a0 la Ley 81 de 1960 y prorrogada por el art\u00edculo 6 de la Ley 37 de 1969.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 6. Son exentos de impuestos b\u00e1sico de renta, los primeros treinta mil \u00a0 \u00a0 pesos ($30.000.00) de los dividendos pagados o abonados en cuenta por sociedades \u00a0 \u00a0 colombianas a personas naturales, sucesiones il\u00edquidadas, asignaciones y \u00a0 \u00a0 donaciones modales cuando el patrimonio l\u00edquido no exceda de dos millones de \u00a0 \u00a0 pesos ($2.000.000.00).<\/p>\n<p>\u00a0 \u00a0 En este sentido se modifica el numeral tercero del art\u00edculo 47 de la Ley 81 de \u00a0 \u00a0 1960 tal como fue subrogado por el art\u00edculo 21 del Decreto 1366 de 1967.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 7. Se consideran exentos del impuesto complementario del patrimonio los \u00a0 \u00a0 primeros trescientos mil pesos ($300.000.00) invertidos en acciones de \u00a0 \u00a0 sociedades an\u00f3nimas colombianas. En este sentido se modifica el ordinal 11 del \u00a0 \u00a0 art\u00edculo 36 del Decreto 1366 de 1967.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 8. La reducci\u00f3n gradual de las exenciones personales y por personas a \u00a0 \u00a0 cargo de que trata el par\u00e1grafo 2 del art\u00edculo 1 de la Ley 27 de 1969 se \u00a0 \u00a0 efectuar\u00e1 en una cantidad igual al veinte por ciento (20%) de la renta l\u00edquida \u00a0 \u00a0 que exceda de sesenta mil pesos ($60.000.00).<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 9. Se aceptar\u00e1n como exenciones personales especiales la totalidad de \u00a0 \u00a0 los pagos efectuados el a\u00f1o o per\u00edodo gravable por personas naturales o \u00a0 \u00a0 sucesiones il\u00edquidas a laboratorios cl\u00ednicos, hospitales o cl\u00ednicas, escuelas, \u00a0 \u00a0 colegios, universidades, m\u00e9dicos, odont\u00f3logos, abogados y a otros profesionales \u00a0 \u00a0 por servicios prestados al contribuyente, su c\u00f3nyuge o a las personas en \u00a0 \u00a0 relaci\u00f3n con los cuales tenga derecho a pedir exenciones por personas a cargo.<\/p>\n<p>\u00a0 \u00a0 Se aceptar\u00e1 igualmente como exenci\u00f3n personal especial, la totalidad de los \u00a0 \u00a0 pagos efectuados por concepto de arrendamientos de la casa o apartamento \u00a0 \u00a0 habitado por el contribuyente.<\/p>\n<p>\u00a0 \u00a0 Par\u00e1grafo 1. El monto total de las exenciones personales especiales se\u00f1aladas en \u00a0 \u00a0 este art\u00edculo ser\u00e1 reducido en la siguiente forma:<\/p>\n<p>\u00a0 \u00a0 a) Cuando la renta l\u00edquida sea superior a $50.000.00 y no exceda de $60.000.00 \u00a0 \u00a0 en el 10%.<\/p>\n<p>\u00a0 \u00a0 b) Cuando la renta l\u00edquida sea superior a $60.000.00 y no exceda de $70.000.00 \u00a0 \u00a0 en el 20%<\/p>\n<p>\u00a0 \u00a0 c) Cuando la renta l\u00edquida sea superior a $70.000.00 y no exceda de $80.000.00 \u00a0 \u00a0 en el 30%<\/p>\n<p>\u00a0 \u00a0 d) Cuando la renta l\u00edquida sea superior a $80.000.00 y no exceda de $90.000.00 \u00a0 \u00a0 en el 40%<\/p>\n<p>\u00a0 \u00a0 e) Cuando la renta l\u00edquida sea superior a $90.000.00 y no exceda de $100.000.00 \u00a0 \u00a0 en el 50%<\/p>\n<p>\u00a0 \u00a0 f) Cuando la renta l\u00edquida sea superior a $100.000.00 y no exceda de $150.000.00 \u00a0 \u00a0 en el 70%<\/p>\n<p>\u00a0 \u00a0 g) Cuando la renta l\u00edquida sea superior a $150.000.00 en el 80%<\/p>\n<p>\u00a0 \u00a0 par\u00e1grafo 2. A las exenciones personales especiales de que trata este art\u00edculo, \u00a0 \u00a0 le son aplicables las normas contenidas en el art\u00edculo 15\u00a0<\/p>\n<p>\u00a0 \u00a0 Decreto 1366 de 1967.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 10. El par\u00e1grafo 2 del art\u00edculo 26 de la Ley 81 de 1960 quedar\u00e1 as\u00ed:<\/p>\n<p>\u00a0 \u00a0 No obstante lo dispuesto en el literal a) de este art\u00edculo, cuando una persona \u00a0 \u00a0 natural posea m\u00e1s del 75% de las acciones de una sociedad an\u00f3nima o en comandita \u00a0 \u00a0 por acciones, se le considerar\u00e1 como dividendo la parte proporcional que le \u00a0 \u00a0 corresponde en la renta l\u00edquida gravable de la sociedad deduciendo de \u00e9sta el \u00a0 \u00a0 monto de la reserva legal m\u00ednima establecida en la ley, y el valor de los \u00a0 \u00a0 impuestos de renta y especiales, liquidados a la sociedad por el mismo a\u00f1o \u00a0 \u00a0 gravable.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 11. Para los efectos del impuesto sobre la renta, complementarios, \u00a0 \u00a0 recargos y especiales de los ciudadanos colombianos que integran las reservas de \u00a0 \u00a0 oficiales de primera y segunda clase de la Fuerza A\u00e9rea, mientras ejerzan \u00a0 \u00a0 actividades de piloto navegante o ingenieros de vuelo, en empresas a\u00e9reas \u00a0 \u00a0 nacionales de transporte p\u00fablico y de trabajos a\u00e9reos especiales, solamente \u00a0 \u00a0 constituyen renta gravable el sueldo b\u00e1sico que perciban de las respectivas \u00a0 \u00a0 empresas, con exclusi\u00f3n de las primas, bonificaciones, horas extras y dem\u00e1s \u00a0 \u00a0 complementos sal\u00e1riales, sin perjuicio de la exenciones generales se\u00f1aladas en \u00a0 \u00a0 la ley.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 12. Para tener derecho a la exenci\u00f3n prevista en el art\u00edculo anterior, \u00a0 \u00a0 el interesado debe acompa\u00f1ar a su declaraci\u00f3n de renta la certificaci\u00f3n expedida \u00a0 \u00a0 por el Comando de la Fuerza A\u00e9rea en la que conste su inscripci\u00f3n en el \u00a0 \u00a0 escalaf\u00f3n de la reserva a\u00e9rea militar.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 13. Cuando los funcionarios de impuestos constaten falta de alg\u00fan \u00a0 \u00a0 documento, certificado de paz y salvo, recibo o comprobante de pagos o aportes \u00a0 \u00a0 al Servicio Nacional de Aprendizaje (SENA), Instituto Colombiano de Seguros \u00a0 \u00a0 Sociales (ICSS), subsidio familiar, menci\u00f3n de \u201cNIT\u201d o alguna otra situaci\u00f3n que \u00a0 \u00a0 sea necesario aclarar, deber\u00e1n solicitar explicaciones al contribuyente fijando \u00a0 \u00a0 para ello un t\u00e9rmino prudencial.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 14. El art\u00edculo 27 del Decreto 1366 de 1967 quedar\u00e1 as\u00ed:<\/p>\n<p>\u00a0 \u00a0 Quien efect\u00fae pagos o abonos en cuenta a personas naturales o jur\u00eddicas \u00a0 \u00a0 residentes en el exterior por concepto de rentas gravables en Colombia \u00a0 \u00a0 diferentes de dividendos y participaciones, tales como intereses, \u00a0 \u00a0 arrendamientos, comisiones, regal\u00edas, asistencia t\u00e9cnica, etc., est\u00e1 obligado a \u00a0 \u00a0 retener y consignar un impuesto sobre la renta del 20% del valor nominal del \u00a0 \u00a0 pago o abono.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 15. El art\u00edculo 28 del Decreto 1366 de 1967 quedar\u00e1 as\u00ed: Las sociedades \u00a0 \u00a0 an\u00f3nimas o en comandita por acciones que paguen o abonen dividendos a compa\u00f1\u00edas \u00a0 \u00a0 u otras entidades extranjeras que no los distribuyan a su vez en el pa\u00eds, o a \u00a0 \u00a0 personas naturales no residentes en Colombia. Est\u00e1n obligadas a retener un \u00a0 \u00a0 impuesto sobre la renta del 20% del valor nominal del pago o abono.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 16. El art\u00edculo 29 del Decreto 1366 de 1967 quedar\u00e1 as\u00ed: Las sociedades \u00a0 \u00a0 diferentes de las an\u00f3nimas y en comandita por acciones, cuando parte de sus \u00a0 \u00a0 derechos sociales corresponda a compa\u00f1\u00edas u otras entidades extranjeras que no \u00a0 \u00a0 distribuyan los dividendos o las utilidades en el pa\u00eds, o a personas naturales \u00a0 \u00a0 no residentes en Colombia, est\u00e1n obligadas a tener un impuesto sobre la renta \u00a0 \u00a0 del veinte por ciento (20%) de las participaciones que a tales socios \u00a0 \u00a0 correspondan en la renta l\u00edquida gravable, previa deducci\u00f3n del impuesto \u00a0 \u00a0 liquidado a la sociedad.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 17. Los l\u00edmites de salarios establecidos en el art\u00edculo 8 de la Ley 63 \u00a0 \u00a0 de 1967 quedan aumentados en un treinta por ciento (30%) a partir de la vigencia \u00a0 \u00a0 de esta Ley y desde 1974 podr\u00e1n ser aumentados por el Ministerio de Hacienda y \u00a0 \u00a0 Cr\u00e9dito P\u00fablico en forma proporcional a los aumentos de los \u00edndices de precios \u00a0 \u00a0 internos con base en el a\u00f1o de 1973.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 18. Son exentos de impuesto b\u00e1sico de renta los primeros cinco mil \u00a0 \u00a0 pesos ($5.000.00), que se inviertan en el pago anual de la prima correspondiente \u00a0 \u00a0 al seguro de vida personal del contribuyente.\u00a0<\/p>\n<p>\u00a0 \u00a0 Par\u00e1grafo. El monto total de esta exenci\u00f3n se reduce en la siguiente forma:<\/p>\n<p>\u00a0 \u00a0 a) Cuando la renta l\u00edquida sea superior a $100.000.00 y no exceda de $120.000.00 \u00a0 \u00a0 en un 10%;<\/p>\n<p>\u00a0 \u00a0 b) Cuando la renta l\u00edquida sea superior a $120.000.00 y no exceda de $140.000.00 \u00a0 \u00a0 en un 20%;<\/p>\n<p>\u00a0 \u00a0 c) Cuando la renta l\u00edquida sea superior a $140.000.00 y no exceda de $160.000.00 \u00a0 \u00a0 en un 30%;<\/p>\n<p>\u00a0 \u00a0 d) Cuando la renta l\u00edquida sea superior a $160.000.00 y no exceda de $180.000.00 \u00a0 \u00a0 en un 40%;<\/p>\n<p>\u00a0 \u00a0 e) Cuando la renta l\u00edquida sea superior a $180.000.00 y no exceda de $200.000.00 \u00a0 \u00a0 en un 50%;<\/p>\n<p>\u00a0 \u00a0 f) Cuando no exceda de $200.000.00 en un 60%.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 19. Los incentivos tributarios de que tratan los art\u00edculos 45 y 46 de \u00a0 \u00a0 la ley \u201cpor la cual se estimula la capitalizaci\u00f3n del sector agropecuario y se \u00a0 \u00a0 dictan disposiciones sobre t\u00edtulos de fomento agropecuario, Fondo Financiero \u00a0 \u00a0 Agropecuario, Fondos Ganaderos, Prenda Agraria, Banco Ganadero, Asistencia \u00a0 \u00a0 T\u00e9cnica, autorizaciones a la Banca Comercial, deducciones y exenciones \u00a0 \u00a0 tributarias y otras materias\u201d, con excepci\u00f3n de los que se refieren a las \u00a0 \u00a0 exenciones de los impuestos complementarios de patrimonio y exceso de \u00a0 \u00a0 utilidades, tendr\u00e1n el car\u00e1cter de deducciones y podr\u00e1n afectar, si fuera el \u00a0 \u00a0 caso, la renta m\u00ednima presunta hasta en un cincuenta por ciento (50%) de \u00e9sta.<\/p>\n<p>\u00a0 \u00a0 Art\u00edculo 20. Esta Ley rige desde su promulgaci\u00f3n y sus disposiciones se \u00a0 \u00a0 aplicar\u00e1n desde el a\u00f1o gravable de 1973, excepci\u00f3n hecha de lo dispuesto en los \u00a0 \u00a0 art\u00edculos 3, sin sus par\u00e1grafos, 6, 7, 8, 9, 11 y 12 que regir\u00e1n para el a\u00f1o \u00a0 \u00a0 gravable de 1972.<\/p>\n<p>\u00a0 \u00a0 El presidente del honorable Senado,\u00a0<\/p>\n<p>\u00a0 \u00a0 HUGO ESCOBAR SIERRA.\u00a0<\/p>\n<p>\u00a0 \u00a0 El Presidente de la honorable C\u00e1mara de representantes,\u00a0<\/p>\n<p>\u00a0 \u00a0 DAVID ALJURE RAMIREZ.\u00a0<\/p>\n<p>\u00a0 \u00a0 El Secretario del honorable Senado,\u00a0<\/p>\n<p>\u00a0 \u00a0 Amaury Guerrero.\u00a0<\/p>\n<p>\u00a0 \u00a0 El Secretario General de la honorable C\u00e1mara de Representantes,\u00a0<\/p>\n<p>\u00a0 \u00a0 Rep\u00fablica de Colombia. Gobierno Nacional.<\/p>\n<p>\u00a0 \u00a0 Bogot\u00e1, D, E., 2 de abril de 1973.<\/p>\n<p>\u00a0 \u00a0 Publ\u00edquese y ejec\u00fatese.<\/p>\n<p>\u00a0 \u00a0 MISAEL PASTRANA BORRERO<\/p>\n<p>\u00a0 \u00a0 El Ministerio de Hacienda y Cr\u00e9dito P\u00fablico,<\/p>\n<p>\u00a0 \u00a0 Rodrigo Llorente Mart\u00ednez.<\/p>\n<p>\u00a0 \u00a0 El Ministro de Defensa Nacional,\u00a0<\/p>\n<p>\u00a0 \u00a0 General Hernando Currea Cubides.<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 LEY 6 DE 1973 \u00a0 \u00a0 (abril 2) \u00a0 \u00a0 por la cual se crean est\u00edmulos tributarios para las sociedades an\u00f3nimas, se \u00a0 \u00a0 aumentan las excepciones personales y se dictan otras disposiciones en materia \u00a0 \u00a0 tributaria. \u00a0 \u00a0 El Congreso de Colombia, \u00a0 \u00a0 DECRETA: \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[116],"tags":[],"class_list":["post-3833","post","type-post","status-publish","format-standard","hentry","category-leyes-1973"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/3833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/comments?post=3833"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/3833\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/media?parent=3833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/categories?post=3833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/tags?post=3833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}