{"id":403,"date":"2020-11-24T15:16:57","date_gmt":"2020-11-24T15:16:57","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-286-de-1996\/"},"modified":"2020-11-24T15:16:57","modified_gmt":"2020-11-24T15:16:57","slug":"ley-286-de-1996","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-286-de-1996\/","title":{"rendered":"LEY 286 DE 1996"},"content":{"rendered":"<p>LEY 286 DE 1996            <\/a><\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><b><font size=\"2\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"http:\/\/dmsjuridica.com\/CODIGOS\/LEGISLACION\/LEYES\/2019\/dms.png\" width=\"138\" height=\"103\"align=\"center\"><\/p>\n<\/p>\n<p align=\"center\"><b><font size=\"6\">LEY 286 DE 1996 <\/font> <\/b><\/p>\n<p align=\"center\"><b><font size=\"2\">(Julio 3) <\/font> <\/b> <\/p>\n<p align=\"center\"><b><font size=\"2\">Diario oficial No. 42.824, de 5 de julio de 1996 <\/font> <\/b><\/p>\n<p align=\"center\"><font size=\"2\">Por la cual se modifican parcialmente las Leyes 142 y 143 de 1994 <\/font><\/p>\n<p align=\"center\"><font size=\"2\">&lt;<b>Notas de Vigencia<\/b>&gt;<\/font><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>      <TR>    <TD><b><font size=\"2\">NOTAS DE VIGENCIA<\/font><\/b><font size=\"2\">:<\/font><\/TD><\/TR>    <TR>    <TD><font size=\"2\">&#8211; Se destaca que el <a hrefx=\"..\/..\/decretos\/2000\/D0955de2000.htm\">Decreto 955 de 2000<\/a>, &quot;por el cual se pone en vigencia el Plan de Inversiones P\u00fablicas para los a\u00f1os 1998 a 2002&quot;, publicado en el Diario Oficial No. 44.020 del 26 de mayo de 2000, introdujo en los art\u00edculos <A       \"D0955000.htm#64\">64<\/A>, <A       \"D0955000.htm#65\">65<\/A>, <A       \"D0955000.htm#66\">66<\/A>, <A       \"D0955000.htm#67\">67<\/A> y <A       \"D0955000.htm#75\">75<\/A> disposiciones relacionadas con la materia de que trata esta ley.<\/font><\/TD><\/TR>    <TR>    <TD><font size=\"2\">El <a hrefx=\"..\/..\/decretos\/2000\/D0955de2000.htm\">Decreto 955 de 2000<\/a>fue declarado INEXEQUIBLE a partir de la comunicaci\u00f3n de la sentencia al Gobierno, por la Corte Constitucional, mediante Sentencia <A       hrefx=\"..\/sentencias\/C-1403.00.rtf\">C-1403-00<\/A> de 19 de octubre de 2000, Magistrado Ponente Dr. Jos\u00e9 Gregorio Hern\u00e1ndez.<\/font><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV>   <\/p>\n<p align=\"center\"><b><font size=\"2\">EL CONGRESO DE COLOMBIA<\/font><\/b><font size=\"2\"> <\/font> <\/p>\n<p align=\"center\"><b><font size=\"2\">DECRETA<\/font><\/b><font size=\"2\">: <\/font> <\/p>\n<p>    <font face=\"Arial\"><A name=1><b><font size=\"2\">ART\u00cdCULO<\/font><\/b><font size=\"2\"> 1o. TR\u00c1NSITO DE LEGISLACI\u00d3N. <\/font> <\/A><font size=\"2\">Las empresas de servicios p\u00fablicos deber\u00e1n alcanzar progresivamente los l\u00edmites establecidos en las Leyes 142 y 143 de 1994 y la Ley 223 de 1995 en materia de factores de contribuci\u00f3n, tarifas y subsidios en el plazo y con la celeridad que establezca antes del 30 de noviembre de 1996 la respectiva Comisi\u00f3n de Regulaci\u00f3n. En ning\u00fan caso, el per\u00edodo de transici\u00f3n podr\u00e1 exceder los plazos que se se\u00f1alan a continuaci\u00f3n: <\/font> <\/font> <DIV>&nbsp;<\/DIV> <font size=\"2\" face=\"Arial\">1. Para los servicios de energ\u00eda el\u00e9ctrica y de gas combustible hasta el 31 de diciembre del a\u00f1o 2000, y <\/font> <DIV>&nbsp;<\/DIV> <font size=\"2\" face=\"Arial\">2. Para los servicios de agua potable, saneamiento b\u00e1sico y telefon\u00eda p\u00fablica b\u00e1sica conmutada hasta el 31 de diciembre del 2001. <\/font> <\/p>\n<p><font face=\"Arial\" size=\"2\">*<b>Nota Jurisprudencia<\/b>*<\/font><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>      <TR>    <TD><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/TD><\/TR>    <TR>    <TD><font size=\"2\" face=\"Arial\">&#8211; La Corte Constitucional se declar\u00f3 INHIBIDA de fallar sobre este art\u00edculo por el primer cargo&nbsp; por ineptitud de la demanda, mediante Sentencia <A       hrefx=\"..\/sentencias\/C-150-03.rtf\">C-150-03<\/A> de 25 de febrero de 2003, Magistrado Ponente Dr. Manuel Jos\u00e9 Cepeda Espinosa; &quot;Consecuencias de la cosa juzgada respecto del art\u00edculo <A      hrefx=\"L0142_94.htm#68\">68<\/A> de la Ley 142 de 1994, e inhibici\u00f3n para estudiar las dem\u00e1s normas acusadas por guardar estrecha relaci\u00f3n con dicho art\u00edculo&quot;.<\/font><\/TD><\/TR>  <\/TABLE><\/p>\n<p>&nbsp;<\/p>\n<p> <font face=\"Arial\"><A name=2><b><font size=\"2\">ART\u00cdCULO<\/font><\/b><font size=\"2\"> 2o.<\/font><\/A><font size=\"2\"> Las entidades descentralizadas y dem\u00e1s empresas que est\u00e9n prestando los servicios a los que se refiere la Ley 142 de 1994, se transformar\u00e1n en empresas de servicios p\u00fablicos de acuerdo con lo establecido en el art\u00edculo <A hrefx=\"L0142_94.htm#17\">17<\/A> de la Ley 142 de 1994, en un plazo hasta de dieciocho (18) meses a partir de la vigencia de la presente Ley. <\/font> <\/font> <\/p>\n<p><font face=\"Arial\" size=\"2\">*<b>Nota Jurisprudencia<\/b>*<\/font><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>      <TR>    <TD><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/TD><\/TR>    <TR>    <TD><font size=\"2\" face=\"Arial\">&#8211; Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante Sentencia <A       hrefx=\"..\/sentencias\/C-086-98.rtf\">C-198-98<\/A> de 18 de marzo de 1998, Magistrado Ponente Dr. Jorge Arango Mej\u00eda.<\/font><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <font face=\"Arial\"><A name=3><b><font size=\"2\">ART\u00cdCULO<\/font><\/b><font size=\"2\"> 3o.<\/font><\/A><font size=\"2\"> Cuando las entidades territoriales hayan estado prestando directamente un servicio p\u00fablico y no se hayan constituido en empresas de servicios p\u00fablicos, seg\u00fan lo hab\u00eda establecido el art\u00edculo <A hrefx=\"L0142_94.htm#182\">182<\/A> de la Ley 142 de 1994, se les concede un plazo hasta de dieciocho (18) meses a partir de la aprobaci\u00f3n de la presente Ley, para que se conviertan en empresas de servicios p\u00fablicos. <\/font> <\/font> <DIV>&nbsp;<\/DIV> <font face=\"Arial\"><A name=4><b><font size=\"2\">ART\u00cdCULO<\/font><\/b><font size=\"2\"> 4o.<\/font><\/A><font size=\"2\"> Ampl\u00edase el plazo establecido en el art\u00edculo <A hrefx=\"L0142_94.htm#181\">181<\/A> de la Ley 142 de 1994, hasta por seis meses m\u00e1s. <\/font> <\/font> <DIV>&nbsp;<\/DIV> <font face=\"Arial\"><A name=5><b><font size=\"2\">ART\u00cdCULO<\/font><\/b><font size=\"2\"> 5o.<\/font><\/A><font size=\"2\"> Las contribuciones que paguen los usuarios del servicio de energ\u00eda el\u00e9ctrica pertenecientes al sector residencial estratos 5 y 6, al sector comercial e industrial regulados y no regulados, los usuarios del servicio de gas combustible distribuido por red f\u00edsica pertenecientes al sector residencial estratos 5 y 6, al sector comercial, y al sector industrial incluyendo los grandes consumidores, y los usuarios de los servicios p\u00fablicos de telefon\u00eda b\u00e1sica conmutada pertenecientes al sector residencial estratos 5 y 6 y a los sectores comercial e industrial, son de car\u00e1cter nacional y su pago es obligatorio. Los valores ser\u00e1n facturados y recaudados por las empresas de energ\u00eda el\u00e9ctrica, de gas combustible distribuido por red f\u00edsica o de telefon\u00eda b\u00e1sica conmutada y ser\u00e1n utilizados por las empresas distribuidoras de energ\u00eda, o de gas, o por las prestadoras del servicio p\u00fablico de telefon\u00eda b\u00e1sica conmutada, seg\u00fan sea el caso, que prestan su servicio en la misma zona territorial del usuario aportante, quienes los aplicar\u00e1n para subsidiar el pago de los consumos de subsistencia de sus usuarios residenciales de los estratos I, II y III \u00e1reas urbanas y rurales. <\/font> <\/font> <DIV><\/p>\n<p align=\"justify\"><b><font size=\"2\" face=\"Arial\">*Nota de vigencia* <\/font> <\/b> <\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border id=\"table1\">      <TR>    <TD>&nbsp;<font face=\"Arial\" size=\"2\">La Ley 508 de 1999 fue declarada INEXEQUIBLE por vicios de forma, por la Corte Constitucional, mediante Sentencia C-557-00 de 16 de mayo de 2000, Magistrado Ponente Dr. Vladimiro Naranjo Mesa. <\/font> <\/TD><\/TR>    <TR>    <TD><font face=\"Arial\" size=\"2\">&#8211; Inciso modificado por el art\u00edculo 79 par\u00e1grafo 1o. de la Ley 508 de 1999, &#39;por la cual se expide el Plan Nacional de Desarrollo para los a\u00f1os de 1999-2002&#39;, publicada en el Diario Oficial No. 43.651 de 30 de julio de 1999. <\/font> <\/TD><\/TR>  <\/TABLE>&nbsp;<\/p>\n<p><font face=\"Arial\" size=\"2\"><b>Texto de la modificaci\u00f3n introducida por el art\u00edculo 79 par\u00e1grafo 1o. de la Ley 508 de 1999:<\/b><\/font><\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border id=\"table2\">      <TR>    <TD><font face=\"Arial\" size=\"2\">&lt;Inciso 1o.&gt; Las contribuciones de solidaridad que paguen los usuarios del servicio de energ\u00eda el\u00e9ctrica pertenecientes al sector residencial estratos 5 y 6, al sector comercial e industrial regulados y no regulados, los usuarios del servicio de gas combustible suministrado por red f\u00edsica pertenecientes al sector residencial estratos 5 y 6 y a los sectores comercial e industrial incluyendo los grandes consumidores, y los usuarios de los servicios p\u00fablicos de telefon\u00eda b\u00e1sica conmutada pertenecientes al sector residencial estratos 5 y 6 y a los sectores comercial e industrial son de car\u00e1cter nacional y su pago es obligatorio. Los valores ser\u00e1n facturados por las empresas prestadoras de los servicios p\u00fablicos, de energ\u00eda el\u00e9ctrica o de gas combustible suministrado por red f\u00edsica, o por las prestadoras del servicio p\u00fablico de telefon\u00eda b\u00e1sica conmutada. Los valores facturados por contribuci\u00f3n de solidaridad ser\u00e1n aplicados por las empresas prestadoras de los servicios p\u00fablicos de energ\u00eda el\u00e9ctrica o de gas combustible suministrado por red f\u00edsica, o por las prestadoras del servicio p\u00fablico de telefon\u00eda b\u00e1sica conmutada, seg\u00fan sea el caso, que prestan su servicio en la misma zona territorial del usuario aportante, para subsidiar el pago de los consumos de subsistencia de sus usuarios residenciales de los estratos I, II y III.<\/font><\/TD><\/TR><\/TABLE><\/p>\n<p>&nbsp;<\/DIV> <font size=\"2\" face=\"Arial\">Quedan excluidas del pago de la contribuci\u00f3n, las entidades establecidas en el numeral 89.7 del art\u00edculo <A hrefx=\"L0142_94.htm#89\">89<\/A> de la Ley 142 de 1994. <\/font> <DIV>&nbsp;<\/DIV> <font size=\"2\" face=\"Arial\">Si despu\u00e9s de aplicar la contribuci\u00f3n correspondiente a los sectores de energ\u00eda el\u00e9ctrica y de gas combustible distribuido por red f\u00edsica, para el cubrimiento trimestral de la totalidad de los subsidios requeridos en la respectiva zona territorial, hubiere excedentes, \u00e9stos ser\u00e1n transferidos por las empresas distribuidoras de energ\u00eda el\u00e9ctrica o de gas combustible distribuido por red f\u00edsica, dentro de los cuarenta y cinco (45) d\u00edas siguientes a su liquidaci\u00f3n trimestral, al &quot;Fondo de Solidaridad para Subsidios y Redistribuci\u00f3n de Ingresos&quot; de la Naci\u00f3n (Ministerio de Minas y Energ\u00eda), y su destinaci\u00f3n se har\u00e1 de conformidad con lo establecido en el numeral 89.3 del art\u00edculo <A hrefx=\"L0142_94.htm#89\">89<\/A> de la Ley 142 de 1994. <\/font> <DIV>&nbsp;<\/DIV> <font size=\"2\" face=\"Arial\">Si despu\u00e9s de aplicar la contribuci\u00f3n correspondiente al servicio de telefon\u00eda b\u00e1sica conmutada para el cubrimiento trimestral de la totalidad de los subsidios requeridos en la respectiva zona territorial hubiere excedentes, \u00e9stos ser\u00e1n transferidos por las empresas prestadoras del servicio de telefon\u00eda, dentro de los cuarenta y cinco (45) d\u00edas siguientes a su liquidaci\u00f3n trimestral, al &quot;Fondo de Comunicaciones del Ministerio&quot; de la Naci\u00f3n (Ministerio de Comunicaciones) el cual los destinar\u00e1 como inversi\u00f3n social al pago de los subsidios de los usuarios residenciales de estratos I, II y III, atendidos por empresas deficitarias prestadoras del servicio y para lo estatuido en el literal e del numeral 74.3 del art\u00edculo <A hrefx=\"L0142_94.htm#74\">74<\/A> de la Ley 142 de 1994. <\/font> <\/p>\n<p><b><font size=\"2\" face=\"Arial\">*Nota de vigencia* <\/font> <\/b> <\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>      <TR>    <TD><b><font size=\"2\" face=\"Arial\">Corte Constitucional<\/font><\/b><\/TD><\/TR>    <TR>    <TD><font size=\"2\" face=\"Arial\">&#8211; Art\u00edculo declarado EXEQUIBLE por la Corte Constitucional mediante Sentencia <A       hrefx=\"..\/sentencias\/C-086-98.rtf\">C-086-98<\/A> de 18 de marzo de 1998, Magistrado Ponente Dr. Jorge Arango Mej\u00eda.<\/font><\/TD><\/TR>    <TR>    <TD><font size=\"2\" face=\"Arial\">&quot;&#8230;considera la Corte que la norma acusada antes que desconocer la autonom\u00eda de las distintas entidades territoriales, es desarrollo de los principios de solidaridad y de redistribuci\u00f3n del ingreso establecido por&nbsp; la Constituci\u00f3n en materia de servicios p\u00fablicos, que no s\u00f3lo obligan a los usuarios sino a las empresas prestatarias de \u00e9stos, que,&nbsp; sin importar su naturaleza, deben colaborar para que en todo el territorio,&nbsp; los habitantes tengan acceso a ellos&quot;.<\/font><\/TD><\/TR>  <\/TABLE><DIV>&nbsp;<\/DIV> <font face=\"Arial\"><A name=6><b><font size=\"2\">ART\u00cdCULO<\/font><\/b><font size=\"2\"> 6o.<\/font><\/A><font size=\"2\"> TRANSITORIO. El Gobierno Nacional har\u00e1 la reglamentaci\u00f3n inicial en lo pertinente a las contribuciones y transferencias de la telefon\u00eda b\u00e1sica conmutada, antes del 31 de diciembre de 1996. <\/font> <\/font> <DIV>&nbsp;<\/DIV> <font face=\"Arial\"><A name=7><b><font size=\"2\">ART\u00cdCULO<\/font><\/b><font size=\"2\"> 7o.<\/font><\/A><font size=\"2\"> La presente Ley rige a partir de su promulgaci\u00f3n y deroga el par\u00e1grafo 2o. del art\u00edculo <A hrefx=\"L0142_94.htm#40\">40<\/A> de la Ley 142 de 1994, el art\u00edculo <A hrefx=\"L0142_94.htm#179\">179<\/A> de la Ley 142 de 1994 y las dem\u00e1s que le sean contrarias, especialmente las normas pertinentes contenidas en las Leyes 142 y 143 de 1994. <\/font> <\/font> <DIV>&nbsp;<\/DIV>   <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">El Presidente del honorable Senado de la Rep\u00fablica, <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">JULIO C\u00c9SAR GUERRA TULENA <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">El Secretario General del honorable Senado de la Rep\u00fablica, <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">PEDRO PUMAREJO VEGA <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">El Presidente de la honorable C\u00e1mara de Representantes, <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">RODRIGO RIVERA SALAZAR <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">El Secretario General de la honorable C\u00e1mara de Representantes, <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">DIEGO VIVAS TAFUR <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">REP\u00daBLICA DE COLOMBIA-GOBIERNO NACIONAL <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">Publ\u00edquese y ejec\u00fatese. <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">Dada en Santa Fe de Bogot\u00e1, D.C., a 3 de julio de 1996. <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">ERNESTO SAMPER PIZANO <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">El Viceministro t\u00e9cnico del Ministerio de Hacienda y Cr\u00e9dito P\u00fablico, <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">encargado de las funciones del despacho del Ministro de Hacienda y Cr\u00e9dito <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">P\u00fablico, <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">LEONARDO VILLAR G\u00d3MEZ <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">El Ministro de Desarrollo Econ\u00f3mico, <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">RODRIGO MAR\u00cdN BERNAL <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">El Viceministro de Energ\u00eda, encargado de las funciones del despacho del <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">Ministro de Minas y Energ\u00eda, <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">LEOPOLDO MONTA\u00d1EZ CRUZ <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">El Ministro de Comunicaciones, <\/font> <\/p>\n<p align=\"center\"><font size=\"2\" face=\"Arial\">JUAN MANUEL TURBAY MARULANDA<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LEY 286 DE 1996 &nbsp; LEY 286 DE 1996 (Julio 3) Diario oficial No. 42.824, de 5 de julio de 1996 Por la cual se modifican parcialmente las Leyes 142 y 143 de 1994 &lt;Notas de Vigencia&gt; NOTAS DE VIGENCIA: &#8211; Se destaca que el Decreto 955 de 2000, &quot;por el cual se pone en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-403","post","type-post","status-publish","format-standard","hentry","category-leyes-1996"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/comments?post=403"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/403\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/media?parent=403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/categories?post=403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/tags?post=403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}