{"id":406,"date":"2020-11-24T15:16:57","date_gmt":"2020-11-24T15:16:57","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-289-de-1996\/"},"modified":"2020-11-24T15:16:57","modified_gmt":"2020-11-24T15:16:57","slug":"ley-289-de-1996","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-289-de-1996\/","title":{"rendered":"LEY 289 DE 1996"},"content":{"rendered":"<p>LEY 289 DE 1996             <\/a><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; line-height: 12.0pt\"><font ><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"http:\/\/dmsjuridica.com\/CODIGOS\/LEGISLACION\/LEYES\/2019\/dms.png\" width=\"138\" height=\"103\"align=\"center\"><\/p>\n<\/p>\n<p class=\"MsoNormal\" style=\"text-align: center; text-autospace: none\">&nbsp;<b><font size=\"6\">LEY 289 DE 1996  <\/font><\/b><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">JULIO 10 <\/font><\/b> <\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">Por medio de la cual se autoriza la emisi\u00f3n de la Estampilla Armero 10 a\u00f1os. <\/font> <\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">EL CONGRESO DE COLOMBIA <\/font> <\/b><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">DECRETA: <\/font> <\/b><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">ART\u00cdCULO 1o.<\/font><\/b><font size=\"2\"> Autor\u00edzase a la Asamblea Departamental del Tolima para que ordene la Emisi\u00f3n de la Estampilla &quot;Armero 10 a\u00f1os&quot;. <\/font> <\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">ART\u00cdCULO 2o.<\/font><\/b><font size=\"2\"> El producido de la Emisi\u00f3n de la Estampilla a que se refiere el art\u00edculo <b>anterior<\/b>, se destinar\u00e1 principalmente para: <\/font> <\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">a) Obras de educaci\u00f3n, deportes y cultura; <\/font> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">b) Terminaci\u00f3n y dotaci\u00f3n del Hospital &quot;Nelson Restrepo Mart\u00ednez&quot;; <\/font> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">c) Construcci\u00f3n hasta su terminaci\u00f3n de &quot;Armero Parque Cementerio&quot; en el sitio de la cat\u00e1strofe.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">ART\u00cdCULO 3o.<\/font><\/b><font size=\"2\"> La Emisi\u00f3n de la Estampilla cuya creaci\u00f3n se autoriza hasta por la suma de mil millones de pesos ($1.000.000.000) el monto total recaudado se establece a precio constante de 1995. <\/font> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">ART\u00cdCULO 4o.<\/font><\/b><font size=\"2\"> El honorable Concejo Municipal de Armero-Guayabal aprobar\u00e1 anualmente en plan de inversi\u00f3n, los proyectos a ejecutarse con el producto del recaudo de la Estampilla. <\/font> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">ART\u00cdCULO 5o.<\/font><\/b><font size=\"2\"> Fac\u00faltese a los Concejos Municipales del Departamento del Tolima para que previa autorizaci\u00f3n de la Asamblea del Departamento hagan obligatorio el uso de la Estampilla que por esta Ley se autoriza emisi\u00f3n con destino al Municipio de Armero-Guayabal. <\/font> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">ART\u00cdCULO 6o.<\/font><\/b><font size=\"2\"> La obligaci\u00f3n de adherir y anular la Estampilla a que se refiere esta Ley queda a cargo de los funcionarios departamentales y municipales que intervienen en los actos. <\/font> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">ART\u00cdCULO 7o.<\/font><\/b><font size=\"2\"> Los recaudos por la venta de la estampilla estar\u00e1n a cargo de las Tesorer\u00edas Municipales en coordinaci\u00f3n con la Secretar\u00eda de Hacienda Departamental de acuerdo a la ordenanza que lo reglamenta y se destinar\u00e1 a lo establecido en el art\u00edculo <b>2<\/b>o. de la presente Ley. <\/font> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">ART\u00cdCULO 8o.<\/font><\/b><font size=\"2\"> El control del recaudo y el traslado de estos recursos como de la inversi\u00f3n de los fondos provenientes del cumplimiento de la presente Ley estar\u00e1n a cargo de la Contralor\u00eda del Departamento del Tolima. <\/font> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">ART\u00cdCULO 9o.<\/font><\/b><font size=\"2\"> Esta ley rige a partir de la fecha de su promulgaci\u00f3n. <\/font> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">El Presidente del honorable Senado de la Rep\u00fablica, <\/font> <\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">JULIO C\u00c9SAR GUERRA TULENA. <\/font> <\/b><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">El Secretario General del honorable Senado de la Rep\u00fablica, <\/font> <\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">PEDRO PUMAREJO VEGA. <\/font> <\/b><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">El Presidente de la honorable C\u00e1mara de Representantes, <\/font> <\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">RODRIGO RIVERA SALAZAR. <\/font> <\/b><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">El Secretario General de la honorable C\u00e1mara de Representantes, <\/font> <\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">DIEGO VIVAS TAFUR. <\/font> <\/b><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">REP\u00daBLICA DE COLOMBIA &#8211; GOBIERNO NACIONAL <\/font> <\/b><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">Publ\u00edquese y ejec\u00fatese. <\/font> <\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">Dada en Santa Fe de Bogot\u00e1, D.C., a 10 de julio de 1996. <\/font> <\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">ERNESTO SAMPER PIZANO. <\/font> <\/b><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">El Viceministro T\u00e9cnico del Ministerio de Hacienda <\/font> <\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">y Cr\u00e9dito P\u00fablico, encargado de las funciones del Despacho <\/font> <\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">del Ministerio de Hacienda y Cr\u00e9dito P\u00fablico, <\/font> <\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><b><font size=\"2\">LEONARDO VILLAR G\u00d3MEZ<\/font><\/b><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\"> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\"><font  size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\"> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\"><font  size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\"> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\"><font  size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\"> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\"><font  size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none; margin-top:0; margin-bottom:0\"><font size=\"2\"> <\/p>\n<p class=\"MsoNormal\" style=\"text-autospace: none; margin-top:0; margin-bottom:0\"><font  size=\"2\">&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">\n<p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">\n<p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">\n<p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">\n<p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">\n<p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/p>\n<p><p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/p>\n<p><p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">\n<p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">\n<p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">\n<p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">\n<p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-autospace: none\">\n<p class=\"MsoNormal\" style=\"text-autospace: none\"><font >&nbsp;<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LEY 289 DE 1996 &nbsp; &nbsp;LEY 289 DE 1996 JULIO 10 &nbsp; Por medio de la cual se autoriza la emisi\u00f3n de la Estampilla Armero 10 a\u00f1os. &nbsp; &nbsp; EL CONGRESO DE COLOMBIA &nbsp; DECRETA: &nbsp; &nbsp; ART\u00cdCULO 1o. Autor\u00edzase a la Asamblea Departamental del Tolima para que ordene la Emisi\u00f3n de la Estampilla &quot;Armero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-406","post","type-post","status-publish","format-standard","hentry","category-leyes-1996"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/comments?post=406"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/406\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/media?parent=406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/categories?post=406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/tags?post=406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}