{"id":427,"date":"2020-11-24T15:16:58","date_gmt":"2020-11-24T15:16:58","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-310-de-1996\/"},"modified":"2020-11-24T15:16:58","modified_gmt":"2020-11-24T15:16:58","slug":"ley-310-de-1996","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-310-de-1996\/","title":{"rendered":"LEY 310 DE 1996"},"content":{"rendered":"<p>LEY 310 DE 1996            <\/a><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" align=\"center\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\"><b><font size=\"2\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"http:\/\/dmsjuridica.com\/CODIGOS\/LEGISLACION\/LEYES\/2019\/dms.png\" width=\"138\" height=\"103\"align=\"center\"><\/font><\/b><\/p>\n<p>&nbsp;<\/font><\/p>\n<\/p>\n<p class=\"MsoNormal\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<p><font face=\"Arial\" size=\"6\" >LEY 310 DE 1996<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" ><b>&nbsp; AGOSTO 6<\/b> <\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >Por medio de la cual se modifica la Ley 86 de 1989<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<p><font face=\"Arial\"  size=\"2\">EL CONGRESO DE COLOMBIA<\/font><font face=\"Arial\"  size=\"2\">&nbsp;<\/font><font face=\"Arial\"  size=\"2\">DECRETA:<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<h4><b><font face=\"Arial\" size=\"2\" >ARTICULO 1\u00ba.<\/font><\/b><font face=\"Arial\" size=\"2\" >El \u00e1rea de influencia de un Sistema de Servicio P\u00fablico Urbano de Transporte Masivo de Pasajeros, estar\u00e1 comprendida por las \u00e1reas urbanas, suburbanas y por los municipios a los cuales el sistema sirve de interconexi\u00f3n directa o indirecta.<\/font><\/h4>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<h4><b><font face=\"Arial\" size=\"2\" >ARTICULO 2.<\/font><\/b><font face=\"Arial\" size=\"2\" >La Naci\u00f3n y sus entidades descentralizadas por servicio cofinanciar\u00e1n o participar\u00e1n con aportes de capital, en dinero o en especie en el Sistema de Servicio P\u00fablico Urbano de Transporte Masivo de Pasajeros, con un m\u00ednimo del 40% y un m\u00e1ximo del 70% del servicio d la deuda del proyecto, siempre y cuando se cumplan los siguientes requisitos:<\/font><\/h4>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\"><font ><font face=\"Arial\" size=\"2\">1.<\/font><font size=\"2\">&nbsp;&nbsp;&nbsp;<\/font><font face=\"Arial\" size=\"2\">Que se constituya una sociedad por acciones que ser\u00e1 la titular de este tipo de sistema de transporte, en caso de hacerse un aporte de capital.<\/font><\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\"><font ><font face=\"Arial\" size=\"2\">2.<\/font><font size=\"2\">&nbsp;&nbsp;&nbsp;<\/font><font face=\"Arial\" size=\"2\">Que el proyecto respectivo tenga concepto previo del Conpes mediante un estudio de factibilidad y rentabilidad, t\u00e9cnico-econ\u00f3mico socio-ambiental y f\u00edsico-espacial, que defina claramente tanto la estrategia como el Sistema Integral de Transporte Masivo propuesto, as\u00ed como el cronograma y los organismos de ejecuci\u00f3n.<\/font><\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\"><font ><font face=\"Arial\" size=\"2\">3.<\/font><font size=\"2\">&nbsp;&nbsp;&nbsp;<\/font><font face=\"Arial\" size=\"2\">Que el Plan Integral de Transporte Masivo propuesto, sea coherente con el respectivo Plan Integral de Desarrollo Urbano, seg\u00fan lo dispuesto en la Ley 9\u00aa de 1.989, o normas que la modifiquen o sustituyan.<\/font><\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\"><font ><font face=\"Arial\" size=\"2\">4.<\/font><font size=\"2\">&nbsp;&nbsp;&nbsp;<\/font><font face=\"Arial\" size=\"2\">Que el proyecto propuesto est\u00e9 debidamente registrado en el Banco de Proyectos de Inversi\u00f3n Nacional, y cumpla los requisitos establecidos por el Decreto 841 de 1.990 y dem\u00e1s disposiciones vigentes sobre la materia.<\/font><\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\"><font ><font face=\"Arial\" size=\"2\">5.<\/font><font size=\"2\">&nbsp;&nbsp;&nbsp;<\/font><font face=\"Arial\" size=\"2\">Que est\u00e9 formalmente constituida una autoridad \u00danica de Transporte para la administraci\u00f3n del Sistema de Servicio P\u00fablico Urbano de Transporte Masivo de Pasajeros propuesto.<\/font><\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\"><font ><font face=\"Arial\" size=\"2\">6.<\/font><font size=\"2\">&nbsp;&nbsp;&nbsp;<\/font><font face=\"Arial\" size=\"2\">Que el proyecto de Sistema de Servicio P\u00fablico Urbano de Transporte Masivo de Pasajeros est\u00e9 incluido en el Plan Nacional de Desarrollo<\/font><\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<h4><b><font face=\"Arial\" size=\"2\" >ARTICULO 3\u00ba.<\/font><\/b><font face=\"Arial\" size=\"2\" >La Naci\u00f3n solamente podr\u00e1 otorgar su garant\u00eda a los cr\u00e9ditos externos que se contraten para los proyectos de los Sistemas de Servicio P\u00fablico Urbano de Transporte Masivo de Pasajeros, cuando se hayan pignorado a su favor rentas en cuant\u00edas suficientes que cubran el pago de la participaci\u00f3n de las entidades territoriales.<\/font><\/h4>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<h4><b><font face=\"Arial\" size=\"2\" >ARTICULO 4\u00ba.<\/font><\/b><font face=\"Arial\" size=\"2\" >Cuando las rentas propias de las entidades territoriales y la sobretasa a los combustibles, no sean suficientes para cubrir la pignoraci\u00f3n de los recursos previstos en el art\u00edculo anterior, quedan facultadas para:<\/font><\/h4>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\"><font ><font face=\"Arial\" size=\"2\">1.<\/font><font size=\"2\">&nbsp;&nbsp;&nbsp;<\/font><font face=\"Arial\" size=\"2\">Aumentar hasta un 20% las tarifas de operaci\u00f3n y las tarifas de los grav\u00e1menes de su competencia.<\/font><\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\"><font ><font face=\"Arial\" size=\"2\">2.<\/font><font size=\"2\">&nbsp;&nbsp;&nbsp;<\/font><font face=\"Arial\" size=\"2\">Crear nuevos grav\u00e1menes sobre derechos de tr\u00e1nsito en ciertas \u00e1reas&nbsp; restringidas o congestionadas, cobro de peajes y cobros especiales para lotes de parqueo.<\/font><\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\"><font ><font face=\"Arial\" size=\"2\">3.<\/font><font size=\"2\">&nbsp;&nbsp;&nbsp;<\/font><font face=\"Arial\" size=\"2\">Celebrar contratos de concesi\u00f3n para la construcci\u00f3n, mantenimiento, operaci\u00f3n y administraci\u00f3n total o parcial de sistemas de transporte&nbsp; masivo, bajo el control de la entidad concedente y dem\u00e1s disposiciones establecidas por la <b><a hrefx=\"L0080_93.htm\">Ley 80 de 1.993<\/a><\/b>.<\/font><\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; text-indent: -14.15pt; margin-left: 14.15pt\">&nbsp;<\/p>\n<p class=\"CONCOR\"><font >NUMERAL 15 DEL ARTICULO 21 DE LA <b><a hrefx=\"L0060_93.htm\">LEY 60 DE 1.993<\/a><\/b>. (TRANSFERENCIAS DE LA NACI\u00d3N). [PARTICIPACI\u00d3N DE LOS MUNICIPIOS EN LOS INGRESOS CORRIENTES DE LA NACI\u00d3N]. Las participaciones a los municipios de que trata el art\u00edculo 357 de la C.N., se destinar\u00e1n a las siguientes actividades. (&#8230;). 15. Construcci\u00f3n y mantenimiento de las redes viales municipales e intermunicipales. (&#8230;).  <\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" ><b>PAR\u00c1GRAFO 1\u00ba. <\/b>Los incrementos y eventos a que se refieren los numerales del presente art\u00edculo se destinar\u00e1n exclusivamente a la financiaci\u00f3n de Sistemas de Servicio P\u00fablico Urbano de Transporte Masivo de Pasajeros y se cobrar\u00e1n a partir del 1\u00ba de enero del a\u00f1o siguiente a aquel en que se&nbsp; perfeccione el contrato para su desarrollo.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" ><b>PAR\u00c1GRAFO 2\u00ba. <\/b>En el evento que resulte necesario acudir a la financiaci\u00f3n parcial mediante el sistema de la contribuci\u00f3n por valorizaci\u00f3n, los&nbsp; estudios, recaudo y administraci\u00f3n en general lo realizar\u00e1 la entidad&nbsp; especializada en el tema del respectivo municipio o del municipio n\u00facleo&nbsp; o metr\u00f3poli, mediante convenio interadministrativo con la empresa o&nbsp; entidad que adelante el sistema masivo de transporte.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<h4><font face=\"Arial\" size=\"2\" >ARTICULO 5\u00ba.<\/font><font face=\"Arial\" size=\"2\" >Las entidades territoriales participantes en el Sistema de&nbsp; Servicio P\u00fablico Urbano de Transporte Masivo de Pasajeros de la ciudad&nbsp; de Medell\u00edn y el Valle de Aburr\u00e1, deber\u00e1n pignorar rentas que garanticen&nbsp; por lo menos de un sesenta por ciento (60%) del valor presente del servicio&nbsp; de la deuda de todos los cr\u00e9ditos que se hayan contra\u00eddo o se encuentren&nbsp; contratados o que est\u00e1n o estuvieron garantizados o avalados por La Naci\u00f3n,&nbsp; para la financiaci\u00f3n de este Sistema, cualquiera sea el estado de amortizaci\u00f3n en que se encuentren. El cuarenta por ciento (40%) restante queda&nbsp; a cargo de la Naci\u00f3n.<\/font><\/h4>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >Para la pignoraci\u00f3n de las rentas a que se refiere el inciso anterior, las&nbsp; entidades territoriales involucradas continuar\u00e1n utilizando las rentas que&nbsp; hasta el momento han servido de garant\u00eda para la Naci\u00f3n.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >Para efectos del inciso anterior, el monto de pignoraci\u00f3n de la contribuci\u00f3n de valorizaci\u00f3n ser\u00e1 de noventa y ocho millones de d\u00f3lares&nbsp; (US $98.000.000.00) de 1.996 y la pignoraci\u00f3n de la renta provenientes del impuesto al consumo de cigarrillo y tabaco se reducir\u00e1 hasta llegar a un cuarenta por ciento (40%) de su valor.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >En el evento en que aplicados los anteriores criterios, y sumada la sobretasa a los combustibles, se exceda del valor m\u00ednimo de pignoraci\u00f3n a favor de la Naci\u00f3n, se podr\u00e1 reducir, adicionalmente, la pignoraci\u00f3n de la renta proveniente del impuesto al consumo del cigarrillo y tabaco hasta el valor nominal de dicho excedente.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >Para implementar el recaudo de la sobretasa del impuesto a los combustibles, \u00e9ste podr\u00e1 efectuarse en las plantas de abastecimiento, por los grandes distribuciones o por los distribuidores minoristas, el Gobierno reglamentar\u00e1 la materia.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >En todo caso, la combinaci\u00f3n de todas las anteriores, siempre garantizar\u00e1n, como m\u00ednimo, el porcentaje establecido en el inciso primero de este art\u00edculo.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" ><b>PAR\u00c1GRAFO.<\/b> En cualquier caso, lo establecido en el presente art\u00edculo, no podr\u00e1 ser m\u00e1s oneroso para las Entidades Territoriales involucradas en el Sistema P\u00fablico Urbano de Transporte Masivo de Pasajeros de la ciudad de Medell\u00edn y en el Valle de Aburr\u00e1 que lo establecido en la Ley 86 de 1.989.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\">&nbsp;<\/p>\n<h4><font face=\"Arial\" size=\"2\" >ARTICULO 6\u00ba.<\/font><font face=\"Arial\" size=\"2\" >Ferrov\u00edas podr\u00e1 aportar los corredores f\u00e9rreos de su propiedad para que formen parte del Sistema de Transporte Masivo. El valor comercial de dichos corredores har\u00e1 parte de los aportes de las entidades descentralizadas, a los cuales se refiere el art\u00edculo 2\u00ba de la presente Ley.<\/font><\/h4>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >Ferrov\u00edas har\u00e1 los estudios necesarios para determinar la posibilidad de entregar en concesi\u00f3n las l\u00edneas f\u00e9rreas que de Zipaquir\u00e1, Facatativ\u00e1 y Soacha ingresan al Centro de Bogot\u00e1.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<h4><b><font face=\"Arial\" size=\"2\" >ARTICULO 7\u00ba.<\/font><\/b><font face=\"Arial\" size=\"2\" >A partir de la vigencia de la presente Ley quedan derogados los art\u00edculos 3\u00ba, 4\u00ba, inciso \u00fanico y par\u00e1grafo 1\u00ba del art\u00edculo 8\u00ba y el art\u00edculo 9\u00ba de la Ley 86 de 1.989, as\u00ed como las dem\u00e1s normas que le sean contrarias.<\/font><\/h4>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><font face=\"Arial\" size=\"2\" >&nbsp;<\/font><\/p>\n<h4><b><font face=\"Arial\" size=\"2\" >ARTICULO 8\u00ba.<\/font><\/b><font face=\"Arial\" size=\"2\" >La presente Ley rige a partir de la fecha de su promulgaci\u00f3n.<\/font><\/h4>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >El Presidente del honorable Senado de la Rep\u00fablica,<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >Julio C\u00e9sar Guerra Tulena.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >El Secretario General del honorable Senado de la Rep\u00fablica,<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >Pedro Pumarejo Vega.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >El Presidente de la honorable C\u00e1mara de Representantes,<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >Rodrigo Rivera Salazar.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >El Secretario General de la honorable C\u00e1mara de Representantes,<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >Diego Vivas Tafur.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\">&nbsp;<\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >REPUBLICA DE COLOMBIA- GOBIERNO NACIONAL<\/font><\/p>\n<p class=\"MsoNormal\" align=\"center\" style=\"text-align: center\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >Publ\u00edquese y ejec\u00fatese.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >Dada en Santa Fe de Bogot\u00e1, D. C., a 6 de agosto de 1.996.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><b><font face=\"Arial\" size=\"2\" >ERNESTO SAMPER PIZANO<\/font><\/b><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >El Ministro de Hacienda y Cr\u00e9dito P\u00fablico,<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >Jos\u00e9 Antonio Ocampo Gaviria.<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\">&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >El Ministro de Transporte,<\/font><\/p>\n<p class=\"MsoNormal\" style=\"text-align: center\"><font face=\"Arial\" size=\"2\" >Carlos Hern\u00e1n L\u00f3pez Guti\u00e9rrez.<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LEY 310 DE 1996 &nbsp; &nbsp; &nbsp; &nbsp; LEY 310 DE 1996 &nbsp; AGOSTO 6 &nbsp; Por medio de la cual se modifica la Ley 86 de 1989 &nbsp; EL CONGRESO DE COLOMBIA&nbsp;DECRETA: &nbsp; ARTICULO 1\u00ba.El \u00e1rea de influencia de un Sistema de Servicio P\u00fablico Urbano de Transporte Masivo de Pasajeros, estar\u00e1 comprendida por las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-427","post","type-post","status-publish","format-standard","hentry","category-leyes-1996"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/comments?post=427"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/427\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/media?parent=427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/categories?post=427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/tags?post=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}