{"id":4548,"date":"2024-02-06T22:26:14","date_gmt":"2024-02-06T22:26:14","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2024\/02\/06\/ley-079-de-1985\/"},"modified":"2024-02-06T22:26:14","modified_gmt":"2024-02-06T22:26:14","slug":"ley-079-de-1985","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2024\/02\/06\/ley-079-de-1985\/","title":{"rendered":"LEY 079 DE 1985"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>LEY 79 DE 1985 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>(OCTUBRE 8) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Por la cual la Naci\u00f3n se asocia a la conmemoraci\u00f3n de los 15 \u00a0 a\u00f1os de creaci\u00f3n y existencia de la Fundaci\u00f3n Universitaria Aut\u00f3noma de Colombia \u00a0 -FUAC-, rinde homenaje a sus fundadores y se dictan otras disposiciones. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>El Congreso de Colombia \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>DECRETA: \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>ARTICULO 1\u00ba.- La Naci\u00f3n se asocia a la conmemoraci\u00f3n de los \u00a0 15 a\u00f1os de creaci\u00f3n y existencia de la Fundaci\u00f3n Universitaria Aut\u00f3noma de \u00a0 Colombia -FUAC-, rinde homenaje a sus fundadores por su noble gesti\u00f3n en pro del \u00a0 desarrollo y progreso. de la educaci\u00f3n superior en Colombia. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>ARTICULO 2\u00ba.- De conformidad con los numerales 11 y 17 del \u00a0 art\u00edculo 76 de la Constituci\u00f3n Pol\u00edtica de Colombia, autorizase al Gobierno \u00a0 Nacional para planificar y desarrollar las siguientes obras de utilidad p\u00fablica \u00a0 y de inter\u00e9s social: \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>&#8211; Construcci\u00f3n de la sede de la Fundaci\u00f3n Universitaria \u00a0 Aut\u00f3noma de Colombia -FUAC-. en donde funcionar\u00e1n las diferentes Facultades de \u00a0 la Universidad con sus laboratorios, aulas de clase y m\u00e1xima, cafeter\u00eda, \u00a0 biblioteca, puestos de salud, oficinas administrativas, centros de \u00a0 investigaci\u00f3n, consultorio jur\u00eddico y dem\u00e1s dependencias de la Instituci\u00f3n \u00a0 Universitaria. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Par\u00e1grafo. Las anteriores obras ser\u00e1n construidas en el lote \u00a0 de propiedad de la FUAC, situado en la calle 13 n\u00famero 4-32. 4-34, 4-42 de la \u00a0 ciudad de Bogot\u00e1. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>ARTICULO 3\u00ba.- Autorizase al Gobierno Nacional para efectuar \u00a0 las operaciones presupuestales correspondientes u obtener empr\u00e9stitos o celebrar \u00a0 los contratos necesarios para dar cumplimiento a la presente Ley. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>ARTICULO 4\u00ba.- Esta Ley rige a partir de su sanci\u00f3n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Dada en Bogot\u00e1, D. E., a los&#8230; d\u00edas del mes de&#8230; de mil \u00a0 novecientos ochenta y cinco (1985). \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>El Presidente del honorable Senado de la Rep\u00fablica, ALVARO \u00a0 VILLEGAS MORENO, el Presidente de la honorable C\u00e1mara de Representantes. MIGUEL \u00a0 PINEDO VIDAL, el Secretario General del honorable Senado de la Rep\u00fablica. \u00a0 Crisp\u00edn Villaz\u00f3n de Armas, el Secretario General de la honorable C\u00e1mara de \u00a0 Representantes. Julio Enrique Olaya Rinc\u00f3n. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>Rep\u00fablica de Colombia &#8211; Gobierno Nacional \u00a0<\/p>\n<p>Bogot\u00e1, D. E., 8 de octubre de 1985. \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>BELISARIO BETANCUR \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>El Ministro de Hacienda y Cr\u00e9dito P\u00fablico, encargado, C\u00e9sar \u00a0 Vallejo Mej\u00eda, la Ministra de Educaci\u00f3n Nacional, Liliam Su\u00e1rez Melo, el \u00a0 Ministro de Obras P\u00fablicas y Transporte, Rodolfo Segovia Salas. \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0 \u00a0\u00a0 LEY 79 DE 1985 \u00a0 \u00a0 \u00a0 \u00a0 (OCTUBRE 8) \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Por la cual la Naci\u00f3n se asocia a la conmemoraci\u00f3n de los 15 \u00a0 a\u00f1os de creaci\u00f3n y existencia de la Fundaci\u00f3n Universitaria Aut\u00f3noma de Colombia \u00a0 -FUAC-, rinde homenaje [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128],"tags":[],"class_list":["post-4548","post","type-post","status-publish","format-standard","hentry","category-leyes-1985"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/4548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/comments?post=4548"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/4548\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/media?parent=4548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/categories?post=4548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/tags?post=4548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}