{"id":4713,"date":"2024-02-06T22:29:50","date_gmt":"2024-02-06T22:29:50","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2024\/02\/06\/ley-33-de-1987\/"},"modified":"2024-02-06T22:29:50","modified_gmt":"2024-02-06T22:29:50","slug":"ley-33-de-1987","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2024\/02\/06\/ley-33-de-1987\/","title":{"rendered":"LEY 33 DE 1987"},"content":{"rendered":"\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p>\u00a0 \u00a0\u00a0<\/p>\n<p>LEY 33 DE 1987 \u00a0<\/p>\n<p>(Octubre 26) \u00a0<\/p>\n<p>Por medio de la cual se aprueba \u00a0 el &#8220;Convenio de Berna para la Protecci\u00f3n de las Obras Literarias y Art\u00edsticas&#8221;, \u00a0 del 9 de septiembre de 1886, completado en Par\u00eds el 4 de mayo de 1896, revisado \u00a0 en Berl\u00edn el 13 de noviembre de 1908, completado en Berna el 20 de marzo de 1914 \u00a0 y revisado en Roma el 2 de junio de 1928, en Bruselas, el 26 de junio de 1948, \u00a0 en Estocolmo el 14 de julio de 1967 y en Par\u00eds el 24 de julio de 1971. \u00a0<\/p>\n<p>El Congreso de Colombia \u00a0<\/p>\n<p>DECRETA: \u00a0<\/p>\n<p>ARTICULO 1\u00ba.-Apru\u00e9base \u00a0 el Convenio de Berna para la Protecci\u00f3n de las Obras Literarias y Art\u00edsticas&#8221; el \u00a0 9 de septiembre de 1886, completado en Par\u00eds el 4 de mayo de 1896, revisado en \u00a0 Berl\u00edn el 13 de noviembre de 1908, completado en Berna el 20 de marzo de 1914 y \u00a0 revisado en Roma el 2 de junio de 1928, en Bruselas, el 26 de junio de 1948, en \u00a0 Estocolmo el 14 de julio de 1967 y en Par\u00eds el 24 de julio de 1971, cuyo texto \u00a0 certificado es el siguiente: \u00a0<\/p>\n<p>Texto oficial espa\u00f1ol establecido \u00a0 en virtud del articulo 37, 1) b) \u00a0<\/p>\n<p>CONVENIO DE BERNA PARA LA \u00a0 PROTECCI\u00d3N DE LAS OBRAS LITERARIAS Y ARTISTICAS \u00a0<\/p>\n<p>Del 9 de septiembre de 1886, \u00a0 completado en Par\u00eda el 4 de mayo de 1896, revisado en Berl\u00edn el 13 de noviembre \u00a0 de 1908, completado en Berna el 20 de marzo de 1914 y revisado el Roma el 2 de \u00a0 junio de 1928, en Bruselas el 26 de junio de 1948, en Estocolmo el 14 de julio \u00a0 de 1967 y en Par\u00eds el 24 de julio 1971. \u00a0<\/p>\n<p>INDICE \u00a0<\/p>\n<p>Articulo primero: \u00a0<\/p>\n<p>Constituci\u00f3n de una Uni\u00f3n. \u00a0<\/p>\n<p>Articulo 2: \u00a0<\/p>\n<p>Obras protegidas: 1. \u00abObras \u00a0 literarias y art\u00edsticas\u00bb; 2. Posibilidad de exigir la fijaci\u00f3n; 3. Obras \u00a0 derivadas; 4. Textos oficiales; 5. Colecciones; 6. Obligaci\u00f3n de proteger; \u00a0 beneficios de la protecci\u00f3n; 7. Obras de artes aplicadas y dibujos y modelos \u00a0 industriales; 8. Noticias. \u00a0<\/p>\n<p>Articulo 2 bis: \u00a0<\/p>\n<p>Posibilidad de limitar la \u00a0 protecci\u00f3n de algunas obras: 1. Determinados discursos; 2. Algunas utilizaciones \u00a0 de conferencias y alocuciones; 3. Derecho de reunir en colecci\u00f3n estas obras. \u00a0<\/p>\n<p>Articulo 3: \u00a0<\/p>\n<p>Criterios para la protecci\u00f3n: 1. \u00a0 Nacionalidad del autor; lugar de publicaci\u00f3n de la obra; 2. Residencia del \u00a0 autor; 3. Obras \u00abpublicadas\u00bb; 4. Obras \u00abpublicas simult\u00e1neamente\u00bb. \u00a0<\/p>\n<p>Articulo 4: \u00a0<\/p>\n<p>Criterios para la protecci\u00f3n de \u00a0 obras cinematogr\u00e1ficas, obras arquitect\u00f3nicas y algunas obras de artes gr\u00e1ficas \u00a0 y pl\u00e1sticas. \u00a0<\/p>\n<p>Articulo 5: \u00a0<\/p>\n<p>Derechos garantizados: 1 y 2. \u00a0 Fuera del pa\u00eds de origen; 3. En el pa\u00eds de origen; 4. \u00abPa\u00eds de origen\u00bb. \u00a0<\/p>\n<p>Articulo 6: \u00a0<\/p>\n<p>Posibilidad de restringir la \u00a0 protecci\u00f3n con respecto terminadas obras de nacionales de algunos pa\u00edses que no \u00a0 pertenezcan a la Uni\u00f3n: 1. En el pa\u00eds en que la obra se public\u00f3 por primera vez \u00a0 y en los dem\u00e1s pa\u00edses; 2. No retroactividad; 3. Notificaci\u00f3n. \u00a0<\/p>\n<p>Articulo 6 bis: \u00a0<\/p>\n<p>Derechos morales: 1. Derecho de \u00a0 reivindicar la paternidad de la obra; derecho de ponerse a algunas \u00a0 modificaciones de la obra y a otros atentados a la misma; 2. Despu\u00e9s de la \u00a0 muerte del autor; 3. Medios procesales. \u00a0<\/p>\n<p>Articulo 7: \u00a0<\/p>\n<p>Vigencia de la protecci\u00f3n: 1. En \u00a0 general; 2. Respecto de las obras cinematogr\u00e1ficas; 3. Respecto de las obras \u00a0 an\u00f3nimas o seud\u00f3nimas; 4. Respecto de las obras fotogr\u00e1ficas y las artes \u00a0 aplicadas; 5. Fecha de partida para calcular los plazos; 6. Plazos superiores; \u00a0 7. Plazos menos extensos; 8. Legislaci\u00f3n aplicable; \u00abcotejo\u00bb de plazos. \u00a0<\/p>\n<p>Articulo 7 bis: \u00a0<\/p>\n<p>Vigencia de la protecci\u00f3n de \u00a0 obras realizadas en colaboraci\u00f3n. \u00a0<\/p>\n<p>Articulo 8: \u00a0<\/p>\n<p>Derecho de traducci\u00f3n. \u00a0<\/p>\n<p>Derecho de reproducci\u00f3n: 1. En \u00a0 general; 2. \u00a0<\/p>\n<p>Articulo 9 \u00a0<\/p>\n<p>Posibles excepciones; 3. \u00a0 Grabaciones sonoras y visuales. \u00a0<\/p>\n<p>Articulo 10: \u00a0<\/p>\n<p>Libre utilizaci\u00f3n de obras en \u00a0 algunos casos: 1. Citas; 2. Ilustraci\u00f3n de la ense\u00f1anza; 3. Menci\u00f3n de la fuente \u00a0 y del autor. \u00a0<\/p>\n<p>Articulo 10 bis: \u00a0<\/p>\n<p>Obras posibilidades de libre \u00a0 utilizaci\u00f3n de obras: 1. De algunos art\u00edculos y obras radiodifundidas; 2. De \u00a0 obras u o\u00eddas en el curso de acontecimientos de actualidad. \u00a0<\/p>\n<p>Articulo 11: \u00a0<\/p>\n<p>Articulo 11 bis: \u00a0<\/p>\n<p>Derechos de radiodifusi\u00f3n y \u00a0 derechos conexos: 1. Radiodifusi\u00f3n u otras comunicaciones, sin hilo, \u00a0 comunicaci\u00f3n p\u00fablica o sin hilo de la obra radiodifundida, comunicaci\u00f3n p\u00fablica \u00a0 mediante altavoz o cualquier otro instrumento an\u00e1logo de la obra radiodifundida; \u00a0 2. Licencias obligatorias; 3. Grabaci\u00f3n: grabaciones ef\u00edmeras. \u00a0<\/p>\n<p>Articulo 11 ter: \u00a0<\/p>\n<p>Algunos derechos correspondientes \u00a0 a las obras literarias: 1. Derecho de recitaci\u00f3n p\u00fablica y de transmisi\u00f3n \u00a0 p\u00fablica de una recitaci\u00f3n; 2. En lo que concierne a las traducciones. \u00a0<\/p>\n<p>Articulo 12: \u00a0<\/p>\n<p>Derecho de adaptaci\u00f3n, arreglo y \u00a0 otra transformaci\u00f3n. \u00a0<\/p>\n<p>Articulo 13: \u00a0<\/p>\n<p>Posibilidad de limitar el derecho \u00a0 de grabar obras musicales y la letra respectiva: 1. Licencias obligatorias; 2. \u00a0 Medidas transitorias; 3. Decomiso de la importaci\u00f3n de ejemplares hechos sin la \u00a0 autorizaci\u00f3n del autor. \u00a0<\/p>\n<p>Articulo 14: \u00a0<\/p>\n<p>Derechos cinematogr\u00e1ficos y \u00a0 derechos conexos: 1. Adaptaci\u00f3n y reproducci\u00f3n cinematogr\u00e1ficas; distribuci\u00f3n; \u00a0 representaci\u00f3n, ejecuci\u00f3n p\u00fablica y transmisi\u00f3n por hilo al p\u00fablico de las obras \u00a0 as\u00ed adaptadas o reproducidas; 2. Adaptaci\u00f3n de realizaciones cinematogr\u00e1ficas; \u00a0 3. Falta de licencias obligatorias. \u00a0<\/p>\n<p>Articulo 14 bis: \u00a0<\/p>\n<p>Disposiciones especiales \u00a0 relativas alas obras cinematogr\u00e1ficas: 1. Asimilaci\u00f3n a las obras \u00aboriginales\u00bb; \u00a0 2. Titulares del derecho de autor; limitaci\u00f3n de algunos derechos de \u00a0 determinados autores de contribuciones; 3. Algunos otros autores de \u00a0 contribuciones. \u00a0<\/p>\n<p>Articulo 14 ter: \u00a0<\/p>\n<p>\u00abDroit de suite\u00bb sobre las obras \u00a0 de arte y los manuscritos: 1. Derecho a obtener una participaci\u00f3n en las \u00a0 reventas; 2. Legislaci\u00f3n aplicable; 3. Procedimientos. \u00a0<\/p>\n<p>Articulo 15: \u00a0<\/p>\n<p>Derecho de hacer valer los \u00a0 derechos protegidos: 1. Cuando se ha indicado el nombre del autor o cuando el \u00a0 seud\u00f3nimo no deje la menor duda sobre la identidad del autor; 2. En el caso de \u00a0 obras cinematogr\u00e1ficas; 3. Para las obras an\u00f3nimas y seud\u00f3nimas; 4. Para algunas \u00a0 obras no publicadas de autor desconocido. \u00a0<\/p>\n<p>Articulo 16: \u00a0<\/p>\n<p>Ejemplares falsificados: 1. \u00a0 Comiso; 2. Comiso de la importaci\u00f3n; 3. Legislaci\u00f3n aplicable. \u00a0<\/p>\n<p>Articulo 17: \u00a0<\/p>\n<p>Posibilidad de vigilar la \u00a0 circulaci\u00f3n, representaci\u00f3n y exposici\u00f3n de obras. \u00a0<\/p>\n<p>Articulo 18: \u00a0<\/p>\n<p>Obras existentes en el momento de \u00a0 la entrada en vigor del Convenio: 1. Podr\u00e1n protegerse cuando el plazo de \u00a0 protecci\u00f3n no haya expirado a\u00fan en el pa\u00eds de origen; 2. No podr\u00e1n protegerse \u00a0 cuando la protecci\u00f3n haya expirado en el pa\u00eds en que se reclame; 3. Aplicaci\u00f3n \u00a0 de estos principios; 4. Casos especiales. \u00a0<\/p>\n<p>Articulo 19: \u00a0<\/p>\n<p>Protecci\u00f3n m\u00e1s amplia que la \u00a0 derivada del Convenio. \u00a0<\/p>\n<p>Articulo 20: \u00a0<\/p>\n<p>Arreglos particulares entre \u00a0 pa\u00edses de la Uni\u00f3n. \u00a0<\/p>\n<p>Articulo 21: \u00a0<\/p>\n<p>Disposiciones especiales \u00a0 concernientes a los pa\u00edses en desarrollo: 1. Referencia al Anexo; 2. El Anexo es \u00a0 parte del Acta. \u00a0<\/p>\n<p>Articulo 22: \u00a0<\/p>\n<p>Asamblea: 1. Constituci\u00f3n y \u00a0 composici\u00f3n; 2. Labores; 3. Qu\u00f3rum, votaci\u00f3n, observadores; 4. Convocatoria; 5. \u00a0 Reglamento. \u00a0<\/p>\n<p>Articulo 23: \u00a0<\/p>\n<p>Comit\u00e9 Ejecutivo: 1. \u00a0 Constituci\u00f3n; 2. Composici\u00f3n; 3. N\u00famero de miembros; 4. Distribuci\u00f3n geogr\u00e1fica; \u00a0 arreglos particulares; 5. Permanencia en funciones, l\u00edmites de reelegibilidad, \u00a0 modalidades de la elecci\u00f3n; 6. Labores; 7. Convocatoria; 8. Qu\u00f3rum, votaci\u00f3n; 9. \u00a0 Observadores; 10. Reglamento. \u00a0<\/p>\n<p>Articulo 24: \u00a0<\/p>\n<p>Oficina Internacional: 1. Tareas \u00a0 en general, Director General; 2. Informaciones generales; 3. Revista; 4. \u00a0 Informaci\u00f3n a los pa\u00edses; 5. Estudios y servicios; 6. Participaci\u00f3n en \u00a0 reuniones; 7. Conferencias de revisi\u00f3n; 8. Las dem\u00e1s tareas. \u00a0<\/p>\n<p>Articulo 25: \u00a0<\/p>\n<p>Finanzas: 1. Presupuesto; 2. \u00a0 Coordinaci\u00f3n con las otras Uniones; 3. Recursos; 4. Contribuciones; posible \u00a0 prorroga del presupuesto anterior; 5. Tasas y sumas debidas; 6. Fondo de \u00a0 operaciones; 7. Anticipos del gobierno que acoge; 8. Verificaci\u00f3n de cuentas. \u00a0<\/p>\n<p>Articulo 26: \u00a0<\/p>\n<p>Modificaciones: 1. Disposiciones \u00a0 que la Asamblea podr\u00e1 modificar; propuestas; 2. Adopci\u00f3n; 3. Entrada en vigor. \u00a0<\/p>\n<p>Articulo 27: \u00a0<\/p>\n<p>Revisi\u00f3n: 1. Objetivo; 2. \u00a0 Conferencias; 3. Adopci\u00f3n. \u00a0<\/p>\n<p>Aceptaci\u00f3n y entrada en vigor del \u00a0 Acta respecto de los pa\u00edses de la Uni\u00f3n: 1. Ratificaci\u00f3n, adhesi\u00f3n; posibilidad \u00a0 de excluir algunas disposiciones; retiro de la exclusi\u00f3n; 2. Entrada en vigor de \u00a0 los art\u00edculos 1 a 21 y del anexo; 3. Entrada en vigor de los art\u00edculos 22 a 38. \u00a0<\/p>\n<p>Articulo 29: \u00a0<\/p>\n<p>Aceptaci\u00f3n y entrada en vigor \u00a0 respecto de pa\u00edses externos a la Uni\u00f3n: 1. Adhesi\u00f3n; 2. Entrada en vigor. \u00a0<\/p>\n<p>Articulo 29 bis: \u00a0<\/p>\n<p>Efecto de la aceptaci\u00f3n del Acta \u00a0 con el fin de aplicar el Articulo 14.2) del Convenio que establece la OMPI. \u00a0<\/p>\n<p>Articulo 30: \u00a0<\/p>\n<p>Reservas: 1. L\u00edmites de la \u00a0 posibilidad de formular; 2. Reservas anteriores; reserva relativa al derecho de \u00a0 traducci\u00f3n; relativo de la reserva. \u00a0<\/p>\n<p>Articulo 31: \u00a0<\/p>\n<p>Aplicabilidad a determinados \u00a0 territorios: 1. Declaraci\u00f3n; 2. Retiro de la declaraci\u00f3n; 3. Fecha de vigencia; \u00a0 4. Ni implica la aceptaci\u00f3n de situaciones de hecho. \u00a0<\/p>\n<p>Articulo 32: \u00a0<\/p>\n<p>Aplicabilidad de la presente Acta \u00a0 y de las Actas anteriores: 1. Entre pa\u00edses que ya son miembros de la Uni\u00f3n; 2. \u00a0 Entre un pa\u00eds que llega a ser miembro de la Uni\u00f3n y otros pa\u00edses miembros de la \u00a0 Uni\u00f3n; 3. Aplicabilidad del Anexo en determinadas relaciones. \u00a0<\/p>\n<p>Articulo 33: \u00a0<\/p>\n<p>Diferencia: 1. Competencia de la \u00a0 Corte Internacional de Justicia; 2. Reserva respecto de esta competencia; 3. \u00a0 Retiro de la reserva. \u00a0<\/p>\n<p>Articulo 34: \u00a0<\/p>\n<p>Cierre de algunas disposiciones \u00a0 anteriores: 1. De Actas anteriores; 2. Del Protocolo anexo al Acta de Estocolmo. \u00a0<\/p>\n<p>Articulo 35: \u00a0<\/p>\n<p>Duraci\u00f3n del Convenio: Denuncia: \u00a0 1. Duraci\u00f3n ilimitada; 2. Posibilidad de denuncia; 3. Fecha en que surtir\u00e1 \u00a0 efecto la denuncia; 4. Moratoria relativa a la denuncia. \u00a0<\/p>\n<p>Articulo 36: \u00a0<\/p>\n<p>Aplicaci\u00f3n del Convenio: 1. \u00a0 Obligaci\u00f3n de adoptar las medidas necesarias; 2. Momento a partir del cual \u00a0 existe esta obligaci\u00f3n. \u00a0<\/p>\n<p>Articulo 37: \u00a0<\/p>\n<p>Cl\u00e1usulas finales: 1. Idiomas del \u00a0 Acta; 2. Firma; 3. Copias certificadas; 4. Registro; 5. Notificaciones. \u00a0<\/p>\n<p>Disposiciones transitorias: 1. \u00a0 Ejercicio del \u00abprivilegio de cinco a\u00f1os\u00bb; 2. Oficina de la Uni\u00f3n, Director de la \u00a0 Oficina; 3. Sucesi\u00f3n de la Oficina de la Uni\u00f3n. \u00a0<\/p>\n<p>ANEXO \u00a0<\/p>\n<p>Disposiciones especiales \u00a0 relativas a los pa\u00edses en desarrollo. \u00a0<\/p>\n<p>Articulo primero: \u00a0<\/p>\n<p>Facultades ofrecidas a los pa\u00edses \u00a0 en desarrollo: 1. Posibilidad de hacer uso de algunas facultades; declaraci\u00f3n; \u00a0 2. Duraci\u00f3n de la validez de la declaraci\u00f3n; 3. Pa\u00eds que haya dejado de ser \u00a0 considerado como pa\u00edses en desarrollo; 4. Existencias de ejemplares; 5. \u00a0 Declaraciones respecto de algunos territorios; 65. L\u00edmites de la reciprocidad. \u00a0<\/p>\n<p>Articulo II: \u00a0<\/p>\n<p>Limitaciones del derecho de \u00a0 traducci\u00f3n: 1. Licencias concedidas por la autoridad competente; 2 a 4. \u00a0 Condiciones en que podr\u00e1n concederse estas licencias; 5. Usos para los que \u00a0 podr\u00e1n concederse licencias; 6. Expiraci\u00f3n de las licencias; 7. Obras compuestas \u00a0 principalmente de ilustraciones; 8. Obras retiradas de la circulaci\u00f3n; 9. \u00a0 Licencias para organismos de radiodifusi\u00f3n. \u00a0<\/p>\n<p>Articulo III: \u00a0<\/p>\n<p>Limitaciones del derecho de \u00a0 reproducci\u00f3n: 1. Licencias concedidas por la autoridad competente; 2 a 5. \u00a0 Condiciones en que se podr\u00e1n conceder estas licencias; 6. Expiraci\u00f3n de \u00a0 licencias; 7. Obras a las que se aplica el presente articulo. \u00a0<\/p>\n<p>Articulo IV: \u00a0<\/p>\n<p>Disposiciones comunes sobre \u00a0 licencias previstas en las Art\u00edculos II y III: 1 y 2. Procedimiento; 3. \u00a0 Indicaci\u00f3n del autor y del t\u00edtulo de la obra; 4. Exportaci\u00f3n de ejemplares; 5. \u00a0 Nota; 6. Remuneraci\u00f3n. \u00a0<\/p>\n<p>Articulo V: \u00a0<\/p>\n<p>Otra posibilidad de limitar el \u00a0 derecho de traducci\u00f3n. 1. R\u00e9gimen previsto por las Actas de 1886 y de 1896; 2. \u00a0 Imposibilidad de cambiar de r\u00e9gimen despu\u00e9s de haber elegido el del Art\u00edculo II; \u00a0 3. Plazo para elegir el otro r\u00e9gimen. \u00a0<\/p>\n<p>Articulo VI: \u00a0<\/p>\n<p>Posibilidad de aplicar o de \u00a0 aceptar la aplicaci\u00f3n de determinadas disposiciones del Anexo antes de quedar \u00a0 obligado por \u00e9ste: 1. Declaraci\u00f3n; 2. Depositario y fecha en que la declaraci\u00f3n \u00a0 surtir\u00e1 efectos. \u00a0<\/p>\n<p>____________ \u00a0<\/p>\n<p>Los Pa\u00edses de la Uni\u00f3n, animadas \u00a0 por el mutuo deseo de proteger del modo m\u00e1s eficaz y uniforme posible los \u00a0 derechos de los autores sobre sus obras literarias y art\u00edsticas. \u00a0<\/p>\n<p>Reconociendo la importancias de \u00a0 los trabajos de las Conferencia de Revisi\u00f3n celebrada en Estocolmo en 1987. \u00a0<\/p>\n<p>Han resulto revisar el Acta \u00a0 adoptada por la Conferencia de Estocolmo, manteniendo sin modificaci\u00f3n los \u00a0 art\u00edculos 1 a 20 y 22 a 26 de esa Acta. \u00a0<\/p>\n<p>Articulo primero \u00a0<\/p>\n<p>[Constituci\u00f3n de una Uni\u00f3n] \u00a0<\/p>\n<p>Los pa\u00edses a los cuales se aplica \u00a0 el presente Convenio est\u00e1n constituidos en Uni\u00f3n para la protecci\u00f3n de los \u00a0 derechos de los autores sobre sus obras literarias y art\u00edsticas. \u00a0<\/p>\n<p>Articulo 2 \u00a0<\/p>\n<p>[Obras protegidas: 1. \u00abObras literarias y art\u00edsticas\u00bb; 2. Posibilidad de exigir \u00a0 la fijaci\u00f3n; 3. Obras derivadas; 4. Textos oficiales; 5. Colecciones; 6. \u00a0 Obligaci\u00f3n de proteger; beneficiarios de la protecci\u00f3n; 7. Obras de artes \u00a0 aplicadas y dibujos y modelos industriales; 8. Noticias]. \u00a0<\/p>\n<p>1) Los t\u00e9rminos \u00abObras literarias \u00a0 y art\u00edsticas\u00bb comprenden todas las producciones en el campo literario, \u00a0 cient\u00edfico y art\u00edstico, cualquiera que sea el modo o forma de expresi\u00f3n, tales \u00a0 como los libros, folletos y otros escritos; las conferencias, alocuciones, \u00a0 sermones y otras obras de la misma naturaleza; las obras dram\u00e1ticas o \u00a0 dram\u00e1tico-musicales; las obras coreogr\u00e1ficas y las pantomimas; las composiciones \u00a0 musicales con o sin letra; las obras cinematogr\u00e1ficas, a las cuales se asimilan \u00a0 las obras expresadas por procedimiento an\u00e1logo a la cinematograf\u00eda; las obras de \u00a0 dibujo, pintura., arquitectura, escultura, grabado, litograf\u00eda; las obras \u00a0 fotogr\u00e1ficas a las cuales se asimilan las expresadas por procedimiento an\u00e1logo a \u00a0 la fotograf\u00eda; las obras de artes aplicadas; las ilustraciones, mapas, planos, \u00a0 croquis y obras pl\u00e1sticas relativos a la geograf\u00eda, a la topograf\u00eda, a la \u00a0 arquitectura o a las ciencias. \u00a0<\/p>\n<p>2) Sin embargo, queda reservada a \u00a0 las legislaciones de los pa\u00edses de la Uni\u00f3n la facultad de establecer que las \u00a0 obras literarias y art\u00edsticas o algunos de sus g\u00e9neros no estar\u00e1n protegidos \u00a0 mientras no hayan sido fijados en un soporte material. \u00a0<\/p>\n<p>3) Estar\u00e1n protegidas como obras \u00a0 originales, sin perjuicio de los derechos del autor de la obra original, las \u00a0 traducciones, adaptaciones, arreglos musicales y dem\u00e1s transformaciones de una \u00a0 obra literaria o art\u00edstica. \u00a0<\/p>\n<p>4) Queda reservada a las \u00a0 legislaciones de los pa\u00edses de la Uni\u00f3n de facultad de determinar la protecci\u00f3n \u00a0 que han de conceder a los textos oficiales de orden legislativo, administrativo \u00a0 o judicial, as\u00ed como a las traducciones oficiales de estos textos. \u00a0<\/p>\n<p>5) las colecciones de obras \u00a0 literarias o art\u00edsticas tales como las enciclopedias y antolog\u00edas que, por la \u00a0 selecci\u00f3n o disposici\u00f3n de las materias, constituyan creaciones intelectuales \u00a0 estar\u00e1n protegidas como tales, sin perjuicio de los derechos de los autores \u00a0 sobre cada una de las obras que forman parte de estas colecciones. \u00a0<\/p>\n<p>6) Las obras antes mencionadas \u00a0 gozar\u00e1n de protecci\u00f3n en todos los pa\u00edses de la Uni\u00f3n. Esta protecci\u00f3n \u00a0 beneficiar\u00e1 al autor y a sus derechohabientes. \u00a0<\/p>\n<p>7) Queda reservada a las \u00a0 legislaciones de los pa\u00edses de la Uni\u00f3n la facultad de regular lo concerniente a \u00a0 las obras de artes aplicadas y a los dibujos y modelos industriales, as\u00ed como lo \u00a0 relativo a los requisitos de protecci\u00f3n de estas obras, dibujos y modelos, \u00a0 teniendo en cuenta las disposiciones del Articulo 7.4) del presente Convenio. \u00a0 Para las obras protegidas \u00fanicamente como dibujos y modelos en el pa\u00eds de origen \u00a0 no se puede reclamar en otro pa\u00eds de la Uni\u00f3n mapas que la protecci\u00f3n especial \u00a0 concedida en este pa\u00eds a los dibujos y modelos; sin embargo, si tal protecci\u00f3n \u00a0 especial no se concede en este pa\u00eds, las obras ser\u00e1n protegidas como obras \u00a0 art\u00edsticas. \u00a0<\/p>\n<p>8) La protecci\u00f3n del presente \u00a0 Convenio no se aplicar\u00e1 a las noticias del d\u00eda ni de los sucesos que tengan el \u00a0 car\u00e1cter de simples informaciones de prensa. \u00a0<\/p>\n<p>Articulo 2 bis \u00a0<\/p>\n<p>[Posibilidad de limitar la protecci\u00f3n de algunas obras: 1. Determinados \u00a0 discursos; 2. Algunas utilizaciones de conferencias y alocuciones; 3. Derecho de \u00a0 reunir en colecci\u00f3n estas obras]. \u00a0<\/p>\n<p>1) Se reserva a las legislaciones \u00a0 de los pa\u00edses de la Uni\u00f3n de facultad de excluir, total o parcialmente, de la \u00a0 protecci\u00f3n prevista en el articulo anterior a los discursos pol\u00edticos y los \u00a0 pronunciados en debates judiciales. \u00a0<\/p>\n<p>2) SE reserva tambi\u00e9n a las \u00a0 legislaciones de los pa\u00edses de la Uni\u00f3n la facultad de establecer las \u00a0 condiciones en las que las conferencias, alocuciones y otras obras de la misma \u00a0 naturaleza, pronunciadas en p\u00fablico, podr\u00e1n ser reproducidas por la prensa, \u00a0 radiodifundidas, transmitidas por hilo al p\u00fablico y ser objeto de las \u00a0 comunicaciones p\u00fablicas a las que se refiere el Articulo 11 bis, 1) del presente \u00a0 Convenio, cuando tal utilizaci\u00f3n est\u00e9 justificada por el fin informativo que se \u00a0 persigue. \u00a0<\/p>\n<p>3) Sin embargo, el autor gozar\u00e1 \u00a0 del derecho exclusivo de reunir en colecci\u00f3n las obras mencionadas en los \u00a0 p\u00e1rrafos precedentes. \u00a0<\/p>\n<p>Articulo 3 \u00a0<\/p>\n<p>[Criterios para la protecci\u00f3n: 1. Nacionalidad del autor; lugar de publicaci\u00f3n \u00a0 de la obra; 2. Residencia del autor; 3. Obras \u00abpublicadas\u00bb; 4. Obras \u00abpublicadas \u00a0 simult\u00e1neamente\u00bb]. \u00a0<\/p>\n<p>1) Estar\u00e1n protegidos en virtud \u00a0 del presente Convenio: \u00a0<\/p>\n<p>a) Los autores nacionales alguno \u00a0 de los pa\u00edses de la Uni\u00f3n, por sus obras, publicadas o no; \u00a0<\/p>\n<p>b) Los autores que no sean \u00a0 nacionales de alguno de los pa\u00edses de la Uni\u00f3n por las obras que hayan publicado \u00a0 por primera vez en alguno de los pa\u00edses o, simult\u00e1neamente, en un pa\u00eds que no \u00a0 pertenezca a la Uni\u00f3n y en un pa\u00eds de la Uni\u00f3n. \u00a0<\/p>\n<p>2) Los autores no nacionales de \u00a0 alguno de los pa\u00edses de la Uni\u00f3n; pero que tengan su residencia habitual en \u00a0 alguno de ellos est\u00e1n asimilados a los nacionales de dicho pa\u00eds en lo que se \u00a0 refiere a la aplicaci\u00f3n del presente Convenio. \u00a0<\/p>\n<p>3) Se entiende por \u00abobras \u00a0 publicadas\u00bb, las que han sido editadas con el consentimiento de sus autores \u00a0 cualquiera sea el modo de fabricaci\u00f3n de los ejemplares, siempre que la cantidad \u00a0 de \u00e9stos puesta a disposici\u00f3n del p\u00fablico satisfaga razonablemente sus \u00a0 necesidades, estimadas de acuerdo con la \u00edndole de la obra. No constituyen \u00a0 publicaci\u00f3n la representaci\u00f3n de una obra dram\u00e1tica, dram\u00e1tico-musical o \u00a0 cinematogr\u00e1fica, la ejecuci\u00f3n de una obra musical, la recitaci\u00f3n publica de una \u00a0 obra literaria, la transmisi\u00f3n o radiodifusi\u00f3n de las obras literarias o \u00a0 art\u00edsticas, la exposici\u00f3n de una obra de arte ni la construcci\u00f3n de una obra \u00a0 arquitect\u00f3nica. \u00a0<\/p>\n<p>a) Ser\u00e1 considerada como \u00a0 publicada simult\u00e1neamente en varios pa\u00edses toda obra aparecida en dos o m\u00e1s de \u00a0 ellos dentro de los treinta d\u00edas siguientes a su primera publicaci\u00f3n. \u00a0<\/p>\n<p>Articulo 4 \u00a0<\/p>\n<p>[Criterios para la protecci\u00f3n de obras cinematogr\u00e1ficas, obras arquitect\u00f3nicas y \u00a0 algunas obras de artes gr\u00e1ficas y pl\u00e1sticas]. \u00a0<\/p>\n<p>Estar\u00e1n protegidos en virtud del \u00a0 presente Convenio aunque no concurran las condiciones previstas en el Articulo \u00a0 3: \u00a0<\/p>\n<p>a) los autores de las obras \u00a0 cinematogr\u00e1ficas cuyo productor tenga su sede o residencia habitual en alguno de \u00a0 los pa\u00edses de la uni\u00f3n; \u00a0<\/p>\n<p>b) los autores de obras \u00a0 arquitect\u00f3nicas edificadas en un pa\u00eds de la Uni\u00f3n o de obras de artes gr\u00e1ficas y \u00a0 pl\u00e1sticas incorporadas a un inmueble sito en un pa\u00eds de la Uni\u00f3n. \u00a0<\/p>\n<p>Articulo 5 \u00a0<\/p>\n<p>[Derechos garantizados: 1 y 2. Fuera del pa\u00eds de origen; 3. En el pa\u00eds de \u00a0 origen; 4. \u00abPa\u00eds de origen\u00bb]. \u00a0<\/p>\n<p>1) Los autores gozar\u00e1n, en lo que \u00a0 concierne a las obras protegidas en virtud del presente Convenio en los pa\u00edses \u00a0 de la Uni\u00f3n que no sean el pa\u00eds de origen de la obra, de los derechos que las \u00a0 leyes respectivas conceden en la actualidad o concedan en lo sucesivo a los \u00a0 nacionales: as\u00ed cono de los derechos especialmente establecidos por el presente \u00a0 Convenio. \u00a0<\/p>\n<p>2) El goce y el ejercicio de \u00a0 estos derechos no estar\u00e1n subordinados a ninguna formalidad y ambos son \u00a0 independientes de la existencia de protecci\u00f3n en el pa\u00eds de origen de la obra. \u00a0 Por lo dem\u00e1s, sin perjuicio de las estipulaciones del presente Convenio, la \u00a0 extensi\u00f3n de la protecci\u00f3n as\u00ed como los medios procesales acordados al autor por \u00a0 la defensa de sus derechos se regir\u00e1n exclusivamente por la legislaci\u00f3n del pa\u00eds \u00a0 en que se reclama la protecci\u00f3n. \u00a0<\/p>\n<p>3) La protecci\u00f3n en el pa\u00eds de \u00a0 origen se regir\u00e1 por la legislaci\u00f3n nacional. Sin embargo, aun cuando el autor \u00a0 no sea nacional del pa\u00eds de origen de la obra protegida por el presente \u00a0 Convenio, tendr\u00e1 en ese pa\u00eds los mismos derechos que los autores nacionales. \u00a0<\/p>\n<p>4) Se considera pa\u00eds de origen: \u00a0<\/p>\n<p>b) para las obras publicadas \u00a0 simult\u00e1neamente en un pa\u00eds que no pertenezca a la Uni\u00f3n y en una pa\u00eds de la \u00a0 Uni\u00f3n, este \u00faltimo pa\u00eds. \u00a0<\/p>\n<p>c) para las obras no publicada o \u00a0 para las obras publicadas por primera vez e n un pa\u00eds que no pertenezca a la \u00a0 Uni\u00f3n, sin publicaci\u00f3n simult\u00e1nea en un pa\u00eds de la Uni\u00f3n a que pertenezca el \u00a0 autor; sin embargo, \u00a0<\/p>\n<p>i) si se trata de obras \u00a0 cinematogr\u00e1ficas cuyo productor tenga su sede o su residencia habitual en un \u00a0 pa\u00eds de la Uni\u00f3n, \u00e9ste ser\u00e1 el pa\u00eds de origen, y \u00a0<\/p>\n<p>ii) si se trata de obras \u00a0 arquitect\u00f3nicas edificadas en un pa\u00eds de la Uni\u00f3n o de obras de artes gr\u00e1ficas y \u00a0 pl\u00e1sticas incorporadas a un inmueble sito en un pa\u00eds de la Uni\u00f3n, \u00e9ste ser\u00e1 el \u00a0 pa\u00eds de origen. \u00a0<\/p>\n<p>Articulo 6 \u00a0<\/p>\n<p>[Posibilidad de restringir la protecci\u00f3n con respecto a determinadas obras de \u00a0 nacionales de algunos pa\u00edses que no pertenezcan a la Uni\u00f3n: 1. En el pa\u00eds en que \u00a0 la obra se public\u00f3 por primera vez y en los dem\u00e1s pa\u00edses; 2. No retroactividad; \u00a0 3. Notificaci\u00f3n]. \u00a0<\/p>\n<p>1) Si un pa\u00eds que no pertenezca a \u00a0 la Uni\u00f3n no protege suficientemente las obras de los autores pertenecientes a \u00a0 alguno de los pa\u00edses de la Uni\u00f3n, este pa\u00eds podr\u00e1 restringir la protecci\u00f3n de \u00a0 las obras cuyos autores sean, en el momento de su primera publicaci\u00f3n, \u00a0 nacionales e aquel otro pa\u00eds y no tengan su residencia habitual en alguno e los \u00a0 pa\u00edses de la Uni\u00f3n. Si el pa\u00eds en que la obra se public\u00f3 por primera vez hace \u00a0 uso de esta facultad, los dem\u00e1s pa\u00edses de la Uni\u00f3n no estar\u00e1n obligados a \u00a0 conceder a las obras que de esta manera hayan quedado sometidas a un trato \u00a0 especial una protecci\u00f3n m\u00e1s amplia que la concedida en aquel pa\u00eds. \u00a0<\/p>\n<p>2) Ninguna restricci\u00f3n \u00a0 establecida al amparo del p\u00e1rrafo precedente deber\u00e1 acarrear perjuicio a los \u00a0 derechos que un autor haya adquirido sobre una obra publicada en un pa\u00eds de la \u00a0 Uni\u00f3n antes del establecimiento de aquella restricci\u00f3n. \u00a0<\/p>\n<p>3) Los pa\u00edses de la Uni\u00f3n quem en \u00a0 virtud de este art\u00edculo, restrinjan la protecci\u00f3n de los derechos de los \u00a0 autores, lo notificar\u00e1n al Director General de la Organizaci\u00f3n Mundial de la \u00a0 Propiedad Intelectual (en lo sucesivo designado con la expresi\u00f3n \u00abDirector \u00a0 General\u00bb) mediante una declaraci\u00f3n escrita en la cual se indicar\u00e1n los pa\u00edses \u00a0 incluidos en la restricci\u00f3n, lo mismo que las restricciones a que ser\u00e1n \u00a0 sometidos los derechos de los autores pertenecientes a estos pa\u00edses. El Director \u00a0 General lo comunicar\u00e1 inmediatamente a todos los pa\u00edses de la Uni\u00f3n. \u00a0<\/p>\n<p>Articulo 6 bis \u00a0<\/p>\n<p>[Derechos morales: 1. Derecho de reivindicar la paternidad de la obra; derecho \u00a0 de oponerse a algunas modificaciones de la obra y a otros atentados a la misma; \u00a0 2. Despu\u00e9s de la muerte del autor; 3. Medios procesales]. \u00a0<\/p>\n<p>1) Independientemente de los \u00a0 derechos patrimoniales del autor, e incluso despu\u00e9s de la cesi\u00f3n de estos \u00a0 derechos, el autor conservar\u00e1 el derecho de reivindicar la paternidad de la obra \u00a0 y de oponerse a cualquier deformaci\u00f3n, mutilaci\u00f3n u otra modificaci\u00f3n de la \u00a0 misma o a cualquier atentado a la misma que cause perjuicio a su honor o a su \u00a0 reputaci\u00f3n. \u00a0<\/p>\n<p>2) Los derechos reconocidos al \u00a0 autor en virtud del p\u00e1rrafo 1) ser\u00e1n mantenidos despu\u00e9s de su muerte, por lo \u00a0 menos hasta la extinci\u00f3n de sus derechos patrimoniales, y ejercidos por las \u00a0 personas o instituciones a las que la legislaci\u00f3n nacional del pa\u00eds en que se \u00a0 reclame la protecci\u00f3n reconozca derechos. Sin embargo, los pa\u00edses cuya \u00a0 legislaci\u00f3n en vigor en el momento de la ratificaci\u00f3n de la presente Acta o de \u00a0 la adhesi\u00f3n a la misma, no contenga disposiciones relativas a la protecci\u00f3n \u00a0 despu\u00e9s de la muerte del autor de todos los derechos reconocidos en virtud del \u00a0 p\u00e1rrafo 1) anterior, tiene la facultad de establecer que alguno de esos derechos \u00a0 no ser\u00e1n mantenidos despu\u00e9s de la muerte del autor. \u00a0<\/p>\n<p>3) Los medios procesales para la \u00a0 defensa de los derechos reconocidos en este articulo estar\u00e1n regidos por la \u00a0 legislaci\u00f3n del pa\u00eds en el que se reclame la protecci\u00f3n. \u00a0<\/p>\n<p>Articulo 7 \u00a0<\/p>\n<p>[Vigencia de la protecci\u00f3n: 1. En general; 2. Respecto de las obras \u00a0 cinematogr\u00e1ficas; 3. Respecto de las obras an\u00f3nimas o seud\u00f3nimas; 4. Respecto de \u00a0 las obras fotogr\u00e1ficas y las artes aplicadas; 5. Fecha de partida para calcular \u00a0 los plazos; 6. Plazos superiores; 7. Plazos menos extensos; 8. Legislaci\u00f3n \u00a0 aplicable; \u00abcotejo\u00bb de plazos]. \u00a0<\/p>\n<p>1) La protecci\u00f3n concedida por el \u00a0 presente Convenio se extender\u00e1 durante la vida del autor y cincuenta a\u00f1os \u00a0 despu\u00e9s de su muerte. \u00a0<\/p>\n<p>2) Sin embargo, para las obras \u00a0 cinematogr\u00e1ficas, los pa\u00edses de la Uni\u00f3n tienen la facultad de establecer que el \u00a0 plazo de protecci\u00f3n expire cincuenta a\u00f1os despu\u00e9s de que la obra haya sido hecha \u00a0 accesible al p\u00fablico con el consentimiento del autor, o que si tal hecho no \u00a0 ocurre durante los cincuenta a\u00f1os siguientes a la realizaci\u00f3n de la obra, la \u00a0 protecci\u00f3n expire al t\u00e9rmino de esos cincuenta a\u00f1os. \u00a0<\/p>\n<p>3) Para las obras an\u00f3nimas o \u00a0 seud\u00f3nimas, el plazo de protecci\u00f3n concedido por el presente Convenio expirar\u00e1 \u00a0 cincuenta a\u00f1os despu\u00e9s de que la obra haya sido l\u00edcitamente hecha accesible al \u00a0 p\u00fablico. Sin embargo, cuando el seud\u00f3nimo adoptado por el autor no deje dudas \u00a0 sobre su identidad, el plazo de protecci\u00f3n ser\u00e1 el previsto en el p\u00e1rrafo 1). Si \u00a0 el autor de una obra an\u00f3nima o seud\u00f3nima revela su identidad durante el \u00a0 expresado per\u00edodo, el plazo de protecci\u00f3n aplicable ser\u00e1 el previsto en el \u00a0 p\u00e1rrafo 1). Los pa\u00edses de la Uni\u00f3n no est\u00e1n obligados a proteger las obras \u00a0 an\u00f3nimas o seud\u00f3nimas, cuando haya motivos para suponer que su autor est\u00e1 muerto \u00a0 desde hace cincuenta a\u00f1os. \u00a0<\/p>\n<p>4) Queda reservada a las \u00a0 legislaciones de los pa\u00edses de la Uni\u00f3n la facultad de establecer el plazo de \u00a0 protecci\u00f3n para las obras fotogr\u00e1ficas y para las artes aplicadas, protegidas \u00a0 como obras art\u00edsticas; sin embargo, este plazo no podr\u00e1 ser inferior a un \u00a0 per\u00edodo de veinticinco a\u00f1os contados desde la realizaci\u00f3n de tales obras. \u00a0<\/p>\n<p>5) El per\u00edodo de protecci\u00f3n \u00a0 posterior a la muerte del autor y los plazos previstos en los p\u00e1rrafos 2), 3), y \u00a0 4) anteriores comenzar\u00e1n a correr desde la muerte o del hecho previsto en \u00a0 aquellos p\u00e1rrafos, pero la duraci\u00f3n de tales plazos se calcular\u00e1 a partir del \u00a0 primero de enero del a\u00f1o que siga a la muerte o al referido hecho. \u00a0<\/p>\n<p>6) Los pa\u00edses de la Uni\u00f3n tienen \u00a0 la facultad de conceder plazos de protecci\u00f3n m\u00e1s extensos que los previstos en \u00a0 los p\u00e1rrafos precedentes. \u00a0<\/p>\n<p>7) Los pa\u00edses de la Uni\u00f3n \u00a0 vinculados por el Acta de Roma del presente Convenio y que conceden en su \u00a0 legislaci\u00f3n nacional en vigor en el momento de suscribir la presente Acta plazos \u00a0 de duraci\u00f3n menos extensos que los previsto en los p\u00e1rrafos precedentes, podr\u00e1n \u00a0 mantenerlos al adherirse a la presente Acta o al ratificarla. \u00a0<\/p>\n<p>8) En todos los casos, el plazo \u00a0 de protecci\u00f3n ser\u00e1 el establecido por la ley del pa\u00eds en el que la protecci\u00f3n se \u00a0 reclame; sin embargo, a menos que la legislaci\u00f3n de este pa\u00eds no disponga otra \u00a0 cosa, la duraci\u00f3n no exceder\u00e1 del plazo fijado en el pa\u00eds de origen de la obra. \u00a0<\/p>\n<p>Articulo 7 bis \u00a0<\/p>\n<p>[Vigencia de la protecci\u00f3n de obras realizadas en colaboraci\u00f3n]. \u00a0<\/p>\n<p>Las disposiciones del articulo \u00a0 anterior son tambi\u00e9n aplicables cuando el derecho de autor pertenece en com\u00fan a \u00a0 los colaboradores de una obra, si bien el periodo consecutivo a la muerte de \u00a0 autor se calcular\u00e1 a partir de la muerte del \u00faltimo superviviente de los \u00a0 colaboradores. \u00a0<\/p>\n<p>Articulo 8 \u00a0<\/p>\n<p>[Derecho de traducci\u00f3n]. \u00a0<\/p>\n<p>Articulo 9 \u00a0<\/p>\n<p>[Derechos de reproducci\u00f3n: 1. En general; 2. Posibles excepciones; 3. \u00a0 Grabaciones sonoras y visuales]. \u00a0<\/p>\n<p>1) Los autores de obras \u00a0 literarias y art\u00edsticas protegidas por el presente Convenio gozar\u00e1n del derecho \u00a0 exclusivo de autorizar la reproducci\u00f3n de sus obras por cualquier procedimiento \u00a0 y bajo cualquier forma. \u00a0<\/p>\n<p>2) Se reserva a las legislaciones \u00a0 de los pa\u00edses de la Uni\u00f3n la facultad de permitir la reproducci\u00f3n de dichas \u00a0 obras en determinados casos especiales, con tal que esa reproducci\u00f3n no atente a \u00a0 la explotaci\u00f3n normal de la obra ni cause un perjuicio injustificado a los \u00a0 intereses leg\u00edtimos del autor. \u00a0<\/p>\n<p>3) Toda grabaci\u00f3n sonora o visual \u00a0 ser\u00e1 considerada como una reproducci\u00f3n en el sentido del presente Convenio. \u00a0<\/p>\n<p>Articulo 10 \u00a0<\/p>\n<p>[Libre utilizaci\u00f3n de obras en algunos casos: 1. Citas; 2. Ilustraci\u00f3n de la \u00a0 ense\u00f1anza; 3. Menci\u00f3n de la fuente y del autor]. \u00a0<\/p>\n<p>1) Son l\u00edcitas las citas tomadas \u00a0 de una obra que se haya hecho l\u00edcitamente accesible al p\u00fablico, a condici\u00f3n de \u00a0 que se hagan conforme a los usos honrados y en la medida justificada por el fin \u00a0 que se persiga, comprendi\u00e9ndose las citas de art\u00edculos period\u00edsticos y \u00a0 colecciones peri\u00f3dicas bajo la forma de revistas de prensa. \u00a0<\/p>\n<p>2) Se reserva a las legislaciones \u00a0 de los pa\u00edses de la Uni\u00f3n y de los arreglos particulares existentes o que se \u00a0 establezcan entre ellos lo que concierne a la facultad de utilizar l\u00edcitamente, \u00a0 en la medida justificada por el fin perseguido, las obras literarias o \u00a0 art\u00edsticas a t\u00edtulo de ilustraci\u00f3n de la ense\u00f1anza por medio de publicaciones, \u00a0 emisiones de radio o grabaciones sonoras o visuales, con tal de que esa \u00a0 utilizaci\u00f3n sea conforme a los usos honrados. \u00a0<\/p>\n<p>3) Las citas y utilizaciones a \u00a0 que se refieren los p\u00e1rrafos precedentes deber\u00e1n mencionar la fuente y el nombre \u00a0 el autor, si este nombre figura en la fuente. \u00a0<\/p>\n<p>Articulo 10 bis \u00a0<\/p>\n<p>[Otras posibilidades de libre utilizaci\u00f3n de obras: 1. De algunos art\u00edculos y \u00a0 obras radiodifundidas; 2. De obras vistas u o\u00eddas en el curso de acontecimientos \u00a0 de actualidad]: \u00a0<\/p>\n<p>1) Se reserva a las legislaciones \u00a0 de los pa\u00edses de la Uni\u00f3n la facultad de permitir la reproducci\u00f3n por la prensa \u00a0 o la radiodifusi\u00f3n o la transmisi\u00f3n por hilo al p\u00fablico de los art\u00edculos de \u00a0 actualidad de discusi\u00f3n econ\u00f3mica, pol\u00edtica o religiosa publicados en peri\u00f3dicos \u00a0 o colecciones peri\u00f3dicas, u obras radiodifundidas que tengan el mismo car\u00e1cter, \u00a0 en los casos en que la reproducci\u00f3n, la radiodifusi\u00f3n o la expresada transmisi\u00f3n \u00a0 no se hayan reservado expresamente. Sin embargo, habr\u00e1 que indicar siempre \u00a0 claramente la fuente; la sanci\u00f3n al incumplimiento de esta obligaci\u00f3n ser\u00e1 \u00a0 determinada por la legislaci\u00f3n del pa\u00eds en el que se reclame la protecci\u00f3n. \u00a0<\/p>\n<p>2) Queda igualmente reservada a \u00a0 las legislaciones de los pa\u00edses de la Uni\u00f3n la facultad de establecer las \u00a0 condiciones en que, con ocasi\u00f3n de las informaciones relativas a acontecimientos \u00a0 de actualidad por medio de la fotograf\u00eda o la cinematogr\u00e1fica, o por \u00a0 radiodifusi\u00f3n o transmisi\u00f3n por hilo al p\u00fablico, puedan ser reproducidas y \u00a0 hechas accesibles al p\u00fablico, en la medida justificada por el fin de la \u00a0 informaci\u00f3n, las obras literarias o art\u00edsticas que hayan de ser vistas u o\u00eddas \u00a0 en el curso del acontecimiento. \u00a0<\/p>\n<p>Articulo 11 \u00a0<\/p>\n<p>[Algunos derechos correspondientes a obras dram\u00e1ticas y musicales: 1. Derecho de \u00a0 representaci\u00f3n o de ejecuci\u00f3n p\u00fablicas y de transmisi\u00f3n p\u00fablica de una \u00a0 representaci\u00f3n o ejecuci\u00f3n; 2. En lo que se refiere a las traducciones]. \u00a0<\/p>\n<p>1) Los autores de la obras \u00a0 dram\u00e1ticas, dram\u00e1tico-musicales y musicales gozar\u00e1n del derecho exclusivo de \u00a0 autorizar; 1\u00ba, la representaci\u00f3n uy la ejecuci\u00f3n p\u00fablica de sus obras, \u00a0 comprendidas la representaci\u00f3n u la ejecuci\u00f3n p\u00fablica por todos los medios o \u00a0 procedimientos; 2\u00ba, la transmisi\u00f3n p\u00fablica, por cualquier medio, de la \u00a0 representaci\u00f3n y de la ejecuci\u00f3n de sus obras. \u00a0<\/p>\n<p>2) Los mismos derechos se \u00a0 conceden a los autores de obras dram\u00e1ticas o dram\u00e1tico-musicales durante todo el \u00a0 plazo de protecci\u00f3n de sus derechos sobre la obra original,. En lo que se \u00a0 refiere a la traducci\u00f3n de sus obras. \u00a0<\/p>\n<p>Articulo 11 bis \u00a0<\/p>\n<p>[Derechos de radiodifusi\u00f3n y derechos conexos: 1. Radiodifusi\u00f3n y otras \u00a0 comunicaciones sin hilo, comunicaci\u00f3n p\u00fablica por hilo o sin hilo de la obra \u00a0 radiodifundida, comunicaci\u00f3n p\u00fablica mediante altavoz o cualquier otro \u00a0 instrumento an\u00e1logo de la obra radiodifundida; 2. Licencias obligatorias; 3. \u00a0 Grabaci\u00f3n; grabaciones ef\u00edmeras]. \u00a0<\/p>\n<p>1) Los autores de obras \u00a0 literarias y art\u00edsticas gozar\u00e1n del derecho exclusivo de autorizar: 1\u00ba, la \u00a0 radiodifusi\u00f3n de sus obras o la comunicaci\u00f3n p\u00fablica de estas obras por \u00a0 cualquier medio que sirva para difundir sin hilo los signos, los sonidos o las \u00a0 im\u00e1genes; 2\u00ba. Toda comunicaci\u00f3n p\u00fablica, por hilo o sin hilo, de la obra \u00a0 radiodifundida, cuando esta comunicaci\u00f3n se haga por distinto organismo que el \u00a0 de origen; 3\u00ba, la comunicaci\u00f3n publica mediante altavoz o mediante cualquier \u00a0 otro instrumento an\u00e1logo transmisor de signos, de sonido o de im\u00e1genes de la \u00a0 obra radiodifundida. \u00a0<\/p>\n<p>2) Corresponde a las \u00a0 legislaciones de los pa\u00edses de la Uni\u00f3n establecer los condiciones para el \u00a0 ejercicio de los derechos a que se refiere el p\u00e1rrafo 1) anterior, pero estas \u00a0 condiciones no tendr\u00e1n m\u00e1s que un resultado estrictamente limitado al pa\u00eds que \u00a0 las haya establecido y no podr\u00e1n en ning\u00fan caso atentar al derecho moral del \u00a0 autor, ni al derecho que le corresponda para obtener una remuneraci\u00f3n \u00a0 equitativa, fijada, en defecto de acuerdo amistoso, por la autoridad competente. \u00a0<\/p>\n<p>3) Salvo estipulaci\u00f3n en \u00a0 contrario, una autorizaci\u00f3n concedida de conformidad con el p\u00e1rrafo 1) del \u00a0 presente articulo no comprender\u00e1 la autorizaci\u00f3n para grabar, por medio de \u00a0 instrumentos que sirvan para la fijaci\u00f3n de sonidos o im\u00e1genes, la obra \u00a0 radiodifundida. Sin embargo, queda reservado a las legislaciones de los pa\u00edses \u00a0 de la Uni\u00f3n establecer el r\u00e9gimen de las grabaciones ef\u00edmeras realizadas por un \u00a0 organismo de radiodifusi\u00f3n por sus propios medios y para sus emisiones. Estas \u00a0 legislaciones podr\u00e1n autorizar la conservaci\u00f3n de esas grabaciones en archivos \u00a0 oficiales en raz\u00f3n de su excepcional car\u00e1cter de documentaci\u00f3n. \u00a0<\/p>\n<p>Articulo 11 ter \u00a0<\/p>\n<p>[Algunos derechos correspondientes a las obras literarias: 1. Derecho de \u00a0 recitaci\u00f3n p\u00fablica y de transmisi\u00f3n p\u00fablica de una recitaci\u00f3n; 2. En lo que \u00a0 concierne a las traducciones]. \u00a0<\/p>\n<p>1) Los autores de obras \u00a0 literarias gozar\u00e1n del derecho exclusivo de autorizar: 1\u00ba, la recitaci\u00f3n publica \u00a0 de sus obras, comprendida la recitaci\u00f3n p\u00fablica por cualquier medio o \u00a0 procedimiento; 2. La transmisi\u00f3n p\u00fablica, por cualquier medio, de la recitaci\u00f3n \u00a0 de sus obras. \u00a0<\/p>\n<p>2) Iguales derechos se conceden a \u00a0 los autores de obras literarias durante todo el plazo de protecci\u00f3n de sus \u00a0 derechos sobre la obra original, en lo que concierne a la traducci\u00f3n de sus \u00a0 obras. \u00a0<\/p>\n<p>Articulo 12 \u00a0<\/p>\n<p>[Derecho de adaptaci\u00f3n, arreglo y \u00a0 otra transformaci\u00f3n]. \u00a0<\/p>\n<p>Los autores de obras literarias o \u00a0 art\u00edsticas gozar\u00e1n del derecho exclusivo de autorizar las adaptaciones, arreglos \u00a0 y otras transformaciones de sus obras. \u00a0<\/p>\n<p>Articulo 13 \u00a0<\/p>\n<p>[Posibilidad de limitar el derecho de grabar obras musicales y la letra \u00a0 respectiva: 1. Licencias obligatorias; 2. Medidas transitorias; 3. Decomiso de \u00a0 la importaci\u00f3n de ejemplares hechos sin la autorizaci\u00f3n del autor]. \u00a0<\/p>\n<p>1) Cada pa\u00eds de la Uni\u00f3n, podr\u00e1, \u00a0 por lo que le concierne, establecer reservas y condiciones en lo relativo al \u00a0 derecho exclusivo de autor de una obra musical y del autor de la letra, cuya \u00a0 grabaci\u00f3n con la obra musical haya sido ya autorizada por este \u00faltimo, para \u00a0 autorizar la grabaci\u00f3n sonora de dicha obra musical, con la letra, en su caso; \u00a0 pero todas las reservas y condiciones de esta naturaleza no tendr\u00e1n m\u00e1s que in \u00a0 efecto estrictamente limitado al pa\u00eds que las haya establecido y no podr\u00e1n en \u00a0 ning\u00fan caso, atentar al derecho que corresponde al autor para contener una \u00a0 remuneraci\u00f3n equitativa fijada, en defecto de acuerdo amistoso, por la autoridad \u00a0 competente. \u00a0<\/p>\n<p>2) Las grabaciones de obras \u00a0 musicales que hayan sido realizadas en un pa\u00eds de la Uni\u00f3n conforme al articulo \u00a0 13.3) de los Convenios suscritos en Roma el 2 de junio de 1928 y en Bruselas el \u00a0 26 de junio de 1948 podr\u00e1n, en este pa\u00eds, ser objeto de reproducciones sin el \u00a0 consentimiento del autor de la obra musical, hasta la expiraci\u00f3n de un periodo \u00a0 de dos a\u00f1os a contar de la fecha en que dicho pa\u00eds quede obligado por la \u00a0 presente Acta. \u00a0<\/p>\n<p>3) las grabaciones hechas en \u00a0 virtud de los p\u00e1rrafos 1) y 2) del presente articulo e importadas, sin \u00a0 autorizaci\u00f3n de las partes interesadas, en un pa\u00eds en que estas grabaciones no \u00a0 sean l\u00edcitas, podr\u00e1n ser decomisadas en este pa\u00eds. \u00a0<\/p>\n<p>Articulo 14 \u00a0<\/p>\n<p>[Derechos cinematogr\u00e1ficos y derecho conexos: 1. Adaptaci\u00f3n y reproducci\u00f3n \u00a0 cinematogr\u00e1ficas, distribuci\u00f3n, representaci\u00f3n, ejecuci\u00f3n p\u00fablica y transmisi\u00f3n \u00a0 por hilo al p\u00fablico de las obras as\u00ed adoptadas o reproducidas; 2. Adaptaci\u00f3n de \u00a0 realizaciones cinematogr\u00e1ficas; 3. Falta de licencias obligatorias]. \u00a0<\/p>\n<p>2) la adaptaci\u00f3n, bajo cualquier \u00a0 forma art\u00edstica, de las realizaciones cinematogr\u00e1ficas extra\u00eddas de obras \u00a0 literarias o art\u00edsticas quedan sometida, sin perjuicio de la autorizaci\u00f3n de los \u00a0 autores de la obra cinematogr\u00e1fica, a la autorizaci\u00f3n de los autores de las \u00a0 obras originales. \u00a0<\/p>\n<p>3) Las disposiciones del Art\u00edculo \u00a0 13.1) no son aplicables. \u00a0<\/p>\n<p>Articulo 14 bis \u00a0<\/p>\n<p>[Disposiciones especiales relativas a las obras cinematogr\u00e1ficas: 1. Asimilaci\u00f3n \u00a0 a las obras \u00aboriginales\u00bb; 2. Titulares del derecho de autor; limitaci\u00f3n de \u00a0 algunos derechos de determinados autores de contribuciones; 3. Algunos otros \u00a0 autores de contribuciones]. \u00a0<\/p>\n<p>1) Sin perjuicio de los derechos \u00a0 del autor de las obras que hayan podido ser adaptadas o reproducidas, la obra \u00a0 cinematogr\u00e1fica se protege como obra original. El titular del derecho de autor \u00a0 sobre la obra cinematogr\u00e1fica gozar\u00e1 de los mismos derechos que el autor de una \u00a0 obra original, comprendidos los derechos a los que se refiere el art\u00edculo \u00a0 anterior. \u00a0<\/p>\n<p>2) a) La determinaci\u00f3n de los \u00a0 titulares del derecho de autor sobre la obra cinematogr\u00e1fica queda reservada a \u00a0 la legislaci\u00f3n del pa\u00eds en que la protecci\u00f3n se reclame. \u00a0<\/p>\n<p>b) Sin embargo, en los pa\u00edses de \u00a0 la Uni\u00f3n en que la legislaci\u00f3n reconoce entre estos titulares a los autores de \u00a0 las contribuciones aportadas a la realizaci\u00f3n de la obra cinematogr\u00e1fica, \u00e9stos, \u00a0 una vez que se han comprometido a aportar tales contribuciones, no podr\u00e1n, salvo \u00a0 estipulaci\u00f3n en contrario o particular, oponerse a la reproducci\u00f3n, \u00a0 distribuci\u00f3n, representaci\u00f3n y ejecuci\u00f3n p\u00fablica, transmisi\u00f3n por hilo al \u00a0 p\u00fablico, radiodifusi\u00f3n, comunicaci\u00f3n al p\u00fablico, subtitulado y doblaje de los \u00a0 textos, de la obra cinematogr\u00e1fica. \u00a0<\/p>\n<p>c) Para determinar si la forma \u00a0 del compromiso referido m\u00e1s arriba debe, por aplicaci\u00f3n del apartado b) \u00a0 anterior, establecer o no en contrato escrito o en un acto escrito equivalente, \u00a0 se estar\u00e1 a lo que disponga la legislaci\u00f3n del pa\u00eds de la Uni\u00f3n en que disponga \u00a0 la legislaci\u00f3n del pa\u00eds de la Uni\u00f3n en que el productor de la obra \u00a0 cinematogr\u00e1fica tenga su sede o su residencia habitual. En todo caso, queda \u00a0 reservada a la legislaci\u00f3n del pa\u00eds de la Uni\u00f3n en que la protecci\u00f3n se reclame, \u00a0 la facultad de establecer que este compromiso conste en contrato escrito o un \u00a0 acto escrito equivalente. Los pa\u00edses que hagan uso de esta facultad deber\u00e1n \u00a0 notificarlo al Director General mediante una declaraci\u00f3n escrita que ser\u00e1 \u00a0 inmediatamente comunicadas por este \u00faltimo a todos los dem\u00e1s \u00a0<\/p>\n<p>d) Por estipulaci\u00f3n en contrario \u00a0 o particular se entender\u00e1 toda condici\u00f3n restrictiva que pueda resultar de dicho \u00a0 compromiso. \u00a0<\/p>\n<p>3) a menos que la legislaci\u00f3n \u00a0 nacional no disponga otra cosa, las disposiciones del apartado 2) b) anterior no \u00a0 ser\u00e1n aplicables a los autores de los guiones, di\u00e1logos y obras \u00a0 cinematogr\u00e1ficas, ni al realizador principal de \u00e9sta. Sin embargo, los pa\u00edses de \u00a0 la Uni\u00f3n cuya legislaci\u00f3n no contenga disposiciones que establezcan la \u00a0 aplicaci\u00f3n del p\u00e1rrafo 2) b) citado a dicho realizador deber\u00e1n notificarlo al \u00a0 Director General mediante declaraci\u00f3n escrita que ser\u00e1 inmediatamente comunicada \u00a0 por este \u00faltimo a todos los dem\u00e1s pa\u00edses de la Uni\u00f3n. \u00a0<\/p>\n<p>Articulo 14 ter \u00a0<\/p>\n<p>[\u00abDroit de suite\u00bb sobre las obras de arte y los manuscritos: 1. Derecho a \u00a0 obtener una participaci\u00f3n en las reventas; 2. Legislaci\u00f3n aplicable; 3. \u00a0 Procedimiento]. \u00a0<\/p>\n<p>1) En lo que concierne a las \u00a0 obras de arte originales y a los manuscritos originales de escritores y \u00a0 compositores, el autor-o, despu\u00e9s de su muerte, las personas o instituciones a \u00a0 las que la legislaci\u00f3n nacional confiera derechos-gozar\u00e1n del derecho \u00a0 inalienable a obtener una participaci\u00f3n en las ventas de la obra posteriores a \u00a0 la primera cesi\u00f3n operada por el autor. \u00a0<\/p>\n<p>2) La protecci\u00f3n prevista en el \u00a0 p\u00e1rrafo anterior no ser\u00e1 exigible en los pa\u00edses de la Uni\u00f3n mientras la \u00a0 legislaci\u00f3n nacional del autor no admita esta protecci\u00f3n y en la medida en que \u00a0 la permita la legislaci\u00f3n del pa\u00eds en que eta protecci\u00f3n sea reclamada. \u00a0<\/p>\n<p>3) Las legislaciones nacionales \u00a0 determinaran las modalidades de la percepci\u00f3n y el monto a percibir. \u00a0<\/p>\n<p>Articulo 15 \u00a0<\/p>\n<p>[Derecho de hacer valer los derechos protegidos: 1. Cuando se ha indicado el \u00a0 nombre del autor o cuando el seud\u00f3nimo no deje la menor duda sobre la identidad \u00a0 del autor; 2. En el caso de obras cinematogr\u00e1ficas; 3. Para las obras an\u00f3nimas y \u00a0 seud\u00f3nimas; 4. Para algunas obras no publicadas de autor desconocido]. \u00a0<\/p>\n<p>1) Para que los autores de las \u00a0 obras literarias y art\u00edsticas protegidas por el presente Convenio ser\u00e1n, salvo \u00a0 prueba en contrario, considerados como tales y admitidos, en consecuencia, ante \u00a0 los tribunales de los pa\u00edses de la Uni\u00f3n para demandar a los defraudadores, \u00a0 bastar\u00e1 que su nombre aparezca estampado en la ora en la forma usual. El \u00a0 presente p\u00e1rrafo se aplicar\u00e1 tambi\u00e9n cuando ese nombre sea seud\u00f3nimo que por lo \u00a0 conocido no deje la menor duda sobre la identificaci\u00f3n del autor. \u00a0<\/p>\n<p>2) se presume productor de la \u00a0 obra cinematogr\u00e1fica, salvo prueba en contrario, la persona f\u00edsica o moral cuyo \u00a0 nombre aparezca en dicha obra en la forma usual. \u00a0<\/p>\n<p>3) Para las obras an\u00f3nimas y para \u00a0 las obras seud\u00f3nimas que no sean aqu\u00e9llas de las que se ha hecho menci\u00f3n en el \u00a0 p\u00e1rrafo 1) anterior, el editor cuyo nombre aparezca estampado en la obra ser\u00e1 \u00a0 considerado, sin necesidad de otras pruebas, representante del autor; con esta \u00a0 cualidad, estar\u00e1 legitimado para defender y hacer valer los derechos de aqu\u00e9l. \u00a0 La disposici\u00f3n del presente p\u00e1rrafo dejar\u00e1 de ser aplicable cuando el autor haya \u00a0 revelado su identidad y justificado su calidad de tal. \u00a0<\/p>\n<p>4) a) Para las obras no \u00a0 publicadas de las que resulte desconocida la identidad del autor pero por las \u00a0 que se pueda suponer que \u00e9l es nacional de un pa\u00eds de la Uni\u00f3n queda reservada a \u00a0 la legislaci\u00f3n de eses pa\u00eds la facultad de designar la autoridad competente para \u00a0 presentar a ese autor y defender y hacer vales los derechos del mismo en los \u00a0 pa\u00edses de la Uni\u00f3n. \u00a0<\/p>\n<p>b) Los pa\u00edses de la Uni\u00f3n que, en \u00a0 virtud de lo establecido anteriormente, procedan a esa designaci\u00f3n, lo \u00a0 notificar\u00e1n al Director General mediante una declaraci\u00f3n escrita en la que se \u00a0 indicar\u00e1 toda la informaci\u00f3n relativa a la autoridad designada. El Director \u00a0 General comunicar\u00e1 inmediatamente esta declaraci\u00f3n a todos los dem\u00e1s pa\u00edses de \u00a0 la Uni\u00f3n. \u00a0<\/p>\n<p>Articulo 16 \u00a0<\/p>\n<p>[Ejemplares falsificados: 1. Comiso; 2. Comiso de la importaci\u00f3n; 3. Legislaci\u00f3n \u00a0 aplicable]. \u00a0<\/p>\n<p>2) Las disposiciones del p\u00e1rrafo \u00a0 precedente ser\u00e1n tambi\u00e9n aplicables a las reproducciones procedentes de un pa\u00eds \u00a0 en que la obra no este protegida o haya dejado de estarlo. \u00a0<\/p>\n<p>3) El comiso tendr\u00e1 lugar \u00a0 conforme a la legislaci\u00f3n de cada pa\u00eds. \u00a0<\/p>\n<p>Articulo 17 \u00a0<\/p>\n<p>[Posibilidad de vigilar la circulaci\u00f3n, representaci\u00f3n y exposici\u00f3n de obras]. \u00a0<\/p>\n<p>Las disposiciones del presente \u00a0 Convenio no podr\u00e1n suponer perjuicio, cualquiera que sea, al derecho que \u00a0 corresponde al gobierno de cada pa\u00eds de la Uni\u00f3n de permitir, vigilar o \u00a0 prohibir, mediante medidas legislativas o de polic\u00eda interior, la circulaci\u00f3n, \u00a0 la representaci\u00f3n, la exposici\u00f3n cualquier obra o producci\u00f3n, respecto a la cual \u00a0 la autoridad competente hubiere de ejercer este derecho. \u00a0<\/p>\n<p>Articulo 18 \u00a0<\/p>\n<p>[Obras existentes en el momento de la entrada en vigor del Convenio: !. Podr\u00e1n \u00a0 protegerse cuando el plazo de protecci\u00f3n no haya expirado a\u00fan en el pa\u00eds de \u00a0 origen; 2. No podr\u00e1n protegerse cuando la protecci\u00f3n haya expirado en el pa\u00eds en \u00a0 que se reclame: 3. Aplicaci\u00f3n de estos principios; 4. Casos especiales]. \u00a0<\/p>\n<p>1) El presente Convenio se \u00a0 aplicar\u00e1 a todas las obras que, en el momento de su entrada en vigor, no hayan \u00a0 paso al dominio p\u00fablico en su pa\u00eds de origen por expiraci\u00f3n de los plazos de \u00a0 protecci\u00f3n. \u00a0<\/p>\n<p>2) Sin embargo, si una obra, por \u00a0 expiraci\u00f3n del plazo de protecci\u00f3n que le haya sido anteriormente concedido \u00a0 hubieses pasado al dominio p\u00fablico en el pa\u00eds en que la protecci\u00f3n se reclame, \u00a0 esta obra no ser\u00e1 protegida all\u00ed de nuevo. \u00a0<\/p>\n<p>3) La aplicaci\u00f3n de este \u00a0 principio tendr\u00e1 lugar conforme a las estipulaciones contenidas en los convenios \u00a0 especiales existentes o que se establezcan a este efecto entre pa\u00edses de la \u00a0 Uni\u00f3n. En defecto de tales estipulaciones, los pa\u00edses respectivos regular\u00e1n, \u00a0 cada uno en lo que le concierne, las modalidades relativas a esa aplicaci\u00f3n. \u00a0<\/p>\n<p>4) Las disposiciones que preceden \u00a0 ser\u00e1n aplicables tambi\u00e9n en el caso de nuevas adhesiones a la Uni\u00f3n y en el caso \u00a0 en que la protecci\u00f3n sea ampliada por aplicaci\u00f3n del Articulo 7 o por renuncia a \u00a0 reservas. \u00a0<\/p>\n<p>Articulo 19 \u00a0<\/p>\n<p>[Protecci\u00f3n m\u00e1s amplia que la \u00a0 derivada del Convenio]. \u00a0<\/p>\n<p>Las disposiciones del presente \u00a0 Convenio no impedir\u00e1n reivindicar la aplicaci\u00f3n del disposiciones m\u00e1s amplias \u00a0 que hayan sido dictadas por la legislaci\u00f3n de alguno de los pa\u00edses de la Uni\u00f3n. \u00a0<\/p>\n<p>Articulo 20 \u00a0<\/p>\n<p>[Arreglos particulares entre \u00a0 pa\u00edses de la Uni\u00f3n]. \u00a0<\/p>\n<p>Los gobiernos de los pa\u00edses de la \u00a0 Uni\u00f3n se reservan el derecho de adoptar entre ellos Arreglos particulares, \u00a0 siempre que estos Arreglos confieran a los autores derechos m\u00e1s amplios que los \u00a0 concedidos por este Convenio, o que comprendan otras estipulaciones que no sean \u00a0 contrarias al presente Convenio. Las disposiciones de los Arreglos existentes \u00a0 que respondan a las condiciones antes citadas continuar\u00e1n siendo aplicables. \u00a0<\/p>\n<p>Articulo 21 \u00a0<\/p>\n<p>[Disposiciones especiales concernientes a los pa\u00edses en desarrollo: 1. \u00a0 Referencia al Anexo; 2. El Anexo es parte del Acta]. \u00a0<\/p>\n<p>1) En el Anexo figuran \u00a0 disposiciones especiales concernientes a los pa\u00edses en desarrollo. \u00a0<\/p>\n<p>2) Con reserva de las \u00a0 disposiciones del Articulo 28.1) b), el Anexo forma parte integrante de la \u00a0 presente Acta. \u00a0<\/p>\n<p>Articulo 22 \u00a0<\/p>\n<p>1) a) La Uni\u00f3n tendr\u00e1 una \u00a0 Asamblea compuesta por los pa\u00edses de la uni\u00f3n obligados por los Art\u00edculos 22 a \u00a0 26. \u00a0<\/p>\n<p>b) El gobierno de cada pa\u00eds \u00a0 miembro estar\u00e1 representado por un delegado que podr\u00e1 ser asistido por \u00a0 suplentes, asesores y experto. \u00a0<\/p>\n<p>c) Los gastos de cada delegaci\u00f3n \u00a0 ser\u00e1n sufragados por el gobierno que la haya designado. \u00a0<\/p>\n<p>2) a) La Asamblea: \u00a0<\/p>\n<p>i) Tratar\u00e1 de todas las \u00a0 cuestiones relativas al mantenimiento, y desarrollo de la Uni\u00f3n y a la \u00a0 aplicaci\u00f3n del presente Convenio; \u00a0<\/p>\n<p>ii) Dar\u00e1 instrucciones a la \u00a0 Oficina Internacional de la Propiedad Intelectual (llamada en lo sucesivo \u00abla \u00a0 Oficina Internacional\u00bb), a la cual se hace referencia en el Convenio que \u00a0 establece la Organizaci\u00f3n Mundial de la Propiedad Intelectual (llamada en lo \u00a0 sucesivo \u00abla Organizaci\u00f3n\u00bb), en relaci\u00f3n con la preparaci\u00f3n de las conferencias \u00a0 de revisi\u00f3n, teniendo debidamente en cuenta las observaciones de los pa\u00edses de \u00a0 la Uni\u00f3n que no est\u00e9n obligados por los Art\u00edculos 22 a 26; \u00a0<\/p>\n<p>iii) Examinar\u00e1 y aprobar\u00e1 los \u00a0 informes y las actividades del Director General de la Organizaci\u00f3n relativos a \u00a0 la Uni\u00f3n y le dar\u00e1 todas las instrucciones necesarias en lo referente a los \u00a0 asuntos de la competencia de la Uni\u00f3n; \u00a0<\/p>\n<p>iv) Elegir\u00e1 a los miembros del \u00a0 Comit\u00e9 Ejecutivo de la Asamblea; \u00a0<\/p>\n<p>v) Fijar\u00e1 el programa, adoptar\u00e1 \u00a0 el presupuesto trienal de la Uni\u00f3n y aprobar\u00e1 sus balances de cuentas; \u00a0<\/p>\n<p>vii) Adoptar\u00e1 el reglamento \u00a0 financiero de la Uni\u00f3n; \u00a0<\/p>\n<p>viii) Crear\u00e1 los comit\u00e9s de \u00a0 expertos y grupos de trabajo que considere convenientes para alcanzar los \u00a0 objetivos de la Uni\u00f3n; \u00a0<\/p>\n<p>ix) Decidir\u00e1 qu\u00e9 pa\u00edses no \u00a0 miembros de la Uni\u00f3n y qu\u00e9 organizaciones intergubernamentales e internacionales \u00a0 no gubernamentales podr\u00e1n ser admitidos en sus reuniones a t\u00edtulo de \u00a0 observadores; \u00a0<\/p>\n<p>x) Adoptar\u00e1 los acuerdos de \u00a0 modificaci\u00f3n de los Articulo 22 a 26; \u00a0<\/p>\n<p>xi) Emprender\u00e1 cualquier otra \u00a0 acci\u00f3n apropiada para alcanzar los objetivos de la Uni\u00f3n; \u00a0<\/p>\n<p>xii) Ejercer\u00e1 las dem\u00e1s funciones \u00a0 que implique el presente Convenio; \u00a0<\/p>\n<p>xiii) Ejercer\u00e1, con la condici\u00f3n \u00a0 de que los acepte, los derechos que le confiere el Convenio que establece la \u00a0 Organizaci\u00f3n. \u00a0<\/p>\n<p>b) En cuestiones que interesen \u00a0 igualmente a otras Uniones administradas por la Organizaci\u00f3n, la Asamblea tomar\u00e1 \u00a0 sus decisiones teniendo en cuenta el dictamen del Comit\u00e9 de Coordinaci\u00f3n de la \u00a0 Organizaci\u00f3n. \u00a0<\/p>\n<p>3) a) Cada pa\u00eds miembro de la \u00a0 Asamblea dispondr\u00e1 de un voto. \u00a0<\/p>\n<p>b) La mitad de los pa\u00edses \u00a0 miembros de la Asamblea constituir\u00e1 el qu\u00f3rum. \u00a0<\/p>\n<p>c) No obstante las disposiciones \u00a0 del apartado b), si el n\u00famero de pa\u00edses representados en cualquier sesi\u00f3n es \u00a0 inferior a la mitad, pero igual o superior a la tercera parte de los pa\u00edses \u00a0 miembros de la Asamblea \u00e9sta podr\u00e1 tomar decisiones; sin embargo, las decisiones \u00a0 de la Asamblea, salvo aquellas relativas a su propio procedimiento, s\u00f3lo ser\u00e1n \u00a0 ejecutivas si se cumplen los siguientes requisitos. La Oficina Internacional \u00a0 comunicar\u00e1 dichas decisiones a los pa\u00edses miembros que no estaban representados, \u00a0 invit\u00e1ndolos a expresar por escrito su voto o su abstenci\u00f3n dentro de un per\u00edodo \u00a0 de tres meses a contar desde la fecha de la comunicaci\u00f3n. Si, al expirar dicho \u00a0 plazo, el n\u00famero de pa\u00edses que hayan as\u00ed expresado su voto o su abstenci\u00f3n \u00a0 asciende al n\u00famero de pa\u00edses que faltaban para que se lograse el qu\u00f3rum en la \u00a0 sesi\u00f3n, dichas decisiones ser\u00e1n ejecutivas, siempre que la mismo tiempo se \u00a0 mantenga la mayor\u00eda necesaria. \u00a0<\/p>\n<p>d) Sin perjuicio de las \u00a0 disposiciones del articulo 26.2), las decisiones de la Asamblea se tomar\u00e1n por \u00a0 mayor\u00eda de dos tercios de los votos emitidos. \u00a0<\/p>\n<p>e) la abstenci\u00f3n no se \u00a0 considerar\u00e1 como un voto. \u00a0<\/p>\n<p>f) Cada delegado no podr\u00e1 \u00a0 representar m\u00e1s que a un solo pa\u00eds y no podr\u00e1 votar m\u00e1s que en nombre de \u00e9l. \u00a0<\/p>\n<p>g) Los pa\u00edses de la Uni\u00f3n que no \u00a0 sean miembros de la Asamblea ser\u00e1n admitidos a sus reuniones en calidad de \u00a0 observadores. \u00a0<\/p>\n<p>4) a) La Asamblea se reunir\u00e1 una \u00a0 vez cada tres a\u00f1os en sesi\u00f3n ordinaria, mediante convocatoria del Director \u00a0 General y, salvo en casos excepcionales, durante el mismo per\u00edodo y en el mismo \u00a0 lugar donde la Asamblea General de la Organizaci\u00f3n. \u00a0<\/p>\n<p>b) La Asamblea se reunir\u00e1 en \u00a0 sesi\u00f3n extraordinaria, mediante convocatoria del Director General, a petici\u00f3n \u00a0 del Comit\u00e9 Ejecutivo o a petici\u00f3n de una cuarta parte de los pa\u00edses miembros de \u00a0 la Asamblea. \u00a0<\/p>\n<p>5) La Asamblea adoptar\u00e1 su propio \u00a0 reglamento interior. \u00a0<\/p>\n<p>Articulo 23 \u00a0<\/p>\n<p>[Comit\u00e9 Ejecutivo: 1. Constituci\u00f3n; 2. Composici\u00f3n; 3. N\u00famero de miembros; 4. \u00a0 Distribuci\u00f3n geogr\u00e1fica; arreglos particulares; 5. Permanencia en funciones, \u00a0 l\u00edmites de reelegibilidad, modalidades de la elecci\u00f3n; 6. Labores; 7. \u00a0 Convocatoria; 8. Qu\u00f3rum, votaci\u00f3n; 9. Observadores; 10. Reglamento]. \u00a0<\/p>\n<p>1) La Asamblea tendr\u00e1 un Comit\u00e9 \u00a0 Ejecutivo. \u00a0<\/p>\n<p>2) a) El Comit\u00e9 Ejecutivo estar\u00e1 \u00a0 compuesto por los pa\u00edses elegidos por la Asamblea entre los pa\u00edses miembros de \u00a0 la misma. Adem\u00e1s el pa\u00eds en cuyo territorio tenga su Sede la Organizaci\u00f3n \u00a0 dispondr\u00e1, ex officio, de un puesto en el Comit\u00e9, sin perjuicio de lo dispuesto \u00a0 en el Articulo 25.7) b). \u00a0<\/p>\n<p>b) El gobierno de cada pa\u00eds \u00a0 miembro del Comit\u00e9 Ejecutivo estar\u00e1 representado por un delegado que podr\u00e1 ser \u00a0 asistido por suplentes, asesores y expertos. \u00a0<\/p>\n<p>c) Los gastos de cada delegaci\u00f3n \u00a0 ser\u00e1n sufragados por el gobierno que la haya designado. \u00a0<\/p>\n<p>3) El n\u00famero de pa\u00edses miembros \u00a0 del Comit\u00e9 Ejecutivo corresponder\u00e1 a la cuarta parte del n\u00famero de los pa\u00edses \u00a0 miembros e la Asamblea. En el c\u00e1lculo de los puestos a proveerse, no se tomar\u00e1 \u00a0 en consideraci\u00f3n el resto que quede despu\u00e9s de dividir por cuatro. \u00a0<\/p>\n<p>4) En la elecci\u00f3n de los miembros \u00a0 del Comit\u00e9 Ejecutivo, la Asamblea tendr\u00e1 en cuenta una distribuci\u00f3n geogr\u00e1fica \u00a0 equitativa y la necesidad de que todos los pa\u00edses que formen parte de los \u00a0 Arreglos particulares que pudieran se establecidos en relaci\u00f3n con la Uni\u00f3n \u00a0 figuren entre los pa\u00edses que constituyan el Comit\u00e9 Ejecutivo. \u00a0<\/p>\n<p>5) a) Los miembros del Comit\u00e9 \u00a0 Ejecutivo permanecer\u00e1n en funciones desde la clausura de la reuni\u00f3n de la \u00a0 Asamblea en la que hayan sido elegidos hasta que termine la reuni\u00f3n ordinaria \u00a0 siguiente de la Asamblea. \u00a0<\/p>\n<p>b) Los Miembros del Comit\u00e9 \u00a0 Ejecutivo ser\u00e1n reelegibles hasta el limite m\u00e1ximo de dos tercios de los mismos. \u00a0<\/p>\n<p>c) La Asamblea reglamentar\u00e1 las \u00a0 modalidades de la elecci\u00f3n y de la posible reelecci\u00f3n de los miembros del Comit\u00e9 \u00a0 Ejecutivo. \u00a0<\/p>\n<p>6) a) El Comit\u00e9 Ejecutivo: \u00a0<\/p>\n<p>i) Preparar\u00e1 el proyecto de orden \u00a0 del d\u00eda de la Asamblea; \u00a0<\/p>\n<p>ii) Someter\u00e1 a la Asamblea \u00a0 propuesta relativas a los proyectos de programa y de presupuesto trienales de la \u00a0 Uni\u00f3n, preparados por el Director General; \u00a0<\/p>\n<p>iii) Se pronunciar\u00e1, dentro de \u00a0 los l\u00edmites del programa y de presupuesto trienal, sobre los programas y \u00a0 presupuestos anuales preparados por el Director General; \u00a0<\/p>\n<p>v) Tomar\u00e1 todas las medidas \u00a0 necesarias para la ejecuci\u00f3n del programa de la Uni\u00f3n por el Director General, \u00a0 de conformidad con las decisiones de la Asamblea teniendo en cuenta las \u00a0 circunstancias que se produzcan entre dos reuniones ordinarias de dicha \u00a0 Asamblea; \u00a0<\/p>\n<p>vi) Ejercer\u00e1 todas las dem\u00e1s \u00a0 funciones que le est\u00e9n atribuidas dentro del marco del presente Convenio. \u00a0<\/p>\n<p>b) En cuestiones que interesen \u00a0 igualmente a otras Uniones administradoras por la Organizaci\u00f3n, el Comit\u00e9 \u00a0 Ejecutivo tomar\u00e1 sus decisiones teniendo en cuenta el dictamen del Comit\u00e9 de \u00a0 Coordinaci\u00f3n de la organizaci\u00f3n. \u00a0<\/p>\n<p>7) a) El comit\u00e9 Ejecutivo se \u00a0 reunir\u00e1 en sesi\u00f3n ordinaria una vez al a\u00f1o, mediante convocatoria del Director \u00a0 General, y siempre que sea posible durante el mismo periodo y en el mismo lugar \u00a0 donde el Comit\u00e9 de Coordinaci\u00f3n de la Organizaci\u00f3n. \u00a0<\/p>\n<p>b) El Comit\u00e9 Ejecutivo se reunir\u00e1 \u00a0 en sesi\u00f3n extraordinaria, mediante convocatoria del Director General, bien a \u00a0 iniciativa de \u00e9ste, bien a petici\u00f3n de su Presidente o de una cuarta parte de \u00a0 sus miembro. \u00a0<\/p>\n<p>8) a) Cada pa\u00eds miembro del \u00a0 Comit\u00e9 Ejecutivo dispondr\u00e1 de un voto. \u00a0<\/p>\n<p>b) La mitad de los pa\u00edses \u00a0 miembros del Comit\u00e9 Ejecutivo constituir\u00e1 el qu\u00f3rum. \u00a0<\/p>\n<p>c) Las decisiones se tomar\u00e1n por \u00a0 mayor\u00eda simple de los votos emitidos. \u00a0<\/p>\n<p>d) La abstenci\u00f3n no se \u00a0 considerar\u00e1 como un voto. \u00a0<\/p>\n<p>e) Un delegado no podr\u00e1 \u00a0 representar m\u00e1s que a un solo pa\u00eds y no podr\u00e1 votar m\u00e1s que en nombre de \u00e9l. \u00a0<\/p>\n<p>9) Los pa\u00edses de la Uni\u00f3n que no \u00a0 sean miembros del Comit\u00e9 Ejecutivo ser\u00e1n admitidos a sus reuniones en calidad de \u00a0 observadores. \u00a0<\/p>\n<p>10) El Comit\u00e9 Ejecutivo adoptar\u00e1 \u00a0 su propio reglamento interior. \u00a0<\/p>\n<p>Articulo 24 \u00a0<\/p>\n<p>[Oficina Internacional: 1. Tareas en General, Director General; 2. Informaciones \u00a0 generales; 3. Revista; 4. Informaci\u00f3n a los pa\u00edses; 5. Estudios y servicios; 6. \u00a0 Participaci\u00f3n en reuniones; 7. Conferencias de revisi\u00f3n; 8. Las dem\u00e1s tareas]. \u00a0<\/p>\n<p>1) a) las tareas administrativas \u00a0 que incumben a la Uni\u00f3n ser\u00e1n desempe\u00f1adas por la Oficina Internacional, que \u00a0 sucede a la Oficina de la Uni\u00f3n, reunida con la Oficina de la Uni\u00f3n instituida \u00a0 por el Convenio Internacional para la Protecci\u00f3n de la Propiedad Industrial. \u00a0<\/p>\n<p>b) La oficina Internacional se \u00a0 encargar\u00e1 especialmente de la Secretar\u00eda de los diversos \u00f3rganos de la Uni\u00f3n. \u00a0<\/p>\n<p>c) El Director General de la \u00a0 Organizaci\u00f3n es el m\u00e1s alto funcionario de la Uni\u00f3n y la representa. \u00a0<\/p>\n<p>2) La Oficina Internacional \u00a0 reunir\u00e1 y publicar\u00e1 informaciones relativas a la protecci\u00f3n del derecho de \u00a0 autor. Cada pa\u00eds de la Uni\u00f3n comunicar\u00e1 lo antes posible a la Oficina \u00a0 Internacional el texto de todas las nuevas leyes y todos los textos oficiales \u00a0 referentes a la protecci\u00f3n del derecho de autor. \u00a0<\/p>\n<p>3) La Oficina Internacional \u00a0 publicar\u00e1 una revista mensual. \u00a0<\/p>\n<p>4) La Oficina Internacional \u00a0 facilitar\u00e1 a los pa\u00edses de la Uni\u00f3n que se lo pidan, informaciones sobre \u00a0 cuestiones relativas a la protecci\u00f3n del derecho de autor. \u00a0<\/p>\n<p>5) La Oficina Internacional \u00a0 realizar\u00e1 estudios y prestar\u00e1 servicios destinados a facilitar la protecci\u00f3n del \u00a0 derecho de autor. \u00a0<\/p>\n<p>6) El Director General, y \u00a0 cualquier miembro del personal designado por \u00e9l, participar\u00e1n, sin derecho de \u00a0 voto, en todas las reuniones de la Asamblea, del Comit\u00e9 Ejecutivo y de cualquier \u00a0 otro comit\u00e9 de expertos o grupo de trabajo. El Director General, o un miembro \u00a0 del personal designado por \u00e9l, ser\u00e1, ex officio, secretario de esos \u00f3rganos. \u00a0<\/p>\n<p>7) a) La Oficina Internacional, \u00a0 siguiendo las instrucciones de la Asamblea y en cooperaci\u00f3n con el Comit\u00e9 \u00a0 Ejecutivo preparar\u00e1 las conferencias de revisi\u00f3n de las disposiciones del \u00a0 Convenio que no sean las comprendidas en los Art\u00edculos 22 a 26. \u00a0<\/p>\n<p>b) La oficina Internacional podr\u00e1 \u00a0 consultar a las organizaciones intergubernamentales e internacionales no \u00a0 gubernamentales en relaci\u00f3n con la preparaci\u00f3n de las conferencias de revisi\u00f3n. \u00a0<\/p>\n<p>c) El Director Genial y las \u00a0 personas que \u00e9l designe participar\u00e1n sin derecho de voto, en las deliberaciones \u00a0 de esas conferencias. \u00a0<\/p>\n<p>8) La Oficina Internacional \u00a0 ejecutar\u00e1 todas las dem\u00e1s tareas que le sean atribuidas. \u00a0<\/p>\n<p>Articulo 25 \u00a0<\/p>\n<p>[Finanzas: 1. Presupuesto; 2. \u00a0 Coordinaci\u00f3n con las otras Uniones; 3. Recursos; 4. Contribuciones; posible \u00a0 pr\u00f3rroga del presupuesto anterior; 5. Tasas y sumas debidas; 6. Fondo de \u00a0 operaciones; 7. Anticipos del Gobierno que acoge; 8. Verificaci\u00f3n de cuentas]. \u00a0<\/p>\n<p>b) El presupuesto de la Uni\u00f3n \u00a0 comprender\u00e1 los ingresos y los gastos de propios de la Uni\u00f3n, su contribuci\u00f3n al \u00a0 presupuesto de los gastos comunes de las Uniones, as\u00ed como, en su caso, la suma \u00a0 puesta a disposici\u00f3n del presupuesto de la Conferencia de la Organizaci\u00f3n. \u00a0<\/p>\n<p>c) Se considerar\u00e1n gastos comunes \u00a0 de las Uniones los gastos que no sean atribuidos exclusivamente a la Uni\u00f3n, sino \u00a0 tambi\u00e9n a una o a varias otras de las Uniones administradas por la Organizaci\u00f3n. \u00a0 La parte de la Uni\u00f3n en esos gastos comunes ser\u00e1 proporcional al inter\u00e9s que \u00a0 tenga en esos gastos. \u00a0<\/p>\n<p>2) Se establecer\u00e1 el presupuesto \u00a0 de la Uni\u00f3n teniendo en cuenta las exigencias de coordinaci\u00f3n con los \u00a0 presupuestos de las otras Uniones administradas por la Organizaci\u00f3n. \u00a0<\/p>\n<p>3) El presupuesto de la Uni\u00f3n se \u00a0 financiar\u00e1 con los recursos siguientes: \u00a0<\/p>\n<p>i) Las contribuciones de los \u00a0 pa\u00edses de la Uni\u00f3n; \u00a0<\/p>\n<p>ii) Las tasas y sumas debidas por \u00a0 servicios prestados por la Oficina Internacional por cuenta de la Uni\u00f3n; \u00a0<\/p>\n<p>iii) El producto de la venta de \u00a0 las publicaciones de la Oficina Internacional referentes a la Uni\u00f3n y los \u00a0 derechos correspondientes a esas publicaciones; \u00a0<\/p>\n<p>iv) Las donaciones, legales y \u00a0 subvenciones; \u00a0<\/p>\n<p>v) Los alquileres, intereses y \u00a0 otros ingresos diversos. \u00a0<\/p>\n<p>4) a) Con el fin de determinar su \u00a0 cuota de contribuci\u00f3n al presupuesto, cada pa\u00eds de la Uni\u00f3n quedar\u00e1 incluido en \u00a0 una clase y pagar\u00e1 sus contribuciones anuales sobre la base de un n\u00famero de \u00a0 unidades fijado de la manera siguiente: \u00a0<\/p>\n<p>Clase I&#8230; &#8230; &#8230; &#8230; &#8230; &#8230; \u00a0 &#8230; &#8230; &#8230; &#8230; &#8230; 25 \u00a0<\/p>\n<p>Clase II &#8230; &#8230; &#8230; &#8230; &#8230; &#8230; \u00a0 &#8230; &#8230; &#8230; &#8230; . 20 \u00a0<\/p>\n<p>Clase III &#8230; &#8230; &#8230; &#8230; &#8230; &#8230; \u00a0 &#8230; &#8230; &#8230; &#8230; 15 \u00a0<\/p>\n<p>Clase IV .. &#8230; &#8230; &#8230; &#8230; &#8230; \u00a0 &#8230; &#8230; &#8230; &#8230; . 10 \u00a0<\/p>\n<p>Clase V &#8230; &#8230; &#8230; &#8230; &#8230; &#8230; \u00a0 &#8230; &#8230; &#8230; &#8230; .. .5 \u00a0<\/p>\n<p>Clase VI &#8230; &#8230; &#8230; &#8230; &#8230; &#8230; \u00a0 &#8230; &#8230; &#8230; &#8230; .. 3 \u00a0<\/p>\n<p>Clase VII &#8230; &#8230; &#8230; &#8230; &#8230; &#8230; \u00a0 &#8230; &#8230; &#8230; &#8230; . 1 \u00a0<\/p>\n<p>b) A menos que los haya hecho ya, \u00a0 cada pa\u00eds indicar\u00e1, en el momento del dep\u00f3sito de su instrumento de ratificaci\u00f3n \u00a0 o de adhesi\u00f3n, la clase a la que desea pertenecer. Podr\u00e1 cambiar de clase. Si \u00a0 escoge una clase inferior, el pa\u00eds deber\u00e1 dar cuenta de ello a la Asamblea \u00a0 durante una de sus reuniones ordinarias. Tal cambio entrar\u00e1 en vigor al comienzo \u00a0 del a\u00f1o civil siguiente a dicha reuni\u00f3n. \u00a0<\/p>\n<p>c) La contribuci\u00f3n anual de cada \u00a0 pa\u00eds consistir\u00e1 en una cantidad que guardar\u00e1, con relaci\u00f3n a la suma total de \u00a0 las contribuciones anuales, de todos los pa\u00edses al presupuesto de la Uni\u00f3n, la \u00a0 misma proporci\u00f3n que el n\u00famero de unidades de la clase a la que pertenezca con \u00a0 relaci\u00f3n al total de las unidades del conjunto de los pa\u00edses. \u00a0<\/p>\n<p>d) Las contribuciones vencen el 1 \u00a0 de enero de cada a\u00f1o. \u00a0<\/p>\n<p>e) Un pa\u00eds atrasado en el pago de \u00a0 sus contribuciones no podr\u00e1 ejercer su derecho de voto, en ninguno de los \u00a0 \u00f3rganos de la Uni\u00f3n de los que sea miembro, cuando la cuant\u00eda de sus atrasos sea \u00a0 igual o superior a la de las contribuciones que deba por los dos a\u00f1os completos \u00a0 transcurridos. Sin embargo, cualquiera de esos \u00f3rganos podr\u00e1 permitir a ese pa\u00eds \u00a0 que contin\u00fae ejerciendo el derecho de voto en dicho \u00f3rgano si estima que el \u00a0 atraso resulta de circunstancias excepcionales e inevitables. \u00a0<\/p>\n<p>f) En caso de que al comienzo de \u00a0 un nuevo ejercicio no se haya adoptado el presupuesto, se continuar\u00e1 aplicando \u00a0 el presupuesto de a\u00f1o precedente, conforme a las modalidades previstas en el \u00a0 reglamento financiero. \u00a0<\/p>\n<p>5) La cuant\u00eda de las tasas y las \u00a0 sumas debidas por servicios prestados por la Oficina Internacional por cuenta de \u00a0 la Uni\u00f3n ser\u00e1 fijada por el Director General, que informar\u00e1 de ello a la \u00a0 Asamblea y al Comit\u00e9 Ejecutivo. \u00a0<\/p>\n<p>6) a) La Uni\u00f3n poseer\u00e1 un fondo \u00a0 de operaciones constituido por una aportaci\u00f3n \u00fanica efectuada por cada uno de \u00a0 los pa\u00edses de la Uni\u00f3n. Si el fondo resultar\u00e1 insuficiente, la Asamblea decidir\u00e1 \u00a0 sobre su aumento. \u00a0<\/p>\n<p>c) La proporci\u00f3n y las \u00a0 modalidades de pago ser\u00e1n determinadas por la Asamblea, a propuesta del Director \u00a0 General y previo dictamen del Comit\u00e9 de Coordinaci\u00f3n de la Organizaci\u00f3n. \u00a0<\/p>\n<p>7) a) El Acuerdo de Sede \u00a0 concluido con el pa\u00eds en cuyo territorio la Organizaci\u00f3n tenga su residencia, \u00a0 proveer\u00e1 que ese pa\u00eds concede anticipos si el fondo de operaciones fuere \u00a0 insuficiente. La cuant\u00eda de esos anticipos y las condiciones en que ser\u00e1n \u00a0 concedidos ser\u00e1n objeto, en cada caso, de acuerdo separados entre el pa\u00eds en \u00a0 cuesti\u00f3n y la Organizaci\u00f3n. Mientras tenga obligaci\u00f3n de conceder esos \u00a0 anticipos, ese pa\u00eds tendr\u00e1 un puesto, ex officio, en el Comit\u00e9 Ejecutivo. \u00a0<\/p>\n<p>b) El pa\u00eds al que se hace \u00a0 referencia en el apartado a) y la Organizaci\u00f3n tendr\u00e1 cada uno el derecho de \u00a0 denunciar el compromiso de conceder anticipos, mediante notificaci\u00f3n por \u00a0 escrito. La denuncia producir\u00e1 efecto tres a\u00f1os despu\u00e9s de terminado el a\u00f1o en \u00a0 el curso del cual haya sido notificada. \u00a0<\/p>\n<p>8) De la intervenci\u00f3n de cuentas \u00a0 se encargar\u00e1n, seg\u00fan las modalidades previstas en el reglamento financiero, uno \u00a0 o varios pa\u00edses de la Uni\u00f3n, o interventores de cuentas que con su \u00a0 consentimiento, ser\u00e1n designados por la Asamblea. \u00a0<\/p>\n<p>Articulo 26 \u00a0<\/p>\n<p>[Modificaciones: 1. Disposiciones que la Asamblea podr\u00e1n modificar; propuestas; \u00a0 2. Adopci\u00f3n; 3. Entrada en vigor]. \u00a0<\/p>\n<p>1) Las propuestas de modificaci\u00f3n \u00a0 de las Articulo 22, 23, 24, 25 y del presente articulo, podr\u00e1n ser presentadas \u00a0 por todo pa\u00eds miembro de la Asamblea, por el Comit\u00e9 Ejecutivo o por el Director \u00a0 General. Esas propuestas ser\u00e1n comunicadas por este \u00faltimo a los pa\u00edses miembros \u00a0 de la Asamblea, al menos seis meses antes de ser sometidas a examen de la \u00a0 Asamblea. \u00a0<\/p>\n<p>2) Toda modificaci\u00f3n de los \u00a0 art\u00edculos a los que se referencia en el p\u00e1rrafo 1) ser\u00e1 adoptada por la \u00a0 Asamblea. La adopci\u00f3n requerir\u00e1 tres cuartos de los votos emitidos; sin embargo, \u00a0 toda modificaci\u00f3n del Articulo 22 y del presente p\u00e1rrafo requerir\u00e1 cuatro \u00a0 quintos de los votos emitidos. \u00a0<\/p>\n<p>3) Toda modificaci\u00f3n de los \u00a0 art\u00edculos a los que se hace referencia en el p\u00e1rrafo 1) entrar\u00e1 en vigor un mes \u00a0 despu\u00e9s de que el Director General haya recibido notificaci\u00f3n escrita de su \u00a0 aceptaci\u00f3n efectuada de conformidad con sus respectivos procedimientos \u00a0 constitucionales, de tres cuartos de los pa\u00edses que eran miembros de la Asamblea \u00a0 en el momento en que la modificaci\u00f3n hubiese sido adoptada. Toda modificaci\u00f3n de \u00a0 dichos art\u00edculos as\u00ed aceptada obligar\u00e1 a todos los pa\u00edses que sean miembros de \u00a0 la Asamblea en el momento en que la modificaci\u00f3n entre el vigor o que se hagan \u00a0 miembros en una fecha ulterior; sin embargo, toda modificaci\u00f3n que incremente \u00a0 las obligaciones financieras de los pa\u00edses de la uni\u00f3n solo obligar\u00e1 a los \u00a0 pa\u00edses que hayan notificado su aceptaci\u00f3n de la mencionada modificaci\u00f3n. \u00a0<\/p>\n<p>Articulo 27 \u00a0<\/p>\n<p>[Revisi\u00f3n: 1. Objetivo; 2. \u00a0 Conferencias; 3. Adopci\u00f3n]. \u00a0<\/p>\n<p>1) El presente Convenio se \u00a0 someter\u00e1 a revisiones con el objeto de introducir en \u00e9l las mejoras que tiendan \u00a0 a perfeccionar el sistema de la Uni\u00f3n. \u00a0<\/p>\n<p>2) Para tales efectos, se \u00a0 celebrar\u00e1n entre los delegados de los pa\u00edses de la Uni\u00f3n conferencias que \u00a0 tendr\u00e1n lugar, sucesivamente, en uno de esos pa\u00edses. \u00a0<\/p>\n<p>3) Sin perjuicio de las \u00a0 disposiciones del Articulo 26 aplicables a la modificaci\u00f3n de los Art\u00edculos 22 a \u00a0 26, toda revisi\u00f3n de la presente Acta, incluido el Anexo, requerir\u00e1 la \u00a0 unanimidad de los votos emitidos. \u00a0<\/p>\n<p>Articulo 28 \u00a0<\/p>\n<p>[Aceptaci\u00f3n y entrada en vigor del Acta respecto de los pa\u00edses de la Uni\u00f3n: 1. \u00a0 Ratificaci\u00f3n, adhesi\u00f3n; posibilidad de excluir algunas disposiciones; retiro de \u00a0 la exclusi\u00f3n; 2. Entrada en vigor de los art\u00edculos 1 a 21 y del Anexo; 3. \u00a0 Entrada en vigor de los art\u00edculos 22 a 38]. \u00a0<\/p>\n<p>1) a) Cada uno de los pa\u00edses de \u00a0 la Uni\u00f3n que hayan firmado la presente Acta podr\u00e1 ratificarla y, si no la \u00a0 hubiere firmado, podr\u00e1 adherirse a ella. Los instrumentos de ratificaci\u00f3n y de \u00a0 adhesi\u00f3n se depositar\u00e1n en poder del Director General. \u00a0<\/p>\n<p>b) Cada uno de los pa\u00edses de la \u00a0 Uni\u00f3n podr\u00e1n declarar, en su instrumento de ratificaci\u00f3n o de adhesi\u00f3n, que su \u00a0 instrumento de ratificaci\u00f3n o su adhesi\u00f3n no es aplicables a los Art\u00edculos 1 a \u00a0 21 ni al Anexo; sin embargo, si ese pa\u00eds hubiese hecho ya una declaraci\u00f3n seg\u00fan \u00a0 el Articulo VI.1) del Anexo, s\u00f3lo podr\u00e1 declarar en dicho instrumento que su \u00a0 ratificaci\u00f3n o su adhesi\u00f3n no se aplica a los Art\u00edculos 1 a 20. \u00a0<\/p>\n<p>c) Cada uno de los pa\u00edses que, de \u00a0 conformidad con el apartado b), haya excluido las disposiciones all\u00ed \u00a0 establecidas de los efectos de su ratificaci\u00f3n o de su adhesi\u00f3n podr\u00e1, en \u00a0 cualquier momento ulterior, declarar que extiende los efectos de su ratificaci\u00f3n \u00a0 o de su adhesi\u00f3n a esas disposiciones. Tal declaraci\u00f3n se depositar\u00e1 en poder \u00a0 del Director General. \u00a0<\/p>\n<p>2) a) Los Art\u00edculos 1 a 21 y el \u00a0 Anexo entrar\u00e1n en vigor tres meses despu\u00e9s de que se hayan cumplido las dos \u00a0 condiciones siguientes. \u00a0<\/p>\n<p>i) que cinco pa\u00edses de la Uni\u00f3n \u00a0 por lo menos hayan ratificado la presente Acta o se hayan adherido a ella sin \u00a0 hacer una declaraci\u00f3n de conformidad con el apartado 1) b); \u00a0<\/p>\n<p>ii) que Espa\u00f1a, los Estados \u00a0 Unidos de Am\u00e9rica, Francia y el Reino Unido de Gran Breta\u00f1a e Irlanda del Norte \u00a0 haya quedado obligados por la Convenci\u00f3n Universal sobre Derecho de Autor, tal \u00a0 como ha sido revisada en Par\u00eds el 24 de julio de 1971. \u00a0<\/p>\n<p>b) La entrada en vigor a la que \u00a0 se hace referencia en el apartado a) se har\u00e1 efectiva, respecto de los pa\u00edses de \u00a0 la Uni\u00f3n que, tres meses antes de dicha entrada en vigor, hayan depositado \u00a0 instrumentos de ratificaci\u00f3n o de adhesi\u00f3n que no contengan una declaraci\u00f3n de \u00a0 conformidad con el apartado 1) b). \u00a0<\/p>\n<p>c) Respecto de todos los pa\u00edses \u00a0 de la Uni\u00f3n a los que no resulte aplicable el apartado b) y que ratifiquen la \u00a0 presente Acta o se adhieran a ella sin hacer una declaraci\u00f3n de conformidad con \u00a0 el apartado 1) b), los Art\u00edculos 1 a 21 y el Anexo entrar\u00e1n en vigor tres meses \u00a0 despu\u00e9s de la fecha en la cual el Director General haya notificado el dep\u00f3sito \u00a0 del instrumento de ratificaci\u00f3n o de adhesi\u00f3n en cuesti\u00f3n, a menos que en el \u00a0 instrumento depositado se haya indicado una fecha posterior. En ese \u00faltimo caso, \u00a0 los Art\u00edculos 1 a 21 y el Anexo entrar\u00e1n en vigor respecto de ese pa\u00eds en la \u00a0 fecha as\u00ed indicada. \u00a0<\/p>\n<p>d) Las disposiciones de los \u00a0 apartados a) a c) no afectar\u00e1n la aplicaci\u00f3n del Articulo VI del Anexo. \u00a0<\/p>\n<p>3) Respecto de cada pa\u00eds de la \u00a0 Uni\u00f3n que ratifique la presente Acta o se adhiera a ella con o sin declaraci\u00f3n \u00a0 de conformidad con el apartado 1) b), los Art\u00edculos 22 a 38 entrar\u00e1n en vigor \u00a0 tres meses despu\u00e9s de la fecha en la cual el Director General haya notificado el \u00a0 dep\u00f3sito del instrumento de ratificaci\u00f3n o adhesi\u00f3n de que se trate, a menos que \u00a0 se haya indicado una fecha posterior en el instrumento depositado. En este \u00a0 \u00faltimo caso, los Art\u00edculos 22 a 38 entrar\u00e1n en vigor, respecto de ese pa\u00eds en la \u00a0 fecha as\u00ed indicada. \u00a0<\/p>\n<p>Articulo 29 \u00a0<\/p>\n<p>[Aceptaci\u00f3n y entrada en vigor respecto de pa\u00edses externos a la Uni\u00f3n: 1. \u00a0 Adhesi\u00f3n; 2. Entrada en vigor]. \u00a0<\/p>\n<p>1) Todo pa\u00eds externo a la Uni\u00f3n \u00a0 podr\u00e1 adherirse a la presente Acta y pasar, por tanto, a ser parte en el \u00a0 presente Convenio y miembro de la Uni\u00f3n. Los instrumentos de adhesi\u00f3n se \u00a0 depositar\u00e1n en poder el Director General. \u00a0<\/p>\n<p>2) a) sin perjuicio de lo \u00a0 dispuesto en el apartado b), el presente Convenio entrar\u00e1 en vigor, respecto de \u00a0 todo pa\u00eds externo a la Uni\u00f3n, tres meses despu\u00e9s de la fecha en la cual el \u00a0 Director General haya notificado el dep\u00f3sito de su instrumento de adhesi\u00f3n, a \u00a0 menos que no se haya indicado una fecha posterior en el instrumento depositado. \u00a0 En este \u00faltimo caso, el presente Convenio entrar\u00e1 en vigor, respecto de ese \u00a0 pa\u00eds, en la fecha as\u00ed indicada. \u00a0<\/p>\n<p>b) Si la entrada en vigor, en \u00a0 aplicaci\u00f3n de lo dispuesto en el apartado a) precede a la entrada en vigor de \u00a0 los art\u00edculos 1 a 21 y del Anexo en aplicaci\u00f3n de lo dispuesto en el articulo \u00a0 28.2) a), dicho pa\u00eds no quedar\u00e1 obligado mientras tanto por los Art\u00edculos 1 a 21 \u00a0 y por el Anexo, sino por los Art\u00edculos 1 a 20 del Acta de Bruselas del presente \u00a0 convenio. \u00a0<\/p>\n<p>Articulo 29 bis \u00a0<\/p>\n<p>[Efecto de la aceptaci\u00f3n del Acta con el fin de aplicar el Articulo 14.2) del \u00a0 Convenio que establece la OMPI]. \u00a0<\/p>\n<p>La ratificaci\u00f3n de la presente \u00a0 Acta o la adhesi\u00f3n a ella por cualquier pa\u00eds que no est\u00e9 obligado por los \u00a0 Art\u00edculos 22 a 38 del Acta de Estocolmo del presente Convenio equivaldr\u00e1, con el \u00a0 fin \u00fanico de poder aplicar el Articulo 14.2) del Convenio que establece la \u00a0 Organizaci\u00f3n, a la ratificaci\u00f3n del Acta de Estocolmo o a la adhesi\u00f3n a esa Acta \u00a0 con la limitaci\u00f3n prevista en el Articulo 28.1 b) i) de dicha Acta. \u00a0<\/p>\n<p>Articulo 30 \u00a0<\/p>\n<p>[Reservas: 1. Limites de la posibilidad de formular reservas; 2. Reservas \u00a0 anteriores; reserva relativa al derecho de traducci\u00f3n; retiro de la reserva]. \u00a0<\/p>\n<p>1) Sin perjuicio de las \u00a0 excepciones posibles previstas en el p\u00e1rrafo 2, del presente articulo, el \u00a0 Articulo 28.1 b), el Articulo 33.2), y el Anexo, la ratificaci\u00f3n o la adhesi\u00f3n \u00a0 supondr\u00e1n, de pleno derecho, la accesi\u00f3n a todas las disposiciones y la \u00a0 administraci\u00f3n para todas las ventajas estipuladas en el presente Convenio. \u00a0<\/p>\n<p>2) a) Cualquier pa\u00eds de la Uni\u00f3n \u00a0 que ratifique la presente Acta o se adhiera a ella podr\u00e1 conservar, sin \u00a0 perjuicio de los dispuesto en el articulo V.2) del Anexo, el beneficio de las \u00a0 reservas que haya formulado anteriormente, a condici\u00f3n de declararlo al hacer el \u00a0 dep\u00f3sito de su instrumento de ratificaci\u00f3n o de adhesi\u00f3n. \u00a0<\/p>\n<p>b) Cualquier pa\u00eds externo a la \u00a0 Uni\u00f3n podr\u00e1 declara, al adherirse al presente Convenio y sin perjuicio de lo \u00a0 dispuesto en el Articulo V.2) del Anexo, que piensa reemplaza, al menos \u00a0 provisionalmente, las disposiciones del articulo 8\u00ba de la presente Acta \u00a0 relativas al derecho de traducci\u00f3n, por las disposiciones del articulo 5\u00ba del \u00a0 Convenio de la Uni\u00f3n de 1886, revisado en Par\u00eds en 1896, en la inteligencia de \u00a0 que esas disposiciones se refieren \u00fanicamente a la traducci\u00f3n en un idioma de \u00a0 uso general en dicho pa\u00eds. Sin perjuicio de lo dispuesto en el articulo I.6) b) \u00a0 del Anexo, en lo tocante al derecho de traducci\u00f3n de las obras que tengan como \u00a0 pa\u00eds de origen uno de los pa\u00edses que hayan hecho tal reserva, todos los pa\u00edses \u00a0 estar\u00e1n facultados para aplicar una protecci\u00f3n equivalente a la que aqu\u00e9l \u00a0 aplique. \u00a0<\/p>\n<p>c) Los pa\u00edses podr\u00e1n retirar en \u00a0 cualquier momento esa reserva mediante notificaci\u00f3n dirigida al Director \u00a0 General. \u00a0<\/p>\n<p>Articulo 31 \u00a0<\/p>\n<p>[Aplicabilidad a determinados territorios: 1. Declaraci\u00f3n; 2. Retiro de la \u00a0 declaraci\u00f3n; 3. Fecha de vigencia; 4. No implica la aceptaci\u00f3n de situaciones de \u00a0 hecho]. \u00a0<\/p>\n<p>1) Cualquier pa\u00eds podr\u00e1 declarar \u00a0 en su instrumento de ratificaci\u00f3n o de adhesi\u00f3n, o podr\u00e1 informar por escrito al \u00a0 Director General en cualquier momento ulterior, que el presente Convenio ser\u00e1 \u00a0 aplicable a la totalidad o parte de los territorios designados en la declaraci\u00f3n \u00a0 o la notificaci\u00f3n, por los que asume la responsabilidad de las relaciones \u00a0 exteriores. \u00a0<\/p>\n<p>2) Cualquier pa\u00eds que haya hecho \u00a0 tal declaraci\u00f3n o efectuado tal notificaci\u00f3n podr\u00e1, en cualquier momento, \u00a0 notificar al director General que el presente Convenio deja de ser aplicable en \u00a0 la totalidad o en parte de esos territorios. \u00a0<\/p>\n<p>3) a) La declaraci\u00f3n hecha en \u00a0 virtud del p\u00e1rrafo 1) surtir\u00e1 efecto en la misma fecha que la ratificaci\u00f3n o la \u00a0 adhesi\u00f3n, en el instrumento en el cual aqu\u00e9lla se haya incluido, y la \u00a0 notificaci\u00f3n efectuada en virtud de ese p\u00e1rrafo surtir\u00e1 efecto tres meses \u00a0 despu\u00e9s de su notificaci\u00f3n por el Director General. \u00a0<\/p>\n<p>b) La notificaci\u00f3n hecha en \u00a0 virtud del p\u00e1rrafo 2) surtir\u00e1 efecto doce meses despu\u00e9s de su recepci\u00f3n por el \u00a0 Director General. \u00a0<\/p>\n<p>4) El presente articulo no podr\u00e1 \u00a0 interpretarse de manera que implique el reconocimiento o la aceptaci\u00f3n t\u00e1cita \u00a0 por un pa\u00eds cualquiera de la Uni\u00f3n de la situaci\u00f3n de hecho de todo territorio \u00a0 al cual se haga aplicable el presente Convenio por otro pa\u00eds de la Uni\u00f3n en \u00a0 virtud de una declaraci\u00f3n hecha en aplicaci\u00f3n del p\u00e1rrafo 1). \u00a0<\/p>\n<p>Articulo 32 \u00a0<\/p>\n<p>[Aplicabilidad de la presente Acta y de las Actas anteriores: 1. Entre pa\u00edses \u00a0 que ya son miembros de la Uni\u00f3n; 2. Entre un pa\u00eds que llega a ser miembro de la \u00a0 Uni\u00f3n y otros pa\u00edses miembros de la Uni\u00f3n; 3. Aplicabilidad del Anexo en \u00a0 determinadas relaciones]. \u00a0<\/p>\n<p>1) La presente Acta reemplaza, en \u00a0 las relaciones entre los pa\u00edses de la Uni\u00f3n a los cuales se aplique y en la \u00a0 medida en que se aplique, al Convenio de Berna del 9 de septiembre de 1886 y a \u00a0 las Actas de Revisi\u00f3n subsiguientes. Las Actas anteriormente en vigor seguir\u00e1n \u00a0 siendo aplicables, en su totalidad o en la medida en que no las reemplace la \u00a0 presente Acta en virtud de la frase precedente, en las relaciones con los pa\u00edses \u00a0 de la Uni\u00f3n que no ratifiquen la presente Acta o que no se adhieran a ella. \u00a0<\/p>\n<p>2) Los pa\u00edses externos a la Uni\u00f3n \u00a0 que lleguen a ser partes en la presente Acta, la aplicar\u00e1n sin perjuicio de las \u00a0 disposiciones del p\u00e1rrafo 3), en sus relaciones con cualquier pa\u00eds de la Uni\u00f3n \u00a0 que no sea parte de esta Acta o que siendo parte, haya hecho la declaraci\u00f3n \u00a0 prevista en el Articulo 28.1) b). Dichos pa\u00edses admitir\u00e1n que el pa\u00eds de la \u00a0 Uni\u00f3n de que se trate, en sus relaciones con ellos: \u00a0<\/p>\n<p>i) aplique las disposiciones del \u00a0 Acta m\u00e1s reciente de la que sea parte, y \u00a0<\/p>\n<p>ii) sin perjuicio de lo dispuesto \u00a0 en el Articulo I.6) del Anexo, est\u00e9 facultado para adaptar la protecci\u00f3n al \u00a0 nivel previsto en la presente Acta. \u00a0<\/p>\n<p>3) Los pa\u00edses que hayan invocado \u00a0 el beneficio de cualquiera de las facultades previstas en el Anexo podr\u00e1n \u00a0 aplicar las disposiciones del Anexo con respecto a la facultad o facultades cuyo \u00a0 beneficio hayan invocado, en sus relaciones con cualquier pa\u00eds de la Uni\u00f3n que \u00a0 no est\u00e9 obligado por la presente Acta, a condici\u00f3n de que este \u00faltimo pa\u00eds haya \u00a0 aceptado la aplicaci\u00f3n de dichas disposiciones. \u00a0<\/p>\n<p>Articulo 33 \u00a0<\/p>\n<p>[Diferencias: 1. Competencia de la Corte Internacional de Justicia; 2. Reserva \u00a0 respecto de esta competencia; 3. Retiro de la reserva]. \u00a0<\/p>\n<p>1) Toda diferencia entre dos o \u00a0 m\u00e1s pa\u00edses de la Uni\u00f3n respecto de la interpretaci\u00f3n o de la aplicaci\u00f3n del \u00a0 presente Convenio que no se hayan conseguido resolver por v\u00eda de negociaci\u00f3n \u00a0 podr\u00e1 ser llevada por cualquiera de los pa\u00edses en litigio ante la Corte \u00a0 Internacional de Justicia mediante petici\u00f3n hecha de conformidad con el Estatuto \u00a0 de la Corte, a menos que los pa\u00edses en litigio convengan otro modo de \u00a0 resolverla. La Oficina Internacional sobre la diferencia prestada a los dem\u00e1s \u00a0 pa\u00edses de la Uni\u00f3n. \u00a0<\/p>\n<p>2) En el momento de firmar la \u00a0 presente Acta o de depositar su instrumento de ratificaci\u00f3n o de adhesi\u00f3n, todo \u00a0 pa\u00eds podr\u00e1 declarar que no se considera obligado por las disposiciones del \u00a0 p\u00e1rrafo 1). Las disposiciones del p\u00e1rrafo 1) no ser\u00e1n aplicables en lo que \u00a0 respecta a las diferencias entre uno de esos pa\u00edses y los dem\u00e1s pa\u00edses de la \u00a0 Uni\u00f3n. \u00a0<\/p>\n<p>3. Todo pa\u00eds que haya hecho una \u00a0 declaraci\u00f3n con arreglo a lo dispuesto en el p\u00e1rrafo 2) podr\u00e1 retirarla, en \u00a0 cualquier momento, mediante una notificaci\u00f3n dirigida al Director General. \u00a0<\/p>\n<p>Articulo 34 \u00a0<\/p>\n<p>[Cierre de algunas disposiciones \u00a0 anteriores: 1. De Actas anteriores; 2. Del Protocolo anexo al Acta de \u00a0 Estocolmo]. \u00a0<\/p>\n<p>1) Sin perjuicio de los dispuesto \u00a0 en el Articulo 29 bis, despu\u00e9s de la entrada en vigor de los Art\u00edculos 1 a 21 y \u00a0 del Anexo, ning\u00fan pa\u00eds podr\u00e1 adherirse a Actas anteriores del presente Convenio \u00a0 o ratificarlas. \u00a0<\/p>\n<p>2) A partir de la entrada en \u00a0 vigor de los Art\u00edculos 1 a 21 y del Anexo, ning\u00fan pa\u00eds podr\u00e1 hacer una \u00a0 declaraci\u00f3n en virtud de lo dispuesto en el Articulo 5 del Protocolo relativo a \u00a0 los pa\u00edses en desarrollo anexo al Acta de Estocolmo. \u00a0<\/p>\n<p>Art\u00edculo 35 \u00a0<\/p>\n<p>[Duraci\u00f3n del Convenio; Denuncia: 1. Duraci\u00f3n ilimitada; 2. Posibilidad de \u00a0 denuncia; 3. Fecha en que surtir\u00e1 efecto la denuncia; 4. Moratoria relativa a la \u00a0 denuncia]. \u00a0<\/p>\n<p>1) El presente Convenio \u00a0 permanecer\u00e1 en vigor sin limitaci\u00f3n de tiempo. \u00a0<\/p>\n<p>2) Todo pa\u00eds podr\u00e1 denunciar la \u00a0 presente Acta mediante notificaci\u00f3n dirigida al Director General. Esta denuncia \u00a0 implicar\u00e1 tambi\u00e9n la denuncia de todas las Actas anteriores y no producir\u00e1 \u00a0 efecto m\u00e1s que respecto del pa\u00eds que la haya hecho, quedando con vigor y \u00a0 ejecutivo el Convenio respecto de los dem\u00e1s pa\u00edses de la Uni\u00f3n. \u00a0<\/p>\n<p>3) La denuncia surtir\u00e1 efecto un \u00a0 a\u00f1o despu\u00e9s de la fecha en que el director General haya recibido la \u00a0 notificaci\u00f3n. \u00a0<\/p>\n<p>4) La facultad de denuncia previa \u00a0 por el presente articulo no podr\u00e1 ser ejercida por una pa\u00eds antes de la \u00a0 expiraci\u00f3n de un plazo de cinco a\u00f1os, contados desde la fecha en que se haya \u00a0 hecho miembro de la Uni\u00f3n. \u00a0<\/p>\n<p>Articulo 36 \u00a0<\/p>\n<p>[Aplicaci\u00f3n del Convenio: 1. Obligaci\u00f3n de adoptar las medidas necesarias; 2. \u00a0 Momento a partir del cual existe esta obligaci\u00f3n]. \u00a0<\/p>\n<p>1) Todo pa\u00eds que forme parte del \u00a0 presente Convenio se compromete a adoptar, de conformidad con su Constituci\u00f3n, \u00a0 las medidas necesarias para asegurar la aplicaci\u00f3n del presente Convenio. \u00a0<\/p>\n<p>2) Se entiende que, en el momento \u00a0 en que un pa\u00eds se obliga por este Convenio, se encuentra en condiciones, \u00a0 conforme a su legislaci\u00f3n interna, de aplicar las disposiciones del mismo. \u00a0<\/p>\n<p>Articulo 37 \u00a0<\/p>\n<p>[Cl\u00e1usulas finales: 1. Idiomas del Acta; 2. Firma; 3. Copias certificadas; 4. \u00a0 Registro; 5. Notificaciones]. \u00a0<\/p>\n<p>1) a) La presente Acta ser\u00e1 \u00a0 firmada en un solo ejemplar en los idiomas franc\u00e9s e ingl\u00e9s y, sin perjuicio de \u00a0 lo dispuesto en el p\u00e1rrafo 2), se depositar\u00e1 en poder del Director General. \u00a0<\/p>\n<p>b) El Director General \u00a0 establecer\u00e1 textos oficiales, despu\u00e9s de consultar a los gobiernos interesados, \u00a0 en alem\u00e1n, \u00e1rabe, espa\u00f1ol, italiano y portugu\u00e9s y en los dem\u00e1s idiomas que la \u00a0 Asamblea pueda indicar. \u00a0<\/p>\n<p>c) En caso de controversia sobre \u00a0 la interpretaci\u00f3n de los diversos textos, har\u00e1 fe el texto franc\u00e9s. \u00a0<\/p>\n<p>3) El Director General remitir\u00e1 \u00a0 dos copias certificadas del texto firmado de la presente Acta a los gobiernos de \u00a0 todos los pa\u00edses de la Uni\u00f3n y al gobierno de cualquier otro pa\u00eds que lo \u00a0 solicite. \u00a0<\/p>\n<p>4) El Director General har\u00e1 \u00a0 registrar la presente Acta en la Secretar\u00eda de las Naciones Unidas. \u00a0<\/p>\n<p>5) El Director General notificar\u00e1 \u00a0 a los gobiernos de todos los pa\u00edses de la Uni\u00f3n las firmas, los dep\u00f3sitos de \u00a0 instrumentos de ratificaci\u00f3n o de adhesi\u00f3n y las declaraciones comprendidas en \u00a0 esos instrumentos o afectadas en cumplimiento de los Art\u00edculos 28.1) c), 30.2) \u00a0 a) y b) 33.2), la entrada en vigor de todas las disposiciones de la presente \u00a0 Acta, las notificaciones de denuncia y las notificaciones hechas en aplicaci\u00f3n \u00a0 de lo dispuesto en los Art\u00edculos 30.2) c), 31.1) y 2), 33.3) y 38.1) y en el \u00a0 Anexo. \u00a0<\/p>\n<p>Articulo 38 \u00a0<\/p>\n<p>[Disposiciones transitorias: 1. \u00a0 Ejercicio del \u00abprivilegio de cinco a\u00f1os\u00bb; 2. Oficina de la Uni\u00f3n, Director de la \u00a0 Oficina; 3. Sucesi\u00f3n de la Oficina de la Uni\u00f3n]. \u00a0<\/p>\n<p>1) los pa\u00edses de la Uni\u00f3n que no \u00a0 hayan ratificado la presente Acta o que no se hayan adherido a ella y que no \u00a0 est\u00e9n obligados por los Articulo 22 a 26 del Acta de Estocolmo podr\u00e1n, si lo \u00a0 desean, ejercer hasta el 26 de abril de 1975 los derechos previstos en dichos \u00a0 art\u00edculos como si estuvieran obligados por ellos. Todo pa\u00eds que desee ejercer \u00a0 los mencionados derechos depositar\u00e1 en poder del Director General una \u00a0 notificaci\u00f3n escrita que surtir\u00e1 efecto en la fecha de su recepci\u00f3n. Esos pa\u00edses \u00a0 ser\u00e1n considerados como miembros de la Asamblea hasta la expiraci\u00f3n de la citada \u00a0 fecha. \u00a0<\/p>\n<p>2) Mientras haya pa\u00edses de la \u00a0 Uni\u00f3n que no se hayan hecho miembros de la Organizaci\u00f3n, la Ofician \u00a0 Internacional de la Organizaci\u00f3n y el Director General ejercer\u00e1 igualmente las \u00a0 funciones correspondientes, respectivamente, a la Oficina de la Uni\u00f3n y a su \u00a0 Director. \u00a0<\/p>\n<p>3) Una vez que todos los pa\u00edses \u00a0 de la Uni\u00f3n se hayan hecho miembros de la Organizaci\u00f3n, los derechos, \u00a0 obligaciones y bienes de la Ofician de la Uni\u00f3n pasar\u00e1n a la Oficina \u00a0 Internacional de la Organizaci\u00f3n. \u00a0<\/p>\n<p>ANEXO \u00a0<\/p>\n<p>[DISPOSICIONES ESPECIALES \u00a0 RELATIVAS A LOS PA\u00cdSES EN DESARROLLO] \u00a0<\/p>\n<p>Articulo primero \u00a0<\/p>\n<p>[Facultades ofrecidas a los pa\u00edses en desarrollo: 1. Posibilidad de hace uso de \u00a0 algunas facultades; declaraci\u00f3n; 2. Duraci\u00f3n de la validez de la declaraci\u00f3n; 3. \u00a0 Pa\u00eds que haya dejado de ser considerado como pa\u00eds en desarrollo; 4. Existencias \u00a0 de ejemplares; 5. Declaraciones respecto de algunos territorios; 6. L\u00edmites de \u00a0 la reciprocidad]. \u00a0<\/p>\n<p>1) Todo pa\u00eds, considerado de \u00a0 conformidad con la pr\u00e1ctica establecida por la Asamblea General de las Naciones \u00a0 Unidas como pa\u00eds en desarrollo, que ratifique la presente Acta, de la cual forma \u00a0 parte integrante el presente Anexo, o que se adhiera a ella, y que en vista de \u00a0 su situaci\u00f3n econ\u00f3mica y sus necesidades sociales o culturales considere no \u00a0 estar en condiciones de tomar de inmediato las disposiciones necesarias para \u00a0 asegurar la protecci\u00f3n de todos los derechos tal como est\u00e1n previstos en la \u00a0 presente Acta, podr\u00e1 declarar, por medio de una notificaci\u00f3n depositada en poder \u00a0 del Director General, en el momento del dep\u00f3sito de su instrumento de \u00a0 ratificaci\u00f3n o de adhesi\u00f3n, o, sin perjuicio de lo dispuesto en el Articulo \u00a0 V.1.c), en cualquier fecha posterior, que har\u00e1 uso de la facultad prevista por \u00a0 el Articulo II, de aqu\u00e9lla prevista por el Articulo III o de ambas facultades. \u00a0 Podr\u00e1, en lugar de hace uso de la facultad prevista por el Articulo II, hacer \u00a0 una declaraci\u00f3n conforme al Articulo V.1)a). \u00a0<\/p>\n<p>2) a) Todo declaraci\u00f3n hecha en \u00a0 virtud del p\u00e1rrafo 1) y notificada antes de la expiraci\u00f3n de un periodo de diez \u00a0 a\u00f1os, contados a partir de la entrada en vigor, conforme al Articulo 28.2), de \u00a0 los Articulo 1 a 21 y del Anexo seguir\u00e1 siendo v\u00e1lida hasta la expiraci\u00f3n de \u00a0 dicho per\u00edodo. Tal declaraci\u00f3n podr\u00e1 ser renovada total o parcialmente por \u00a0 per\u00edodos sucesivos de diez a\u00f1os, depositando en cada ocasi\u00f3n una nueva \u00a0 notificaci\u00f3n en poder del Director General en un t\u00e9rmino no superior a quince \u00a0 meses ni inferior a tres antes de la expiraci\u00f3n del per\u00edodo decenal en curso. \u00a0<\/p>\n<p>b) Toda declaraci\u00f3n hecha en \u00a0 virtud del p\u00e1rrafo 1), que fuere notificada una vez expirado el t\u00e9rmino de diez \u00a0 a\u00f1os despu\u00e9s de la entrada en vigor, conforme al Articulo 28.2), de los Articulo \u00a0 1 a 1 y del Anexo, seguir\u00e1 siendo v\u00e1lida hasta la expiraci\u00f3n del per\u00edodo decenal \u00a0 en curso. Tal declaraci\u00f3n podr\u00e1 ser renovada de la manera prevista en la segunda \u00a0 frase del subp\u00e1rrafo a). \u00a0<\/p>\n<p>3) Un pa\u00eds miembro de la Uni\u00f3n \u00a0 que haya dejado de ser considerado como pa\u00eds en desarrollo, seg\u00fan lo dispuesto \u00a0 por el p\u00e1rrafo 1), ya no estar\u00e1 habilitado para renovar su declaraci\u00f3n conforme \u00a0 al p\u00e1rrafo 2) y, la retire oficialmente o no, ese pa\u00eds perder\u00e1 la posibilidad de \u00a0 invocar el beneficio de las facultades a que se refiere el p\u00e1rrafo 1), bien sea \u00a0 tres a\u00f1os despu\u00e9s de que haya dejado de ser pa\u00eds en desarrollo, bien sea a la \u00a0 expiraci\u00f3n del per\u00edodo decenal en curso, debiendo aplicarse el plazo que expire \u00a0 m\u00e1s tarde. \u00a0<\/p>\n<p>4) Si, a la \u00e9poca en que la \u00a0 declaraci\u00f3n hecha en virtud de los p\u00e1rrafos 1) o 2) deja de surtir efectos, \u00a0 hubiera en existencias ejemplares producidos en aplicaci\u00f3n de la licencia \u00a0 concedida en virtud de las disposiciones del presente Anexo, dichos ejemplares \u00a0 podr\u00e1n seguir siendo puestos en circulaci\u00f3n hasta agotar las existencias. \u00a0<\/p>\n<p>5) Todo pa\u00eds que est\u00e9 obligado \u00a0 por las disposiciones de la presente Acta y que haya depositado una declaraci\u00f3n \u00a0 o una notificaci\u00f3n de conformidad con el Articulo 31.1.) con respecto a la \u00a0 aplicaci\u00f3n de dicha Acta a un territorio determinado cuya situaci\u00f3n pueda \u00a0 considerarse como an\u00e1loga a la de los pa\u00edses a que se hace referencia en el \u00a0 p\u00e1rrafo 1), podr\u00e1, con respecto a ese territorio, hacer la declaraci\u00f3n a que se \u00a0 refiere el p\u00e1rrafo 1) y la notificaci\u00f3n de renovaci\u00f3n a que se hace referencia \u00a0 en el p\u00e1rrafo 2). Mientras esa declaraci\u00f3n o esa notificaci\u00f3n siga siendo \u00a0 v\u00e1lidas las disposiciones del presente Anexo se aplicar\u00e1n al territorio respecto \u00a0 del cual se hayan hecho. \u00a0<\/p>\n<p>6) a) El hecho de que un pa\u00eds \u00a0 invoque el beneficio de una de las facultades a las que se hace referencia en el \u00a0 p\u00e1rrafo 1) no permitir\u00e1 a otro pa\u00eds dar a las obras cuyo pa\u00eds de origen sea el \u00a0 primer pa\u00eds en cuesti\u00f3n, una protecci\u00f3n inferior a la que est\u00e1 obligado a \u00a0 otorgar de conformidad a los Art\u00edculos 1 a 20. \u00a0<\/p>\n<p>b) El derecho de aplicar la \u00a0 reciprocidad prevista en el frase segunda del Articulo 30.2) b), no se podr\u00e1 \u00a0 ejercer, antes de la fecha de expiraci\u00f3n del plazo aplicable en virtud del \u00a0 Articulo 1.3), con respecto a las obras cuyo pa\u00eds de origen sea un pa\u00eds que haya \u00a0 formulado una declaraci\u00f3n en virtud del Articulo V.1) a). \u00a0<\/p>\n<p>Articulo II \u00a0<\/p>\n<p>[Limitaciones del derecho de traducci\u00f3n: 1. Licencias concedidas por la \u00a0 autoridad competente; 2. a 4. Condiciones en que podr\u00e1n concederse estas \u00a0 licencias; 5. Usos para los que podr\u00e1n concederse licencias. 6. Expiraci\u00f3n de \u00a0 las licencias; 7. Obras compuestas principalmente de ilustraciones; 8. Obras \u00a0 retiradas de la circulaci\u00f3n; 9. Licencias para organismos de radiodifusi\u00f3n]. \u00a0<\/p>\n<p>1) Todo pa\u00eds que haya declarado \u00a0 que har\u00e1 uso de beneficio de la facultad prevista por el presente articulo \u00a0 tendr\u00e1 derecho, en lo que respecta a las obras publicadas en forma de edici\u00f3n \u00a0 impresa o cualquier otra forma an\u00e1loga de reproducci\u00f3n, de sustituir el derecho \u00a0 exclusivo de traducci\u00f3n, previsto en el Articulo 8, por un r\u00e9gimen de licencias \u00a0 no exclusivas e intransferibles, concedidas por la autoridad competente en las \u00a0 condiciones que se indican a continuaci\u00f3n, conforme a los dispuesto en el \u00a0<\/p>\n<p>Articulo IV. \u00a0<\/p>\n<p>2) a) Sin perjuicio de lo que \u00a0 dispone el p\u00e1rrafo 3), si a la expiraci\u00f3n de un plazo de tres a\u00f1os o de un \u00a0 per\u00edodo m\u00e1s largo determinado por la legislaci\u00f3n nacional de dicho pa\u00eds, \u00a0 contados desde la fecha de la primera publicaci\u00f3n de una obra, no se hubieses \u00a0 publicado una traducci\u00f3n de dicha obra en un idioma de uso general en ese pa\u00eds \u00a0 por el titular del derecho de traducci\u00f3n o con su autorizaci\u00f3n, todo nacional de \u00a0 dicho pa\u00eds podr\u00e1 obtener una licencia para efectuar la traducci\u00f3n de una obra en \u00a0 dicho idioma, y publicar dicha traducci\u00f3n en forma impresa o en cualquier otra \u00a0 forma an\u00e1loga de reproducci\u00f3n. \u00a0<\/p>\n<p>b) Tambi\u00e9n se podr\u00e1 conceder una \u00a0 licencia en las condiciones previstas en el presente articulo, si se han agotado \u00a0 todas las ediciones de la traducci\u00f3n publicadas en el idioma de que se trate. \u00a0<\/p>\n<p>3) a) En el caso de traducciones \u00a0 a un idioma que no sea de uso general en uno o m\u00e1s pa\u00edses desarrollados que sean \u00a0 miembros de la Uni\u00f3n, un plazo de un a\u00f1o sustituir\u00e1 al plazo de tres a\u00f1os \u00a0 previstos en el p\u00e1rrafo 29 a). \u00a0<\/p>\n<p>b) Todo pa\u00eds de los mencionados \u00a0 en el p\u00e1rrafo 1) podr\u00e1, con el acuerdo un\u00e1nime de todos los pa\u00edses desarrollados \u00a0 miembros de la Uni\u00f3n, en los cuales el mismo idioma fuere de uso general, \u00a0 sustituir, en el caso de traducciones a ese idioma, el plazo de los tres a\u00f1os a \u00a0 que se refiere el p\u00e1rrafo 2) a) por el plazo inferior que ese acuerdo determine \u00a0 y que no podr\u00e1 ser inferior a un a\u00f1o. No obstante, las disposiciones antedichas \u00a0 no se aplicar\u00e1n cuando el idioma de que se trate sea el espa\u00f1ol, franc\u00e9s o \u00a0 ingl\u00e9s. Los gobiernos que concluyan acuerdos como los mencionados, deber\u00e1n \u00a0 notificar los miembros al Director General. \u00a0<\/p>\n<p>4) a) La licencia a que se \u00a0 refiere el presente articulo no podr\u00e1 concederse antes de la expiraci\u00f3n de un \u00a0 plazo suplementario de seis meses, cuando pueda obtenerse al expirar un periodo \u00a0 de tres a\u00f1os y de nueve meses, cuando pueda obtenerse al expirar un periodo de \u00a0 un a\u00f1o: \u00a0<\/p>\n<p>i) a partir de la fecha en que el \u00a0 interesado haya cumplido los requisitos previstos en el Articulo IV.1). \u00a0<\/p>\n<p>ii) o bien, si la identidad o la \u00a0 direcci\u00f3n del titular del derecho de traducci\u00f3n son desconocidos, a partir de la \u00a0 fecha en que el interesado efect\u00fae seg\u00fan lo previsto en el Articulo IV.2), el \u00a0 env\u00edo de copias de la petici\u00f3n de licencia, que haya presentado a la autoridad \u00a0 competente. \u00a0<\/p>\n<p>b) Si, durante el plazo de seis o \u00a0 de nueve meses, una traducci\u00f3n en el idioma para el cual se formul\u00f3 la petici\u00f3n \u00a0 es publicada por el titular del derecho de traducci\u00f3n o con su autorizaci\u00f3n, no \u00a0 se podr\u00e1 conceder la licencia prevista en el presente articulo. \u00a0<\/p>\n<p>5) no podr\u00e1 concederse licencias \u00a0 en virtud de este articulo sino para uso escolar, universitario o de \u00a0 investigaci\u00f3n. \u00a0<\/p>\n<p>6) Si la traducci\u00f3n de una obra \u00a0 fuere publicada por el titular del derecho de traducci\u00f3n o con su autorizaci\u00f3n a \u00a0 un precio comparable al que normalmente se cobra en el pa\u00eds en cuesti\u00f3n por \u00a0 obras de naturaleza semejante, las licencias concedidas en virtud de este \u00a0 articulo cesar\u00e1n si esa traducci\u00f3n fuera en el mismo idioma y substancialmente \u00a0 del mismo contenido que la traducci\u00f3n publicada en virtud de la licencia. Sin \u00a0 embargo, podr\u00e1 continuarse la distribuci\u00f3n de los ejemplares comenzada antes de \u00a0 la terminaci\u00f3n de la licencia, hasta agotar las existencias. \u00a0<\/p>\n<p>7) Para las obras que est\u00e9n \u00a0 compuestas principalmente de ilustraci\u00f3n, s\u00f3lo se podr\u00e1n conceder una licencia \u00a0 para efectuar y publicar una traducci\u00f3n del texto y para reproducir y publicar \u00a0 las ilustraciones se cumplen las condiciones del Articulo III. \u00a0<\/p>\n<p>8) No podr\u00e1 concederse la \u00a0 licencia prevista en el presente articulo, si el autor hubiere retirado de la \u00a0 circulaci\u00f3n todos los ejemplares de su obra. \u00a0<\/p>\n<p>9) a) Podr\u00e1 otorgarse a un \u00a0 organismo de radiodifusi\u00f3n que tenga su sede en un pa\u00eds de aqu\u00e9llos a los que se \u00a0 refiere el p\u00e1rrafo 1) una licencia para efectuar la traducci\u00f3n de una obra que \u00a0 haya sido publicada en forma impresa o an\u00e1loga si dicho organismo la solicita a \u00a0 la autoridad competente de ese pa\u00eds, siempre que se cumplan las condiciones \u00a0 siguientes: \u00a0<\/p>\n<p>i) que la traducci\u00f3n sea hecha de \u00a0 un ejemplar producido y adquirido conforme a la legislaci\u00f3n de dicho pa\u00eds; \u00a0<\/p>\n<p>iii) que la traducci\u00f3n sea usada \u00a0 exclusivamente para los fines contemplados en el subp\u00e1rrafo ii) a trav\u00e9s de \u00a0 emisiones efectuadas legalmente y destinadas a ser recibidas en el territorio de \u00a0 dicho pa\u00eds, incluso emisiones efectuadas por medio de grabaciones sonoras o \u00a0 visuales efectuadas en forma legal y exclusivamente para esas emisiones; \u00a0<\/p>\n<p>iv) que el uso que se haga de la \u00a0 traducci\u00f3n no tenga fines de lucro. \u00a0<\/p>\n<p>b) Las grabaciones sonoras o \u00a0 visuales de una traducci\u00f3n que haya sido hecha por un organismo de radiodifusi\u00f3n \u00a0 bajo una licencia concedida en virtud de este p\u00e1rrafo podr\u00e1, para los fines y \u00a0 sujeto a las condiciones previstas en el subp\u00e1rrafo a), con el consentimiento de \u00a0 ese organismo, ser usada tambi\u00e9n por otro organismo de radiodifusi\u00f3n que tenga \u00a0 su sede en el pa\u00eds cuyas autoridades competentes hayan otorgado la licencia en \u00a0 cuesti\u00f3n. \u00a0<\/p>\n<p>c) Podr\u00e1 tambi\u00e9n otorgarse una \u00a0 licencia a un organismo de radiodifusi\u00f3n, siempre que se cumplan todos los \u00a0 requisitos y condiciones establecidos en el subp\u00e1rrafo a), para traducir textos \u00a0 incorporados a una fijaci\u00f3n audiovisual efectuada y publicada con el solo \u00a0 prop\u00f3sito de utilizarla para fines escolares o universitarios. \u00a0<\/p>\n<p>d) Sin perjuicio de los que \u00a0 disponen los subp\u00e1rrafos a) a c), las disposiciones de los p\u00e1rrafos precedentes \u00a0 se aplicar\u00e1n a la concesi\u00f3n y uso de las licencias en virtud de este p\u00e1rrafo. \u00a0<\/p>\n<p>Articulo III \u00a0<\/p>\n<p>[Limitaciones del derecho de reproducci\u00f3n: 1. Licencias concedidas por la \u00a0 autoridad competente; 2 a 5. Condiciones en que se podr\u00e1n conceder estas \u00a0 licencias; 6. Expiraci\u00f3n de licencias; 7. Obras a las que se aplica el presente \u00a0 articulo]. \u00a0<\/p>\n<p>1) Todo pa\u00eds que haya declarado \u00a0 que invocar\u00e1 el beneficio de la facultad prevista por el presente articulo \u00a0 tendr\u00e1 derecho a reemplazar el derecho exclusivo de reproducci\u00f3n previsto en el \u00a0 Articulo 9 por un r\u00e9gimen de licencias no exclusivas e intransferibles, \u00a0 concedidas por la autoridad competente en las condiciones que se indican a \u00a0 continuaci\u00f3n y de conformidad a lo dispuesto en el Articulo IV. \u00a0<\/p>\n<p>2) a) Cuando, con relaci\u00f3n a una \u00a0 obra a la cual este articulo es aplicable en virtud del p\u00e1rrafo 7), a la \u00a0 expiraci\u00f3n: \u00a0<\/p>\n<p>i) del plazo establecido en el \u00a0 p\u00e1rrafo 3) y calculado desde la fecha de la primera publicaci\u00f3n de una \u00a0 determinada edici\u00f3n de una obra, o \u00a0<\/p>\n<p>ii) de un plazo superior, fijado \u00a0 por la legislaci\u00f3n nacional del pa\u00eds al que se hace referencia en el p\u00e1rrafo 1) \u00a0 y contado desde la misma fecha, no hayan sido puestos a la venta, en dicho pa\u00eds, \u00a0 ejemplares de esa edici\u00f3n para responder a las necesidades del p\u00fablico en \u00a0 general o de la ense\u00f1anza escolar y universitaria por el titular del derecho de \u00a0 reproducci\u00f3n o con su autorizaci\u00f3n, a un precio comparable al que se cobre en \u00a0 dicho pa\u00eds podr\u00e1 obtener una licencia para reproducir y publicar dicha edici\u00f3n a \u00a0 ese previo o a un previo inferior, con el fin de responder a las necesidades de \u00a0 la ense\u00f1anza escolar o universitaria. \u00a0<\/p>\n<p>Articulo IV \u00a0<\/p>\n<p>[Disposiciones comunes sobre licencias previstas en los Art\u00edculos II y III: 1 y \u00a0 2. Procedimiento; 3. Indicaci\u00f3n del autor y del titulo de la obra; 4. \u00a0 Exportaci\u00f3n de ejemplares; 5. Nota; 6. Remuneraci\u00f3n]. \u00a0<\/p>\n<p>1) Toda licencia referida al \u00a0 Articulo II o III no podr\u00e1 ser concedida sino cuando el solicitante, de \u00a0 conformidad con las disposiciones vigentes en el pa\u00eds donde se presente la \u00a0 solicitud, justifiquen haber pedido al titular del derecho la autorizaci\u00f3n para \u00a0 efectuar una traducci\u00f3n y publicarla o reproducir y publicar la edici\u00f3n, seg\u00fan \u00a0 proceda, y que, despu\u00e9s de las diligencias correspondientes por su parte, no ha \u00a0 podido ponerse en contacto con ese titular ni ha podido obtener su autorizaci\u00f3n. \u00a0 En el momento de presentar su petici\u00f3n el solicitante deber\u00e1 informar a todo \u00a0 centro nacional o internacional de informaci\u00f3n previsto en el p\u00e1rrafo 2). \u00a0<\/p>\n<p>2) a) Cuando, con relaci\u00f3n a una \u00a0 obra a la cual este articulo es aplicables en virtud del p\u00e1rrafo 7), a la \u00a0 expiraci\u00f3n: \u00a0<\/p>\n<p>i) del plazo establecido en el \u00a0 p\u00e1rrafo 3) y calculado desde la fecha de la primera publicaci\u00f3n de una \u00a0 determinada edici\u00f3n de una obra, o \u00a0<\/p>\n<p>ii) de un plazo superior, fijado \u00a0 por la legislaci\u00f3n nacional del pa\u00eds al que se hace referencia en el p\u00e1rrafo 19 \u00a0 y contado desde la misma fecha, no hayan sido puestos a la venta, en dicho pa\u00eds, \u00a0 ejemplares de esa edici\u00f3n para responder a las necesidades del p\u00fablico en \u00a0 general o de la ense\u00f1anza escolar y universitaria por el titular del derecho de \u00a0 reproducci\u00f3n o con su autorizaci\u00f3n, a un previo comparable al que se sobre en \u00a0 dicho pa\u00eds podr\u00e1 obtener un licencia para reproducir y publicar dicha edici\u00f3n a \u00a0 ese previo o a un previo inferior, con el fin de responder a las necesidades de \u00a0 la ense\u00f1anza escolar y universitaria. \u00a0<\/p>\n<p>b) Se podr\u00e1 tambi\u00e9n conceder, en \u00a0 las condiciones previstas en el presente articulo, licencias para reproducir y \u00a0 publicar una edici\u00f3n que se haya distribuido seg\u00fan lo previsto en el subp\u00e1rrafo \u00a0 a), siempre que, una vez transcurrido el plazo correspondiente, no se haya \u00a0 puesto en venta ning\u00fan ejemplar de dicha edici\u00f3n durante un per\u00edodo de seis \u00a0 meses, en el pa\u00eds interesado, para responder a las necesidades del p\u00fablico en \u00a0 general o de la ense\u00f1anza escolar y universitaria y a un previo comparable al \u00a0 que se cobre en dicho pa\u00eds por obras an\u00e1logas. \u00a0<\/p>\n<p>3) El plazo al que se hace \u00a0 referencia en el p\u00e1rrafo 2) a) i) ser\u00e1 de cinco a\u00f1os. Sin embargo, \u00a0<\/p>\n<p>i) para las obras que traten de \u00a0 ciencias exactas, naturales o de tecnolog\u00eda, ser\u00e1 de tres a\u00f1os; \u00a0<\/p>\n<p>ii) para las obras que \u00a0 pertenezcan al campo de la imaginaci\u00f3n tales como novelas, obras po\u00e9ticas, \u00a0 dram\u00e1ticas y musicales, y para los libros de arte, ser\u00e1 de siete a\u00f1os. \u00a0<\/p>\n<p>4) a) Las licencias que puedan \u00a0 obtenerse al expirar un plazo de tres a\u00f1os no podr\u00e1 concederse en virtud del \u00a0 presente articulo hasta que no haya pasado un plazo de seis meses: \u00a0<\/p>\n<p>i) a partir de la fecha en que el \u00a0 interesado haya cumplido los requisitos previstos en el Articulo IV.1); \u00a0<\/p>\n<p>ii) o bien, si la identidad o la \u00a0 direcci\u00f3n del titular del derecho de reproducci\u00f3n son desconocidos, a partir de \u00a0 la fecha en que el interesado efect\u00faa, seg\u00fan lo previsto en el articulo IV.2), \u00a0 el env\u00edo de copias de la petici\u00f3n de licencia, que haya presentado a la \u00a0 autoridad competente. \u00a0<\/p>\n<p>b) En los dem\u00e1s casos y siendo \u00a0 aplicable el Articulo IV:2), no se podr\u00e1 conceder la licencia antes de que \u00a0 transcurra un plazo de tres meses a partir del env\u00edo de las copias de la \u00a0 solicitud. \u00a0<\/p>\n<p>c) No podr\u00e1 conceder se una \u00a0 licencia durante el plazo de seis o tres meses mencionado en el subp\u00e1rrafo a) si \u00a0 hubiere tenido lugar una distribuci\u00f3n en la forma descrita en el p\u00e1rrafo 2). \u00a0<\/p>\n<p>d) No se podr\u00e1 conceder una \u00a0 licencia cuando el autor haya retirado de la circulaci\u00f3n todos los ejemplares de \u00a0 la edici\u00f3n para la reproducci\u00f3n y publicaci\u00f3n de la cual la licencia se haya \u00a0 solicitado. \u00a0<\/p>\n<p>5) No se conceder\u00e1 en virtud del \u00a0 presente articulo una licencia para reproducir y publicar una traducci\u00f3n de una \u00a0 obra, en los casos que se indican a continuaci\u00f3n: \u00a0<\/p>\n<p>i) cuando la traducci\u00f3n de que se \u00a0 trate no haya sido publicada por el titular del derecho de autor o con su \u00a0 autorizaci\u00f3n; \u00a0<\/p>\n<p>ii) cuando la traducci\u00f3n no se \u00a0 haya efectuado en el idioma de uso general en el pa\u00eds que otorga la licencia. \u00a0<\/p>\n<p>6) Si se pusieren en venta \u00a0 ejemplares de una edici\u00f3n de una obra en el pa\u00eds al que se hace referencia en el \u00a0 p\u00e1rrafo 1) para responder a las necesidades bien del p\u00fablico, bien de la \u00a0 ense\u00f1anza escolar y universitaria, por el titular del derecho de autor o con su \u00a0 autorizaci\u00f3n, a un precio comparable al que se acostumbra en dicho pa\u00eds para \u00a0 obras an\u00e1logas, toda licencia concedida en virtud del presente articulo \u00a0 terminar\u00e1 si esa edici\u00f3n se ha hecho en el mismo idioma que la edici\u00f3n publicada \u00a0 en virtud de esta licencia y si su contenido es esencialmente el mismo. Queda \u00a0 entendido, sin embargo, que la puesta en circulaci\u00f3n de todos los ejemplares ya \u00a0 producidos antes de la expiraci\u00f3n de la licencia podr\u00e1 continuarse hasta su \u00a0 agotamiento. \u00a0<\/p>\n<p>7) a) Sin perjuicio de lo que \u00a0 dispone el subp\u00e1rrafo b), las disposiciones del presente art\u00edculo se aplicar\u00e1n \u00a0 exclusivamente a las obras publicadas en forma de edici\u00f3n impresa o en cualquier \u00a0 otra forma an\u00e1loga de reproducci\u00f3n. \u00a0<\/p>\n<p>b) Las disposiciones del presente \u00a0 articulo se aplicar\u00e1n igualmente a la reproducci\u00f3n audiovisual de fijaciones \u00a0 audiovisuales efectuadas legalmente y que constituyan o incorporen obras \u00a0 protegidas, y a la traducci\u00f3n del texto que las acompa\u00f1e en un idioma de uso \u00a0 general en el pa\u00eds donde la licencia se solicite, entendi\u00e9ndose en todo caso que \u00a0 las fijaciones audiovisuales han sido concebidas y publicadas con el fin \u00a0 exclusivo de ser utilizadas para las necesidades de la ense\u00f1anza escolar y \u00a0 universitaria. \u00a0<\/p>\n<p>Articulo IV \u00a0<\/p>\n<p>[Disposiciones comunes sobre \u00a0 licencias previstas en los Art\u00edculos II y III: 1 y 2. Procedimiento; 3. \u00a0 Indicaci\u00f3n del autor y del t\u00edtulo de la obra; 4. Exportaci\u00f3n de ejemplares; 5. \u00a0 Nota; 6. Remuneraci\u00f3n]. \u00a0<\/p>\n<p>1) Toda licencia referida al \u00a0 Articulo II o III no podr\u00e1 ser concedida sino cuando el solicitante, de \u00a0 conformidad con las disposiciones vigentes en el pa\u00eds donde se presente la \u00a0 solicitud, justifique haber pedido al titular del derecho la autorizaci\u00f3n para \u00a0 efectuar una traducci\u00f3n y publicarla o reproducir y publicar la edici\u00f3n, seg\u00fan \u00a0 proceda y que, despu\u00e9s de las diligencias correspondientes por su parte, no ha \u00a0 podido obtener su autorizaci\u00f3n. En el momento de presentar su petici\u00f3n el \u00a0 solicitante deber\u00e1 informar a todo centro nacional o internacional de \u00a0 informaci\u00f3n previsto en el p\u00e1rrafo 2). \u00a0<\/p>\n<p>2) Si el titular del derecho no \u00a0 ha podido ser localizado por el solicitante, \u00e9ste deber\u00e1 dirigir, por correo \u00a0 a\u00e9reo certificado, copias de la petici\u00f3n de licencia que haya presentado la \u00a0 autoridad competente, al editor cuyo nombre figure en la obra y a cualquier \u00a0 centro nacional o internacional de informaci\u00f3n que pueda haber sido designado, \u00a0 para ese efecto, en una notificaci\u00f3n depositada en poder del Director General, \u00a0 por el gobierno del pa\u00eds en el que se suponga que el editor tiene su centro \u00a0 principal de actividad. \u00a0<\/p>\n<p>3) El nombre del autor deber\u00e1 \u00a0 indicarse en todos los ejemplares de la traducci\u00f3n o reproducci\u00f3n publicados en \u00a0 virtud de una licencia concedida de conformidad con el Art\u00edculo II o del \u00a0 Articulo III. El titulo de la obra deber\u00e1 figurar en todos esos ejemplares. En \u00a0 el caso de una traducci\u00f3n, el titulo original de la obra deber\u00e1 aparecer en todo \u00a0 caso en todas los ejemplares mencionados. \u00a0<\/p>\n<p>4) a) Las licencias concedidas en \u00a0 virtud del Articulo II o del Articulo III no se extender\u00e1n a la exportaci\u00f3n de \u00a0 ejemplares y no ser\u00e1n v\u00e1lidas sino para la publicaci\u00f3n de la traducci\u00f3n o de la \u00a0 reproducci\u00f3n, seg\u00fan el caso, en el interior del territorio del pa\u00eds donde se \u00a0 solicite la licencia. \u00a0<\/p>\n<p>b) Para los fines del subp\u00e1rrafo \u00a0 a), el concepto de exportaci\u00f3n comprender\u00e1 el env\u00edo de ejemplares desde un \u00a0 territorio al pa\u00eds que, con respecto a ese territorio, haya hecho una \u00a0 declaraci\u00f3n de acuerdo al Articulo 1.5). \u00a0<\/p>\n<p>c) Si un organismo gubernamental \u00a0 o publico de un pa\u00eds que ha concedido una licencia para efectuar una traducci\u00f3n \u00a0 en virtud del Articulo II, a un idioma distinto del espa\u00f1ol, franc\u00e9s o ingl\u00e9s, \u00a0 env\u00eda ejemplares de la traducci\u00f3n publicada bajo esa licencia a otro pa\u00eds, dicho \u00a0 env\u00edo no ser\u00e1 considerado como exportaci\u00f3n, para los fines del subp\u00e1rrafo a), \u00a0 siempre que se cumplan todas las condiciones siguientes: \u00a0<\/p>\n<p>i) Que los destinatarios sean \u00a0 personas privadas, nacionales del pa\u00eds cuya autoridad competente otorg\u00f3 la \u00a0 licencia o asociaciones compuestas por esos nacionales; \u00a0<\/p>\n<p>ii) Que los ejemplares sean \u00a0 utilizados exclusivamente con fines escolares, universitarios o de \u00a0 investigaci\u00f3n; \u00a0<\/p>\n<p>iii) Que el env\u00edo y distribuci\u00f3n \u00a0 de los ejemplares a los destinatarios no tengan fines de lucro; \u00a0<\/p>\n<p>iv) Que el pa\u00eds al cual los \u00a0 ejemplares hayan sido enviados haya celebrado un acuerdo con el pa\u00eds cuyas \u00a0 autoridades competentes han otorgado la licencia para autorizar la recepci\u00f3n, la \u00a0 distribuci\u00f3n o ambas operaciones y que el gobierno de ese ultimo pa\u00eds lo haya \u00a0 notificado al Director General. \u00a0<\/p>\n<p>5) Todo ejemplar publicado de \u00a0 conformidad con una licencia otorgada en virtud del Articulo II o del Articulo \u00a0 III deber\u00e1 contener una nota, en el idioma que corresponda, advirtiendo que el \u00a0 ejemplar se pone en circulaci\u00f3n s\u00f3lo en el pa\u00eds o en el territorio donde dicha \u00a0 licencia se aplique. \u00a0<\/p>\n<p>6) a) Se adoptar\u00e1n medias \u00a0 adecuadas a nivel nacional con el fin de asegurar: \u00a0<\/p>\n<p>ii) El pago y la transferencia de \u00a0 esa remuneraci\u00f3n; si existiera una reglamentaci\u00f3n nacional en materia de \u00a0 divisas, la autoridad competente no escatimar\u00e1 esfuerzos, recurriendo a los \u00a0 mecanismos internacionales, para asegurar la transferencia de la remuneraci\u00f3n en \u00a0 moneda internacionalmente convertible o en su equivalente. \u00a0<\/p>\n<p>b) Se adoptar\u00e1n medidas adecuadas \u00a0 en el marco de la legislaci\u00f3n nacional para garantizar una traducci\u00f3n correcta \u00a0 de la obra o una reproducci\u00f3n exacta de la edici\u00f3n de que se trate, seg\u00fan los \u00a0 casos. \u00a0<\/p>\n<p>Articulo V \u00a0<\/p>\n<p>[Otra posibilidad de limitar el derecho de traducci\u00f3n: 1. R\u00e9gimen previsto por \u00a0 las Actas de 1886 y de 1896; 2. Imposibilidad de cambiar de r\u00e9gimen despu\u00e9s de \u00a0 haber elegido el del Articulo II; 3. Plazo para elegir el otro r\u00e9gimen]. \u00a0<\/p>\n<p>1) a) todo pa\u00eds habilitado para \u00a0 hacer una declaraci\u00f3n en el sentido de que har\u00e1 uso de la facultad prevista por \u00a0 el Articulo II, podr\u00e1 al ratificar la presente Acta o al adherirse a ella, en \u00a0 lugar del tal declaraci\u00f3n: \u00a0<\/p>\n<p>i) si se trata de un pa\u00eds al cual \u00a0 el Articulo 30.2) a) no es aplicable, formular una declaraci\u00f3n de acuerdo a esa \u00a0 disposici\u00f3n con respecto al derecho de traducci\u00f3n; \u00a0<\/p>\n<p>ii) Si se trata de un pa\u00eds al \u00a0 cual el Articulo 30.2) a) no es aplicable, aun cuando no fuera un pa\u00eds externo a \u00a0 la Uni\u00f3n, formular una declaraci\u00f3n en el sentido del Articulo 30.2) b), primera \u00a0 frase. \u00a0<\/p>\n<p>b) En el caso de un pa\u00eds que haya \u00a0 cesado de ser considerado como pa\u00eds en desarrollo, seg\u00fan el Articulo I.1), toda \u00a0 declaraci\u00f3n formulada con arreglo al presente p\u00e1rrafo conserva su validez hasta \u00a0 la fecha de expiraci\u00f3n del plazo aplicable en virtud del Articulo I.3). \u00a0<\/p>\n<p>c) Todo pa\u00eds que haya hecho una \u00a0 declaraci\u00f3n conforme al presente subp\u00e1rrafo no podr\u00e1 invocar ulteriormente el \u00a0 beneficio de la facultad prevista por el Articulo II ni siquiera en el caso de \u00a0 retirar dicha declaraci\u00f3n. \u00a0<\/p>\n<p>2) Bajo reserva de lo dispuesto \u00a0 en el p\u00e1rrafo 3), todo pa\u00eds que haya invocado el beneficio de la facultad \u00a0 prevista por el Articulo II no podr\u00e1 hacer ulteriormente un declaraci\u00f3n conforme \u00a0 al p\u00e1rrafo 1). \u00a0<\/p>\n<p>3) Todo pa\u00eds que haya dejado de \u00a0 ser considerado como pa\u00eds en desarrollo seg\u00fan el Articulo I.1) podr\u00e1, a m\u00e1s \u00a0 tardar dos a\u00f1os antes de la expiraci\u00f3n del plazo aplicable en virtud del \u00a0 Articulo I.3), hacer una declaraci\u00f3n en el sentido del Articulo 30.2) b), \u00a0 primera frase, a pesar del hecho de no ser un pa\u00eds externo a la Uni\u00f3n. Dicha \u00a0 declaraci\u00f3n surtir\u00e1 efecto en la fecha en la que expire el plazo aplicable en \u00a0 virtud del Articulo I.3). \u00a0<\/p>\n<p>Articulo VI \u00a0<\/p>\n<p>[Posibilidades de aplicar la aplicaci\u00f3n de determinadas disposiciones del Anexo \u00a0 antes de quedar obligado por \u00e9ste: 1. Declaraci\u00f3n; 2. Depositario y fecha en que \u00a0 la declaraci\u00f3n surtir\u00e1 efectos]. \u00a0<\/p>\n<p>1) Todo pa\u00eds de la Uni\u00f3n podr\u00e1 \u00a0 declarar a partir de la firma de la presente Acta o en cualquier momento antes \u00a0 de quedar obligado por los Art\u00edculos 1 a 21 y por el presente Anexo; \u00a0<\/p>\n<p>i) Si se trata de un pa\u00eds que \u00a0 estando obligado por los Art\u00edculos 1 a 21 y por el presente Anexo estuviese \u00a0 habilitado para acogerse al beneficio de las facultades a las que se hace \u00a0 referencia en el Articulo II o III o de ambos a las obras cuyo pa\u00eds de origen \u00a0 sea un pa\u00eds que, en aplicaci\u00f3n del subp\u00e1rrafo ii) que figura a continuaci\u00f3n, \u00a0 acepte la aplicaci\u00f3n de esos art\u00edculos a tales obras o que este obligado por los \u00a0 Art\u00edculos 1 a 21 y por el presente Anexo; esa declaraci\u00f3n podr\u00e1 referirse \u00a0 tambi\u00e9n al Articulo V o solamente al Articulo II. \u00a0<\/p>\n<p>ii) Que acepta la aplicaci\u00f3n del \u00a0 presente Anexo a las obras de las que sea pa\u00eds de origen por parte de los pa\u00edses \u00a0 que hayan hecho un declaraci\u00f3n en virtud del subp\u00e1rrafo i) anterior o una \u00a0 notificaci\u00f3n en virtud del Articulo I. \u00a0<\/p>\n<p>2) Toda declaraci\u00f3n de \u00a0 conformidad con el p\u00e1rrafo 1) deber\u00e1 se hecha por escrito y depositada en poder \u00a0 del Director General. Surtir\u00e1 efectos desde la fecha de su dep\u00f3sito. \u00a0<\/p>\n<p>Certifico que es copia fiel del \u00a0 texto oficial espa\u00f1ol del Acta de Par\u00eds, del 24 de julio de 1971, del Convenio \u00a0 de Berna para la Protecci\u00f3n de las Obras Literarias y Art\u00edsticas, establecido el \u00a0 9 de septiembre de 1886. \u00a0<\/p>\n<p>ARPAD BOGSCH \u00a0<\/p>\n<p>Director General. \u00a0<\/p>\n<p>Ginebra, 20 de junio de 1984. \u00a0<\/p>\n<p>RAMA EJECUTIVA DEL PODER \u00a0 PUBLICO \u00a0<\/p>\n<p>PRESIDENCIA DE LA REPUBLICA \u00a0<\/p>\n<p>Bogot\u00e1, D.E., octubre de 1985. \u00a0<\/p>\n<p>Aprobado. Som\u00e9tase a la \u00a0 consideraci\u00f3n del honorable Congreso Nacional para los efectos constitucionales. \u00a0<\/p>\n<p>(Fdo.) BELISARIO BETANCUR \u00a0<\/p>\n<p>El Ministro de Relaciones \u00a0 Exteriores, \u00a0<\/p>\n<p>(Fdo.) Augusto Ram\u00edrez Ocampo. \u00a0<\/p>\n<p>Es fiel copia del texto \u00a0 certificado en espa\u00f1ol del Acta de Par\u00eds, del 24 de julio de 1971, del Convenio \u00a0 de Berna sobre la Protecci\u00f3n de las Obras Literarias y art\u00edsticas, establecido \u00a0 el 9 de septiembre de 1886, que reposa en los archivos de la Divisi\u00f3n de Asuntos \u00a0 Jur\u00eddicos de la Canciller\u00eda. \u00a0<\/p>\n<p>El Jefe de la Divisi\u00f3n de Asuntos \u00a0 Jur\u00eddicos, \u00a0<\/p>\n<p>Joaquin Barreto Ruiz \u00a0<\/p>\n<p>ARTICULO 2\u00ba.-Esta \u00a0 Ley entrar\u00e1 en vigencia una vez cumplidos los tr\u00e1mites establecidos en la \u00a0 Ley 7a. del 30 de noviembre de 1944, en relaci\u00f3n con el Convenio que por \u00a0 esta misma Ley se aprueba. \u00a0<\/p>\n<p>Dada en Bogot\u00e1, D. E., a los &#8230; \u00a0 d\u00edas del mes de &#8230; de mil novecientos ochenta y siete (1987). \u00a0<\/p>\n<p>El Presidente del honorable \u00a0 Senado de la Rep\u00fablica, PEDRO MARTIN LEYES HERNANDEZ, el Presidente de la \u00a0 honorable C\u00e1mara de Representantes, CESAR PEREZ GARCIA, el Secretario General \u00a0 del honorable Senado de la Rep\u00fablica, Crisp\u00edn Villaz\u00f3n de Armas, el Secretario \u00a0 General de la honorable C\u00e1mara de Representantes, Luis Lorduy Lorduy. \u00a0<\/p>\n<p>Rep\u00fablica de Colombia-Gobierno \u00a0 Nacional \u00a0<\/p>\n<p>Bogot\u00e1, D. E., 26 de octubre de \u00a0 1987. \u00a0<\/p>\n<p>Publ\u00edquese y ejec\u00fatese. \u00a0<\/p>\n<p>VIRGILIO BARCO \u00a0<\/p>\n<p>El Ministro de Gobierno, C\u00e9sar \u00a0 Gaviria Trujillo, el Ministro de Comunicaciones. encargado de las funciones del \u00a0 Despacho del Ministro de Relaciones Exteriores, Fernando Cepeda Ulloa. \u00a0<\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0 LEY 33 DE 1987 \u00a0 (Octubre 26) \u00a0 Por medio de la cual se aprueba \u00a0 el &#8220;Convenio de Berna para la Protecci\u00f3n de las Obras Literarias y Art\u00edsticas&#8221;, \u00a0 del 9 de septiembre de 1886, completado en Par\u00eds el 4 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[130],"tags":[],"class_list":["post-4713","post","type-post","status-publish","format-standard","hentry","category-leyes-1987"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/4713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/comments?post=4713"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/4713\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/media?parent=4713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/categories?post=4713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/tags?post=4713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}