{"id":478,"date":"2020-11-24T15:26:20","date_gmt":"2020-11-24T15:26:20","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-361-de-1997\/"},"modified":"2020-11-24T15:26:20","modified_gmt":"2020-11-24T15:26:20","slug":"ley-361-de-1997","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2020\/11\/24\/ley-361-de-1997\/","title":{"rendered":"LEY 361 DE 1997"},"content":{"rendered":"<p>             <\/font> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"logo3.gif\" width=\"118\" height=\"94\" align=\"center\"><br \/>&nbsp;<\/font><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"6\" face=\"Verdana\">LEY 361 DE 1997<\/font><\/p>\n<p> <\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">(febrero 7 DE 1997)<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><i><font size=\"2\" face=\"Verdana\">Por la cual se establecen mecanismos de integraci\u00f3n social de las personas con limitaci\u00f3n y se dictan otras disposiciones. <\/font><\/i><\/p>\n<div align=\"justify\"><font face=\"Verdana\"><font size=\"2\"><b>*<\/b><\/font><b><font size=\"2\">Notas de Vigencia*<\/font><\/b><\/font><\/font><\/div>\n<div align=\"justify\">&nbsp;<\/div>\n<table cellSpacing=\"0\" cellPadding=\"6\" rules=\"none\" width=\"100%\" border=\"1\" frame=\"border\" id=\"table1\">\n<tr>\n<td align=\"justify\">\n<p align=\"justify\"><font face=\"Verdana\" size=\"2\">Modificado por el<b><a hrefx=\"..\/..\/..\/ESTATUTOS\/EST%20ANTITRAMITRES\/0019.htm\">Decreto 019 de 2012<\/a><\/b>, publicado en el Diario Oficial No. 480308 de Enero 10 de 2012. &quot;<font >Por el cual se dictan normas para suprimir o reformar regulaciones, procedimientos y tr\u00e1mites innecesarios existentes en la Administraci\u00f3n P\u00fablica&quot;.&nbsp; <\/font><\/font><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\">\n<p align=\"justify\"><font size=\"2\" face=\"Verdana\">Modificada por la <b><a hrefx=\"..\/2009\/LEY_1316_DE_2009.htm\">Ley 1316 de 2009<\/a><\/b>, publicada en el Diario Oficial No. 47.409 de 13 de julio de 2009, &#39;por medio de la cual se reforma parcialmente la Ley 361 de 1997, se reconoce un espacio en los espect\u00e1culos para personas con discapacidad y se dictan otras disposiciones&#39;. <\/font><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font size=\"2\" face=\"Verdana\">Ver <b><a hrefx=\"..\/2009\/LEY_1306_DE_2009.htm\">Ley 1306 de 2009<\/a><\/b><\/font><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\">\n<p align=\"justify\"><font size=\"2\" face=\"Verdana\">Modificada por la <b><a hrefx=\"..\/2009\/LEY_1287_DE_2009.htm\">Ley 1287 de 2009 <\/a><\/b>, publicada en el Diario Oficial No. 47.280 de 3 de marzo de 2009, &#39;Por la cual se adiciona la Ley 361 de 1997&#39;&nbsp; <\/font><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\">\n<p align=\"justify\"><font size=\"2\" face=\"Verdana\">Modificada por la <b><a hrefx=\"..\/2007\/L1145007.htm\">Ley 1145 de 2007<\/a><\/b>, publicada en el Diario Oficial No. 46.685 de 10 de julio de 2007, &quot;Por medio de la cual se organiza el Sistema Nacional de Discapacidad y se dictan otras disposiciones&quot;<\/font><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font size=\"2\" face=\"Verdana\">Modificada por la <b><a hrefx=\"..\/2005\/L0982005.htm\">Ley 982 de 2005<\/a><\/b>, publicada en el Diario Oficial No. 45.995 de 09 de agosto de 2005, &quot;Por la cual se establecen normas tendientes a la equiparaci\u00f3n de oportunidades para las personas sordas y sordociegas y se dictan otras disposiciones<\/font><\/td>\n<\/tr>\n<\/table>\n<p align=\"justify\"><font face=\"Verdana\"><b><font size=\"1\">*CONCORDANCIAS*<\/font><\/b><\/font><\/font><\/p>\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\" dir=\"ltr\">\n<tr>\n<td><b><a hrefx=\"..\/..\/decretos\/2012\/0734.htm\"><font size=\"1\" face=\"Verdana\">Decreto 734 de 2012<\/font><\/a><\/b><\/td>\n<\/tr>\n<\/table>\n<p align=\"center\"><b><font size=\"2\" face=\"Verdana\">EL CONGRESO DE COLOMBIA<\/font><\/b><\/p>\n<p align=\"center\">&nbsp;<\/p>\n<p align=\"center\"><b><font size=\"2\" face=\"Verdana\">DECRETA: <\/font> <\/b> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel001><font size=\"2\" face=\"Verdana\">T\u00cdTULO I. <\/font> <\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">DE LOS PRINCIPIOS GENERALES<\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><A name=1><b><font size=\"2\">Art\u00edculo 1\u00b0.<\/font><\/b><\/A><font size=\"2\"> Los principios que inspiran la presente Ley, se fundamentan en los art\u00edculos <b><a hrefx=\"..\/..\/..\/contitucion_politica\/contitucion_politica.htm#13\">13,<\/a><\/b> <b><a hrefx=\"..\/..\/..\/contitucion_politica\/contitucion_politica.htm#47\">47,<\/a><\/b> <b><a hrefx=\"..\/..\/..\/contitucion_politica\/contitucion_politica.htm#54\">54<\/a><\/b> y <b><a hrefx=\"..\/..\/..\/contitucion_politica\/contitucion_politica.htm#68\">68<\/a><\/b> que la Constituci\u00f3n Nacional reconocen en consideraci\u00f3n a la dignidad que le es propia a las personas con limitaci\u00f3n en sus derechos fundamentales, econ\u00f3micos, sociales y culturales para su completa realizaci\u00f3n personal y su total integraci\u00f3n social y a las personas con limitaciones severas y profundas, la asistencia y protecci\u00f3n necesarias. <\/font> <\/font> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Notas Jurisprudenciales* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">Aparte subrayado declarado EXEQUIBLE por la Corte Constitucional mediante <b> <a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2011\/C-824-11.rtf\">Sentencia C-824-11<\/a><\/b> seg\u00fan Comunicado de Prensa de la Sala Plena de 2 de noviembre de 2011, Magistrado Ponente Dr. Luis Ernesto Vargas Silva. <\/font><\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><A name=2><b><font size=\"2\">Art\u00edculo 2\u00b0.<\/font><\/b><\/A><font size=\"2\"> El Estado garantizar\u00e1 y velar\u00e1 por que en su ordenamiento jur\u00eddico no prevalezca discriminaci\u00f3n sobre habitante alguno en su territorio, por circunstancias personales, econ\u00f3micas, f\u00edsicas, fisiol\u00f3gicas, s\u00edquicas, sensoriales y sociales. <\/font> <\/font> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><A name=3><b><font size=\"2\">Art\u00edculo 3\u00b0.<\/font><\/b><\/A><font size=\"2\"> El Estado Colombiano inspira esta ley para la normalizaci\u00f3n social plena y la total integraci\u00f3n de las personas con limitaci\u00f3n y otras disposiciones legales que se expidan sobre la materia en la Declaraci\u00f3n de los Derechos Humanos proclamada por las Naciones Unidas en el a\u00f1o 1948, en la Declaraci\u00f3n de los Derechos del Deficiente Mental aprobada por la ONU el 20 de diciembre de 1971, en la Declaraci\u00f3n de los Derechos de las Personas con Limitaci\u00f3n, aprobada por la Resoluci\u00f3n 3447 de la misma organizaci\u00f3n, del 9 de diciembre de 1975, en el Convenio 159 de la OIT, en la Declaraci\u00f3n de Sund Berg de Torremolinos, Unesco 1981, en la Declaraci\u00f3n de las Naciones Unidas concerniente a las personas con limitaci\u00f3n de 1983 y en la recomendaci\u00f3n 168 de la OIT de 1983.<\/font><\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Notas Jurisprudenciales* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Aparte subrayado declarado EXEQUIBLE, en el entendido que refiere \u00fanica y exclusivamente a la obligaci\u00f3n del Estado y la sociedad de eliminar las barreras del entorno f\u00edsico y social, por la Corte Constitucional mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2013\/C-066-13.html\">Sentencia C-066-13<\/a><\/b> de 11 de febrero de 2013, Magistrado Ponente Dr. Luis Ernesto Vargas Silva.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><A name=4><b><font size=\"2\">Art\u00edculo<\/font><\/b><font size=\"2\"><b> 4\u00b0<\/b>.<\/font><\/A><font size=\"2\"> Las ramas del poder p\u00fablico pondr\u00e1n a disposici\u00f3n todos los recursos necesarios para el ejercicio de los derechos a que se refiere el art\u00edculo 1o. de la presente Ley, siendo obligaci\u00f3n ineludible del Estado la prevenci\u00f3n, los cuidados m\u00e9dicos y sicol\u00f3gicos, la habilitaci\u00f3n y la rehabilitaci\u00f3n adecuadas, la educaci\u00f3n apropiada, la orientaci\u00f3n, la integraci\u00f3n laboral, la garant\u00eda de los derechos fundamentales econ\u00f3micos, culturales y sociales. <\/font> <\/font> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">Para estos efectos estar\u00e1n obligados a participar para su eficaz realizaci\u00f3n, la administraci\u00f3n central, el sector descentralizado, las administraciones departamentales, distritales y municipales, todas las corporaciones p\u00fablicas y privadas del pa\u00eds. <\/font> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><A name=5><b><font size=\"2\">Art\u00edculo 5\u00b0.<\/font><\/b><\/A><font size=\"2\"> Las personas con limitaci\u00f3n deber\u00e1n aparecer calificadas como tales en el carn\u00e9 de afiliado al Sistema de Seguridad en Salud, ya sea el r\u00e9gimen contributivo o subsidiado. Para tal efecto las empresas promotoras de salud deber\u00e1n consignar la existencia de la respectiva <i>limitaci\u00f3n<\/i> en el carn\u00e9 de afiliado, para lo cual solicitar\u00e1n en el formulario de afiliaci\u00f3n la informaci\u00f3n respectiva y la verificar\u00e1n a trav\u00e9s de diagn\u00f3stico m\u00e9dico en caso de que dicha <i>limitaci\u00f3n<\/i> no sea evidente. <\/font> <\/font> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">Dicho carn\u00e9 especificar\u00e1 el car\u00e1cter de persona con limitaci\u00f3n y el grado de <i>limitaci\u00f3n<\/i> moderada, severa o profunda de la persona. Servir\u00e1 para identificarse como titular de los derechos establecidos en la presente Ley. <\/font> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">El Consejo Nacional de Seguridad Social en Salud realizar\u00e1 las modificaciones necesarias al formulario de afiliaci\u00f3n y al carn\u00e9 de los afiliados al Sistema General de Seguridad Social en Salud con el objeto de incorporar las modificaciones aqu\u00ed se\u00f1aladas. <\/font> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">Lo dispuesto en este art\u00edculo se entiende sin perjuicio de las pol\u00edticas que con relaci\u00f3n a las personas con limitaci\u00f3n establezca el &quot;Comit\u00e9 Consultivo Nacional de las Personas con <i>Limitaci\u00f3n<\/i>&quot; a que se refiere el art\u00edculo siguiente. <\/font> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Notas Jurisprudenciales* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. Y la expresi\u00f3n subrayada y en cursiva &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n &quot;discapacidad&quot; por la misma <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia<\/a><\/b>.<\/font><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Aparte subrayado declarado EXEQUIBLE, por el cargo de violaci\u00f3n del art\u00edculo 29 de la C.P. y el bloque de constitucionalidad por la Corte Constitucional mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2012\/C-606-12.html\">Sentencia C-606-12<\/a><\/b> de 1o. de agosto de 2012, Magistrada Ponente Dra. Adriana Mar\u00eda Guill\u00e9n Arango. Inepta demanda en relaci\u00f3n con el cargo por violaci\u00f3n del Pre\u00e1mbulo y los art\u00edculos 1, 2, 4, 5, 9, 11, 13, 16, 25, 47, 48, 53, 54, 93; los numerales 2 y 4 del art\u00edculo 95; el literal a) del art\u00edculo 52, 230 de la Constituci\u00f3n y los elementos del bloque de constitucionalidad.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><A name=6><b><font size=\"2\">Art\u00edculo 6\u00b0.<\/font><\/b><\/A><i><b><font size=\"2\"> * Derogado por la <\/font><\/b><font size=\"2\"><b><a hrefx=\"..\/2007\/L1145007.htm\">Ley 1145 de 2007<\/a><\/b><\/font><b><font size=\"2\">*<\/font><\/b><\/i><\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p><DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\" size=\"2\"><b>*Nota de vigencia*<\/b><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border id=\"table6\">       <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Art\u00edculo derogado por el art\u00edculo 19 de la <b><a hrefx=\"..\/2007\/L1145007.htm\">Ley 1145 de 2007<\/a><\/b>, publicada en el Diario Oficial No. 46.685 de 10 de julio de 2007.<\/font><\/TD><\/TR>   <\/TABLE>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\" size=\"2\"><b>*Texto original de la Ley 361 de 1997*<\/b><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border id=\"table7\">        <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\"><b>Art\u00edculo 6. <\/b>Constit\u00fayese el &#39;Comit\u00e9 Consultivo Nacional de las Personas con Limitaci\u00f3n&#39;, como asesor institucional para el seguimiento y verificaci\u00f3n de la puesta en marcha de las pol\u00edticas, estrategias y programas que garanticen la integraci\u00f3n social del limitado. Dicho Comit\u00e9 tendr\u00e1 car\u00e1cter permanente y estar\u00e1 coordinado por una Consejer\u00eda Presidencial designada para tal efecto. <\/font> <\/TD><\/TR>      <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Ser\u00e1 as\u00ed mismo funci\u00f3n del Comit\u00e9, velar por el debido cumplimiento de las disposiciones y principios establecidos en esta ley, y deber\u00e1 adem\u00e1s promover las labores de coordinaci\u00f3n interinstitucional conformando grupos de enlace sectorial con los Ministros de Salud, Educaci\u00f3n, Trabajo y Seguridad Social, Transporte, Desarrollo Econ\u00f3mico, Comunicaciones, Hacienda y las dem\u00e1s entidades y organismos que se estime conveniente vincular. <\/font> <\/TD><\/TR>      <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">El Comit\u00e9 estar\u00e1 presidido por el Ministro de Salud y tendr\u00e1 los siguientes miembros: cinco representantes de organizaciones de y para limitados dentro de los cuales habr\u00e1 un representante de organizaciones de padres de familia de limitados, tres representantes de organizaciones acad\u00e9micas y\/o cient\u00edficas que tengan que ver con la materia y tres representantes de personas jur\u00eddicas cuya capacidad de actuaci\u00f3n gire en torno a este objeto social. Los anteriores miembros ser\u00e1n designados por el Ministro de Salud. Adem\u00e1s har\u00e1n parte del Comit\u00e9 un delegado de la Defensor\u00eda del Pueblo, el Director del Fondo de Inversi\u00f3n Social, FIS, el jefe de la Unidad de Inversi\u00f3n Social del Departamento Nacional de Planeaci\u00f3n, y un Secretario T\u00e9cnico quien ser\u00e1 designado por el Comit\u00e9 quien estar\u00e1 vinculado a la planta de personal del Ministerio de Salud. <\/font> <\/TD><\/TR>      <TR>    <TD> <font size=\"2\" face=\"Verdana\">Este Comit\u00e9 deber\u00e1 iniciar su operaci\u00f3n a m\u00e1s tardar dentro de los seis meses siguientes a la vigencia de la presente Ley, de acuerdo con la reglamentaci\u00f3n que para el efecto expida el Gobierno Nacional dentro del mismo t\u00e9rmino.. <\/font> <\/TD><\/TR>   <\/TABLE><\/DIV><DIV>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/DIV>   <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel002><font size=\"2\" face=\"Verdana\">T\u00cdTULO II. <\/font> <\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><i><b><font size=\"2\" face=\"Verdana\">DE LA PREVENCI\u00d3N, LA EDUCACI\u00d3N Y LA REHABILITACI\u00d3N <\/font> <\/b> <\/i> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel003><font size=\"2\" face=\"Verdana\">CAP\u00cdTULO I. <\/font> <\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><i><b><font size=\"2\" face=\"Verdana\">DE LA PREVENCI\u00d3N <\/font> <\/b><\/i> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=7><b><font size=\"2\">Art\u00edculo<\/font><\/b><font size=\"2\"><b> 7\u00b0<\/b>.<\/font><\/A><font size=\"2\"> El Gobierno junto con el Comit\u00e9 Consultivo velar\u00e1 por que se tomen las medidas preventivas necesarias para disminuir y en lo posible eliminar las distintas circunstancias causantes de limitaci\u00f3n, evitando de este modo consecuencias f\u00edsicas y psicosociales posteriores que pueden llevar hasta la propia minusval\u00eda, tales como: el control pre y post natal, el mejoramiento de las pr\u00e1cticas nutricionales, el mejoramiento de las acciones educativas en salud, el mejoramiento de los servicios sanitarios, la debida educaci\u00f3n en materia de higiene y de seguridad en el hogar, en el trabajo y en el medio ambiente, el control de accidentes, entre otras. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Para tal efecto, las Entidades Promotoras de Salud incluir\u00e1n en su plan obligatorio de Salud las acciones encaminadas a la detecci\u00f3n temprana y la intervenci\u00f3n oportuna de la limitaci\u00f3n, y las Administradoras de Riesgos Profesionales deber\u00e1n incluir en sus programas de Salud Ocupacional las directrices que sobre seguridad laboral dicte el Comit\u00e9 Consultivo; las autoridades Departamentales o Municipales correspondientes deber\u00e1n adoptar las medidas de tr\u00e1nsito que les recomiende el Comit\u00e9 Consultivo. <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Lo previsto en este art\u00edculo incluye las medidas de apoyo, diagn\u00f3stico de deficiencia, discapacidad y minusval\u00eda y las acciones terap\u00e9uticas correspondientes realizadas por profesionales especializados en el campo m\u00e9dico, de la enfermer\u00eda y terap\u00e9utico. <\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=8><b><font size=\"2\">Art\u00edculo 8\u00b0.<\/font><\/b><\/A><font size=\"2\"> El Gobierno a trav\u00e9s del Ministerio de Educaci\u00f3n Nacional tomar\u00e1 las medidas necesarias para que tanto en el proceso educativo como en el de culturizaci\u00f3n en general, se asegure dentro de la formaci\u00f3n integral de la persona la prevenci\u00f3n de aquellas condiciones generalmente causantes de limitaci\u00f3n. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">1. Para estos efectos las entidades p\u00fablicas y privadas que tengan por objeto la formaci\u00f3n y capacitaci\u00f3n de profesionales de la educaci\u00f3n, la salud, trabajadores sociales, psic\u00f3logos, arquitectos, ingenieros, o cualquier otra profesi\u00f3n que pueda tener injerencia en el tema, deber\u00e1n incluir en sus curr\u00edculos tem\u00e1ticas referentes a la atenci\u00f3n y prevenci\u00f3n de las enfermedades y dem\u00e1s causas de limitaci\u00f3n y minusval\u00edas.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><b><font face=\"Verdana\" size=\"2\">*Nota Jurisprudencial*<\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\"><b><font face=\"Verdana\" size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">E<\/font><font face=\"Arial\"><font face=\"Verdana\" size=\"2\">xpresi\u00f3n subrayada &quot;minusval\u00edas&quot; declarada CONDICIONALMENTE exequible, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/font><\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=9><b><font size=\"2\">Art\u00edculo<\/font><\/b><font size=\"2\"><b> 9\u00b0<\/b>.<\/font><\/A><font size=\"2\"> A partir de la vigencia de la presente Ley el Gobierno Nacional a trav\u00e9s de los Ministerios de Salud, Trabajo y Educaci\u00f3n, deber\u00e1 incluir en sus planes y programas el desarrollo de un Plan Nacional de Prevenci\u00f3n con miras a la disminuci\u00f3n y en lo posible la eliminaci\u00f3n de las condiciones causantes de <i>limitaci\u00f3n<\/i> y a la atenci\u00f3n de sus consecuencias. Para estos efectos deber\u00e1n tomarse las medidas pertinentes en los sectores laboral, salud y de seguridad social.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada y en cursiva &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n &quot;discapacidad&quot; por la misma<b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia<\/a><\/b>.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV>   <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel004><font size=\"2\" face=\"Verdana\">CAP\u00cdTULO II. <\/font> <\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><i><b><font size=\"2\" face=\"Verdana\">DE LA EDUCACI\u00d3N <\/font> <\/b><\/i> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=10><b><font size=\"2\">Art\u00edculo 10.<\/font><\/b><\/A><font size=\"2\"> El Estado Colombiano en sus instituciones de Educaci\u00f3n P\u00fablica garantizar\u00e1 el acceso a la educaci\u00f3n y la capacitaci\u00f3n en los niveles primario, secundario, profesional y t\u00e9cnico para las personas con limitaci\u00f3n, quienes para ello dispondr\u00e1n de una formaci\u00f3n integral dentro del ambiente m\u00e1s apropiado a sus necesidades especiales. <\/font> <\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=11><b><font size=\"2\">Art\u00edculo 11.<\/font><\/b><\/A><font size=\"2\"> En concordancia con lo establecido en la <b><a hrefx=\"..\/..\/..\/REGIMENES\/REG_EDUCACION\/REG_EDUCACION.htm\">Ley 115 de 1994<\/a><\/b>, nadie podr\u00e1 ser discriminado por raz\u00f3n de su <i>limitaci\u00f3n<\/i>, para acceder al servicio de educaci\u00f3n ya sea en una entidad p\u00fablica o privada y para cualquier nivel de formaci\u00f3n. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Para estos efectos y de acuerdo con lo previsto en el art\u00edculo siguiente, el Gobierno Nacional promover\u00e1 la integraci\u00f3n de la poblaci\u00f3n con limitaci\u00f3n a las aulas regulares en establecimientos educativos que se organicen directamente o por convenio con entidades gubernamentales y no gubernamentales, para lo cual se adoptar\u00e1n las acciones pedag\u00f3gicas necesarias para integrar acad\u00e9mica y socialmente a los <i>limitados<\/i>, en el marco de un Proyecto Educativo Institucional. <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Las entidades territoriales y el Gobierno Nacional, a trav\u00e9s del Sistema Nacional de Cofinanciaci\u00f3n, apoyar\u00e1n estas instituciones en el desarrollo de los programas establecidos en este cap\u00edtulo y las dotar\u00e1 de los materiales educativos que respondan a las necesidades espec\u00edficas seg\u00fan el tipo de limitaci\u00f3n que presenten los alumnos.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\" height=\"83\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;poblaci\u00f3n con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. Y las expresiones subrayadas y en cursiva &quot;limitaci\u00f3n&quot; y &quot;limitados&quot; declaradas CONDICIONALMENTE exequibles, en el entendido que debe reemplazarse por la expresi\u00f3n &quot;discapacidad&quot; por la misma<b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia<\/a><\/b>.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=12><b><font size=\"2\">Art\u00edculo 12.<\/font><\/b><\/A><font size=\"2\"> Para efectos de lo previsto en este cap\u00edtulo, el Gobierno Nacional deber\u00e1 establecer la metodolog\u00eda para el dise\u00f1o y ejecuci\u00f3n de programas educativos especiales de car\u00e1cter individual seg\u00fan el tipo de <i>limitaci\u00f3n<\/i>, que garanticen el ambiente menos restrictivo para la formaci\u00f3n integral de las personas con limitaci\u00f3n. <\/font> <\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. Y la expresi\u00f3n subrayada y en cursiva &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n &quot;discapacidad&quot; por la misma <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia<\/a><\/b>.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=13><b><font size=\"2\">Art\u00edculo 13.<\/font><\/b><\/A><font size=\"2\"> El Ministerio de Educaci\u00f3n Nacional establecer\u00e1 el dise\u00f1o, producci\u00f3n y difusi\u00f3n de materiales educativos especializados, as\u00ed como de estrategias de capacitaci\u00f3n y actualizaci\u00f3n para docentes en servicio. As\u00ed mismo deber\u00e1 impulsar la realizaci\u00f3n de convenios entre las administraciones territoriales, las universidades y organizaciones no gubernamentales que ofrezcan programas de educaci\u00f3n especial, psicolog\u00eda, trabajo social, terapia ocupacional, fisioterapia, terapia del lenguaje y fonoaudiolog\u00eda entre otras, para que apoyen los procesos terap\u00e9uticos y educativos dirigidos a esta poblaci\u00f3n. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Tanto las Organizaciones No Gubernamentales como las dem\u00e1s instituciones de cualquier naturaleza que presten servicios de capacitaci\u00f3n a los limitados, deber\u00e1n incluir la rehabilitaci\u00f3n como elemento preponderante de sus programas. <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Par\u00e1grafo. Todo centro educativo de cualquier nivel deber\u00e1 contar con los medios y recursos que garanticen la atenci\u00f3n educativa apropiada a las personas con limitaciones. Ning\u00fan centro educativo podr\u00e1 negar los servicios educativos a personas limitadas f\u00edsicamente, so pena de hacerse acreedor de sanciones que impondr\u00e1 el Ministerio de Educaci\u00f3n Nacional o la Secretar\u00eda de Educaci\u00f3n en las que delegue esta facultad, que pueden ir desde multas sucesivas de car\u00e1cter pecuniario de 50 a 100 salarios m\u00ednimos legales mensuales hasta el cierre del establecimiento. Dichos dineros ingresar\u00e1n a la Tesorer\u00eda Nacional, Departamental o Municipal seg\u00fan el caso. <\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaciones&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=14><b><font size=\"2\">Art\u00edculo 14.<\/font><\/b><\/A><font size=\"2\"> El Ministerio de Educaci\u00f3n Nacional y el Icfes, establecer\u00e1n los procedimientos y mecanismos especiales que faciliten a las personas con limitaciones f\u00edsicas y sensoriales la presentaci\u00f3n de ex\u00e1menes de estado y conjuntamente con el Icetex, facilitar\u00e1 el acceso a cr\u00e9ditos educativos y becas a quienes llenen los requisitos previstos por el Estado para tal efecto. As\u00ed mismo, Coldeportes promover\u00e1 y dar\u00e1 apoyo financiero con un porcentaje no inferior al 10% de sus presupuestos regionales, a las entidades territoriales para el desarrollo de programas de recreaci\u00f3n y deporte dirigidos a la poblaci\u00f3n limitada f\u00edsica, sensorial y s\u00edquicamente. Estos programas deber\u00e1n ser incluidos en el plan nacional del deporte, recreaci\u00f3n y educaci\u00f3n f\u00edsica.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresiones subrayadas &quot;personas con limitaciones f\u00edsicas&quot; y &quot;poblaci\u00f3n limitada&quot; declaradas CONDICIONALMENTE exequibles, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. <\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=15><b><font size=\"2\">Art\u00edculo 15.<\/font><\/b><\/A><font size=\"2\"> El Gobierno a trav\u00e9s de las instituciones que promueven la cultura suministrar\u00e1 los recursos humanos, t\u00e9cnicos y econ\u00f3micos que faciliten el desarrollo art\u00edstico y cultural de la persona con limitaci\u00f3n. As\u00ed mismo las bibliotecas p\u00fablicas y privadas tendr\u00e1n servicios especiales que garanticen el acceso para las personas con limitaci\u00f3n.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaciones&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Dichas instituciones tomar\u00e1n para el efecto, las medidas pertinentes en materia de barreras arquitect\u00f3nicas dentro del a\u00f1o siguiente a la vigencia de la presente Ley, so pena de sanciones que impondr\u00e1 el Ministerio de Educaci\u00f3n Nacional o las Secretar\u00edas de Educaci\u00f3n en quienes delegue, que pueden ir desde multas de 50 a 100 salarios m\u00ednimos legales mensuales hasta el cierre del establecimiento. Dichos dineros ingresar\u00e1n a la Tesorer\u00eda Nacional, Departamental o Municipal seg\u00fan el caso.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=16><b><font size=\"2\">Art\u00edculo 16.<\/font><\/b><\/A><font size=\"2\"> Lo dispuesto en este cap\u00edtulo ser\u00e1 igualmente aplicable para las personas con excepcionalidad, a quienes tambi\u00e9n se les garantiza el derecho a una formaci\u00f3n integral dentro del ambiente m\u00e1s apropiado, seg\u00fan las necesidades espec\u00edficas individuales y de acuerdo a lo establecido en los art\u00edculos precedentes. <\/font> <\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font face=\"Verdana\" size=\"2\">*Nota Jurisprudencial*<\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\"><b><font face=\"Verdana\" size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Aparte subrayado &quot;con excepcionalidad&quot; declarado exequible, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=17><b><font size=\"2\">Art\u00edculo 17.<\/font><\/b><\/A><font size=\"2\"> El Ministerio de Educaci\u00f3n Nacional ejercer\u00e1 el control permanente respecto del cumplimiento de las disposiciones contenidas en los art\u00edculos precedentes. El Gobierno deber\u00e1 reglamentar lo establecido en este cap\u00edtulo dentro de los dos meses posteriores a la fecha de vigencia de la presente Ley. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/DIV>   <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel005><font size=\"2\" face=\"Verdana\">CAP\u00cdTULO III. <\/font> <\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">DE LA REHABILITACI\u00d3N <\/font> <\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=18><b><font size=\"2\">Art\u00edculo 18.<\/font><\/b><\/A><font size=\"2\"> Toda persona con limitaci\u00f3n que no haya desarrollado al m\u00e1ximo sus capacidades, o que con posterioridad a su escolarizaci\u00f3n hubiere sufrido la <i>limitaci\u00f3n<\/i>, tendr\u00e1 derecho a seguir el proceso requerido para alcanzar sus \u00f3ptimos niveles de funcionamiento ps\u00edquico, f\u00edsico, fisiol\u00f3gico, ocupacional y social.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;persona con limitaciones&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. <\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Para estos efectos el Gobierno Nacional a trav\u00e9s de los Ministerios de Trabajo, Salud y Educaci\u00f3n Nacional, establecer\u00e1 los mecanismos necesarios para que los <i>limitados<\/i> cuenten con los programas y servicios de rehabilitaci\u00f3n integral, en t\u00e9rminos de readaptaci\u00f3n funcional, rehabilitaci\u00f3n profesional y para que en general cuenten con los instrumentos que les permitan autorrealizarse, cambiar la calidad de sus vidas y a intervenir en su ambiente inmediato y en la sociedad. <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Lo anterior sin perjuicio de las obligaciones en materia de rehabilitaci\u00f3n establecidas en el Plan Obligatorio de Salud para las Empresas Promotoras de Salud y para las Administradoras de Riesgos Profesionales cuando se trate de <i>limitaciones<\/i> surgidas por enfermedad profesional o accidentes de trabajo.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresiones subrayadas y en cursiva &quot;limitaci\u00f3n&quot; y &quot;limitados&quot; declaradas CONDICIONALMENTE exequibles, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cdiscapacidad\u201d &quot;personas en situaci\u00f3n de discapacidad&quot;<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. <\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=19><b><font size=\"2\">Art\u00edculo 19.<\/font><\/b><\/A><font size=\"2\"> Los limitados de escasos recursos ser\u00e1n beneficiarios del R\u00e9gimen Subsidiado de Seguridad Social establecido en la  <\/font> <\/font><font  FACE=\"Verdana\" size=\"2\"><b><a hrefx=\"..\/..\/..\/REGIMENES\/REG_SEGURIDAD_SOCIAL\/REG_SEGURIDAD_SOCIAL.htm\">Ley 100 de 1993<\/a><\/b>. <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Para los efectos de este art\u00edculo y con el fin de ampliar la oferta de servicios a la poblaci\u00f3n con limitaci\u00f3n beneficiaria de dicho r\u00e9gimen, el Consejo Nacional de Seguridad, Social en Salud establecido en la <b><a hrefx=\"..\/..\/..\/REGIMENES\/REG_SEGURIDAD_SOCIAL\/REG_SEGURIDAD_SOCIAL.htm\">Ley 100 de 1993<\/a><\/b>, deber\u00e1 incluir en el Plan Obligatorio de Salud. Subsidiado, los servicios de tratamiento y rehabilitaci\u00f3n de la poblaci\u00f3n con limitaci\u00f3n, lo cual deber\u00e1 ser plasmado en un decreto expedido por el Ministerio de Salud.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;poblaci\u00f3n con limitaciones&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Par\u00e1grafo. El Ministerio de Salud y el Consejo Nacional de Seguridad Social en Salud determinar\u00e1n los beneficios a los que tendr\u00e1n acceso los limitados de escasos recursos no afiliados al R\u00e9gimen de Seguridad Social en Salud establecido en la <b><a hrefx=\"..\/..\/..\/REGIMENES\/REG_SEGURIDAD_SOCIAL\/REG_SEGURIDAD_SOCIAL.htm\">Ley 100 de 1993<\/a><\/b>, hasta el a\u00f1o 2001, fecha en que la cobertura ser\u00e1 universal. <\/font><\/p>\n<p><DIV>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=20><b><font size=\"2\">Art\u00edculo 20.<\/font><\/b><\/A><font size=\"2\"> Los Municipios podr\u00e1n destinar recursos de su participaci\u00f3n en los ingresos corrientes de la Naci\u00f3n a subsidiar la adquisici\u00f3n de pr\u00f3tesis, aparatos ortop\u00e9dicos u otros elementos necesarios para la poblaci\u00f3n con limitaci\u00f3n de escasos recursos, dentro de las atenciones del Plan Obligatorio de Salud.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;poblaci\u00f3n con limitaciones&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=21><b><font size=\"2\">Art\u00edculo 21.<\/font><\/b><\/A><font size=\"2\"> Con el fin de mejorar la oferta de servicios integrales de rehabilitaci\u00f3n a los <i>limitados<\/i>, la Consejer\u00eda Presidencial promover\u00e1 iniciativas para poner en marcha proyectos en cabeza de las entidades territoriales, las organizaciones no gubernamentales y la cooperaci\u00f3n t\u00e9cnica internacional, de manera que toda persona <i>limitada<\/i>, durante su proceso de educaci\u00f3n, capacitaci\u00f3n, habilitaci\u00f3n o rehabilitaci\u00f3n seg\u00fan el caso, tenga derecho a que se le suministren los equipos y ayudas especiales requeridas para cumplir con \u00e9xito su proceso.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresiones subrayadas y en cursiva &quot;limitada&quot; y &quot;limitados&quot; declaradas CONDICIONALMENTE exequibles, en el entendido que debe reemplazarse por la expresi\u00f3n <i>&quot;personas en situaci\u00f3n de discapacidad&quot;<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. <\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV>   <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel006><font size=\"2\" face=\"Verdana\">CAP\u00cdTULO IV<\/font><\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">DE LA INTEGRACI\u00d3N LABORAL <\/font> <\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=22><b><font size=\"2\">Art\u00edculo<\/font><\/b><font size=\"2\"><b> 22<\/b>.<\/font><\/A><font size=\"2\"> El Gobierno dentro de la pol\u00edtica nacional de empleo adoptar\u00e1 las medidas pertinentes dirigidas a la creaci\u00f3n y fomento de las fuentes de trabajo para las personas con <i>limitaci\u00f3n<\/i>, para lo cual utilizar\u00e1 todos los mecanismos adecuados a trav\u00e9s de los Ministerios de Trabajo y Seguridad Social, Salud P\u00fablica, Educaci\u00f3n Nacional y otras entidades gubernamentales, organizaciones de personas con <i>limitaci\u00f3n<\/i> que se dediquen a la educaci\u00f3n, a la educaci\u00f3n especial, a la capacitaci\u00f3n, a la habilitaci\u00f3n y a la rehabilitaci\u00f3n.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaciones&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. Y la expresi\u00f3n subrayada y en cursiva &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n &quot;discapacidad&quot; por la misma <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia<\/a><\/b>.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Igualmente el Gobierno establecer\u00e1 programas de empleo protegido para aquellos casos en que la <i>disminuci\u00f3n padecida<\/i> no permita la inserci\u00f3n al sistema competitivo.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada y en cursiva &quot;disminuci\u00f3n padecida&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n &quot;<i>situaci\u00f3n de discapacidad<\/i>&quot;, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. <\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=23><b><font size=\"2\">Art\u00edculo 23.<\/font><\/b><\/A><font size=\"2\"> El Servicio Nacional de Aprendizaje, Sena, realizar\u00e1 acciones de promoci\u00f3n de sus cursos entre la poblaci\u00f3n con limitaci\u00f3n y permitir\u00e1 el acceso en igualdad de condiciones de dicha poblaci\u00f3n previa valoraci\u00f3n de sus potencialidades a los diferentes programas de formaci\u00f3n. As\u00ed mismo a trav\u00e9s de los servicios de informaci\u00f3n para el empleo establecer\u00e1 unas l\u00edneas de orientaci\u00f3n laboral que permita relacionar las capacidades del beneficiario y su adecuaci\u00f3n con la demanda laboral.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;poblaci\u00f3n con limitaciones&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=24><b><font size=\"2\">Art\u00edculo 24.<\/font><\/b><\/A><font size=\"2\"> Los particulares empleadores que vinculen laboralmente personas con limitaci\u00f3n tendr\u00e1n las siguientes garant\u00edas: <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">a) A que sean preferidos en igualdad de condiciones en los procesos de licitaci\u00f3n, adjudicaci\u00f3n y celebraci\u00f3n de contratos, sean estos p\u00fablicos o privados si estos tienen en sus n\u00f3minas por lo menos un m\u00ednimo del 10% de sus empleados en las condiciones de discapacidad enunciadas en la presente ley debidamente certificadas por la oficina de trabajo de la respectiva zona y contratados por lo menos con anterioridad a un a\u00f1o; igualmente deber\u00e1n mantenerse por un lapso igual al de la contrataci\u00f3n; <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">b) Prelaci\u00f3n en el otorgamiento de cr\u00e9ditos subvenciones de organismos estatales, siempre y cuando estos se orienten al desarrollo de planes y programas que impliquen la participaci\u00f3n activa y permanente de personas con limitaci\u00f3n; <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">c) El Gobierno fijar\u00e1 las tasas arancelarias a la importaci\u00f3n de maquinaria y equipo especialmente adoptados o destinados al manejo de personas con limitaci\u00f3n. El Gobierno clasificar\u00e1 y definir\u00e1 el tipo de equipos que se consideran cubiertos por el beneficiario. <\/font> <\/p>\n<p><DIV>&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=25><b><font size=\"2\">Art\u00edculo 25.<\/font><\/b><\/A><font size=\"2\"> El Gobierno a trav\u00e9s del Comit\u00e9 Consultivo a que se refiere el art\u00edculo 6\u00b0 podr\u00e1 solicitar estad\u00edsticas detalladas y actualizadas sobre los beneficios y resultados de los programas para las personas con limitaci\u00f3n.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p><DIV><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><font SIZE=\"2\"><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\" ><b><a name=\"26\">Art\u00edculo 26.<\/a> No discriminaci\u00f3n a persona en situaci\u00f3n de discapacidad. <\/b><\/font><b><i><font face=\"Verdana\">*Modificado<\/font><font face=\"Verdana\"> por <\/font>  <font face=\"Verdana\">e<\/font><font face=\"Verdana\">l <\/font> <\/i><\/b><font face=\"Verdana\" size=\"2\"><i><b><a hrefx=\"..\/..\/..\/ESTATUTOS\/EST%20ANTITRAMITRES\/0019.htm\">Decreto 019 de 2012<\/a><\/b><\/i><\/font><b><i><font face=\"Verdana\">,<\/font><font face=\"Verdana\"> nuevo texto:<\/font><font face=\"Verdana\">* <\/font> <\/i><\/b><font face=\"Verdana\" >En ning\u00fan caso la <i>limitaci\u00f3n<\/i> de una persona, podr\u00e1 ser motivo para obstaculizar una vinculaci\u00f3n laboral, a menos que dicha <i>limitaci\u00f3n<\/i> sea claramente demostrada como incompatible e insuperable en el cargo que se va a desempe\u00f1ar. As\u00ed mismo, ninguna persona <i>limitada<\/i> podr\u00e1 ser despedida o su contrato terminado por raz\u00f3n de su <i>limitaci\u00f3n<\/i>, salvo que medie autorizaci\u00f3n del Ministerio del Trabajo.<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\" >Sin perjuicio de lo establecido en el inciso anterior, no se requerir\u00e1 de autorizaci\u00f3n por parte del Ministerio del Trabajo cuando el trabajador <i>limitado<\/i> incurra en alguna de las causales establecidas en la ley como justas causas para dar por terminado el contrato, Siempre se garantizar\u00e1 el derecho al debido proceso. <\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\" >No obstante, quienes fueren despedidos o su contrato terminado por raz\u00f3n de su <i>limitaci\u00f3n<\/i>, sin el cumplimiento del requisito previsto en el inciso primero del presente art\u00edculo, tendr\u00e1n derecho a una indemnizaci\u00f3n equivalente a ciento ochenta (180) d\u00edas del salario, sin perjuicio de las dem\u00e1s prestaciones e indemnizaciones a que hubiere lugar de acuerdo con el <\/font><font FACE=\"Verdana\" SIZE=\"2\" ><b><a hrefx=\"..\/..\/..\/CODIGOS\/COD_SUSTANTIVO_TRABAJO\/COD_SUSTANTIVO_TRABAJO.htm\">C\u00f3digo Sustantivo del Trabajo<\/a><\/b><\/font><font face=\"Verdana\" > y dem\u00e1s normas que lo modifiquen, adicionen, complementen o aclaren.<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: justify; margin-top:0; margin-bottom:0\"><b><font face=\"Verdana\" size=\"2\">*Nota de Vigencia*<\/font><\/b><\/p>\n<p style=\"TEXT-ALIGN: justify; margin-top:0; margin-bottom:0\">&nbsp;<\/p>\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\" dir=\"ltr\" id=\"table14\">\n<tr>\n<td align=\"justify\"><font size=\"2\" face=\"Verdana\">Art\u00edculo modificado por el art\u00edculo <b><a hrefx=\"..\/..\/..\/ESTATUTOS\/EST%20ANTITRAMITRES\/0019.htm#137\">137<\/a><\/b> del&nbsp;<b><a hrefx=\"..\/..\/..\/ESTATUTOS\/EST%20ANTITRAMITRES\/0019.htm\">Decreto 019 de 2012<\/a><\/b>, publicado en el Diario Oficial No. 48308 de Enero 10 de 2012.<\/font><\/td>\n<\/tr>\n<\/table>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\" size=\"2\"><b>*Notas Jurisprudenciales*<\/b><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>      <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><b><font size=\"2\" face=\"Verdana\">Corte Constitucional<\/font><\/b><\/TD><\/TR>    <TR>    <TD align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresiones subrayadas &quot;limitaci\u00f3n&quot;, &quot;limitada&quot; y &quot;limitado&quot; declaradas CONDICIONALMENTE exequibles, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cdiscapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. <\/font><\/TD><\/TR>    <TR>    <TD align=\"justify\"><font size=\"2\" face=\"Verdana\">La Corte Constitucional declar\u00f3 estarse a lo resuelto en la Sentencia C-744-12, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2012\/C-848-12.html\">Sentencia C-848-12<\/a><\/b> de 24 de octubre de 2012, Magistrado Ponente Dr. Mauricio Gonz\u00e1lez Cuervo.<\/font><\/TD><\/TR>    <TR>    <TD align=\"justify\"><font size=\"2\" face=\"Verdana\">La Corte Constitucional declar\u00f3 estarse a lo resuelto en la Sentencia C-744-12, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2012\/C-847-12.html\">Sentencia C-847-12<\/a><\/b> de 24 de octubre de 2012, Magistrado Ponente Dr. Mauricio Gonz\u00e1lez Cuervo.<\/font><\/TD><\/TR>    <TR>    <TD align=\"justify\"><font size=\"2\" face=\"Verdana\">La Corte Constitucional declar\u00f3 estarse a lo resuelto en la Sentencia C-744-12, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2012\/C-783-12.html\">Sentencia C-783-12<\/a><\/b> de 10 de octubre de 2012, Magistrado Ponente Dr. Jorge Iv\u00e1n Palacio Palacio.<\/font><\/TD><\/TR>    <TR>    <TD align=\"justify\"><font size=\"2\" face=\"Verdana\">Art\u00edculo 137 del Decreto 19 de 2012 declarado INEXEQUIBLE por la Corte Constitucional mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2012\/C-744-12.html\">Sentencia C-744-12<\/a><\/b> de 26 de septiembre de 2012, Magistrado Ponente Dr. Nilson Pinilla Pinilla.<\/font><\/TD><\/TR>    <TR>    <TD align=\"justify\"><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Aparte subrayado declarado EXEQUIBLE por la Corte Constitucional mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2000\/C-531-00.rtf\">Sentencia C-531-00<\/a><\/b> de 5 de mayo de 2000, Magistrado Ponente Dr. \u00c1lvaro Tafur Galvis.<\/font><\/TD><\/TR>    <TR>    <TD align=\"justify\"><\/p>\n<p align=\"justify\"><font size=\"2\" face=\"Verdana\">Inciso segundo declarado CONDICIONALMENTE EXEQUIBLE por la Corte Constitucional mediante <\/font><font size=\"2\" face=\"Verdana\"><b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2000\/C-531-00.rtf\">Sentencia C-531-00<\/a><\/b> de 5 de mayo de 2000, Magistrado Ponente Dr. \u00c1lvaro Tafur Galvis, &quot;bajo el supuesto de que en los t\u00e9rminos de esta providencia y debido a los principios de respeto a la dignidad humana, solidaridad e igualdad (C.P., arts. 2o. y 13), as\u00ed como de especial protecci\u00f3n constitucional en favor de los disminuidos f\u00edsicos, sensoriales y s\u00edquicos (C.P., arts. 47 y 54), carece de todo efecto jur\u00eddico el despido o la terminaci\u00f3n del contrato de una persona por raz\u00f3n de su limitaci\u00f3n sin que exista autorizaci\u00f3n previa de la oficina de Trabajo que constate la configuraci\u00f3n de la existencia de una justa causa para el despido o terminaci\u00f3n del respectivo contrato.&quot;<\/font><\/TD><\/TR><\/TABLE><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font face=\"Verdana\">*Texto original de la Ley 361 de 1997* <\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\"><font face=\"Verdana\"><b><font size=\"2\">Art\u00edculo 26.<\/font><\/b><font size=\"2\"> En ning\u00fan caso la limitaci\u00f3n de una persona, podr\u00e1 ser motivo para obstaculizar una vinculaci\u00f3n laboral, a menos que dicha limitaci\u00f3n sea claramente demostrada como incompatible e insuperable en el cargo que se va a desempe\u00f1ar. As\u00ed mismo, ninguna persona limitada podr\u00e1 ser despedida o su contrato terminado por raz\u00f3n de su limitaci\u00f3n, salvo que medie autorizaci\u00f3n de la oficina de Trabajo.<\/font><\/font><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font size=\"2\" face=\"Verdana\"><i><b>*CONDICIONALMENTE exequble*<\/b><\/i> No obstante, quienes fueren despedidos o su contrato terminado por raz\u00f3n de su limitaci\u00f3n, sin el cumplimiento del requisito previsto en el inciso anterior, tendr\u00e1n derecho a una indemnizaci\u00f3n equivalente a ciento ochenta d\u00edas del salario, sin perjuicio de las dem\u00e1s prestaciones e indemnizaciones a que hubiere lugar de acuerdo con el <b><a hrefx=\"..\/..\/..\/CODIGOS\/COD_SUSTANTIVO_TRABAJO\/COD_SUSTANTIVO_TRABAJO.htm\">C\u00f3digo Sustantivo del Trabajo<\/a><\/b> y dem\u00e1s normas que lo modifiquen, adicionen, complementen o aclaren.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p><\/font><\/DIV>  &nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=27><b><font size=\"2\">Art\u00edculo 27.<\/font><\/b><\/A><font size=\"2\"> En los concursos que se organicen para el ingreso al servicio p\u00fablico, ser\u00e1n admitidas en igualdad de condiciones la personas con limitaci\u00f3n, y si se llegare a presentar un empate, se preferir\u00e1 entre los elegibles a la persona con limitaci\u00f3n, siempre y cuando el tipo o clase de <i>limitaci\u00f3n<\/i> no resulten extremo incompatible o insuperable frente al trabajo ofrecido, luego de haberse agotado todos los medios posibles de capacitaci\u00f3n.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. Y la expresi\u00f3n subrayada y en cursiva &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n &quot;discapacidad&quot; por la misma <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia<\/a><\/b>.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=28><b><font size=\"2\">Art\u00edculo 28.<\/font><\/b><\/A><font size=\"2\"> Las Entidades P\u00fablicas podr\u00e1n establecer convenios de formaci\u00f3n y capacitaci\u00f3n profesional con el Servicio Nacional de Aprendizaje, Sena, con las universidades, centros educativos, organizaciones no gubernamentales o con instituciones especializadas para preparar a las personas con limitaci\u00f3n, seg\u00fan los requisitos y aptitudes exigidas para el cargo y seg\u00fan el grado de especializaci\u00f3n del mismo.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=29><b><font size=\"2\">Art\u00edculo 29.<\/font><\/b><\/A><font size=\"2\"> Las personas con limitaci\u00f3n que con base en certificaci\u00f3n m\u00e9dica autorizada, no puedan gozar de un empleo competitivo y por lo tanto no puedan producir ingresos al menos equivalentes al salario m\u00ednimo legal vigente, tendr\u00e1n derecho a ser beneficiario del R\u00e9gimen Subsidiado de Seguridad Social, establecido en la <b><a hrefx=\"..\/..\/..\/REGIMENES\/REG_SEGURIDAD_SOCIAL\/REG_SEGURIDAD_SOCIAL.htm\">Ley 100 de 1993<\/a><\/b>.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=30><b><font size=\"2\">Art\u00edculo 30.<\/font><\/b><\/A><font size=\"2\"> Las entidades estatales de todo orden, preferir\u00e1n en igualdad de condiciones, los productos, bienes y servicios que les sean ofrecidos por entidades sin \u00e1nimo de lucro constituidas por las personas con limitaci\u00f3n. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Las entidades estatales que cuenten con conmutadores telef\u00f3nicos, preferir\u00e1n en igualdad de condiciones para su operaci\u00f3n a personas con limitaciones diferentes a las auditivas debidamente capacitadas para el efecto.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaciones&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=31><b><font size=\"2\">Art\u00edculo 31.<\/font><\/b><\/A><font size=\"2\"> Los empleadores que ocupen trabajadores con <i>limitaci\u00f3n<\/i> no inferior al 25% comprobada y que est\u00e9n obligados a presentar declaraci\u00f3n de renta y complementarios, tienen derecho a deducir de la renta el 200% del valor de los salarios y prestaciones sociales pagados durante el a\u00f1o o per\u00edodo gravable a los trabajadores con <i>limitaci\u00f3n<\/i>, mientras esta subsista. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Par\u00e1grafo. La cuota de aprendices que est\u00e1 obligado a contratar el empleador se disminuir\u00e1 en un 50%, si los contratados por \u00e9l son personas con discapacidad comprobada no inferior al 25%. <\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada y en cursiva &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cdiscapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=32><b><font size=\"2\">Art\u00edculo 32.<\/font><\/b><\/A><font size=\"2\"><b> <\/b>Las personas con limitaci\u00f3n que se encuentren laborando en talleres de trabajo protegido, no podr\u00e1n ser remuneradas por debajo del 50% del salario m\u00ednimo legal vigente, excepto cuando el limitado se encuentre a\u00fan bajo terapia en cuyo caso no podr\u00e1 ser remunerado por debajo del 75% del salario m\u00ednimo legal vigente. <\/font> <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\"><b>*Nota Jurisprudencial*<\/b><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border id=\"table8\">       <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><b><font size=\"2\" face=\"Verdana\">Corte Constitucional<\/font><\/b><\/TD><\/TR>     <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Art\u00edculo declarado CONDICIONALMENTE exequible por la Corte Constitucional mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2007\/C-810-07.rtf\">Sentencia C-810-07<\/a><\/b> de 3 de octubre de 2007, Magistrado Ponente Dr. Rodrigo Escobar Gil, <i>&#39;en el entendido que dichos talleres tienen por objeto actividades formativas, de integraci\u00f3n social o de rehabilitaci\u00f3n sin \u00e1nimo de lucro para el organizador del taller, de personas con diversidad funcional severa y que la relaci\u00f3n existente entre ellas y el taller no corresponde a una relaci\u00f3n labora&#39;<\/i>.<\/font><\/TD><\/TR>   <\/TABLE>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=33><b><font size=\"2\">Art\u00edculo 33.<\/font><\/b><\/A><font size=\"2\"> El ingreso al servicio p\u00fablico o privado de una persona <i>limitada<\/i> que se encuentre pensionada, no implicar\u00e1 la p\u00e9rdida ni suspensi\u00f3n de su mesada pensional, siempre que no implique doble asignaci\u00f3n del tesoro p\u00fablico. <\/font> <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Notas Jurisprudenciales* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada y en cursiva &quot;limitada&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>&quot;personas en situaci\u00f3n de discapacidad&quot;<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. <\/font><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font size=\"2\" face=\"Verdana\">Aparte subrayado declarado EXEQUIBLE, por los cargos estudiados, por la Corte Constitucional mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2003\/C-072-03.rtf\">Sentencia C-072-03<\/a><\/b> de 4 de febrero de 2003, Magistrado Ponente Dr. Alfredo Beltr\u00e1n Sierra.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=34><b><font size=\"2\">Art\u00edculo 34.<\/font><\/b><\/A><font size=\"2\"> El Gobierno Nacional a trav\u00e9s del Ministerio de Desarrollo (Instituto de Fomento Industrial &#8211; IFI), establecer\u00e1 l\u00edneas de cr\u00e9ditos blandos para el funcionamiento y constituci\u00f3n de peque\u00f1as y medianas empresas cualquiera que sea su forma jur\u00eddica, dedicadas a la producci\u00f3n de materiales, equipos, accesorios, partes o ayudas que permitan a las personas con limitaci\u00f3n desarrollar actividades cotidianas, o que les sirva para la prevenci\u00f3n, restauraci\u00f3n o correcci\u00f3n de la correspondiente <i>limitaci\u00f3n<\/i> o que sean utilizadas para la pr\u00e1ctica deportiva o recreativa de estas personas. Para tener acceso a estas l\u00edneas de cr\u00e9dito dichas empresas deber\u00e1n ser propiedad de una o m\u00e1s personas limitadas y su planta de personal estar\u00e1 integrada en no menos del 80% por personas con limitaci\u00f3n.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresiones subrayadas &quot;personas limitas&quot; y &quot;personas con limitaciones&quot; declaradas CONDICIONALMENTE exequibles, en el entendido que debe reemplazarse por la expresi\u00f3n<i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. Y la expresi\u00f3n subrayada y en cursiva &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n &quot;discapacidad&quot; por la misma <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia<\/a><\/b>.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV>   <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel007><font size=\"2\" face=\"Verdana\">T\u00cdTULO III. <\/font> <\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">DEL BIENESTAR SOCIAL<\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=35><b><font size=\"2\">Art\u00edculo 35.<\/font><\/b><\/A><font size=\"2\"> En desarrollo de lo establecido en los art\u00edculos 12, 13, 47, 54, 68 y <b><a hrefx=\"..\/..\/..\/contitucion_politica\/contitucion_politica.htm#366\">366<\/a><\/b> de la Constituci\u00f3n Pol\u00edtica, el Estado garantizar\u00e1 que las personas con limitaci\u00f3n reciban la atenci\u00f3n social que requieran, seg\u00fan su grado de <i>limitaci\u00f3n<\/i>. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Dentro de dichos servicios se dar\u00e1 especial prioridad a las labores de informaci\u00f3n y orientaci\u00f3n familiar; as\u00ed como la instalaci\u00f3n de residencias, hogares comunitarios y la realizaci\u00f3n de actividades culturales, deportivas y recreativas. <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Par\u00e1grafo. Sin perjuicio de las labores que sobre este aspecto corresponda a otras entidades y organismos, lo previsto en este art\u00edculo en especial las actividades relativas a la orientaci\u00f3n e informaci\u00f3n de la poblaci\u00f3n limitada, estar\u00e1 a cargo de la Consejer\u00eda Presidencia\u00ad, la cual para estos efectos organizar\u00e1 una oficina especial de orientaci\u00f3n e informaci\u00f3n, abierta constantemente al p\u00fablico.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresiones subrayadas &quot;personas con limitaci\u00f3n&quot; y &quot;poblaci\u00f3n limitada&quot; declaradas CONDICIONALMENTE exequibles, en el entendido que debe reemplazarse por la expresi\u00f3n<i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. Y la expresi\u00f3n subrayada y en cursiva &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n &quot;discapacidad&quot; por la misma <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia<\/a><\/b>.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=36><b><font size=\"2\">Art\u00edculo 36.<\/font><\/b><\/A><font size=\"2\"> Los servicios de orientaci\u00f3n familiar, tendr\u00e1n como objetivo informar y capacitar a las familias, as\u00ed como entrenar\u00edas para atender la estimulaci\u00f3n de aquellos de sus miembros que adolezcan de alg\u00fan tipo de <i>limitaci\u00f3n<\/i>, con miras a lograr la normalizaci\u00f3n de su entorno familiar como uno de los elementos preponderantes de su formaci\u00f3n integral. <\/font><\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\"><b>*Nota Jurisprudencial*<\/b><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>      <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><b><font size=\"2\" face=\"Verdana\">Corte Constitucional<\/font><\/b><\/TD><\/TR>    <TR>    <TD><\/p>\n<p align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cdiscapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/TD><\/TR>    <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\" size=\"2\">Aparte subrayado declarado EXEQUIBLE, por la Corte Constitucional mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2013\/C-066-13.html\">Sentencia C-066-13<\/a><\/b> de 11 de febrero de 2013, Magistrado Ponente Dr. Luis Ernesto Vargas Silva.<\/font><\/TD><\/TR>  <\/TABLE>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=37><b><font size=\"2\">Art\u00edculo 37.<\/font><\/b><\/A><font size=\"2\"> El Gobierno a trav\u00e9s del Instituto Colombiano de Bienestar Familiar y en cooperaci\u00f3n con las organizaciones de personas con limitaci\u00f3n, apropiar\u00e1 los recursos necesarios para crear un red nacional de residencias, hogares comunitarios y escuelas de trabajo cuyo objetivo ser\u00e1 atender las necesidades de aquellas personas con limitaciones severas, carentes de familia, o que a\u00fan teni\u00e9ndola adolezcan de severos problemas de integraci\u00f3n.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n (es)&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=38><b><font size=\"2\">Art\u00edculo 38.<\/font><\/b><\/A><font size=\"2\"> Todo env\u00edo postal nacional de material especial para la atenci\u00f3n, educaci\u00f3n, capacitaci\u00f3n y rehabilitaci\u00f3n de personas con limitaci\u00f3n, gozar\u00e1n de franquicia postal. Para estos efectos se requerir\u00e1 prueba acerca de la naturaleza del material. La Administraci\u00f3n Postal Nacional &#8211; Adpostal &#8211; abrir\u00e1 un registro de organizaciones p\u00fablicas o privadas que representen o agrupen personas con limitaci\u00f3n. En todo caso se establecer\u00e1 un cupo m\u00e1ximo mensual de env\u00edos con franquicia de este tipo.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=39><b><font size=\"2\">Art\u00edculo 39.<\/font><\/b><\/A><font size=\"2\"> El Gobierno a trav\u00e9s de Coldeportes organizar\u00e1 y financiar\u00e1 el desarrollo de eventos deportivos y de recreaci\u00f3n a nivel nacional para la participaci\u00f3n de personas con limitaci\u00f3n, as\u00ed como para aquellas organizaciones, que les prestan servicios en eventos de esta naturaleza a nivel internacional.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=40><b><font size=\"2\">Art\u00edculo 40.<\/font><\/b><\/A><font size=\"2\"> Los campos y escenarios deportivos p\u00fablicos deber\u00e1n ser facilitados a los organismos oficiales o privados que se dediquen a la educaci\u00f3n, habilitaci\u00f3n y rehabilitaci\u00f3n de personas con limitaci\u00f3n, previa solicitud por escrito ante Coldeportes o las juntas administradoras del deporte. Estos organismos facilitar\u00e1n y coordinar\u00e1n el uso de dichos campos y escenarios deportivos por parte de la poblaci\u00f3n con limitaci\u00f3n.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresiones subrayadas &quot;personas con limitaci\u00f3n&quot; y &quot;poblaci\u00f3n limitada&quot; declaradas CONDICIONALMENTE exequibles, en el entendido que debe reemplazarse por la expresi\u00f3n<i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Par\u00e1grafo. Las juntas directivas de los entes deportivos departamentales y municipales que creen las asambleas y los consejos respectivamente, ser\u00e1n de 6 miembros, uno de ellos deber\u00e1 ser un representante de la actividad deportiva de los <i>limitados<\/i>. Los dem\u00e1s miembros seguir\u00e1n designados de acuerdo con lo dispuesto en la Ley 181 de 1995.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada y en cursiva &quot;limitados&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>&quot;personas en situaci\u00f3n de discapacidad&quot;<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. <\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=41><b><font size=\"2\">Art\u00edculo 41.<\/font><\/b><\/A><font size=\"2\"> Los escenarios culturales de propiedad de la Naci\u00f3n o de cualquier otra entidad p\u00fablica, deber\u00e1n ser facilitados a las entidades oficiales o privadas dedicadas a la educaci\u00f3n, rehabilitaci\u00f3n y capacitaci\u00f3n de personas con limitaci\u00f3n o sus organizaciones, previa solicitud en tal sentido ante Colcultura o las entidades regionales correspondientes.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaciones&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=42><b><font size=\"2\">Art\u00edculo 42.<\/font><\/b><\/A><font size=\"2\"> A partir de la vigencia de la presente ley, la Junta Directiva del Banco de la Rep\u00fablica deber\u00e1 tener en cuenta que todo papel moneda y moneda met\u00e1lica que se emita, deber\u00e1 diferenciarse de tal manera que pueda ser f\u00e1cilmente distinguible por toda persona, sea est\u00e1 normal o <i>limitada<\/i>.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada y en cursiva &quot;limitada&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>&quot;personas en situaci\u00f3n de discapacidad&quot;<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. <\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV>   <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel008><font size=\"2\" face=\"Verdana\">T\u00cdTULO IV<\/font><\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">DE LA ACCESIBILIDAD<\/font><\/b><\/p>\n<p><DIV><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">&nbsp; <\/font> <\/b> <\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel009><font size=\"2\" face=\"Verdana\">CAP\u00cdTULO I<\/font><\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">NOCIONES GENERALES<\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=43><b><font size=\"2\">Art\u00edculo 43.<\/font><\/b><\/A><font size=\"2\"> El presente t\u00edtulo establece las normas y criterios b\u00e1sicos para facilitar la accesibilidad a las personas con movilidad reducida, sea \u00e9sta temporal o permanente, o cuya capacidad de orientaci\u00f3n se encuentre disminuida por la edad, analfabetismo, <i>limitaci\u00f3n<\/i> o enfermedad. As\u00ed mismo se busca suprimir y evitar toda clase de barreras f\u00edsicas en el dise\u00f1o y ejecuci\u00f3n de las v\u00edas y espacios p\u00fablicos y del mobiliario urbano, as\u00ed como en la construcci\u00f3n o reestructuraci\u00f3n de edificios de propiedad p\u00fablica o privada.<\/font><\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Lo dispuesto en este t\u00edtulo se aplica as\u00ed mismo a los medios de transporte e instalaciones complementarias de los mismos y a los medios de comunicaci\u00f3n.<\/font><\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Par\u00e1grafo. Los espacios y ambientes descritos en los art\u00edculos siguientes, deber\u00e1n adecuarse, dise\u00f1arse y construirse de manera que se facilite el acceso y tr\u00e1nsito seguro de la poblaci\u00f3n en general y en especial de las personas con limitaci\u00f3n.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. Y la expresi\u00f3n subrayada y en cursiva &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n &quot;<i>discapacidad<\/i>&quot; por la misma <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia<\/a><\/b>.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=44><b><font size=\"2\">Art\u00edculo 44.<\/font><\/b><\/A><font size=\"2\"> Para los efectos de la presente ley, se entiende por accesibilidad como la condici\u00f3n que permite en cualquier espacio o ambiente interior o exterior, el f\u00e1cil y seguro desplazamiento de la poblaci\u00f3n en general, y el uso en forma confiable y segura de los servicios instalados en estos ambientes. Por barreras f\u00edsicas se entiende a todas aquellas trabas, irregularidades y obst\u00e1culos f\u00edsicos que limiten o impidan la libertad o movimiento de las personas. Y por telecomunicaciones, toda emisi\u00f3n, transmisi\u00f3n o recepci\u00f3n de se\u00f1ales, escrituras, im\u00e1genes, signos, datos o informaci\u00f3n de cualquier naturaleza, por hilo, radio u otros sistemas \u00f3pticos o electromagn\u00e9ticos. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=45><b><font size=\"2\">Art\u00edculo 45.<\/font><\/b><\/A><font size=\"2\"> Son destinatarios especiales de este t\u00edtulo, las personas que por motivo del entorno en que se encuentran, tienen necesidades esenciales y en particular los individuos con <i>limitaciones<\/i> que les haga requerir de atenci\u00f3n especial, los ancianos y las dem\u00e1s personas que necesiten de asistencia temporal.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial*<\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;limitaciones&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cdiscapacidades\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=46><b><font size=\"2\">Art\u00edculo 46.<\/font><\/b><\/A><font size=\"2\"> La accesibilidad es un elemento esencial de los servicios p\u00fablicos a cargo del Estado y por lo tanto deber\u00e1 ser tenida en cuenta por los organismos p\u00fablicos o privados en la ejecuci\u00f3n de dichos servicios. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">El Gobierno reglamentar\u00e1 la proyecci\u00f3n, coordinaci\u00f3n y ejecuci\u00f3n de las pol\u00edticas en materia de accesibilidad y velar\u00e1 porque se promueva la cobertura nacional de este servicio. <\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV>   <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel010><font size=\"2\" face=\"Verdana\">CAP\u00cdTULO II. <\/font> <\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">ELIMINACI\u00d3N DE BARRERAS ARQUITECT\u00d3NICAS<\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=47><b><font size=\"2\">Art\u00edculo<\/font><\/b><font size=\"2\"><b> 47<\/b>.<\/font><\/A><font size=\"2\"> La construcci\u00f3n, ampliaci\u00f3n y reforma de los edificios abiertos al p\u00fablico y especialmente de las instalaciones de car\u00e1cter sanitario, se efectuar\u00e1n de manera tal que ellos sean accesibles a todos los destinatarios de la presente ley. Con tal fin, el Gobierno dictar\u00e1 las normas t\u00e9cnicas pertinentes, las cuales deber\u00e1n contener las condiciones m\u00ednimas sobre barreras arquitect\u00f3nicas a las que deben ajustarse los proyectos, as\u00ed como los procedimientos de inspecci\u00f3n y de sanci\u00f3n en caso de incumplimiento de estas disposiciones. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Las instalaciones y edificios ya existentes se adaptar\u00e1n de manera progresiva, de acuerdo con las disposiciones previstas en el inciso anterior, de tal manera que deber\u00e1 adem\u00e1s contar con pasamanos al menos en uno de sus dos laterales. <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">El Gobierno establecer\u00e1 las sanciones por el incumplimiento a lo establecido en este art\u00edculo. <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Par\u00e1grafo. En todas las facultades de arquitectura, ingenier\u00eda y dise\u00f1o de la Rep\u00fablica de Colombia se crear\u00e1n talleres para los futuros profesionales de la arquitectura, los cuales ser\u00e1n evaluados y calificados con el objetivo primordial de fomentar la cultura de la eliminaci\u00f3n de las barreras y limitaciones en la construcci\u00f3n. <\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=48><b><font size=\"2\">Art\u00edculo 48.<\/font><\/b><\/A><font size=\"2\"> Las puertas principales de acceso de toda construcci\u00f3n, sea \u00e9sta p\u00fablica o privada, se deber\u00e1n abrir hacia el exterior o en ambos sentidos, deber\u00e1n as\u00ed mismo contar con manijas autom\u00e1ticas al empujar, y si son de cristal siempre llevar\u00e1n franjas anaranjadas o blanco-fluorecente a la altura indicada. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">En toda construcci\u00f3n del territorio nacional y en particular las de car\u00e1cter educativo, sean \u00e9stas p\u00fablicas o privadas, las puertas se abrir\u00e1n hacia el exterior en un \u00e1ngulo no inferior a 180 grados y deber\u00e1n contar con escape de emergencia, debidamente instalados de acuerdo con las normas t\u00e9cnicas internacionales sobre la materia. <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Par\u00e1grafo. Lo previsto en este art\u00edculo se entiende sin perjuicio del deber de tomar las previsiones relativas a la organizaci\u00f3n y amoblamiento de las v\u00edas p\u00fablicas, los parques y jardines, con el prop\u00f3sito de que puedan ser utilizados por todos los destinatarios de la presente ley. Para estos efectos, las distintas entidades estatales deber\u00e1n incluir en sus presupuestos, las partidas necesarias para la financiaci\u00f3n de las adaptaciones de los inmuebles de su propiedad. <\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=49><b><font size=\"2\">Art\u00edculo 49.<\/font><\/b><\/A><font size=\"2\"> Como m\u00ednimo un 10% de los proyectos elaborados por el Gobierno para la construcci\u00f3n de vivienda de inter\u00e9s social, se programar\u00e1n con las caracter\u00edsticas constructivas necesarias para facilitar el acceso de los destinatarios de la presente ley, as\u00ed como el desenvolvimiento normal de sus actividades motrices y su integraci\u00f3n en el n\u00facleo en que habiten. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Lo previsto en este art\u00edculo rige tambi\u00e9n para los proyectos de vivienda de cualquier otra clase que se construyan o promuevan por entidades oficiales o privadas. El Gobierno expedir\u00e1 las disposiciones reglamentarias para dar cumplimiento a lo previsto en este art\u00edculo y en especial para garantizar la instalaci\u00f3n de ascensores con capacidad para transportar al menos una persona en su silla de ruedas. <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Par\u00e1grafo. Cuando el Proyecto se refiere a conjuntos de edificios e instalaciones que constituyan un complejo arquitect\u00f3nico, \u00e9ste se proyectar\u00e1 y construir\u00e1 en condiciones que permitan, en todo caso, la accesibilidad de las personas con limitaci\u00f3n a los diferentes inmuebles e instalaciones complementarias.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=50><b><font size=\"2\">Art\u00edculo<\/font><\/b><font size=\"2\"><b> 50<\/b>.<\/font><\/A><font size=\"2\"> Sin perjuicio de lo dispuesto en los art\u00edculos anteriores y en concordancia con las normas que regulen los asuntos relativos a la elaboraci\u00f3n, proyecci\u00f3n y dise\u00f1o de proyectos b\u00e1sicos de construcci\u00f3n, el Gobierno Nacional expedir\u00e1 las disposiciones que establezcan las condiciones m\u00ednimas que deber\u00e1n tenerse en cuenta en los edificios de cualquier clase, con el fin de permitir la accesibilidad de las personas con cualquier tipo de <i>limitaci\u00f3n<\/i>. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">La autoridad competente de todo orden se abstendr\u00e1 de otorgar el permiso correspondiente para aquellos proyectos de construcci\u00f3n que no cumplan con lo dispuesto en este art\u00edculo.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial*<\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cdiscapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=51><b><font size=\"2\">Art\u00edculo 51.<\/font><\/b><\/A><font size=\"2\"> Para los efectos de este t\u00edtulo, se entiende por &quot;Rehabilitaci\u00f3n de viviendas&quot;, las reformas y reparaciones que las personas a que se refiere la presente ley, tengan que realizar en su vivienda habitual y permanente por causa de su <i>limitaci\u00f3n<\/i>. Para estos efectos, el Gobierno Nacional dictar\u00e1 las normas mediante las cuales se regulen l\u00edneas de cr\u00e9dito especiales, as\u00ed como las condiciones requeridas para la concesi\u00f3n de subsidios, para financiar las rehabilitaciones de vivienda a que se refiere el presente art\u00edculo.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial*<\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cdiscapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=52><b><font size=\"2\">Art\u00edculo 52.<\/font><\/b><\/A><font size=\"2\">&nbsp; Lo dispuesto en este t\u00edtulo y en sus disposiciones reglamentarias, ser\u00e1 tambi\u00e9n de obligatorio cumplimiento para las edificaciones e instalaciones abiertas al p\u00fablico que sean de propiedad particular, quienes dispondr\u00e1n de un t\u00e9rmino de cuatro a\u00f1os contados a partir de la vigencia de la presente ley, para realizar las adecuaciones correspondientes. El Gobierno Nacional reglamentar\u00e1 las sanciones de tipo pecuniario e institucional, para aquellos particulares que dentro de dicho t\u00e9rmino no hubieren cumplido con lo previsto en este t\u00edtulo.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=53><b><font size=\"2\">Art\u00edculo 53.<\/font><\/b><\/A><font size=\"2\"> En las edificaciones de varios niveles que no cuenten con ascensor, existir\u00e1n rampas con las especificaciones t\u00e9cnicas y de seguridad adecuadas, de acuerdo con la reglamentaci\u00f3n que para el efecto expida el Gobierno Nacional o se encuentren vigentes. <\/font> <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=54><b><font size=\"2\">Art\u00edculo 54.<\/font><\/b><\/A><font size=\"2\"> Toda construcci\u00f3n temporal o permanente que pueda ofrecer peligro para las personas con limitaci\u00f3n, deber\u00e1 estar provista de la protecci\u00f3n correspondiente y de la adecuada se\u00f1alizaci\u00f3n.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=55><b><font size=\"2\">Art\u00edculo<\/font><\/b><font size=\"2\"><b> 55<\/b>.<\/font><\/A><font size=\"2\"> En todo complejo vial y\/o medio de transporte masivo, incluidos los puentes peatonales, t\u00faneles o estaciones que se construyan en el territorio nacional, se deber\u00e1 facilitar la circulaci\u00f3n de las personas a que se refiere la presente ley, planeando e instalando rampas o elevadores con acabados de material antideslizante que permitan movilizarse de un lugar a otro y deber\u00e1n contar con la se\u00f1alizaci\u00f3n respectiva. <\/font> <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><A name=56><b><font size=\"2\">Art\u00edculo 56.<\/font><\/b><\/A><font size=\"2\"><b><i>*<\/i><\/b><\/font><i><font size=\"2\"><b>Modificado por la<a hrefx=\"..\/2009\/LEY_1316_DE_2009.htm\">Ley 1316 de 2009<\/a>, nuevo texto:* <\/b>&nbsp;<\/font><\/i><font size=\"2\">Toda persona natural o jur\u00eddica, p\u00fablica o privada, que organice un espect\u00e1culo o tenga sitios abiertos al p\u00fablico, de car\u00e1cter recreacional o cultural, como teatros y cines, deber\u00e1 reservar un espacio del cinco por ciento (5%) del aforo, para que sea ocupado exclusivamente por personas con discapacidad y un acompa\u00f1ante.<\/font><\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\"><br \/>Dicho espacio deber\u00e1 cumplir, al menos, los siguientes requisitos:<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\"><br \/>a) Estar claramente delimitado y se\u00f1alizado;<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\"><br \/>b) Garantizar la visibilidad, la audici\u00f3n y el goce del espect\u00e1culo o de la actividad de car\u00e1cter recreacional o cultural de que se trate;<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\"><br \/>c) Contar con una superficie acorde a la magnitud del espect\u00e1culo o del sitio abierto al p\u00fablico;<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\"><br \/>d) Garantizar zonas de emergencia y de servicios sanitarios, as\u00ed como facilidades de acceso y egreso, tanto desde la entrada como hacia las salidas;<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\"><br \/>e) Disponer de espacios localizados para personas en silla de ruedas, con las respectivas facilidades de acceso y egreso. En caso de sitios abiertos al p\u00fablico, como teatros y cines, dichos espacios no podr\u00e1n ser inferiores al dos por ciento (2%) de su capacidad total.<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\"><br \/>f) La boleter\u00eda tendr\u00e1 un precio especial que en ning\u00fan caso superar\u00e1 el setenta y cinco (75%) del precio de la boleta de mayor valor.<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\"><br \/>Par\u00e1grafo 1. En lo referente a los espect\u00e1culos, ser\u00e1 requisito indispensable para solicitar el permiso a la autoridad Municipal o Distrital correspondiente, la entrega de un plano que indique con toda precisi\u00f3n el espacio y la accesibilidad destinada para las&nbsp; personas con discapacidad, en los t\u00e9rminos arriba indicados. Las autoridades podr\u00e1n inspeccionar el lugar, as\u00ed como denegar o suspender dichos espect\u00e1culos, cuando se constate el incumplimiento de los requerimientos previstos en este art\u00edculo, con sujeci\u00f3n a los mandatos del debido proceso.<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\"><br \/>Par\u00e1grafo 2. Los espacios exclusivos para personas con discapacidad previstos en el presente art\u00edculo, se someter\u00e1n a las dimensiones internacionales que al respecto se establezcan y a la Norma T\u00e9cnica Colombiana NTC 4904 sobre accesibilidad de las personas al medio ambiente f\u00edsico y estacionamientos accesibles y dem\u00e1s normas que la modifiquen, adicionen o deroguen.<\/font><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\"> &nbsp;Todos los sitios abiertos al p\u00fablico, de car\u00e1cter recreacional o cultural, como teatros y cines, deber\u00e1n disponer de espacios localizados al comienzo o al final de cada fila central, para personas en silla de ruedas. Para estos efectos se utilizar\u00e1 un \u00e1rea igual a la de una silla de teatro y no se dispondr\u00e1 de m\u00e1s de dos espacios contiguos en la misma fila. <\/font> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p><DIV><\/p>\n<div align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><font size=\"2\"><b>*<\/b><\/font><b><font size=\"2\">Nota de Vigencia*<\/font><\/b><\/font><\/div>\n<div align=\"justify\">&nbsp;<\/div>\n<table cellSpacing=\"0\" cellPadding=\"6\" rules=\"none\" width=\"100%\" border=\"1\" frame=\"border\" id=\"table4\">\n<tr>\n<td>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Art\u00edculo modificado por el art\u00edculo 1\u00b0 de la <b><a hrefx=\"..\/2009\/LEY_1316_DE_2009.htm\">Ley 1316 de 2009<\/a><\/b>, publicada en el Diario Oficial No. 47409 de 13 de julio de 2009. <\/font><\/td>\n<\/tr>\n<\/table>\n<div align=\"justify\">&nbsp;<\/div>\n<div align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><font size=\"2\"><b>*Texto original de la Ley 361 de 1997<\/b><\/font><b><font size=\"2\">*<\/font><\/b><\/font><\/div>\n<div align=\"justify\">&nbsp;<\/div>\n<table cellSpacing=\"0\" cellPadding=\"6\" rules=\"none\" width=\"100%\" border=\"1\" frame=\"border\" id=\"table5\">\n<tr>\n<td>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\"><b>Art\u00edculo 56. <\/b> La determinaci\u00f3n del n\u00famero de espacios de esta clase, ser\u00e1 del dos por ciento de la capacidad total del teatro. Un porcentaje similar se aplicar\u00e1 en los vestuarios de los centros recreacionales, para las personas en silla de ruedas.<\/font><\/td>\n<\/tr>\n<tr>\n<td>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Par\u00e1grafo. En todo caso, \u00e9stas y las dem\u00e1s instalaciones abiertas al p\u00fablico, deber\u00e1n contar por lo menos con un sitio accesible para las personas en silla de ruedas. <\/font> <\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=57><b><font size=\"2\">Art\u00edculo 57.<\/font><\/b><\/A><font size=\"2\"> En un t\u00e9rmino no mayor de diez y ocho meses, contados a partir de la vigencia de la presente ley, las entidades estatales competentes, elaborar\u00e1n planes para la adaptaci\u00f3n de los espacios p\u00fablicos, edificios, servicios e instalaciones dependientes, de acuerdo con lo previsto en esta ley sus normas reglamentarias. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=58><b><font size=\"2\">Art\u00edculo 58.<\/font><\/b><\/A><font size=\"2\"> Para los efectos previstos en este cap\u00edtulo, el Gobierno Nacional compilar\u00e1 en un s\u00f3lo estatuto org\u00e1nico, todas las disposiciones relativas a la eliminaci\u00f3n de barreras arquitect\u00f3nicas y as\u00ed mismo unificar\u00e1 un r\u00e9gimen especial de sanciones por su incumplimiento. <\/font> <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV>   <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel011><font size=\"2\" face=\"Verdana\">CAP\u00cdTULO III<\/font><\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">DEL TRANSPORTE<\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=59><b><font size=\"2\">Art\u00edculo 59.<\/font><\/b><\/A><font size=\"2\"> Las empresas de car\u00e1cter p\u00fablico, privado o mixto cuyo objeto sea el transporte a\u00e9reo, terrestre, mar\u00edtimo, ferroviario o fluvial, deber\u00e1n facilitar sin costo adicional alguno para la persona con limitaci\u00f3n, el transporte de los equipos de ayuda biomec\u00e1nica, sillas de ruedas u otros implementos directamente relacionados con la <i>limitaci\u00f3n<\/i>, as\u00ed como los perros gu\u00edas que acompa\u00f1en laspersonas con limitaci\u00f3n visual. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">As\u00ed mismo se deber\u00e1n reservar las sillas de la primera fila para las personas con limitaci\u00f3n, en el evento de que en el respectivo viaje se encuentre como pasajero alguna persona limitada.<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresiones subrayadas &quot;personas con limitaci\u00f3n&quot; y &quot;persona limitada&quot; declaradas CONDICIONALMENTE exequibles, en el entendido que debe reemplazarse por la expresi\u00f3n<i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. Y la expresi\u00f3n subrayada y en cursiva &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n &quot;<i>discapacidad<\/i>&quot; por la misma <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia<\/a><\/b>.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=60><b><font size=\"2\">Art\u00edculo 60.<\/font><\/b><\/A><font size=\"2\"> <i><b>*Aparte subrayado declarado CONDICIONALMENTE EXEQUIBLE*<\/b><\/i> Los autom\u00f3viles as\u00ed como cualquier otra clase de veh\u00edculos conducidos por una persona con limitaci\u00f3n, siempre que lleven el distintivo, nombre o iniciales respectivos, tendr\u00e1n derecho a estacionar en los lugares espec\u00edficamente demarcados con el s\u00edmbolo internacional de accesibilidad. Lo mismo se aplicar\u00e1 para el caso de los veh\u00edculos pertenecientes a centros educativos especiales o de rehabilitaci\u00f3n. El Gobierno reglamentar\u00e1 la materia. <\/font> <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\"><b>*Notas Jurisprudenciales*<\/b><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border>      <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><b><font size=\"2\" face=\"Verdana\">Corte Constitucional<\/font><\/b><\/TD><\/TR>    <TR>    <TD><\/p>\n<p align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/TD><\/TR>    <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Aparte subrayado declarado EXEQUIBLE por la Corte Constitucional mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2001\/C-410-01.rtf\">Sentencia C-410-01<\/a><\/b> del&nbsp; 25 de abril de 2001, Magistrado Ponente Dr. \u00c1lvaro Tafur Galvis, <i>&quot;bajo el entendido de que la norma se refiere simplemente a los veh\u00edculos que transportan a alguna de las personas destinatarias de dicha Ley&quot;<\/i>. <\/font> <\/TD><\/TR><\/TABLE><DIV>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=61><b><font size=\"2\">Art\u00edculo 61.<\/font><\/b><\/A><font size=\"2\"> El Gobierno Nacional dictar\u00e1 las medidas necesarias para garantizar la adaptaci\u00f3n progresiva del transporte p\u00fablico, as\u00ed como los transportes escolares y laborales, cualquiera que sea la naturaleza de las personas o entidades que presten dichos servicios. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">En todo caso, el plazo para cumplir con lo dispuesto en este art\u00edculo, no podr\u00e1 ser superior a cinco a\u00f1os contados a partir de la vigencia de la presente ley. <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=62><b><font size=\"2\">Art\u00edculo 62.<\/font><\/b><\/A><font size=\"2\"> Todos los sitios abiertos al p\u00fablico como centros comerciales, nuevas urbanizaciones y unidades residenciales, deber\u00e1n disponer de acceso y en especial sitios de parqueo para las personas a que se refiere la presente ley, de acuerdo a dimensiones adoptadas internacionalmente en un n\u00famero de por lo menos el 2% del total. Deber\u00e1n as\u00ed mismo estar diferenciados por el s\u00edmbolo internacional de la accesibilidad.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\"><b>*Nota de vigencia*<\/b><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border id=\"table9\">       <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Para la interpretaci\u00f3n de este art\u00edculo debe tenerse en cuenta lo dispuesto por el art\u00edculo 3 de la <b><a hrefx=\"..\/2009\/LEY_1287_DE_2009.htm\">Ley 1287 de 2009<\/a><\/b>, publicada en el Diario Oficial No. 47280 de 3 de marzo de 2009: <i>&quot;Por la cual se adiciona la Ley 361 de 1997&quot;<\/i>. <\/font> <\/TD><\/TR>   <\/TABLE><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=63><b><font size=\"2\">Art\u00edculo 63.<\/font><\/b><\/A><font size=\"2\"> En las principales calles y avenidas de los distritos y municipios donde haya sem\u00e1foros, las autoridades correspondientes deber\u00e1n disponer lo necesario para la instalaci\u00f3n de se\u00f1ales sonoras que permitan la circulaci\u00f3n segura de las personas con <i>limitaci\u00f3n<\/i> visual.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial*<\/font><\/b><\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cdiscapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=64><b><font size=\"2\">Art\u00edculo 64.<\/font><\/b><\/A><font size=\"2\"> Las zonas de cruce peatonal deben estar se\u00f1alizadas en forma visible y adecuada. Las autoridades distritales y municipales correspondientes deber\u00e1n imponer las sanciones previstas para los conductores que violen las disposiciones que obligan a respetar las zonas de cruce peatonal. <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=65><b><font size=\"2\">Art\u00edculo 65.<\/font><\/b><\/A><font size=\"2\"> El Gobierno Nacional a trav\u00e9s del Ministerio de Transporte, en coordinaci\u00f3n con las alcald\u00edas municipales y las distritales incluido el Distrito Capital, ser\u00e1n los encargados de dictar y hacer cumplir las normas del presente cap\u00edtulo, en especial las destinadas a facilitar el transporte y el desplazamiento de todas las personas a quienes se les aplica la presente ley. Para estos efectos, el Gobierno compilar\u00e1 en un s\u00f3lo estatuto org\u00e1nico, todas las normas existentes relativas a lo regulado por este cap\u00edtulo, y as\u00ed mismo establecer\u00e1 un r\u00e9gimen especial de sanciones por su incumplimiento. <\/font> <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV>   <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel012><font size=\"2\" face=\"Verdana\">CAP\u00cdTULO IV. <\/font> <\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><i><b><font size=\"2\" face=\"Verdana\">DE LAS COMUNICACIONES <\/font> <\/b><\/i> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=66><b><font size=\"2\">Art\u00edculo<\/font><\/b><font size=\"2\"><b> 66<\/b>.<\/font><\/A><font size=\"2\"> El Gobierno Nacional a trav\u00e9s del Ministerio de Comunicaciones+, adoptar\u00e1 las medidas necesarias para garantizarle a las personas con limitaci\u00f3n el derecho a la informaci\u00f3n. <\/font> <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><b><i><font size=\"2\" face=\"Verdana\">*<\/font><\/i><font size=\"2\" face=\"Verdana\">Nota Vigencia*<\/font><\/b><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV><\/p>\n<table border=\"1\" width=\"100%\" id=\"table12\" cellspacing=\"0\" cellpadding=\"6\">\n<tr>\n<td>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">+ El nombre, objeto, y funciones del Ministerio de Comunicaciones fueron redefinidos por los art\u00edculos 16, 17 y 18 de la <b><a hrefx=\"..\/2009\/LEY_1341_DE_2009.htm\">Ley 1341 de 2009<\/a><\/b>, publicada en el Diario Oficial No. 47.426 de 30 de julio de 2009, &#39;por la cual se definen principios y conceptos sobre la sociedad de la informaci\u00f3n y la organizaci\u00f3n de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones \u2013TIC\u2013, se crea la Agencia Nacional de Espectro y se dictan otras disposiciones&#39;&nbsp;&nbsp; <\/font><\/td>\n<\/tr>\n<\/table>\n<p><\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=67><b><font size=\"2\">Art\u00edculo 67.<\/font><\/b><\/A><font size=\"2\"> De acuerdo con lo establecido en el art\u00edculo anterior, las emisiones televisivas de inter\u00e9s cultural e informativo en el territorio nacional, deber\u00e1n disponer de servicios de int\u00e9rpretes o letras que reproduzcan el mensaje para personas con <i>limitaci\u00f3n<\/i> auditiva. El Ministerio de Comunicaciones en un t\u00e9rmino de seis meses a partir de la promulgaci\u00f3n de esta ley deber\u00e1 expedir resoluci\u00f3n que especifique los criterios para establecer qu\u00e9 programas est\u00e1n obligados por lo dispuesto en este art\u00edculo.  <\/font> <\/font> <\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">La empresa Programadora que no cumpla con lo dispuesto en este art\u00edculo se har\u00e1 acreedora de multas sucesivas de 100 salarios m\u00ednimos mensuales legales vigentes hasta que cumplan con su obligaci\u00f3n. La sanci\u00f3n la impondr\u00e1 el Ministerio de Comunicaciones y los dineros ingresar\u00e1n al Tesoro Nacional. <\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\"><b>*Nota de vigencia*<\/b><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border id=\"table10\">       <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">+ El nombre, objeto, y funciones del Ministerio de Comunicaciones fueron redefinidos por los art\u00edculos 16, 17 y 18 de la <b><a hrefx=\"..\/2009\/LEY_1341_DE_2009.htm\">Ley 1341 de 2009<\/a><\/b>, publicada en el Diario Oficial No. 47.426 de 30 de julio de 2009, &#39;por la cual se definen principios y conceptos sobre la sociedad de la informaci\u00f3n y la organizaci\u00f3n de las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones \u2013TIC\u2013, se crea la Agencia Nacional de Espectro y se dictan otras disposiciones&#39;&nbsp;&nbsp; <\/font><\/TD><\/TR>     <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">Seg\u00fan lo expresa la Corte Constitucional en <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2007\/C-338-07.rtf\">Sentencia C-338-07<\/a><\/b> de 9 de mayo de 2007, Magistrado Ponente Dr. Nilson Pinilla Pinilla, las expresiones \u201cde inter\u00e9s cultural e informativo\u201d y \u201cEl Ministerio de Comunicaciones en un t\u00e9rmino de seis meses a partir de la promulgaci\u00f3n de esta ley deber\u00e1 expedir resoluci\u00f3n que especifique los criterios para establecer qu\u00e9 programas est\u00e1n obligados por lo dispuesto en este art\u00edculo\u201d fueron subrogadas t\u00e1citamente por el art\u00edculo 13 de la <b><a hrefx=\"..\/2005\/L0982005.htm\">Ley 982 de 2005<\/a><\/b>, &#39;por la cual se establecen normas tendientes a la equiparaci\u00f3n de oportunidades para las personas sordas y sordo-ciegas y se dictan otras disposiciones&#39;, publicada en el Diario Oficial No. 45.995 de 09 de agosto de 2005.<\/font><\/TD><\/TR>   <\/TABLE><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">&nbsp;<\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\"><b>*Nota Jurisprudencial*<\/b><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><TABLE cellSpacing=0 cellPadding=6 rules=none width=\"100%\"  border=1 frame=border id=\"table11\">       <TR>    <TD><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><b><font size=\"2\" face=\"Verdana\">Corte Constitucional<\/font><\/b><\/TD><\/TR>     <TR>    <TD align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cdiscapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado. <\/font><\/TD><\/TR>     <TR>    <TD align=\"justify\"><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font size=\"2\" face=\"Verdana\">La Corte Constitucional se declar\u00f3 INHIBIDA de fallar sobre este art\u00edculo por carencia actual de objeto, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2007\/C-338-07.rtf\">Sentencia C-338-07<\/a><\/b> de 9 de mayo de 2007, Magistrado Ponente Dr. Nilson Pinilla Pinilla.<\/font><\/TD><\/TR>   <\/TABLE><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=68><b><font size=\"2\">Art\u00edculo 68.<\/font><\/b><\/A><font size=\"2\"> El lenguaje utilizado por personas sordas, es un medio v\u00e1lido de manifestaci\u00f3n de la voluntad y ser\u00e1 reconocido como tal por todas las autoridades p\u00fablicas y privadas.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=69><b><font size=\"2\">Art\u00edculo 69.<\/font><\/b><\/A><font size=\"2\"> Para los efectos previstos en este cap\u00edtulo, el Gobierno Nacional compilar\u00e1 en un solo estatuto org\u00e1nico todas las normas y disposiciones que permitan a las diferentes personas con limitaci\u00f3n acceder al servicio de comunicaciones. Deber\u00e1 as\u00ed mismo incluirse en dicho estatuto, un r\u00e9gimen especial de sanciones por el incumplimiento de dichas normas.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresi\u00f3n subrayada &quot;personas con limitaci\u00f3n&quot; declarada CONDICIONALMENTE exequible, en el entendido que debe reemplazarse por la expresi\u00f3n <i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV>   <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><A name=Nivel013><font size=\"2\" face=\"Verdana\">T\u00cdTULO V. <\/font> <\/A><\/b><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><i><b><font size=\"2\" face=\"Verdana\">DISPOSICIONES VARIAS <\/font> <\/b><\/i> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=70><b><font size=\"2\">Art\u00edculo 70.<\/font><\/b><\/A><font size=\"2\"> Las distintas administraciones tanto del orden nacional como territorial incluir\u00e1n en sus planes de desarrollo econ\u00f3mico y social, programas y proyectos que permitan la financiaci\u00f3n y el desarrollo adecuados a las distintas disposiciones contenidas en la presente ley. <\/font> <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><A name=71><b><font size=\"2\">Art\u00edculo 71.<\/font><\/b><\/A><font size=\"2\"> En el t\u00e9rmino de 10 meses contados a partir de la vigencia de la presente ley, las personas jur\u00eddicas de car\u00e1cter p\u00fablico, privado o mixto deber\u00e1n adecuar sus estatutos de acuerdo con las disposiciones de la presente ley, cuando fuere el caso. Las distintas entidades de inspecci\u00f3n y vigilancia verificar\u00e1n el cumplimiento de lo dispuesto en este art\u00edculo. <\/font> <\/font> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=72><b><font size=\"2\">Art\u00edculo 72.<\/font><\/b><\/A><font size=\"2\"> El Estado garantizar\u00e1 los adecuados mecanismos de concertaci\u00f3n en el dise\u00f1o y ejecuci\u00f3n de las pol\u00edticas que tengan que ver con la poblaci\u00f3n limitada, con las organizaciones de y para personas con limitaci\u00f3n.<\/font><\/font><\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">*Nota Jurisprudencial* <\/font><\/b> <\/p>\n<p align=\"justify\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<div align=\"center\">\n<table border=\"1\" cellpadding=\"6\" cellspacing=\"0\" width=\"100%\">\n<tr>\n<td align=\"justify\">\n<p style=\"margin-top: 0; margin-bottom: 0\"><font face=\"Verdana\"><b><font size=\"2\">Corte Constitucional<\/font><\/b><\/td>\n<\/tr>\n<tr>\n<td align=\"justify\"><font face=\"Verdana\" size=\"2\">Expresiones subrayadas &quot;personas con limitaci\u00f3n&quot; y &quot;poblaci\u00f3n limitada&quot; declaradas CONDICIONALMENTE exequibles, en el entendido que debe reemplazarse por la expresi\u00f3n<i>\u201cpersona o personas en situaci\u00f3n de discapacidad\u201d<\/i>, mediante <b><a hrefx=\"..\/..\/..\/..\/JURISPRUDENCIA\/CORTE_CONSTITUCIONAL\/docs\/2015\/boletines\/30.pdf\">Sentencia C-458-15<\/a><\/b> seg\u00fan Comunicado de Prensa 30 de 22 de Julio de 2015, Magistrada Ponente Dra. Gloria Stella Ortiz Delgado.<\/font><\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\"><font face=\"Verdana\"><A name=73><b><font size=\"2\">Art\u00edculo 73.<\/font><\/b><\/A><font size=\"2\"> La presente Ley rige a partir de la fecha de su publicaci\u00f3n y deroga todas las disposiciones que le sean contrarias. <\/font> <\/font> <\/p>\n<p style=\"margin-top: 0; margin-bottom: 0\" align=\"justify\">&nbsp;<\/p>\n<p><DIV>&nbsp;<\/DIV> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">El Presidente del honorable Senado de la Rep\u00fablica<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">LU\u00cdS FERNANDO LONDO\u00d1O CAPURRO <\/font> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">El Secretario General del honorable Senado de la Rep\u00fablica<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">PEDRO PUMAREJO VEGA <\/font> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">El Presidente de la honorable C\u00e1mara de Representantes<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">GIOVANNI LAMBOGLIA MAZZILLI <\/font> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">El Secretario General de la honorable C\u00e1mara de Representantes<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">DIEGO VIVAS TAFUR <\/font> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><b><font size=\"2\" face=\"Verdana\">REP\u00daBLICA DE COLOMBIA &#8211; GOBIERNO NACIONAL <\/font> <\/b> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">Publ\u00edquese y ejec\u00fatese<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">Dada en Santa F\u00e9 de Bogot\u00e1, D. C., a 7 de febrero de 1997<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">ERNESTO SAMPER PIZANO <\/font> <\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">El Ministro de Educaci\u00f3n Nacional<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">JAIME NI\u00d1O DIEZ<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">El Ministro de Trabajo y Seguridad Social<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">ORLANDO OBREG\u00d3N SABOGAL<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">La Ministra de Salud<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">MAR\u00cdA TERESA FORERO DE SAADE<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\">&nbsp;<\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">el Ministro de Transporte<\/font><\/p>\n<p align=\"center\" style=\"margin-top: 0; margin-bottom: 0\"><font size=\"2\" face=\"Verdana\">CARLOS HERN\u00c1N L\u00d3PEZ GUTI\u00c9RREZ<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; LEY 361 DE 1997 &nbsp; (febrero 7 DE 1997) &nbsp; Por la cual se establecen mecanismos de integraci\u00f3n social de las personas con limitaci\u00f3n y se dictan otras disposiciones. *Notas de Vigencia* &nbsp; Modificado por elDecreto 019 de 2012, publicado en el Diario Oficial No. 480308 de Enero 10 de 2012. &quot;Por el cual [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-478","post","type-post","status-publish","format-standard","hentry","category-leyes-1997"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/comments?post=478"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/478\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/media?parent=478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/categories?post=478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/tags?post=478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}