{"id":5491,"date":"2025-07-31T09:17:16","date_gmt":"2025-07-31T14:17:16","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/?p=5491"},"modified":"2025-07-31T09:17:22","modified_gmt":"2025-07-31T14:17:22","slug":"ley-2494-de-2025","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/2025\/07\/31\/ley-2494-de-2025\/","title":{"rendered":"LEY 2494 DE 2025"},"content":{"rendered":"\n<p>LEY 2494 DE 2025<\/p>\n\n\n\n<p>(julio 23)<\/p>\n\n\n\n<p>D.O. 53.191, julio 24 de 2025<\/p>\n\n\n\n<p>por medio de la cual se establecen medidas sobre la elaboraci\u00f3n, publicaci\u00f3n y divulgaci\u00f3n de encuestas y se dictan otras disposiciones.<\/p>\n\n\n\n<p>El Congreso de Colombia,<\/p>\n\n\n\n<p>DECRETA:<\/p>\n\n\n\n<p>Art\u00edculo 1\u00b0. Objeto. La presente ley tiene por objeto regular la realizaci\u00f3n y divulgaci\u00f3n de encuestas para cargos de elecci\u00f3n popular y de opini\u00f3n pol\u00edtica, con el fin de garantizar la igualdad al acceso de la informaci\u00f3n y la transparencia de los datos en aras de aumentar la confiabilidad y robustecer t\u00e9cnicamente la aplicaci\u00f3n de dichas t\u00e9cnicas de investigaci\u00f3n en el territorio nacional.<\/p>\n\n\n\n<p>Art\u00edculo 2\u00b0. Alcance. Las disposiciones contenidas en la presente ley son aplicables a todo estudio cuantitativo que se publique y a las personas jur\u00eddicas que los realicen y divulguen, cuyo objetivo sea dar a conocer preferencias, opini\u00f3n o tendencias pol\u00edticas y electorales. Incluyendo la intenci\u00f3n de voto y la imagen de los candidatos para procesos de decisi\u00f3n o elecci\u00f3n mediante voto popular.<\/p>\n\n\n\n<p>Sin importar el nombre, denominaci\u00f3n o metodolog\u00eda que se le d\u00e9 al estudio cuantitativo para ser publicado y divulgado deber\u00e1 cumplir todas las exigencias de la presente ley para las encuestas que se incluyan en dicho estudio.<\/p>\n\n\n\n<p>Al publicar los resultados de un sondeo en prensa, radio, televisi\u00f3n o plataformas digitales -incluidas las redes sociales- se debe informar que \u00e9ste no se considera representativo del grupo poblacional en donde se adelant\u00f3 la medici\u00f3n, de conformidad con las definiciones del art\u00edculo 3\u00b0 de la presente ley.<\/p>\n\n\n\n<p>Art\u00edculo 3\u00b0. Definiciones. Para la aplicaci\u00f3n de la presente ley, se deben considerar las siguientes definiciones:<\/p>\n\n\n\n<p>Encuesta o encuesta por muestreo probabil\u00edstico: Producto t\u00e9cnico de base cient\u00edfica que consiste en aplicar un conjunto de t\u00e9cnicas y procedimientos mediante los cuales, sobre la base de un cuestionario espec\u00edfico, se obtienen datos e informaci\u00f3n respecto de las opiniones, deseos, actitudes o comportamientos de un grupo representativo de consultados y cuyos resultados pueden ser generalizados a universos definidos y conocidos de la poblaci\u00f3n. Esta herramienta tiene por objeto obtener informaci\u00f3n estad\u00edstica, del proceso electoral o de opini\u00f3n p\u00fablica que permite una medici\u00f3n objetiva de los procesos pol\u00edticos.<\/p>\n\n\n\n<p>Para efectos de la presente ley, enti\u00e9ndase por encuesta, toda encuesta probabil\u00edstica.<\/p>\n\n\n\n<p>Sondeo: Procedimiento que permite conocer las opiniones y actitudes de un grupo espec\u00edfico por medio de un cuestionario que se aplica a un grupo de sus integrantes. Este procedimiento expedito de medici\u00f3n est\u00e1 dirigido a muestras no probabil\u00edsticas de la poblaci\u00f3n que no se juzgan como representativas del conjunto al que pertenecen. Los resultados de este tipo de estudio no son generalizables para la poblaci\u00f3n, su prop\u00f3sito es conocer la percepci\u00f3n sobre temas de inter\u00e9s pol\u00edtico instituciones o funcionarios. No podr\u00e1n publicarse ni divulgarse sondeos sobre intenci\u00f3n de voto electoral.<\/p>\n\n\n\n<p>Firmas encuestadoras: Para todos los efectos de la presente ley, se entender\u00e1n como firmas encuestadoras a todas las personas jur\u00eddicas* que publiquen encuestas cuyo objetivo sea el levantamiento, la recolecci\u00f3n y el procesamiento de datos, con el fin de dar a conocer preferencias o tendencias pol\u00edticas o electorales para procesos de decisi\u00f3n o elecci\u00f3n mediante voto popular, y que se hayan registrado para tal fin en el Registro Nacional de Firmas Encuestadoras.<\/p>\n\n\n\n<p>Municipios y Distritos de inclusi\u00f3n forzosa para la toma de muestras en encuestas de car\u00e1cter nacional: Ser\u00e1n aquellos municipios o distritos con una poblaci\u00f3n igual o superior a 800,000 habitantes. Tambi\u00e9n son de inclusi\u00f3n forzosa los municipios o distritos de mayor poblaci\u00f3n en las regiones que no tengan municipios o distritos con poblaci\u00f3n igual o superior a 800,000 habitantes.<\/p>\n\n\n\n<p>Municipios grandes para la toma de muestras en investigaciones cuantitativas: ser\u00e1n aquellos municipios con una poblaci\u00f3n inferior a 799,999 y superior a 100,000 habitantes.<\/p>\n\n\n\n<p>Municipios medianos para la toma de muestras en investigaciones cuantitativas: ser\u00e1n aquellos municipios con una poblaci\u00f3n inferior a 99,999 habitantes y superior a 50.000 habitantes.<\/p>\n\n\n\n<p>Municipios peque\u00f1os para la toma de muestras en investigaciones cuantitativas: ser\u00e1n aquellos municipios con una poblaci\u00f3n inferior a 50,000 habitantes.<\/p>\n\n\n\n<p>Margen de error de Dise\u00f1o. Margen de error utilizado para calcular el tama\u00f1o de la muestra.<\/p>\n\n\n\n<p>Margen de error calculado para indicadores: Margen de error calculado individualmente para cada indicador a ra\u00edz de los datos recolectados.<\/p>\n\n\n\n<p>Modelo de pron\u00f3stico: Es un modelo estad\u00edstico o tipo de proyecci\u00f3n estad\u00edstica realizado sobre los datos de las encuestas o sondeos.<\/p>\n\n\n\n<p>Art\u00edculo 4\u00b0. De la Selecci\u00f3n de la Muestra. Toda encuesta de car\u00e1cter electoral que sea publicada y divulgada en medios de comunicaci\u00f3n debe garantizar representatividad a trav\u00e9s de un m\u00e9todo cient\u00edfico dentro del dise\u00f1o muestral, de la siguiente manera:<\/p>\n\n\n\n<p>En una encuesta del nivel nacional, se debe tener un margen de error de dise\u00f1o, calculado para cada indicador publicado de m\u00e1ximo tres por ciento (3%) y un nivel de confianza m\u00ednimo del noventa y cinco por ciento (95%) para las preguntas de opini\u00f3n pol\u00edtica, conocimiento, favorabilidad e intenci\u00f3n de voto, para personajes y\/o candidatos, de elecci\u00f3n popular, con valores de un fen\u00f3meno de ocurrencia como m\u00ednimo menores al cuarenta por ciento (40%) o mayores a sesenta por ciento (60%).<\/p>\n\n\n\n<p>En una encuesta de nivel Departamental, Distrital y\/o municipal, se debe tener un margen de error de dise\u00f1o y calculado para cada indicador publicado m\u00e1ximo del cinco por ciento (5%) y el nivel de confianza m\u00ednimo del noventa y cinco por ciento (95%) para las preguntas de opini\u00f3n pol\u00edtica, conocimiento, favorabilidad e intenci\u00f3n de voto, para personajes y\/o candidatos, de elecci\u00f3n popular, con valores de un fen\u00f3meno de ocurrencia como m\u00ednimo menores al cuarenta por ciento (40%) o mayores a sesenta por ciento (60%).<\/p>\n\n\n\n<p>Adem\u00e1s, la distribuci\u00f3n de la muestra deber\u00e1 cumplir con los siguientes par\u00e1metros:<\/p>\n\n\n\n<p>a) Cuando se trate de encuestas sobre opini\u00f3n p\u00fablica y pol\u00edtica, mecanismos de participaci\u00f3n ciudadana o procesos electorales de car\u00e1cter nacional, la muestra deber\u00e1 incluir a todos los municipios y distritos con poblaci\u00f3n igual o superior a 800.000 habitantes de acuerdo a la proyecci\u00f3n m\u00e1s actualizada del Departamento Administrativo Nacional de Estad\u00edstica DANE. Tambi\u00e9n incluir\u00e1 el municipio o distrito con mayor poblaci\u00f3n de cada regi\u00f3n que no tenga municipios o distritos con poblaci\u00f3n igual o superior a 800.000 habitantes, as\u00ed como un subconjunto de municipios peque\u00f1os, medianos y grandes de todas las regiones del pa\u00eds.<\/p>\n\n\n\n<p>b) Cuando se trate de encuestas sobre opini\u00f3n p\u00fablica y pol\u00edtica, mecanismos de participaci\u00f3n ciudadana o procesos electorales de car\u00e1cter departamental, la muestra deber\u00e1 incluir a la capital departamental y como m\u00ednimo el 20% de los municipios del respectivo Departamento.<\/p>\n\n\n\n<p>c) Cuando se trate de encuestas sobre opini\u00f3n p\u00fablica y pol\u00edtica, mecanismos de participaci\u00f3n ciudadana o procesos electorales de nivel distrital o municipal, se deber\u00e1 asegurar que la muestra incluya una representaci\u00f3n adecuada de las subdivisiones administrativas, seleccionadas mediante un m\u00e9todo probabil\u00edstico.<\/p>\n\n\n\n<p>Par\u00e1grafo 1\u00b0. Para efectos de lo previsto en este art\u00edculo se entender\u00e1 por regiones las descritas en el art\u00edculo 45 de la Ley 2056 de 2020.<\/p>\n\n\n\n<p>Par\u00e1grafo 2\u00b0. En los eventos de alteraci\u00f3n del orden p\u00fablico, desastres naturales u otras circunstancias de fuerza mayor las firmas encuestadoras podr\u00e1n hacer uso para efectos de la selecci\u00f3n de municipios a las que se refiere este art\u00edculo de las sobre muestras o muestras de reemplazo.<\/p>\n\n\n\n<p>Art\u00edculo 5\u00b0. Encuestas de conocimiento, favorabilidad pol\u00edtica, opini\u00f3n o intenci\u00f3n del voto. Cuando se indague por el conocimiento, favorabilidad, opini\u00f3n sobre pol\u00edticos o personajes p\u00fablicos susceptibles de ser elegidos a un cargo uninominal de elecci\u00f3n popular, se deber\u00e1 incluir a candidatos que posean relevancia o notoriedad p\u00fablica significativa, hayan participado en elecciones similares previas o tengan favorabilidad o reconocimiento manifiesto.<\/p>\n\n\n\n<p>Las encuestas que incluyan preguntas relacionadas con intenci\u00f3n de voto solo podr\u00e1n realizarse a partir de los tres meses anteriores del primer d\u00eda de inscripciones de candidatos. Una vez haya finalizado el t\u00e9rmino para la inscripci\u00f3n a elecciones uninominales, las encuestas tendr\u00e1n que incluir a todos los candidatos inscritos para la respectiva contienda electoral.<\/p>\n\n\n\n<p>Art\u00edculo 6\u00b0. Requisitos formales para la publicaci\u00f3n de encuestas y sondeos. Toda encuesta de opini\u00f3n de car\u00e1cter electoral al ser publicada o divulgada tendr\u00e1 que serlo en su totalidad y deber\u00e1 indicar de manera clara y visible la siguiente informaci\u00f3n, a manera de ficha t\u00e9cnica:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>La persona natural o jur\u00eddica que la realiz\u00f3 y qui\u00e9n la encomend\u00f3.<\/li>\n\n\n\n<li>La fuente de su financiaci\u00f3n.<\/li>\n\n\n\n<li>El tipo, tama\u00f1o de la muestra y procedimiento utilizado para seleccionar las unidades muestrales.<\/li>\n\n\n\n<li>El tema o temas concretos a los que se refiere.<\/li>\n\n\n\n<li>El texto literal de la pregunta o preguntas formuladas, y el orden en el que se realizaron.<\/li>\n\n\n\n<li>Los candidatos, personas o instituciones por quienes se indag\u00f3.<\/li>\n\n\n\n<li>El espacio geogr\u00e1fico y la fecha o per\u00edodo de tiempo en que se realiz\u00f3.<\/li>\n\n\n\n<li>El margen de error de dise\u00f1o.<\/li>\n\n\n\n<li>Tipo de estudio con arreglo a las categor\u00edas descritas en la presente ley.<\/li>\n\n\n\n<li>El prop\u00f3sito del estudio.<\/li>\n\n\n\n<li>Universo representado.<\/li>\n\n\n\n<li>M\u00e9todo de recolecci\u00f3n de datos.<\/li>\n\n\n\n<li>Nivel de confiabilidad.<\/li>\n\n\n\n<li>Nombres y apellidos de los profesionales en estad\u00edstica responsables de la encuesta.<\/li>\n\n\n\n<li>Declaraci\u00f3n en la que se informe si hubo alg\u00fan tipo de contraprestaci\u00f3n por responder la encuesta. En caso de que se hubiere otorgado contraprestaci\u00f3n, se deber\u00e1 declarar la naturaleza y el valor de dicha contraprestaci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<p>Par\u00e1grafo 1\u00b0. Adicionalmente, se deber\u00e1 publicar, en anexos t\u00e9cnicos abiertos y accesibles al p\u00fablico, el n\u00famero efectivo de respuestas a cada una de las preguntas en forma individual, y el margen de error calculado de cada indicador y los microdatos, anonimizando informaci\u00f3n personal de conformidad con los est\u00e1ndares del tratamiento de datos personales consagrados en la Ley 1581 de 2012 y dem\u00e1s normas concordantes, y las variables necesarias para replicar los c\u00e1lculos publicados.<\/p>\n\n\n\n<p>Par\u00e1grafo 2\u00b0. Las encuestas que no cumplan con los requisitos establecidos en este art\u00edculo no podr\u00e1n ser publicadas ni divulgadas por ning\u00fan medio de comunicaci\u00f3n.<\/p>\n\n\n\n<p>Par\u00e1grafo 3\u00b0. En su revisi\u00f3n posterior, el Consejo Nacional Electoral ejercer\u00e1 vigilancia sobre el cumplimiento de la presente ley y especialmente sobre la forma en que se realizan las preguntas, no inducci\u00f3n a las respuestas, la adecuada selecci\u00f3n de la muestra, la veracidad de los datos reportados, publicados y las buenas pr\u00e1cticas en todas las etapas de la encuesta hasta su publicaci\u00f3n y divulgaci\u00f3n. En caso de detectarse pr\u00e1cticas que induzcan respuestas, manipulen la muestra o alteren los datos publicados, se dar\u00e1 inicio al procedimiento sancionatorio correspondiente, conforme a lo previsto en esta ley y en el r\u00e9gimen de procedimiento administrativo vigente.<\/p>\n\n\n\n<p>Par\u00e1grafo 4\u00b0. En toda publicaci\u00f3n deber\u00e1 incluirse, de manera resaltada y claramente visible, que todas las encuestas se ven afectadas por m\u00e1rgenes de error.<\/p>\n\n\n\n<p>Par\u00e1grafo 5\u00b0. A partir de la entrada en vigencia de esta ley el Consejo Nacional Electoral deber\u00e1 mantener actualizado y accesible en su p\u00e1gina web un repositorio con la informaci\u00f3n se\u00f1alada en este art\u00edculo de cada encuesta publicada, la informaci\u00f3n deber\u00e1 ser p\u00fablica en el repositorio en un plazo no superior a cinco (5) d\u00edas desde su reporte por parte de la respectiva firma encuestadora.<\/p>\n\n\n\n<p>Par\u00e1grafo 6\u00b0. Los sondeos de opini\u00f3n p\u00fablica y electorales deber\u00e1n ser acompa\u00f1ados en su publicaci\u00f3n y divulgaci\u00f3n de lo siguiente: La persona natural o jur\u00eddica que la realiz\u00f3 y la encomend\u00f3, la fuente de su financiaci\u00f3n, el tipo, tama\u00f1o de la muestra y procedimiento utilizado para seleccionar las unidades muestrales, el texto literal de la pregunta o preguntas formuladas, y el orden en el que se realizaron, las personas o instituciones por quienes se indag\u00f3, el espacio geogr\u00e1fico y la fecha o per\u00edodo de tiempo en que se realiz\u00f3, el prop\u00f3sito del estudio y el universo representado.<\/p>\n\n\n\n<p>Art\u00edculo 7\u00b0. Comisi\u00f3n T\u00e9cnica y de Vigilancia de Encuestas sobre Opini\u00f3n Pol\u00edtica y Electoral. Cr\u00e9ase la Comisi\u00f3n T\u00e9cnica de Vigilancia de Encuestas sobre Opini\u00f3n Pol\u00edtica y Electoral, la cual es un cuerpo t\u00e9cnico del Consejo Nacional Electoral, que tendr\u00e1 a cargo las siguientes funciones:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Estudiar, evaluar, auditar y conceptuar sobre el cumplimiento de las disposiciones que regulan la elaboraci\u00f3n y publicaci\u00f3n de encuestas.<\/li>\n\n\n\n<li>Asesorar al Consejo Nacional Electoral en la regulaci\u00f3n, vigilancia y seguimiento a las encuestas y estudios de opini\u00f3n pol\u00edtica.<\/li>\n\n\n\n<li>Expedir su propio reglamento y designar coordinador.<\/li>\n<\/ol>\n\n\n\n<p>Par\u00e1grafo transitorio. Mientras la Comisi\u00f3n expide su reglamento se regir\u00e1 por las siguientes reglas: i) la secretar\u00eda t\u00e9cnica ser\u00e1 ejercida por la Secretar\u00eda General del Consejo Nacional Electoral, ii) el qu\u00f3rum para realizar sesiones o tomar decisiones se cumplir\u00e1 con la presencia f\u00edsica o virtual de no menos de 3 comisionados, iii) La sesiones ser\u00e1n convocadas con al menos siete (7) d\u00edas de anticipaci\u00f3n a la fecha de la reuni\u00f3n iv) el coordinador de la comisi\u00f3n asignar\u00e1 entre uno (1) y dos (2) comisionados para elaborar la ponencia de las auditor\u00edas, informes o conceptos que se requieran haciendo uso de un reparto aleatorio y equitativo v) la aprobaci\u00f3n de conceptos, informes y auditor\u00edas as\u00ed como las dem\u00e1s decisiones de la comisi\u00f3n requieren del voto afirmativo de al menos 3 miembros de la comisi\u00f3n.<\/p>\n\n\n\n<p>Art\u00edculo 8\u00b0. Conformaci\u00f3n de la Comisi\u00f3n T\u00e9cnica y de Vigilancia de Encuestas sobre Opini\u00f3n Pol\u00edtica y Electoral. La Comisi\u00f3n estar\u00e1 integrada por cinco (5) miembros con t\u00edtulo profesional reconocido en Colombia, que hayan realizado estudios de pregrado, especializaci\u00f3n, maestr\u00eda y\/o doctorado en estad\u00edstica y que cuenten con experiencia profesional demostrable de al menos 2 a\u00f1os relacionada con encuestas por muestreo probabil\u00edstico.<\/p>\n\n\n\n<p>Los miembros ser\u00e1n elegidos por el Consejo Nacional Electoral a partir de una lista de postulados presentada por los decanos o directores de departamento de universidades que ofrezcan programas de pregrado, especializaci\u00f3n, maestr\u00eda y\/o doctorado en estad\u00edstica, acreditados en alta calidad por el Ministerio de Educaci\u00f3n Nacional. Cada programa acreditado podr\u00e1 postular hasta tres candidatos. Durante los cuatro a\u00f1os siguientes a su conformaci\u00f3n, en caso de renuncia, inhabilidad, fallecimiento u otra circunstancia que genere una vacante en la comisi\u00f3n, el reemplazo ser\u00e1 seleccionado de la lista de postulados.<\/p>\n\n\n\n<p>Par\u00e1grafo 1\u00b0. Inhabilidades e incompatibilidades. No podr\u00e1n ser miembros de la Comisi\u00f3n:<\/p>\n\n\n\n<p>a. Quienes hayan sido sancionados por las conductas previstas en la presente ley.<\/p>\n\n\n\n<p>b. Quienes sean afiliados o hayan tenido v\u00ednculos contractuales o laborales en los \u00faltimos tres (3) a\u00f1os con partidos, movimientos o campa\u00f1as pol\u00edticas.<\/p>\n\n\n\n<p>c. Quienes hayan tenido v\u00ednculos laborales o contractuales, en los \u00faltimos dos (2) a\u00f1os, con personas naturales o jur\u00eddicas dedicadas a realizar encuestas o investigaciones pol\u00edticas cuantitativas o cualitativas.<\/p>\n\n\n\n<p>d. Quienes tengan v\u00ednculo por matrimonio, uni\u00f3n permanente o parientes hasta el cuarto grado de consanguinidad, segundo de afinidad o primero civil con: candidatos; directivos de partidos, movimientos y campa\u00f1as pol\u00edticas; socios, miembros de junta directiva o trabajadores de confianza y manejo vinculados a personas naturales o jur\u00eddicas registradas como encuestadoras pol\u00edticas.<\/p>\n\n\n\n<p>Par\u00e1grafo 2\u00b0. Los honorarios de los miembros de la Comisi\u00f3n ser\u00e1n pagados mensualmente de acuerdo a la tabla vigente de honorarios de la organizaci\u00f3n electoral.<\/p>\n\n\n\n<p>Par\u00e1grafo 3\u00b0. En temporada electoral el Consejo Nacional Electoral podr\u00e1 vincular a supernumerarios para asistir la tarea\u00b7 de la Comisi\u00f3n de acuerdo con los requerimientos solicitados por ella.<\/p>\n\n\n\n<p>Par\u00e1grafo transitorio. Para la conformaci\u00f3n inicial de la Comisi\u00f3n el Consejo Nacional Electoral solicitar\u00e1 a las instituciones de educaci\u00f3n superior se\u00f1aladas en este art\u00edculo los listados de candidatos en un plazo de diez (10) d\u00edas desde la entrada en vigencia de la presente ley, a su vez deber\u00e1 elegir a los miembros de la comisi\u00f3n en el plazo de dos (2) meses desde la entrada vigencia de la presente ley.<\/p>\n\n\n\n<p>Art\u00edculo 9\u00b0. De las firmas encuestadoras. Solamente podr\u00e1n realizar encuestas de car\u00e1cter electoral con \u00e1nimo de publicaci\u00f3n, las firmas encuestadoras previamente registradas ante el Consejo Nacional Electoral.<\/p>\n\n\n\n<p>No est\u00e1 permitida la publicaci\u00f3n y difusi\u00f3n en medios masivos de comunicaci\u00f3n, incluidas redes sociales, de encuestas y sondeos falsos, que incumplan las disposiciones establecidas en la presente ley, o utilicen emblemas de empresas encuestadoras registradas sin su autorizaci\u00f3n.<\/p>\n\n\n\n<p>Art\u00edculo 10. Del registro. Para la inscripci\u00f3n en el Registro Nacional de Firmas Encuestadoras, se deber\u00e1 aportar la siguiente informaci\u00f3n:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Acreditaci\u00f3n de experiencia en materia de realizaci\u00f3n de encuestas. Para ello, se aportar\u00e1n los contratos cuyo objeto sea la realizaci\u00f3n de estudios de mercado y encuestas de opini\u00f3n p\u00fablica que hayan sido legalmente ejecutados con personas naturales o jur\u00eddicas en los cinco (5) a\u00f1os anteriores a la presentaci\u00f3n de la solicitud de inscripci\u00f3n en el registro. En caso de que las partes hayan convenido cl\u00e1usulas o acuerdos de confidencialidad, el Consejo Nacional Electoral (CNE) garantizar\u00e1 la reserva de la informaci\u00f3n sobre el objeto del contrato.<\/li>\n\n\n\n<li>Constituci\u00f3n como sociedad cuyo objeto principal sea la realizaci\u00f3n de estudios de mercado y encuestas: al menos tres (3) a\u00f1os antes de la fecha de la solicitud de registro. Para tal efecto, se allegar\u00e1 el correspondiente certificado de existencia y representaci\u00f3n legal, expedido por la autoridad competente, con una antelaci\u00f3n no mayor de tres meses a la fecha en que se solicite la inscripci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<p>Par\u00e1grafo 1\u00b0. Cuando se trate de mediciones sobre preferencias electorales a nivel nacional, las firmas encuestadoras adicionalmente deber\u00e1n acreditar el cumplimiento del est\u00e1ndar de calidad m\u00e1s exigente para el sector de la investigaci\u00f3n de mercado, investigaci\u00f3n social y de la opini\u00f3n, reconocido por el Subsistema Nacional de Calidad o la entidad que lo sustituya o haga sus veces. En caso de contradicci\u00f3n entre la norma t\u00e9cnica y lo previsto en esta ley prevalece la ley.<\/p>\n\n\n\n<p>Par\u00e1grafo 2\u00b0. Las solicitudes de inscripci\u00f3n que no cumplan con los requisitos y con las formalidades establecidas en la presente ley ser\u00e1n inadmitidas. El solicitante tendr\u00e1 un plazo de un (1) mes para subsanarlos, de lo contrario se proceder\u00e1 conforme al art\u00edculo 17 del C\u00f3digo de Procedimiento Administrativo y de lo Contencioso Administrativo.<\/p>\n\n\n\n<p>Par\u00e1grafo 3\u00b0. La inscripci\u00f3n en el Registro Nacional de Firmas Encuestadoras se renovar\u00e1 cada tres (3) a\u00f1os. La no solicitud de renovaci\u00f3n por parte de los interesados conlleva su expiraci\u00f3n autom\u00e1tica. En caso que, a la fecha de vencimiento del t\u00e9rmino inicial para el cual se realiz\u00f3 la inscripci\u00f3n, el Consejo Nacional Electoral no se haya pronunciado sobre la solicitud de renovaci\u00f3n, esta se entender\u00e1 prorrogada hasta que haya un pronunciamiento definitivo sobre la misma.<\/p>\n\n\n\n<p>Par\u00e1grafo 4\u00b0. Cualquier cambio que se produzca en la representaci\u00f3n legal, en la naturaleza de la sociedad y en la direcci\u00f3n del domicilio de las personas inscritas en el Registro Nacional de Firmas Encuestadoras del Consejo Nacional Electoral, debe ser notificado por el representante legal, o quien haga sus veces, aportando los certificados correspondientes.<\/p>\n\n\n\n<p>Par\u00e1grafo 5\u00b0. la nacionalidad o pa\u00eds de domicilio de las personas jur\u00eddicas que deban registrarse en el Registro Nacional de Firmas Encuestadoras no las exime de la obligaci\u00f3n de registrarse y de cumplir los requisitos legales para la elaboraci\u00f3n, publicaci\u00f3n y divulgaci\u00f3n de encuestas.<\/p>\n\n\n\n<p>Par\u00e1grafo Transitorio. Las personas naturales que puedan acreditar que su actividad principal ha sido la realizaci\u00f3n de estudios de mercado y encuestas de car\u00e1cter pol\u00edtico y electoral, tendr\u00e1n un plazo de un a\u00f1o (1) a\u00f1o contado a partir de la entrada en vigencia de la presente ley para constituirse como personas jur\u00eddicas y solicitar su inscripci\u00f3n en el Registro Nacional de Firmas Encuestadoras.<\/p>\n\n\n\n<p>Podr\u00e1n acreditar el cumplimiento de lo previsto en la presente ley con los soportes que den cuenta de la realizaci\u00f3n como personas naturales de estudios de mercado y encuestas de car\u00e1cter pol\u00edtico y electoral como actividad principal, por lo menos en los dos (2) a\u00f1os anteriores a la entrada en vigencia de la presente ley.<\/p>\n\n\n\n<p>Art\u00edculo 11. Responsabilidad de las firmas encuestadoras. Las firmas encuestadoras deber\u00e1n cumplir con las leyes de la estad\u00edstica. Si no lo hicieren, responder\u00e1n civil y penalmente por sus actos cuando corresponda.<\/p>\n\n\n\n<p>Art\u00edculo 12. Auditor\u00eda y trazabilidad de los datos. Para garantizar que se disponga de la informaci\u00f3n necesaria para la realizaci\u00f3n de auditor\u00edas, las firmas encuestadoras deber\u00e1n entregar al Consejo Nacional Electoral de manera simult\u00e1nea a la entrega de los productos terminados al cliente y guardar copia, por un lapso no inferior a dos (2) a\u00f1os, la siguiente informaci\u00f3n:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Lo se\u00f1alado en el art\u00edculo 6\u00b0;<\/li>\n\n\n\n<li>Los c\u00e1lculos y justificaci\u00f3n del tama\u00f1o y selecci\u00f3n de la muestra;<\/li>\n\n\n\n<li>El c\u00f3digo computacional usado para el procesamiento de los datos y el c\u00e1lculo de los indicadores;<\/li>\n\n\n\n<li>Los registros primarios utilizados tales como cuestionarios diligenciados, ficheros de datos, grabaciones u otros similares;<\/li>\n\n\n\n<li>Los productos de la auditor\u00eda interna.<\/li>\n<\/ol>\n\n\n\n<p>Adicionalmente para el caso de encuestas en hogares se deber\u00e1 entregar el c\u00f3digo computacional usado y que haga posible replicar la selecci\u00f3n de las unidades muestrales. En encuestas telef\u00f3nicas la descripci\u00f3n del procedimiento de selecci\u00f3n de la muestra y n\u00fameros telef\u00f3nicos.<\/p>\n\n\n\n<p>Todas las encuestas electorales, pol\u00edticas y de opini\u00f3n p\u00fablica de cobertura nacional ser\u00e1n auditadas por la comisi\u00f3n. Las encuestas territoriales ser\u00e1n auditadas aleatoriamente. El Consejo Nacional Electoral podr\u00e1 contratar auditor\u00edas externas.<\/p>\n\n\n\n<p>Par\u00e1grafo. A partir de la entrada en vigencia de la presente ley el CNE deber\u00e1 conservar al menos dos copias en dispositivos independientes de la informaci\u00f3n aqu\u00ed se\u00f1alada en expedientes digitales.<\/p>\n\n\n\n<p>Art\u00edculo 13. Prohibici\u00f3n de aportes. Las firmas encuestadoras registradas ante el Consejo Nacional Electoral y sus representantes legales, o miembros de junta directiva no podr\u00e1n realizar aportes a las campa\u00f1as pol\u00edticas.<\/p>\n\n\n\n<p>Art\u00edculo 14. Actualizaci\u00f3n normativa. El Consejo Nacional Electoral deber\u00e1 expedir una resoluci\u00f3n actualizando las resoluciones 23 de 1996 y 50 de 1997 de conformidad a los contenidos de la presente ley en los dos meses siguientes a su entrada en vigencia.<\/p>\n\n\n\n<p>Art\u00edculo 15. Rectificaci\u00f3n de la informaci\u00f3n err\u00f3nea. Los medios de comunicaci\u00f3n que publiquen o difundan resultados de encuestas electorales, de opini\u00f3n p\u00fablica, sondeos y\/o consultas abiertas con errores sustanciales o que violen lo dispuesto en la presente ley, deber\u00e1n rectificar la informaci\u00f3n dentro de un plazo m\u00e1ximo de tres (3) d\u00edas contados a partir del pronunciamiento del Consejo Nacional Electoral, mencionando el motivo de la rectificaci\u00f3n, lo cual deber\u00e1 realizarse a trav\u00e9s de los mismos canales y espacios en los que fue difundida la informaci\u00f3n original. Lo anterior sin perjuicio de las sanciones a las que haya lugar.<\/p>\n\n\n\n<p>Art\u00edculo 16. El Consejo Nacional Electoral garantizar\u00e1 mecanismos de participaci\u00f3n y\/o veedur\u00eda para la ciudadan\u00eda que quiera presentar observaciones, solicitudes de revisi\u00f3n o denuncias sobre encuestas publicadas, relacionadas con procesos de elecci\u00f3n popular y\/o de opini\u00f3n pol\u00edtica. Estas observaciones, solicitudes o denuncias deber\u00e1n ser tramitadas de manera pronta y efectiva, con el fin de promover y garantizar el control ciudadano y la legitimidad democr\u00e1tica.<\/p>\n\n\n\n<p>Art\u00edculo 17. Vigencia. La presente ley rige a partir de su promulgaci\u00f3n y deroga todas las disposiciones que le sean contrarias, especialmente el art\u00edculo 10 de la Resoluci\u00f3n 23 de 1996 expedida por el Consejo Nacional Electoral.<\/p>\n\n\n\n<p>El Presidente del Honorable Senado de la Rep\u00fablica,<\/p>\n\n\n\n<p>Efra\u00edn Cepeda Sarabia.<\/p>\n\n\n\n<p>El Secretario General del Honorable Senado de la Rep\u00fablica,<\/p>\n\n\n\n<p>Diego Alejandro Gonz\u00e1lez Gonz\u00e1lez.<\/p>\n\n\n\n<p>El Presidente de la Honorable C\u00e1mara de Representantes,<\/p>\n\n\n\n<p>Jaime Ra\u00fal Salamanca Torres.<\/p>\n\n\n\n<p>El Secretario General de la Honorable C\u00e1mara de Representantes,<\/p>\n\n\n\n<p>Jaime Luis Lacouture Pe\u00f1aloza.<\/p>\n\n\n\n<p>REP\u00daBLICA DE COLOMBIA &#8211; GOBIERNO NACIONAL<\/p>\n\n\n\n<p>Publ\u00edquese y c\u00famplase.<\/p>\n\n\n\n<p>Dada, a 23 de julio de 2025.<\/p>\n\n\n\n<p>GUSTAVO PETRO URREGO<\/p>\n\n\n\n<p>El Ministro del Interior,<\/p>\n\n\n\n<p>Armando Benedetti Villaneda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LEY 2494 DE 2025 (julio 23) D.O. 53.191, julio 24 de 2025 por medio de la cual se establecen medidas sobre la elaboraci\u00f3n, publicaci\u00f3n y divulgaci\u00f3n de encuestas y se dictan otras disposiciones. El Congreso de Colombia, DECRETA: Art\u00edculo 1\u00b0. Objeto. La presente ley tiene por objeto regular la realizaci\u00f3n y divulgaci\u00f3n de encuestas para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134],"tags":[],"class_list":["post-5491","post","type-post","status-publish","format-standard","hentry","category-leyes-2025"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/5491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/comments?post=5491"}],"version-history":[{"count":1,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/5491\/revisions"}],"predecessor-version":[{"id":5492,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/posts\/5491\/revisions\/5492"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/media?parent=5491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/categories?post=5491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/legislacion\/leyes\/wp-json\/wp\/v2\/tags?post=5491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}