{"id":53873,"date":"2024-05-17T20:41:48","date_gmt":"2024-05-17T20:41:48","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/sc811-2021-1993-00001-02\/"},"modified":"2024-05-17T20:41:48","modified_gmt":"2024-05-17T20:41:48","slug":"sc811-2021-1993-00001-02","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/sc811-2021-1993-00001-02\/","title":{"rendered":"SC811 2021"},"content":{"rendered":"<p>SC811-2021 (1993-00001-02)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado &nbsp;Ponente &nbsp;<\/p>\n<p>SC811-2020 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00b0 11001-31-03-004-1993-00001-02 &nbsp;<\/p>\n<p>(Aprobada &nbsp;en sesi\u00f3n virtual de seis de agosto de dos mil veinte) &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., quince (15) de marzo de dos mil veintiuno (2021). &nbsp;<\/p>\n<p>Decide &nbsp;la Corte el recurso de casaci\u00f3n interpuesto por la &nbsp;sociedad Sanclemente, Fern\u00e1ndez y Hern\u00e1ndez Abogados &nbsp;S.A. &nbsp;frente a la sentencia de 22 de julio de 2013, proferida por el &nbsp;Tribunal Superior del Distrito Judicial de Bogot\u00e1- Sala Civil &nbsp;de Descongesti\u00f3n, dentro del proceso ordinario que el &nbsp;recurrente promovi\u00f3 contra Industrias &nbsp;y Cr\u00e9ditos S.A. &nbsp;al cual se vincul\u00f3 a Inversionistas &nbsp;Asociados Basora S.A. &nbsp;<\/p>\n<p>1. &nbsp;EL LITIGIO &nbsp;<\/p>\n<p>1. &nbsp;Sanclemente, &nbsp;Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. &nbsp;solicit\u00f3 se hicieran las siguientes declaraciones y condenas: &nbsp;<\/p>\n<p>a) &nbsp;Se declare que le pertenece \u226ael &nbsp;derecho de dominio pleno y absoluto del lote de terreno N\u00b0 tres &nbsp;(3) y distinguido anteriormente con el N\u00b0 59-12 de la carrera &nbsp;Tercera (3\u00aa) del plano de Bogot\u00e1, hoy en d\u00eda &nbsp;identificado con la nomenclatura urbana de la ciudad de Santa Fe de &nbsp;Bogot\u00e1 con el N\u00b0 3-15 de la calle 60 o Avenida &nbsp;Circunvalar, distinguido con C\u00e9dula Catastral N\u00b0 59-T-3, &nbsp;antes N\u00b0 53-7 E 25 y registrado con Matr\u00edcula Inmobiliaria &nbsp;n\u00famero 050-1079044 de la Oficina de Registro de Instrumentos &nbsp;P\u00fablicos de Bogot\u00e1; con una cabida aproximada de 800 &nbsp;metros cuadrados comprendido bajo los siguientes linderos, los cuales &nbsp;aparecen descritos en la escritura p\u00fablica N\u00b0 2660 de &nbsp;septiembre 20 de 1989 de la Notar\u00eda 33 de Bogot\u00e1. POR &nbsp;EL NORTE. -En l\u00ednea curva que tiene 35 metros de longitud, con &nbsp;la calle 60 o Avenida Circunvalar. POR EL ORIENTE. &#8211; En l\u00ednea &nbsp;recta de 19 metros de longitud con predio de propiedad de la &nbsp;exponente. POR EL OCCIDENTE. &#8211; En longitud de 35 metros con el lote &nbsp;n\u00famero dos (2) de propiedad de Gerardo Amezquita y otra.- POR &nbsp;EL SUR.- En l\u00ednea curva de 24 metros de longitud con la calle &nbsp;59 o transversal primera\u226b. &nbsp;<\/p>\n<p>b) &nbsp;Declarar que Industrias &nbsp;y Cr\u00e9ditos S.A. es &nbsp;poseedora de mala fe. &nbsp;<\/p>\n<p>c) &nbsp;Se condene a Industrias y Cr\u00e9ditos S.A. a restituir cinco (5) &nbsp;d\u00edas despu\u00e9s de ejecutoriada la sentencia en favor de &nbsp;Sanclemente, Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. el &nbsp;inmueble descrito e identificado en la declaraci\u00f3n primera. &nbsp;<\/p>\n<p>d) &nbsp;Se le imponga el pago en favor de la convocante de los frutos &nbsp;civiles, seg\u00fan lo probado por el peritaje, desde el d\u00eda &nbsp;12 de febrero de 1991 hasta la fecha en que se haga la entrega real o &nbsp;efectiva del inmueble. &nbsp;<\/p>\n<p>e) &nbsp;Se declare que Sanclemente, &nbsp;Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. &nbsp;queda &nbsp;exenta de pagar a Industrias &nbsp;y Cr\u00e9ditos S.A. las &nbsp;expensas necesarias a que se refiere el art\u00edculo 965 del &nbsp;C\u00f3digo Civil. &nbsp;<\/p>\n<p>f) &nbsp;Se ordene la cancelaci\u00f3n de todos los grav\u00e1menes que &nbsp;haya constituido la convocada sobre el inmueble reivindicado y la &nbsp;inscripci\u00f3n de la sentencia en la Oficina de Registro de &nbsp;Instrumentos P\u00fablicos. &nbsp;<\/p>\n<p>2. &nbsp;Soportan tales reclamaciones los supuestos f\u00e1cticos que &nbsp;admiten el siguiente compendio &nbsp;(fls. &nbsp;57 &nbsp;a 70 Cd. 1): &nbsp;<\/p>\n<p>a.-) &nbsp;Mediante Escritura P\u00fablica 2660 de 20 de septiembre de 1989 de &nbsp;la Notar\u00eda 33 de Bogot\u00e1 Sanclemente, Fern\u00e1ndez y &nbsp;Hern\u00e1ndez Abogados S.A. adquiri\u00f3 por daci\u00f3n en &nbsp;pago, de manos de Glor\u00eda Garc\u00eda G\u00f3mez, el &nbsp;derecho de dominio y posesi\u00f3n del inmueble antes referido, &nbsp;quien a su vez lo obtuvo por compra hecha en mayor extensi\u00f3n a &nbsp;Urbanizaci\u00f3n El Bosque Calder\u00f3n Barriga y C\u00eda. &nbsp;Ltda. en liquidaci\u00f3n, por escritura p\u00fablica No. 7906 de &nbsp;24 de noviembre de 1986, otorgada en la Notar\u00eda Segunda de &nbsp;Bogot\u00e1. &nbsp;<\/p>\n<p>b.-) &nbsp;A su turno, Urbanizaciones El Bosque Calder\u00f3n Barriga y C\u00eda. &nbsp;Ltda. en liquidaci\u00f3n lo adquiri\u00f3 por compra en mayor &nbsp;extensi\u00f3n a la Compa\u00f1\u00eda Constructora y &nbsp;Urbanizadora S.A., mediante escritura p\u00fablica No. 3412 de 18 &nbsp;de junio de 1946, de la Notar\u00eda Segunda de Bogot\u00e1, &nbsp;registrada en el folio de matr\u00edcula inmobiliaria No. &nbsp;050-05423513. &nbsp;<\/p>\n<p>c.-) &nbsp;Salvo la variaci\u00f3n de nomenclatura y linderos, alterados a &nbsp;ra\u00edz de la construcci\u00f3n de la Avenida Circunvalar o &nbsp;calle 60, existe identidad f\u00edsica entre el fundo detallado en &nbsp;el hecho primero de la demanda con respecto a los determinados en las &nbsp;escrituras antes referidas. &nbsp;<\/p>\n<p>d.-) &nbsp;Sanclemente, Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. es &nbsp;actual propietaria inscrita del lote a reivindicar, quien est\u00e1 &nbsp;privada de la posesi\u00f3n material. &nbsp;<\/p>\n<p>e.-) &nbsp;Industrias y Cr\u00e9ditos S.A. es el actual poseedor material, de &nbsp;mala fe, pues adquiri\u00f3 esta mediante la utilizaci\u00f3n &nbsp;tortuosa de un juicio de deslinde y amojonamiento, en donde, a &nbsp;sabiendas, omiti\u00f3 citar a Sanclemente, Fern\u00e1ndez y &nbsp;Hern\u00e1ndez Abogados S.A. y otros propietarios, que a la prostre &nbsp;resultaron despojados de sus tierras. &nbsp;<\/p>\n<p>f.-) &nbsp;Con sentencia de 12 de febrero de 1991, del Juzgado Trece Civil del &nbsp;Circuito de Santa Fe de Bogot\u00e1, Industrias y Cr\u00e9ditos &nbsp;S.A. \u226aobtuvo &nbsp;la inclusi\u00f3n f\u00edsica del inmueble a reivindicar dentro &nbsp;del lote supuestamente de su propiedad que era objeto de deslinde y &nbsp;amojonamiento\u226b. &nbsp;Procedi\u00f3 dicho despacho, desde esa fecha, a hacerle entrega &nbsp;real y material del predio de propiedad de Sanclemente, Fern\u00e1ndez &nbsp;y Hern\u00e1ndez Abogados S.A, ya que este \u226aqued\u00f3 &nbsp;absorbido en forma total por el inmueble alinderado y supuestamente &nbsp;de propiedad de INDUSTRIAS Y CR\u00c9DITOS S.A.\u226b. &nbsp;Por lo dem\u00e1s, se asegur\u00f3 que desde esta \u00e9poca, &nbsp;la poseedora viene ejerciendo actos de se\u00f1or\u00edo, tales &nbsp;como cerramiento del lote y vigilancia armada -a trav\u00e9s de una &nbsp;empresa privada-. &nbsp;<\/p>\n<p>3. &nbsp;Industrias y Cr\u00e9ditos S.A. formul\u00f3 las excepciones &nbsp;perentorias que denomin\u00f3: \u201cfalta de legitimaci\u00f3n &nbsp;en causa activa y pasiva\u201d; \u201cnulidad de los t\u00edtulos &nbsp;y de la cadena de tradiciones\u201d y \u201cprescripci\u00f3n &nbsp;adquisitiva\u201d (fls. &nbsp;88 a 98 Cd 1). &nbsp;<\/p>\n<p>4. &nbsp;El 5 de octubre de 2000, el juez de conocimiento dispuso, en los &nbsp;t\u00e9rminos del art\u00edculo 59 del C.P.C., la vinculaci\u00f3n &nbsp;al tr\u00e1mite de la sociedad Inversionistas Asociados Basora &nbsp;S.A., quien puesta a juicio se opuso a las pretensiones y dijo &nbsp;ratificar todas las excepciones propuestas por Industrias y Cr\u00e9ditos &nbsp;S.A. &nbsp;<\/p>\n<p>5. &nbsp;El &nbsp;Juzgado Veinte &nbsp;Civil &nbsp;del Circuito de Descongesti\u00f3n &nbsp;de Bogot\u00e1 defini\u00f3 la instancia el 29 de junio de 2012, &nbsp;negando las pretensiones impetradas (fls. &nbsp;1678 &nbsp;a 1700, &nbsp;cuaderno 1). &nbsp;<\/p>\n<p>6. &nbsp;El 22 de julio de 2013, el Tribunal Superior de Bogot\u00e1 Sala &nbsp;Civil de Descongesti\u00f3n, confirm\u00f3 &nbsp;la decisi\u00f3n &nbsp;(fls. &nbsp;38 a 72). &nbsp;<\/p>\n<p>II. &nbsp;FUNDAMENTOS DEL FALLO DEL TRIBUNAL &nbsp;<\/p>\n<p>Luego &nbsp;de memorar los presupuestos axiol\u00f3gicos de la acci\u00f3n &nbsp;reivindicatoria, el a &nbsp;quem adujo, &nbsp;que si bien se acredit\u00f3 el dominio de Sanclemente, Fern\u00e1ndez &nbsp;y Hern\u00e1ndez Abogados S.A. respecto del predio identificado con &nbsp;el folio de matr\u00edcula inmobiliaria N\u00b0 &nbsp;50C-1079044, &nbsp;haci\u00e9ndose evidente su legitimaci\u00f3n por activa, no &nbsp;ocurre lo propio con la demandada, comoquiera que su condici\u00f3n &nbsp;de poseedora no se prob\u00f3. &nbsp;<\/p>\n<p>A &nbsp;partir de la valoraci\u00f3n de las pruebas allegadas soport\u00f3 &nbsp;su decisi\u00f3n, en lo medular, en la falta de identidad entre el &nbsp;reclamado y el detentado por la pasiva y, en su caso, el pose\u00eddo &nbsp;por Basora S.A., cuya sinopsis es la que sigue (fls. &nbsp;38 a 72, cuaderno 8): &nbsp;<\/p>\n<p>1.- &nbsp;Refiere, que \u226ala &nbsp;sociedad demandada sobre el particular adujo que el terreno que &nbsp;detenta es el aludido en el interior del proceso de \u201cdeslinde y &nbsp;amojonamiento adelantado por (\u00e9sta) contra la Naci\u00f3n y &nbsp;otros colindantes, en el que quedaron claramente determinados y &nbsp;alinderados los lotes objeto de la posesi\u00f3n&#8230;\u201d &nbsp;(fls. 80 &nbsp;c1 y 50 c.4); y as\u00ed examinada esa actuaci\u00f3n, seg\u00fan &nbsp;las copias que de la misma obran entre los folios 436 a 439 del &nbsp;cuaderno No. 1. se infiere que los predios a los que alude aquella &nbsp;demandada Industrias y Cr\u00e9ditos S.A\u2026.\u226b, &nbsp;son los linderos que all\u00ed se definieron, a partir de lo cual &nbsp;afirma, que \u226a[E]se &nbsp;proceso de deslinde y amojonamiento, involucr\u00f3 los inmuebles &nbsp;identificados con las matr\u00edculas inmobiliarias 050-409930 &nbsp;(fl. 595 c 1 A), 050-0096383 &nbsp;(fl. 596); 050-0542513 (fl. 598 c 1 A) y 050-1039518 &nbsp;(fl. 599)\u226b &nbsp;y \u226aciertamente &nbsp;los dos predios pedidos por el demandante, no se identifican con el &nbsp;que dicen detentar Industrias y Cr\u00e9ditos S.A. a t\u00edtulo &nbsp;de tenencia y Basora S.A. como poseedora\u226b. &nbsp;<\/p>\n<p>2.- &nbsp;Destaca el Tribunal las manifestaciones realizadas por la sociedad &nbsp;Inversionistas Asociados Basora S.A., en el desarrollo de la &nbsp;diligencia de inspecci\u00f3n judicial, practicada el 5 de octubre &nbsp;de 2000, a cuya pr\u00e1ctica se opuso aduciendo, que \u226ano &nbsp;existen los elementos necesarios, la claridad suficiente para llevar &nbsp;a cabo la &nbsp;identificaci\u00f3n f\u00edsica del predio o predios materia &nbsp;objeto de la reivindicaci\u00f3n deprecada y que son motivo de esta &nbsp;diligencia, tal como obra en el expediente los planos base de los &nbsp;predios antes se\u00f1alados fueron desincorporados de la oficina &nbsp;de planeaci\u00f3n distrital lo cual impone que no hay elementos &nbsp;claros para llevar a cabo tal identificaci\u00f3n m\u00e1xime &nbsp;cuando tales predios se superponen a un predio totalmente distinto &nbsp;respecto del cual existen debidamente acreditados los planos &nbsp;expedidos por planeaci\u00f3n y catastro distrital y adem\u00e1s &nbsp;acompa\u00f1ados de una tradici\u00f3n intachable que se proyecta &nbsp;m\u00e1s all\u00e1 de treinta a\u00f1os, circunstancia que &nbsp;brilla por su audiencia (sic) respecto de los predios que se &nbsp;pretenden identificar\u2026\u226b, &nbsp;as\u00ed como de los t\u00edtulos antecedentes que soportan los &nbsp;derechos que esgrime. &nbsp;<\/p>\n<p>Manifestaciones &nbsp;con las cuales, al decir del Tribunal, Basora S.A. \u201cniega &nbsp;su calidad de poseedora de los lotes Nos. 2 y &nbsp;3\u201d; &nbsp;trasladando as\u00ed la carga demostrativa de dicho supuesto al &nbsp;extremo activo, quien no la satisfizo. &nbsp;<\/p>\n<p>3.- &nbsp;Apunt\u00f3 el juzgador que se practicaron tres (3) inspecciones &nbsp;judiciales y tres (3) experticias \u2013haciendo referencia a las &nbsp;incidencias m\u00e1s relevantes en su desarrollo, con miras a la &nbsp;identificaci\u00f3n de los terrenos a reivindicar- de cuyo &nbsp;escrutinio coligi\u00f3, que \u226apese &nbsp;a los ingentes esfuerzos por lograr la identificaci\u00f3n de los &nbsp;predios que tratan los procesos \u2013inicial y acumulado. Ese &nbsp;prop\u00f3sito no se logr\u00f3\u226b. &nbsp;<\/p>\n<p>4.- &nbsp;Procedi\u00f3 seguidamente el Tribunal a rese\u00f1ar las &nbsp;declaraciones rendidas en el curso de la instancia por los se\u00f1ores &nbsp;Gilberto Sanclemente Vel\u00e1squez, Fernando Morales, Eduardo &nbsp;Arango V\u00e9lez, Myriam Yolanda Mendoza Pedraza y Jos\u00e9 &nbsp;Gabriel N\u00fa\u00f1ez Remolina, respecto de las cuales &nbsp;considera, \u226ano &nbsp;reporta la prueba exigida para casos semejantes, como que ninguna de &nbsp;ellas da cuenta de la forma como Industrias y Cr\u00e9ditos S.A. &nbsp;hasta el \u201ca\u00f1o 91\u201d; y luego, la sociedad Basora &nbsp;S.A. hasta la actualidad, desarrollaron la posesi\u00f3n de &nbsp;aquellos lotes Nos. 2 y 3 en los t\u00e9rminos definidos en cada &nbsp;uno de los libelos actores, los testigos se limitaron a relatar la &nbsp;forma como los demandantes detentaban tales predios, la vigilancia &nbsp;que de ellos ejerc\u00edan por su cuenta y el hecho de la &nbsp;existencia del proceso de deslinde y amojonamiento que adelant\u00f3 &nbsp;la demandada Industrias y Cr\u00e9ditos S.A., nada m\u00e1s\u226b. &nbsp;<\/p>\n<p>5.- &nbsp;Concluy\u00f3 diciendo, que \u226ael &nbsp;an\u00e1lisis de pruebas, seg\u00fan estimaci\u00f3n que &nbsp;precede, pone al descubierto dos situaciones puntuales; una, que no &nbsp;se arrim\u00f3 medio probatorio que pusiera en cabeza de las &nbsp;sociedades industrias y Cr\u00e9ditos S.A. y Basora S.A., la &nbsp;posesi\u00f3n de los predios denominados lotes 2 y 3, con &nbsp;matr\u00edculas inmobiliarias Nos. 050-1079044 y 050-1046714, &nbsp;respectivamente; y otra, que ciertamente no se obtuvo la plena &nbsp;identificaci\u00f3n de los inmuebles en menci\u00f3n. De manera &nbsp;que no se acreditaron los dos presupuestos axiol\u00f3gicos de la &nbsp;acci\u00f3n de dominio\u226b. &nbsp;<\/p>\n<p>III. &nbsp;LA DEMANDA DE CASACI\u00d3N &nbsp;<\/p>\n<p>\u00daNICO &nbsp;CARGO &nbsp;<\/p>\n<p>Con &nbsp;apoyo en la causal primera denunci\u00f3 la vulneraci\u00f3n &nbsp;indirecta por aplicaci\u00f3n indebida de los art\u00edculos 762, &nbsp;946 del C\u00f3digo Civil. Y por falta de aplicaci\u00f3n de los &nbsp;art\u00edculos 665, 669, 673, 740, 754, 756, 947, inc. 1, 950, 952, &nbsp;961, 962, 963, 964, 969, 2527, 2531 y 2532 del mismo estatuto, a &nbsp;consecuencia de errores de hecho en la apreciaci\u00f3n de los &nbsp;elementos de convicci\u00f3n, al no dar por demostrado, est\u00e1ndolo: &nbsp;(i.) &nbsp;La identidad jur\u00eddica entre el bien pose\u00eddo por una de &nbsp;las accionadas con aquel del cual es propietario Sanclemente, &nbsp;Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. (ii.) &nbsp;Que Inversionistas Asociados Basora S.A. (en liquidaci\u00f3n) es &nbsp;poseedora del bien objeto de reivindicaci\u00f3n. (iii.) &nbsp;Que Inversionistas Asociados Basora S.A. (en liquidaci\u00f3n) &nbsp;reconoci\u00f3 ser poseedora material, al alegar la prescripci\u00f3n &nbsp;adquisitiva. &nbsp;<\/p>\n<p>En &nbsp;su desarrollo, razon\u00f3: &nbsp;<\/p>\n<p>1.- &nbsp;El Tribunal hizo una mala apreciaci\u00f3n de las declaraciones de &nbsp;los se\u00f1ores Eduardo Arango V\u00e9lez (fls. &nbsp;758-761) &nbsp;y Gilberto Sanclemente Vel\u00e1squez (fls. &nbsp;556-557), &nbsp;as\u00ed como de la Escritura P\u00fablica N\u00b0 3077 de 24 de &nbsp;noviembre de 1988, otorgada en la Notar\u00eda 33 de Bogot\u00e1, &nbsp;junto con el plano 284-1-04 de Planeaci\u00f3n Distrital, que se &nbsp;protocoliz\u00f3 con dicho instrumento (fls. &nbsp;17-38), &nbsp;de la inspecci\u00f3n judicial realizada el d\u00eda 15 de abril &nbsp;de 2004 (fls. &nbsp;1097-1098), &nbsp;del dictamen pericial rendido por los peritos Jos\u00e9 Manuel &nbsp;Gonz\u00e1lez y Orlando Duque, de fecha enero 18 de 1999 (fl. &nbsp;65 Cd 14), &nbsp;y del informe t\u00e9cnico de la Unidad Administrativa Especial de &nbsp;Catastro Distrital e Instituto Geogr\u00e1fico Agust\u00edn &nbsp;Codazzi (fls. &nbsp;1881 y s.s.). &nbsp;Adem\u00e1s, porque no apreci\u00f3 la contestaci\u00f3n del &nbsp;libelo hecha por Inversionistas Asociados Basora S.A. en liquidaci\u00f3n &nbsp;(fls. &nbsp;1881 y s.s.). &nbsp;<\/p>\n<p>Errores &nbsp;que llevaron al Tribunal a concluir erradamente que, no se demostr\u00f3 &nbsp;\u201cla &nbsp;posesi\u00f3n del bien materia objeto de reivindicaci\u00f3n por &nbsp;el demandado y la identidad del bien pose\u00eddo con aquel del &nbsp;cual es propietario las demandantes\u201d &nbsp;(sic), lo que sostiene no es cierto, porque: &nbsp;<\/p>\n<p>a.-) &nbsp;El testigo Eduardo V\u00e9lez Arango manifest\u00f3: \u201cPREGUNTADO: &nbsp;Diga el testigo si le consta y por qu\u00e9 motivo de que &nbsp;INDUSTRIAS Y CREDITOS S.A., se haya hecho a la posesi\u00f3n del &nbsp;lote N\u00b0 2 materia de este proceso. CONTEST\u00d3: INDUSTRIAS Y &nbsp;CREDITOS hizo un juicio de deslinde y amojonamiento contra estos &nbsp;lotes y ese juicio o desde ese juicio de deslinde y amojonamiento fue &nbsp;que se hicieron a la posesi\u00f3n de estos lotes, antes no, &nbsp;eso fue m\u00e1s o menos en el 91, en esos lotes antes hab\u00edan &nbsp;(sic) sus celadores y todo, ah\u00ed no hab\u00eda INDUSTRIAS Y &nbsp;CREDITOS\u201d. &nbsp;<\/p>\n<p>El &nbsp;se\u00f1or Gilberto Sanclemente Vel\u00e1squez se\u00f1al\u00f3: &nbsp;\u201cPREGUNTADO: &nbsp;Diga el testigo si le consta y en caso afirmativo hacernos un relato &nbsp;sucinto de la forma en que INDUSTRIAS Y CR\u00c9DITOS S.A., se hizo &nbsp;a la posesi\u00f3n de esos lotes, incluyendo el 2. De este proceso. &nbsp;CONTESTO: Si me consta porque quien se encontraba como celador MOISES &nbsp;CRUZ, fue sacado del lote que celaba a cuidaba por funcionarios de &nbsp;esa empresa y me acuerdo mucho que fue a la oficina de ANTONIO &nbsp;SANCLEMENTE como a las cinco de la tarde a informar lo sucedido, o &nbsp;sea lo despojaron de su cargo en cuanto a la celadur\u00eda y &nbsp;tumbaron una caseta donde \u00e9l se guarnec\u00eda de las &nbsp;inclemencias del clima.\u201d &nbsp;<\/p>\n<p>De &nbsp;dichas manifestaciones adujo, que es claro que el primer poseedor de &nbsp;mala fe fue Industrias y Cr\u00e9ditos S.A., quien transfiri\u00f3 &nbsp;la posesi\u00f3n a Inversionistas Asociados Basora S.A., \u201craz\u00f3n &nbsp;por la cual no se encuentra impedimento a lo expresado en los &nbsp;testimonios citados para demostrar la posesi\u00f3n del bien en &nbsp;cabeza del demandado\u201d. &nbsp;<\/p>\n<p>b.-) &nbsp;El Tribunal no tuvo en cuenta la postura asumida por Inversionistas &nbsp;Asociados Basora S.A. frente a la demanda, \u201cpor &nbsp;una parte al proponer la Excepci\u00f3n perentoria de prescripci\u00f3n &nbsp;adquisitiva y por otra, al confesar ser poseedora del predio N\u00b0 3 &nbsp;de propiedad de mi asistido\u201d. &nbsp;<\/p>\n<p>Lo &nbsp;anterior, por cuanto al hecho 12 respondi\u00f3: \u201cNo &nbsp;es cierto, la poseedora del inmueble es mi mandante\u201d; &nbsp;y frente al hecho 6 replic\u00f3 diciendo: \u201cNo &nbsp;es cierto, mi mandante est\u00e1 en posesi\u00f3n del inmueble &nbsp;desde que se lo transfiri\u00f3 Industrias y Cr\u00e9ditos\u201d. &nbsp;Encontr\u00e1ndose de esta manera demostrada \u201cla &nbsp;condici\u00f3n de poseedora de mala fe que tiene la demandada &nbsp;respecto del inmueble a reivindicar\u201d. &nbsp;<\/p>\n<p>Esa &nbsp;condici\u00f3n de poseedora de mala fe, aduce, se reafirma \u201ccon &nbsp;la sola formulaci\u00f3n por la demandada en el escrito de &nbsp;contestaci\u00f3n de demanda de la excepci\u00f3n de prescripci\u00f3n &nbsp;adquisitiva respecto del bien, lo que supone una absoluta confesi\u00f3n &nbsp;de su condici\u00f3n de poseedora de mala fe respecto del bien que &nbsp;se reivindica\u201d, &nbsp;exceptiva que, adicionalmente, tiene el triple efecto de: (a.) &nbsp;Poner de presente la condici\u00f3n de poseedor de mala fe (b.) &nbsp;Constituye plena prueba de la identidad f\u00edsica del lote que se &nbsp;reivindica con el que admite poseer el demandado. (c.) &nbsp;Constituye aceptaci\u00f3n respecto de una condici\u00f3n de no &nbsp;propietario, que aunada a la prueba de propiedad por parte del &nbsp;demandante, exige la prosperidad de la pretensi\u00f3n &nbsp;reivindicatoria. &nbsp;<\/p>\n<p>c.-) &nbsp;Luego de referir las conclusiones que obtuvo el Tribunal frente a la &nbsp;inspecci\u00f3n judicial llevada a cabo el 15 de abril de 2004, &nbsp;afirm\u00f3: \u201cOtra &nbsp;cosa consideramos se observa de la diligencia de inspecci\u00f3n &nbsp;judicial, donde el juez logr\u00f3 constatar que existe identidad &nbsp;entre el bien a reivindicar y el bien pose\u00eddo, a la vez que se &nbsp;observa que en la diligencia se realiz\u00f3 un reconocimiento y &nbsp;descripci\u00f3n del bien a reivindicar expresando en ella: &nbsp;<\/p>\n<p>\u201cSobre &nbsp;este predio no se observa, construcci\u00f3n alguna, est\u00e1 &nbsp;cubierto por peque\u00f1os arbustos y algunos \u00e1rboles, por &nbsp;el costado que colinda con la transversal primera o costado oriental, &nbsp;se observa cerca del alambre ca\u00edda, POR EL COSTADO que colinda &nbsp;con terrenos que dice son del Idu tambi\u00e9n se observa cerca de &nbsp;alambre al igual que por el costado de la Avenida Circunvalar. Por el &nbsp;costado no existe cerca alguna. De esta manera el Despacho deja &nbsp;determinado el inmueble inspeccionado en relaci\u00f3n con los &nbsp;puntos solicitados a verificar por el demandante\u2026\u201d\u201d. &nbsp;<\/p>\n<p>A &nbsp;partir de lo anterior manifest\u00f3, que \u201c[E]s &nbsp;claro entonces que el juez ha podido observar de primera mano con &nbsp;ayuda de los auxiliares de justicia que existe identidad entre el &nbsp;bien que solicita se reivindique y el bien pose\u00eddo por el &nbsp;demandado, que en este caso es la sociedad BASORA S.A.\u201d. &nbsp;<\/p>\n<p>d.-) &nbsp;Dijo, que \u201clos &nbsp;informes t\u00e9cnicos obrantes a partir del folio 1881 por parte &nbsp;de la Unidad Administrativa Especial de Catastro Distrital y el &nbsp;Instituto Agust\u00edn Codazzi, permiten sostener, que, no obstante &nbsp;los cambios generados como consecuencia de la terminaci\u00f3n del &nbsp;proceso de actualizaci\u00f3n catastral que determinaron la &nbsp;desincorporaci\u00f3n de varios predios del censo catastral, la &nbsp;existencia f\u00edsica del lote que se reivindica es innegable y el &nbsp;mismo informe lo ratifica. Esta desincorporaci\u00f3n de que da &nbsp;noticia la entidad distrital tiene simples prop\u00f3sitos &nbsp;estad\u00edsticos, y en nada afectan ni la titularidad ni mucho &nbsp;menos la existencia f\u00edsica del objeto de reivindicaci\u00f3n\u201d. &nbsp;Apoy\u00f3 &nbsp;esta aseveraci\u00f3n en el contenido del art\u00edculo 18 de la &nbsp;Resoluci\u00f3n 2555 de 1988, tras lo cual apunt\u00f3, que \u201ccomo &nbsp;se advirti\u00f3 durante la actuaci\u00f3n procesal el concepto &nbsp;remitido por Catastro Distrital, no tiene el alcance de dictamen &nbsp;pericial, y surge dentro del proceso como una prueba m\u00e1s de la &nbsp;existencia y plena identidad de los lotes que se reivindican, m\u00e1s &nbsp;no pueden ser objeto del tratamiento de dictamen pericial con el que &nbsp;la demandada ha pretendido seguir agregando confusi\u00f3n a esta &nbsp;causa\u2026\u201d. En &nbsp;ese orden, -se asever\u00f3- el Tribunal apreci\u00f3 &nbsp;err\u00f3neamente la Escritura 3077 de 24 de noviembre de 1988 &nbsp;otorgada en la Notar\u00eda 33 de Bogot\u00e1 junto con el plano &nbsp;284-1-04 de Planeaci\u00f3n Distrital que se protocoliz\u00f3 con &nbsp;dicho instrumento. &nbsp;<\/p>\n<p>e.-) &nbsp;El Tribunal descalific\u00f3 la experticia rendida por los peritos &nbsp;Jos\u00e9 Manuel Gonz\u00e1lez y Orlando Duque, del 18 de enero &nbsp;de 1999 (fl. &nbsp;65 Cd 14), &nbsp;en la cual, seg\u00fan su sentir, \u00e9stos \u201cidentificaron &nbsp;y alinderaron el lote n\u00famero 3\u2026 lo cual demuestra la &nbsp;singularidad de la cosa a reivindicar\u201d, &nbsp;por lo que sostuvo, que \u201cresultan &nbsp;evidentes los errores de hecho en que incurri\u00f3 el tribunal al &nbsp;valorar este medio de prueba, que de haberse evaluado correctamente &nbsp;seguro hubiese accedido a las pretensiones\u201d. &nbsp;<\/p>\n<p>Concluy\u00f3 &nbsp;diciendo, que \u201cdentro &nbsp;de esta causa y desde la demanda se pueden observar los linderos del &nbsp;inmueble, al igual que en la escritura p\u00fablica y se anex\u00f3 &nbsp;el certificado, a la vez, se ha demostrado que efectivamente existe &nbsp;identidad entre el bien que se pretende reivindicar y del bien que el &nbsp;demandado de forma irregular ha ejercido la posesi\u00f3n\u201d. &nbsp;<\/p>\n<p>\u201cEn &nbsp;efecto se afirma que se encuentra demostrado este presupuesto de la &nbsp;acci\u00f3n reivindicatoria, ya que existe plena prueba en el caso &nbsp;que nos ocupa, como lo es la inspecci\u00f3n judicial citada, ya &nbsp;que el Juez por ser testigo directo de las circunstancias encontradas &nbsp;en el bien objeto de reivindicaci\u00f3n dar\u00e1n plena fe de &nbsp;las situaciones, es decir, de la posesi\u00f3n por parte del &nbsp;demandado en el terreno singular que se pretende reivindicar\u201d. &nbsp;<\/p>\n<p>IV. &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1.- &nbsp;Resulta necesario precisar, de manera liminar, que el C\u00f3digo &nbsp;de Procedimiento Civil es el llamado a gobernar la definici\u00f3n &nbsp;del asunto sub &nbsp;examine. &nbsp;<\/p>\n<p>2.- &nbsp; Conforme qued\u00f3 expuesto en precedencia, la sociedad &nbsp;Sanclemente, Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A., &nbsp;reclamaron de la jurisdicci\u00f3n, se declarara que es la titular &nbsp;del derecho pleno de dominio y posesi\u00f3n del lote de terreno &nbsp;denominado n\u00famero tres (3), distinguido anteriormente con el &nbsp;n\u00famero 59-12 de la carrera 3\u00aa, actualmente con el n\u00famero &nbsp;3-15 de la calle 60 o Avenida Circunvalar, con c\u00e9dula &nbsp;catastral N\u00b0 59- T-1-3 antes 53-7 E-25 y matr\u00edcula &nbsp;inmobiliaria N\u00b0 &nbsp;050-1079044, &nbsp;que actualmente est\u00e1 en posesi\u00f3n de la llamada a juicio &nbsp;y se le ordene a \u00e9sta su restituci\u00f3n, junto con los &nbsp;frutos a que haya lugar, as\u00ed como la cancelaci\u00f3n de los &nbsp;grav\u00e1menes que se hubieran constituido sobre el mismo. &nbsp;<\/p>\n<p>3.- &nbsp;Las citadas pretensiones fueron negadas en la primera instancia. &nbsp;Decisi\u00f3n que el Tribunal confirm\u00f3 al desatar la r\u00e9plica &nbsp;vertical, que en su momento present\u00f3 Sanclemente, &nbsp;Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. &nbsp;<\/p>\n<p>4.- &nbsp;La impugnante &nbsp;adujo &nbsp;que tal fallo incurri\u00f3 en evidentes errores en la apreciaci\u00f3n &nbsp;de algunas de las pruebas que fueron incorporadas al tr\u00e1mite, &nbsp;las que considera, contrario a lo indicado por el Tribunal, s\u00ed &nbsp;demuestran la identidad del predio que se pretende reivindicar con el &nbsp;pose\u00eddo por la demandada y la posesi\u00f3n misma que \u00e9sta &nbsp;ostenta, de mala fe. &nbsp;<\/p>\n<p>5.- &nbsp;De vieja data, se ha indicado por esta Corporaci\u00f3n que la &nbsp;censura de las sentencias por la v\u00eda indirecta, &nbsp;en la modalidad de error de hecho en la valoraci\u00f3n probatoria, &nbsp;tiene lugar cuando el juzgador supone, omite o altera el contenido de &nbsp;las pruebas, siempre y cuando dicha anomal\u00eda tenga incidencia &nbsp;en la forma en que se defini\u00f3 el debate, de tal manera que de &nbsp;no haber existido, indiscutiblemente, otro ser\u00eda el resultado. &nbsp;<\/p>\n<p>En &nbsp;consonancia, con esto, el yerro endilgado debe aparecer palmario o &nbsp;demostrado con contundencia. Sin desconocer que el juez de &nbsp;conocimiento en su labor\u00edo goza de una discreta autonom\u00eda &nbsp;para apreciar &nbsp;el caudal probatorio arrimado al juicio, acorde con los postulados de &nbsp;la sana cr\u00edtica. Esto es, bajo el apremio de estimarlos con &nbsp;soporte en el sentido com\u00fan, la l\u00f3gica y las reglas &nbsp;tanto de la ciencia, como de la experiencia. &nbsp;<\/p>\n<p>En &nbsp;ese orden, cuando la censura se enfila por la causal primera del &nbsp;art\u00edculo 368 del C\u00f3digo de Procedimiento Civil, por la &nbsp;v\u00eda indirecta, sobre la base de haberse cometido un error de &nbsp;hecho en la apreciaci\u00f3n de las pruebas, su acreditaci\u00f3n &nbsp;presupone, entre otras exigencias, que la inferencia probatoria &nbsp;atacada sea abiertamente contraria al contenido objetivo de la &nbsp;prueba. &nbsp;<\/p>\n<p>Esto &nbsp;significa que \u00fanicamente se abrir\u00e1 paso la acusaci\u00f3n, &nbsp;en la medida en que el yerro devenga tan evidente que -sin mayor &nbsp;esfuerzo-, quede expuesto. Valga decir, que sea perceptible a simple &nbsp;vista y de tal magnitud que resulte ostensiblemente contrario a lo &nbsp;que revela el expediente. &nbsp;<\/p>\n<p>Por &nbsp;eso se ha dicho, que \u201cel &nbsp;error de hecho, al cual, como motivo de casaci\u00f3n, alude el &nbsp;inciso segundo del numeral primero del art\u00edculo 368 del C\u00f3digo &nbsp;de Procedimiento Civil, puede tener lugar cuando el juzgador supone o &nbsp;pretermite la prueba. Incurrir\u00e1 en lo primero, cuando se funda &nbsp;en un medio en verdad inexistente o cuando distorsiona el contenido &nbsp;del obrante en el proceso, para darle un significado que no contiene. &nbsp;Caer\u00e1 en lo segundo, cuando ignora del todo la presencia del &nbsp;elemento de juicio debidamente incorporado al plenario o lo cercena, &nbsp;para, en esta \u00faltima hip\u00f3tesis, asignarle una &nbsp;significaci\u00f3n contraria o diversa\u201d. &nbsp;<\/p>\n<p>\u201cEn &nbsp;palabras de la Corte, este dislate \u00ab(\u2026) ata\u00f1e a &nbsp;la prueba como elemento material del proceso, por creer el &nbsp;sentenciador que existe cuando falta, o que falta cuando existe, y &nbsp;debido a ella da por probado o no probado el hecho (\u2026)\u00bb1. &nbsp;Denunciada una o todas de las anteriores posibilidades, el acusador &nbsp;ha de demostrar que la equivocaci\u00f3n atribuida al Juzgador es &nbsp;evidente y, adem\u00e1s, trascendente por haber determinado la &nbsp;decisi\u00f3n reprochada, de tal forma que de no haberse ca\u00eddo &nbsp;en esa sinraz\u00f3n muy otra hubiera sido el resultado final.\u201d &nbsp;(CSJ SC 10825-2016 de 8 de agosto de 2016, Rad. 2011-00213-01). &nbsp;<\/p>\n<p>Resulta &nbsp;relevante para el caso en estudio lo referente a la identidad de la &nbsp;cosa que se pretende reivindicar. Sobre el particular esta Corte ha &nbsp;indicado, que: &nbsp;<\/p>\n<p>\u201cLa &nbsp;determinaci\u00f3n y singularidad de la cosa pretendida &nbsp;circunscribe el campo de la acci\u00f3n reivindicatoria, porque &nbsp;como lo tiene dicho la Corte, \u2018cuando la cosa que se intenta &nbsp;reivindicar no se ha podido determinar no se puede decretar la &nbsp;reivindicaci\u00f3n\u2019. De modo que este elemento atisba a la &nbsp;seguridad y certeza de la decisi\u00f3n, am\u00e9n de su &nbsp;entronque \u00edntimo con el derecho protegido, pues no puede &nbsp;olvidarse que trat\u00e1ndose de la acci\u00f3n reivindicatoria, &nbsp;tutela del derecho real de dominio y expresi\u00f3n del ius &nbsp;persequendi, la determinaci\u00f3n misma de la cosa se torna en &nbsp;elemento sine qua non, porque el derecho real de dominio s\u00f3lo &nbsp;puede hacerse realidad como poder directo y efectivo sobre una cosa &nbsp;determinada, es decir, una cosa individualizada como un cuerpo &nbsp;cierto\u201d &nbsp;(CSJ &nbsp;SC de &nbsp;14 de marzo de 1997, Rad. 3692). &nbsp;<\/p>\n<p>7.- &nbsp;Desacierta el censor en los reproches que formula al Tribunal, &nbsp;relativos a la comisi\u00f3n de errores de hecho. &nbsp;<\/p>\n<p>7.1. &nbsp;Adujo que se equivoc\u00f3 el Tribunal al no dar &nbsp;por demostrado, est\u00e1ndolo: (i.) &nbsp;la identidad jur\u00eddica entre el bien pose\u00eddo por una de &nbsp;las sociedades demandadas con aquel del cual es propietario &nbsp;Sanclemente, Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A.; (ii.) &nbsp;que Inversionistas Asociados Basora S.A. (en liquidaci\u00f3n) es &nbsp;poseedora del inmueble objeto de reivindicaci\u00f3n; y (iii.) &nbsp;que al alegar la prescripci\u00f3n adquisitiva Inversionistas &nbsp;Asociados Basora S.A. (en liquidaci\u00f3n) reconoci\u00f3 ser &nbsp;poseedora material. &nbsp;<\/p>\n<p>7.2. &nbsp;Errores que se soportan en lo siguiente: no haberse apreciado &nbsp;adecuadamente los testimonios de los se\u00f1ores Eduardo Arango &nbsp;V\u00e9lez y Gilberto Sanclemente Vel\u00e1squez. Empero, es lo &nbsp;cierto es que, m\u00e1s all\u00e1 de la eficacia probatoria que &nbsp;pudiera reconocerse a la prueba testimonial para la identificaci\u00f3n &nbsp;de un inmueble, las mencionadas juramentadas no fueron las \u00fanicas &nbsp;declaraciones que soportaron la decisi\u00f3n de instancia. En &nbsp;efecto, el Tribunal valor\u00f3 las rendidas por Fernando Morales, &nbsp;Myriam Yolanda Mendoza Pedraza y Jos\u00e9 Gabriel N\u00fa\u00f1ez &nbsp;Remolina, de las cuales estim\u00f3 que no resultaron eficaces para &nbsp;la demostraci\u00f3n de la posesi\u00f3n del denominado lote &nbsp;n\u00famero 3 por parte de Industrias y Cr\u00e9ditos S.A. e &nbsp;Inversionistas Asociados Basora S.A. &nbsp;<\/p>\n<p>El &nbsp;primero de los testimonios, que se dice mal apreciados -el de Eduardo &nbsp;V\u00e9lez Arango-, refiere a un antecedente de dominio que en su &nbsp;momento tuvo la sociedad Urbanizaci\u00f3n El Bosque Calder\u00f3n &nbsp;Barriga S.A. &nbsp;<\/p>\n<p>En &nbsp;efecto, con relaci\u00f3n a esta \u00faltima, se hizo alusi\u00f3n &nbsp;a la acci\u00f3n judicial de deslinde y amojonamiento. Empero, todo &nbsp;lo anterior no revela inequ\u00edvocamente que esas acciones &nbsp;hubieran sido adelantadas sobre terrenos que no fueran propiedad de &nbsp;la demandada. Y de suyo, la posesi\u00f3n echada de menos respecto &nbsp;del predio de propiedad de la reclamante. &nbsp;<\/p>\n<p>El &nbsp;segundo, de Gilberto Sanclemente Vel\u00e1squez, respecto de la &nbsp;identidad, expres\u00f3 que \u201cquedaba &nbsp;en una curva en la avenida circunvalar de la cra 3\u00aa pegado al &nbsp;lote N\u00b0 2\u201d. &nbsp;Se refiri\u00f3 al \u201cdespojo\u201d &nbsp;practicado por cuenta de Industrias y Cr\u00e9ditos S.A., en la &nbsp;diligencia del a\u00f1o 1991, practicada en aquel juicio de &nbsp;deslinde y amojonamiento que curs\u00f3 ante el Juzgado Trece Civil &nbsp;del Circuito de esta Ciudad. &nbsp;<\/p>\n<p>Al &nbsp;entrar en mayores detalles, el deponente asever\u00f3 que los lotes &nbsp;2 y 3, durante varios a\u00f1os, permanecieron cercados por cuenta &nbsp;de la estaci\u00f3n de polic\u00eda \u201chasta &nbsp;cuando la se\u00f1ora Garc\u00eda logr\u00f3 que le &nbsp;restituyeran esos lotes en el a\u00f1o 89 por parte de un juzgado &nbsp;el cual no recuerdo\u201d. &nbsp;As\u00ed y todo, no es posible establecer que aquella acci\u00f3n &nbsp;judicial, que por dem\u00e1s est\u00e1 cobijada por una &nbsp;presunci\u00f3n de legalidad y acierto, hubiera involucrado el &nbsp;predio de propiedad de Sanclemente, &nbsp;Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. &nbsp;En una palabra, no es posible aseverar que es incontestablemente &nbsp;sobre el relatado inmueble que los convocados ejercen su posesi\u00f3n &nbsp;y que, precisamente, corresponde a aquel que se pretende reivindicar. &nbsp;<\/p>\n<p>Luego, &nbsp;el juzgador no desatin\u00f3 en la apreciaci\u00f3n de dichas &nbsp;declaraciones: les confiri\u00f3 el valor que su exacto contenido &nbsp;ameritaban. En efecto, de ellas no pod\u00eda extraerse esa &nbsp;identidad necesaria entre lo pretendido y lo pose\u00eddo -que &nbsp;habilitase la reivindicaci\u00f3n-. &nbsp;<\/p>\n<p>7.3. &nbsp;Por &nbsp;su parte, la Escritura P\u00fablica N\u00b0 3077 de 24 de noviembre &nbsp;de 1988, otorgada en la Notar\u00eda 33 de Bogot\u00e1, junto con &nbsp;el plano 284-1-04 de Planeaci\u00f3n Distrital, que se protocoliz\u00f3 &nbsp;con \u00e9sta (fls. &nbsp;17-38), &nbsp;se debe recibir como un instrumento limitado a corregir y aclarar las &nbsp;medidas y linderos de los lotes que fueron objeto de las &nbsp;enajenaciones all\u00ed referidas. Entre estas, desde luego, &nbsp;aquella relacionada con el lote n\u00famero 3, realizada mediante &nbsp;la escritura p\u00fablica 7906 del 24 de noviembre de 1986 de la &nbsp;Notaria Segunda de Bogot\u00e1. En una palabra, los instrumentos &nbsp;referidos tampoco pod\u00edan ofrecer mayor aporte. &nbsp;<\/p>\n<p>7.4. &nbsp;En relaci\u00f3n con la &nbsp;inspecci\u00f3n judicial realizada el d\u00eda 15 de abril de &nbsp;2004 (fls. &nbsp;1097-1098), &nbsp;en la sentencia el Tribunal se refiere no solo a \u00e9sta, sino a &nbsp;las practicadas el 18 de marzo de 1997 y 5 de octubre de 2000. Se &nbsp;apunt\u00f3, lo que efectivamente acaeci\u00f3, que la Directora &nbsp;del proceso \u201cdispone &nbsp;que los auxiliares utilizando para tomar medidas cinta m\u00e9trica &nbsp;y varillas para fijar puntos de referencia y descripci\u00f3n &nbsp;f\u00edsica que coninside (sic) con el documento anexo al dictamen &nbsp;y visible a folio 64 del mismo (cuaderno marcado como dictamen &nbsp;percial (sic) febrero 15 de 1999 con 109 folios). Sobre este predio &nbsp;no se observa construcci\u00f3n alguna, est\u00e1 cubierto por &nbsp;peque\u00f1os arbustos y algunos \u00e1rboles, por el costado que &nbsp;colinda con la transversal primera o costado oriental, se observa &nbsp;cerca de alambre ca\u00edda, POR EL COSTADO que colinda con &nbsp;terrenos que dice son del Idu tambi\u00e9n se observa cerca de &nbsp;alambre al igual que por el costado de la avenida circunvalar. Por el &nbsp;costado sur no existe cerca alguna. De esta manera el despacho deja &nbsp;determinado el inmueble inspeccionado en relaci\u00f3n con los &nbsp;puntos solicitados por el demandante FERNANDO SANCLEMENTE y otro se &nbsp;corrige ANTONIO SANCLEMENTE folio 52 literales C y D con las &nbsp;constancias dejada por el despacho respecto a c\u00f3mo se observa &nbsp;el inmueble y sin que haya personas a las cuales sobre el mismo &nbsp;indagar sobre la raz\u00f3n de su presencia, dado que como el &nbsp;inmueble se dijo est\u00e1 desabitado (sic) se cumple por lo all\u00ed &nbsp;pedido\u201d. &nbsp;<\/p>\n<p>Por &nbsp;lo dem\u00e1s, el prop\u00f3sito de dicha prueba, de acuerdo con &nbsp;lo indicado en la demanda, era \u201cestablecer &nbsp;la identidad f\u00edsica del lote sobre el terreno, mediante &nbsp;constataci\u00f3n de sus linderos y cabida, seg\u00fan lo &nbsp;establecido en la Cl\u00e1usula Primera de la escritura No 2660 del &nbsp;20 de septiembre de 1989 de la Notar\u00eda 33 de Bogot\u00e1\u201d &nbsp;y los literales C y D, que all\u00ed se alude estaban encaminados a &nbsp;\u201cc.) &nbsp;Determinar que persona natural o jur\u00eddica se encuentra en &nbsp;posesi\u00f3n material del citado inmueble\u201d; \u201cd.)Indicar &nbsp;el estado actual de conservaci\u00f3n del inmueble\u201d. &nbsp;<\/p>\n<p>As\u00ed &nbsp;las cosas, el resultado de la diligencia -a lo sumo- pod\u00eda &nbsp;determinar la individualizaci\u00f3n del lote que se procuraba &nbsp;reivindicar. Sin embargo, no pod\u00eda revelar la cuestionada &nbsp;identidad con el pose\u00eddo por la demandada y, particularmente, &nbsp;esa posesi\u00f3n inequ\u00edvoca de \u00e9sta. Empero, como &nbsp;qued\u00f3 dicho, se dej\u00f3 constancia que no hab\u00eda &nbsp;construcci\u00f3n alguna y que estaba deshabitado (incluso, con las &nbsp;cercas ca\u00eddas). &nbsp;<\/p>\n<p>7.5. &nbsp;Por su parte el &nbsp;dictamen pericial, rendido por los peritos Jos\u00e9 Manuel &nbsp;Gonz\u00e1lez y Orlando Duque (18 de enero de 1999), alinder\u00f3 &nbsp;el predio objeto de la Litis as\u00ed: \u201cNorte: &nbsp;En l\u00ednea curva con la avenida circunvalar. Sur: &nbsp;En l\u00ednea recta con predios de la estaci\u00f3n segunda de &nbsp;polic\u00eda Departamento Tisquesusa. Oriente: &nbsp;En l\u00ednea curva con la transversal primera A y Occidente: &nbsp;En l\u00ednea curva con la avenida circunvalar\u201d. &nbsp;<\/p>\n<p>Empero, &nbsp;seguido de esto, se precis\u00f3 que \u201c[B]asados &nbsp;en un estudio pormenorizado de los documentos que hacen parte del &nbsp;expediente como son: Escrituras, matr\u00edculas inmobiliarias, &nbsp;certificados de tradici\u00f3n y libertad, planos estudios, etc., Y &nbsp;despu\u00e9s de efectuar una inspecci\u00f3n en el terreno, &nbsp;complement\u00e1ndolo con visitas e investigaciones realizadas al &nbsp;Geogr\u00e1fico Agust\u00edn Codazzi, a las oficinas de Registro &nbsp;de Instrumentos P\u00fablicos, Planeaci\u00f3n Distrital, &nbsp;Departamento Administrativo de Catastro Distrital (Unidad de &nbsp;Cartograf\u00eda), el &nbsp;inmueble identificado como lote #3 efectivamente se halla dentro del &nbsp;globo de terreno de mayor extensi\u00f3n identificado y descrito en &nbsp;la inspecci\u00f3n judicial. &nbsp;(Resalta la Corte). &nbsp;<\/p>\n<p>\u201c(\u2026) &nbsp;El lote de terreno conocido como lote n\u00famero tres (3) objeto &nbsp;de la demanda est\u00e1 ubicado en la parte final y al norte del &nbsp;globo de terreno descrito en la diligencia de inspecci\u00f3n &nbsp;judicial y coincide tambi\u00e9n con el descrito en la demanda e &nbsp;identificado en la escritura No. 2660 del veinte (20) de septiembre &nbsp;de 1989 de la Notar\u00eda Treinta y Tres (33) del C\u00edrculo &nbsp;de Bogot\u00e1 y el plano topogr\u00e1fico correspondiente &nbsp;protocolizado con dicha escritura. &nbsp;<\/p>\n<p>\u201cCabe &nbsp;resaltar que tambi\u00e9n coincide con la cabida y linderos &nbsp;estipulados en el folio de matr\u00edcula inmobiliaria &nbsp;#050-1079044\u201d. &nbsp;<\/p>\n<p>A\u00fan &nbsp;m\u00e1s, en el citado trabajo se trajo a cuento el contenido de &nbsp;varias escrituras, relacionadas con la tradici\u00f3n del predio, &nbsp;incluida la n\u00famero 7906 del 26 de diciembre de 1986, mediante &nbsp;la cual este le fue entregado en venta a Glor\u00eda Ider Garc\u00eda &nbsp;G\u00f3mez. Y, a rengl\u00f3n seguido, apuntaron que \u201cNosotros &nbsp;los peritos analizando la anterior escritura y ubicando el LOTE # 3 &nbsp;en el plano topogr\u00e1fico a escala 1:500 aceptado por el &nbsp;departamento Administrativo de Planeaci\u00f3n Distrital &nbsp;incorporado a las planchas J42 escala 1:2000 levantado por el &nbsp;top\u00f3grafo HELMUT CEDE\u00d1O R. las dimensiones, ni \u00e1rea, &nbsp;ni linderos, ni ubicaci\u00f3n coinciden con este lote\u201d. &nbsp;<\/p>\n<p>\u201cMotivo &nbsp;por el cual trascribimos lo que nos dice la escritura aclaratoria &nbsp;#3077 del veinticuatro (24) de noviembre de 1988 de la notar\u00eda &nbsp;Treinta y Tres del C\u00edrculo de Bogot\u00e1 D.E.\u201d. &nbsp;Que, como &nbsp;se rese\u00f1\u00f3 en precedencia, contiene una modificaci\u00f3n &nbsp;y aclaraci\u00f3n de medidas y linderos que de manera unilateral &nbsp;hicieran los adquirentes Gerardo Le\u00f3n Am\u00e9zquita Plaza, &nbsp;Gina Rodr\u00edguez Lanao y Glor\u00eda Garc\u00eda G\u00f3mez, &nbsp;sin la intervenci\u00f3n de su tradente Urbanizaci\u00f3n El &nbsp;Bosque Calder\u00f3n Barriga y C\u00eda. &nbsp;<\/p>\n<p>Se &nbsp;extienden los auxiliares en su historiar hasta la escritura 2660 de &nbsp;20 de septiembre de 1986 de la Notar\u00eda 33 de Bogot\u00e1, a &nbsp;trav\u00e9s de la cual la mencionada se\u00f1ora Garc\u00eda &nbsp;G\u00f3mez transfiere el dominio del lote n\u00famero 3 a &nbsp;Sanclemente, Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. &nbsp;Empero, como se advirti\u00f3, dan cuenta de la existencia de una &nbsp;superposici\u00f3n de predios y que, de suyo, fue referida en otras &nbsp;probanzas, entre ellas, la Resoluci\u00f3n 660 del 23 de diciembre &nbsp;de 1991 emitida por el Director del Departamento Administrativo de &nbsp;Planeaci\u00f3n Distrital. Precisamente, con esta Resoluci\u00f3n &nbsp;660 se resolvi\u00f3 \u201crevocar &nbsp;directamente el oficio DC-297-86 del 16 de diciembre de 1986, &nbsp;mediante el cual se acept\u00f3 la incorporaci\u00f3n del plano &nbsp;topogr\u00e1fico No. 284\/1-04 en las plantas a escala 1:2000 N\u00b0 &nbsp;J2 del Instituto Geogr\u00e1fico Agust\u00edn Codazzi\u201d. &nbsp;<\/p>\n<p>Sostuvo &nbsp;el censor que el Tribunal descalific\u00f3 la mencionada &nbsp;experticia, en la cual los auxiliares \u201cidentificaron &nbsp;y alinderaron el lote n\u00famero 3 \u2026 lo cual demuestra la &nbsp;singularidad de la cosa a reivindicar\u201d. &nbsp;Sin embargo, en modo alguno combate el argumento toral de la &nbsp;decisi\u00f3n, cual fue, la posesi\u00f3n de los convocados sobre &nbsp;el predio a reivindicar y la identidad de este con aquel de propiedad &nbsp;de Sanclemente, Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. &nbsp;<\/p>\n<p>7.6. &nbsp;En relaci\u00f3n con el informe remitido por la Unidad &nbsp;Administrativa Especial de Catastro Distrital, dicha entidad, con la &nbsp;comunicaci\u00f3n del 17 de septiembre de 2008, refiri\u00f3 la &nbsp;situaci\u00f3n catastral de los predios denominados, Lote 3 y Lote &nbsp;2 con matr\u00edculas 050C-1079044 y 050C-1046714, respectivamente, &nbsp;que formaban parte del Lote de mayor extensi\u00f3n n\u00famero &nbsp;7, del Lote n\u00famero 10 con matr\u00edcula 050C1203185, que se &nbsp;desenglob\u00f3 formando tres predios denominados Lotes A, B y de &nbsp;Cesi\u00f3n, con matr\u00edculas 050-1333120, 050C-1333121 y &nbsp;050C-1333122. Se precis\u00f3 que \u201cactualmente &nbsp;el lote A folio de matr\u00edcula inmobiliaria 050C1333120, no se &nbsp;encuentra incorporado cartogr\u00e1ficamente por presentar &nbsp;traslape, realizado el estudio jur\u00eddico, se verific\u00f3 &nbsp;que el \u00e1rea de este lote (A) se encuentra inmersa en el lote &nbsp;7\u201d &nbsp;y finaliz\u00f3 diciendo, que \u201cAl &nbsp;observar la manzana catastral digital (anexa) donde se indica la &nbsp;ubicaci\u00f3n del lote No. 7 y la ubicaci\u00f3n de los predios &nbsp;008215 10 09 y 008215 10 03 (lotes 2 y 3), se observa que estos &nbsp;forman parte del que se llam\u00f3 lote No. 7, igualmente se &nbsp;aprecia en el folio matriz 050C542513 que estos lotes fueron &nbsp;segregados seg\u00fan las anotaciones 18 y 19. No obstante lo &nbsp;anterior existe una zona de traslape de el (sic) lote No 7 con el &nbsp;lote A (segregado del lote No 10) de la Urbanizaci\u00f3n Bosque &nbsp;Calder\u00f3n como se muestra en la manzana catastral conservada. &nbsp;(anexa) como ya se manifest\u00f3 anteriormente\u201d. &nbsp;Todo lo anterior, evidencia la ya mencionada superposici\u00f3n de &nbsp;predios. &nbsp;<\/p>\n<p>Consecuente &nbsp;con lo indicado, no refulge evidente el yerro que se imputa al &nbsp;Tribunal. &nbsp;<\/p>\n<p>7.7. &nbsp;Punto importante de la censura es el relacionado con la no &nbsp;apreciaci\u00f3n por parte del Tribunal de la confesi\u00f3n &nbsp;contenida en la contestaci\u00f3n que hiciera Inversionistas &nbsp;Asociados Basora S.A. en liquidaci\u00f3n. En efecto, aduce que con &nbsp;la respuesta dada a los hechos sexto y d\u00e9cimo segundo del &nbsp;libelo inicial y la formulaci\u00f3n de la excepci\u00f3n de &nbsp;prescripci\u00f3n adquisitiva se genera, como efecto, la aceptaci\u00f3n &nbsp;de \u201cla &nbsp;condici\u00f3n de poseedora de mala fe que tiene la demandada &nbsp;respecto del inmueble a reivindicar, condici\u00f3n que inclusive, &nbsp;seg\u00fan lo que se ha puesto de presente ha sido aceptada de &nbsp;forma voluntaria por la demandada en el escrito de contestaci\u00f3n &nbsp;de demanda\u201d. &nbsp;Se sostuvo, seg\u00fan &nbsp;jurisprudencia &nbsp;de esta Corporaci\u00f3n, que ello \u201csupone &nbsp;una absoluta confesi\u00f3n de su condici\u00f3n de poseedora de &nbsp;mala fe respecto del bien que se reivindica\u201d, &nbsp;as\u00ed como tambi\u00e9n \u201cplena &nbsp;prueba de la identidad f\u00edsica del inmueble que se demanda &nbsp;reivindicar con el que acepta poseer el demandado\u201d &nbsp;y &nbsp;\u201caceptaci\u00f3n &nbsp;respecto de una condici\u00f3n de no propietario, que aunada a la &nbsp;prueba de propiedad por parte del demandante, exige la prosperidad de &nbsp;las pretensiones de la demanda reivindicatoria\u201d. &nbsp;<\/p>\n<p>Esta &nbsp;Colegiatura, frente al alcance que tiene la confesi\u00f3n para la &nbsp;demostraci\u00f3n de los presupuestos axiol\u00f3gicos de la &nbsp;acci\u00f3n reivindicatoria, particularmente en lo que hace a la &nbsp;posesi\u00f3n e identidad, ha dicho lo siguiente: &nbsp;<\/p>\n<p>\u201cBien &nbsp;es verdad que la jurisprudencia ha sostenido, y de continuo adem\u00e1s, &nbsp;que \u201ccuando el demandado en acci\u00f3n de dominio, al &nbsp;contestar la demanda inicial del proceso, confiesa ser el poseedor &nbsp;del inmueble en litigio, esa confesi\u00f3n tiene virtualidad &nbsp;suficiente para demostrar a la vez la posesi\u00f3n del demandado y &nbsp;la identidad del bien que es materia del pleito\u201d, tanto m\u00e1s &nbsp;si dentro de su gesti\u00f3n defensiva esgrime la prescripci\u00f3n &nbsp;extintiva (por todas se cita la que aparece en la G. J. CLXV, n\u00fam. &nbsp;2406, p. 125). &nbsp;<\/p>\n<p>Tr\u00e1tase &nbsp;de un derrotero cuya solidez es de probado reconocimiento, pues que &nbsp;aquilata lo que acontece las m\u00e1s de las veces. All\u00ed, &nbsp;simplemente, actor y reo est\u00e1n convenidos en que disputan un &nbsp;mismo bien, convirti\u00e9ndose en punto pac\u00edfico de la &nbsp;controversia. &nbsp;<\/p>\n<p>No significa, &nbsp;empero, que la cuesti\u00f3n ingrese as\u00ed en arca sellada &nbsp;para siempre, y adquiera la categor\u00eda de verdad inexpugnable, &nbsp;de tal suerte que sobre ella no se pueda volver la mirada; porque hay &nbsp;que convenir que, hoy por hoy, ninguna circunstancia, en tanto que &nbsp;forme parte del debate procesal, puede adquirir tama\u00f1a &nbsp;impermeabilidad y mir\u00e1rsela como verdad absoluta; as\u00ed y &nbsp;todo provenga de la denominada \u201creina de las pruebas\u201d, &nbsp;por supuesto que la confesi\u00f3n ya no ejerce el mismo imperio de &nbsp;anta\u00f1o, cuando se hablaba de una verdad suficiente, sin &nbsp;importar si acompasaba con la verdad verdadera. Es principio admitido &nbsp;ahora que la confesi\u00f3n es infirmable, seg\u00fan expresi\u00f3n &nbsp;paladina, en cuanto a nuestro ordenamiento respecta, del art. 201 del &nbsp;C\u00f3digo de Procedimiento Civil. &nbsp;<\/p>\n<p>As\u00ed que &nbsp;-regresando al punto de partida-, forzoso es concluir que la &nbsp;confesi\u00f3n del demandado en reivindicaci\u00f3n aquieta por &nbsp;lo pronto el litigio en cuanto a la identificaci\u00f3n de la cosa, &nbsp;para no aludir aqu\u00ed sino a lo que estrictamente hace al caso. &nbsp;Dicha confesi\u00f3n, en cuanto persista tal estado de cosas, &nbsp;\u201creleva al demandante de toda prueba sobre esos extremos de la &nbsp;acci\u00f3n y exonera al juzgador de analizar otras probanzas &nbsp;tendientes a demostrar la posesi\u00f3n\u201d, conforme agreg\u00f3 &nbsp;la Corte en la cita jurisprudencial acabada de hacer. &nbsp;<\/p>\n<p>Pero &nbsp;es claro que si la identificaci\u00f3n de la heredad no logra &nbsp;conseguirse finalmente, como ac\u00e1 sucedi\u00f3, el &nbsp;sosegamiento procesal se altera, torn\u00e1ndose en un escollo para &nbsp;el \u00e9xito de la acci\u00f3n reivindicatoria, sin poderse &nbsp;arg\u00fcir que, aun as\u00ed, se deban mantener a ultranza los &nbsp;efectos iniciales de confesi\u00f3n, porque ser\u00eda tanto como &nbsp;hacer primar la ficci\u00f3n a la realidad. Sucede sencillamente &nbsp;que en tal evento la confesi\u00f3n decae en su poder de convicci\u00f3n &nbsp;ante el resultado de las pruebas practicadas en desarrollo del &nbsp;litigio. (Sent. Cas. &nbsp;Civ. de 1\u00b0 de junio de 2001. Exp. 6286). &nbsp;<\/p>\n<p>Y &nbsp;ello es lo que ocurre en el presente caso, toda vez que el Tribunal &nbsp;no cuestion\u00f3 el car\u00e1cter de propietario que tiene la &nbsp;sociedad Sanclemente, &nbsp;Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A., respecto del lote &nbsp;n\u00famero 3, identificado con el folio de matr\u00edcula &nbsp;inmobiliaria 050-1079044 (adquirido por daci\u00f3n en pago, con &nbsp;escritura p\u00fablica 2660 de 20 de septiembre de 1989, otorgada &nbsp;en la Notar\u00eda 33 de Bogot\u00e1). El cuestionamiento se &nbsp;concentr\u00f3 en la identidad entre este particular predio con &nbsp;aquel pose\u00eddo por el extremo convocado. &nbsp;<\/p>\n<p>Lo &nbsp;anterior, por cuanto no puede olvidarse que la contestaci\u00f3n de &nbsp;la demanda, al igual que el libelo introductorio, deber\u00e1 ser &nbsp;interpretada y valorada por el juzgador en todo su contenido, no de &nbsp;manera sesgada o parcial. &nbsp;<\/p>\n<p>Por &nbsp;ello esta Corte ha dicho que ese ejercicio de interpretaci\u00f3n &nbsp;debe realizarse consultando &nbsp;la prevalencia del derecho sustancial, el acceso a la administraci\u00f3n &nbsp;de justicia y la soluci\u00f3n real de los conflictos, a partir de &nbsp;un an\u00e1lisis serio, fundado y razonable de todo su contenido &nbsp;\u201csiempre &nbsp;en conjunto, porque la intenci\u00f3n del actor est\u00e1 muchas &nbsp;veces contenida no s\u00f3lo en la parte petitoria, sino tambi\u00e9n &nbsp;en los fundamentos de hecho y de derecho\u201d &nbsp;y \u201c[n]o existe &nbsp;en nuestra legislaci\u00f3n procedimental un sistema r\u00edgido &nbsp;o sacramental que obligue al demandante a se\u00f1alar en &nbsp;determinada parte de la demanda o con f\u00f3rmulas especiales su &nbsp;intenci\u00f3n, sino que basta que ella aparezca claramente en el &nbsp;libelo, ya de una manera directa o expresa, ya por una interpretaci\u00f3n &nbsp;l\u00f3gica basada en todo el conjunto de la demanda\u201d &nbsp;(XLIV, p. 527; XIV, 488 y 833; LXI, 460; CXXXII, 241; CLXXVI, 182 y &nbsp;CCXXV, 2\u00aa parte, 185)\u201d &nbsp;(CSJ SC de 27 de agosto de 2008, [SC-084-2008]). &nbsp;<\/p>\n<p>Si &nbsp;ello es as\u00ed, no es dable pregonar que con las respuestas dadas &nbsp;por Industrias y Cr\u00e9ditos S.A. e Inversionistas Asociados &nbsp;Basora S.A. emerja la confesi\u00f3n que se alega, porque de ellas &nbsp;no se &nbsp;deduce claramente el reconocimiento sobre esa identidad necesaria &nbsp;respecto del lote de terreno objeto de la reivindicaci\u00f3n, ni &nbsp;su posesi\u00f3n sobre ese especifico bien. &nbsp;<\/p>\n<p>En &nbsp;efecto, el objeto de la daci\u00f3n en pago fue, el \u201cLote &nbsp;de terreno conocido como lote n\u00famero tres (3) y distinguido &nbsp;anteriormente con el n\u00famero cincuenta y nueve doce (59-12) de &nbsp;la carrera tercera (3\u00aa) del plano de la ciudad, que tiene cabida &nbsp;aproximada de ochocientos metros cuadrados (800,00 mts2) y se &nbsp;identifica por los siguientes linderos: partiendo del moj\u00f3n &nbsp;M-3, situado sobre el paramento Sur de la Avenida Circunvalar, se &nbsp;sigue en l\u00ednea curva, bordeando dicho paramento, direcci\u00f3n &nbsp;oriental y en una longitud de cuarenta metros con cincuenta y cuatro &nbsp;cent\u00edmetros (40,54 &nbsp;mts) hasta &nbsp;encontrar el moj\u00f3n M-4, situado sobre el mismo paramento; &nbsp;lindando en esta longitud por el norte con la Avenida Circunvalar. De &nbsp;este punto en l\u00ednea recta, direcci\u00f3n sur en una &nbsp;longitud de dieciocho metros con veintitr\u00e9s cent\u00edmetros &nbsp;(18,23 mts) &nbsp;hasta encontrar el moj\u00f3n M-5, situado sobre el paramento norte &nbsp;de la transversal primera (tv 1\u00aa) lindando en esa longitud por &nbsp;el oriente con terrenos de Eduardo Arango. De este punto en l\u00ednea &nbsp;curva, bordeando el paramento norte de la Transversal primera (1\u00aa) &nbsp;pasando por el moj\u00f3n M.5-A, direcci\u00f3n Sur-Occidental y &nbsp;en una longitud de veinticuatro (24.oo &nbsp;mts) hasta &nbsp;encontrar el moj\u00f3n M-6, lindando en esta longitud por el sur &nbsp;oriente con la Transversal Primera 91\u00aa) (sic). De este punto en &nbsp;l\u00ednea recta, direcci\u00f3n Nor-Occidental y en una longitud &nbsp;de treinta y cinco metros (35.oo &nbsp;mts) hasta &nbsp;encontrar el moj\u00f3n M-3, punto de partida y encierra; lindando &nbsp;en esta longitud por el Sur-Occidente con el lote n\u00famero dos &nbsp;(2) de propiedad de Gerardo Le\u00f3n Am\u00e9zquita Plaza y Gina &nbsp;Rodr\u00edguez Lanao\u201d. (Resalta &nbsp;la Corte). &nbsp;<\/p>\n<p>En &nbsp;tanto que, en el certificado de tradici\u00f3n de dicha heredad, &nbsp;por solo citar uno, se identifica as\u00ed: \u201cpor &nbsp;el NORTE: en l\u00ednea curva tiene treinta y cinco metros (35,00 &nbsp;mts). &nbsp;Circunvalar. POR EL ORIENTE: En l\u00ednea recta de diecinueve &nbsp;metros (19,00 &nbsp;mts) de &nbsp;longitud con predios de propiedad de la exponente. POR EL OCCIDENTE: &nbsp;En longitud de treinta y cinco (35,00 &nbsp;mts) de &nbsp;longitud con lote n\u00famero dos (2) de propiedad de GERARDO &nbsp;AM\u00c9ZQUITA Y OTRA. POR EL SUR: En l\u00ednea curva de &nbsp;veinticuatro metros (24,00 &nbsp;mts) de &nbsp;longitud con la calle cincuenta y nueve (59) o transversal primera &nbsp;(tv 1\u00aa)\u201d. De &nbsp;donde se infiere, l\u00f3gicamente, que no est\u00e1 debidamente &nbsp;demostrada la identidad o singularizaci\u00f3n general del &nbsp;mencionado predio. &nbsp;<\/p>\n<p>Por &nbsp;el otro, en la contestaci\u00f3n que hiciera Industrias y Cr\u00e9ditos &nbsp;S.A., \u00e9sta de manera previa da cuenta de \u201cla &nbsp;titulaci\u00f3n [de mi mandante] sobre el predio que posee y que se &nbsp;pretende reivindicar, es clara y di\u00e1fana, pues la cadena que &nbsp;lo leg\u00edtima se remonta al a\u00f1o 1953\u201d. &nbsp;Puso as\u00ed de presente la existencia de un derecho de dominio &nbsp;amparado en t\u00edtulo id\u00f3neo cuestionando, &nbsp;correlativamente, la validez y eficacia de los que esgrime &nbsp;Sanclemente, &nbsp;Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. &nbsp;As\u00ed las cosas, se opuso a las pretensiones. Dijo no ser cierto &nbsp;que aquella hubiera adquirido el predio que se pretend\u00eda &nbsp;reivindicar, sino \u201cotro &nbsp;distinto\u201d &nbsp;y que el tr\u00e1mite de deslinde y amojonamiento se llev\u00f3 a &nbsp;cabo con los colindantes del inmueble. Esto es, no acept\u00f3 &nbsp;poseer aquel predio de propiedad de Sanclemente, &nbsp;Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. &nbsp;<\/p>\n<p>En &nbsp;lo que hace con la excepci\u00f3n de prescripci\u00f3n, si bien &nbsp;no se discute su formulaci\u00f3n, no se puede obviar que para &nbsp;ello, muy sucintamente, reiter\u00f3 la condici\u00f3n de &nbsp;propietario y poseedor que tiene sobre el predio y la cadena de &nbsp;t\u00edtulos por un periodo superior a 20 a\u00f1os continuos, &nbsp;que aport\u00f3 al juicio para respaldar la condici\u00f3n &nbsp;alegada. Y remat\u00f3 diciendo, que \u201cen &nbsp;el remoto caso de que la viciada titulaci\u00f3n que pretende hacer &nbsp;valer para acreditar el dominio y propiedad por parte del actor &nbsp;fueran reconocidas, la acci\u00f3n reivindicatoria no podr\u00eda &nbsp;prosperar, por cuanto la prescripci\u00f3n alegada mediante esta &nbsp;excepci\u00f3n favorecer\u00eda a mi mandante\u201d. &nbsp;<\/p>\n<p>Por &nbsp;su parte la sociedad Inversionistas Asociados Basora S.A., desde 5 de &nbsp;octubre del a\u00f1o 2000, cuando se llev\u00f3 a cabo la &nbsp;diligencia de inspecci\u00f3n judicial sobre el predio, se opuso a &nbsp;la misma. Cuestion\u00f3 la inexistencia de elementos necesarios &nbsp;para la plena identificaci\u00f3n de los bienes, aduciendo \u201cm\u00e1xime &nbsp;cuando tales predios se superponen a un predio totalmente distinto &nbsp;respecto del cual existen debidamente acreditados los planos &nbsp;expedidos por planeaci\u00f3n y caastro (sic) &nbsp;distrital &nbsp;y adem\u00e1s acomp\u00f1ados (sic) &nbsp;de &nbsp;una t4adici\u00f3n (sic) &nbsp;intachable &nbsp;que se proyevta (sic) &nbsp;m\u00e1s &nbsp;all\u00e1 de treinta a\u00f1os\u201d. &nbsp;Y aport\u00f3 \u201ccopia &nbsp;de la escritura no. 4005 en la cual constan los linderos del lote &nbsp;donde nos encontramos\u201d, &nbsp;junto con el plano 732\/I-01 del Departamento Administrativo de &nbsp;Planeaci\u00f3n Distrital, de cuyo contenido considera \u201cse &nbsp;desprende clara y objetivamente que el lote donde nos encontramos &nbsp;pertenece por corpus y por titularidad a Basora S.A.\u201d. &nbsp;<\/p>\n<p>Cumplido &nbsp;esto, la citada sociedad se pronunci\u00f3 contra las pretensiones &nbsp;formuladas por Sanclemente, Fern\u00e1ndez y Hern\u00e1ndez &nbsp;Abogados S.A. Hizo, de manera inicial, una s\u00edntesis de lo &nbsp;actuado y del alcance de los t\u00edtulos aportados por los &nbsp;intervinientes en la Litis. Y asegur\u00f3, que \u201cel &nbsp;asunto debe resolverse de una manera simple y sencilla, como en &nbsp;efecto se solicitar\u00e1 acudiendo a lo dispuesto en el art. 243 &nbsp;numeral 3 del C.P.C., para que sea directamente el Departamento &nbsp;Administrativo de Catastro Distrital a trav\u00e9s de sus &nbsp;funcionarios, quien dictamine sobre la titulaci\u00f3n que sobre un &nbsp;mismo inmueble exhiben el demandado y el demandante y determine los &nbsp;linderos del lote10 y as\u00ed confirme que el predio y la &nbsp;titulaci\u00f3n correcta del mismo, no es otra diferente a la de mi &nbsp;poderdante\u201d. &nbsp;<\/p>\n<p>De &nbsp;igual forma dicha entidad afirm\u00f3, que \u201cacojo &nbsp;la respuesta dada por el se\u00f1or apoderado de Industrias y &nbsp;Cr\u00e9ditos\u201d &nbsp;y refut\u00f3 en los mismos t\u00e9rminos que aquella el alcance &nbsp;del dominio adquirido por Sanclemente, &nbsp;Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A, mediante &nbsp;la escritura p\u00fablica 2660 de 20 de septiembre de 1989 y la &nbsp;legalidad de los t\u00edtulos que conforman su tradici\u00f3n, y &nbsp;que soportan su acci\u00f3n. &nbsp;<\/p>\n<p>Al &nbsp;punto que, en la r\u00e9plica que realiz\u00f3 al hecho quinto, &nbsp;que refiere al dominio de Sanclemente, &nbsp;Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A., &nbsp;sostuvo: \u201cEs &nbsp;cierta, en cuanto que est\u00e1 inscrita en un folio en la oficina &nbsp;de Registro, pero desprendido y segregado del lote No. 7 y no del &nbsp;lote No. 10, al que corresponde el inmueble, que supuestamente se &nbsp;quiere reivindicar\u201d. &nbsp;Seguidamente, contra el hecho sexto, en el cual se alude a la &nbsp;privaci\u00f3n de la posesi\u00f3n del predio que se quiere &nbsp;reivindicar, arguy\u00f3 que \u201cNo &nbsp;es cierto, mi mandante est\u00e1 en posesi\u00f3n del inmueble &nbsp;desde que se lo transfiri\u00f3 Industrias y Cr\u00e9ditos\u201d. &nbsp;<\/p>\n<p>En &nbsp;cuanto a la excepci\u00f3n de prescripci\u00f3n que se dice se &nbsp;aleg\u00f3, es claro que se limit\u00f3 a se\u00f1alar: &nbsp;\u201cRatifico &nbsp;todas y cada una de las excepciones propuestas por el se\u00f1or &nbsp;apoderado de Industrias y Cr\u00e9ditos, tales como falta de &nbsp;legitimaci\u00f3n activa y pasiva, nulidad de los t\u00edtulos y &nbsp;de la cadena de tradiciones, prescripci\u00f3n adquisitiva, las que &nbsp;me abstengo de repetir aqu\u00ed, dada la correcta exposici\u00f3n &nbsp;que de las mismas hizo el se\u00f1or apoderado de Industrias y &nbsp;Cr\u00e9ditos\u201d. &nbsp;<\/p>\n<p>As\u00ed &nbsp;las cosas, con tales manifestaciones, en modo alguno, se pueda tener &nbsp;por confesada la posesi\u00f3n de los convocados. Emerge de lo &nbsp;expuesto, que el censor no demostr\u00f3, como le correspond\u00eda, &nbsp;el error de hecho que se endilga a la sentencia acusada. &nbsp;<\/p>\n<p>8.- &nbsp;El cargo, por lo tanto, no prospera. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>V. DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;virtud de lo discurrido, la Corte Suprema de Justicia, Sala de &nbsp;Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica de Colombia y por autoridad de la ley, NO &nbsp;CASA &nbsp;la sentencia proferida por el Tribunal Superior del Distrito Judicial &nbsp;de Bogot\u00e1- Sala Civil de Descongesti\u00f3n- el 22 de julio &nbsp;de 2013, en el proceso ordinario (reivindicatorio) promovido por &nbsp;Sanclemente, Fern\u00e1ndez y Hern\u00e1ndez Abogados S.A. contra &nbsp;Industrias y Cr\u00e9ditos S.A. al que se vincul\u00f3 la &nbsp;sociedad Inversionistas Asociados Basora S.A. &nbsp;<\/p>\n<p>Costas &nbsp;en casaci\u00f3n a cargo de la parte recurrente. Liqu\u00eddense &nbsp;en los t\u00e9rminos de ley, incluyendo la suma de $3.000.000, como &nbsp;agencias en derecho. &nbsp;<\/p>\n<p>C\u00f3piese, &nbsp;notif\u00edquese y oportunamente devu\u00e9lvase al Tribunal de &nbsp;origen. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;<\/p>\n<p>LUIS ARMANDO &nbsp;TOLOSA VILLABONA &nbsp;<\/p>\n<p>Presidente de la &nbsp;Sala &nbsp;<\/p>\n<p>\u00c1LVARO &nbsp;FERNANDO GARC\u00cdA RESTREPO &nbsp;<\/p>\n<p>AROLDO WILSON &nbsp;QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS ALONSO &nbsp;RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO AUGUSTO &nbsp;TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>1 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CSJ. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Civil. G. J., t. LXXVIII, p\u00e1gina 313. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>SC811-2021 (1993-00001-02) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; Magistrado &nbsp;Ponente &nbsp; SC811-2020 &nbsp; Radicaci\u00f3n &nbsp;n\u00b0 11001-31-03-004-1993-00001-02 &nbsp; (Aprobada &nbsp;en sesi\u00f3n virtual de seis de agosto de dos mil veinte) &nbsp; Bogot\u00e1 &nbsp;D.C., quince (15) de marzo de dos mil veintiuno (2021). &nbsp; Decide &nbsp;la Corte el recurso de casaci\u00f3n interpuesto por la &nbsp;sociedad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"class_list":["post-53873","post","type-post","status-publish","format-standard","hentry","category-marzo"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/53873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=53873"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/53873\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=53873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=53873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=53873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}