{"id":54235,"date":"2024-05-17T20:41:52","date_gmt":"2024-05-17T20:41:52","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac1854-2021-2019-03058-00\/"},"modified":"2024-05-17T20:41:52","modified_gmt":"2024-05-17T20:41:52","slug":"ac1854-2021-2019-03058-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac1854-2021-2019-03058-00\/","title":{"rendered":"AC 1854 2021"},"content":{"rendered":"<p>AC1854-2021 (2019-03058-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC1854-2021 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2019-03058-00 &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., diecinueve &nbsp;(19) de mayo de dos mil veintiuno (2021). &nbsp;<\/p>\n<p>Procede la Corte a &nbsp;pronunciarse sobre la admisibilidad del recurso extraordinario de &nbsp;revisi\u00f3n interpuesto en el presente asunto. &nbsp;<\/p>\n<p>I. ANTECEDENTES &nbsp;<\/p>\n<p>1. Angelcom S.A.S. &nbsp;y Sistemas Asesor\u00edas y Redes S.A.S., interpusieron recurso de &nbsp;revisi\u00f3n contra la sentencia proferida el 7 de julio de 2016 &nbsp;por la Sala Civil del Tribunal Superior del Distrito Judicial de &nbsp;Bogot\u00e1. &nbsp;<\/p>\n<p>2. En auto &nbsp;calendado a los 13 d\u00edas del mes de abril de 2021 y notificado &nbsp;por estado al d\u00eda siguiente, esta Corporaci\u00f3n inadmiti\u00f3 &nbsp;el libelo genitor mencionado, para que las sociedades promotoras &nbsp;precisaran \u201cla &nbsp;fecha de ejecutoria de la sentencia\u201d &nbsp;impugnada &nbsp;e informaran \u201ccu\u00e1les &nbsp;son los documentos que se habr\u00edan encontrado \u00abdespu\u00e9s &nbsp;de proferida la sentencia\u00bb recurrida, que exist\u00edan para &nbsp;el momento del fallo y de manera concreta su incidencia en la &nbsp;decisi\u00f3n y las razones de fuerza mayor, caso fortuito u obra &nbsp;de la parte contraria, por la cual no pudieron ser aportados al &nbsp;proceso\u201d, &nbsp;otorgando &nbsp;el t\u00e9rmino de cinco (5) d\u00edas1. &nbsp;<\/p>\n<p>3. Dentro de la &nbsp;oportunidad concedida, las firmas comerciales impugnantes &nbsp;manifestaron que el fallo rebatido cobr\u00f3 firmeza el 18 de &nbsp;septiembre de 2017, y que solo el oficio No. 2013EE4191 de fecha 15 &nbsp;de abril de 2013, exist\u00eda antes de la decisi\u00f3n de &nbsp;m\u00e9rito de segunda instancia; sin embargo, argumentaron, \u201c[l]as &nbsp;actas referidas en los numerales 1.1. y 1.2., si bien no exist\u00edan &nbsp;para la fecha de la sentencia, su contenido se refiere[,] &nbsp;de manera exclusiva[,] &nbsp;a la ejecuci\u00f3n de contratos que terminaron en el a\u00f1o &nbsp;2015 y que son el eje central del proceso subyacente (\u2026)\u201d. &nbsp;<\/p>\n<p>En lo concerniente &nbsp;a las razones con ocasi\u00f3n de las cuales no pudieron aportar al &nbsp;proceso dichos documentos, se\u00f1alaron, en relaci\u00f3n con &nbsp;el primero, que fue por \u201cobra &nbsp;de la parte contraria, es decir[,] &nbsp;Recaudo Bogot\u00e1 S.A.S.\u201d y &nbsp;frente a los dos \u00faltimos, por tratarse de actas suscritas &nbsp;hasta el a\u00f1o 2017, lo cual imposibilit\u00f3 tener acceso a &nbsp;ellas con anterioridad, hecho endilgable a \u201cla &nbsp;entidad contratante\u201d &nbsp;y no a su propia voluntad. &nbsp;<\/p>\n<p>Adicionalmente, &nbsp;recabaron en la trascendencia de tales evidencias en la resoluci\u00f3n &nbsp;del asunto materia de reproche, por acreditar la inexistencia de la &nbsp;conducta desleal por cuya comisi\u00f3n resultaron condenadas. &nbsp;<\/p>\n<p>II. &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;De acuerdo con el art\u00edculo 358 del C\u00f3digo General del &nbsp;Proceso \u201c[s]e &nbsp;declarar\u00e1 inadmisible la demanda cuando no re\u00fana los &nbsp;requisitos formales exigidos en el art\u00edculo anterior, as\u00ed &nbsp;como tambi\u00e9n cuando no vaya dirigida contra todas las personas &nbsp;que deben intervenir en el recurso, casos en los cuales se le &nbsp;conceder\u00e1 al interesado un plazo de cinco (5) d\u00edas para &nbsp;subsanar los defectos advertidos. De no hacerlo en tiempo h\u00e1bil &nbsp;la demanda ser\u00e1 rechazada\u201d. &nbsp;<\/p>\n<p>Significa &nbsp;lo anterior que, en caso de inadmisi\u00f3n del libelo genitor, &nbsp;corresponde al interesado enmendar, tempestivamente, las falencias &nbsp;identificadas en la respectiva providencia, so pena del rechazo de su &nbsp;s\u00faplica. &nbsp;<\/p>\n<p>2. &nbsp;En &nbsp;el sub &nbsp;j\u00fadice, &nbsp;las recurrentes no cumplieron con la carga de subsanaci\u00f3n &nbsp;impuesta en el prove\u00eddo de 13 de abril de 2021, pues si bien &nbsp;puntualizaron la fecha de ejecutoria de la determinaci\u00f3n &nbsp;recriminada e individualizaron los documentos no tomados en &nbsp;consideraci\u00f3n al momento de dirimir la controversia por no &nbsp;haber sido adosados a la foliatura, desatendieron los dem\u00e1s &nbsp;requerimientos. &nbsp;<\/p>\n<p>En efecto, aunque &nbsp;basaron su censura en la causal primera del art\u00edculo 355 del &nbsp;C\u00f3digo General del Proceso, &nbsp;no &nbsp;explicaron en qu\u00e9 consistieron los actos de la contraparte con &nbsp;ocasi\u00f3n de los cuales les fue imposible conocer y aportar al &nbsp;proceso el oficio No. 2013EE4191 de 15 de abril de 2013, pues se &nbsp;limitaron a afirmar que esa fue la causa de tal suceso, sin &nbsp;desarrollar su argumento. &nbsp;<\/p>\n<p>Es m\u00e1s, en &nbsp;el escrito inicial aseveraron no haber podido introducir esta prueba &nbsp;al decurso, no por maniobras atribuibles a su contendora, sino porque &nbsp;\u201cse &nbsp;tuvo conocimiento de ella con posterioridad a la decisi\u00f3n &nbsp;judicial cuya revisi\u00f3n aqu\u00ed se solicita\u201d, &nbsp;circunstancia ajena a las establecidas por el legislador para dar v\u00eda &nbsp;libre a la revisi\u00f3n de la sentencia, pues no demostraron la &nbsp;existencia de una situaci\u00f3n \u201cimprevisible, &nbsp;irresistible, intempestiva, excepcional, sorpresiva que &nbsp;imposibilitara[,] &nbsp;de manera fatal[,] &nbsp;acceder a las piezas en que se finca el mecanismo extraordinario. &nbsp;Mucho menos dan cuenta de que la sociedad fiduciaria hubiera tenido &nbsp;en su poder los legajos y los hubiera ocultado (CSJ &nbsp;AC1668-2021, 5 may., rad. 2021-00569-00). &nbsp;<\/p>\n<p>Tampoco satisfacen &nbsp;las memoradas exigencias, las actas de liquidaci\u00f3n final de &nbsp;contratos suscritas el 14 de diciembre de 2017, entre Transmilenio &nbsp;S.A. y la Uni\u00f3n Temporal Fase II, pues se trata de papeles &nbsp;inexistentes para el momento del proferimiento del fallo de segundo &nbsp;grado aqu\u00ed confutado, lo cual descarta la admisibilidad de la &nbsp;censura con soporte en ellas. &nbsp;<\/p>\n<p>Sobre el punto, &nbsp;tiene dicho la jurisprudencia de esta Corporaci\u00f3n, que: &nbsp;<\/p>\n<p>\u00ab(\u2026) &nbsp;para la cabal estructuraci\u00f3n del referido motivo, como &nbsp;condici\u00f3n sine qua non determinante del \u00e9xito del &nbsp;recurso de revisi\u00f3n, es indispensable probar, de modo &nbsp;fehaciente, los concurrentes elementos a continuaci\u00f3n &nbsp;expuestos: (a) que las pruebas documentales de que se trate hayan &nbsp;sido halladas ulteriormente al momento en que fue proferido el fallo, &nbsp;habida cuenta que \u201cla prueba de eficacia en revisi\u00f3n y &nbsp;desde el punto de vista que se est\u00e1 tratando, debe &nbsp;tener existencia desde el momento mismo en que se entabla la acci\u00f3n &nbsp;[\u2026] de donde se sigue que no constituyendo esa pieza &nbsp;documental -bien por su contenido o por cualquier otra circunstancia- &nbsp;una aut\u00e9ntica e incontestable novedad frente al material &nbsp;probatorio recogido en el proceso, la predicada injusticia de esa &nbsp;resoluci\u00f3n no puede vincularse causalmente con la ausencia del &nbsp;documento aparecido\u2019 (Sentencia 237 de 1\u00ba de julio de &nbsp;1988); (b) que el alcance del valor persuasivo de tales probanzas &nbsp;habr\u00eda transformado la decisi\u00f3n contenida en ese &nbsp;prove\u00eddo, por cuanto \u201cel documento nuevo, per se, debe &nbsp;ser decisivo y por tanto tener la suficiente fuerza como para &nbsp;determinar un cambio sustancial de la sentencia recurrida\u201d; y, &nbsp;(c) que no pudieron aportarse tempestivamente, debido a fuerza mayor &nbsp;o caso fortuito o por obra de la parte contraria, raz\u00f3n por la &nbsp;que \u201cno basta que la prueba exista para que la revisi\u00f3n &nbsp;sea viable, sino que es necesario para ello que haya sido imposible &nbsp;aducirla, o por un hecho independiente de las partes, o por un hecho &nbsp;doloso de la parte favorecida\u00bb (CSJ &nbsp;SC, 5 dic. 2012, rad. 2003-00164-01, reiterada en AC4795-2018, 8 &nbsp;nov., rad. 2018-02442-00). &nbsp;<\/p>\n<p>3. Como el legajo &nbsp;sobre cuya base pretendi\u00f3 edificarse la impugnaci\u00f3n &nbsp;extraordinaria no satisface las exigencias consagradas en el numeral &nbsp;1\u00ba del art\u00edculo 355 del C\u00f3digo General del &nbsp;Proceso, se impone el rechazo de la respectiva demanda. &nbsp;<\/p>\n<p>III. DECISI\u00d3N &nbsp;<\/p>\n<p>En m\u00e9rito &nbsp;de lo expuesto, la Corte Suprema de Justicia, Sala de Casaci\u00f3n &nbsp;Civil, RESUELVE: &nbsp;<\/p>\n<p>PRIMERO: &nbsp;RECHAZAR la &nbsp;demanda de revisi\u00f3n presentada por Angelcom &nbsp;S.A.S. y Sistemas Asesor\u00edas y Redes S.A.S., contra la &nbsp;sentencia proferida el 7 de julio de 2016 por la Sala Civil del &nbsp;Tribunal Superior del Distrito Judicial de Bogot\u00e1. &nbsp;<\/p>\n<p>SEGUNDO: &nbsp;DEVU\u00c9LVANSE &nbsp;los &nbsp;anexos de la demanda, previas las constancias de rigor. &nbsp;<\/p>\n<p>Notif\u00edquese, &nbsp;<\/p>\n<p>HILDA GONZ\u00c1LEZ &nbsp;NEIRA &nbsp;<\/p>\n<p>Magistrada &nbsp;<\/p>\n<p>1 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folio 120, cuaderno \u00fanico. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC1854-2021 (2019-03058-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC1854-2021 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2019-03058-00 &nbsp; Bogot\u00e1 &nbsp;D.C., diecinueve &nbsp;(19) de mayo de dos mil veintiuno (2021). &nbsp; Procede la Corte a &nbsp;pronunciarse sobre la admisibilidad del recurso extraordinario de &nbsp;revisi\u00f3n interpuesto en el presente asunto. &nbsp; I. ANTECEDENTES &nbsp; 1. Angelcom S.A.S. &nbsp;y Sistemas Asesor\u00edas y Redes S.A.S., [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-54235","post","type-post","status-publish","format-standard","hentry","category-mayo"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/54235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=54235"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/54235\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=54235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=54235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=54235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}