{"id":54272,"date":"2024-05-17T20:41:52","date_gmt":"2024-05-17T20:41:52","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac1982-2021-2013-00297-01\/"},"modified":"2024-05-17T20:41:52","modified_gmt":"2024-05-17T20:41:52","slug":"ac1982-2021-2013-00297-01","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac1982-2021-2013-00297-01\/","title":{"rendered":"AC 1982 2021"},"content":{"rendered":"<p>AC1982-2021 (2013-00297-01)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC1982-2021 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 &nbsp;47001-31-03-001-2013-00297-01 &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., veintis\u00e9is (26) de mayo de dos mil veintiuno (2021).- &nbsp;<\/p>\n<p>El &nbsp;apoderado judicial de EFRA\u00cdN &nbsp;SEGUNDO MIRANDA VILLALOBOS &nbsp;interpuso recurso de reposici\u00f3n contra \u201cla &nbsp;presunta ejecutoria\u201d del &nbsp;auto de 15 de diciembre de 2020; prove\u00eddo por medio del cual, &nbsp;la Sala inadmiti\u00f3 la demanda presentada por \u00e9ste para &nbsp;sustentar el recurso de casaci\u00f3n formulado contra la &nbsp;sentencia &nbsp;del 26 de marzo de 2019 proferida por la Sala Civil Familia del &nbsp;Tribunal Superior del Distrito Judicial de Santa Marta dentro del &nbsp;proceso de la referencia, &nbsp;pero seleccion\u00f3 positivamente el respectivo libelo, para &nbsp;emitir posteriormente pronunciamiento de fondo sobre el asunto. &nbsp;<\/p>\n<p>En &nbsp;sustento de su petici\u00f3n, el memorialista adujo que ha estado &nbsp;pendiente de lo actuado en este proceso, desde que ingres\u00f3 el &nbsp;expediente a Despacho el 27 de noviembre de 2019, lo que incluye el &nbsp;tiempo en el que se suspendieron los t\u00e9rminos judiciales. &nbsp;Agreg\u00f3 que durante el mes de diciembre de 2020, no funcion\u00f3 &nbsp;la p\u00e1gina de la Rama Judicial-Sistema Siglo XXI, as\u00ed &nbsp;como tampoco la consulta individual de procesos, por lo que no es &nbsp;posible visualizar los autos proferidos, lo que solo resulta viable, &nbsp;cuando son enviados \u201cmediante &nbsp;notificaci\u00f3n personal\u201d. &nbsp;<\/p>\n<p>En &nbsp;esas condiciones -esgrime el memorialista-, que no puede decirse que &nbsp;\u201cel &nbsp;t\u00e9rmino venci\u00f3 y pasar el proceso a Despacho\u201d, &nbsp;sin que el enteramiento de la providencia se haya cumplido en cabal &nbsp;forma, por lo que se debe \u201crevocar\u201d &nbsp;la \u201cejecutoria\u201d &nbsp;de la providencia mencionada anteriormente. &nbsp;<\/p>\n<p>Para &nbsp;resolver lo pertinente frente a ese remedio, se &nbsp;considera: &nbsp;<\/p>\n<p>1. &nbsp;La ejecutoria de las providencias es &nbsp;un fen\u00f3meno procesal &nbsp;que acaece cuando i) &nbsp;estas no son impugnadas; ii) &nbsp;no proceden recursos contra ellas; y iii) &nbsp;una vez son resueltos los mecanismos de impugnaci\u00f3n que se &nbsp;hayan formulado frente a las mismas, al igual que las solicitudes de &nbsp;aclaraci\u00f3n o complementaci\u00f3n propuestas (Art. 302, &nbsp;C.G.P.). &nbsp;<\/p>\n<p>La &nbsp;consecuencia de que respecto de una providencia se estructure su &nbsp;ejecutoria, particularmente un auto, es que sobre este al juzgador no &nbsp;le es posible revocarlo, modificarlo o alterarlo, pues, estima la &nbsp;doctrina autorizada, que al ser el procedimiento una sucesi\u00f3n &nbsp;encadenada de actuaciones destinada al cumplimiento de un prop\u00f3sito &nbsp;(resolver el caso en sentencia), retrotraer lo actuado implicar\u00eda &nbsp;desconocer el principio de preclusividad, que da orden y seguridad al &nbsp;tr\u00e1mite judicial que se adelanta1. &nbsp;<\/p>\n<p>2. &nbsp;En el anterior orden, si el mencionado auto de 15 de diciembre de &nbsp;2020 alcanz\u00f3 su ejecutoria por no haberse elevado respecto del &nbsp;mismo ninguna petici\u00f3n dentro de los tres d\u00edas &nbsp;siguientes a su notificaci\u00f3n por anotaci\u00f3n en el estado &nbsp;virtual, no es posible, como lo reclama la parte recurrente, &nbsp;\u201crevocar\u201d &nbsp;dicha ejecutoria. &nbsp;<\/p>\n<p>3. &nbsp;Adem\u00e1s, cumple recordar que siendo los recursos, y el de &nbsp;reposici\u00f3n por supuesto que lo es, actos de postulaci\u00f3n &nbsp;destinados a que la parte perjudicada con una determinada providencia &nbsp;pueda obtener su revocatoria o modificaci\u00f3n, por no estar &nbsp;ajustada a derecho, el presente, que se estudia, de entrada denota su &nbsp;improcedencia, por cuanto no hay nada que se le censur\u00f3 al &nbsp;auto, que de un lado inadmiti\u00f3 la demanda de casaci\u00f3n, &nbsp;y del otro la seleccion\u00f3 positivamente para los prop\u00f3sitos &nbsp;de emitir sentencia. &nbsp;<\/p>\n<p>4. &nbsp;Por otro lado, verificado el pliego contentivo de la actuaci\u00f3n &nbsp;surtida hasta el momento en esta sede, no se aprecia configurada la &nbsp;indebida notificaci\u00f3n sugerida por el peticionario en relaci\u00f3n &nbsp;con el mencionado prove\u00eddo, que d\u00e9 lugar a la eventual &nbsp;nulidad de esta, pues, se hizo conforme a la ley que disciplina el &nbsp;caso, esto es, los art\u00edculos 295 ib\u00eddem y 9\u00b0 del &nbsp;Decreto 806 de 2020, a trav\u00e9s de estado electr\u00f3nico No. &nbsp;072 del 16 de diciembre de ese mismo a\u00f1o2, &nbsp;el cual se publicit\u00f3 en el canal digital previsto por la Corte &nbsp;para ello3, &nbsp;as\u00ed como en las distintas opciones de consulta dispuestas en &nbsp;la p\u00e1gina Web de la Rama Judicial4, &nbsp;decisi\u00f3n a la cual pudo \u00e9ste acceder dirigiendo la &nbsp;respectiva solicitud a la direcci\u00f3n electr\u00f3nica &nbsp;precavida por la Corporaci\u00f3n con ese fin5. &nbsp;<\/p>\n<p>Por &nbsp;tanto, se &nbsp;RECHAZA el remedio horizontal propuesto. En consecuencia, una vez &nbsp;notificada esta providencia, regrese al despacho la actuaci\u00f3n &nbsp;para dar cumplimiento a lo se\u00f1alado en el ordinal tercero del &nbsp;auto de 15 de diciembre de 2020. &nbsp;<\/p>\n<p>Notif\u00edquese &nbsp;y c\u00famplase. &nbsp;<\/p>\n<p>\u00c1LVARO &nbsp;FERNANDO GARC\u00cdA RESTREPO &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>1 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;En ese sentido, MORALES MOLINA, Hernando, Curso &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;de Derecho Procesal Civil, Parte General, Novena Edici\u00f3n, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Editorial ABC, 1985, p\u00e1g. 476. &nbsp;<\/p>\n<p>2https:\/\/cortesuprema.gov.co\/corte\/wp-content\/uploads\/not\/civil20\/estado072civil16122020.pdf &nbsp;<\/p>\n<p>3 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<A HRef=\"https:\/\/cortesuprema.gov.co\/corte\/index.php\/notificacionescivil2020\/  \">https:\/\/cortesuprema.gov.co\/corte\/index.php\/notificacionescivil2020\/  <\/A><\/p>\n<p>4 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<A HRef=\"https:\/\/procesos.ramajudicial.gov.co\/procesoscs\/ConsultaJusticias21.aspx?EntryId=AjJE3C3JR9x6kW3d%2fBgBcOGb4RQ%3d  \">https:\/\/procesos.ramajudicial.gov.co\/procesoscs\/ConsultaJusticias21.aspx?EntryId=AjJE3C3JR9x6kW3d%2fBgBcOGb4RQ%3d  <\/A><\/p>\n<p>5 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;copiasprovidenciascasacioncivil@cortesuprema.ramajuducial.gov.cob &nbsp;<\/p>\n<p>4 &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC1982-2021 (2013-00297-01) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC1982-2021 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 &nbsp;47001-31-03-001-2013-00297-01 &nbsp; Bogot\u00e1 &nbsp;D.C., veintis\u00e9is (26) de mayo de dos mil veintiuno (2021).- &nbsp; El &nbsp;apoderado judicial de EFRA\u00cdN &nbsp;SEGUNDO MIRANDA VILLALOBOS &nbsp;interpuso recurso de reposici\u00f3n contra \u201cla &nbsp;presunta ejecutoria\u201d del &nbsp;auto de 15 de diciembre de 2020; prove\u00eddo por medio del cual, &nbsp;la Sala [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-54272","post","type-post","status-publish","format-standard","hentry","category-mayo"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/54272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=54272"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/54272\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=54272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=54272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=54272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}