{"id":54282,"date":"2024-05-17T20:41:52","date_gmt":"2024-05-17T20:41:52","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac1996-2021-2021-01521-00\/"},"modified":"2024-05-17T20:41:52","modified_gmt":"2024-05-17T20:41:52","slug":"ac1996-2021-2021-01521-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac1996-2021-2021-01521-00\/","title":{"rendered":"AC 1996 2021"},"content":{"rendered":"<p>AC1996-2021 (2021-01521-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC1996-2021 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n. 11001-02-03-000-2021-01521-00 &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., veintis\u00e9is (26) de mayo de dos mil veintiuno (2021). &nbsp;<\/p>\n<p>I. ANTECEDENTES &nbsp;<\/p>\n<p>1. El 7 de &nbsp;noviembre de 2019, el ICBF Centro Zonal Santa Fe, previa solicitud de &nbsp;N\u00e9stor Ren\u00e9 Zorro Cajamarca, radic\u00f3 demanda de &nbsp;investigaci\u00f3n de paternidad contra Dora Nelly Monsalve Parra, &nbsp;respecto del menor -L.E.M.P.-. El convocante fij\u00f3 la &nbsp;competencia en los jueces de familia de Bogot\u00e1 \u201c{p}or &nbsp;la naturaleza del asunto y el domicilio del ni\u00f1o\u201d &nbsp;(folios &nbsp;13 a 15, cuaderno principal 2010-01158, expediente digital). &nbsp;<\/p>\n<p>2. El asunto le &nbsp;fue asignado por reparto al Juzgado Dieciocho de Familia de Bogot\u00e1 &nbsp;que, por auto del 25 del mismo mes y a\u00f1o, lo admiti\u00f3 y &nbsp;orden\u00f3 correr traslado a la demandada (folio 18, ib.). &nbsp;<\/p>\n<p>3. El solicitante &nbsp;N\u00e9stor Ren\u00e9 Zorro pidi\u00f3 la remisi\u00f3n de &nbsp;las actuaciones al municipio de Garagoa (Boyac\u00e1), atendiendo &nbsp;al cambio de domicilio del menor por traslado laboral de su &nbsp;progenitora, pedimento al que accedi\u00f3 el referido despacho, &nbsp;resguardado en el inciso 2\u00ba, numeral 2\u00ba del art\u00edculo &nbsp;28 del C\u00f3digo General del Proceso (archivo 13, expediente &nbsp;digital). &nbsp;<\/p>\n<p>4. Al recibir las &nbsp;diligencias, el Juzgado Promiscuo de Familia de Garagoa (Boyac\u00e1) &nbsp;rehus\u00f3 su conocimiento, arguyendo que la justificaci\u00f3n &nbsp;en que fund\u00f3 su solicitud el demandante no configura ninguna &nbsp;excepci\u00f3n a la \u201cperpetuatio &nbsp;iurisdictionis\u201d, &nbsp;por lo que suscit\u00f3 conflicto negativo de competencia (archivo &nbsp;14, expediente digital). &nbsp;<\/p>\n<p>II. &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1. Corresponde a &nbsp;esta Sala, a trav\u00e9s de la magistrada sustanciadora, dirimir el &nbsp;presente conflicto, en tanto la Corte es superior funcional com\u00fan &nbsp;de los despachos involucrados, los cuales pertenecen a diferentes &nbsp;distritos judiciales. As\u00ed lo establecen los art\u00edculos &nbsp;139 del C\u00f3digo General del Proceso y 16 de la Ley 270 de 1996, &nbsp;modificado por el 7\u00ba de la Ley 1285 de 2009. &nbsp;<\/p>\n<p>2. Al &nbsp;tenor de lo dispuesto en el inciso 2\u00ba, numeral 2\u00ba del &nbsp;art\u00edculo 28 del C\u00f3digo General del Proceso, \u201cEn &nbsp;los procesos de alimentos, p\u00e9rdida o suspensi\u00f3n de la &nbsp;patria potestad, investigaci\u00f3n &nbsp;o impugnaci\u00f3n de la paternidad o maternidad, &nbsp;custodias, cuidado personal y regulaci\u00f3n de visitas, permisos &nbsp;para salir del pa\u00eds, medidas cautelares sobre personas o &nbsp;bienes vinculados a tales procesos, en los que el ni\u00f1o, ni\u00f1a &nbsp;o adolescente sea demandante o demandado, la &nbsp;competencia corresponde en forma privativa al juez del domicilio o &nbsp;residencia de aquel\u201d &nbsp;(se destaca). &nbsp;<\/p>\n<p>Dicho aparte &nbsp;normativo fue justamente el invocado por el Instituto Colombiano de &nbsp;Bienestar Familiar cuando al radicar la demanda de investigaci\u00f3n &nbsp;de paternidad \u201cen &nbsp;aras de restablecer el derecho de filiaci\u00f3n del ni\u00f1o &nbsp;(\u2026)\u201d &nbsp;L.E.M.P. fij\u00f3 la competencia en el juez de familia de la &nbsp;ciudad de Bogot\u00e1, pues era este el lugar de su domicilio; sin &nbsp;embargo, del escrito radicado por el promotor de la causa se advierte &nbsp;que aqu\u00e9l vari\u00f3 al municipio de Garagoa, en raz\u00f3n &nbsp;del cambio de lugar de trabajo de su se\u00f1or madre, demandada en &nbsp;el tr\u00e1mite. &nbsp;<\/p>\n<p>3. Frente a dicha &nbsp;situaci\u00f3n, podr\u00eda pensarse, como lo hizo la juzgadora &nbsp;de esa locaci\u00f3n que, en virtud del principio de \u201cperpetuatio &nbsp;iurisdictionis\u201d, \u00ab(&#8230;) &nbsp;el juez que le d\u00e9 inicio a la actuaci\u00f3n conservar\u00e1 &nbsp;su competencia (&#8230;) dado que cuando se activa la jurisdicci\u00f3n &nbsp;el funcionario a quien se dirige el libelo correspondiente tiene el &nbsp;compromiso con la administraci\u00f3n de justicia y con el usuario &nbsp;que a la misma accede, de calificar la demanda eficazmente, tema que &nbsp;involucra la evaluaci\u00f3n, c\u00f3mo no, tambi\u00e9n de su &nbsp;\u201ccompetencia\u201d, aspecto tal que, una vez avocado el &nbsp;conocimiento, torna en \u00e9l la prorrogaci\u00f3n de aquella &nbsp;at\u00e1ndolo a permanecer en la postura asumida hasta tanto dicha &nbsp;se controvierta\u00bb &nbsp;(CSJ &nbsp;AC4557-2019, 21 oct., rad No. 2019-03420-00, reiterada en CSJ &nbsp;AC2332-2020, 21 sep., rad. 2020-02298-00). &nbsp;<\/p>\n<p>No obstante, &nbsp;tambi\u00e9n se ha dicho que la indicada regla puede \u00ab(\u2026) &nbsp;y &nbsp;debe ceder ante circunstancias verdaderamente excepcionales, de &nbsp;evidenciarse la manifiesta inconveniencia de que el tr\u00e1mite &nbsp;siga siendo gestionado por quien originalmente avoc\u00f3 su &nbsp;conocimiento\u00bb &nbsp;(CSJ &nbsp;AC3405-2020, 4 dic., rad. 2019-04181-00), &nbsp;como ocurre en los eventos en que el inter\u00e9s superior del &nbsp;menor se vea favorecido con la remisi\u00f3n de las diligencias. &nbsp;<\/p>\n<p>Ello, en tanto, &nbsp;\u00abla &nbsp;finalidad de alterar la competencia tiene sustento en las siguientes &nbsp;dos premisas: i) para salvaguardar los derechos e intereses del menor &nbsp;y ii) mayor celeridad en el tr\u00e1mite. Esto \u00faltimo &nbsp;estriba en que es m\u00e1s f\u00e1cil fijar la competencia en el &nbsp;lugar donde se encuentra el menor, por cuanto hace expedita la &nbsp;instrucci\u00f3n, la recolecci\u00f3n de pruebas, la verificaci\u00f3n &nbsp;en tiempo real de las condiciones de vida de los menores, sus &nbsp;necesidades afectivas y econ\u00f3micas reales\u00bb &nbsp;(CSJ &nbsp;AC2332-2020, 21 sep., rad. 2020-02298-00). &nbsp;<\/p>\n<p>4. Bajo ese &nbsp;entendido, no existe raz\u00f3n para que la juzgadora de la &nbsp;municipalidad de Garagoa rehusara la competencia en el caso, pues, a &nbsp;m\u00e1s de que, en dicho territorio se encuentran domiciliados el &nbsp;menor respecto del cual se discute la paternidad y su progenitora &nbsp;-demandada en el proceso-, fue el propio convocante quien solicit\u00f3 &nbsp;el traslado del expediente, &nbsp;con &nbsp;el \u00fanico prop\u00f3sito de garantizar los derechos del &nbsp;infante. &nbsp;<\/p>\n<p>Dicha posici\u00f3n &nbsp;se acompasa con los principios de celeridad y econom\u00eda &nbsp;procesal que deben regir toda actuaci\u00f3n judicial, dado que &nbsp;ning\u00fan sentido tendr\u00eda adelantar el juicio en una &nbsp;ubicaci\u00f3n geogr\u00e1fica ajena a los extremos procesales e &nbsp;involucrados en el litigio y, en cambio, s\u00ed representar\u00eda &nbsp;un desgaste tanto para ellos como para la administraci\u00f3n de &nbsp;justicia, reflejado, entre otros, en gastos de desplazamiento y &nbsp;comisiones para la pr\u00e1ctica de diligencias. &nbsp;<\/p>\n<p>5. As\u00ed las &nbsp;cosas, f\u00e1cil resulta concluir que la competencia para conocer &nbsp;este tipo de controversias, desde el punto de vista territorial, &nbsp;recae en la autoridad del lugar \u201cdonde &nbsp;se encuentre\u201d &nbsp;el ni\u00f1o, ni\u00f1a o adolescente involucrado en el asunto, &nbsp;que para este caso es el Juzgado Promiscuo de Garagoa (Boyac\u00e1), &nbsp;a quien ser\u00e1n remitidas. &nbsp;<\/p>\n<p>III. DECISI\u00d3N &nbsp;<\/p>\n<p>En m\u00e9rito &nbsp;de lo expuesto, la Corte Suprema de Justicia, Sala de Casaci\u00f3n &nbsp;Civil, RESUELVE: &nbsp;<\/p>\n<p>PRIMERO: &nbsp;Declarar que el &nbsp;Juzgado Promiscuo de Familia de Garagoa (Boyac\u00e1) es el &nbsp;competente para asumir el conocimiento del proceso de la referencia. &nbsp;<\/p>\n<p>SEGUNDO: &nbsp;Remitir el expediente a esa autoridad para que contin\u00fae con el &nbsp;tr\u00e1mite del asunto. &nbsp;<\/p>\n<p>TERCERO: &nbsp;Comunicar esta decisi\u00f3n al Juzgado &nbsp;Dieciocho de Familia de Bogot\u00e1 y a los interesados. &nbsp;<\/p>\n<p>Notif\u00edquese, &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Magistrada &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC1996-2021 (2021-01521-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC1996-2021 &nbsp; Radicaci\u00f3n &nbsp;n. 11001-02-03-000-2021-01521-00 &nbsp; Bogot\u00e1 &nbsp;D.C., veintis\u00e9is (26) de mayo de dos mil veintiuno (2021). &nbsp; I. ANTECEDENTES &nbsp; 1. El 7 de &nbsp;noviembre de 2019, el ICBF Centro Zonal Santa Fe, previa solicitud de &nbsp;N\u00e9stor Ren\u00e9 Zorro Cajamarca, radic\u00f3 demanda de &nbsp;investigaci\u00f3n de paternidad contra Dora [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-54282","post","type-post","status-publish","format-standard","hentry","category-mayo"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/54282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=54282"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/54282\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=54282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=54282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=54282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}