{"id":54573,"date":"2024-05-17T20:41:22","date_gmt":"2024-05-17T20:41:22","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac2669-2021-2021-01843-00\/"},"modified":"2024-05-17T20:41:22","modified_gmt":"2024-05-17T20:41:22","slug":"ac2669-2021-2021-01843-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac2669-2021-2021-01843-00\/","title":{"rendered":"AC 2669 2021"},"content":{"rendered":"<p>AC2669-2021 (2021-01843-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC2669-2021 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 &nbsp;11001-02-03-000-2021-01843-00 &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., treinta (30) de junio de dos mil veintiuno (2021).- &nbsp;<\/p>\n<p>Se &nbsp;decide lo pertinente sobre el conflicto de competencia suscitado &nbsp;entre los Juzgados de Peque\u00f1as Causas y Competencia M\u00faltiple, &nbsp;Treinta y Siete de Bogot\u00e1 y Municipal de Popay\u00e1n, para &nbsp;conocer de la acci\u00f3n ejecutiva promovida por la &nbsp;COOPERATIVA MULTIACTIVA COPROYECCI\u00d3N contra &nbsp;MANUEL &nbsp;ANTONIO ARTEAGA ASMAZA. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. La cooperativa &nbsp;convocante solicit\u00f3 a la jurisdicci\u00f3n librar orden &nbsp;coercitiva a su favor y en contra del llamado a juicio, con &nbsp;el fin de obtener el pago de las obligaciones derivadas del pagar\u00e9 &nbsp;No 1033070. &nbsp;Para &nbsp;ello finc\u00f3 la competencia en los despachos judiciales de &nbsp;Bogot\u00e1, \u201clugar &nbsp;de cumplimiento de la obligaci\u00f3n\u201d &nbsp;estipulado en la \u201ccl\u00e1usula &nbsp;5 (quinta)\u201d &nbsp;del citado documento cambiario1. &nbsp;<\/p>\n<p>2. Previo reparto &nbsp;del asunto, el Despacho Treinta &nbsp;y Siete de &nbsp;Peque\u00f1as Causas y Competencia M\u00faltiple de la preanotada &nbsp;capital, lo rechaz\u00f3 y remiti\u00f3 a los juzgadores de &nbsp;Popay\u00e1n, conforme \u201cal &nbsp;\u00edtem de notificaciones\u201d &nbsp;establecido en la demanda, y al numeral 1\u00b0 del canon 28 del &nbsp;C\u00f3digo General del Proceso, se\u00f1alando que, salvo norma &nbsp;en contrario, la competencia gravita en los funcionarios del &nbsp;\u201cdomicilio &nbsp;del demandado\u201d2. &nbsp;<\/p>\n<p>3. A su vez, el &nbsp;estrado de la municipalidad de destino, tambi\u00e9n se abstuvo de &nbsp;avocar conocimiento, y en consecuencia, propuso la colisi\u00f3n &nbsp;negativa que ahora se resuelve, tras desmentir que la accionante haya &nbsp;elegido el fuero general de atribuci\u00f3n, para en su lugar &nbsp;resaltar, que en sincron\u00eda con lo \u201csuscrito &nbsp;en el t\u00edtulo valor\u201d &nbsp;y la pauta 3\u00aa del precepto 28 Ib\u00eddem, &nbsp;el libelo fue radicado en la urbe donde se halla la sede judicial &nbsp;remitente, por ser el sitio de satisfacci\u00f3n de las &nbsp;acreencias3. &nbsp;<\/p>\n<p>4. Planteada as\u00ed &nbsp;la controversia, llegaron las actuaciones a la Corte para dirimirla. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;Como la &nbsp;discusi\u00f3n planteada involucra dos autoridades judiciales de &nbsp;diferente distrito judicial, corresponder\u00eda dirimirla a esta &nbsp;Sala de la Corte Suprema de Justicia Especializada en lo Civil, &nbsp;por ser la superior funcional com\u00fan a ambos, seg\u00fan lo &nbsp;establecido en los art\u00edculos 139 de la ley 1564 de 2012 &nbsp;(C\u00f3digo General del Proceso), y 16 de la ley 270 de 1996 &nbsp;-modificado por el 7\u00ba de la ley 1285 de 2009. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;Se advierte, &nbsp;por otra parte, que los factores de competencia determinan el juez al &nbsp;que el ordenamiento jur\u00eddico le ha atribuido el conocimiento &nbsp;de un asunto en especial, y que para los efectos de resolver el &nbsp;dilema que motiva el presente pronunciamiento, las normas generales &nbsp;que regulan la materia son las encargadas de darle soluci\u00f3n. &nbsp;Por ello debe recordarse que al momento de acometer el estudio &nbsp;preliminar sobre el conocimiento del asunto que se le ha encomendado, &nbsp;el administrador de justicia tiene la carga de valorar las reglas que &nbsp;consagra el referido estatuto, y en particular las contenidas en el &nbsp;T\u00edtulo II, Libro Primero, las cuales le han de orientar para &nbsp;que adopte la determinaci\u00f3n de rigor en torno de su propia &nbsp;competencia. &nbsp;<\/p>\n<p>3.&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;numeral &nbsp;1\u00ba del art\u00edculo 28 ejusdem &nbsp;consagra la regla general que \u201c[e]n &nbsp;los procesos contenciosos, salvo disposici\u00f3n legal en &nbsp;contrario, es competente el juez del domicilio del demandado\u201d, &nbsp;previsi\u00f3n &nbsp;que complementa el numeral 3\u00ba ib\u00eddem &nbsp;en &nbsp;relaci\u00f3n con \u201c\u2026los &nbsp;procesos originados en un negocio jur\u00eddico o que involucren &nbsp;t\u00edtulos ejecutivos\u2026\u201d, &nbsp;donde \u201ces &nbsp;tambi\u00e9n competente el juez del lugar de cumplimiento de &nbsp;cualquiera de las obligaciones\u2026\u201d &nbsp;<\/p>\n<p>Lo &nbsp;cual significa que si en la pr\u00e1ctica el domicilio del &nbsp;convocado no coincide con el sitio de satisfacci\u00f3n de las &nbsp;prestaciones, el actor puede escoger, entre la dupla de funcionarios &nbsp;ante los que la ley le permite acudir, el que quiere que rit\u00fae &nbsp;y decida el litigio en ciernes. &nbsp;<\/p>\n<p>Voluntad &nbsp;que si es ejercida en consonancia con tales alternativas no puede ser &nbsp;alterada por el elegido, sin perjuicio del debate que en la forma y &nbsp;oportunidad debidas plantee su contradictor; pero que si no guarda &nbsp;armon\u00eda obliga a encauzar el asunto dentro de las &nbsp;posibilidades que brinda el ordenamiento, en todo caso respetando en &nbsp;la medida de lo posible ese querer. &nbsp;<\/p>\n<p>Sobre lo anterior, &nbsp;la Corte se ha pronunciado en reiteradas oportunidades, para destacar &nbsp;que &nbsp;<\/p>\n<p>\u201cAl &nbsp;demandante es a quien la ley lo faculta para escoger, dentro de los &nbsp;distintos fueros del factor territorial, la autoridad judicial que &nbsp;debe pronunciarse sobre un asunto determinado, suficientemente se &nbsp;tiene dicho que una vez elegido por aqu\u00e9l su juez natural, la &nbsp;competencia se torna en privativa, sin que el funcionario judicial &nbsp;pueda a su iniciativa eliminarla o variarla, a menos que el demandado &nbsp;fundadamente la objete mediante los mecanismos legales que sean &nbsp;procedentes\u201d &nbsp;(AC2434-2020). &nbsp;<\/p>\n<p>4. De conformidad &nbsp;con la exposici\u00f3n efectuada en p\u00e1rrafos precedentes, se &nbsp;advierte que, en el caso analizado, la &nbsp;entidad ejecutante determin\u00f3 en su libelo que la competencia, &nbsp;por el factor territorial, la atribu\u00eda de acuerdo a lo &nbsp;se\u00f1alado en el numeral 3\u00ba del art\u00edculo 28 del &nbsp;C.G.P., relativo al lugar de cumplimiento de la obligaci\u00f3n, &nbsp;que como se indic\u00f3 anteriormente, se encuentra en Bogot\u00e14. &nbsp;<\/p>\n<p>5. De manera que &nbsp;se\u00f1alado como fue, que el lugar de cumplimiento de la &nbsp;obligaci\u00f3n era Bogot\u00e1, no cab\u00eda alternativa &nbsp;diferente a dejar las diligencias en el juzgador de esa ciudad, &nbsp;porque, se insiste, fue el lugar de cumplimiento de la obligaci\u00f3n &nbsp;y no el lugar del domicilio del demandado, el foro de competencia &nbsp;seleccionado expresamente en el escrito inaugural. &nbsp;<\/p>\n<p>Acertada result\u00f3 &nbsp;entonces la decisi\u00f3n del funcionario de Popay\u00e1n, en el &nbsp;sentido de rechazar la actuaci\u00f3n, porque ese no fue el foro &nbsp;escogido por la demandante en el momento de presentaci\u00f3n de la &nbsp;demanda. &nbsp;<\/p>\n<p>Sobre este aspecto &nbsp;ha se\u00f1alado la Sala que el demandante: &nbsp;<\/p>\n<p>\u201c(\u2026) tiene la &nbsp;opci\u00f3n de accionar, ad libitum, en uno u otro lugar, o sea, en &nbsp;el domicilio de la contraparte o donde el pacto objeto de discusi\u00f3n &nbsp;o t\u00edtulo de ejecuci\u00f3n deb\u00eda cumplirse; pero, &nbsp;ins\u00edstese, ello queda, en principio, a la determinaci\u00f3n &nbsp;expresa de su promotor\u201d (AC4412, 13 jul. 2016, rad. &nbsp;2016-01858-00). &nbsp;<\/p>\n<p>Equivocada &nbsp;aparece, por su parte, la determinaci\u00f3n del juzgado de Bogot\u00e1, &nbsp;porque desconoci\u00f3 los t\u00e9rminos concretos en los que el &nbsp;actor seleccion\u00f3 la competencia territorial por: \u201cel &nbsp;cumplimiento de la obligaci\u00f3n\u201d, &nbsp;y adicionalmente, pas\u00f3 por alto que en el t\u00edtulo valor &nbsp;se expresa con absoluta claridad que el lugar de pago es la &nbsp;mencionada ciudad. &nbsp;<\/p>\n<p>No hab\u00eda &nbsp;manera, entonces, para que el juzgador de Bogot\u00e1, motu &nbsp;proprio, &nbsp;eludiera el conocimiento del asunto, y menos sobre la base de un &nbsp;fuero no escogido por el demandante al radicar su demanda. &nbsp;<\/p>\n<p>6. &nbsp; &nbsp; &nbsp; &nbsp;En &nbsp;definitiva, se ordenar\u00e1 remitir el expediente al Juzgado &nbsp;Treinta y Siete de Peque\u00f1as Causas y Competencia M\u00faltiple &nbsp;de Bogot\u00e1, para que reasuma el conocimiento del asunto y &nbsp;contin\u00fae el tr\u00e1mite que legalmente le corresponde, sin &nbsp;perjuicio del debate que, en su oportunidad, pueda plantear la parte &nbsp;ejecutada en relaci\u00f3n con la competencia. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>Por lo expuesto, &nbsp;la Corte Suprema de Justicia, Sala de Casaci\u00f3n Civil, RESUELVE &nbsp;el &nbsp;conflicto de competencia surgido entre los Juzgados mencionados, &nbsp;determinando que al Juzgado &nbsp;Treinta y Siete de Peque\u00f1as Causas y Competencia M\u00faltiple &nbsp;de Bogot\u00e1, &nbsp;corresponde conocer de la acci\u00f3n promovida &nbsp;por la Cooperativa Multiactiva COPROYECCI\u00d3N contra MANUEL &nbsp;ANTONIO ARTEAGA ASMAZA. En consecuencia, rem\u00edtase el &nbsp;expediente a dicha autoridad, y mediante oficio comun\u00edquese de &nbsp;esta determinaci\u00f3n a la otra involucrada. &nbsp;<\/p>\n<p>Notif\u00edquese, &nbsp;<\/p>\n<p>\u00c1LVARO &nbsp;FERNANDO GARC\u00cdA RESTREPO &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Cdno 04 Demanda Anexos. &nbsp;<\/p>\n<p>2\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Cdno 08 Rechaza por Competencia. &nbsp;<\/p>\n<p>3\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Cdno 09 ProponeConflictoCompetencia. &nbsp;<\/p>\n<p>4\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folio 3 c. 04 demanda anexos. Ibidem &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC2669-2021 (2021-01843-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC2669-2021 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 &nbsp;11001-02-03-000-2021-01843-00 &nbsp; Bogot\u00e1 &nbsp;D.C., treinta (30) de junio de dos mil veintiuno (2021).- &nbsp; Se &nbsp;decide lo pertinente sobre el conflicto de competencia suscitado &nbsp;entre los Juzgados de Peque\u00f1as Causas y Competencia M\u00faltiple, &nbsp;Treinta y Siete de Bogot\u00e1 y Municipal de Popay\u00e1n, para &nbsp;conocer de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-54573","post","type-post","status-publish","format-standard","hentry","category-junio"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/54573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=54573"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/54573\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=54573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=54573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=54573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}