{"id":58543,"date":"2024-05-17T20:42:56","date_gmt":"2024-05-17T20:42:56","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/stc13909-2021\/"},"modified":"2024-05-17T20:42:56","modified_gmt":"2024-05-17T20:42:56","slug":"stc13909-2021","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/stc13909-2021\/","title":{"rendered":"STC13909 2021"},"content":{"rendered":"<p>STC13909-2021<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Magistrada &nbsp;ponente &nbsp;<\/p>\n<p>STC13909-2021 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 11001-02-30-000-2021-01681-00 &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., diecinueve (19) de octubre de dos mil veintiuno (2021). &nbsp;<\/p>\n<p>Se &nbsp;desata la tutela que Laura Natalia Vanegas Riobo le instaur\u00f3 &nbsp;al &nbsp;Consejo Superior de la Judicatura \u2013 Unidad de Registro Nacional &nbsp;de Abogados y Auxiliares de la Justicia, extensiva al Consejo &nbsp;Seccional de la Judicatura de Tolima. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>1. La &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;libelista, actuando en nombre propio, reclam\u00f3 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;la protecci\u00f3n de los derechos a la \u00abeducaci\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;y petici\u00f3n\u00bb, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;presuntamente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;quebrantados por la autoridad querellada, para que, en consecuencia, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;se le ordenara \u00abdar &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;respuesta inmediata a mi petici\u00f3n de la soluci\u00f3n del &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;problema presentado en la plataforma SIRNA (\u2026). Expedir una &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;vez solucionado dicho problema de manera inmediata mi tarjeta &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;profesional, teniendo en cuenta las dilataciones que se han venido &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;presentando, desde la solicitud de la resoluci\u00f3n de la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;judicatura\u00bb. &nbsp;<\/p>\n<p>En &nbsp;sustento adujo que el 12 de mayo de 2021 requiri\u00f3 a trav\u00e9s &nbsp;de la p\u00e1gina SIRNA expedici\u00f3n de la \u00abtarjeta &nbsp;temporal\u00bb y \u00abresoluci\u00f3n de aprobaci\u00f3n de &nbsp;pr\u00e1ctica jur\u00eddica\u00bb. &nbsp;<\/p>\n<p>Sostuvo &nbsp;que con ocasi\u00f3n a una \u00abacci\u00f3n &nbsp;de tutela\u00bb &nbsp;anterior que interpuso, le contestaron \u00fanicamente lo relativo &nbsp;a la \u00abexpedici\u00f3n &nbsp;de la resoluci\u00f3n\u00bb, &nbsp;empero a &nbsp;la fecha \u00abla &nbsp;solicitud sigue generada en &nbsp;la plataforma, impidiendo que pueda &nbsp;realizar &nbsp;la nueva solicitud de expedici\u00f3n de la tarjeta profesional\u00bb. &nbsp;<\/p>\n<p>Aseguro &nbsp;que por ese motivo envi\u00f3 correo electr\u00f3nico a la &nbsp;direcci\u00f3n csjsirnasoporte@deaj.ramajudicial.gov.co, &nbsp;pero &nbsp;no ha recibido respuesta. &nbsp;<\/p>\n<p>Afirm\u00f3 &nbsp;que \u00abla &nbsp;dilataci\u00f3n que ha tenido el consejo superior en cada una de &nbsp;las solicitudes realizadas me ha perjudicado en gran manera, ya que &nbsp;me han impedido graduarme en el tiempo correspondiente, limit\u00e1ndome &nbsp;a la hora de postularme en empleos, adem\u00e1s de la limitaci\u00f3n &nbsp;de ejercer el derecho como abogada &nbsp;litigante\u00bb. &nbsp;<\/p>\n<p>2. &nbsp;La Unidad de Registro Nacional de Abogados y Auxiliares de la &nbsp;Justicia del Consejo Superior de la Judicatura manifest\u00f3 que &nbsp;\u00ab(\u2026) &nbsp;mediante &nbsp;correo electr\u00f3nico del d\u00eda 13 de octubre de 2021, env\u00edo &nbsp;respuesta a la solicitud al correo asesoria@abogadosvya.co de la &nbsp;accionante, en la cual se le inform\u00f3: \u201c(\u2026) &nbsp;En relaci\u00f3n con su solicitud, me permito informarle que se &nbsp;desactiv\u00f3 el tr\u00e1mite No. 10.388 de Licencia Temporal, &nbsp;para poder realizar el de la tarjeta profesional (\u2026)\u201d, &nbsp;cuya &nbsp;copia allego. As\u00ed mismo, esta Unidad mediante oficio del 14 de &nbsp;octubre del a\u00f1o en curso, dio respuesta a la petici\u00f3n &nbsp;de la Sra. LAURA NATALIA VANEGAS RIOBO, la cual le fue notificada a &nbsp;los correos electr\u00f3nicos asesoria@abogadosvya.co y &nbsp;vanegas.juridicos@gmail.com de la accionante (\u2026)\u00bb. &nbsp;<\/p>\n<p>El &nbsp;Consejo Seccional de la Judicatura de Tolima arguy\u00f3 falta de &nbsp;legitimaci\u00f3n en la causa por pasiva; sin embargo, comunic\u00f3 &nbsp;que \u00abconsultada &nbsp;en el d\u00eda de hoy 14 de octubre de 2021, la p\u00e1gina Web &nbsp;de la Rama Judicial y el aplicativo del Sistema de informaci\u00f3n &nbsp;del Registro Nacional de Abogados SIRNA, el estado del tr\u00e1mite &nbsp;solicitado por la accionante relacionado con la cancelaci\u00f3n de &nbsp;su licencia temporal, ya no aparece este tr\u00e1mite pendiente, es &nbsp;decir, en blanco, lo que permite deducir que la accionante, ya podr\u00e1 &nbsp;diligenciar su solicitud de preinscripci\u00f3n de tarjeta &nbsp;profesional de abogados, previo cumplimiento de los requisitos para &nbsp;tal fin y conforme a la normatividad vigente que rige estos tr\u00e1mites &nbsp;(\u2026)\u00bb. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1.- &nbsp;Laura &nbsp;Natalia Vanegas Riobo denuncia &nbsp;por esta v\u00eda al Consejo Superior de la Judicatura \u2013 &nbsp;Unidad de Registro Nacional de Abogados porque para cuando radic\u00f3 &nbsp;la demanda superlativa no hab\u00eda contestado la \u00abpetici\u00f3n &nbsp;de soluci\u00f3n del problema presentado en la plataforma SIRNA\u00bb &nbsp;ni &nbsp;tramitado &nbsp;la \u00abtarjeta &nbsp;profesional\u00bb. &nbsp;<\/p>\n<p>2.- &nbsp;No obstante, resulta &nbsp;di\u00e1fano que el resguardo no &nbsp;tiene vocaci\u00f3n de prosperidad por carencia actual de objeto &nbsp;por \u00abhecho &nbsp;superado\u00bb &nbsp;frente a lo que al primer pedimento se refiere, como quiera que la &nbsp;Unidad de Registro Nacional de Abogados y Auxiliares de la Justicia &nbsp;del Consejo Superior de la Judicatura accedi\u00f3 a su &nbsp;requerimiento de solucionar el &nbsp;\u00abproblema &nbsp;presentado en la plataforma SIRNA\u00bb, respuesta &nbsp;que fue &nbsp; notificada &nbsp;a la interesada &nbsp;a las direcciones e-mail: &nbsp;vanegas.juridicos@gmail.com. &nbsp;asesoria@abogadosvya.co &nbsp;<\/p>\n<p>Sobre &nbsp;dicho t\u00f3pico, la Corte Constitucional ha esbozado: &nbsp;<\/p>\n<p>\u201c(\u2026) &nbsp;[La] &nbsp;jurisprudencia, ha indicado que la carencia actual de objeto se &nbsp;configura cuando frente a las pretensiones esbozadas en la acci\u00f3n &nbsp;de tutela, &nbsp;cualquier orden emitida por el juez no tendr\u00eda alg\u00fan &nbsp;efecto o simplemente \u201ccaer\u00eda en el vac\u00edo\u201d. &nbsp;Espec\u00edficamente, esta figura se materializa a trav\u00e9s en &nbsp;las siguientes circunstancias: &nbsp;(\u2026)\u00bb. &nbsp;<\/p>\n<p>\u00abHecho &nbsp;superado. &nbsp;Este escenario se presenta cuando entre &nbsp;el momento de interposici\u00f3n de la acci\u00f3n de tutela y el &nbsp;fallo, se evidencia que [,] &nbsp;como consecuencia del obrar de la accionada, se super\u00f3 o &nbsp;ces\u00f3 &nbsp;la vulneraci\u00f3n de derechos fundamentales alegada por el &nbsp;accionante. &nbsp;Dicha superaci\u00f3n se configura cuando se realiz\u00f3 la &nbsp;conducta pedida (acci\u00f3n u abstenci\u00f3n) y, por tanto, &nbsp;termin\u00f3 la afectaci\u00f3n, resultando inocua cualquier &nbsp;intervenci\u00f3n del juez constitucional en aras de proteger &nbsp;derecho fundamental alguno, pues ya la accionada los ha garantizado\u2026\u00bb &nbsp;(C.C. &nbsp;T-038 de 2019; EXP. T-7.000.184 citada en STC12401-2021). &nbsp;<\/p>\n<p>3.- &nbsp;Ahora, &nbsp;en &nbsp;lo concerniente &nbsp;con &nbsp;la aspiraci\u00f3n dirigida a que se ordene \u00abexpedir &nbsp;una vez solucionado dicho problema de manera inmediata mi tarjeta &nbsp;profesional\u00bb, &nbsp;se &nbsp;subraya que ello &nbsp;implicar\u00eda una indebida intromisi\u00f3n en los fueros &nbsp;propios del organismo convocado comoquiera &nbsp;que, en el marco de sus competencias, debe efectuar un an\u00e1lisis &nbsp;concienzudo de la documentaci\u00f3n necesaria para verificar el &nbsp;cumplimiento de los requisitos, m\u00e1xime si esa misma entidad &nbsp;mediante oficio (14 oct 2021) le indic\u00f3 que \u00ab(\u2026)deber\u00e1 &nbsp;realizar la respectiva preinscripci\u00f3n en el Sistema de &nbsp;Informaci\u00f3n- SIRNA, en el link: &nbsp;https:\/\/sirna.ramajudicial.gov.co\/Paginas\/Inicio.aspx &nbsp; y allegar, a trav\u00e9s del correo electr\u00f3nico &nbsp;regnal@cendoj.ramajudicial.gov.co &nbsp;, el Formulario \u00danico de M\u00faltiples Tr\u00e1mites, &nbsp;debidamente diligenciado, junto con los dem\u00e1s documentos y &nbsp;requisitos para el tr\u00e1mite de inscripci\u00f3n y expedici\u00f3n &nbsp;de la Tarjeta profesional de abogado(\u2026)\u00bb. &nbsp;<\/p>\n<p>Esta &nbsp;Colegiatura ha sostenido en forma reiterada, &nbsp;que &nbsp;<\/p>\n<p>\u201c(\u2026) &nbsp;este &nbsp;medio de resguardo no fue establecido para sustituir o desplazar las &nbsp;competencias propias de las autoridades judiciales &nbsp;o administrativas, ni &nbsp;para anticipar las decisiones de determinado asunto sometido a su &nbsp;consideraci\u00f3n, pretextando la supuesta violaci\u00f3n de &nbsp;derechos fundamentales. &nbsp;Mientras &nbsp;las personas tengan a su alcance otros medios defensivos &nbsp;o &nbsp;los mismos est\u00e9n siguiendo su curso normal, &nbsp;no &nbsp;es dable acudir a este mecanismo de protecci\u00f3n, &nbsp;ya que no fue instituido para alternar con las herramientas de &nbsp;defensa judicial que el ordenamiento jur\u00eddico ha contemplado, &nbsp;sino cuando carezca de \u00e9stas &nbsp;(STC, &nbsp;28 oct. 2011, rad. 00312-01, reiterada en STC8897-2017, STC10432-2017 &nbsp;y STC6904-2020, entre otras). &nbsp;<\/p>\n<p>4.- &nbsp;Como &nbsp;colof\u00f3n, el amparo instado es inviable. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica de Colombia y por autoridad de la Constituci\u00f3n, &nbsp;DECLARA &nbsp;IMPROCEDENTE la &nbsp;tutela incoada por &nbsp;Laura Natalia Vanegas Riobo. &nbsp;<\/p>\n<p>Comun\u00edquese a &nbsp;las partes por un medio id\u00f3neo y, en caso de no ser impugnado &nbsp;el fallo, rem\u00edtase el expediente a la Corte Constitucional &nbsp;para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>\u00c1LVARO &nbsp;FERNANDO GARC\u00cdA RESTREPO &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC13909-2021 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp; Magistrada &nbsp;ponente &nbsp; STC13909-2021 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 11001-02-30-000-2021-01681-00 &nbsp; Bogot\u00e1, &nbsp;D.C., diecinueve (19) de octubre de dos mil veintiuno (2021). &nbsp; Se &nbsp;desata la tutela que Laura Natalia Vanegas Riobo le instaur\u00f3 &nbsp;al &nbsp;Consejo Superior de la Judicatura \u2013 Unidad de Registro Nacional &nbsp;de Abogados y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-58543","post","type-post","status-publish","format-standard","hentry","category-octubre"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/58543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=58543"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/58543\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=58543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=58543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=58543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}