{"id":58755,"date":"2024-05-17T20:43:04","date_gmt":"2024-05-17T20:43:04","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/stc14424-2021\/"},"modified":"2024-05-17T20:43:04","modified_gmt":"2024-05-17T20:43:04","slug":"stc14424-2021","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/stc14424-2021\/","title":{"rendered":"STC14424 2021"},"content":{"rendered":"<p>STC14424-2021<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>Magistrado &nbsp;Ponente &nbsp;<\/p>\n<p>STC14424-2021 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-04-000-2021-01307-01 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n virtual de veintisiete de octubre de dos mil &nbsp;veintiuno) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., veintisiete (27) de octubre de dos mil veintiuno (2021). &nbsp;<\/p>\n<p>Decide &nbsp;la Corte la impugnaci\u00f3n formulada frente a la sentencia &nbsp;proferida el ocho (8) de julio de 2021 por la Sala de Casaci\u00f3n &nbsp;Penal de esta Corporaci\u00f3n, en la acci\u00f3n de tutela &nbsp;promovida por Martha In\u00e9s Garc\u00eda Casas, contra la Sala &nbsp;de Descongesti\u00f3n No. 2 de la Sala de Casaci\u00f3n Laboral &nbsp;de la Corte Suprema de Justicia, la Sala Laboral del Tribunal &nbsp;Superior de Bucaramanga, el Juzgado Segundo Laboral del Circuito de &nbsp;dicha ciudad y BBVA Horizonte Pensiones y Cesant\u00edas, tr\u00e1mite &nbsp;al cual fueron vinculadas las partes e intervinientes en el asunto &nbsp;que origina la presente queja constitucional. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp;La promotora del resguardo, a trav\u00e9s de apoderado judicial, &nbsp;deprec\u00f3 la protecci\u00f3n de sus derechos fundamentales al &nbsp;debido proceso, m\u00ednimo vital y seguridad social, entre otros, &nbsp;presuntamente conculcados por los accionados en el proceso materia de &nbsp;resguardo. que inco\u00f3 contra, con la finalidad de obtener &nbsp;reconocimiento y pago de pensi\u00f3n de sobreviviente por &nbsp;fallecimiento de su esposo Luis Jes\u00fas Romero (q.e.p.d.). &nbsp;<\/p>\n<p>2. &nbsp;Del libelo tutelar y de la informaci\u00f3n aqu\u00ed allegada, &nbsp;se sintetizan, en lo relevante, los siguientes supuestos f\u00e1cticos: &nbsp;<\/p>\n<p>2.1. &nbsp;La aqu\u00ed gestora promovi\u00f3 demanda ordinaria laboral en &nbsp;contra de BBVA Horizonte Pensiones y Cesant\u00edas, solicitando el &nbsp;reconocimiento de la pensi\u00f3n de sobreviviente &nbsp;por fallecimiento &nbsp;de su compa\u00f1ero permanente Luis Jes\u00fas Romero; proceso &nbsp;que correspondi\u00f3, por reparto, al Juzgado Segundo Laboral del &nbsp;Circuito de Bucaramanga, quien, mediante providencia de 30 de &nbsp;septiembre de 2008, neg\u00f3 las pretensiones invocadas, por no &nbsp;haberse cumplido con los requisitos del art\u00edculo 12 de la Ley &nbsp;797 de 2003, ni la fidelidad de cotizaciones exigidas en dicha norma. &nbsp;<\/p>\n<p>El &nbsp;30 de agosto de 2012, la Sala Laboral del Tribunal Superior del &nbsp;Distrito Judicial de esa ciudad, confirm\u00f3 la determinaci\u00f3n &nbsp;de primera instancia. &nbsp;<\/p>\n<p>En &nbsp;sentencia SL1949 de 16 de mayo de 2018, la Sala de Descongesti\u00f3n &nbsp;N\u00b0 2 de la Sala de Casaci\u00f3n Laboral, decidi\u00f3 \u201cno &nbsp;casar\u201d &nbsp;el fallo de segundo grado. &nbsp;<\/p>\n<p>En &nbsp;criterio de la promotora, las providencias proferidas en el decurso &nbsp;criticado tienen un &nbsp;<\/p>\n<p>\u201cenfoque &nbsp;ecl\u00e9ctico de arribar con la interpretaci\u00f3n de una norma &nbsp;(\u2026) &nbsp;que ve truncado su derecho a la pensi\u00f3n de sobreviviente, &nbsp;disponiendo los operadores judiciales en sus diferentes instancias, &nbsp;que no existe por manera alguna de salirse del encuadre dogm\u00e1tico &nbsp;de la ley 797 de 2003, porque acudir a la condici\u00f3n m\u00e1s &nbsp;beneficiosa le era imposible asomar a los designios de la &nbsp;favorabilidad que le abrigaba (\u2026) &nbsp;en &nbsp;el marco del Acuerdo 049 de 1990, aprobada por el Decreto 758 de &nbsp;1990, siendo el causante un cotizante desde su otrora primigenio.\u201d. &nbsp;<\/p>\n<p>Esgrime &nbsp;que su compa\u00f1ero permanente, era quien le propiciaba su &nbsp;\u201cseguridad &nbsp;econ\u00f3mica\u201d &nbsp;as\u00ed como la de sus dos hijos, por tanto, ante el fallecimiento &nbsp;de aqu\u00e9l, debi\u00f3 radicarse en la ciudad de Los \u00c1ngeles &nbsp;\u2013 Estados Unidos -, con el fin de \u201cconseguir &nbsp;un trabajo bajo la f\u00e9rula de empresas que contratan mano de &nbsp;obra barata\u201d. &nbsp;<\/p>\n<p>LAS &nbsp;RESPUESTAS DE LOS CONVOCADOS &nbsp;<\/p>\n<p>1. &nbsp;La &nbsp;Sala de Descongesti\u00f3n n.\u00b0 2 de Casaci\u00f3n Laboral &nbsp;defendi\u00f3 la legalidad de su pronunciamiento, pues el mismo se &nbsp;encuentra acompasado con el criterio jurisprudencial de la Sala &nbsp;Laboral permanente de esta Corporaci\u00f3n, para la fecha en que &nbsp;se dict\u00f3 la providencia aqu\u00ed criticada y el cual se &nbsp;mantiene invariable hasta la actualidad en lo relacionado a la &nbsp;delimitaci\u00f3n del principio de la condici\u00f3n m\u00e1s &nbsp;beneficiosa a la norma inmediatamente anterior en pensi\u00f3n de &nbsp;sobrevivientes. &nbsp;<\/p>\n<p>2. &nbsp;Los dem\u00e1s accionados guardaron silencio. &nbsp;<\/p>\n<p>LA &nbsp;SENTENCIA IMPUGNADA &nbsp;<\/p>\n<p>El &nbsp;a &nbsp;quo neg\u00f3 &nbsp;el resguardo implorado, tras advertir.: &nbsp;<\/p>\n<p>\u201c(\u2026) &nbsp;no est\u00e1 al arbitrio de la parte tutelante acudir a la acci\u00f3n &nbsp;constitucional para exponer su tesis y obtener un resultado &nbsp;favorable, de ah\u00ed que &nbsp;superflua &nbsp;se torna la pretensi\u00f3n al invocar vulneraci\u00f3n de &nbsp;derechos fundamentales, aspirando con ello a imponer sus razones &nbsp;frente a la interpretaci\u00f3n efectuada por las autoridades &nbsp;judiciales al asunto puesto a su consideraci\u00f3n, en donde con &nbsp;argumentos claros y ajustados al ordenamiento jur\u00eddico se &nbsp;emiti\u00f3 la decisi\u00f3n que puso fin al debate (\u2026)\u201d. &nbsp;<\/p>\n<p>LA &nbsp;IMPUGNACI\u00d3N &nbsp;<\/p>\n<p>La accionante insisti\u00f3 en los argumentos de disenso expuestos &nbsp;en el escrito genitor. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;Conforme al art\u00edculo 86 de la Constituci\u00f3n Pol\u00edtica, &nbsp;la acci\u00f3n de tutela es un mecanismo jur\u00eddico concebido &nbsp;para proteger los derechos fundamentales, cuando son vulnerados o &nbsp;amenazados por los actos u omisiones de las autoridades p\u00fablicas, &nbsp;y en determinadas hip\u00f3tesis de los particulares, cuya &nbsp;naturaleza subsidiaria y residual no permite sustituir o desplazar a &nbsp;los jueces funcionalmente competentes, ni los medios comunes de &nbsp;defensa judicial. &nbsp;<\/p>\n<p>Por &nbsp;lineamiento jurisprudencial, trat\u00e1ndose de actuaciones y &nbsp;providencias judiciales, el resguardo procede de manera excepcional y &nbsp;limitado a la presencia de un \u00abproceder &nbsp;ileg\u00edtimo [que] no es dable removerlo a trav\u00e9s de los &nbsp;medios ordinarios previstos en la ley\u00bb &nbsp;(CSJ STC, 11 may. 2001, rad. n.\u00b0 2001-00183-01); y, por supuesto, &nbsp;siempre que se cumplan los requisitos para su procedencia. &nbsp;<\/p>\n<p>2. &nbsp;Descendiendo al caso concreto se advierte que la queja constitucional &nbsp;censura la interpretaci\u00f3n que la Sala de Descongesti\u00f3n &nbsp;Laboral n.\u00b0 2 dispens\u00f3 al plexo normativo aplicable a la &nbsp;accionante para acceder a la pensi\u00f3n de sobreviviente por &nbsp;muerte de su compa\u00f1ero permanente, en aplicaci\u00f3n del &nbsp;principio de \u201ccondici\u00f3n &nbsp;m\u00e1s beneficiosa\u201d; &nbsp;pues aunque la Colegiatura accionada inicialmente cuestion\u00f3 &nbsp;las fallas t\u00e9cnicas de la demanda de casaci\u00f3n, &nbsp;finalmente emiti\u00f3 pronunciamiento sobre aquel aspecto. &nbsp;<\/p>\n<p>3. &nbsp;La pretensi\u00f3n pensional fue desestimada por la referida &nbsp;colegiatura en sentencia de 16 de mayo de 2018, al estimar que a la &nbsp;peticionaria le era aplicable, en el mejor de los casos, el &nbsp;ordenamiento jur\u00eddico \u201cinmediatamente &nbsp;anterior\u201d al &nbsp;vigente para el momento del fallecimiento de su consorte, sin poder &nbsp;emplear otro m\u00e1s a\u00f1ejo en tanto la condici\u00f3n m\u00e1s &nbsp;beneficiosa debe tener l\u00edmite temporal. &nbsp;<\/p>\n<p>Al &nbsp;respecto, indic\u00f3: &nbsp;<\/p>\n<p>\u201cEs &nbsp;criterio de esta Corporaci\u00f3n que, por regla general, el &nbsp;precepto que regula la pensi\u00f3n de sobrevivientes, es el &nbsp;vigente para la fecha en que fallece el afiliado, pues no fue &nbsp;intenci\u00f3n del legislador implantar reg\u00edmenes de &nbsp;transici\u00f3n para esta clase de prestaciones. En ese sentido, y &nbsp;como lo coligi\u00f3 el Tribunal, la norma aplicable era el &nbsp;art\u00edculo 46 de la Ley 100 de 1993, modificado por el 12 de la &nbsp;Ley 797 de 2003\u201d. &nbsp;<\/p>\n<p>\u201cNo &nbsp;obstante, se han determinado los par\u00e1metros para acudir a la &nbsp;norma anterior y salvaguardar a un grupo poblacional con expectativa &nbsp;leg\u00edtima, no con derecho adquirido, que goza de una situaci\u00f3n &nbsp;jur\u00eddica concreta, cual es, la acreditaci\u00f3n de las &nbsp;semanas m\u00ednimas que exige la reglamentaci\u00f3n derogada &nbsp;para acceder a la prestaci\u00f3n que cubre la contingencia por &nbsp;muerte del afiliado\u201d. &nbsp;<\/p>\n<p>\u201cTambi\u00e9n &nbsp;se ha explicado que es la norma inmediatamente derogada, m\u00e1s &nbsp;no cualquiera en el pasado que contenga una condici\u00f3n que &nbsp;pueda ser cumplida por quien alega que el mencionado principio le &nbsp;beneficie (Sentencia CSJ SL, 14 de ago. 2012, rad. 41671)\u201d. &nbsp;<\/p>\n<p>\u201cPor &nbsp;ello mismo, bajo ninguna circunstancia podr\u00eda acudirse a los &nbsp;art\u00edculos 6\u00b0 y 25 del Acuerdo 049 de 1990, aprobado por el &nbsp;Decreto 758 de 1990, para justificar el reconocimiento de la pensi\u00f3n &nbsp;de sobrevivientes cuando el afiliado muere en vigencia de la Ley 797 &nbsp;de 2003, pues la norma aplicable, en desarrollo de la condici\u00f3n &nbsp;m\u00e1s beneficiosa seria la Ley 100 de 1993 sin modificaciones, &nbsp;siempre y cuando se acrediten los supuestos definidos por esta &nbsp;Corporaci\u00f3n en la sentencia CSJ SL4650-2017\u201d en la que &nbsp;se indic\u00f3:\u201d &nbsp;<\/p>\n<p>\u201c3.1 &nbsp;Afiliado que se encontraba cotizando al momento del cambio normativo\u201d &nbsp;<\/p>\n<p>\u201ca) &nbsp;Que al 29 de enero de 2003 el afiliado estuviese cotizando. &nbsp;<\/p>\n<p>b) &nbsp;Que hubiese aportado 26 semanas en cualquier tiempo, anterior al 29 &nbsp;de enero de 2003. &nbsp;<\/p>\n<p>c) &nbsp;Que la muerte se produzca entre el 29 de enero de 2003 y el 29 de &nbsp;enero de 2006. &nbsp;<\/p>\n<p>d) &nbsp;Que al momento del fallecimiento estuviese cotizando, y &nbsp;<\/p>\n<p>e) &nbsp;Que hubiese cotizado 26 semanas en cualquier tiempo, antes del &nbsp;deceso\u201d. &nbsp;<\/p>\n<p>\u201c3.2 &nbsp; &nbsp; &nbsp; &nbsp;Afiliado &nbsp;que no se encontraba cotizando al momento del cambio normativo\u201d &nbsp;<\/p>\n<p>\u201ca) &nbsp;Que al 29 de enero de 2003 el afiliado no estuviese cotizando. &nbsp;<\/p>\n<p>b) &nbsp;Que hubiese aportado 26 semanas en el a\u00f1o que antecede a dicha &nbsp;data, es decir, entre el 29 de enero de 2003 y el 29 de enero de &nbsp;2002. &nbsp;<\/p>\n<p>c) &nbsp;Que la muerte se produzca entre el 29 de enero de 2003 y el 29 de &nbsp;enero de 2006. &nbsp;<\/p>\n<p>e) &nbsp;Que hubiese cotizado 26 semanas en el a\u00f1o que antecede al &nbsp;fallecimiento\u201d. &nbsp;<\/p>\n<p>\u201c4. &nbsp;Combinaci\u00f3n permisible de las situaciones anteriores\u201d &nbsp;<\/p>\n<p>\u201cA &nbsp;todas estas, tambi\u00e9n hay que tener presente, para otorgar la &nbsp;pensi\u00f3n de invalidez bajo la \u00e9gida de la condici\u00f3n &nbsp;m\u00e1s beneficiosa, la combinaci\u00f3n de las hip\u00f3tesis &nbsp;en precedencia, as\u00ed:\u201d &nbsp;<\/p>\n<p>\u201c4.1 &nbsp;Afiliado que se encontraba cotizando al momento del cambio normativo &nbsp;y cuando falleci\u00f3 no estaba cotizando &nbsp;<\/p>\n<p>La &nbsp;situaci\u00f3n jur\u00eddica concreta se explica porque el &nbsp;afiliado al momento del cambio legislativo, esto es, 29 de enero de &nbsp;2003, se encontraba cotizando al sistema y hab\u00eda aportado 26 &nbsp;semanas o m\u00e1s en cualquier tiempo\u201d. &nbsp;<\/p>\n<p>\u201cSi &nbsp;el mencionado afiliado, adem\u00e1s, no estaba cotizando para la &nbsp;\u00e9poca del siniestro de la muerte &#8211; \u00abhecho que hace &nbsp;exigible el acceso a la pensi\u00f3n\u00bb- que debe sobrevenir &nbsp;entre el 29 de enero de 2003 y 29 de enero de 2006, pero ten\u00eda &nbsp;26 semanas de cotizaci\u00f3n en el a\u00f1o inmediatamente &nbsp;anterior al fallecimiento, es dable la aplicaci\u00f3n del &nbsp;principio de la condici\u00f3n m\u00e1s beneficiosa. Acontece, &nbsp;sin embargo, que de no verificarse este \u00faltimo supuesto, no &nbsp;aplica tal postulado\u201d. &nbsp;<\/p>\n<p>\u201cAunque &nbsp;suene repetitivo, es menester insistir en que si al momento del &nbsp;cambio legislativo, esto es, 29 de enero de 2003, el afiliado se &nbsp;encontraba cotizando al sistema y no le hab\u00eda aportado 26 &nbsp;semanas o m\u00e1s en cualquier tiempo, no goza de una situaci\u00f3n &nbsp;jur\u00eddica concreta\u201d. &nbsp;<\/p>\n<p>\u201c4.2 &nbsp;Afiliado que no se encontraba cotizando al momento del cambio &nbsp;normativo y cuando falleci\u00f3 estaba cotizando\u201d. &nbsp;<\/p>\n<p>\u201cAc\u00e1, &nbsp;la situaci\u00f3n jur\u00eddica concreta nace si el afiliado al &nbsp;momento del cambio legislativo, vale decir, 29 de enero de 2003, no &nbsp;estaba cotizando al sistema pero hab\u00eda aportado 26 o m\u00e1s &nbsp;semanas en el a\u00f1o inmediatamente anterior, esto es, entre el &nbsp;29 de enero de 2003 y 29 de enero de 2002\u201d. &nbsp;<\/p>\n<p>\u201cAhora, &nbsp;si el aludido afiliado estaba cotizando al momento de la muerte &#8211; &nbsp;\u00abhecho que hace exigible el acceso a la pensi\u00f3n\u00bb- &nbsp;que debe suceder entre el 29 de enero de 2003 y el 29 de enero de &nbsp;2006, y ten\u00eda 26 semanas de cotizaci\u00f3n en el cualquier &nbsp;tiempo, igualmente se aplica el postulado de la condici\u00f3n m\u00e1s &nbsp;beneficiosa. La Sala juzga pertinente advertir que de no cumplirse &nbsp;este \u00faltimo supuesto, no se aplica dicho principio\u201d. &nbsp;<\/p>\n<p>\u201cEn &nbsp;el mismo sentido que en el caso delantero, y a\u00fan a riesgo de &nbsp;fatigar, debe acentuarse que si el afiliado al momento del cambio &nbsp;legislativo, esto es, 29 de enero de 2003, no estaba cotizando al &nbsp;sistema y tampoco hab\u00eda aportado 26 o m\u00e1s semanas en el &nbsp;a\u00f1o inmediatamente anterior, esto es, entre el 29 de enero de &nbsp;2003 y 29 de enero de 2002, no existe una situaci\u00f3n jur\u00eddica &nbsp;concreta\u201d. &nbsp;<\/p>\n<p>Al &nbsp;aplicar el anterior criterio en el caso bajo estudio, la Sala de &nbsp;Descongesti\u00f3n tutelada, concluy\u00f3: &nbsp;<\/p>\n<p>\u201c(\u2026) &nbsp;[P]asa la Corte a establecer si el causante, Luis Jes\u00fas &nbsp;Romero, dej\u00f3 acreditada la pensi\u00f3n de sobrevivientes en &nbsp;desarrollo del principio de la condici\u00f3n m\u00e1s &nbsp;beneficiosa:\u201d &nbsp;<\/p>\n<p>\u201c1. &nbsp;Que al 29 de enero de 2003 el causante no estuviese cotizando: &nbsp;de acuerdo con la historia laboral de folio 84 del cuaderno &nbsp;principal, el fallecido, para dicha fecha no estaba cotizando\u201d. &nbsp;<\/p>\n<p>\u201c2. &nbsp;Que hubiese aportado 26 semanas en el a\u00f1o que antecede a dicha &nbsp;data, es decir, entre el 29 de enero de 2003 y el 29 de enero de &nbsp;2002: &nbsp;el causante ten\u00eda 12,42 semanas de cotizaci\u00f3n entre las &nbsp;fechas mencionadas\u201d. &nbsp;<\/p>\n<p>\u201c3. &nbsp;Que la muerte se produzca entre el 29 de enero de 2003 y el 29 de &nbsp;enero de 2006: &nbsp;el &nbsp;se\u00f1or Luis Jes\u00fas Romero falleci\u00f3 el 21 de &nbsp;octubre de 2004, es decir, dentro de las fechas indicadas\u201d. &nbsp;<\/p>\n<p>\u201c4. &nbsp;Que al momento del deceso no estuviese cotizando: &nbsp;seg\u00fan historia laboral de folio 87 ib\u00eddem, el causante &nbsp;no estaba cotizando para la calenda del deceso, y\u201d &nbsp;<\/p>\n<p>\u201c5. &nbsp;Que hubiese cotizado 26 semanas en el a\u00f1o que antecede al &nbsp;fallecimiento: &nbsp;en dicho periodo el causante solo cotiz\u00f3 12.85 semanas\u201d. &nbsp;<\/p>\n<p>\u201cDe &nbsp;manera que el extinto no logr\u00f3 satisfacer las condiciones &nbsp;expuestas para aplicar en favor de sus beneficiarios el principio de &nbsp;la condici\u00f3n m\u00e1s beneficiosa, y con ello emplear el &nbsp;art\u00edculo 46 original de la Ley 100 de 1993, cuyos requisitos, &nbsp;como se vio, tampoco satisfizo\u201d. &nbsp;<\/p>\n<p>As\u00ed &nbsp;las cosas, se concluye que la decisi\u00f3n controvertida &nbsp;no luce antojadiza, caprichosa o subjetiva, con independencia de que &nbsp;se comparta, descart\u00e1ndose la presencia de una v\u00eda de &nbsp;hecho, de manera que la queja de la peticionaria no halla recibo en &nbsp;esta sede excepcional. &nbsp;<\/p>\n<p>Y &nbsp;es que, en rigor, lo que plante\u00f3 la inconforme es una &nbsp;diferencia de criterio acerca de la manera como el estrado acusado &nbsp;interpret\u00f3 las normas que rigen el reconocimiento de la &nbsp;pensi\u00f3n de sobrevivientes requerida por ella y los argumentos &nbsp;expuestos en la decisi\u00f3n reprochada, la cual, acogi\u00f3 la &nbsp;l\u00ednea jurisprudencial que tiene la Sala de Casaci\u00f3n &nbsp;Laboral respecto del principio de la condici\u00f3n m\u00e1s &nbsp;beneficiosa. &nbsp;<\/p>\n<p>Tales &nbsp;inferencias no pueden ser desaprobadas de plano o calificadas de &nbsp;absurdas o arbitrarias, \u201cm\u00e1xime &nbsp;si la que ha hecho no resulta contraria a la raz\u00f3n, es decir &nbsp;si no est\u00e1 demostrado el defecto apuntado en la demanda, ya &nbsp;que con ello desconocer\u00edan normas de orden p\u00fablico &nbsp;(&#8230;) &nbsp;y entrar\u00eda a la relaci\u00f3n procesal a usurpar las &nbsp;funciones asignadas v\u00e1lidamente al \u00faltimo para definir &nbsp;el conflicto de intereses\u201d &nbsp;(CSJ STC, 11 en. 2005, rad. 1451). &nbsp;<\/p>\n<p>Sobre &nbsp;el particular, tambi\u00e9n se ha dicho de forma reiterada que &nbsp;\u201cno &nbsp;se puede recurrir a la acci\u00f3n tutelar para imponer al fallador &nbsp;una determinada interpretaci\u00f3n de las normas procesales &nbsp;aplicables al asunto sometido a su estudio o una espec\u00edfica &nbsp;valoraci\u00f3n probatoria, a efectos de que su raciocinio coincida &nbsp;con el de las partes\u201d. &nbsp;(CSJ STC, 18 abr. 2012, rad. 2012-0009-01; STC, 27 jun. 2012, rad. &nbsp;2012-00088-01; y STC, 12 ago. 2013, rad. 2013-00125-01). &nbsp;<\/p>\n<p>Lo &nbsp;anterior debido a que la funci\u00f3n jurisdiccional dota al juez &nbsp;de autonom\u00eda plena, de manera que s\u00f3lo el yerro &nbsp;ostensible, innegable y trascendente, sirve de apoyo por v\u00eda &nbsp;de tutela para dar al traste con el pronunciamiento del juzgador &nbsp;natural. &nbsp;<\/p>\n<p>4. &nbsp;Corolario de lo discurrido en precedencia, y sin m\u00e1s &nbsp;consideraciones por ser innecesarias, se impone mantener el fallo &nbsp;refutado, advirtiendo que para la Sala es procedente el respeto por &nbsp;las decisiones judiciales, m\u00e1xime cuando se trata de &nbsp;organismos de cierre, salvo cuando aparezcan visibles las causales de &nbsp;procedibilidad del amparo, comp\u00e1rtase o no lo decidido por el &nbsp;juez natural, posici\u00f3n que mantendr\u00e1 en decisiones &nbsp;futuras a partir de esta fecha en que se presenta este cambio de &nbsp;posici\u00f3n frente a decisiones judiciales. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica y por autoridad de la ley, confirma &nbsp;el &nbsp;fallo impugnado. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;mediante telegrama a los interesados y rem\u00edtase el expediente &nbsp;a la Corte Constitucional para la eventual revisi\u00f3n. &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>\u00c1LVARO &nbsp;FERNANDO GARC\u00cdA RESTREPO &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC14424-2021 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp; Magistrado &nbsp;Ponente &nbsp; STC14424-2021 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-04-000-2021-01307-01 &nbsp; (Aprobado &nbsp;en sesi\u00f3n virtual de veintisiete de octubre de dos mil &nbsp;veintiuno) &nbsp; Bogot\u00e1, &nbsp;D.C., veintisiete (27) de octubre de dos mil veintiuno (2021). &nbsp; Decide &nbsp;la Corte la impugnaci\u00f3n formulada frente a la sentencia &nbsp;proferida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-58755","post","type-post","status-publish","format-standard","hentry","category-octubre"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/58755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=58755"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/58755\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=58755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=58755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=58755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}