{"id":58926,"date":"2024-05-17T20:42:04","date_gmt":"2024-05-17T20:42:04","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac5409-2021-2021-04034-00-1\/"},"modified":"2024-05-17T20:42:04","modified_gmt":"2024-05-17T20:42:04","slug":"ac5409-2021-2021-04034-00-1","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac5409-2021-2021-04034-00-1\/","title":{"rendered":"AC 5409 2021"},"content":{"rendered":"<p>AC5409-2021 (2021-04034-00)_1<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC5409-2021 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2021-04034-00 &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., diecisiete (17) de noviembre de dos mil veintiuno (2021). &nbsp;<\/p>\n<p>Se &nbsp;decide el conflicto de competencia que surgi\u00f3 entre el Juzgado &nbsp;Promiscuo del Circuito de la Virginia y el despacho Diecis\u00e9is &nbsp;Civil del Circuito de Bogot\u00e1, atinente al conocimiento de la &nbsp;acci\u00f3n popular instaurada por Sebasti\u00e1n Colorado contra &nbsp;el Banco Davivienda S.A. &nbsp;<\/p>\n<p>I. &nbsp;ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp;En defensa del bien colectivo, el demandante interpuso acci\u00f3n &nbsp;popular en contra de la aludida entidad, argumentando que \u00aben &nbsp;la &nbsp;actualidad no Cuenta en el Inmueble donde presta sus servicios &nbsp;p\u00fablicos, con un int\u00e9rprete profesional ni con un gu\u00eda &nbsp;interprete profesional\u2026, tal como lo ordena la ley 982 de &nbsp;2005\u00bb1. &nbsp;<\/p>\n<p>Asimismo, &nbsp;tras pregonar que \u00abla &nbsp;vulneraci\u00f3n o &nbsp;agravio &nbsp;ocurre a lo LARGO Y ANCHO DEL TERRITORIO PATRIO\u00bb, &nbsp;precis\u00f3 &nbsp;que el sitio de la vulneraci\u00f3n es en \u00abBOGOTA &nbsp;CUNDIMARCA (sic)\u00bb. &nbsp;Adem\u00e1s, resalt\u00f3 que las \u00abnotificaciones\u00bb &nbsp;del \u00abaccionado\u00bb &nbsp;se han de efectuar en la \u00abCARRERA &nbsp;68 B # 40 -39 LOC 106 CENTRO COMERCIAL \/ SALITRE PLAZA\u00bb2. &nbsp;<\/p>\n<p>A &nbsp;partir de la anterior denuncia, el gestor solicit\u00f3 a la &nbsp;judicatura ordenar a la sociedad accionada que \u00abcontrate &nbsp;de planta un profesional interprete y un profesional gu\u00eda &nbsp;interprete de planta en el inmueble de la entidad accionada a fin de &nbsp;cumplir ley 982 de 2005, art 8 en un t\u00e9rmino NO MAYOR A 30 &nbsp;DIAS o contrate con entidad id\u00f3nea CERTIFICADA por el &nbsp;ministerio de educaci\u00f3n nacional\u00bb. &nbsp;Adicionalmente, \u00abaplicar &nbsp;art 34 ley 472 de 1998 inciso final, el cual no est\u00e1 derogado &nbsp;por autoridad alguna y Se concedan COSTAS [sic]\u00bb, &nbsp;entre &nbsp;otras.3 &nbsp;<\/p>\n<p>2. Por reparto, el &nbsp;escrito inicial fue asignado al despacho Promiscuo del Circuito de la &nbsp;Virginia, el cual, mediante prove\u00eddo del 18 de noviembre de &nbsp;2020, admiti\u00f3 la demanda. Posteriormente, por auto del 15 de &nbsp;abril de 2021, declar\u00f3 la nulidad de todo lo actuado y la &nbsp;rechaz\u00f3 por falta de competencia. &nbsp;En &nbsp;consecuencia, remiti\u00f3 el expediente a los Juzgados Civiles del &nbsp;Circuito de Bogot\u00e1 \u2013 Cundinamarca, en tanto consider\u00f3 &nbsp;que: &nbsp;<\/p>\n<p>\u00ab\u2026aunque &nbsp;el actor popular decidi\u00f3 presentar su demanda ante el Juez &nbsp;Promiscuo del Circuito de La Virginia &#8211; Risaralda, tal proceder no se &nbsp;ajusta a las opciones que le otorga el art\u00edculo 16 de la Ley &nbsp;472 de 1998, pues dicho funcionario no es el juzgador del territorio &nbsp;de ocurrencia de los hechos narrados, ni el del domicilio principal &nbsp;de la demandada, por cuanto pese a que en este municipio existe una &nbsp;sucursal de la entidad financiera accionada, ese motivo no es &nbsp;suficiente para que se radique el conocimiento sobre el asunto en &nbsp;esta localidad, como quiera que la norma no establece dicho factor &nbsp;como determinante para fijar la competencia en las acciones &nbsp;populares\u00bb4. &nbsp;<\/p>\n<p>Inconforme &nbsp;con la anterior decisi\u00f3n, el actor interpuso recurso de &nbsp;reposici\u00f3n y en subsidio apelaci\u00f3n, entre otros, &nbsp;amparado en que \u00abLa &nbsp;juez no puede desconocer la perpetuatio jurisdictionis\u2026tampoco &nbsp;se puede desconocer normas de orden publico (sic) y nopuede (sic) ni &nbsp;declarar la nulidad de lo actuado y menos rechazar por &nbsp;competencia\u2026\u00bb5. &nbsp;<\/p>\n<p>3. &nbsp;Por auto del 29 de abril de 2021, la autoridad judicial de la &nbsp;Virginia resolvi\u00f3 mantener su postura. &nbsp;<\/p>\n<p>4. &nbsp;Cumplidos &nbsp;los tr\u00e1mites, el expediente fue entregado al &nbsp;despacho Diecis\u00e9is Civil del Circuito de Bogot\u00e1. Sin &nbsp;embargo, en &nbsp;resoluci\u00f3n del 26 de julio de 2021, opt\u00f3 por manifestar &nbsp;que no le correspond\u00eda asumir este asunto. En consecuencia, &nbsp;promovi\u00f3 el conflicto que ocupa la atenci\u00f3n de la &nbsp;Corte. Para ello, expres\u00f3 que &nbsp;<\/p>\n<p>\u00ab\u2026dando &nbsp;aplicaci\u00f3n al principio de perpetuatio jurisdictionis y en &nbsp;concordancia con los art\u00edculos 16 y 139 del C\u00f3digo &nbsp;General del Proceso, al rompe se advierte que no resulta de recibo la &nbsp;argumentaci\u00f3n que expone el juzgado remitente para sustrarse &nbsp;del conocimiento del proceso, cuando la competencia ya hab\u00eda &nbsp;sido asumida por dicha agencia judicial&#8230;\u00bb6. &nbsp;<\/p>\n<p>5. &nbsp;As\u00ed &nbsp;las cosas, conforme al canon 139 del C\u00f3digo General del &nbsp;Proceso, se entra a desatar el t\u00f3pico en cuesti\u00f3n. &nbsp;<\/p>\n<p>II. &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;Habida cuenta que se &nbsp;enfrentan juzgados de distinto distrito judicial -Pereira y Bogot\u00e1-, &nbsp;la Corte es la competente para resolver el conflicto negativo &nbsp;suscitado entre ellos, de conformidad con los art\u00edculos 139 &nbsp;ibidem &nbsp;y 16 de la Ley 270 de 1996, modificado por el 7\u00ba de su par 1285 &nbsp;de 2009. &nbsp;<\/p>\n<p>2. &nbsp;El &nbsp;ordenamiento jur\u00eddico establece factores de competencia para &nbsp;definir a qu\u00e9 funcionario judicial le corresponde el &nbsp;conocimiento de determinado asunto. Tales criterios, incluso, pueden &nbsp;ser concurrentes. &nbsp;<\/p>\n<p>La &nbsp;Corte, en un pronunciamiento que guarda simetr\u00eda con el aqu\u00ed &nbsp;analizado, tuvo ocasi\u00f3n de se\u00f1alar que: &nbsp;<\/p>\n<p>\u00abLa &nbsp;rese\u00f1ada norma consagra un evento de \u201cconcurrencia de &nbsp;fueros\u201d, que en el \u00e1mbito del \u201cfactor Territorial\u201d &nbsp;posibilitan al \u201cactor popular\u201d la escogencia del &nbsp;funcionario judicial para presentar el escrito introductorio, aspecto &nbsp;este que la doctrina jurisprudencial de esta Corporaci\u00f3n ha &nbsp;explicado en reiteradas oportunidades, se\u00f1alando que \u201cel &nbsp;gestor de la demanda al momento de seleccionar el funcionario &nbsp;competente, bien puede encontrarse frente a la presencia de uno s\u00f3lo &nbsp;de los fueros o de varios de ellos, (\u2026), evento ante el cual, &nbsp;iterase, le corresponder\u00e1, a su arbitrio, determinar por cu\u00e1l &nbsp;de ellos se decide. Y, claro una vez defina sobre el particular, en &nbsp;principio, en esos t\u00e9rminos deja definida la competencia, la &nbsp;que, por excepci\u00f3n, puede variar solo si el demandado, &nbsp;mediante los mecanismos id\u00f3neos refuta la atribuci\u00f3n &nbsp;efectuada por el demandante (CSJ &nbsp;AC013-2016, 12 ene. 2015, rad. 2015-03159). &nbsp;<\/p>\n<p>El &nbsp;anterior lineamiento, atribuye al actor popular la facultad de &nbsp;definir ante que autoridad jurisdiccional ventila el asunto. Por &nbsp;supuesto, teniendo como derroteros el juez del lugar de ocurrencia de &nbsp;los hechos o el domicilio del demandado -a prevenci\u00f3n del &nbsp;gestor-. Una vez materializada dicha escogencia, resulta vinculante &nbsp;para el funcionario ante el cual se efect\u00faa. &nbsp;<\/p>\n<p>4. &nbsp;En &nbsp;el asunto objeto de estudio, la Sala advierte que no se configura el &nbsp;cumplimiento del factor territorial mencionado. Por una parte, el &nbsp;actor present\u00f3 la acci\u00f3n en un sitio distinto al &nbsp;se\u00f1alado en el escrito inicial como domicilio de la demandada &nbsp;-Bogot\u00e1-. Y por otra, el lugar consignado como de ocurrencia &nbsp;de los hechos fue la misma ciudad. No obstante, inexplicablemente el &nbsp;actor radic\u00f3 la demanda en la Virginia (Risaralda), no siendo &nbsp;esta municipalidad ni el domicilio anunciado ni el lugar de &nbsp;consumaci\u00f3n de los hechos. &nbsp;<\/p>\n<p>Sin &nbsp;embargo, el Juzgado Promiscuo del Circuito de la Virginia no se &nbsp;percat\u00f3 de dichas circunstancias. Por el contrario, mediante &nbsp;auto de fecha 18 de noviembre de 2020, dio por acreditado los &nbsp;requisitos del art\u00edculo 18 de la Ley 472 de 1998 y avoc\u00f3 &nbsp;conocimiento de la demanda, present\u00e1ndose as\u00ed, la &nbsp;prorrogabilidad de la competencia. &nbsp;<\/p>\n<p>En &nbsp;el punto, la Sala ha considerado que: &nbsp;<\/p>\n<p>\u00ab\u2026Al &nbsp;juzgador, &nbsp;\u2018en l\u00ednea de principio, le est\u00e1 vedado sustraerse &nbsp;por su propia iniciativa de la competencia que inicialmente asumi\u00f3, &nbsp;pues una vez admitida la demanda, s\u00f3lo el demandado puede &nbsp;controvertir ese aspecto cuando se le notifica de la existencia del &nbsp;proceso. Dicho de otro modo, \u2018en virtud del principio de la &nbsp;\u00abperpetuatio jurisdictionis\u00bb, una vez establecida la &nbsp;competencia territorial, atendiendo para el efecto las atestaciones &nbsp;de la demanda, las ulteriores alteraciones de las circunstancias que &nbsp;la determinaron no extinguen la competencia del juez que aprehendi\u00f3 &nbsp;el conocimiento del asunto. \u201cSi el demandado (\u2026) no &nbsp;objeta la competencia, a la parte actora y al propio juez le est\u00e1 &nbsp;vedado modificarla\u2026\u00bb (CSJ &nbsp;SC AC051-2016, 15 ene. 2016, rad. 2015-02913-00). &nbsp;<\/p>\n<p>5. &nbsp;Bajo dicha hermen\u00e9utica y revisadas las actuaciones &nbsp;jurisdiccionales, se evidencia que el funcionario judicial avoc\u00f3 &nbsp;el tr\u00e1mite de la acci\u00f3n asumiendo de esta manera su &nbsp;competencia. Por tanto, no pod\u00eda a su arbitrio separarse del &nbsp;conocimiento del asunto, a menos que el demandado hubiese cuestionado &nbsp;dicho proceder, circunstancia que no acaeci\u00f3. &nbsp;<\/p>\n<p>Sobre &nbsp;el particular, la Sala indic\u00f3 que \u00abUna &nbsp;vez el asunto es asignado a un operador judicial, a \u00e9l le &nbsp;corresponde verificar lo relativo a la competencia. Si admite la &nbsp;demanda, ese acto comporta la asunci\u00f3n de la aptitud legal &nbsp;para conocer de la causa, con lo cual afirma la misma y excluye a &nbsp;todos los dem\u00e1s de todas las jurisdicciones y todas las &nbsp;competencias, o bien puede, rechazarla y remitirla a la autoridad que &nbsp;considere competente\u201d7. &nbsp;<\/p>\n<p>Asimismo, &nbsp;en un caso de an\u00e1logo temperamento, destac\u00f3 que \u00ab\u2026una &nbsp;vez el caso fue admitido por el prenombrado estrado judicial de La &nbsp;Virginia, \u00e9ste se equivoc\u00f3 al repelerlo, desconociendo &nbsp;el principio de la perpetuatio jurisdictionis, de manera que se le &nbsp;remitir\u00e1 para contin\u00fae el tr\u00e1mite que legalmente &nbsp;corresponda y se pondr\u00e1 al tanto de ello a la otra autoridad &nbsp;judicial involucrada\u2026\u00bb (CSJ &nbsp;AC2959-2021, 22 jul. rad. 2021-02330-00). &nbsp;<\/p>\n<p>6. &nbsp;Por &nbsp;las razones expuestas, procede remitir la presente demanda al &nbsp;Despacho Promiscuo del Circuito de la Virginia -Risaralda- para que &nbsp;contin\u00fae con el tr\u00e1mite de &nbsp;la acci\u00f3n emprendida. &nbsp;<\/p>\n<p>III. &nbsp;DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, &nbsp;la Sala de Casaci\u00f3n Civil de la Corte Suprema, &nbsp;<\/p>\n<p>RESUELVE &nbsp;<\/p>\n<p>PRIMERO. &nbsp;Declarar &nbsp;que el Juzgado Promiscuo del Circuito de la Virginia es el competente &nbsp;para conocer de la acci\u00f3n popular de la referencia, quien &nbsp;deber\u00e1 continuar con su tr\u00e1mite. &nbsp;<\/p>\n<p>SEGUNDO. &nbsp;Comunicar &nbsp;lo decidido al Juzgado Diecis\u00e9is Civil del Circuito de Bogot\u00e1, &nbsp;acompa\u00f1\u00e1ndole copia &nbsp;de este prove\u00eddo. &nbsp;<\/p>\n<p>TERCERO. &nbsp;Remitir &nbsp;el expediente a la autoridad judicial referida en el numeral primero &nbsp;de esta decisi\u00f3n. &nbsp;<\/p>\n<p>CUARTO: &nbsp;Por &nbsp;Secretar\u00eda, librar los oficios correspondientes y dejar las &nbsp;constancias del caso. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folio 2 archivo 01. 2020-00143 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;AP DAVIVIENDA SALITRE PLAZA BOGOTA.PDF Expediente digital &nbsp;<\/p>\n<p>2\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Ibidem &nbsp;<\/p>\n<p>3\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Ibidem. &nbsp;<\/p>\n<p>4\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folio 1-6 del archivo 04. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;ESTADO 15 ABRIL 2021 2020-00141 al 300 NULIDAD.pdf Expediente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;digital &nbsp;<\/p>\n<p>5\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folio 1-3 del archivo 06. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Interpone reposici\u00f3n 80 al 300.docx Expediente digital &nbsp;<\/p>\n<p>6\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folios 1-5 del archivo 17. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Auto 26 de julio de 2021 ConflictoCompetencia .pdf Expediente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;digital &nbsp;<\/p>\n<p>7\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CSJ AC1836-2019. &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC5409-2021 (2021-04034-00)_1 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC5409-2021 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2021-04034-00 &nbsp; Bogot\u00e1 &nbsp;D.C., diecisiete (17) de noviembre de dos mil veintiuno (2021). &nbsp; Se &nbsp;decide el conflicto de competencia que surgi\u00f3 entre el Juzgado &nbsp;Promiscuo del Circuito de la Virginia y el despacho Diecis\u00e9is &nbsp;Civil del Circuito de Bogot\u00e1, atinente al conocimiento de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-58926","post","type-post","status-publish","format-standard","hentry","category-noviembre"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/58926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=58926"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/58926\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=58926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=58926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=58926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}