{"id":58982,"date":"2024-05-17T20:42:06","date_gmt":"2024-05-17T20:42:06","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac5560-2021-2021-00184-00\/"},"modified":"2024-05-17T20:42:06","modified_gmt":"2024-05-17T20:42:06","slug":"ac5560-2021-2021-00184-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/ac5560-2021-2021-00184-00\/","title":{"rendered":"AC 5560 2021"},"content":{"rendered":"<p>AC5560-2021 (2021-00184-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado &nbsp;Ponente &nbsp;<\/p>\n<p>AC5560-2021 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2021-00184-00 &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., veinticinco (25) de noviembre de dos mil veintiuno (2021). &nbsp;<\/p>\n<p>Se &nbsp;decide lo pertinente frente al recurso de s\u00faplica, interpuesto &nbsp;por Eduardo Rojas Hurtado frente &nbsp;al auto proferido por el Magistrado Ponente el 8 de marzo de 2021 &nbsp;(AC732), con el cual se resolvi\u00f3 la queja propuesta contra el &nbsp;prove\u00eddo del 8 de octubre de 2020 que neg\u00f3 conceder el &nbsp;recurso de casaci\u00f3n interpuesto por el recurrente contra la &nbsp;sentencia proferida por la Sala Civil del Tribunal Superior de Bogot\u00e1 &nbsp;el 31 de enero de 2020, en el proceso verbal de pertenencia incoado &nbsp;por este contra Credigane Electrodom\u00e9sticos S.A. y personas &nbsp;indeterminadas. &nbsp;<\/p>\n<p>I. &nbsp;ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp;Con providencia del 8 de octubre de 2020, la Sala Civil del Tribunal &nbsp;Superior de Bogot\u00e1, deneg\u00f3 la concesi\u00f3n del &nbsp;recurso extraordinario de casaci\u00f3n interpuesto por el &nbsp;accionante, tras considerar que no se cumpli\u00f3 con el requisito &nbsp;consagrado en el art\u00edculo 338 del C\u00f3digo General del &nbsp;Proceso. El pretensor propuso reposici\u00f3n y en subsidio queja. &nbsp;Sin embargo, la Magistrada sustanciadora mantuvo su decisi\u00f3n, &nbsp;por lo que orden\u00f3 darle curso a la queja. &nbsp;<\/p>\n<p>2. &nbsp;Surtido el traslado de que trata el inciso 4\u00b0 de la regla 353 del &nbsp;estatuto adjetivo, el Magistrado sustanciador, con auto del 8 de &nbsp;marzo de 2021 (AC732), resolvi\u00f3 declarar bien denegado el &nbsp;recurso de casaci\u00f3n propuesto frente a la sentencia del 31 de &nbsp;enero de 2020, proferida por la Sala Civil del Tribunal Superior de &nbsp;Bogot\u00e1 en el proceso referenciado. &nbsp;<\/p>\n<p>Inconforme &nbsp;con esa decisi\u00f3n, el demandante interpuso \u00abrecurso &nbsp;de s\u00faplica\u00bb. &nbsp;En este, sostuvo que, \u00abEL &nbsp;ARGUMENTO PRINCIPAL sobre el cual versa el presente RECURSO es la &nbsp;naturaleza misma del objeto de discusi\u00f3n. En efecto, con el &nbsp;recurso de QUEJA presentado, se argument\u00f3 el asunto de la &nbsp;CUANTIA para presentar el RECURSO DE CASACION, pero no ha quedado lo &nbsp;suficiente claro los MOTIVOS por los cuales el presente asunto no es &nbsp;un ASUNTO objeto de INTERES NACIONAL1\u00bb. &nbsp;Remat\u00f3 &nbsp;exponiendo que en \u00abla &nbsp;PROVIDENCIA que es motivo de estudio, el MAGISTRADO \u00fanicamente &nbsp;realiza un an\u00e1lisis sobre el VALOR DE LA PRETENSION, pero &nbsp;omite el an\u00e1lisis a lo m\u00e1s importante del RECURSO que &nbsp;es la UNIFICACION DE CRITERIOS\u00bb. &nbsp;<\/p>\n<p>3. &nbsp;La Secretar\u00eda de la Sala corri\u00f3 el traslado respectivo, &nbsp;el cual venci\u00f3 en silencio. Posteriormente, ingres\u00f3 el &nbsp;expediente a este despacho para resolver lo pertinente. &nbsp;<\/p>\n<p>II. &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;Conforme al art\u00edculo 331 del C.G.P., el recurso de s\u00faplica &nbsp;procede contra los autos \u00abque &nbsp;por su naturaleza serian apelables, dictados por el Magistrado &nbsp;sustanciador en el curso de la segunda instancia o \u00fanica &nbsp;instancia, o durante el tr\u00e1mite de la apelaci\u00f3n de un &nbsp;auto. Tambi\u00e9n procede contra el auto que resuelve sobre la &nbsp;admisi\u00f3n del recurso de apelaci\u00f3n o casaci\u00f3n y &nbsp;contra los autos que en el tr\u00e1mite de los recursos &nbsp;extraordinarios de casaci\u00f3n o revisi\u00f3n profiera &nbsp;el magistrado sustanciador y que por su naturaleza hubieran sido &nbsp;susceptibles de apelaci\u00f3n. No &nbsp;procede contra los autos mediante los cuales se resuelva la apelaci\u00f3n &nbsp;o queja\u00bb &nbsp;-se subraya-. &nbsp;<\/p>\n<p>2. &nbsp;Bajo esa perspectiva, en el caso en concreto, se advierte la &nbsp;improcedencia del mecanismo aludido, formulado frente al auto que &nbsp;desat\u00f3 la queja propuesta contra la providencia proferida por &nbsp;la Sala Civil del Tribunal Superior de Bogot\u00e1 el 31 de enero &nbsp;de 2020, con la cual se deneg\u00f3 la concesi\u00f3n de la &nbsp;impugnaci\u00f3n extraordinaria. Lo anterior, por cuanto la &nbsp;procedibilidad de dicho recurso est\u00e1 expresamente excluida en &nbsp;la norma legal citada. &nbsp;<\/p>\n<p>3. &nbsp;As\u00ed las cosas, la s\u00faplica invocada de rechazar\u00e1 &nbsp;de plano por improcedente. &nbsp;<\/p>\n<p>III. &nbsp;DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Sala de Casaci\u00f3n Civil de la &nbsp;Corte Suprema de Justicia, &nbsp;<\/p>\n<p>RESUELVE: &nbsp;<\/p>\n<p>PRIMERO. &nbsp;RECHAZAR por &nbsp;improcedente el recurso de s\u00faplica interpuesto frente al auto &nbsp;AC732 del 8 de marzo de 2021. &nbsp;<\/p>\n<p>SEGUNDO. &nbsp;Retornar &nbsp;el expediente al Despacho del Magistrado Ponente para lo que &nbsp;corresponda. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Fl. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;3-4. Recurso de s\u00faplica. Expediente digital. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC5560-2021 (2021-00184-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; Magistrado &nbsp;Ponente &nbsp; AC5560-2021 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2021-00184-00 &nbsp; Bogot\u00e1 &nbsp;D.C., veinticinco (25) de noviembre de dos mil veintiuno (2021). &nbsp; Se &nbsp;decide lo pertinente frente al recurso de s\u00faplica, interpuesto &nbsp;por Eduardo Rojas Hurtado frente &nbsp;al auto proferido por el Magistrado Ponente el 8 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-58982","post","type-post","status-publish","format-standard","hentry","category-noviembre"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/58982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=58982"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/58982\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=58982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=58982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=58982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}