{"id":59437,"date":"2024-05-17T20:42:24","date_gmt":"2024-05-17T20:42:24","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/stc15473-2021\/"},"modified":"2024-05-17T20:42:24","modified_gmt":"2024-05-17T20:42:24","slug":"stc15473-2021","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/stc15473-2021\/","title":{"rendered":"STC15473 2021"},"content":{"rendered":"<p>STC15473-2021<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>HILDA GONZ\u00c1LEZ &nbsp;NEIRA &nbsp;<\/p>\n<p>Magistrada ponente &nbsp;<\/p>\n<p>STC15473-2021 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 11001-02-30-000-2021-01947-00 &nbsp;<\/p>\n<p>(Aprobado en &nbsp;sesi\u00f3n de diecisiete de noviembre de dos mil veintiuno) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., diecisiete (17) de noviembre de dos mil veintiuno (2021). &nbsp;<\/p>\n<p>Se desata la &nbsp;tutela que Ana Mar\u00eda Jalkh Cuello le instaur\u00f3 al &nbsp;Consejo Superior de la Judicatura \u2013 Unidad de Registro Nacional &nbsp;de Abogados y Auxiliares de la Justicia, extensiva al Juzgado Quinto &nbsp;Penal del Circuito de Valledupar. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1.- &nbsp;La libelista, actuando en nombre propio, reclam\u00f3 la protecci\u00f3n &nbsp;de los derechos de \u00abpetici\u00f3n &nbsp;e igualdad\u00bb &nbsp;para que, en consecuencia, se ordenara \u00ab &nbsp;(\u2026) expedir &nbsp;certificado de aprobaci\u00f3n de las solicitadas pr\u00e1cticas &nbsp;jur\u00eddicas (\u2026)\u00bb. &nbsp;<\/p>\n<p>En &nbsp;sustento adujo que desde el 5 de octubre de 2020 hasta el 31 de &nbsp;agosto de 2021 realiz\u00f3 la \u00abpr\u00e1ctica &nbsp;jur\u00eddica\u00bb &nbsp;en el Juzgado Quinto Penal del Circuito de Valledupar. &nbsp;<\/p>\n<p>Indic\u00f3 &nbsp;que el 10 de septiembre de 2021 radic\u00f3 solicitud de &nbsp;reconocimiento de \u00abjudicatura\u00bb &nbsp;a la direcci\u00f3n electr\u00f3nica de la autoridad convocada. &nbsp;<\/p>\n<p>Se &nbsp;doli\u00f3 de que a la fecha &nbsp;\u00abhan &nbsp;transcurrido casi 2 meses de espera\u00bb &nbsp;sin obtener respuesta. &nbsp;<\/p>\n<p>2.- La &nbsp;Unidad de Registro Nacional de Abogados y Auxiliares de la Justicia &nbsp;del Consejo Superior de la Judicatura inform\u00f3 que en el &nbsp;presente caso se materializ\u00f3 un \u00abhecho &nbsp;superado\u00bb, &nbsp;en la medida que expidi\u00f3 la \u00abresoluci\u00f3n &nbsp;n\u00ba &nbsp;7628 de 5 de noviembre de 2021\u00bb &nbsp;y la comunic\u00f3 a la suplicante. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1.- &nbsp;La gestora denuncia &nbsp;al Consejo Superior de la Judicatura \u2013 Unidad de Registro &nbsp;Nacional de Abogados y Auxiliares de la Justicia porque no le hab\u00eda &nbsp;expedido la certificaci\u00f3n de \u00abpr\u00e1ctica &nbsp;jur\u00eddica\u00bb. &nbsp;<\/p>\n<p>2.- &nbsp;Empero, &nbsp;resulta &nbsp;di\u00e1fano que el resguardo no &nbsp;tiene vocaci\u00f3n de prosperidad por sobrevenir una carencia &nbsp;actual de objeto por hecho superado, como quiera que la Unidad de &nbsp;Registro accionada expidi\u00f3 la Resoluci\u00f3n n\u00ba 7628 &nbsp;de 5 de &nbsp;noviembre de 2021, en la que \u00ab[reconoci\u00f3] &nbsp;la pr\u00e1ctica jur\u00eddica establecida como requisito &nbsp;alternativo para optar al t\u00edtulo de abogado\u00bb, &nbsp;lo cual se pudo verificar en documento adjunto con la &nbsp;\u00abrespuesta\u00bb, &nbsp;que &nbsp;le notici\u00f3 en su direcci\u00f3n e-mail: anajalkhc@gmail.com. &nbsp;<\/p>\n<p>Lo &nbsp;anterior significa que la situaci\u00f3n f\u00e1ctica que origin\u00f3 &nbsp;la salvaguarda se encuentra \u00absuperada\u00bb &nbsp;y, en esa medida, \u00abcarecer\u00eda &nbsp;de objeto\u00bb &nbsp;y raz\u00f3n emitir alguna orden con ese prop\u00f3sito, puesto &nbsp;que el fin que se persigue ya se cristaliz\u00f3. &nbsp;<\/p>\n<p>As\u00ed las &nbsp;cosas, no hay duda de la estructuraci\u00f3n de la \u00abcarencia &nbsp;actual de objeto por hecho superado\u00bb &nbsp;y, en ese escenario \u00ab(\u2026) &nbsp;ning\u00fan &nbsp;sentido tiene que aqu\u00ed se imparta cualquier tipo de orden en &nbsp;relaci\u00f3n con unas circunstancias que en el pasado hubieran &nbsp;podido configurarse pero que, en este momento procesal, no existen o, &nbsp;cuando menos, presentan caracter\u00edsticas diferentes a las &nbsp;iniciales\u00bb &nbsp;(CSJ &nbsp;STC4943-2019 y STC6409-2021). &nbsp;<\/p>\n<p>3.- &nbsp;Como &nbsp;colof\u00f3n, la ayuda superlativa resulta inviable. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica de Colombia y por autoridad de la Constituci\u00f3n, &nbsp;DECLARA &nbsp;IMPROCEDENTE &nbsp;la tutela &nbsp;instada por &nbsp;Ana Mar\u00eda Jalkh Cuello. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;por el medio m\u00e1s id\u00f3neo y, en caso de no ser impugnado &nbsp;este fallo, rem\u00edtase el expediente a la Corte Constitucional &nbsp;para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>\u00c1LVARO &nbsp;FERNANDO GARC\u00cdA RESTREPO &nbsp;<\/p>\n<p>(Ausencia &nbsp;justificada) &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>(Ausencia &nbsp;justificada) &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC15473-2021 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; HILDA GONZ\u00c1LEZ &nbsp;NEIRA &nbsp; Magistrada ponente &nbsp; STC15473-2021 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 11001-02-30-000-2021-01947-00 &nbsp; (Aprobado en &nbsp;sesi\u00f3n de diecisiete de noviembre de dos mil veintiuno) &nbsp; Bogot\u00e1, &nbsp;D.C., diecisiete (17) de noviembre de dos mil veintiuno (2021). &nbsp; Se desata la &nbsp;tutela que Ana Mar\u00eda Jalkh Cuello le instaur\u00f3 al &nbsp;Consejo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-59437","post","type-post","status-publish","format-standard","hentry","category-noviembre"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/59437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=59437"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/59437\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=59437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=59437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=59437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}