{"id":59470,"date":"2024-05-17T20:42:24","date_gmt":"2024-05-17T20:42:24","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/stc15520-2021\/"},"modified":"2024-05-17T20:42:24","modified_gmt":"2024-05-17T20:42:24","slug":"stc15520-2021","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/17\/stc15520-2021\/","title":{"rendered":"STC15520 2021"},"content":{"rendered":"<p>STC15520-2021<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>Magistrado &nbsp;ponente &nbsp;<\/p>\n<p>STC15520-2021 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2021-04061-00 &nbsp;<\/p>\n<p>(Aprobado en &nbsp;sesi\u00f3n de diecisiete de noviembre de dos mil veintiuno) &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., diecisiete (17) de noviembre de dos mil veintiuno (2021). &nbsp;<\/p>\n<p>Se resuelve la &nbsp;acci\u00f3n de tutela que Diego &nbsp;Fernando Fern\u00e1ndez Galvis interpuso contra la Sala de Casaci\u00f3n &nbsp;Penal de la Corte Suprema de Justicia, extensiva a la Sala Penal del &nbsp;Tribunal Superior del Distrito Judicial de Neiva, al Juzgado Primero &nbsp;Penal del Circuito de Pitalito y a los intervinientes en el proceso &nbsp;2010-02833-00. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1.- &nbsp;El libelista pidi\u00f3 que se ordene a la Corporaci\u00f3n &nbsp;accionada revocar la sentencia SP4240-2021, por medio de la cual se &nbsp;neg\u00f3 a casar el veredicto del Tribunal de Neiva, que ratific\u00f3 &nbsp;la condena impuesta a su defendido Jos\u00e9 &nbsp;Fernando Riascos Salcedo &nbsp;por el delito de hurto agravado y calificado, y \u201cproceder &nbsp;a expedir el fallo que corresponda con la Constituci\u00f3n &nbsp;Pol\u00edtica de Colombia y el derecho vigente\u201d. &nbsp;<\/p>\n<p>Expuso, &nbsp;en esencia, que la judicatura infiri\u00f3 que Jos\u00e9 &nbsp;Fernando Riascos Salcedo particip\u00f3 en el hurto ocurrido el 16 &nbsp;de diciembre de 2010 en el inmueble ubicado en la Calle 15 No. 1 E-94 &nbsp;en el municipio de Pitalito, Huila, en el que se sustrajeron dineros &nbsp;que le pertenec\u00edan a Nelson Tulc\u00e1n Salcedo, a pesar de &nbsp;que las evidencias recaudadas en el proceso eran insuficientes para &nbsp;responsabilizarlo por esa conducta. &nbsp;<\/p>\n<p>2.- &nbsp;La Sala reprochada y el Tribunal de Neiva defendieron las decisiones &nbsp;que expidieron en la causa penal criticada. &nbsp;<\/p>\n<p>No hubo m\u00e1s &nbsp;pronunciamientos para el momento en que esta decisi\u00f3n fue &nbsp;proyectada. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>El &nbsp;ruego propuesto debe ser desestimado por falta de legitimaci\u00f3n &nbsp;en la causa, ya que Diego Fern\u00e1ndez Galvis acudi\u00f3 a &nbsp;este sendero en nombre Jos\u00e9 &nbsp;Fernando Riascos Salcedo, sin estar facultado para ello. &nbsp;<\/p>\n<p>En &nbsp;efecto, el suscriptor del libelo present\u00f3 el resguardo a favor &nbsp;de los intereses de Riascos Salcedo, a quien represent\u00f3 en el &nbsp;juicio 2010-02833-00, &nbsp;mas no alleg\u00f3 poder que lo facultara para el efecto, el cual &nbsp;era necesario, porque, como lo ha reiterado esta Corporaci\u00f3n, &nbsp;a esta herramienta, a tono con lo previsto en los art\u00edculos 10 &nbsp;y 31 del Decreto 2591, &nbsp;<\/p>\n<p>Cuando la acci\u00f3n de &nbsp;tutela se ejerce a t\u00edtulo de otro, es necesario contar con &nbsp;poder especial para (\u2026) su interposici\u00f3n. La carencia &nbsp;de la citada personer\u00eda para iniciar la acci\u00f3n de &nbsp;amparo constitucional, no se suple con la presentaci\u00f3n del &nbsp;apoderamiento otorgado para un asunto diferente. (\u2026) La falta &nbsp;de poder especial para adelantar el proceso de tutela por parte de un &nbsp;apoderado judicial, aun &nbsp;cuando tenga poder espec\u00edfico o general en otros asuntos, &nbsp;no lo habilita para ejercer la acci\u00f3n de amparo constitucional &nbsp;a nombre de su mandante y, por lo tanto, en estos casos, la tutela &nbsp;debe ser declarada improcedente (\u2026). (CSJ &nbsp;STC5308-2021). &nbsp;<\/p>\n<p>En &nbsp;este orden de ideas, el &nbsp;\u00fanico &nbsp;habilitado para promover esta ayuda en &nbsp;procura de repeler las fallas que se denuncian con ocasi\u00f3n lo &nbsp;zanjado en la causa penal 2010-02833-00 &nbsp;ser\u00eda &nbsp;Jos\u00e9 Riascos, quien no habilit\u00f3 legalmente a Diego &nbsp;Fern\u00e1ndez Galvis para interceder por \u00e9l ante el juez &nbsp;constitucional o por lo menos de tal potestad no obra prueba en este &nbsp;tr\u00e1mite. &nbsp;<\/p>\n<p>Son &nbsp;estos breves argumentos los que conducen a la desestimaci\u00f3n de &nbsp;la salvaguarda. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica y por autoridad de la Constituci\u00f3n, &nbsp;DECLARA IMPROCEDENTE la &nbsp;tutela planteada por Diego &nbsp;Fernando Fern\u00e1ndez Galvis. &nbsp;<\/p>\n<p>Inf\u00f3rmese &nbsp;a los participantes por el medio m\u00e1s expedito y rem\u00edtase &nbsp;el paginario a la Corte Constitucional para su eventual revisi\u00f3n, &nbsp;de no impugnarse esta resoluci\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>Ausencia &nbsp;justificada &nbsp;<\/p>\n<p>\u00c1LVARO &nbsp;FERNANDO GARC\u00cdA RESTREPO &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>Ausencia &nbsp;justificada &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC15520-2021 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp; Magistrado &nbsp;ponente &nbsp; STC15520-2021 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2021-04061-00 &nbsp; (Aprobado en &nbsp;sesi\u00f3n de diecisiete de noviembre de dos mil veintiuno) &nbsp; Bogot\u00e1 &nbsp;D.C., diecisiete (17) de noviembre de dos mil veintiuno (2021). &nbsp; Se resuelve la &nbsp;acci\u00f3n de tutela que Diego &nbsp;Fernando Fern\u00e1ndez Galvis interpuso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-59470","post","type-post","status-publish","format-standard","hentry","category-noviembre"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/59470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=59470"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/59470\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=59470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=59470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=59470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}