{"id":63071,"date":"2024-05-20T21:00:00","date_gmt":"2024-05-20T21:00:00","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac1699-2022-2022-00408-00\/"},"modified":"2024-05-20T21:00:00","modified_gmt":"2024-05-20T21:00:00","slug":"ac1699-2022-2022-00408-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac1699-2022-2022-00408-00\/","title":{"rendered":"AC 1699 2022"},"content":{"rendered":"<p>AC1699-2022 (2022-00408-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC1699-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2022-00408-00 &nbsp;<\/p>\n<p>Bogot\u00e1 D. &nbsp;C., tres (3) de mayo de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>Se &nbsp;inadmite la demanda con que Carmenza &nbsp;Mar\u00eda Cort\u00e9s Velandia &nbsp;pretendi\u00f3 sustentar &nbsp;el recurso extraordinario de revisi\u00f3n frente a la &nbsp;sentencia del 31 &nbsp;de octubre de 2019, proferida por el Tribunal Superior del Distrito &nbsp;Judicial de Tunja, Sala Civil, en el proceso declarativo de &nbsp;responsabilidad civil extracontractual que promovi\u00f3 contra &nbsp;Dirney Soto de Alba, Efra\u00edn Soto Soler y Efr\u00e9n Augusto &nbsp;Alba Soto, &nbsp;para lo cual se &nbsp;considera: &nbsp;<\/p>\n<p>1. A continuaci\u00f3n &nbsp;se precisar\u00e1n las falencias que presenta el libelo de la &nbsp;radicaci\u00f3n con el fin de que, dentro del t\u00e9rmino &nbsp;pertinente, sean subsanadas por el recurrente, de conformidad con lo &nbsp;previsto en los art\u00edculos 357 y 358 del C\u00f3digo General &nbsp;del Proceso. &nbsp;<\/p>\n<p>De acuerdo con el &nbsp;precepto 357, numeral 2, en concordancia con el art\u00edculo 82, &nbsp;del C\u00f3digo General del Proceso, falta: &nbsp;<\/p>\n<p>1.1. &nbsp; &nbsp; &nbsp; &nbsp;Las &nbsp;direcciones electr\u00f3nicas de todas las personas que deben ser &nbsp;parte (art. 82-10 del CGP), para lo cual deber\u00e1 la parte &nbsp;actora en aplicaci\u00f3n de los art\u00edculos 6\u00ba y 8\u00ba &nbsp;del Decreto 806 de 2020, agotar las diligencias a su alcance en aras &nbsp;de obtener y aportar el correo electr\u00f3nico actualizado de &nbsp;estas, requeridos para actuaciones procesales. &nbsp;<\/p>\n<p>As\u00ed mismo, &nbsp;no se alleg\u00f3 prueba de la remisi\u00f3n electr\u00f3nica &nbsp;del libelo introductor a los demandados. &nbsp;<\/p>\n<p>1.2. &nbsp; &nbsp; &nbsp; &nbsp;Tambi\u00e9n &nbsp;falta informar el despacho judicial donde se encuentra el expediente &nbsp;(art. 357-3). &nbsp;<\/p>\n<p>1.3. Narrar \u00ablos &nbsp;hechos concretos que le sirven de fundamento\u00bb &nbsp;a la causal de revisi\u00f3n invocada, &nbsp;como dispone el art\u00edculo 354, numeral 4\u00ba, del C\u00f3digo &nbsp;General del Proceso. &nbsp;<\/p>\n<p>En la demanda se &nbsp;invoc\u00f3 la &nbsp;causal primera &nbsp;del art\u00edculo 355 del C\u00f3digo General del Proceso, &nbsp;consistente en que se encuentran \u00abdespu\u00e9s &nbsp;de pronunciada la sentencia documentos que habr\u00edan variado la &nbsp;decisi\u00f3n contenida en ella, y que el recurrente no pudo &nbsp;aportarlos al proceso por fuerza mayor o caso fortuito o por obra de &nbsp;la parte contraria\u00bb. &nbsp;<\/p>\n<p>Sobre &nbsp;esa causal la Corte ha sentado que el recurrente debe revelar cu\u00e1les &nbsp;son esos instrumentos anteriores al fallo, pero hallados con &nbsp;posterioridad, junto con los hechos aducidos para estructurar el &nbsp;motivo de revisi\u00f3n solicitado, para cuya estructuraci\u00f3n &nbsp;es razonable exigencia que se trate de: &nbsp;<\/p>\n<p>a) &nbsp; &nbsp; &nbsp; &nbsp;documentos &nbsp;preexistentes &nbsp;a la demanda genitora del proceso cuya sentencia se pide revisar o &nbsp;que existan por lo menos desde el vencimiento de la \u00faltima &nbsp;oportunidad procesal para aportar pruebas; &nbsp;b) &nbsp; &nbsp; &nbsp; &nbsp;documentos &nbsp;trascendentales, &nbsp;es decir, que habr\u00edan variado la decisi\u00f3n contenida en &nbsp;la sentencia impugnada en revisi\u00f3n; &nbsp;c) &nbsp; &nbsp; &nbsp; &nbsp;imposibilidad &nbsp;de aducirlos tempestivamente por fuerza mayor o caso fortuito o por &nbsp;obra de la parte contraria, explicando, como es obvio en qu\u00e9 &nbsp;consisti\u00f3 la causa extra\u00f1a que impidi\u00f3 el aporte &nbsp;(CSJ &nbsp;SC, 17 mar. 2014, rad. 2013-02413, entre varios pronunciamientos. &nbsp;Subrayado del texto original). &nbsp;<\/p>\n<p>Requerimientos &nbsp;que no aparecen cumplidos en el escrito introductorio del pretendido &nbsp;recurso, puesto que la recurrente narr\u00f3 que el Tribunal revoc\u00f3 &nbsp;la sentencia de primera instancia por falta de legitimaci\u00f3n en &nbsp;la causa por activa en atenci\u00f3n a que en el folio de matr\u00edcula &nbsp;inmobiliaria del predio sobre el que se pretende la indemnizaci\u00f3n, &nbsp;la peticionaria no era quien figuraba como la titular de dominio para &nbsp;la fecha de la ocurrencia de los hechos lesivos. &nbsp;<\/p>\n<p>Manifestando, &nbsp;adem\u00e1s, que no se tuvo en cuenta la existencia de un documento &nbsp;privado de 2014 que aclar\u00f3 la escritura de compraventa n.\u00ba &nbsp;509 de 29 de octubre de 2009 de la Notar\u00eda \u00danica del &nbsp;C\u00edrculo de Tinjac\u00e1 (Boyac\u00e1), donde se indic\u00f3 &nbsp;que Cortes Velandia estaba facultada para cobrar perjuicios por los &nbsp;da\u00f1os sufridos sobre el inmueble. &nbsp;<\/p>\n<p>Tal &nbsp;relato no logra exteriorizar \u00abhechos &nbsp;concretos que le sirven de fundamento\u00bb &nbsp;a la causal primera de revisi\u00f3n porque &nbsp;ni siquiera precisa cu\u00e1les fueron los hechos constitutivos de &nbsp;caso fortuito, fuerza mayor o imputables a la parte contraria que &nbsp;impidieron allegar el documento al plenario a dentro del t\u00e9rmino &nbsp;legal oportuno, por lo que no habr\u00eda manera de comprender por &nbsp;qu\u00e9 no fue aducido durante la instancia. &nbsp;<\/p>\n<p>As\u00ed las &nbsp;cosas, lo que en \u00faltimas se pretende es la obtenci\u00f3n de &nbsp;nuevas oportunidades procesales para volver a plantear defensas o la &nbsp;posibilidad de hacer valer pruebas que debieron aducirse en el &nbsp;proceso mismo, situaciones que carecen de idoneidad para fundamentar &nbsp;la causal de revisi\u00f3n invocada. &nbsp;<\/p>\n<p>Acerca &nbsp;de la forma en que tienen que invocarse las causales de revisi\u00f3n &nbsp;en la correspondiente demanda, la Corte ha reiterado que: &nbsp;<\/p>\n<p>&#8230;desde &nbsp;un comienzo debe el recurrente justificar por qu\u00e9 considera &nbsp;fundada la causal de revisi\u00f3n que alega. Desde luego que, en &nbsp;ese contexto, el recurrente tiene \u2018una &nbsp;carga argumentativa cualificada, consistente en formular una &nbsp;acusaci\u00f3n precisa con base en enunciados f\u00e1cticos que &nbsp;guarden completa simetr\u00eda con la causal de revisi\u00f3n que &nbsp;se invoca, al punto que pueda entenderse que la demostraci\u00f3n &nbsp;de esos supuestos, en principio, har\u00eda venturoso el ataque. &nbsp;Dicho de otro modo, corresponde al recurrente explicar por qu\u00e9 &nbsp;considera que la sentencia debe revisarse y, para ello, ha de hacer &nbsp;una presentaci\u00f3n que permita establecer, desde un comienzo, &nbsp;que existen motivos &nbsp;id\u00f3neos &nbsp;que justifican el inicio de este tr\u00e1mite, destinado, como se &nbsp;sabe, a impedir la solidificaci\u00f3n definitiva de la cosa &nbsp;juzgada. De ah\u00ed que si el recurrente no expresa la causal de &nbsp;revisi\u00f3n que pretende hacer valer, o no pone de presente los &nbsp;hechos que la configurar\u00edan, la demanda no puede servir de &nbsp;percutor para la actividad de la Corte; igual sucede, cuando se &nbsp;advierte que los &nbsp;hechos que expone el impugnador no tienen idoneidad para configurar &nbsp;la causal de revisi\u00f3n que se alega, caso en el cual la demanda &nbsp;tampoco tiene vocaci\u00f3n para ser admitida, no s\u00f3lo por &nbsp;el incumplimiento de un perentorio requisito legal, sino porque si en &nbsp;gracia de discusi\u00f3n se tolerara esa deficiencia, tendr\u00eda &nbsp;que adelantarse una actuaci\u00f3n judicial que, a buen seguro, &nbsp;ning\u00fan resultado arrojar\u00eda, m\u00e1xime si se tiene &nbsp;en cuenta que por la dispositividad del recurso y por la importancia &nbsp;que para el ordenamiento tiene el principio de la seguridad jur\u00eddica, &nbsp;el juez de la revisi\u00f3n no puede hacer pronunciamientos &nbsp;oficiosos, ni salirse del preciso marco de referencia planteado por &nbsp;el censor &nbsp;(Se &nbsp;resalt\u00f3. CSJ ARC de 2 de diciembre de 2009, rad. 2009-01923, &nbsp;transcrito en providencias posteriores como en prove\u00eddo del 27 &nbsp;de agosto de 2012, rad. 11001-0203-000-2012-01285-00). &nbsp;<\/p>\n<p>De ah\u00ed que, &nbsp;adem\u00e1s de los otros aspectos formales, sea menester inadmitir &nbsp;la demanda de revisi\u00f3n por falta de planteamiento de unos &nbsp;hechos &nbsp;concretos &nbsp;que puedan estructurar la causal de revisi\u00f3n que se pretende &nbsp;arg\u00fcir. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;Por &nbsp;lo anterior, se inadmitir\u00e1 el escrito introductorio para que &nbsp;se cumplan los anteriores requerimientos. &nbsp;<\/p>\n<p>Con base en lo &nbsp;expuesto, la Corte Suprema de Justicia, Sala de Casaci\u00f3n &nbsp;Civil, resuelve: &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;Inadmitir la &nbsp;demanda de revisi\u00f3n, a fin de que sean subsanados los defectos &nbsp;anteriormente anotados. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;Conceder a la &nbsp;parte interesada el t\u00e9rmino legal de cinco (5) d\u00edas &nbsp;para ello, so pena de rechazo. &nbsp;<\/p>\n<p>3. Reconocer &nbsp;personer\u00eda al abogado Whitman Dar\u00edo Hern\u00e1ndez &nbsp;Deaza, como apoderado de la recurrente, en los t\u00e9rminos del &nbsp;memorial poder obrante en los escritos contentivos del recurso de &nbsp;revisi\u00f3n. &nbsp;<\/p>\n<p>Notif\u00edquese. &nbsp;<\/p>\n<p>AROLDO WILSON &nbsp;QUIROZ MONSALVO &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC1699-2022 (2022-00408-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC1699-2022 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2022-00408-00 &nbsp; Bogot\u00e1 D. &nbsp;C., tres (3) de mayo de dos mil veintid\u00f3s (2022). &nbsp; Se &nbsp;inadmite la demanda con que Carmenza &nbsp;Mar\u00eda Cort\u00e9s Velandia &nbsp;pretendi\u00f3 sustentar &nbsp;el recurso extraordinario de revisi\u00f3n frente a la &nbsp;sentencia del 31 &nbsp;de octubre de 2019, proferida por el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63071","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63071"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63071\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}