{"id":63079,"date":"2024-05-20T21:00:00","date_gmt":"2024-05-20T21:00:00","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac1709-2022-2022-01176-00\/"},"modified":"2024-05-20T21:00:00","modified_gmt":"2024-05-20T21:00:00","slug":"ac1709-2022-2022-01176-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac1709-2022-2022-01176-00\/","title":{"rendered":"AC 1709 2022"},"content":{"rendered":"<p>AC1709-2022 (2022-01176-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AC1709-2022 &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., tres (03) de mayo de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>Ser\u00eda &nbsp;del caso que la Corte decidiera el conflicto &nbsp;de competencia suscitado entre los Juzgados Primero &nbsp;Promiscuo Municipal &nbsp;de Sabaneta &nbsp;y &nbsp;S\u00e9ptimo &nbsp;Civil Municipal &nbsp;de Buenaventura, &nbsp;de no ser porque es prematuro. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>1. Ante &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el primer Despacho, el &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Banco Davivienda, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;como titular de prenda sin tenencia sobre un &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;veh\u00edculo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;de uso particular cuya ubicaci\u00f3n no indic\u00f3, solicit\u00f3 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;librar mandamiento de pago por las sumas incorporadas en el pagar\u00e9 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;adjunto contra Mar\u00eda Teresa Torres Guti\u00e9rrez, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;domiciliada en Sabaneta, atribuy\u00e9ndole la competencia \u00abpor &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el domicilio de las partes, as\u00ed como por el lugar se\u00f1alado &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;para el cumplimiento de la obligaci\u00f3n\u00bb. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>2. Esa &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;autoridad rechaz\u00f3 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;caso &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;aduciendo que la covocada es vecina de Buenaventura, de conformidad &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;con la direcci\u00f3n informada para notificarla (14 en. 2022).<\/p>\n<p>3. El &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;destinatario &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;tambi\u00e9n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;repeli\u00f3 el pleito porque al versar sobre un derecho real y &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;recaer sobre un bien que \u00abpor &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;su naturaleza no tiene un lugar est\u00e1tico\u00bb, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;cuya &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;ubicaci\u00f3n no qued\u00f3 restringida contractualmente a &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;determinado lugar ni la actora indica que sea Buenaventura, am\u00e9n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;de que est\u00e1 matriculado en Sabaneta, de donde la llamada es &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;vecina, no debe aplicarse la regla especial de competencia del &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;numeral 7\u00ba del art\u00edculo 28 del C\u00f3digo General del &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Proceso, sino la que elija el demandante. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; En &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;consecuencia, plante\u00f3 la controversia indicada y remiti\u00f3 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el caso a esta sede para desatarla (29 mar. 2022). &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>1. Comoquiera &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;que la divergencia que se analiza se trab\u00f3 entre dos estrados &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;de diferentes &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;distritos &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;judiciales, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;a esta Corporaci\u00f3n le ata\u00f1er\u00eda &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;dirimirla como superior funcional com\u00fan de ellos, por &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;conducto del suscrito Magistrado Sustanciador en Sala Unitaria, como &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;lo establecen los art\u00edculos 35 y 139 del C\u00f3digo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;General del Proceso y 16 de la Ley 270 de 1996, este \u00faltimo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;modificado por el 7 de la 1285 de 2009. &nbsp;<\/p>\n<p>2.- &nbsp;El estatuto adjetivo &nbsp;se ocup\u00f3 de la distribuci\u00f3n de competencia en asuntos &nbsp;civiles, comerciales, agrarios y de familia con atenci\u00f3n en &nbsp;los diversos factores que la determinan. En ese orden, el art\u00edculo &nbsp;28 de la Ley 1564 de 2012 consagra las directrices a tener en cuenta &nbsp;por el fuero territorial y en su numeral 7 dispone que: &nbsp;<\/p>\n<p>[e]n &nbsp;los procesos en que se ejerciten derechos reales, en los divisorios, &nbsp;de deslinde y amojonamiento, expropiaci\u00f3n, servidumbres, &nbsp;posesorios de cualquier naturaleza, restituci\u00f3n de tenencia, &nbsp;declaraci\u00f3n de pertenencia y de bienes vacantes y mostrencos, &nbsp;ser\u00e1 competente, de modo privativo, el Juez del lugar donde &nbsp;est\u00e9n ubicados los bienes, y se hallen en distintas &nbsp;circunscripciones territoriales, el de cualquiera de ellas a elecci\u00f3n &nbsp;del demandante. &nbsp;<\/p>\n<p>Aflora &nbsp;de all\u00ed la intenci\u00f3n clara del legislador que toda &nbsp;actuaci\u00f3n litigiosa que revele el ejercicio de un derecho real &nbsp;se adelante ante la autoridad del sitio donde est\u00e1 el bien &nbsp;involucrado, tanto as\u00ed que esa pauta excluye cualquier otra, &nbsp;dado el car\u00e1cter privativo que le dio. &nbsp;<\/p>\n<p>3.- &nbsp;En el sub &nbsp;lite, &nbsp;como se dej\u00f3 advertido, el patr\u00f3n que impera para &nbsp;definir la discordia es la localizaci\u00f3n del bien objeto de &nbsp;aprehensi\u00f3n. &nbsp;<\/p>\n<p>Si &nbsp;bien es cierto los &nbsp;contratantes no convinieron el lugar exacto en el que deber\u00eda &nbsp;permanecer el automotor, pues acordaron que la &nbsp;garante se obligaba a mantenerlo dentro del territorio colombiano, &nbsp;seg\u00fan consta en el literal a) de la cl\u00e1usula segunda &nbsp;del &nbsp;contrato de prenda, &nbsp;ello no quiere decir que en la pr\u00e1ctica no exista un lugar en &nbsp;el que, al menos, de manera principal pueda localizarse. &nbsp;<\/p>\n<p>Por &nbsp;consiguiente, para efecto de fijar la competencia a partir de un &nbsp;elemento objetivo que escape a la mera voluntad de la impulsora de &nbsp;este tr\u00e1mite de promoverlo en cualquier parte del suelo &nbsp;patrio, es perentorio que esta informe esa circunstancia de manera &nbsp;previa a determinar el juzgador facultado para ese fin. &nbsp;<\/p>\n<p>Como &nbsp;no lo hizo y los estrados comprometidos en esta disputa no utilizaron &nbsp;el mecanismo de inadmisbi\u00f3n previsto en el art\u00edculo 90 &nbsp;del C\u00f3digo General del Proceso, apropiado para obtener esta &nbsp;informaci\u00f3n, no contaban con suficientes elementos de juicio &nbsp;para determinar si eran los habilitados para adelantar la actuaci\u00f3n; &nbsp;por supuesto, la Corte tampoco los tiene ahora para definir de fondo &nbsp;el conflicto. &nbsp;<\/p>\n<p>En &nbsp;tal sentido, en AC5186-2021, la Sala dijo que &nbsp;<\/p>\n<p>[e]ntonces, &nbsp;como el criterio de escogencia luce impreciso y tampoco halla &nbsp;respaldo en alguno de los soportes arrimados al plenario, ello &nbsp;significa que era deber de quien recepcion\u00f3 &nbsp;el caso en un comienzo exigir la precisi\u00f3n correspondiente en &nbsp;aras de establecer certeza respecto del par\u00e1metro llamado a &nbsp;definir la competencia por el factor territorial, de conformidad con &nbsp;lo previsto en el art\u00edculo 28 del C\u00f3digo General del &nbsp;Proceso. &nbsp;<\/p>\n<p>4.- &nbsp;En consecuencia, se declarar\u00e1 el apresuramiento con el que &nbsp;procedieron los juzgados involucrados y se devolver\u00e1n las &nbsp;diligencias al que primero se le repartieron para que utilice las &nbsp;herramientas que brinda el ordenamiento procesal a efecto de conocer &nbsp;la ubicaci\u00f3n del veh\u00edculo y con ello el despacho &nbsp;facultado para cononcer el cobro prendario. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, Sala de &nbsp;Casaci\u00f3n Civil, &nbsp;<\/p>\n<p>RESUELVE &nbsp;<\/p>\n<p>Primero: &nbsp;Declarar prematuro el &nbsp;planteamiento del conflicto de competencia. &nbsp;<\/p>\n<p>Segundo: &nbsp; &nbsp; &nbsp; &nbsp;Remitir &nbsp;el expediente al Juzgado Primero Promiscuo &nbsp;Municipal de Sabaneta &nbsp;para que proceda de conformidad con lo expuesto. &nbsp;<\/p>\n<p>Cuarto: &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;L\u00edbrense los oficios correspondientes, por secretar\u00eda. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>Magistrado &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC1709-2022 (2022-01176-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AC1709-2022 &nbsp; Bogot\u00e1 &nbsp;D.C., tres (03) de mayo de dos mil veintid\u00f3s (2022). &nbsp; Ser\u00eda &nbsp;del caso que la Corte decidiera el conflicto &nbsp;de competencia suscitado entre los Juzgados Primero &nbsp;Promiscuo Municipal &nbsp;de Sabaneta &nbsp;y &nbsp;S\u00e9ptimo &nbsp;Civil Municipal &nbsp;de Buenaventura, &nbsp;de no ser porque es prematuro. &nbsp; ANTECEDENTES &nbsp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63079","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63079"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63079\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}