{"id":63084,"date":"2024-05-20T21:00:00","date_gmt":"2024-05-20T21:00:00","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac1720-2022-2022-01211-00\/"},"modified":"2024-05-20T21:00:00","modified_gmt":"2024-05-20T21:00:00","slug":"ac1720-2022-2022-01211-00","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac1720-2022-2022-01211-00\/","title":{"rendered":"AC 1720 2022"},"content":{"rendered":"<p>AC1720-2022 (2022-01211-00)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>Magistrado &nbsp;ponente &nbsp;<\/p>\n<p>AC1720-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 &nbsp;11001-02-03-000-2022-01211-00 &nbsp;<\/p>\n<p>Bogot\u00e1 D.C., cuatro (4) &nbsp;de mayo de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>Se &nbsp;decide lo pertinente respecto de la solicitud de cambio de radicaci\u00f3n &nbsp;signada por Mar\u00eda Carlina, Ra\u00fal Antonio, N\u00e9stor &nbsp;Guillermo, Eutiquiano, Luz Marina y Martha Esperanza Cubillos &nbsp;Penagos, en relaci\u00f3n con el proceso de sucesi\u00f3n doble &nbsp;intestada de Rosa Adelia Penagos y Jos\u00e9 No\u00e9 Cubillos &nbsp;Guti\u00e9rrez (rads. 2008-00195 y 2013-00206), que cursa en el &nbsp;Juzgado Promiscuo de Familia de Fusagasug\u00e1. &nbsp;<\/p>\n<p>Los peticionarios relatan que a &nbsp;pesar de que su gestor judicial ha radicado en varias oportunidades &nbsp;mandato judicial que lo habilite para intervenir en el proceso en &nbsp;cuesti\u00f3n, el estrado judicial de conocimiento viene &nbsp;absteni\u00e9ndose de reconocerle personer\u00eda, no obstante &nbsp;que s\u00ed la reconoci\u00f3 a la apoderada judicial de Jos\u00e9 &nbsp;Epimenio Cubillos Penagos, quien aport\u00f3 poder judicial con &nbsp;posterioridad. &nbsp;<\/p>\n<p>Agregaron que otros dos &nbsp;gestores judiciales renunciaron a los mandatos que les hab\u00edan &nbsp;conferido, que los dependientes del estrado judicial mencionado les &nbsp;impidieron acceder al expediente pretextando que deben acudir a su &nbsp;apoderado judicial, y que tal juzgado dispuso la terminaci\u00f3n &nbsp;del proceso por desistimiento t\u00e1cito, lo que fue reversado por &nbsp;v\u00eda de tutela con sentencia de 13 de octubre de 2021, dictada &nbsp;por la Sala de Casaci\u00f3n Civil del a H. Corte Suprema de &nbsp;Justicia. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. Por mandato del numeral 8\u00ba &nbsp;del art\u00edculo 30 del C\u00f3digo General del Proceso (Ley &nbsp;1564 de 2012), la resoluci\u00f3n de una solicitud de cambio de &nbsp;radicaci\u00f3n est\u00e1 atribuida a la Corte Suprema de &nbsp;Justicia, si se pretende el traslado de un litigio de un estrado a &nbsp;otro de diverso distrito judicial. &nbsp;<\/p>\n<p>As\u00ed mismo, el numeral 6\u00ba &nbsp;del art\u00edculo 31 de la misma obra asigna a los tribunales &nbsp;superiores de distrito judicial la competencia para conocer, en sala &nbsp;civil, de &nbsp;\u00ab(\u2026) las peticiones de cambio de radicaci\u00f3n de un &nbsp;proceso o actuaci\u00f3n, que implique su remisi\u00f3n al &nbsp;interior de un mismo distrito judicial, de conformidad con lo &nbsp;previsto en el numeral 8\u00b0 del art\u00edculo 30\u00bb. &nbsp;<\/p>\n<p>2. En el sub &nbsp;lite, los &nbsp;peticionarios solicitan el traslado de un juicio de sucesi\u00f3n &nbsp;doble intestada que cursa en el Distrito Judicial de Cundinamarca, &nbsp;porque estiman que la funcionaria que conoce de esa causa ha cometido &nbsp;desafueros que evidencian su parcialidad. &nbsp;<\/p>\n<p>Sin embargo y a pesar de que &nbsp;los quejosos deprecaron el &nbsp;traslado de la tramitaci\u00f3n referida al Distrito Judicial de &nbsp;Bogot\u00e1, no plasmaron la m\u00e1s m\u00ednima argumentaci\u00f3n &nbsp;que justifique el cambio de distrito judicial, y tampoco se &nbsp;advierte queja en &nbsp;relaci\u00f3n con el &nbsp;Tribunal Superior del Distrito Judicial de Cundinamarca, que afectase &nbsp;\u00ab(\u2026) &nbsp;el orden p\u00fablico, la imparcialidad o la independencia de la &nbsp;administraci\u00f3n de justicia, las garant\u00edas procesales o &nbsp;la seguridad o integridad de los intervinientes (\u2026)\u00bb. &nbsp;<\/p>\n<p>As\u00ed las cosas, en casos &nbsp;como el presente, de establecerse una cualquiera de las causales &nbsp;establecidas en el citado art\u00edculo 30, el cambio perfectamente &nbsp;puede tener lugar en el mismo distrito judicial, y una determinaci\u00f3n &nbsp;de esa \u00edndole, con arreglo a las normas en referencia, no &nbsp;podr\u00e1 ser tomada m\u00e1s que por el competente, que para el &nbsp;caso de autos es el respectivo tribunal. &nbsp;<\/p>\n<p>Es que, como precedentemente lo &nbsp;adoctrin\u00f3 la Sala: &nbsp;<\/p>\n<p>\u00ab(\u2026) &nbsp;Contrario a lo que pregona la Sala de Familia a la que se asign\u00f3 &nbsp;inicialmente su soluci\u00f3n, esta intervenci\u00f3n no deriva &nbsp;siempre en el traslado del pleito de un circuito a otro de distinta &nbsp;sede territorial (\u2026). &nbsp;<\/p>\n<p>\u00abSobre el &nbsp;particular dijo la Corporaci\u00f3n que \u201ces posible que se &nbsp;presenten situaciones que a pesar de no tener ninguna relaci\u00f3n &nbsp;con los par\u00e1metros que fijan la competencia, tornan necesario &nbsp;el desprendimiento del juez respecto del asunto de que viene &nbsp;conociendo, como por ejemplo, que recaiga en \u00e9l una causal &nbsp;constitutiva de impedimento o recusaci\u00f3n; que deje vencer el &nbsp;t\u00e9rmino establecido en el Par\u00e1grafo del art\u00edculo &nbsp;124 del C\u00f3digo de Procedimiento Civil &nbsp;\u2013ahora, &nbsp;art\u00edculo 121 del C\u00f3digo General del Proceso\u2013 &nbsp;para dictar sentencia de primera o de segunda instancia; o que se &nbsp;demuestre la existencia de uno de los hechos que ameritan el cambio &nbsp;de radicaci\u00f3n y que se encuentran taxativamente se\u00f1alados &nbsp;en el numeral 8\u00ba del art\u00edculo 30 (\u2026) [ib\u00eddem]. &nbsp;La procedencia de esta \u00faltima medida es de car\u00e1cter &nbsp;excepcional y est\u00e1 sujeta al cumplimiento de los motivos &nbsp;expresamente se\u00f1alados en la norma, los cuales se concretan en &nbsp;las siguientes situaciones: (\u2026) ii) Cuando se adviertan &nbsp;deficiencias de gesti\u00f3n y celeridad en los procesos (\u2026) &nbsp;El retraso en el diligenciamiento de la actuaci\u00f3n puede &nbsp;deberse, por ejemplo, a problemas estructurales o coyunturales de &nbsp;congesti\u00f3n de un despacho, o de los juzgados de toda una \u00e1rea, &nbsp;lo que justifica el traslado del foro a una oficina judicial en la &nbsp;que se pueda desarrollar el proceso con normalidad\u201d (auto de 15 &nbsp;de mayo de 2013, exp. 2013-00659-00)\u00bb (CSJ &nbsp;AC de 25 jul. 2013, rad. n.\u00ba 2013-01390-00; reiterado en AC1546 &nbsp;de 13 mar. 2017, rad. n.\u00ba 2017-00400-00). &nbsp;<\/p>\n<p>En suma, aun cuando el &nbsp;ordenamiento jur\u00eddico confiri\u00f3 a la Corte la potestad &nbsp;de trasladar un juicio de un distrito judicial a otro, ello no &nbsp;faculta al interesado para escoger, inopinadamente, al margen de las &nbsp;caracter\u00edsticas del caso y en forma caprichosa, el funcionario &nbsp;competente para conocer del cambio de radicaci\u00f3n; pues las &nbsp;puntuales circunstancias aducidas ser\u00e1n las que habr\u00e1n &nbsp;de llevarlo a establecer si le corresponde a esta Sala o a la Civil &nbsp;del tribunal del correspondiente distrito. &nbsp;<\/p>\n<p>Consecuentemente, la omisiva &nbsp;argumentaci\u00f3n de los peticionarios devela la falta de &nbsp;competencia de la Corte, por lo que, con base en el mandato &nbsp;consagrado en el art\u00edculo 90 del C\u00f3digo General del &nbsp;Proceso, se ordenar\u00e1 enviar la solicitud de la referencia a la &nbsp;Sala Civil &#8211; Familia del Tribunal Superior del Distrito Judicial de &nbsp;Cundinamarca, para lo de su competencia. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En m\u00e9rito de lo &nbsp;expuesto, la Corte Suprema de Justicia, Sala de Casaci\u00f3n &nbsp;Civil, RESUELVE: &nbsp;<\/p>\n<p>1\u00ba. Rechazar, &nbsp;por falta de competencia, la petici\u00f3n de cambio de radicaci\u00f3n &nbsp;suscrita por Mar\u00eda &nbsp;Carlina, Ra\u00fal Antonio, N\u00e9stor Guillermo, Eutiquiano, &nbsp;Luz Marina y Martha Esperanza Cubillos Penagos. &nbsp;<\/p>\n<p>3\u00ba. &nbsp;Comunicar la presente decisi\u00f3n a los peticionarios. &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>Magistrado &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC1720-2022 (2022-01211-00) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp; Magistrado &nbsp;ponente &nbsp; AC1720-2022 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 &nbsp;11001-02-03-000-2022-01211-00 &nbsp; Bogot\u00e1 D.C., cuatro (4) &nbsp;de mayo de dos mil veintid\u00f3s (2022). &nbsp; Se &nbsp;decide lo pertinente respecto de la solicitud de cambio de radicaci\u00f3n &nbsp;signada por Mar\u00eda Carlina, Ra\u00fal Antonio, N\u00e9stor &nbsp;Guillermo, Eutiquiano, Luz Marina [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63084","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63084"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63084\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}