{"id":63105,"date":"2024-05-20T21:00:02","date_gmt":"2024-05-20T21:00:02","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac1791-2022-2017-00019-01\/"},"modified":"2024-05-20T21:00:02","modified_gmt":"2024-05-20T21:00:02","slug":"ac1791-2022-2017-00019-01","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/ac1791-2022-2017-00019-01\/","title":{"rendered":"AC 1791 2022"},"content":{"rendered":"<p>AC1791-2022 (2017-00019-01)<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Magistrada &nbsp;ponente &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 13001-31-03-003-2017-00019-01 &nbsp;<\/p>\n<p>(Aprobado en &nbsp;sesi\u00f3n de veintiocho de abril de dos mil veintid\u00f3s) &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., treinta y uno (31) de mayo de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>Decide la Corte &nbsp;sobre &nbsp;la admisibilidad de la demanda presentada &nbsp;por Diana Mar\u00eda Ricardo Garc\u00e9s y Enrique Mario Rivera &nbsp;Ricardo, &nbsp;para &nbsp;sustentar el recurso &nbsp;extraordinario &nbsp;de casaci\u00f3n interpuesto frente &nbsp;a la sentencia de &nbsp;22 de julio de 2020, proferida por la Sala Civil \u2013 Familia del &nbsp;Tribunal Superior del Distrito Judicial de Cartagena, dentro del &nbsp;proceso verbal de responsabilidad civil promovido por los impugnantes &nbsp;contra Coomeva E.P.S. S.A., Litotricia S.A., Promotora Bocagrande &nbsp;S.A. Proboca S.A. y Pedro Alonso V\u00e9lez de Pombo, tr\u00e1mite &nbsp;en cual se vincul\u00f3 como llamados en garant\u00eda a La &nbsp;Previsora S.A. Compa\u00f1\u00eda de Seguros, Mapfre Seguros &nbsp;Generales de Colombia S.A. y Seguros Generales Suramericana S.A. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp;Mediante demanda, los actores solicitaron declarar responsables &nbsp;solidaria y extracontractualmente a los demandados, por la muerte de &nbsp;F\u00e9lix Enrique Rivera Pineda, ocurrida el 14 de agosto de 2015, &nbsp;y, en consecuencia, se les condene al pago de los perjuicios causados &nbsp;por concepto de da\u00f1o emergente, lucro cesante, da\u00f1o &nbsp;moral y da\u00f1o a la vida en relaci\u00f3n, seg\u00fan los &nbsp;especifican y estiman. &nbsp;<\/p>\n<p>2. &nbsp;Como sustento de esos pedimentos, se inform\u00f3 que el 12 de &nbsp;agosto de 2015, al se\u00f1or F\u00e9lix Enrique Rivera Pineda, &nbsp;respectivamente c\u00f3nyuge y padre de los demandantes, el m\u00e9dico &nbsp;ur\u00f3logo Pedro V\u00e9lez de Pombo, en el Nuevo Hospital de &nbsp;Bocagrande de Cartagena, le practic\u00f3 el procedimiento &nbsp;denominado nefrectom\u00eda parcial derecha, el cual desemboc\u00f3 &nbsp;en el fallecimiento del paciente el 14 de agosto de 2015. &nbsp;<\/p>\n<p>El deceso del &nbsp;se\u00f1or Rivera Pineda ocurri\u00f3 \u00abno &nbsp;solo porque durante la cirug\u00eda hubo mala pr\u00e1ctica de un &nbsp;equipo m\u00e9dico que le provoca al paciente un sangrado interno &nbsp;sino tambi\u00e9n porque posteriormente dicho sangrado no se &nbsp;detect\u00f3 oportunamente a pesar de la se\u00f1ales cl\u00ednicas &nbsp;y f\u00edsicas que los hac\u00edan evidente y que fueron incluso &nbsp;notadas y avisadas por los familiares del hoy difunto\u00bb. &nbsp;<\/p>\n<p>Llegaron a similar &nbsp;conclusi\u00f3n, el m\u00e9dico verificador y habilitador de la &nbsp;I.P.S. Javith Gabriel Rodr\u00edguez Camargo, quien realiz\u00f3 &nbsp;un informe pericial por solicitud de familia, como la coordinadora de &nbsp;peticiones, quejas y reclamos Clara Eugenia Sumosa P\u00e9rez, &nbsp;encargada de la investigaci\u00f3n del Departamento Administrativo &nbsp;Distrital de Salud \u2013 DADIS, quien inform\u00f3 \u00abse &nbsp;evidencia que la falla presentada ante la urgencia del paciente se &nbsp;debi\u00f3 al tiempo de la resoluci\u00f3n de su complicaci\u00f3n &nbsp;post-quir\u00fargica\u00bb, &nbsp;lo &nbsp;cual coincide con la historia cl\u00ednica de la cual se desprenden &nbsp;\u00ablas &nbsp;circunstancias de tiempo, modo y lugar en que se dio la deficiente &nbsp;atenci\u00f3n m\u00e9dica\u00bb. &nbsp;<\/p>\n<p>Luego &nbsp;de la \u00abmala &nbsp;pr\u00e1ctica m\u00e9dica en la que se provoc\u00f3 un sangrado &nbsp;previsible, y posteriormente detectable\u00bb &nbsp;no debi\u00f3 ordenarse en el postoperatorio el traslado del &nbsp;paciente a una habitaci\u00f3n, como si se tratara de una cirug\u00eda &nbsp;de baja complejidad, sino a una destinada a cuidados intensivos, por &nbsp;lo cual, \u00abse &nbsp;hace evidente la negligencia e impericia [ya que]\u2026 los &nbsp;s\u00edntomas se\u00f1alaban que el paciente se desangraba ante &nbsp;los ojos de todo el personal m\u00e9dico y la \u00fanica que &nbsp;notaba la gravedad de este ser humano era su esposa \u2026 al &nbsp;paciente se le deja a su suerte 21 horas sin el tratamiento adecuado &nbsp;y es cuando se valora nuevamente\u00bb, &nbsp;se inici\u00f3 c\u00f3digo azul, se realiz\u00f3 intubaci\u00f3n &nbsp;orotraqueal y fue trasladado a UCI. &nbsp;<\/p>\n<p>El &nbsp;paciente present\u00f3 schok hipovol\u00e9mico, raz\u00f3n por &nbsp;la cual se dispone su reintervenci\u00f3n, el 13 de agosto de 2015, &nbsp;\u00abencontrando &nbsp;hemoperitoneo con Drenaje de 1500 cc, se identifica en ri\u00f1\u00f3n &nbsp;derecho residual puntos de sangrados se procede a realizar tomar &nbsp;corte y ligadura de hilio renal inferior y superior con seda, se deja &nbsp;dren en lecho quir\u00fargico, se introducen asas intestinales en &nbsp;cavidad, se cierra herida por planos verificado previa hemostasia en &nbsp;lecho quir\u00fargico. Se le trasfunden 3 Un de GRE y 3 Un[as] &nbsp;plaquetas y 3 Un Plasma. Reingresa a UCI, donde presenta cuadro de &nbsp;falla multiorganica con lesi\u00f3n hepatocelular y estado de &nbsp;coagulaci\u00f3n intravascular diseminada\u00bb &nbsp;y &nbsp;de forma posterior a solicitarse revaloraci\u00f3n por urolog\u00eda &nbsp;y cirug\u00eda general, ante posible isquemia de asas intestinales &nbsp;por el aumento de presi\u00f3n intra abdominal, se decidi\u00f3 &nbsp;realizar procedimiento de laparatomia exploradora descompresiva en &nbsp;UCI, encontrando &nbsp;\u00abdilataci\u00f3n &nbsp;y edema de asas intestinales, moderados co\u00e1gulos en cavidad, &nbsp;dos grandes co\u00e1gulos depositados en espacio sub-diafragm\u00e1tico &nbsp;derecho, discreto sangrado en NAPA de paed, fosa renal y receso &nbsp;parieto-c\u00f3lico derecho\u00bb. &nbsp;<\/p>\n<p>Como &nbsp;consecuencia de la atenci\u00f3n tard\u00eda, el se\u00f1or &nbsp;Rivera Pineda empeor\u00f3 progresivamente, siendo las 11:41 de la &nbsp;ma\u00f1ana del 14 de agosto de 2015, \u00abentra &nbsp;en bradicardia con reanimaci\u00f3n con atropina IV sin respuesta &nbsp;se buscan pulsos perif\u00e9ricos, carotideo y femoral sin &nbsp;presencia, se activa (por fin) c\u00f3digo azul iniciando maniobras &nbsp;b\u00e1sicas y avanzadas con compresiones card\u00edacas. Aplican &nbsp;10 ampollas de adrenalia, vasopresina y noradrenalina sin respuesta &nbsp;favorable con persistencia de asistolia por lo que se ordena &nbsp;suspender reanimaci\u00f3n registr\u00e1ndose as\u00ed el &nbsp;fallecimiento\u00bb. &nbsp;<\/p>\n<p>Se &nbsp;demuestra la negligencia, impericia, imprudencia y desconocimiento &nbsp;por parte de los m\u00e9dicos del Nuevo Hospital de Bocagrande y &nbsp;Litotricia S.A., quienes incurrieron en un error de diagn\u00f3stico &nbsp;y tratamiento inadecuado, por cuanto las decisiones se adoptaron por &nbsp;los aparentes signos cl\u00ednicos y no el cuadro cl\u00ednico &nbsp;real que presentaba el paciente, incumpliendo con los protocolos, &nbsp;gu\u00edas de manejo y lex &nbsp;artix &nbsp;m\u00e9dica. &nbsp;<\/p>\n<p>3. &nbsp;Por intermedio de apoderado judicial, las convocadas contestaron en &nbsp;tiempo la demanda y, en tal virtud, se opusieron a las pretensiones &nbsp;de la demanda, formularon excepciones de m\u00e9rito, y realizaron &nbsp;llamamiento en garant\u00eda. &nbsp;<\/p>\n<p>Litotricia S.A., &nbsp;Promotora Bocagrande S.A. Proboca S.A. y Pedro Alonso V\u00e9lez de &nbsp;Pombo, representados por la misma apoderada contestaron la demanda de &nbsp;forma individual y presentaron excepciones perentorias. &nbsp;<\/p>\n<p>3.1 &nbsp;I.P.S. Nuevo Hospital Bocagrande Promotora S.A. se opuso a las &nbsp;pretensiones y formul\u00f3 las excepciones de i) &nbsp;inexistencia de un da\u00f1o indemnizable \u2013 caso fortuito; &nbsp;ii) correcci\u00f3n de un riesgo permitido; iii) inexistencia del &nbsp;da\u00f1o imputable a mala pr\u00e1ctica m\u00e9dica; iv) &nbsp;inexistencia de la obligaci\u00f3n de indemnizar. &nbsp;<\/p>\n<p>Nuevo Hospital &nbsp;Bocagrande S.A. Proboca S.A. llam\u00f3 en garant\u00eda a Mapfre &nbsp;Seguros Generales de Colombia S.A. La aseguradora se opuso a las &nbsp;pretensiones de la demanda, como a las pretensiones del llamamiento &nbsp;en garant\u00eda, por considerar que no existi\u00f3 negligencia &nbsp;o falla m\u00e9dica en los servicios m\u00e9dicos prestados al &nbsp;paciente. Present\u00f3 como medios de defensa i) &nbsp;inexistencia de la obligaci\u00f3n de indemnizar por la diligencia &nbsp;en el cumplimiento total de las obligaciones a cargo de la entidad de &nbsp;salud o m\u00e9dico tratante; ii) ausencia de los elementos &nbsp;constitutivos de la responsabilidad profesional m\u00e9dica; iii) &nbsp;falta de nexo de causalidad; iv) indebida cuantificaci\u00f3n de &nbsp;perjuicios; v) carga de la prueba del demandante; vi) inexigibilidad &nbsp;de la obligaci\u00f3n que surge del contrato de seguro por ausencia &nbsp;de cobertura; vii) l\u00edmite de valor asegurado y deducible; &nbsp;viii) excepci\u00f3n gen\u00e9rica y ecum\u00e9nica. &nbsp;<\/p>\n<p>3.2 &nbsp;I.P.S. Litotricia contest\u00f3 la demanda, tambi\u00e9n se opuso &nbsp;a las pretensiones de la demanda y formul\u00f3 las excepciones que &nbsp;denomin\u00f3 i) &nbsp;inexistencia de un da\u00f1o indemnizable \u2013 caso fortuito; &nbsp;ii) actualizaci\u00f3n de riesgo permitido y aceptado por el &nbsp;paciente Felix Enrique Rivera Pineda \u2013 caso fortuito; iii) &nbsp;inexistencia del da\u00f1o imputable a mala pr\u00e1ctica m\u00e9dica; &nbsp;iv) inexistencia de la obligaci\u00f3n de indemnizar. &nbsp;<\/p>\n<p>Y propuso como &nbsp;excepciones de m\u00e9rito respecto del llamamiento en garant\u00eda &nbsp; las que nomin\u00f3 i) &nbsp;inexistencia de la obligaci\u00f3n indemnizatoria con cargo a la &nbsp;p\u00f3liza No. 1001711 por ausencia de responsabilidad de la &nbsp;sociedad Litotricia S.A.; ii) inexistencia de solidaridad frente a la &nbsp;Previsora S.A. Compa\u00f1\u00eda de Seguros; iii) l\u00edmite &nbsp;de cobertura de acuerdo con los sublimites pactados; iv) deducible; &nbsp;v) excepci\u00f3n innominada; vi) cualesquiera otras excepciones &nbsp;perentoria que se deriven de la ley o del contrato de seguro recogi\u00f3 &nbsp;en la p\u00f3liza de responsabilidad civil extracontractual &nbsp;invocada como fundamento de la citaci\u00f3n incluida la de &nbsp;prescripci\u00f3n de las acciones derivadas del contrato de seguro, &nbsp;sin que implique reconocimiento alguno de responsabilidad por parte &nbsp;de mi prohijada. &nbsp;<\/p>\n<p>3.3 &nbsp;El m\u00e9dico Pedro V\u00e9lez de Pombo de la misma manera se &nbsp;opuso a las pretensiones de la demanda, propuso las excepciones de &nbsp;m\u00e9rito de i) &nbsp;inexistencia de un da\u00f1o indemnizable \u2013 caso fortuito; &nbsp;ii) inexistencia del da\u00f1o imputable a mala pr\u00e1ctica &nbsp;m\u00e9dica; iii) inexistencia de la obligaci\u00f3n de &nbsp;indemnizar. &nbsp;<\/p>\n<p>El ur\u00f3logo &nbsp;V\u00e9lez de Pombo llam\u00f3 en garant\u00eda a Seguros &nbsp;Generales Suramericana S.A., la cual en relaci\u00f3n con la &nbsp;demanda formul\u00f3 las excepciones de i) &nbsp;ausencia de responsabilidad del demandado Pedro V\u00e9lez de &nbsp;Pombo, y por tanto ausencia de cobertura de la p\u00f3liza de &nbsp;seguro invocada por quien ha formulado el llamamiento en garant\u00eda; &nbsp;ii) aceptaci\u00f3n del riesgo \u2013 inexistencia de mala praxis; &nbsp;y &nbsp;como excepciones frente al llamamiento en garant\u00eda i) &nbsp;aplicaci\u00f3n de los limites asegurados previstos en la p\u00f3liza &nbsp;de seguro; ii) aplicaci\u00f3n del deducible pactado en la p\u00f3liza. &nbsp;10% del valor a pagar; iii) aplicaci\u00f3n de las exclusiones &nbsp;pactadas en la p\u00f3liza. &nbsp;<\/p>\n<p>3.4 &nbsp;Coomeva E.P.S. S.A. al contestar la demanda adem\u00e1s de oponerse &nbsp;a las pretensiones propuso los medios de defensa que denomin\u00f3 &nbsp;i) &nbsp;inexistencia de la obligaci\u00f3n de indemnizar por ausencia de &nbsp;los elementos estructurales de la responsabilidad civil; ii) caso &nbsp;fortuito; iii) inexistencia de solidaridad de Coomeva EPS S.A y &nbsp;Litotricia S.A. frente a los hechos y pretensiones de la demanda; iv) &nbsp;las obligaciones m\u00e9dicas son de medio y no de resultado; v) el &nbsp;r\u00e9gimen de responsabilidad civil m\u00e9dica se rige por la &nbsp;culpa probada de acuerdo al art. 177 del C.P.C.; vi) la innominada de &nbsp;que trata el art. 306 del C.P.C. &nbsp;<\/p>\n<p>Coomeva E.P.S. &nbsp;S.A. llam\u00f3 en garant\u00eda a la codemandada Litotricia &nbsp;S.A., sin que se presentaran excepciones por la aseguradora frente al &nbsp;llamamiento. &nbsp;<\/p>\n<p>4. &nbsp;El Juzgado Tercero Civil del Circuito de Cartagena de Indias D. T. y &nbsp;C. profiri\u00f3 sentencia el 2 de diciembre de 2019, por encontrar &nbsp;probadas varias de las excepciones propuestas, neg\u00f3 las &nbsp;pretensiones de la demanda. Para desatar la apelaci\u00f3n que &nbsp;contra ese prove\u00eddo interpuso el promotor de la controversia, &nbsp;la Sala Civil \u2013 Familia del Tribunal Superior del Distrito &nbsp;Judicial de Cartagena dict\u00f3 sentencia el 22 de julio de 2020, &nbsp;en la que confirm\u00f3 la determinaci\u00f3n apelada. &nbsp;<\/p>\n<p>LA &nbsp;SENTENCIA DEL TRIBUNAL &nbsp;<\/p>\n<p>El Tribunal &nbsp;emprendi\u00f3 su estudio destacando que conforme a la &nbsp;jurisprudencia de esta Corte, cuando se trata de responsabilidad &nbsp;m\u00e9dica, una de sus reglas es la de culpa probada, por cuanto &nbsp;no se presume la culpa por el solo hecho del inconformismo del &nbsp;paciente, no existe una responsabilidad objetiva, sino que se debe &nbsp;demostrar la imprudencia, negligencia, descuido o desatenci\u00f3n &nbsp;de la lex &nbsp;artis, &nbsp;siendo carga del actor el enunciar en su demanda, con precisi\u00f3n &nbsp;y claridad, los actos culposos o dolosos que produjeron el da\u00f1o, &nbsp;para luego emprender su demostraci\u00f3n y contradicci\u00f3n en &nbsp;el juicio. &nbsp;<\/p>\n<p>Anot\u00f3, que &nbsp;aunque el apoderado de la parte demandante indic\u00f3 que en la &nbsp;historia cl\u00ednica no se registr\u00f3 el estado de salud del &nbsp;paciente de forma posterior al procedimiento, concretamente entre las &nbsp;entre las 17:00 y las 21:58 del 12 de agosto de 2015, omisi\u00f3n &nbsp;que destaca como relevante en la medida que con ella se pudo &nbsp;identificar y tratar oportunamente el shock hipovol\u00e9mico, lo &nbsp;cierto es que el se\u00f1or Rivera si estuvo vigilado por distintos &nbsp;profesionales de la salud como lo demuestran las ordenes m\u00e9dicas &nbsp;y control de signos vitales, aunque en todo caso, para la hora 21:58 &nbsp;de ese d\u00eda de la intervenci\u00f3n \u00abno &nbsp;mostraba signos ni s\u00edntomas claros que evidenciaran que estaba &nbsp;sufriendo un \u201cshock hipovol\u00e9mico\u201d, de suerte que, &nbsp;antes o hasta ese momento, no se le pod\u00eda exigir a los &nbsp;demandados que aplicaran el procedimiento previsto por la ciencia &nbsp;m\u00e9dica para contrarrestar esa posible dolencia\u00bb. &nbsp;<\/p>\n<p>Conclusi\u00f3n &nbsp;a la que lleg\u00f3 de la evaluaci\u00f3n de las declaraciones de &nbsp;Antonio Marzan Esquivel (anestesi\u00f3logo), Juan Manuel Benedetti &nbsp;Sarasty (anestesi\u00f3logo), C\u00e9sar Schamud Fayad (ur\u00f3logo) &nbsp;y Gustavo Alonso Garc\u00eda Fern\u00e1ndez (cirujano general), &nbsp;la historia cl\u00ednica allegada, y confrontar la gu\u00eda para &nbsp;manejo de urgencias del Ministerio de Protecci\u00f3n Social. &nbsp;<\/p>\n<p>De las precedentes &nbsp;pruebas estableci\u00f3 que el manejo que se impon\u00eda para &nbsp;tratar la \u201chemorragia\u201d &nbsp;era &nbsp;\u201ccompensar &nbsp;al paciente con el suministro de \u201cl\u00edquidos\u201d y &nbsp;componentes sangu\u00edneos y luego de \u201cestabilizarlo\u201d, &nbsp;si proceder a su reintervenci\u00f3n quir\u00fargica\u201d y &nbsp;posteriormente continuar con medidas secundarias, \u201cno &nbsp;siendo predicable un error en el tratamiento que recibi\u00f3 FELIX &nbsp;ENRIQUE RIVERA PINEDA (q.e.p.d.) comoquiera que su estado de salud en &nbsp;general, la misma hemorragia y las paradas cardiacas que sufri\u00f3 &nbsp;le imped\u00edan al equipo m\u00e9dico someterlo a una nueva &nbsp;cirug\u00eda de manera \u201cinmediata\u201d, sin que antes fuera &nbsp;estabilizado hemodin\u00e1micamente\u201d sin &nbsp;que se pueda sostener que el paciente deb\u00eda ser reintervenido, &nbsp;pues dadas las condiciones f\u00edsicas en que se encontraba &nbsp;representaba un mayor riesgo para su vida. &nbsp;<\/p>\n<p>Frente a lo &nbsp;expresado por &nbsp;el DADIS, y la IPS Promotora Bocagrande S.A., en el &nbsp;sentido que la segunda intervenci\u00f3n fue &nbsp;\u201cinoportuna\u201d &nbsp;precis\u00f3 que en todo caso se puede inferir que para dichas &nbsp;instituciones el paciente pod\u00eda ser reintervenido luego de la &nbsp;segunda parada cardiaca, esto es, a partir de las 02:43 del 13 de &nbsp;agosto de 2015, siempre que el paciente estuviera estable &nbsp;hemodin\u00e1micamente, lo que se sit\u00faa entre las 4:30 y &nbsp;5:30 am del 13 de agosto de 2015, aunque no se logr\u00f3 demostrar &nbsp;que la \u201cinoportunidad\u201d &nbsp;haya sido la causa eficiente de la muerte, ya que exist\u00eda una &nbsp;alta probabilidad que al paciente superara las dolencias que &nbsp;presentaba, desdibujando el nexo de causalidad requerido para &nbsp;predicar responsabilidad. &nbsp;<\/p>\n<p>Destac\u00f3 &nbsp;que la desatenci\u00f3n telef\u00f3nica del m\u00e9dico ur\u00f3logo &nbsp;no determin\u00f3 un error diagnostico o un servicio m\u00e9dico &nbsp;deficiente, pues en su ausencia estuvieron al tanto los m\u00e9dicos &nbsp;Schamud Fayad (ur\u00f3logo) y Liendo Herrera (cirujano e &nbsp;intensivista), quienes estaban en condiciones de atender las &nbsp;complicaciones que se presentaran en las instalaciones de la I.P.S. &nbsp;Promotora Bocagrande S.A. &nbsp;<\/p>\n<p>LA DEMANDA DE &nbsp;CASACI\u00d3N &nbsp;<\/p>\n<p>La demandante &nbsp;formul\u00f3 dos acusaciones contra la sentencia del Tribunal, &nbsp;enmarcadas en las causales segunda y tercera de casaci\u00f3n. &nbsp;<\/p>\n<p>PRIMER CARGO &nbsp;<\/p>\n<p>En s\u00edntesis, &nbsp;con este se denuncia que en la sentencia del Tribunal se violaron &nbsp;indirectamente los art\u00edculos 1613, 1614, 1615, 1626, 2341, &nbsp;2343,2344 y 2356 del C\u00f3digo Civil, al desconocer la existencia &nbsp;de la prueba testimonial y la historia cl\u00ednica que refieren al &nbsp;abandono negligente por m\u00e1s de cinco (5) horas del paciente. &nbsp;<\/p>\n<p>El juez ad &nbsp;quem ignor\u00f3 &nbsp;la declaraci\u00f3n del m\u00e9dico intensivista Jhonatan Liendo &nbsp;Herrera, la prueba trasladada, las que demuestran la desatenci\u00f3n &nbsp;que sufri\u00f3 el paciente por parte de su m\u00e9dico ur\u00f3logo, &nbsp;lo que \u00aben &nbsp;esta rama del derecho se califica como negligencia, una de las formas &nbsp;de culpa dado que es evidente que al negar la atenci\u00f3n &nbsp;oportuna del paciente le quitaron la oportunidad de sobrevivir, el &nbsp;chance de vida a que ten\u00eda derecho si hubiera sido &nbsp;reintervenido a tiempo\u201d, &nbsp;y como &nbsp;no se valoraron al momento de emitirse la sentencia la totalidad de &nbsp;los medios probatorios admitidos, \u201cel &nbsp;fallo debe revocarse para en su lugar dictar uno condenatorio contra &nbsp;todos los demandados\u00bb. &nbsp;<\/p>\n<p>SEGUNDO CARGO &nbsp;<\/p>\n<p>Se aduce que se &nbsp;configur\u00f3 la causal tercera del art\u00edculo 336 del C\u00f3digo &nbsp;General del Proceso, en la medida que el &nbsp;ad quem tergivers\u00f3 &nbsp;los hechos de la demanda e incluso se contradice, pues, aunque &nbsp;argument\u00f3 que no se acredit\u00f3, ni se manifest\u00f3 &nbsp;que la causa de la muerte del paciente se debi\u00f3 a la atenci\u00f3n &nbsp;m\u00e9dica inoportuna, en el expediente se encuentra la &nbsp;declaraci\u00f3n del m\u00e9dico Jhonatan Liendo, como la &nbsp;decisi\u00f3n del DADIS, de las que se deduce lo contrario, ya que &nbsp;el paciente se encontraba \u00abhemodin\u00e1micamente &nbsp;estable cuando se empez\u00f3 a buscar la presencia de alguno de &nbsp;los ur\u00f3logos por espacio de cinco horas en las que se negaron &nbsp;a comparecer\u00bb, es &nbsp;decir, no existe consonancia entre la sentencia y los hechos. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;En &nbsp;el marco del estatuto procesal civil, el recurso extraordinario de &nbsp;casaci\u00f3n civil prospera ante la existencia de una de las &nbsp;causales consagradas por el art\u00edculo 336 del C\u00f3digo &nbsp;General del Proceso, cuyo rigor en su presentaci\u00f3n se &nbsp;encuentra previsto por el art\u00edculo 344 del mismo ordenamiento. &nbsp;<\/p>\n<p>Se\u00f1ala &nbsp;la norma que la demanda de casaci\u00f3n, am\u00e9n de reunir la &nbsp;especificaci\u00f3n del proceso con los detalles que relaciona en &nbsp;su numeral 1\u00ba el citado art\u00edculo 344, deber\u00e1 &nbsp;referirse de manera formal a cada uno de los cargos con la exposici\u00f3n &nbsp;de sus fundamentos y con sujeci\u00f3n a las reglas all\u00ed &nbsp;impuestas. &nbsp;<\/p>\n<p>Exigencias que &nbsp;tienen su origen en la naturaleza dispositiva y excepcional del &nbsp;recurso, que lo diferencian de &nbsp;las instancias ordinarias, en las cuales, las partes pueden &nbsp;libremente transitar sobre todas las cuestiones de hecho y de derecho &nbsp;en discusi\u00f3n. &nbsp;<\/p>\n<p>Esto, &nbsp;en cambio, no sucede en casaci\u00f3n, el fin de este recurso &nbsp;extraordinario es el de &nbsp;defender la unidad e integridad del ordenamiento jur\u00eddico, &nbsp;lograr la eficacia de los instrumentos internacionales suscritos por &nbsp;Colombia en el derecho interno, proteger los derechos &nbsp;constitucionales, controlar la legalidad de los fallos, unificar la &nbsp;jurisprudencia nacional y reparar los agravios irrogados a las partes &nbsp;con ocasi\u00f3n de la providencia recurrida (art. 333 C.G.P.).&nbsp; &nbsp;<\/p>\n<p>El &nbsp;ataque por esta especial v\u00eda se encamina a romper, quebrar o &nbsp;anular una decisi\u00f3n judicial revestida del principio de &nbsp;legalidad, por lo que solamente procede en casos espec\u00edficos &nbsp;que constituyen numerus &nbsp;clausus. &nbsp;<\/p>\n<p>En &nbsp;este caso, se alegan dos casuales de casaci\u00f3n, la primera con &nbsp;soporte en la causal segunda, en consideraci\u00f3n del recurrente &nbsp;se configur\u00f3 violaci\u00f3n indirecta de la ley sustancial &nbsp;por error de hecho, la segunda, se invoca con apoyo en el numeral &nbsp;tercero, por falta de consonancia entre la sentencia y lo expuesto &nbsp;por la parte impugnante en la demanda. &nbsp;<\/p>\n<p>2. &nbsp;La &nbsp;violaci\u00f3n por la v\u00eda indirecta puede ser de hecho o &nbsp;derecho, la primera hip\u00f3tesis ocurre cuando el fallador cree &nbsp;equivocadamente en la existencia o inexistencia de un medio de prueba &nbsp;o cuando realiza la interpretaci\u00f3n de manera equivocada del &nbsp;material suasorio existente; la segunda posibilidad, de derecho, &nbsp;cuando realiza la valoraci\u00f3n sin atender la normatividad sobre &nbsp;el particular. &nbsp;<\/p>\n<p>En el cargo por &nbsp;error de hecho se deben relacionar cada una de las pruebas en las que &nbsp;se considera ocurri\u00f3 el desacierto en la actividad de &nbsp;apreciaci\u00f3n, ya sea acreditando que se dio una suposici\u00f3n &nbsp;de un medio probatorio, o se pretermiti\u00f3 su an\u00e1lisis, o &nbsp;se tergivers\u00f3 el contenido de este, demostrando la dimensi\u00f3n &nbsp;del error. &nbsp;<\/p>\n<p>La acometida debe &nbsp;comprender la totalidad de las deducciones probatorias sobre las &nbsp;cuales se edific\u00f3 la providencia, dirigi\u00e9ndose con &nbsp;precisi\u00f3n absoluta a que dichas conclusiones muestren que fue &nbsp;grave y notoria la falta en que incurri\u00f3 la sentencia del &nbsp;tribunal. &nbsp;<\/p>\n<p>T\u00e9ngase en &nbsp;cuenta que, en cuanto ata\u00f1e a los supuestos para que prospere &nbsp;la causal segunda &nbsp;de casaci\u00f3n consagrada en el art\u00edculo 336 del C\u00f3digo &nbsp;General del Proceso, fundada en la existencia de error de hecho, la &nbsp;Corte ha dicho que: &nbsp;<\/p>\n<p>\u00ab[ocurre &nbsp;cuando se supone o pretermite la prueba, entendi\u00e9ndose que &nbsp;incurrir\u00e1 en la primera hip\u00f3tesis el juzgador que halla &nbsp;un medio en verdad inexistente o distorsiona el que s\u00ed obra &nbsp;para darle un significado que no contiene, y en la segunda situaci\u00f3n &nbsp;cuando ignora del todo su presencia o lo cercena en parte, para, en &nbsp;esta \u00faltima eventualidad, asignarle una significaci\u00f3n &nbsp;contraria o diversa. El error \u2018ata\u00f1e a la prueba como &nbsp;elemento material del proceso, por creer el sentenciador que existe &nbsp;cuando falta, o que falta cuando existe, y debido a ella da por &nbsp;probado o no probado el hecho\u2019 (G. J., T. LXXVIII, p\u00e1gina &nbsp;313) (\u2026) Denunciada una de las anteriores posibilidades, el &nbsp;impugnador debe acreditar que la falencia endilgada es manifiesta y, &nbsp;adem\u00e1s, que es trascendente por haber determinado la &nbsp;resoluci\u00f3n reprochada, de tal suerte que, de no haberse &nbsp;incurrido en esa sinraz\u00f3n, otra hubiera sido la resoluci\u00f3n &nbsp;adoptada (\u2026) Acorde con la a\u00f1eja, reiterada y uniforme &nbsp;jurisprudencia de la Corporaci\u00f3n, el yerro f\u00e1ctico ser\u00e1 &nbsp;evidente o notorio, \u2018cuando su s\u00f3lo planteamiento haga &nbsp;brotar que el criterio\u2019 del juez \u2018est\u00e1 por &nbsp;completo divorciado de la m\u00e1s elemental sind\u00e9resis; si &nbsp;se quiere, que repugna al buen juicio\u2019, lo que ocurre en &nbsp;aquellos casos en que \u00e9l \u2018est\u00e1 convicto de &nbsp;contraevidencia\u2019 (sentencias de 11 de julio de 1990 y de 24 de &nbsp;enero de 1992), o cuando es \u2018de tal entidad que a primer golpe &nbsp;de vista ponga de manifiesto la contraevidencia de la determinaci\u00f3n &nbsp;adoptada en el fallo combatido con la realidad que fluya del proceso\u2019 &nbsp;(sentencia 146 de 17 de octubre de 2006, exp. 06798-01); dicho en &nbsp;t\u00e9rminos diferentes, significa que la providencia debe &nbsp;aniquilarse cuando aparezca claro que \u2018se estrell\u00f3 &nbsp;violentamente contra la l\u00f3gica o el buen sentido com\u00fan, &nbsp;evento en el cual no es nada razonable ni conveniente persistir &nbsp;tozudamente en el mantenimiento de la decisi\u00f3n so pretexto de &nbsp;aquella autonom\u00eda\u2019 (G. J., T. CCXXXI, p\u00e1gina &nbsp;644)\u00bb. &nbsp;(CSJ sentencia de 21 feb. 2012, rad. 2004-00649, reiterada sentencia &nbsp;24 jul. 2012, rad. 2005-00595-01).1 &nbsp;<\/p>\n<p>Obs\u00e9rvese, &nbsp;adem\u00e1s, que el p\u00e1rrafo primero del art\u00edculo 344 &nbsp;del C\u00f3digo General del Proceso exige que &nbsp;<\/p>\n<p>\u00abCuando &nbsp;se invoque la infracci\u00f3n de normas de derecho sustancial, ser\u00e1 &nbsp;suficiente se\u00f1alar cualquiera disposici\u00f3n de esa &nbsp;naturaleza que, constituyendo base esencial del fallo impugnado o &nbsp;habiendo debido serlo, a juicio del recurrente haya sido violada, sin &nbsp;que sea necesario integrar una proposici\u00f3n jur\u00eddica &nbsp;completa\u00bb. &nbsp;<\/p>\n<p>Adem\u00e1s, &nbsp;<\/p>\n<p>\u00abSea &nbsp;que la acusaci\u00f3n descanse en presunta violaci\u00f3n directa &nbsp;o indirecta, el quejoso deber\u00e1 se\u00f1alar los c\u00e1nones &nbsp;de derecho sustancial que estime inobservados, eventos en los que es &nbsp;suficiente denunciar cualquier precepto de esa estirpe que, &nbsp;constituyendo base substancial de la resoluci\u00f3n rebatida, o &nbsp;habiendo debido serlo, haya sido infringido, sin que sea &nbsp;imprescindible integrar una proposici\u00f3n jur\u00eddica &nbsp;completa. &nbsp;<\/p>\n<p>Es &nbsp;necesario recalcar con relaci\u00f3n a &nbsp;lo primero, que a &nbsp;riesgo de la inadmisi\u00f3n y deserci\u00f3n de \u00e9sta, no &nbsp;puede el reclamante sustraerse de especificar aquellas &nbsp;que poseen esa calidad; siendo tales, las que \u00ab\u2026en &nbsp;raz\u00f3n de una situaci\u00f3n f\u00e1ctica concreta, &nbsp;declaran, crean, modifican o extinguen relaciones jur\u00eddicas &nbsp;tambi\u00e9n concretas entre las personas implicadas en tal &nbsp;situaci\u00f3n\u2026\u00bb, de manera que no son de esa &nbsp;naturaleza aquellas que se \u00ablimitan a definir fen\u00f3menos &nbsp;jur\u00eddicos o a descubrir los elementos de \u00e9stos o a &nbsp;hacer enumeraciones o enunciaciones, como tampoco las tienen las &nbsp;disposiciones ordenativas o reguladoras de la actividad in &nbsp;procedendo\u00bb. (CSJ AC, del 5 de may. 2000).2 &nbsp;<\/p>\n<p>3. &nbsp;La trasgresi\u00f3n por incongruencia, tiene cabida en aquellos &nbsp;casos en que se presente inconsonancia respecto de las pretensiones &nbsp;demandadas o las excepciones propuestas. Como la sentencia es el acto &nbsp;por medio del cual el Estado decide qu\u00e9 tutela dispensa a un &nbsp;inter\u00e9s jur\u00eddico determinado, claramente debe existir &nbsp;una estrecha armon\u00eda entre aquella y lo propuesto por las &nbsp;partes, de tal forma que el fallo es incongruente cuando se decide &nbsp;sobre puntos ajenos a la controversia, se deja sin decidir alg\u00fan &nbsp;punto de la demanda o de las excepciones, o se decide sobre puntos &nbsp;ajenos a la controversia. &nbsp;<\/p>\n<p>Le &nbsp;corresponde al impugnante se\u00f1alar concretamente los puntos &nbsp;ajenos al debate sobre los cuales se pronunci\u00f3 el &nbsp;sentenciador, o las pretensiones oportunamente deducidas por las &nbsp;partes que omiti\u00f3 decidir, a finde destacar la incongruencia &nbsp;en que aquel habr\u00eda incurrido &nbsp;<\/p>\n<p>\u00abel &nbsp;juzgador decide el [juicio] por fuera de las pretensiones o &nbsp;excepciones probadas en el caso (extra petita), o m\u00e1s all\u00e1 &nbsp;de lo pedido (ultra petita), o cercenando lo que fue objeto de &nbsp;alegaci\u00f3n y demostraci\u00f3n (citra petita). Tambi\u00e9n &nbsp;se configura cuando la sentencia no guarda correlaci\u00f3n con las &nbsp;\u2018afirmaciones formuladas por las partes\u2019, puesto que es &nbsp;obvio que el juez no &nbsp;puede hacer m\u00e9rito de un hecho que no haya sido afirmado por &nbsp;ninguna de ellas. &nbsp;Y se ha reconocido, asimismo, que la incongruencia como causal de &nbsp;casaci\u00f3n se da en los eventos en los que se presenta \u2018una &nbsp;desviaci\u00f3n del tema que fue objeto de la pretensi\u00f3n &nbsp;deducida en la sustentaci\u00f3n del recurso\u00bb (La subraya es &nbsp;para resaltar) (AC280-2021, 8 feb., rad. 2013-00031-02). &nbsp;<\/p>\n<p>El &nbsp;proceso civil contiene una relaci\u00f3n jur\u00eddico\u2013procesal &nbsp;en virtud de la cual la actividad de las partes y el campo de &nbsp;decisi\u00f3n del juez quedan vinculados a los t\u00e9rminos de &nbsp;la demanda y su contestaci\u00f3n. Por tanto, \u00ab(&#8230;) los &nbsp;hechos y las pretensiones de la demanda, y las excepciones del &nbsp;demandado trazan, en principio, los l\u00edmites dentro de los &nbsp;cuales debe el juez decidir sobre el derecho disputado en juicio; por &nbsp;consiguiente, la incongruencia de un fallo se verifica mediante una &nbsp;labor comparativa entre el contenido de lo expuesto en tales piezas &nbsp;del proceso y las resoluciones adoptadas en \u00e9l, todo en &nbsp;armon\u00eda con el art\u00edculo 305 del C\u00f3digo de &nbsp;Procedimiento Civil [hoy 281 del C\u00f3digo General del Proceso]; &nbsp;de ese modo se podr\u00e1 establecer si en verdad el juzgador se &nbsp;sustrajo, por exceso o por defecto, a tan precisas pautas (CSJ SC, 6 &nbsp;Jul. 2005, rad. 5214; CSJ SC, 1\u00ba nov. 2006, rad. &nbsp;2002-01309-01)\u00bb&nbsp;(CSJ SC11331-2015, 27 ago., rad, &nbsp;2006-00119-01; reiterado en CSJ AC2115-2021, 2 jun., rad. &nbsp;2013-00193-01). &nbsp;<\/p>\n<p>La &nbsp;Sala ha sido enf\u00e1tica al recabar, que \u00ab(\u2026) &nbsp;no es suficiente con esbozar una falta de coherencia en lo decidido, &nbsp;sino que su planteamiento, para &nbsp;que sea completo, &nbsp;debe comprender la contraposici\u00f3n del fallo con todos los &nbsp;elementos debatidos al interior del litigio y que incidir\u00edan &nbsp;en su proferimiento, esto es la demanda, la contestaci\u00f3n y las &nbsp;excepciones propuestas (\u2026) de tal manera que aparezca de bulto &nbsp;una real desarmon\u00eda con el contexto (\u2026)\u00bb (CSJ &nbsp;AC6075-2021, 16 dic., rad. 2018-01593-01).3 &nbsp;<\/p>\n<p>4. &nbsp;Confrontadas &nbsp;las exigencias formales mencionadas, desde ya se advierte su &nbsp;incumplimiento en los cargos planteados, como pasa a explicarse &nbsp;enseguida. &nbsp;<\/p>\n<p>4.1 &nbsp;Cargo &nbsp;primero. &nbsp;<\/p>\n<p>El &nbsp;recurrente encuadra su denuncia en la causal segunda del canon 336 &nbsp;del C\u00f3digo General del Proceso, indicando que se verifica la &nbsp;<\/p>\n<p>\u00abviolaci\u00f3n &nbsp;indirecta de los art\u00edculos 1613, &nbsp;1614, 1615, 1626, 2341, 2343,2344 y 2356 del C\u00f3digo Civil, a &nbsp;causa de los errores &nbsp;de hecho manifiestos y trascendentes en &nbsp;que incurri\u00f3 el Tribunal cuando desconoce la existencia de la &nbsp;prueba testimonial del m\u00e9dico intensivista a (sic) JHONATAN &nbsp;LIENDO HERRERA y la documental consistente en sus informes &nbsp;consignados en la historia cl\u00ednica y posteriormente ante sus &nbsp;superiores\u00bb. &nbsp;<\/p>\n<p>De &nbsp;manera insistente aduce &nbsp;el censor en &nbsp;la exposici\u00f3n de hechos en que se edifica la acusaci\u00f3n, &nbsp;que &nbsp;el juzgador de segundo grado omiti\u00f3 valorar la prueba &nbsp;testimonial del m\u00e9dico Jhonatan Liendo Herrera, la declaraci\u00f3n &nbsp;de Diana Mar\u00eda Ricardo Garc\u00eda, la historia cl\u00ednica, &nbsp;y la prueba trasladada proveniente del Departamento Distrital de &nbsp;Salud de Cartagena, pruebas de las cuales se pod\u00eda concluir &nbsp;\u00abel &nbsp;abandono negligente de FELIX RIVERA PINEDA por m\u00e1s de cinco &nbsp;horas por parte del personal m\u00e9dico del NUEVO HOSPITAL DE &nbsp;BOCAGRANDE y LITOTRICIA a sabiendas que el paciente sufr\u00eda a &nbsp;la vista de todos el profuso y contante sangrado interno que &nbsp;finalmente le llev\u00f3 a la muerte por shock hipovol\u00e9mico\u00bb, &nbsp;enfatizando en \u00faltimas, que de haberse valorado estos medios &nbsp;de prueba, la conclusi\u00f3n no pod\u00eda ser otra que fue la &nbsp;atenci\u00f3n tard\u00eda de los demandados lo que gener\u00f3 &nbsp;el da\u00f1o, en este caso la muerte del paciente. &nbsp;<\/p>\n<p>El cuestionamiento &nbsp;por error de hecho en este caso estriba en que el sentenciador dej\u00f3 &nbsp;de ver y, por lo tanto, de estimar, pruebas existentes en el juicio, &nbsp;sin embargo, obs\u00e9rvese que el impugnante omiti\u00f3 por &nbsp;completo seguir con fidelidad el rastro de la ponderaci\u00f3n &nbsp;probatoria y la argumentaci\u00f3n jur\u00eddica de la sentencia, &nbsp;mostrando con suficiencia y detalle en qu\u00e9 consistieron cada &nbsp;uno de los desv\u00edos, respecto de todos los fundamentos de la &nbsp;providencia, y la demostraci\u00f3n del vicio en s\u00ed y de su &nbsp;incidencia, confrontando sistem\u00e1ticamente hechos, pruebas, &nbsp;fallo y ley. &nbsp;<\/p>\n<p>La Corte no puede &nbsp;suplir carencias de la demanda, no basta con se\u00f1alar el texto &nbsp;legal que se considera violado, pues si se trata de error en la &nbsp;apreciaci\u00f3n de la prueba, por cuya causa se ha producido un &nbsp;agravio a la ley, es necesario indicar el error que caus\u00f3 el &nbsp;quebranto respectivo, sin que pueda esta Corporaci\u00f3n suponer &nbsp;cu\u00e1les, de una serie de disposiciones citadas en conjunto, &nbsp;fueron quebrantadas por el Tribunal. &nbsp;<\/p>\n<p>El recurrente &nbsp;omiti\u00f3 realizar un espec\u00edfico juicio de valor &nbsp;precisando las acusaciones, pues tan solo se limit\u00f3 a realizar &nbsp;una mera relaci\u00f3n de normas, sin replicar la decisi\u00f3n &nbsp;revestida de presunci\u00f3n de acierto, &nbsp;pues &nbsp;no se trata de que se ensaye un planteamiento distinto al adoptado &nbsp;por el juzgador, para que se configure el error de hecho que se &nbsp;imputa. &nbsp;<\/p>\n<p>El ataque por v\u00eda &nbsp;indirecta se refiere que se dejaron de evaluar la totalidad de las &nbsp;pruebas que obraban en el proceso, sin embargo, obs\u00e9rvese que &nbsp;el cuerpo colegiado no solamente enunci\u00f3 las pruebas en las &nbsp;que edific\u00f3 su decisi\u00f3n, sino que realiz\u00f3 un &nbsp;estudio conjunto de estas, respecto de las cuales el casacionista &nbsp;omiti\u00f3 efectuar alg\u00fan tipo de cuestionamiento, &nbsp;desatendiendo la completitud y enfoque que debe predicarse de todo &nbsp;cargo enrostrado. &nbsp;<\/p>\n<p>En el fallo se &nbsp;valoraron los testimonios de los m\u00e9dicos Antonio Marzan &nbsp;Esquivel, Juan Manuel Benedetti Sarasty, C\u00e9sar Schamud Fayad y &nbsp;Gustavo Alonso Garc\u00eda Fern\u00e1ndez, de los apartes &nbsp;transcritos se logra colegir que la palidez mucocut\u00e1nea &nbsp;generalizada de un paciente en un postoperatorio pr\u00f3ximo no &nbsp;necesariamente es indicativo alguna patol\u00f3gica especifica, y &nbsp;que en este caso, el paciente para las 10 de la noche de ese 12 de &nbsp;agosto no presentaba signos de alarma que permitiera establecer que &nbsp;cursaba alg\u00fan tipo de complicaci\u00f3n, por el contrario, &nbsp;para ese momento, la respiraci\u00f3n y &nbsp;frecuencia cardiaca &nbsp;estaban dentro de los rangos normales, mostraba abdomen blando, &nbsp;depresible, per\u00edstasis normal, Glasgow de 15\/15, hemoglobina &nbsp;de 10, y solo si aquella descend\u00eda a 6 o 5, se considerar\u00eda &nbsp;alg\u00fan tipo de intervenci\u00f3n, como transfusi\u00f3n o &nbsp;correcci\u00f3n. &nbsp;<\/p>\n<p>Conforme &nbsp;la &nbsp;historia cl\u00ednica, solamente hasta la 1:34 a.m. del 13 de &nbsp;agosto, el paciente present\u00f3 paro cardiaco, evento en el que &nbsp;fue asistido por el m\u00e9dico cirujano e intensivista Jhonatan &nbsp;Liendo, quien dio inicio al protocolo de reanimaci\u00f3n y realiz\u00f3 &nbsp;una intubaci\u00f3n orotraqueal, pero dicha condici\u00f3n se &nbsp;presenta nuevamente a las 2:43 a.m., oportunidad en la que se &nbsp;relaciona que se llam\u00f3 al ur\u00f3logo tratante, &nbsp;realiz\u00e1ndose 18 llamadas sin respuesta, sin que tampoco &nbsp;contestara el ur\u00f3logo de turno, por lo cual se continu\u00f3 &nbsp;con \u00abvasopresina &nbsp;para mejoramiento de cifras tensionales, se inicia gastroprotecci\u00f3n &nbsp;con omeprazol, se pasa bicarbonato de sodio iv en paciente con gases &nbsp;arteriales con acidosis metab\u00f3lica severa\u00bb &nbsp;en UCI se realiz\u00f3 trasfusi\u00f3n de componentes sangu\u00edneos, &nbsp;fluidoterapia, cristaloides, crioprecipitados y diferentes &nbsp;medicamentos. Consiguiendo la estabilizaci\u00f3n del paciente &nbsp;entre las 4:30 a.m. y 5:00 a.m. tal como lo inform\u00f3 el m\u00e9dico &nbsp;Jhonatan Liendo ante el DADIS. A las 7:53 es reintervenido por el &nbsp;ur\u00f3logo Pedro Alonso V\u00e9lez de Pombo, quien identific\u00f3 &nbsp;puntos de sangrado en el ri\u00f1\u00f3n residual derecho, por lo &nbsp;que llev\u00f3 a cabo nefrectom\u00eda total derecha, drenando &nbsp;1.500 cc de sangre. Debido a rigidez abdominal, a las 18:21 se &nbsp;practic\u00f3 laparotom\u00eda exploratoria y descompresiva, con &nbsp;todo, el paciente falleci\u00f3 a las 12:12m del d\u00eda &nbsp;siguiente. &nbsp;<\/p>\n<p>El manejo &nbsp;descrito, consignado en la historia cl\u00ednica, coincide con lo &nbsp;expuesto por lo m\u00e9dicos en sus declaraciones, pero adem\u00e1s &nbsp;atiende los pasos del protocolo de urgencias del Ministerio de Salud, &nbsp;el cual da prioridad a proveer oxigenaci\u00f3n y ventilaci\u00f3n, &nbsp;como al suministro de l\u00edquidos, para luego de estabilizar el &nbsp;paciente proceder con la reintervenci\u00f3n, procurando evitar que &nbsp;en el acto quir\u00fargico se presente una mayor complicaci\u00f3n. &nbsp;<\/p>\n<p>Lo expuesto llev\u00f3 &nbsp;al Tribunal a considerar que no se present\u00f3 un error en el &nbsp;hecho de aguardar que el paciente se estabilizara hemodin\u00e1micamente, &nbsp;para luego proceder con la reintervenci\u00f3n. &nbsp;<\/p>\n<p>Ahora bien, &nbsp;asevera el censor que se omiti\u00f3 valorar la prueba trasladada, &nbsp;y el testimonio del Doctor Liendo, de los cuales se pod\u00eda &nbsp;colegir que debido a la demora en la pr\u00e1ctica del segundo &nbsp;procedimiento o cirug\u00eda de correcci\u00f3n el paciente &nbsp;falleci\u00f3, pero eso no fue as\u00ed, lo cierto es que, &nbsp;primero, el Tribunal relacion\u00f3 que en efecto el DADIS &nbsp;consider\u00f3 que la segunda intervenci\u00f3n quir\u00fargica &nbsp;fue inoportuna, al punto que en la Resoluci\u00f3n No. 4301 de 3 de &nbsp;junio de 2018 consign\u00f3 \u00abhubo &nbsp;demora en el tratamiento del shock hemorr\u00e1gico en el paciente &nbsp;fallecido atribuible a la falta de disponibilidad de ur\u00f3logo &nbsp;en ese momento\u00bb, &nbsp;agregando que la I.P.S. Promotora Bocagrande S.A. en el Acta de &nbsp;Comit\u00e9 de 1\u00ba de enero de 2104, coincidi\u00f3 sobre la &nbsp;\u00abinoportunidad &nbsp;en la reintervenci\u00f3n en procedimiento por no presencia ur\u00f3logo &nbsp;de 5 horas aproximadamente desde la identificaci\u00f3n de &nbsp;necesidad de reintervenci\u00f3n hasta el procedimiento realizado a &nbsp;las 7:53 a.m.\u00bb, &nbsp;y segundo, esa Corporaci\u00f3n realiz\u00f3 la valoraci\u00f3n &nbsp;de la prueba, labor\u00edo propio y exclusivo del juez, operaci\u00f3n &nbsp;mental que tiene por fin conocer el m\u00e9rito o valor de &nbsp;convicci\u00f3n que pueda deducirse de su contenido4, &nbsp;desembocando en la notable &nbsp;ausencia de convencimiento sobre los &nbsp;hechos que serv\u00edan de fundamento a la pretensi\u00f3n del &nbsp;demandante, pese a que se acopiaron pruebas encaminadas para tratar &nbsp;de establecerlos. &nbsp;<\/p>\n<p>Tras confrontar &nbsp;las conclusiones de la I.P.S. promotora Bocagrande S.A. como el &nbsp;DADIS, con los testimonios de los m\u00e9dicos que asistieron al &nbsp;paciente, cotejando la atenci\u00f3n brindada con los par\u00e1metros &nbsp;de la gu\u00eda de manejo de urgencias, el sentenciador encontr\u00f3 &nbsp;apropiada el proceder de los m\u00e9dicos en el manejo de la &nbsp;complicaci\u00f3n que present\u00f3 el se\u00f1or Rivera &nbsp;Pineda, pues era imperativo la estabilizaci\u00f3n del paciente &nbsp;previo a la reintervenci\u00f3n en b\u00fasqueda de la causa de &nbsp;su estado cr\u00edtico, y que de modo alguno, trascurrieron cinco &nbsp;(5) horas sin que el paciente fuera reintervenido por ausencia de un &nbsp;ur\u00f3logo en la instituci\u00f3n, pues, escindi\u00f3 dos &nbsp;momentos cruciales, uno en el que se advierte la necesidad de &nbsp;reintervenci\u00f3n, y otro, cuando el paciente en efecto puede ser &nbsp;objeto de la misma, los cuales no son coincidentes, ya que se &nbsp;requer\u00eda su estabilizaci\u00f3n, lo que hizo el m\u00e9dico &nbsp;Liendo entre las 4:30 y 5:00 de la ma\u00f1ana de ese 13 de agosto, &nbsp;procediendo el ur\u00f3logo a la cirug\u00eda de correcci\u00f3n &nbsp;a las 7:53 a.m, una vez estuvo estable hemodin\u00e1micamente el &nbsp;paciente, sin que pueda perderse de vista que aquel jam\u00e1s dej\u00f3 &nbsp;de estar cr\u00edtico, de modo que como lo sostuvo el m\u00e9dico &nbsp;Sarasty, con cirug\u00eda o no, ten\u00eda la posibilidad de &nbsp;muerte de casi el 100% en las siguientes 24 horas, como fatalmente &nbsp;ocurri\u00f3. &nbsp;<\/p>\n<p>Expuso el Tribunal &nbsp;que el anterior desenlace afectaba de forma frontal el nexo de &nbsp;causalidad, pues no se prob\u00f3 que la \u201ctardanza\u201d en &nbsp;la reintervenci\u00f3n, en realidad correspondiera a la causa &nbsp;eficiente de la muerte, pues la posibilidad de fallecimiento estaba &nbsp;latente a\u00fan de haberse practicado la cirug\u00eda antes de &nbsp;la hora en que efectivamente se llev\u00f3 a cabo, y a\u00fan &nbsp;menos se acredit\u00f3 que justamente el trascurso del tiempo &nbsp;incidi\u00f3 en su deceso. &nbsp;<\/p>\n<p>De esta manera, no &nbsp;existi\u00f3 tal preterici\u00f3n de los medios de prueba que con &nbsp;desatino denuncia el casacionista dej\u00f3 de valorar el Tribunal, &nbsp;pero es que, adem\u00e1s, en realidad, la circunstancia llana de &nbsp;que en un fallo no se cite determinada prueba o parte del contenido &nbsp;de esta no implica error manifiesto de hecho, a menos que de haberse &nbsp;apreciado tal medio, la conclusi\u00f3n del pronunciamiento hubiera &nbsp;tenido que ser evidentemente distinta de la adoptada por el &nbsp;sentenciador. &nbsp;<\/p>\n<p>Dicho de otra &nbsp;manera, un fallo solamente puede ser infirmado por error por v\u00eda &nbsp;de hecho, cuando el ataque contra el mismo destruye totalmente sus &nbsp;bases, m\u00e1s no as\u00ed cuando alguna de estas queda en pie, &nbsp;bien sea porque la impugnaci\u00f3n no la cobija, o bien porque la &nbsp;misma resulte inane para destruirla. &nbsp;<\/p>\n<p>Como el &nbsp;juzgador colegiado consider\u00f3 que, \u00abse &nbsp;insiste, para que una persona sea obligada a resarcir los perjuicios &nbsp;reclamados, no s\u00f3lo se debe demostrar que obr\u00f3 con &nbsp;culpa, sino, adem\u00e1s, que esa acci\u00f3n u omisi\u00f3n &nbsp;fue la causa eficiente de los da\u00f1os irrogados, lo cual, seg\u00fan &nbsp;las probanzas que obran en el expediente, no fue acreditado\u00bb, &nbsp;es patente, la deficiencia &nbsp;t\u00e9cnica en la demanda por incompletitud, pues dicha &nbsp;aseveraci\u00f3n qued\u00f3 en eso, hu\u00e9rfana de &nbsp;cuestionamiento id\u00f3neo que soporte el cargo que se analiza. &nbsp;<\/p>\n<p>No bastaba para la &nbsp;prosperidad de la pretensi\u00f3n de responsabilidad civil, &nbsp;acreditar la existencia del da\u00f1o, como la conducta &nbsp;reprochable, sino, adem\u00e1s, el nexo de causalidad, el que esa &nbsp;conducta era la determinante del da\u00f1o, conclusi\u00f3n a la &nbsp;que descendi\u00f3 en \u00faltimas el juzgador de segundo grado, &nbsp;lo cual no fue objeto de censura por error de hecho manifiesto en la &nbsp;apreciaci\u00f3n de la prueba. &nbsp;<\/p>\n<p>Si bien se aduce &nbsp;que el fallador de \u00faltima instancia cometi\u00f3 error &nbsp;f\u00e1ctico, cuando confirm\u00f3 la negativa de declaratoria de &nbsp;responsabilidad sin detenerse en la totalidad de los medios de &nbsp;prueba, lo cierto es que el cargo luce incompleto, valga &nbsp;anotar, que no toca la totalidad de los argumentos en que se ciment\u00f3 &nbsp;el prove\u00eddo de segundo grado. &nbsp;<\/p>\n<p>Tampoco el &nbsp;impugnante acredit\u00f3 que la falencia enrostrada fuera &nbsp;trascendente, de tal suerte que, de no haberse incurrido en ella, &nbsp;otra hab\u00eda sido la suerte de la resoluci\u00f3n adoptada, ni &nbsp;que el yerro alegado recayera sobre uno de los hechos decisivos de la &nbsp;litis, &nbsp;es decir, no se prob\u00f3 que tuviera incidencia suficiente para &nbsp;generar la modificaci\u00f3n de la sentencia, siento tal error &nbsp;inocuo. &nbsp;<\/p>\n<p>Cuando el juzgador &nbsp;haciendo uso de su poder discrecional de apreciaci\u00f3n, tiene &nbsp;por demostrado un determinado hecho m\u00e1s bien que otro, no &nbsp;puede decirse que se incurri\u00f3 en error de hecho trascedente en &nbsp;casaci\u00f3n, porque el yerro de esta clase ha de ser evidente y &nbsp;esa evidencia no se configura cuando el Tribunal, sin violentar la &nbsp;l\u00f3gica, deduce del contenido de la prueba la conclusi\u00f3n &nbsp;que acoge. Ha de respetarse el razonamiento que bajo la presunci\u00f3n &nbsp;de acierto se ampara en el marco de la autonom\u00eda que al &nbsp;fallador de instancia reconoce la ley, y que, por tanto, no puede ser &nbsp;variado a trav\u00e9s del recurso extraordinario. &nbsp;<\/p>\n<p>En estas &nbsp;condiciones el cargo formulado no se aviene a las exigencias formales &nbsp;del art\u00edculo 344 del C\u00f3digo General del Proceso, lo &nbsp;cual es &nbsp;motivo suficiente para declararlo infundado. &nbsp;<\/p>\n<p>4.2 &nbsp;Cargo &nbsp;segundo. &nbsp;<\/p>\n<p>El segundo cargo &nbsp;se invoc\u00f3 con apoyo en la causal tercera de casaci\u00f3n, &nbsp;se anuncia que la sentencia \u00abno &nbsp;estuvo en consonancia con los hechos de la demanda y que de haberlo &nbsp;estado la decisi\u00f3n fuese condenatoria dado que dicho fallo se &nbsp;funda en la premisa falsa de no haberse alegado la inoportunidad en &nbsp;la atenci\u00f3n m\u00e9dica como causa de la muerte del &nbsp;paciente\u00bb &nbsp; dijo que resulta evidente que el \u00abad &nbsp;quem tergiversa los hechos de la demanda e incluso en un mismo &nbsp;p\u00e1rrafo de la sentencia se contradice en torno a ellos lo cual &nbsp;se hace patente cuando al referirse a la inoportuna intervenci\u00f3n &nbsp;m\u00e9dica como la causa &nbsp;de la muerte se\u00f1ala que tal &nbsp;situaci\u00f3n ni se acredit\u00f3 ni se manifest\u00f3 a pesar &nbsp;de que en la demanda, en la atestaci\u00f3n del m\u00e9dico &nbsp;intensivista JHONATAN LIENDO como en la decisi\u00f3n del DADIS se &nbsp;acredita hasta la saciedad que la causa de la muerte fue la atenci\u00f3n &nbsp;inoportuna\u00bb. &nbsp;<\/p>\n<p>Agreg\u00f3 que &nbsp;la parte demandante \u00abno &nbsp;adujo que la demora en la segunda intervenci\u00f3n quir\u00fargica &nbsp;le rest\u00f3 la oportunidad a FELIX ENRIQUE RIVERA PINEDA para &nbsp;mejorar su salud\u00bb, lo &nbsp;cual resulta contrario a los hechos, en lo que s\u00ed insisti\u00f3 &nbsp;fue en precisar que debido a la atenci\u00f3n tard\u00eda el &nbsp;paciente empeor\u00f3 progresivamente. &nbsp;<\/p>\n<p>Al respecto, es &nbsp;ostensible el desatino del recurrente al fundamentar este cargo, no &nbsp;solamente dej\u00f3 de lado realizar un labor\u00edo t\u00e9cnico &nbsp;inteligible, exacto, envolvente de esta causal, sino que tras &nbsp;confrontarse esta demanda con la que se inici\u00f3 este tr\u00e1mite, &nbsp;ning\u00fan reproche puede hacerse en torno de la congruencia de la &nbsp;sentencia, pues no concurren ninguna de las formas que integran esta &nbsp;causal de casaci\u00f3n. &nbsp;<\/p>\n<p>En el &nbsp;planteamiento del censor no se revela un fallo que se pronuncie sobre &nbsp;cuestiones ajenas, o que haya dejado pendiente algunas resoluciones, &nbsp;que fue excesivo o deficiente respecto de lo que los planteamientos &nbsp;de las partes, dicho de otra forma, no se discute si la decisi\u00f3n &nbsp;de segundo grado se pronunci\u00f3 sobre asuntos extra\u00f1os a &nbsp;la relaci\u00f3n jur\u00eddico procesal, o que no se acomoda en &nbsp;su totalidad con las pretensiones formuladas en oportunidad, al &nbsp;haberse dejado peticiones del reclamante o de la defensa sin &nbsp;resolver, o hab\u00e9rseles concedido m\u00e1s de lo que &nbsp;pretendieron. &nbsp;<\/p>\n<p>Reit\u00e9rese &nbsp;sobre los requerimientos para la configuraci\u00f3n de esta causal &nbsp;lo expuesto recientemente por esta Sala &nbsp;<\/p>\n<p>\u00ab(\u2026) &nbsp;para la prosperidad de la causal tercera prevista en el art\u00edculo &nbsp;336 del C\u00f3digo General del Proceso, es menester que el &nbsp;recurrente demuestre un exabrupto palpable entre lo narrado y exigido &nbsp;en la demanda, as\u00ed como lo planteado en las defensas del &nbsp;oponente, frente a lo que aparece consignado en el fallo, de tal &nbsp;manera que se note de bulto c\u00f3mo lo decidido es extra\u00f1o &nbsp;al debate (\u2026)\u00bb (SC4407-2021, 22 oct., rad. &nbsp;2016-00298-01) &nbsp;<\/p>\n<p>Los &nbsp;cuestionamientos de los convocados sobre la falta de coherencia &nbsp;intr\u00ednseca de la sentencia, por desarrollar en su parte &nbsp;considerativa el estudio de los elementos axiol\u00f3gicos de la &nbsp;simulaci\u00f3n relativa, para terminar accediendo a la &nbsp;declaratoria de simulaci\u00f3n absoluta, no resultan enmarcables &nbsp;en la v\u00eda casacional elegida, pues est\u00e1 claro que por &nbsp;medio de ella \u00fanicamente es dable repeler un fallo &nbsp;inconsonante \u00ab(\u2026) con &nbsp;los hechos y las pretensiones aducidos en la demanda y en las dem\u00e1s &nbsp;oportunidades que este C\u00f3digo contempla, y con las excepciones &nbsp;que aparezcan probadas y hubieren sido alegadas si as\u00ed lo &nbsp;exige la ley\u2019. Luego, la incongruencia no se presenta solo &nbsp;cuando existe una disonancia entre lo invocado en las pretensiones de &nbsp;la demanda y lo fallado, sino que tambi\u00e9n se patentiza cuando &nbsp;la sentencia no armoniza con lo pedido en la sustentaci\u00f3n del &nbsp;recurso que, indudablemente, corresponde a una pretensi\u00f3n del &nbsp;derecho sustancial controvertido (SC5142, 16 dic. 2020, rad. n.\u00b0 &nbsp;2010-00197-01). &nbsp;5 &nbsp;<\/p>\n<p>La incongruencia &nbsp;como causal de casaci\u00f3n no consiste en que la sentencia &nbsp;disienta de las pretensiones de la demanda, sino que el juez &nbsp;colegiado resuelva o no, seg\u00fan el caso, sobre cuestiones &nbsp;incluidas o no, en la acci\u00f3n o en la defensa, lo que impone &nbsp;que la Corte efect\u00fae una tarea de comparaci\u00f3n donde se &nbsp;pueda concluir si existe entre una ostensible desarticulaci\u00f3n, &nbsp;ya porque el fallo resuelve sobre lo que no le fue impetrado, ora &nbsp;porque al decidir omite, en todo o en parte, acerca de las peticiones &nbsp;de la demanda o las excepciones de los convocados. &nbsp;<\/p>\n<p>Ac\u00e1 eso no &nbsp;se informa por el recurrente, lo que si subray\u00f3 fue en decir &nbsp;que el Tribunal tergivers\u00f3 \u00ablos &nbsp;hechos de la demanda &nbsp;o que se contradice &nbsp;en torno a ellos, pese &nbsp;a que se acredit\u00f3 &nbsp;hasta la saciedad que la causa de la muerte fue la atenci\u00f3n &nbsp;inoportuna, a\u00f1adiendo &nbsp;que la sentencia en &nbsp;su parte resolutiva no solo es contraria a los hechos de la demanda &nbsp;sino que un mismo p\u00e1rrafo se controvierte a si misma en su &nbsp;tesis exculpativa afirmando hechos ajenos a la realidad que fue &nbsp;puesta de presente tanto en la demanda como en la prueba trasladada &nbsp;contentiva del testimonio del intensivista que atendi\u00f3 al &nbsp;paciente y en la Resoluci\u00f3n No. 4301 del 3 de junio de 2018 &nbsp;proferida por el DADIS, y &nbsp;que por dichas condiciones, el fallo no &nbsp;estuvo en consonancia con los hechos de la demanda\u00bb. &nbsp;<\/p>\n<p>En otras palabras, &nbsp;la incongruencia que reclama esta causal no es la discordancia en s\u00ed &nbsp;misma de la decisi\u00f3n, sino el desacoplamiento respecto de la &nbsp;acci\u00f3n o la excepci\u00f3n, pues, &nbsp;<\/p>\n<p>\u00ab\u2026esta &nbsp;causal no autoriza ni puede autorizar a entrar en el examen de las &nbsp;consideraciones que han servido al Juzgador como motivos &nbsp;determinantes de su fallo, porque si la censura parte de haber &nbsp;cometido el sentenciador yerros de apreciaci\u00f3n en cuanto a lo &nbsp;pedido y lo decidido, y \u2018a consecuencia de ello resuelve de &nbsp;manera diferente a como se le solicit\u00f3, no comete &nbsp;incongruencia sino un vicio in-judicando, que debe ser atacado por la &nbsp;causal primera de casaci\u00f3n\u2019\u2026 (Sentencia de 7 de &nbsp;marzo de 1997, exp. 4636). &nbsp;<\/p>\n<p>Tambi\u00e9n &nbsp;se ha indicado que: &nbsp;<\/p>\n<p>\u2026la &nbsp;falta de congruencia resultante de la comparaci\u00f3n objetiva del &nbsp;petitum, causa petendi, excepciones y la sentencia proferida (cas. &nbsp;civ. 22 de mayo de 2008, [SC-045-200], exp. &nbsp;25151-3103-001-2003-00100-01), sea por exceso (ultra o extra petita), &nbsp;ya por defecto (minus petita), ora por invenci\u00f3n de los hechos &nbsp;\u2026 es ajena a cualquier error de hecho o de derecho en la &nbsp;valoraci\u00f3n f\u00e1ctica o jur\u00eddica de las pruebas, y &nbsp;a todo eventual yerro interpretativo de la demanda o su respuesta, en &nbsp;el cual, podr\u00e1 presentarse \u2018un vicio in-judicando, que &nbsp;debe ser atacado por la causal primera de casaci\u00f3n\u2019 &nbsp;(CXVI, p. 84, y CCXLVI, 1, 157)\u2026\u2018ostenta &nbsp;naturaleza objetiva, al margen de las consideraciones normativas, la &nbsp;valoraci\u00f3n probatoria o eventuales yerros de juzgamiento, y no &nbsp;se estructura por simple divergencia o disentimiento con la decisi\u00f3n\u00bb &nbsp;(cas. civ. sentencia de 2 de junio de 2010, exp. &nbsp;11001-3103-021-1995-09578-01). &nbsp;6 &nbsp;<\/p>\n<p>Para abundar en &nbsp;razones frente a la ausencia de una exposici\u00f3n coherente de &nbsp;este cargo, obs\u00e9rvese que como lo ha sostenido de manera &nbsp;inveterada esta Corte, resulta del todo contrario a la t\u00e9cnica &nbsp;de casaci\u00f3n entremezclar temas probatorios en cargos &nbsp;relacionados con la causales primera, tercera y cuarta, prohibici\u00f3n &nbsp;contenida en los literales a) y b) del numeral 2\u00ba del art\u00edculo &nbsp;344 del C\u00f3digo General del Proceso. &nbsp;<\/p>\n<p>Finalmente, no &nbsp;sobra precisar que cuando el Tribunal afirma que \u00abtal &nbsp;planteamiento no fue expuesto, ni en los hechos de la demanda ni en &nbsp;las pretensiones, se &nbsp;refiere realmente a que el demandante adujo &nbsp;que la demora en la segunda intervenci\u00f3n quir\u00fargica le &nbsp;rest\u00f3 oportunidad a FELIZ ENRIQUE RIVERA PINEDA (q.e.p.d.) de &nbsp;mejorar su estado de salud\u00bb, &nbsp;figura &nbsp;relacionada como da\u00f1o indemnizable, ausente por completo desde &nbsp;el punto de vista argumentativo por el censor en su demanda de &nbsp;casaci\u00f3n. &nbsp;<\/p>\n<p>Por &nbsp;lo tanto, se inadmitir\u00e1 el cargo. &nbsp;<\/p>\n<p>En &nbsp;suma, como la demanda no re\u00fane los requisitos formales y &nbsp;t\u00e9cnicos que le son propios, habr\u00e1 de inadmitirse, en &nbsp;los t\u00e9rminos del numeral 1\u00ba del art\u00edculo 346 del &nbsp;C\u00f3digo General del Proceso. &nbsp;<\/p>\n<p>6. &nbsp;Resta decir, que esta Sala no encuentra razones suficientes para &nbsp;seleccionar la sentencia acusada, toda vez que a la actora se le &nbsp;garantizaron sus derechos superiores y se le resolvi\u00f3 su &nbsp;proceso en debida forma, sin que se advierta una afectaci\u00f3n &nbsp;del orden p\u00fablico o de la legalidad, o se requiera rectificar &nbsp;un punto en derecho para fines de unificaci\u00f3n de &nbsp;jurisprudencia, sin verse comprometido ning\u00fan derecho de orden &nbsp;constitucional, y la decisi\u00f3n acusada no afect\u00f3 norma &nbsp;sustancial alguna ni apartada del soporte probatorio debidamente &nbsp;recaudado. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En m\u00e9rito &nbsp;de lo expuesto, la Corte Suprema de Justicia, en Sala de Casaci\u00f3n &nbsp;Civil, INADMITE &nbsp;la demanda presentada para sustentar el recurso de casaci\u00f3n &nbsp;que Diana Mar\u00eda Ricardo Garc\u00e9s y Enrique Mario Rivera &nbsp;Ricardo, presentaron frente a la sentencia de 21 de julio de 2020, &nbsp;proferida por la Sala Civil \u2013 Familia del Tribunal Superior del &nbsp;Distrito Judicial de Cartagena, dentro del proceso adelantado contra &nbsp;Coomeva E.P.S. S.A., Litotricia S.A., Promotora Bocagrande S.A. &nbsp;Proboca S.A. y Pedro Alonso V\u00e9lez de Pombo, tr\u00e1mite en &nbsp;cual se vincul\u00f3 como llamados en garant\u00eda a La &nbsp;Previsora S.A. Compa\u00f1\u00eda de Seguros, Mapfre Seguros &nbsp;Generales de Colombia S.A. y Seguros Generales Suramericana S.A. &nbsp;<\/p>\n<p>Notif\u00edquese &nbsp;y, en oportunidad, devu\u00e9lvase el expediente al Tribunal de &nbsp;origen. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;y C\u00daMPLASE, &nbsp;<\/p>\n<p>HILDA GONZALEZ &nbsp;NEIRA &nbsp;<\/p>\n<p>Presidente de Sala &nbsp;<\/p>\n<p>MARTHA PATRICIA &nbsp;GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>(Comisi\u00f3n &nbsp;de servicios) &nbsp;<\/p>\n<p>LUIS ALONSO &nbsp;RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO AUGUSTO &nbsp;TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;SC &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;4407 de 2021. &nbsp;<\/p>\n<p>2\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;AC742-2020. &nbsp;<\/p>\n<p>3\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;AC 999 de 2022. &nbsp;<\/p>\n<p>4\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Cfr. &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Dev\u00eds Echand\u00eda Hernando. Teor\u00eda general de la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Prueba Judicial. Tomo I. Argentina. 1970. P\u00e1g. 287. &nbsp;<\/p>\n<p>5\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;AC 999 de 2022. &nbsp;<\/p>\n<p>6\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Reiterado en AC 901 de 2020. &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>AC1791-2022 (2017-00019-01) &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp; Magistrada &nbsp;ponente &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 13001-31-03-003-2017-00019-01 &nbsp; (Aprobado en &nbsp;sesi\u00f3n de veintiocho de abril de dos mil veintid\u00f3s) &nbsp; Bogot\u00e1 &nbsp;D.C., treinta y uno (31) de mayo de dos mil veintid\u00f3s (2022). &nbsp; Decide la Corte &nbsp;sobre &nbsp;la admisibilidad de la demanda presentada &nbsp;por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63105","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63105"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63105\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}