{"id":63259,"date":"2024-05-20T21:00:06","date_gmt":"2024-05-20T21:00:06","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc691-2022\/"},"modified":"2024-05-20T21:00:06","modified_gmt":"2024-05-20T21:00:06","slug":"atc691-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc691-2022\/","title":{"rendered":"ATC691 2022"},"content":{"rendered":"<p>ATC691-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>Magistrado &nbsp;Ponente &nbsp;<\/p>\n<p>ATC691-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 &nbsp;05000-22-13-000-2022-00041-01 &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., veintitr\u00e9s (23) de mayo de dos mil veintid\u00f3s &nbsp;(2022). &nbsp;<\/p>\n<p>1. &nbsp; Respecto de la impugnaci\u00f3n formulada frente a la sentencia &nbsp;proferida por la Sala &nbsp;Civil Familia del Tribunal Superior del Distrito Judicial de &nbsp;Antioquia el &nbsp;2 de marzo de 2022, &nbsp;dentro de la acci\u00f3n de tutela promovida por Juan &nbsp;Bernardo Garc\u00eda Cort\u00e9s contra &nbsp;los &nbsp;Juzgados &nbsp;Promiscuo Municipal de Venecia &nbsp;y &nbsp;Promiscuo &nbsp;del Circuito de Titirib\u00ed, &nbsp;se &nbsp;advierte que quien interpuso dicho recurso carece de mandato id\u00f3neo &nbsp;para representar al libelista, lo que inviabiliza su procedencia y le &nbsp;resta competencia funcional a esta Corporaci\u00f3n. &nbsp;<\/p>\n<p>2. &nbsp; Lo anterior, en raz\u00f3n a que la impugnaci\u00f3n fue &nbsp;impetrada por Mart\u00edn Fabi\u00e1n Torres Toro, \u00ababogado &nbsp;coadyuvante del accionante en el asunto de la referencia\u00bb, &nbsp;pero no alleg\u00f3 poder especial de quien dice result\u00f3 &nbsp;afectado con la decisi\u00f3n atacada, por lo que, se concluye, &nbsp;carece &nbsp;de postulaci\u00f3n para actuar al interior de la presente acci\u00f3n &nbsp;constitucional. &nbsp;<\/p>\n<p>3. &nbsp; En efecto, en trat\u00e1ndose de tutelas que no se promuevan &nbsp;directamente por el interesado, el criterio que sent\u00f3 esta &nbsp;Corte corresponde a que \u00abcuando &nbsp;la presunta violaci\u00f3n de los derechos fundamentales dimana de &nbsp;actuaciones cumplidas en un espec\u00edfico tr\u00e1mite &nbsp;judicial, &nbsp;la legitimidad para pretender su reparaci\u00f3n s\u00f3lo est\u00e1 &nbsp;radicada en quienes son parte en tal asunto y no, como aqu\u00ed &nbsp;acontece, en quien no tiene tal calidad [\u2026], &nbsp;\u2018pues si no se tiene apoderamiento y, por tanto, legitimaci\u00f3n &nbsp;para promover la solicitud de amparo, tampoco se puede tener para &nbsp;impugnar o recurrir las providencias que se dicten en el curso\u2019 &nbsp;de dichos procesos\u00bb &nbsp;(CSJ &nbsp;ATC, 16 abr. 2008, rad. 2007-00272-01). &nbsp;<\/p>\n<p>Igualmente, &nbsp;en relaci\u00f3n con el tema la Sala indic\u00f3 \u00ab(\u2026) &nbsp;por cuanto a la profesional del derecho que promovi\u00f3 la acci\u00f3n &nbsp;y quien &nbsp;seguidamente impugn\u00f3 lo resuelto en primera instancia, &nbsp;no se le confiri\u00f3 poder especial para representar a quien dice &nbsp;fungir como afectado, y tampoco se invoc\u00f3 que actuara como &nbsp;agente oficioso de \u00e9ste, no se satisface el presupuesto de la &nbsp;legitimaci\u00f3n en la causa que habilite su intervenci\u00f3n &nbsp;en sede de tutela\u00bb &nbsp;(CJS &nbsp;STC3125-2017, &nbsp;8 mar. 2017, rad. 2016-00801-01, citada en STC10249-2018, 10 ago. &nbsp;2018, rad. 00130-01). &nbsp;<\/p>\n<p>4. &nbsp;Aunado a lo anterior, tampoco &nbsp;podr\u00eda tenerse al profesional del derecho como habilitado para &nbsp;impugnar, bajo el supuesto de que el tribunal a-quo &nbsp;lo hubiera enterado de la iniciaci\u00f3n de la salvaguarda, ni &nbsp;tampoco por encontrarse vulnerados sus derechos a t\u00edtulo &nbsp;personal, ya que la actuaci\u00f3n desplegada en el asunto que se &nbsp;cuestiona, solo &nbsp;les compete a las partes all\u00ed involucradas. &nbsp;<\/p>\n<p>5. &nbsp; As\u00ed, en el presente caso resultaba perentorio que el abogado &nbsp;que impugn\u00f3 el fallo desestimatorio del auxilio demostrara en &nbsp;debida forma el derecho &nbsp;de postulaci\u00f3n &nbsp;para tal evento, omisi\u00f3n que impide dar tr\u00e1mite al &nbsp;recurso, m\u00e1s si se tiene en cuenta que \u00abcuando &nbsp;un Juez se enfrenta con una solicitud de impugnaci\u00f3n, preciso &nbsp;es que se examine la legitimaci\u00f3n, el inter\u00e9s y la &nbsp;oportunidad respectiva\u00bb &nbsp;(CSJ &nbsp;STC 14 dic. 2010, rad. 00008-02, citada en ATC1445-2019, 17 sep. &nbsp;2019, rad. 00424-01), y como en el caso analizado no se cumplen a &nbsp;cabalidad tales condiciones, la admisi\u00f3n del recurso deviene &nbsp;impr\u00f3spera. &nbsp;<\/p>\n<p>6. &nbsp;De conformidad con lo antes discurrido, se inadmitir\u00e1 la &nbsp;impugnaci\u00f3n planteada y en su lugar se ordenar\u00e1 remitir &nbsp;el expediente a la Corte Constitucional, conforme al inciso 2\u00ba &nbsp;del art\u00edculo 31 del Decreto 2591 de 1991. &nbsp;<\/p>\n<p>7. &nbsp; Se precisa que la presente decisi\u00f3n se adopta manteniendo el &nbsp;criterio que se\u00f1al\u00f3 esta Corporaci\u00f3n en los &nbsp;prove\u00eddos ATC2123-2018, 13 nov., rad. 2018-02435; ATC285-2019, &nbsp;28 feb., rad. 2019-00002; ATC1052-2019, 16 jul., rad. 2019-00232; &nbsp;ATC1185-2019, 1 ago., rad. 2019-00103; ATC1445-2019, 17 sep., rad. &nbsp;2019-00424; ATC1630-2019, 17 oct., rad. 2019-00274; ATC1047-2020, 4 &nbsp;nov., rad. 2020-00043 y ATC1132-2021, 5 ago., rad. 2021-00441, entre &nbsp;otros. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, el suscrito Magistrado de la Corte &nbsp;Suprema de Justicia, Sala de Casaci\u00f3n Civil, &nbsp;<\/p>\n<p>RESUELVE &nbsp;<\/p>\n<p>PRIMERO: &nbsp; Declarar inadmisible la impugnaci\u00f3n interpuesta contra la &nbsp;sentencia de fecha, naturaleza y procedencia inicialmente referidas. &nbsp;<\/p>\n<p>SEGUNDO: &nbsp; &nbsp;Previa &nbsp;comunicaci\u00f3n de lo resuelto a las partes y al a &nbsp;quo, se &nbsp;ordena la remisi\u00f3n del expediente a &nbsp;la Corte Constitucional para que se surta el tr\u00e1mite de su &nbsp;eventual revisi\u00f3n. &nbsp;<\/p>\n<p>Notif\u00edquese &nbsp;y c\u00famplase, &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>Magistrado &nbsp;<\/p>\n<p>2 &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>ATC691-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; LUIS &nbsp;ALONSO RICO PUERTA &nbsp; Magistrado &nbsp;Ponente &nbsp; ATC691-2022 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 &nbsp;05000-22-13-000-2022-00041-01 &nbsp; Bogot\u00e1, &nbsp;D.C., veintitr\u00e9s (23) de mayo de dos mil veintid\u00f3s &nbsp;(2022). &nbsp; 1. &nbsp; Respecto de la impugnaci\u00f3n formulada frente a la sentencia &nbsp;proferida por la Sala &nbsp;Civil Familia del Tribunal Superior del Distrito Judicial de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63259","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63259"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63259\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}