{"id":63273,"date":"2024-05-20T21:00:06","date_gmt":"2024-05-20T21:00:06","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc719-2022\/"},"modified":"2024-05-20T21:00:06","modified_gmt":"2024-05-20T21:00:06","slug":"atc719-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc719-2022\/","title":{"rendered":"ATC719 2022"},"content":{"rendered":"<p>ATC719-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Magistrada &nbsp;ponente &nbsp;<\/p>\n<p>&nbsp;ATC719-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2022-00531-00 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de veintis\u00e9is de mayo de dos mil veintid\u00f3s) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., veintis\u00e9is (26) de mayo de dos mil veintid\u00f3s &nbsp;(2022). &nbsp;<\/p>\n<p>Se &nbsp;procede a resolver lo conducente en cuanto al impedimento expresado &nbsp;por los Magistrados &nbsp;Hilda &nbsp;Gonz\u00e1lez Neira, Aroldo Wilson Quiroz Monsalvo, &nbsp;Luis &nbsp;Alonso Rico Puerta, Octavio Augusto Tejeiro Duque y &nbsp;Francisco Ternera Barrios, quienes &nbsp;expresaron impedimento para &nbsp;conocer en primera instancia de la tutela de &nbsp;la referencia propuesta &nbsp;por &nbsp;el se\u00f1or &nbsp;Jos\u00e9 &nbsp;Bernardo Vanegas Acevedo contra &nbsp;el Tribunal Superior de Antioquia Sala Civil Familia. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. El &nbsp;se\u00f1or Vanegas Acevedo, &nbsp;present\u00f3 la acci\u00f3n de tutela &nbsp;referida en la que invoc\u00f3 la protecci\u00f3n de los derechos &nbsp;fundamentales al debido proceso, acceso a la administraci\u00f3n de &nbsp;justicia e igualdad, presuntamente vulnerados por la Corporaci\u00f3n &nbsp;accionada. &nbsp;<\/p>\n<p>Manifest\u00f3 &nbsp;que, junto con otras personas presentaron demanda declarativa &nbsp;de simulaci\u00f3n absoluta del contrato de compraventa del &nbsp;inmueble identificado con el folio de matr\u00edcula inmobiliaria &nbsp;No. 020-5985, negocio contenido en la escritura p\u00fablica No. &nbsp;3098 de 24 de diciembre de 2013, protocolizada ante la Notar\u00eda &nbsp;Primera del C\u00edrculo Notarial de Rionegro, Antioquia, contra la &nbsp;Cooperativa Multiactiva y Solidaria -Cooperemos- en Liquidaci\u00f3n &nbsp;(vendedora) y la sociedad Bosques de la Macarena S.A.S. (compradora). &nbsp;<\/p>\n<p>El &nbsp;Juzgado Primero Civil del Circuito de Oralidad de Rionegro, en &nbsp;audiencia de 11 de septiembre de 2017, profiri\u00f3 sentencia en &nbsp;la que, entre otras cosas, declar\u00f3 la simulaci\u00f3n del &nbsp;contrato de compraventa, dispuso que el bien objeto del mismo &nbsp;regresara al haber patrimonial de la nombrada Cooperativa y desestim\u00f3 &nbsp;las excepciones planteadas por la demandada. &nbsp;<\/p>\n<p>Agreg\u00f3 &nbsp;que la sociedad demandada apel\u00f3 la decisi\u00f3n, y el &nbsp;Tribunal accionado el 10 de diciembre de 2020 la &nbsp;revoc\u00f3, incurriendo en defecto f\u00e1ctico, \u00abal &nbsp;concluir sin estar probado, que todos los &nbsp;asociados cooperativos estaban en capacidad de impugnar &nbsp;decisiones de la Asamblea General y del Consejo de Administraci\u00f3n &nbsp;de Cooperemos por estar completamente informados al no haber valorado &nbsp;en su integridad, las pruebas, testimonios, \u00f3 INTERROGATORIOS &nbsp;como el absuelto por la se\u00f1ora (\u2026) Si el Tribunal &nbsp;hubiera valorado debidamente todas las pruebas, la decisi\u00f3n &nbsp;del mismo hubiera sido contraria a la establecida por el mismo, y la &nbsp;m\u00e1cula del negocio jur\u00eddico hubiera deslumbrado, pero &nbsp;el Tribunal no las valor\u00f3\u00bb, &nbsp;adem\u00e1s que afirma, &nbsp;la sentencia \u00abno est\u00e1 motivada, solo se limit\u00f3 a &nbsp;se\u00f1alar algunos medios de prueba sin darles el valor jur\u00eddico &nbsp;debido (\u2026) &nbsp;<\/p>\n<p>Inconforme &nbsp;el 21 de junio de 2021, present\u00f3 recurso &nbsp;extraordinario de casaci\u00f3n, que fue inadmitido mediante Auto &nbsp;AC 3016 del 2021. &nbsp;<\/p>\n<p>Por &nbsp;lo narrado, solicit\u00f3, dejar si efectos la sentencia de 10 de &nbsp;diciembre de 2020, \u00abPor &nbsp;haber incurrido en &nbsp;v\u00edas de hecho por (a) defecto f\u00e1ctico al haber &nbsp;efectuado una valoraci\u00f3n probatoria arbitraria al dejar de &nbsp;valorar las pruebas aportadas y practicadas en debida forma en el &nbsp;proceso, las cuales eran determinantes para la resoluci\u00f3n del &nbsp;caso, (b) por falta de motivaci\u00f3n, por cuanto que (sic) en el &nbsp;Fallo demandado no se da cuenta de las razones f\u00e1cticas por &nbsp;las cuales se dejaron sin efecto todas las actuaciones y las pruebas &nbsp;que fueron el sustento del fallo de Primera Instancia, despu\u00e9s &nbsp;de haber sido admitido el Fallo inicialmente como perfecto, (d) por &nbsp;violaci\u00f3n directa de la Constituci\u00f3n Pol\u00edtica, &nbsp;al conculcar lo ordenado por ella en el art\u00edculo 29\u00bb. &nbsp;<\/p>\n<p>2. &nbsp;Correspondi\u00f3 conocer a esta Sala de Casaci\u00f3n, y la &nbsp;Magistrada &nbsp;Hilda Gonz\u00e1lez Neira, &nbsp;a quien se le asign\u00f3 el conocimiento, en auto de 25 de febrero &nbsp;de 2022 se declar\u00f3 impedida para asumirlo, en los t\u00e9rminos &nbsp;del art\u00edculo &nbsp;56-6 del C\u00f3digo de Procedimiento Penal, \u00ab(\u2026) &nbsp;toda &nbsp;vez que fui Ponente del prove\u00eddo AC3016-2021 (12 ag.), contra &nbsp;el que se dirige el presente resguardo\u00bb. &nbsp;<\/p>\n<p>Igualmente, &nbsp;y por encontrarse incursos en la misma causal, los Magistrados &nbsp;Aroldo &nbsp;Wilson Quiroz Monsalvo, &nbsp;Luis &nbsp;Alonso Rico Puerta, Octavio Augusto Tejeiro Duque y &nbsp;Francisco Ternera Barrios, manifestaron &nbsp;su impedimento para intervenir en la decisi\u00f3n de la acci\u00f3n &nbsp;de tutela de la referencia, \u00abcomoquiera &nbsp;que se extiende a lo resuelto por esta Corporaci\u00f3n en el &nbsp;prove\u00eddo AC3016-2021, 12 ago., rad. 2014- 00377-01, en el cual &nbsp;particip\u00e9; decisi\u00f3n en la que se resolvi\u00f3 &nbsp;<\/p>\n<p>sobre &nbsp;la admisibilidad de la demanda para sustentar el recurso &nbsp;extraordinario de casaci\u00f3n contra el fallo de segundo grado &nbsp;proferido por la Sala Civil Familia del Tribunal Superior del &nbsp;Distrito Judicial de Antioquia, en el curso del declarativo de &nbsp;simulaci\u00f3n\u00bb. &nbsp;<\/p>\n<p>3. &nbsp;En auto del 4 de abril anterior, como quiera que no concurre causal &nbsp;de impedimento en la suscrita magistrada, as\u00ed se dej\u00f3 &nbsp;consignado con la consecuente remisi\u00f3n del expediente por &nbsp;intermedio de la Secretar\u00eda a la Presidencia de la Sala, quien &nbsp;fij\u00f3 &nbsp;el 3 de mayo de 2022 &nbsp;como &nbsp;fecha para el sorteo de los Conjueces que &nbsp;han de participar en el estudio y decisi\u00f3n de esta acci\u00f3n &nbsp;de tutela, quedando &nbsp;conformada por los Doctores &nbsp;Edgar Javier Mun\u00e9var Arciniegas, Jorge Ernesto Oviedo Alb\u00e1n, &nbsp;Alba mar\u00eda Rueda V\u00e1squez, Miquelina Olivieri Mej\u00eda &nbsp;y Nicol\u00e1s Uribe Lozada, &nbsp;quienes &nbsp;aceptaron la designaci\u00f3n. &nbsp;<\/p>\n<p>El &nbsp;9 de mayo, la &nbsp;secretar\u00eda ingres\u00f3 nuevamente el expediente, informando &nbsp;la conformaci\u00f3n de la sala para lo pertinente. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;En &nbsp;el juzgador radica el deber de declararse impedido en presencia de &nbsp;una de las causales expresas, taxativas y restrictivas tipificadas &nbsp;por el ordenamiento jur\u00eddico para garantizar a los ciudadanos &nbsp;la plenitud del debido proceso, la rectitud, autonom\u00eda, &nbsp;objetividad e imparcialidad de la administraci\u00f3n de justicia &nbsp;(art\u00edculos 209, 228 y 230 Constituci\u00f3n Pol\u00edtica), &nbsp;previniendo y excluyendo toda hip\u00f3tesis subjetiva u objetiva &nbsp;de perturbaci\u00f3n en el proceso y en su decisi\u00f3n. &nbsp;<\/p>\n<p>Por &nbsp;esta inteligencia, la manifestaci\u00f3n de impedimento constituye &nbsp;un acto imperativo amparado en la probidad, buena fe y correcci\u00f3n &nbsp;del &nbsp;funcionario judicial quien solicita su separaci\u00f3n del &nbsp;conocimiento del asunto por concurrir en \u00e9l una de sus &nbsp;causales, cuya omisi\u00f3n faculta a los sujetos procesales para &nbsp;recusarlo. &nbsp;<\/p>\n<p>2. &nbsp;En este evento se propone como objeto de estudio la causal de &nbsp;impedimento consagrada en el numeral 6\u00ba del art\u00edculo 56 &nbsp;del Estatuto Procesal Penal y en el art\u00edculo 39 del Decreto &nbsp;2591 de 1991. &nbsp;<\/p>\n<p>De &nbsp;manera puntual, los Magistrados citados se\u00f1alaron que en ellos &nbsp;concurre causal de impedimento por haber participado en la Sala de &nbsp;Decisi\u00f3n donde se discuti\u00f3 y profiri\u00f3 la &nbsp;providencia &nbsp;AC3016-2021, &nbsp;12 ag., rad. 2014-00377-01, &nbsp;en &nbsp;la que se declar\u00f3 inadmisible la demanda de casaci\u00f3n &nbsp;presentada por el aqu\u00ed libelista y otro, contra la sentencia &nbsp;proferida por la Sala Civil &nbsp;Familia del Tribunal Superior del &nbsp;Distrito Judicial de Antioquia el 10 de diciembre de 2020, en el &nbsp;curso del proceso declarativo de simulaci\u00f3n absoluta que &nbsp; inici\u00f3 contra &nbsp;la Cooperativa Multiactiva y Solidaria -Cooperemos- en Liquidaci\u00f3n &nbsp;y la sociedad Bosques de la Macarena S.A.S., lo &nbsp;que sin duda pone en evidencia, que lo resuelto se encuentra &nbsp;involucrado dentro de la controversia constitucional planteada, como &nbsp;consta en el expediente. &nbsp;<\/p>\n<p>Precept\u00faa &nbsp;el numeral 6\u00ba del art\u00edculo 56 del C\u00f3digo de &nbsp;Procedimiento Penal, aplicable en el tr\u00e1mite de las acciones &nbsp;de tutela seg\u00fan el art\u00edculo 39 del Decreto 2591 de &nbsp;1991: &nbsp;<\/p>\n<p>\u00abArt\u00edculo &nbsp;56. Causales de impedimento. Son causales de impedimento: &nbsp;<\/p>\n<p>(\u2026) &nbsp;6. Que el funcionario judicial haya dictado la providencia de cuya &nbsp;revisi\u00f3n se trata, o hubiere participado dentro del proceso &nbsp;(\u2026)\u00bb. &nbsp;<\/p>\n<p>3. &nbsp;En consecuencia, se declara que los mencionados funcionarios quedan &nbsp;separados del conocimiento en el asunto en estudio. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, Sala de &nbsp;Conjueces de la Sala de Casaci\u00f3n Civil, &nbsp;<\/p>\n<p>RESUELVE: &nbsp;<\/p>\n<p>ACEPTAR &nbsp;los &nbsp;impedimentos manifestados por los Magistrados &nbsp;Hilda &nbsp;Gonz\u00e1lez Neira, Aroldo Wilson Quiroz Monsalvo, &nbsp;Luis &nbsp;Alonso Rico Puerta, Octavio Augusto Tejeiro Duque y &nbsp;Francisco Ternera Barrios, quienes &nbsp;expresaron impedimento para &nbsp;conocer en primera instancia de la tutela de &nbsp;la referencia propuesta &nbsp;por &nbsp;el se\u00f1or &nbsp;Jos\u00e9 &nbsp;Bernardo Vanegas Acevedo contra &nbsp;el Tribunal Superior de Antioquia Sala Civil Familia. &nbsp;<\/p>\n<p>Por &nbsp;Secretar\u00eda ingr\u00e9sense las diligencias a la aqu\u00ed &nbsp;ponente, para continuar con la actuaci\u00f3n correspondiente, &nbsp;efectuando la compensaci\u00f3n respectiva en el reparto. &nbsp;<\/p>\n<p>Notif\u00edquese &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>Magistrada &nbsp;Ponente &nbsp;<\/p>\n<p>EDGAR &nbsp;JAVIER MUNEVAR ARCINIEGAS &nbsp;<\/p>\n<p>Conjuez &nbsp;<\/p>\n<p>JORGE &nbsp;ERNESTO OVIEDO ALBAN &nbsp;<\/p>\n<p>Conjuez &nbsp;<\/p>\n<p>ALBA &nbsp;MARIA RUEDA VASQUEZ &nbsp;<\/p>\n<p>Conjuez &nbsp;<\/p>\n<p>MIQUELINA &nbsp;OLIVIERI MEJIA &nbsp;<\/p>\n<p>Conjuez &nbsp;<\/p>\n<p>NICOLAS &nbsp;URIBE LOZADA &nbsp;<\/p>\n<p>Conjuez &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>ATC719-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp; Magistrada &nbsp;ponente &nbsp; &nbsp;ATC719-2022 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 11001-02-03-000-2022-00531-00 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de veintis\u00e9is de mayo de dos mil veintid\u00f3s) &nbsp; Bogot\u00e1, &nbsp;D.C., veintis\u00e9is (26) de mayo de dos mil veintid\u00f3s &nbsp;(2022). &nbsp; Se &nbsp;procede a resolver lo conducente en cuanto al impedimento expresado &nbsp;por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63273","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63273"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63273\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}