{"id":63276,"date":"2024-05-20T21:00:06","date_gmt":"2024-05-20T21:00:06","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc722-2022\/"},"modified":"2024-05-20T21:00:06","modified_gmt":"2024-05-20T21:00:06","slug":"atc722-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/atc722-2022\/","title":{"rendered":"ATC722 2022"},"content":{"rendered":"<p>ATC722-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Magistrada &nbsp;ponente &nbsp;<\/p>\n<p>ATC722-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 50001-22-14-000-2022-00087-01 &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., veintisiete (27) de mayo de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>1.- &nbsp;Corresponder\u00eda resolver la impugnaci\u00f3n formulada contra &nbsp;el fallo proferido el 10 de mayo de 2022 por la Sala Civil Familia &nbsp;Laboral del Tribunal Superior del Distrito Judicial de Villavicencio, &nbsp;en la tutela que Nancy Zambrano Camayo le instaur\u00f3 al Juzgado &nbsp;Primero de Familia de esa ciudad, si no fuera porque se omiti\u00f3 &nbsp;notificar en debida forma a la totalidad de los intervinientes en la &nbsp;queja constitucional, concretamente, al Instituto Nacional de &nbsp;Medicina Legal y Ciencias Forenses \u2013 Grupo Nacional de Gen\u00e9tica &nbsp;\u2013 Contrato I.C.B.F. &nbsp;<\/p>\n<p>2.- &nbsp;El art\u00edculo 16 del Decreto 2591 de 1991 prev\u00e9 que \u201clas &nbsp;providencias que se dicten se notificar\u00e1n a las partes o &nbsp;intervinientes, por el medio que el juez considere m\u00e1s &nbsp;expedito y eficaz\u201d, &nbsp;pauta que ratifica el art\u00edculo 5 del Decreto 306 de 1992, al &nbsp;se\u00f1alar que: &nbsp;<\/p>\n<p>\u00abDe &nbsp;conformidad con el art\u00edculo 16 del Decreto 2591 de 1991 todas &nbsp;las providencias que se dicten en el tr\u00e1mite de una acci\u00f3n &nbsp;de tutela se deber\u00e1n notificar a las partes o a los &nbsp;intervinientes. Para este efecto son partes la persona que ejerce la &nbsp;acci\u00f3n de tutela y el particular, la entidad o autoridad &nbsp;p\u00fablica contra la cual se dirige la acci\u00f3n de tutela de &nbsp;conformidad con el art\u00edculo 13 del Decreto 2591 de 1991. &nbsp;<\/p>\n<p>El &nbsp;juez velar\u00e1 porque de acuerdo con las circunstancias, el medio &nbsp;y la oportunidad de la notificaci\u00f3n aseguren la eficacia de la &nbsp;misma y la posibilidad de ejercer el derecho de defensa\u00bb &nbsp;(Se destaca). &nbsp;<\/p>\n<p>3.- &nbsp;En el sub &nbsp;lite, &nbsp;aunque el a &nbsp;quo &nbsp;dispuso la convocatoria de los intervinientes en la actuaci\u00f3n &nbsp;fustigada, ninguna de las piezas que integran el expediente digital &nbsp;remitido a esta Corporaci\u00f3n revelan la efectividad de dichas &nbsp;comunicaciones, ni dan cuenta de la suficiencia de tal gesti\u00f3n &nbsp;para garantizar la participaci\u00f3n del Instituto Nacional de &nbsp;Medicina Legal y Ciencias Forenses \u2013 Grupo Nacional de Gen\u00e9tica &nbsp;\u2013 Contrato I.C.B.F, omisi\u00f3n que cobra especial &nbsp;relevancia, teniendo en cuenta que, en el plenario obran sus &nbsp;\u00abdirecciones &nbsp;de notificaci\u00f3n personal\u00bb, &nbsp;donde bien pudo ser noticiado de la existencia de esta acci\u00f3n &nbsp;superlativa. &nbsp;<\/p>\n<p>As\u00ed &nbsp;las cosas, dado el particular inter\u00e9s que eventualmente le &nbsp;asiste, se impone invalidar lo rituado, para que la Sala de origen &nbsp;restablezca sus prerrogativas y dicte una nueva decisi\u00f3n con &nbsp;su participaci\u00f3n. Lo anterior, si se tiene en cuenta que, &nbsp;<\/p>\n<p>\u201cNo &nbsp;obstante ser la tutela un mecanismo preferente y sumario, no es ajena &nbsp;\u2013como no lo es ninguna acci\u00f3n judicial- a las reglas del &nbsp;debido proceso, por lo que su conocimiento debe corresponder al juez &nbsp;que se encuentre legalmente facultado para resolverla, &nbsp;dado que, &nbsp;como lo ha explicado la jurisprudencia, en su tr\u00e1mite \u2018se &nbsp;deben satisfacer ciertos presupuestos b\u00e1sicos del juicio como &nbsp;son, entre otros, la capacidad de las partes, la competencia y la &nbsp;debida integraci\u00f3n de la causa pasiva\u2019 &nbsp;(Corte &nbsp;Constitucional. Auto 257 de 1996)\u201d &nbsp;(ATC4548-2018 reiterada en ATC1435-2021). &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, &nbsp;<\/p>\n<p>RESUELVE: &nbsp;<\/p>\n<p>PRIMERO: &nbsp;Declarar la nulidad de lo actuado en el auxilio de la referencia, a &nbsp;fin de vincular al Instituto &nbsp;Nacional de Medicina Legal y Ciencias Forenses \u2013 Grupo Nacional &nbsp;de Gen\u00e9tica \u2013 Contrato I.C.B.F. &nbsp;<\/p>\n<p>Por &nbsp;tanto, el tr\u00e1mite deber\u00e1 renovarse con ese exclusivo &nbsp;prop\u00f3sito, permaneciendo inc\u00f3lume la validez de las &nbsp;pruebas practicadas, de conformidad con lo previsto en el inciso &nbsp;segundo del art\u00edculo 138 del C\u00f3digo General del &nbsp;Proceso. &nbsp;<\/p>\n<p>SEGUNDO: &nbsp;Devolver el expediente a la Sala Civil Familia Laboral del Tribunal &nbsp;Superior de Villavicencio. para que adopte las medidas que estime &nbsp;necesarias a fin de renovar el procedimiento. &nbsp;<\/p>\n<p>TERCERO: &nbsp;Ent\u00e9rese de lo resuelto a los intervinientes y al a &nbsp;quo &nbsp;por el medio m\u00e1s expedito. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Magistrada &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>ATC722-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp; Magistrada &nbsp;ponente &nbsp; ATC722-2022 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 50001-22-14-000-2022-00087-01 &nbsp; Bogot\u00e1, &nbsp;D.C., veintisiete (27) de mayo de dos mil veintid\u00f3s (2022). &nbsp; 1.- &nbsp;Corresponder\u00eda resolver la impugnaci\u00f3n formulada contra &nbsp;el fallo proferido el 10 de mayo de 2022 por la Sala Civil Familia &nbsp;Laboral del Tribunal Superior [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63276","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63276"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63276\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}