{"id":63307,"date":"2024-05-20T21:00:08","date_gmt":"2024-05-20T21:00:08","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc5348-2022\/"},"modified":"2024-05-20T21:00:08","modified_gmt":"2024-05-20T21:00:08","slug":"stc5348-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc5348-2022\/","title":{"rendered":"STC5348 2022"},"content":{"rendered":"<p>STC5348-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>Magistrado &nbsp;ponente &nbsp;<\/p>\n<p>STC5348-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 11001-02-30-000-2022-00640-00 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de cuatro de mayo de dos mil veintid\u00f3s) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., cuatro (4) de mayo de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>Se &nbsp;resuelve la salvaguarda instaurada por Mar\u00eda Roc\u00edo &nbsp;Castillo Ram\u00edrez y Jos\u00e9 Augusto T\u00e1mara Garrido, &nbsp;en calidad de agentes oficiosos de Jos\u00e9 \u00c1ngel Ram\u00edrez, &nbsp;contra la Corte Constitucional, Fiscal\u00eda General de la Naci\u00f3n, &nbsp;Procuradur\u00eda General de la Naci\u00f3n, Presidencia de la &nbsp;Rep\u00fablica, Tribunal Superior del Distrito Judicial de &nbsp;Bucaramanga y el INPEC \u2013 C\u00e1rcel Modelo de Bucaramanga, &nbsp;extensiva al Juzgado S\u00e9ptimo Civil del Circuito de &nbsp;Bucaramanga, partes, autoridades y dem\u00e1s intervinientes en el &nbsp;ruego n\u00b0 68001-31-03-007-2021-00120-00\/01. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>1. Los &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;promotores solicitaron \u00abi) &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;se [les] entregue el fallo sobre el caso [antes citado] que entr\u00f3 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;para revisi\u00f3n en la Corte Constitucional \u2013 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Jurisprudencia de Corte Constitucional; y, ii) se exhorte a la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;fiscal\u00eda a originar las \u00f3rdenes de captura en contra &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;de los intervinientes dentro del fraude procesal, lesiones &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;personales y obstrucci\u00f3n a la justicia \u2013 pues el fraude &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;completa hoy 8 meses\u00bb. &nbsp;<\/p>\n<p>En &nbsp;sustento, adujeron que se hallan a la espera de una revisi\u00f3n &nbsp;de la Corte Constitucional sobre un caso que busca amparar los &nbsp;derechos de Jos\u00e9 \u00c1ngel Ram\u00edrez Ram\u00edrez y &nbsp;que llevan 8 meses sin obtener respuesta, ni la intervenci\u00f3n &nbsp;de la Procuradur\u00eda o la Fiscal\u00eda. Contaron que &nbsp;presentaron denuncia por obstrucci\u00f3n y fraude procesal \u00abal &nbsp;igual que una posible falsedad en documento p\u00fablico\u00bb. &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>2. La &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Corte Constitucional inform\u00f3 que el asunto se radic\u00f3 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;en esas dependencias bajo el n\u00famero T8366739, en el que &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;mediante auto de 15 de octubre de 2021 fue excluido de revisi\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;y dispuso la devoluci\u00f3n al juzgado de origen, lo cual se hizo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el 7 de marzo pasado. Alert\u00f3 que frente a dicha determinaci\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;\u00ablos &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;accionantes no presentaron escrito de solicitud ciudadana de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;revisi\u00f3n\u00bb, y &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;en ese escenario solicit\u00f3 declarar improcedente el ruego. La &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Sala Civil Familia del Tribunal Superior de Bucaramanga se opuso a &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;las pretensiones y ados\u00f3 copia del prove\u00eddo all\u00ed &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;emitido con las constancias de notificaci\u00f3n. La Procuradur\u00eda &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Regional Santander y el Inpec esgrimieron la falta de legitimaci\u00f3n &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;en la causa por pasiva. Para el momento en que se elabor\u00f3 el &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;proyecto no se hab\u00edan recibido m\u00e1s respuestas. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>El &nbsp;amparo ser\u00e1 denegado por las razones que pasan a explicarse. &nbsp;<\/p>\n<p>En &nbsp;ese orden, no puede admitirse que a trav\u00e9s de este camino &nbsp;supralegal se irrogue la soluci\u00f3n de cuestiones que &nbsp;correspond\u00eda dirimir al juez natural y que no se adelant\u00f3 &nbsp;porque los querellantes no acudieron en la oportunidad establecida en &nbsp;la ley al \u00f3rgano limite en lo constitucional a pedir la &nbsp;revisi\u00f3n &nbsp;que &nbsp;por esta senda se intenta. &nbsp;<\/p>\n<p>2.- &nbsp;Ahora, en lo atinente a que la Fiscal\u00eda emita \u00f3rdenes &nbsp;de captura en el caso iniciado por la denuncia que los interesados &nbsp;interpusieron, el amparo no es viable por tampoco satisfacer el &nbsp;requisito de subsidiariedad, en la medida en que en el expediente no &nbsp;obra prueba de que eso mismo haya sido solicitado directamente al &nbsp;ente acusador. Importa &nbsp;recordar que los censores tambi\u00e9n &nbsp;cuentan con la posibilidad de acudir &nbsp;ante las instancias con atribuci\u00f3n legal para indagar si &nbsp;los funcionarios o &nbsp;alguno de sus colaboradores incurrieron en punibles o contravinieron &nbsp;los deberes propios de sus respectivos cargos, &nbsp;dado que la acci\u00f3n de tutela no fue consagrada para impulsar &nbsp;actuaciones de ese tipo. De &nbsp;esta manera, &nbsp;<\/p>\n<p>(\u2026) &nbsp;si el aqu\u00ed convocante estima que alguno de los intervinientes &nbsp;incurri\u00f3 en conductas disciplinarias y penales que deben &nbsp;averiguarse, y cuenta con los elementos y argumentos necesarios para &nbsp;sostener su denuncia, est\u00e1 facultado para radicar en forma &nbsp;directa la noticia criminal o sancionatoria respectiva, haci\u00e9ndose &nbsp;por supuesto responsable de su gesti\u00f3n y consecuencias. Sobre &nbsp;el punto ha dicho la Sala: \u2018En relaci\u00f3n a la petici\u00f3n &nbsp;de compulsar copias a la Fiscal\u00eda General de la Naci\u00f3n, &nbsp;el peticionario queda en plena libertad de formular la &nbsp;correspondiente denuncia penal toda vez que no se cuentan con los &nbsp;elementos de juicio para determinar la existencia de un delito. (CSJ &nbsp;STC011-2018, reiterada en STC4324-2018 y STC2152-2020, STC3965-2021 &nbsp;entre otras). &nbsp;<\/p>\n<p>Con &nbsp;base en lo expuesto, se negar\u00e1 la s\u00faplica de los &nbsp;promotores. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica y por autoridad de la Constituci\u00f3n, resuelve: &nbsp;NEGAR &nbsp;por improcedente la &nbsp;tutela instada. &nbsp;<\/p>\n<p>Inf\u00f3rmese &nbsp;a los participantes por el medio m\u00e1s expeditoy rem\u00edtase &nbsp;el paginario a la Corte Constitucional para su eventual revisi\u00f3n, &nbsp;de no impugnarse esta resoluci\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>Ausencia &nbsp;justificada &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>Ausencia &nbsp;justificada &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC5348-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp; Magistrado &nbsp;ponente &nbsp; STC5348-2022 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 11001-02-30-000-2022-00640-00 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de cuatro de mayo de dos mil veintid\u00f3s) &nbsp; Bogot\u00e1, &nbsp;D.C., cuatro (4) de mayo de dos mil veintid\u00f3s (2022). &nbsp; Se &nbsp;resuelve la salvaguarda instaurada por Mar\u00eda Roc\u00edo &nbsp;Castillo Ram\u00edrez y Jos\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63307","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63307"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63307\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}