{"id":63482,"date":"2024-05-20T21:00:12","date_gmt":"2024-05-20T21:00:12","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc5736-2022\/"},"modified":"2024-05-20T21:00:12","modified_gmt":"2024-05-20T21:00:12","slug":"stc5736-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc5736-2022\/","title":{"rendered":"STC5736 2022"},"content":{"rendered":"<p>STC5736-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado &nbsp;Ponente &nbsp;<\/p>\n<p>STC5736-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n.\u00b0 54001-22-13-000-2022-00094-01 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de once de mayo de dos mil veintid\u00f3s). &nbsp;<\/p>\n<p>Bogot\u00e1 &nbsp;D.C., once (11) de mayo de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>La &nbsp;Corte decide la impugnaci\u00f3n interpuesta frente a la sentencia &nbsp;proferida por la &nbsp;Sala Civil-Familia del Tribunal Superior del Distrito Judicial de &nbsp;C\u00facuta el &nbsp;31 de marzo de 2022, &nbsp;con la cual se neg\u00f3 por improcedente el amparo reclamado por &nbsp;Bleyddy &nbsp;Karina Quintero contra &nbsp;el Consejo Seccional de la Judicatura de Norte de Santander y los &nbsp;Juzgados Primero Civil y Segundo Penal del Circuito de Oca\u00f1a. &nbsp;<\/p>\n<p>I. &nbsp;ANTECEDENTES &nbsp;<\/p>\n<p>1. La &nbsp;accionante, &nbsp;actuando por medio de apoderado judicial, reclam\u00f3 la &nbsp;protecci\u00f3n de sus derechos fundamentales al &nbsp;m\u00e9rito, empleo p\u00fablico, trabajo, dignidad humana y a la &nbsp;carrera administrativa, presuntamente &nbsp;vulnerados por los &nbsp;accionados en &nbsp;el cumplimiento del Acuerdo CSJNS2022-160 del 2 de marzo de 2022 \u201cPor &nbsp;medio del cual se modifica el Acuerdo CSJNS2021-563 de diciembre 15 &nbsp;de 2021, \u201cPor medio del cual se formula ante el Juez Primero &nbsp;Civil del Circuito de Oca\u00f1a, Lista de elegibles para el cargo &nbsp;de vacante de secretario Nominado c\u00f3digo 261826\u201d, y se &nbsp;integra Lista de elegibles para el cargo de vacante de Secretario &nbsp;Nominado c\u00f3digo 261826, del Juzgado Primero Civil del Circuito &nbsp;de Oca\u00f1a\u201d1. &nbsp;Y de la Resoluci\u00f3n No. 003 del 03 de marzo de 2022 del &nbsp;Despacho Primero Civil del Circuito de Oca\u00f1a, \u201cpor &nbsp;medio del cual se deja sin efecto las Resoluciones Nos 001 y 002 del &nbsp;2022\u201d2. &nbsp;<\/p>\n<p>2. &nbsp;Indic\u00f3 que, en el mes de diciembre de 2021, ante el Consejo &nbsp;Seccional de Oca\u00f1a se postul\u00f3 a los cargos de &nbsp;Secretario Nominado en los Juzgados Primero Civil del Circuito y &nbsp;Segundo Penal del Circuito de esa localidad. &nbsp;<\/p>\n<p>2.1. &nbsp;Narr\u00f3 que una vez se levant\u00f3 la vacancia judicial, y al &nbsp;no recibir informaci\u00f3n acerca de sus postulaciones, present\u00f3 &nbsp;derecho de petici\u00f3n el 24 de enero de 2022 ante el Consejo, &nbsp;solicitando la remisi\u00f3n de la lista de aspirantes de los &nbsp;cargos a los que se postul\u00f3. Ese mismo d\u00eda, en &nbsp;comunicaci\u00f3n CSJNS-DM-MIBT-0089 la entidad accionada dio &nbsp;respuesta, en la cual se pod\u00eda evidenciar que era la \u00fanica &nbsp;que figuraba en las listas de elegibles de secretario nominado tanto &nbsp;en el Juzgado Primero Civil3 &nbsp;como en el Segundo Penal4 &nbsp;del Circuito de Oca\u00f1a. &nbsp;<\/p>\n<p>2.2. &nbsp;El &nbsp;25 de enero de 2022, mediante resoluci\u00f3n 002 se realiz\u00f3 &nbsp;el nombramiento de la accionante como Secretario Nominado en el &nbsp;Despacho Segundo Penal. Y por resoluci\u00f3n No. 001 se dispuso su &nbsp;nombramiento al mismo cargo en el Juzgado Primero Civil. &nbsp;<\/p>\n<p>2.3. &nbsp;Destac\u00f3 que el 03 de febrero de 2022, procedi\u00f3 a &nbsp;aceptar el cargo en el Juzgado Primero Civil del Circuito. En &nbsp;consecuencia, rehus\u00f3 del cargo en el Despacho Segundo Penal. &nbsp;<\/p>\n<p>2.4. &nbsp;Relat\u00f3 que, por situaciones de \u00edndole personal, el 22 &nbsp;de febrero de 2022 solicit\u00f3 ante el Juzgado civil la pr\u00f3rroga &nbsp;de su posesi\u00f3n, la cual, fue aceptada por el despacho -con &nbsp;auto del 24 de febrero del a\u00f1o en curso-. Sin embargo, el 3 de &nbsp;marzo siguiente, antes de que se cumpliera el t\u00e9rmino otorgado &nbsp;como pr\u00f3rroga, el Consejo Superior de la Judicatura de Norte &nbsp;de Santander emiti\u00f3 el Acuerdo CSJNS2022-1605 &nbsp;por medio del cual modificaba el CSJNS2021-563 y se integr\u00f3 a &nbsp;la lista de elegibles para el cargo de Secretario Nominado a Juan &nbsp;Diego Reyes Ortiz, quien figuraba con un puntaje superior al de &nbsp;ella6. &nbsp;<\/p>\n<p>2.5. &nbsp;La entidad argument\u00f3 que el cambio se deb\u00eda a una &nbsp;omisi\u00f3n involuntaria de la postulaci\u00f3n del se\u00f1or &nbsp;Reyes, la cual hab\u00eda quedado en la bandeja de entrada del &nbsp;correo electr\u00f3nico de la secretaria de esa entidad. &nbsp;<\/p>\n<p>2.6. &nbsp;En cumplimiento de dicho acuerdo, el Juzgado Primero Civil del &nbsp;Circuito de Oca\u00f1a -con resoluci\u00f3n 003 del 03 de marzo &nbsp;de 2022- resolvi\u00f3: \u201cPRIMERO: &nbsp;DEJAR sin efectos las Resoluciones Nos 001 del 25 de enero y 002 del &nbsp;24 de febrero de 2022\u201d &nbsp;por medio de las cuales se daba el nombramiento de la accionante y se &nbsp;otorgaba la pr\u00f3rroga de su posesi\u00f3n al mismo. &nbsp;<\/p>\n<p>3. &nbsp;Por lo anterior, la accionante solicit\u00f3 que \u00ab(\u2026) &nbsp;se proceda ordenar REVOCAR el ACUERDO CSJNS2022-160 de fecha 02 de &nbsp;marzo de 2022, mediante el cual intempestiva y abruptamente se &nbsp;modifica la lista de elegibles para el cargo de SECRETARIO JUZGADO DE &nbsp;CIRCUITO NOMINADO (\u2026)\u00bb. &nbsp;Adicionalmente, se revoque la resoluci\u00f3n No. 0037. &nbsp;<\/p>\n<p>II. &nbsp;LAS RESPUESTAS RECIBIDAS &nbsp;<\/p>\n<p>1. &nbsp;El Juzgado Primero Civil del Circuito de Oca\u00f1a, &nbsp;despu\u00e9s de relatar las actuaciones surtidas en el asunto &nbsp;debatido, inform\u00f3 que &nbsp;hasta este momento no se ha realizado el nombramiento de Juan Diego &nbsp;Reyes Ort\u00ecz, por cuanto la accionante interpuso recurso de &nbsp;reposici\u00f3n y, en subsidio apelaci\u00f3n, contra la &nbsp;resoluci\u00f3n que dej\u00f3 sin efectos su nombramiento8. &nbsp;<\/p>\n<p>2. &nbsp;El Juzgado Segundo Promiscuo de Familia de esa municipalidad censur\u00f3 &nbsp;la manifestaci\u00f3n temeraria hecha por la accionante, \u00ab\u2026en &nbsp;el sentido de que juzgado \u201cno ha provisto el cargo de &nbsp;Secretario Nominado &nbsp;c\u00f3digo &nbsp;261826, &nbsp;pero &nbsp;tampoco &nbsp;ha &nbsp; informado &nbsp;que &nbsp;el &nbsp;mismo &nbsp;aparece &nbsp;vacante, &nbsp;no apareciendo &nbsp;como &nbsp; opci\u00f3n &nbsp;de &nbsp;sede &nbsp;durante &nbsp;los &nbsp;meses &nbsp;de &nbsp;diciembre &nbsp;2021, &nbsp; enero, &nbsp;febrero &nbsp;y marzo &nbsp;de &nbsp;2022, &nbsp;sin &nbsp;haber &nbsp;sido &nbsp;este &nbsp;provisto &nbsp; en &nbsp;propiedad, &nbsp;quit\u00e1ndonos &nbsp;la &nbsp;posibilidad &nbsp;a muchas &nbsp;personas que por m\u00e9ritos ganamos el concurso de poder optar &nbsp;por dicho cargo\u201d\u00bb. &nbsp;<\/p>\n<p>3. &nbsp;El Consejo Seccional de la Judicatura se opuso a la prosperidad de la &nbsp;acci\u00f3n constitucional, \u00abtoda &nbsp;vez que no ha vulnerado derecho fundamental &nbsp;alguno de &nbsp;la &nbsp; accionante, &nbsp;teniendo &nbsp;en &nbsp;cuenta, a &nbsp;la &nbsp;fecha &nbsp;se &nbsp;encuentra &nbsp;vigente hasta por cuatro (4) a\u00f1os el Registro Seccional de &nbsp;elegibles para el cargo que aspir\u00f3 que la misma, facultad que &nbsp;le permite continuar optando a las vacantes que bien le &nbsp;parezcan, &nbsp;que al &nbsp;momento &nbsp;de &nbsp;concursar, &nbsp;estuvo &nbsp;sometida &nbsp;a &nbsp;las &nbsp;reglas &nbsp;de &nbsp;la convocatoria misma, la cual es p\u00fablica y reglada, que a la &nbsp;fecha contin\u00faa ocupando el segundo lujar en la Lista de &nbsp;Elegibles proferida mediante Acuerdo CSJNS2022-160 del &nbsp;2 &nbsp;de &nbsp;marzo &nbsp; de &nbsp;2022, y &nbsp;finalmente, teniendo &nbsp;en &nbsp;cuenta, &nbsp;que &nbsp;el &nbsp;apoderado &nbsp; de &nbsp;la accionante, &nbsp;ya &nbsp;ha &nbsp;instaurado &nbsp;por &nbsp;la &nbsp;v\u00eda &nbsp; contenciosa &nbsp;administrativa diligencias &nbsp;por &nbsp;las cuales &nbsp;solicita, &nbsp; bajo &nbsp;argumentos &nbsp;similares &nbsp;a &nbsp;la &nbsp;presente &nbsp;actuaci\u00f3n &nbsp; constitucional, &nbsp;la revocatoria del acuerdo precitado\u00bb9. &nbsp;<\/p>\n<p>4. &nbsp;El Juzgado Segundo Penal del Circuito de Oca\u00f1a, manifest\u00f3 &nbsp;que ese despacho no tiene injerencia en la presunta vulneraci\u00f3n &nbsp;de los derechos fundamentales aludidos. &nbsp;<\/p>\n<p>5. &nbsp;La Universidad Aut\u00f3noma del Caribe, afirm\u00f3 que no le &nbsp;consta ninguno de los hechos aludidos en el escrito inicial. Sin &nbsp;embargo, frente a uno de ellos, manifest\u00f3 que \u201cUNDECIMO &nbsp;(\u2026) es cierto que la se\u00f1ora BLEDDY QUINTERO NI\u00d1O, &nbsp;se encuentra vinculada actualmente a la UNIVERSIDAD AUTONOMA DEL &nbsp;CARIBE, mediante contrato de trabajo vigente\u201d10. &nbsp;<\/p>\n<p>6. &nbsp;Los dem\u00e1s vinculados guardaron silencio. &nbsp;<\/p>\n<p>III. &nbsp;LA SENTENCIA IMPUGNADA &nbsp;<\/p>\n<p>El a &nbsp;quo &nbsp;constitucional resolvi\u00f3 negar por improcedente la &nbsp;salvaguarda. Para ello, consider\u00f3 que \u00ab(\u2026) &nbsp;muy a pesar del &nbsp;querer de la accionante, tampoco hay lugar a despachar favorablemente &nbsp;las pretensiones elevadas en contra del Juzgado Primero Civil del &nbsp;Circuito de Oca\u00f1a y el Consejo Seccional de la Judicatura de &nbsp;Norte de Santander, por no encontrarse configurado el presupuesto de &nbsp;subsidiariedad, como se pasa a exponer: En lo que ata\u00f1e al &nbsp;Juzgado Primero Civil del Circuito de Oca\u00f1a, se otea que su &nbsp;titular ha sido cumplidora del procedimiento establecido para el uso &nbsp;de la lista de elegibles remitida por el Consejo Seccional de la &nbsp;Judicatura de Norte de Santander en la forma y t\u00e9rminos que lo &nbsp;contemplan las normas reguladoras de la materia, correspondi\u00e9ndole &nbsp;ahora desatar los medios impugnatorios ordinarios propuestos por la &nbsp;interesada, se\u00f1ora Bleyddy Karina, en contra de la decisi\u00f3n &nbsp;de revocatoria de su nombramiento, para determinar si, a partir de &nbsp;las sustentaciones de la recurrente y de la revisi\u00f3n de sus &nbsp;decisiones como nominadora, hay lugar a dejar sin efecto la &nbsp;resoluci\u00f3n atacada\u00bb11. &nbsp;<\/p>\n<p>IV. &nbsp;LA IMPUGNACI\u00d3N &nbsp;<\/p>\n<p>La &nbsp;accionante, a trav\u00e9s de apoderado, impugn\u00f3 fincada en &nbsp;que \u00abSobre &nbsp; el &nbsp;particular, &nbsp;en &nbsp;la &nbsp;Sentencia &nbsp;SU-913 &nbsp;de &nbsp;2009 &nbsp; &nbsp;estableci\u00f3 &nbsp; que &nbsp;una &nbsp;lista &nbsp;de elegibles genera en las personas un derecho de &nbsp;car\u00e1cter subjetivo a ser nombradas en &nbsp;el &nbsp;cargo &nbsp;para &nbsp;el &nbsp; cual &nbsp;concursaron, &nbsp;cuando &nbsp;este &nbsp;quede &nbsp;vacante &nbsp;o &nbsp;est\u00e9 &nbsp; siendo desempe\u00f1ado por un funcionario en encargo o &nbsp;provisionalidad, de manera que la consolidaci\u00f3n del derecho &nbsp;\u201cse encuentra indisolublemente determinado por el lugar que se &nbsp;ocup\u00f3 dentro de la lista y el n\u00famero de plazas o &nbsp;vacantes a proveer\u201d, raz\u00f3n por &nbsp;la &nbsp;cual, &nbsp;las &nbsp;listas &nbsp; de &nbsp;elegibles, &nbsp;una &nbsp;vez &nbsp;publicadas &nbsp;y &nbsp;en &nbsp;firme, &nbsp;son &nbsp;inmodificables\u2026\u00bb12. &nbsp;Adem\u00e1s, afirm\u00f3 que \u00abAntes &nbsp;de desplegar la argumentaci\u00f3n propia del caso, huelga aclarar &nbsp;que el suscrito litigante, no ha interpuesto revocatoria directa de &nbsp;acto administrativo alguno, como equivocadamente lo expresa el &nbsp;Consejo Seccional de la Judicatura de Norte de Santander, simplemente &nbsp;y paralelo a la acci\u00f3n de tutela como mecanismo eminentemente &nbsp;transitorio, se incoaron los recursos de la actuaci\u00f3n &nbsp;administrativa (reposici\u00f3n, apelaci\u00f3n y queja)13\u00bb. &nbsp;<\/p>\n<p>V. &nbsp;CONSIDERACIONES &nbsp;<\/p>\n<p>1. En &nbsp;el sub &nbsp;examine, &nbsp;la &nbsp;actora pretende que \u00ab(\u2026) &nbsp;se proceda ordenar REVOCAR el ACUERDO CSJNS2022-160 de fecha 02 de &nbsp;marzo de 2022, mediante el cual intempestiva y abruptamente se &nbsp;modifica la lista de elegibles para el cargo de SECRETARIO JUZGADO DE &nbsp;CIRCUITO NOMINADO (\u2026)\u00bb. &nbsp;Adicionalmente, &nbsp;se revoque la resoluci\u00f3n No. 00314. &nbsp;<\/p>\n<p>2. &nbsp;Pronto la Sala &nbsp;advierte la improcedencia del amparo constitucional. Y, por tanto, la &nbsp;providencia impugnada habr\u00e1 de ser confirmada, por las razones &nbsp;que se exponen. &nbsp;<\/p>\n<p>3. &nbsp;Del an\u00e1lisis de los medios de convicci\u00f3n obrantes en el &nbsp;expediente, &nbsp;la Sala observa que frente al primer reproche no se satisface el &nbsp;presupuesto de subsidiariedad. Ello pues, la tutelante cuenta con la &nbsp;acci\u00f3n de nulidad y restablecimiento de derecho para hacer &nbsp;valer las prerrogativas que por esta v\u00eda reclama. E incluso, &nbsp;en dicha instancia puede solicitar la suspensi\u00f3n provisional &nbsp;de ciertos actos administrativos desde el momento de la presentaci\u00f3n &nbsp;de la demanda. Por tanto, al disponer la accionante de otros &nbsp;mecanismos para reclamar en favor de sus derechos, no le es dable &nbsp;acudir a esta acci\u00f3n constitucional pues, dado su car\u00e1cter &nbsp;residual y subsidiario no es el mecanismo apropiado para definir la &nbsp;pretensi\u00f3n invocada. &nbsp;<\/p>\n<p>4. &nbsp;Sumado a lo anterior, y en atenci\u00f3n a la queja frente a la &nbsp;resoluci\u00f3n 003, con la cual se dej\u00f3 sin efectos su &nbsp;nombramiento, se concluye tambi\u00e9n la improcedencia de la &nbsp;solicitud de amparo, pues la accionante interpuso recurso de &nbsp;reposici\u00f3n y, en subsidio apelaci\u00f3n15 &nbsp;frente a ese acto administrativo, los cuales se encuentran pendientes &nbsp;de resolverse. As\u00ed &nbsp;las cosas, no le es dable al Juez constitucional sustituir la &nbsp;competencia del juez natural y emitir una decisi\u00f3n anticipada, &nbsp;dado el car\u00e1cter subsidiario y residual que gobierna la acci\u00f3n &nbsp;tutelar.16 &nbsp;<\/p>\n<p>4.1. &nbsp;En todo caso, los motivos invocados por la tutelante no justifican &nbsp;acudir directamente a este mecanismo eminentemente residual, pues &nbsp;tampoco se configura un perjuicio irremediable. Ello pues, la &nbsp;Universidad Aut\u00f3noma del Caribe, en su respuesta, afirm\u00f3 &nbsp;que la actora tiene un contrato de trabajo vigente con dicha &nbsp;Instituci\u00f3n educativa17, &nbsp;de tal modo que no se encuentra en peligro su m\u00ednimo vital. &nbsp;<\/p>\n<p>5. &nbsp;Por &nbsp;lo expuesto, se confirmar\u00e1 el fallo impugnado. &nbsp;<\/p>\n<p>VI. &nbsp;DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Sala de Casaci\u00f3n Civil de la &nbsp;Corte Suprema de Justicia, en nombre de la Rep\u00fablica de &nbsp;Colombia y por autoridad de la ley, CONFIRMA &nbsp;la sentencia impugnada por improcedencia de la acci\u00f3n. &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;esta providencia a los interesados en la forma prevista por el &nbsp;art\u00edculo 30 del Decreto 2591 de 1991. Oportunamente, rem\u00edtase &nbsp;el &nbsp;expediente a la Corte Constitucional para su eventual revisi\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZMAN \u00c1LVAREZ &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folio 78. Archivo 03. ANEXOS TUTELA.pdf. Expediente digital. &nbsp;<\/p>\n<p>2\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Folio 81- 84. Archivo 03. ANEXOS TUTELA.pdf. &nbsp;<\/p>\n<p>3\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Acuerdo CSJNS2022-563 de diciembre 15 de 25021. &nbsp;<\/p>\n<p>4\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Acuerdo CSJNS2022-561 de diciembre 15 de 25021. &nbsp;<\/p>\n<p>5\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;CITAR donde esta &nbsp;<\/p>\n<p>6\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Ibidem. &nbsp;<\/p>\n<p>7\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Por medio de la cual se revoca el nombramiento al cargo de la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;accionante. &nbsp;<\/p>\n<p>8\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo 11.RESPUESTA JUZGADO PRIMERO CIVIL CTO OCA\u00d1A.pdf. &nbsp;<\/p>\n<p>9\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;15. RESPUESTAS CONSEJO SECCIONAL DE LA JUDICATURA.pdf. &nbsp;<\/p>\n<p>10\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;20. RESPUESTA UNIVERSIDAD AUTONOMA DEL CARIBE.pdf. &nbsp;<\/p>\n<p>11\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;28. SENTENCIA.pdf. &nbsp;<\/p>\n<p>12\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;30.ESCRITO IMPUGNACION ACCIONANTE.pdf. &nbsp;<\/p>\n<p>13\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Ibidem. &nbsp;<\/p>\n<p>14\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Por medio de la cual se revoca el nombramiento al cargo de la &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;accionante. &nbsp;<\/p>\n<p>15\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;30. ESCRITO DE IMPUGNACION.pdf y Archivo 11. RESPUESTA JUZGADO &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;PRIMERO CIVIL CTO OCA\u00d1A.pdf. &nbsp;<\/p>\n<p>16\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Al respecto, esta Corporaci\u00f3n ha sostenido que: &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>\u00ab(\u2026) &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;es palmario que la tutela no es un mecanismo que se pueda activar, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;seg\u00fan la discrecionalidad del interesado\u2026, para &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;reclamar prematuramente un pronunciamiento del juez constitucional, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;que le est\u00e1 vedado, por cuanto no puede arrogarse &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;anticipadamente facultades que no le corresponden, con miras a &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;decidir lo que debe resolver el funcionario competente (\u2026) &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;para que de una manera r\u00e1pida y eficaz se le proteja el &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;derecho fundamental al debido proceso\u2019, pues, reit\u00e9rase, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;no &nbsp;es este un instrumento del que pueda hacer uso antojadizamente &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;el interesado, ni mucho menos para eludir el que de manera &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;espec\u00edfica se\u00f1ale la ley (\u2026)\u00bb (ver &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;recientemente en STC11209-2020, 9 dic. 2020, rad. 2020-00472-01, &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;entre otras). &nbsp;<\/p>\n<p>17\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Archivo &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;20. RESPUESTA UNIVERSIDAD AUTONOMA DEL CARIBE.pdf. &nbsp;<\/p>\n<p>4 &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC5736-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; Magistrado &nbsp;Ponente &nbsp; STC5736-2022 &nbsp; Radicaci\u00f3n &nbsp;n.\u00b0 54001-22-13-000-2022-00094-01 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de once de mayo de dos mil veintid\u00f3s). &nbsp; Bogot\u00e1 &nbsp;D.C., once (11) de mayo de dos mil veintid\u00f3s (2022). &nbsp; La &nbsp;Corte decide la impugnaci\u00f3n interpuesta frente a la sentencia &nbsp;proferida por la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63482","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63482"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63482\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}