{"id":63579,"date":"2024-05-20T21:00:14","date_gmt":"2024-05-20T21:00:14","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc6006-2022\/"},"modified":"2024-05-20T21:00:14","modified_gmt":"2024-05-20T21:00:14","slug":"stc6006-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc6006-2022\/","title":{"rendered":"STC6006 2022"},"content":{"rendered":"<p>STC6006-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>Magistrada &nbsp;ponente &nbsp;<\/p>\n<p>STC6006-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 05000-22-21-000-2022-00011-01 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de dieciocho de mayo de dos mil veintid\u00f3s) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., dieciocho (18) de mayo de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>Decide &nbsp;la Corte la impugnaci\u00f3n de la sentencia &nbsp;proferida por la Sala &nbsp;Civil Especializada en Restituci\u00f3n de Tierras del Tribunal &nbsp;Superior del Distrito Judicial de Antioquia el 22 de abril de 2022, &nbsp;en la acci\u00f3n de tutela formulada por Miguel Samper Strouss &nbsp;contra el Juzgado Segundo Civil del Circuito Especializado en &nbsp;Restituci\u00f3n de Tierras de Antioquia, tr\u00e1mite al que &nbsp;fueron vinculadas las partes e intervinientes en el juicio especial a &nbsp;que alude el escrito originario, identificado bajo el consecutivo &nbsp;05000312100220140001800. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;peticionario reclam\u00f3 la &nbsp;protecci\u00f3n de los derechos fundamentales al debido &nbsp;proceso, acceso a la administraci\u00f3n de justicia &nbsp;y a la propiedad, &nbsp;presuntamente vulnerados por la autoridad judicial accionada. &nbsp;<\/p>\n<p>En &nbsp;s\u00edntesis relat\u00f3, que el Juzgado Segundo Civil del &nbsp;Circuito Especializado en Restituci\u00f3n de Tierras de Antioquia, &nbsp;profiri\u00f3 sentencia de restituci\u00f3n de 10 de diciembre de &nbsp;2014, en la que se impusieron \u00f3rdenes a cargo de la Agencia &nbsp;Nacional de Tierras, de la que era su Director, y posteriormente, por &nbsp;petici\u00f3n del solicitante protegido frente a la supuesta &nbsp;inobservancia de la orden pronunciada a su favor, se dio inicio al &nbsp;incidente de desacato regulado en esa especial normativa, del cual, &nbsp;asegura, nunca fue enterado, tr\u00e1mite en el que mediante auto &nbsp;de 25 de junio de 2018,le fue impuesta como sanci\u00f3n por &nbsp;incumplimiento, una multa equivalente a 10 salarios m\u00ednimos &nbsp;mensuales legales vigentes. &nbsp;<\/p>\n<p>Explic\u00f3, &nbsp;que el 3 de marzo de 2022, fue notificado del mandamiento de pago que &nbsp;en su contra dict\u00f3 la Divisi\u00f3n de Fondos Especiales y &nbsp;Cobro Coactivo de la Direcci\u00f3n Ejecutiva de Administraci\u00f3n &nbsp;Judicial, fundada en la multa impuesta en desarrollo del incidente de &nbsp;desacato memorado, del que, reitera, nunca fue informado. &nbsp;<\/p>\n<p>Manifest\u00f3 &nbsp;que acude al presente mecanismo excepcional, en busca de la &nbsp;protecci\u00f3n de los bienes jur\u00eddicos que invoc\u00f3, &nbsp;pues no es posible que hubiese sido sancionado en calidad de Director &nbsp;de la Agencia Nacional de Tierras, sin antes poder ejercer su &nbsp;leg\u00edtima defensa. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;Con &nbsp;fundamento en lo anteriormente expuesto, &nbsp;solicit\u00f3 que se &nbsp;ordene al Juzgado Segundo Civil del Circuito Especializado en &nbsp;Restituci\u00f3n de Tierras de Antioquia, dejar sin efecto la &nbsp;citada providencia adoptada en el tr\u00e1mite incidental para que, &nbsp;en consecuencia, se invalide todo lo actuado en el juicio compulsivo &nbsp;que a continuaci\u00f3n se adelant\u00f3. &nbsp;<\/p>\n<p>RESPUESTA &nbsp;DEL ACCIONADO Y LA VINCULADA &nbsp;<\/p>\n<p>1. &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;Juzgado Segundo Civil del Circuito Especializado en Restituci\u00f3n &nbsp;de Tierras de Antioquia se limit\u00f3 a remitir copia de las &nbsp;actuaciones surtidas en las diligencias incidentales. &nbsp;<\/p>\n<p>2. &nbsp; &nbsp; &nbsp; &nbsp;El &nbsp;abogado de la Oficina Jur\u00eddica de la Agencia Nacional de &nbsp;Tierras, puso de presente, que los autos a trav\u00e9s de los &nbsp;cuales se abri\u00f3 y se resolvi\u00f3 el mencionado incidente, &nbsp;s\u00ed fueron notificados a la entidad, seg\u00fan lo reportado &nbsp;en sus bases de datos y que para la fecha en que el mismo fue &nbsp;tramitado, quien obraba como Director, era el se\u00f1or Miguel &nbsp;Samper Strauss. &nbsp;<\/p>\n<p>LA &nbsp;SENTENCIA IMPUGNADA &nbsp;<\/p>\n<p>El &nbsp;Tribunal Superior de Antioquia, Sala Civil Especializada en &nbsp;Restituci\u00f3n de Tierras, neg\u00f3 la protecci\u00f3n &nbsp;constitucional al estimar el incumplimiento del presupuesto de &nbsp;subsidiariedad, por cuanto, \u00absi &nbsp;el accionante considera que no fue notificado o vinculado en debida &nbsp;forma al incidente de desacato que se adelant\u00f3 en su contra, &nbsp;tiene a su disposici\u00f3n el r\u00e9gimen de nulidades &nbsp;procesales consagrado en el cap\u00edtulo II del t\u00edtulo IV &nbsp;del C\u00f3digo General del Proceso, sin que se advierta que dentro &nbsp;del respectivo tr\u00e1mite incidental haya elevado petici\u00f3n &nbsp;alguna en tal sentido\u00bb. &nbsp;<\/p>\n<p>LA &nbsp;IMPUGNACI\u00d3N &nbsp;<\/p>\n<p>La &nbsp;formul\u00f3 el accionante insistiendo en los argumentos iniciales, &nbsp;adem\u00e1s de hacer \u00e9nfasis en la imposibilidad de ejercer &nbsp;las respectivas herramientas de contradicci\u00f3n frente a las &nbsp;decisiones de las que se queja, precisamente por no haber sido &nbsp;debidamente convocado al asunto donde estas fueron proferidas. &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>1. &nbsp;Consistentemente la Sala ha reiterado, que, por &nbsp;lineamiento jurisprudencial, &nbsp;este instrumento excepcional no procede respecto de providencias &nbsp;judiciales, salvo que el funcionario adopte una decisi\u00f3n por &nbsp;completo desviada del camino previamente se\u00f1alado, sin ninguna &nbsp;objetividad, afincado en sus particulares designios, a tal extremo &nbsp;que configure el proceder denominado v\u00eda de hecho, situaci\u00f3n &nbsp;frente a la cual se abre paso el amparo para restablecer las &nbsp;garant\u00edas esenciales conculcadas siempre y cuando se hayan &nbsp;agotado las v\u00edas ordinarias de defensa, dado el car\u00e1cter &nbsp;subsidiario y residual del amparo y, &nbsp;por supuesto, se observe el requisito de la inmediatez connatural a &nbsp;su ejercicio. (Ver &nbsp;entre muchas, STC11845-2021). &nbsp;<\/p>\n<p>2. En &nbsp;el asunto que ocupa la atenci\u00f3n de la Sala, el se\u00f1or &nbsp;Miguel Samper Strouss pretende &nbsp;que, a trav\u00e9s de este mecanismo excepcional, se deje sin &nbsp;efecto la providencia de 25 de junio de 2018, a trav\u00e9s del &nbsp;cual se le sancion\u00f3 porque la Agencia Nacional de Tierras &nbsp;(entidad que para esa fecha dirig\u00eda), no atendi\u00f3 lo &nbsp;dispuesto en la sentencia de restituci\u00f3n de tierras proferida &nbsp;el 10 de diciembre de 2014, como epilogo del juicio identificado con &nbsp;el consecutivo 2014-00018. &nbsp;<\/p>\n<p>3. &nbsp; &nbsp; &nbsp; &nbsp;No &nbsp;obstante, la Sala advierte la improcedibilidad del amparo, tal y como &nbsp;lo consider\u00f3 el a &nbsp;quo constitucional, &nbsp; ante el incumplimiento del presupuesto de la subsidiariedad que &nbsp;gobierna esta especial\u00edsima v\u00eda, en tanto que, de la &nbsp;revisi\u00f3n de las pruebas allegadas a este tr\u00e1mite, se &nbsp;evidencia que el accionante no ha acudido ante el juez de &nbsp;conocimiento con el fin de hacer uso del mecanismo previsto por el &nbsp;legislador para debatir la tem\u00e1tica que seg\u00fan afirma, &nbsp;afecta los derechos fundamentales que invoc\u00f3, este es, el &nbsp;concerniente incidente de nulidad, con base en lo dispuesto en el &nbsp;numeral 8 del canon 133 del C\u00f3digo General del Proceso (norma &nbsp;aplicable al asunto, de conformidad a lo normado en el art\u00edculo &nbsp;1 ejusdem). &nbsp;<\/p>\n<p>Tal &nbsp;omisi\u00f3n imposibilita el uso de este instrumento &nbsp;extraordinario, merced a que el &nbsp;accionante todav\u00eda &nbsp;cuenta con la facultad de &nbsp;ventilar en el estadio natural, la &nbsp;situaci\u00f3n irregular que ahora alega, circunstancia que &nbsp;desencadena la inviabilidad de la protecci\u00f3n, comoquiera que &nbsp;ha sido enf\u00e1tica esta Corte en se\u00f1alar, que &nbsp;<\/p>\n<p>\u00abno &nbsp;es admisible que el Juez de tutela se anticipe a una decisi\u00f3n &nbsp;que por competencia debe adoptar el juzgador natural; por tanto, el &nbsp;constitucional no puede invadir la competencia, despojando de las &nbsp;atribuciones asignadas v\u00e1lidamente al funcionario de &nbsp;conocimiento por el constituyente y el legislador, pues si fuera de &nbsp;otra manera, desconocer\u00eda el car\u00e1cter residual de esta &nbsp;senda y las normas de orden p\u00fablico, que son de obligatoria &nbsp;aplicaci\u00f3n, con la consiguiente alteraci\u00f3n de las &nbsp;reglas preestablecidas y el quebrantamiento de las prerrogativas de &nbsp;los intervinientes en tal causa (STC3840-2022). &nbsp;<\/p>\n<p>4. &nbsp;De &nbsp;conformidad con lo anterior, se confirmar\u00e1 la sentencia &nbsp;impugnada. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica de Colombia y por autoridad de la Ley, CONFIRMA &nbsp;la &nbsp;sentencia de fecha, naturaleza y procedencia conocida. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC6006-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; Magistrada &nbsp;ponente &nbsp; STC6006-2022 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 05000-22-21-000-2022-00011-01 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de dieciocho de mayo de dos mil veintid\u00f3s) &nbsp; Bogot\u00e1, &nbsp;D.C., dieciocho (18) de mayo de dos mil veintid\u00f3s (2022). &nbsp; Decide &nbsp;la Corte la impugnaci\u00f3n de la sentencia &nbsp;proferida por la Sala &nbsp;Civil Especializada en Restituci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63579","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63579"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63579\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}