{"id":63635,"date":"2024-05-20T21:00:16","date_gmt":"2024-05-20T21:00:16","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc6071-2022\/"},"modified":"2024-05-20T21:00:16","modified_gmt":"2024-05-20T21:00:16","slug":"stc6071-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc6071-2022\/","title":{"rendered":"STC6071 2022"},"content":{"rendered":"<p>STC6071-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>Magistrado &nbsp;ponente &nbsp;<\/p>\n<p>STC6071-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00b0 11001-02-30-000-2022-00691-00&nbsp; &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n virtual de dieciocho de mayo dos mil veintid\u00f3s).&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D. C., dieciocho (18) de mayo de dos mil veintid\u00f3s (2022).&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>Decide &nbsp;la Sala la acci\u00f3n de tutela instaurada por Glenen Alexander &nbsp;Ross frente a la Corte Constitucional. Al tr\u00e1mite se dispuso &nbsp;vincular a los intervinientes de la acci\u00f3n p\u00fablica de &nbsp;inconstitucionalidad de radicado D-14.732. &nbsp;<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>I. ANTECEDENTES &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>1. &nbsp;El gestor demand\u00f3 la salvaguarda de su garant\u00eda &nbsp;fundamental a la \u00abprotecci\u00f3n &nbsp;judicial\u00bb, &nbsp;presuntamente vulnerada por la autoridad convocada.&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>2. &nbsp;Del escrito inicial y las pruebas allegadas se resaltan los &nbsp;siguientes hechos y alegaciones relevantes:&nbsp; &nbsp;<\/p>\n<p>2.1. &nbsp;El 4 de marzo de 2022, el tutelante y Rosandy Colina Silgado &nbsp;promovieron una demanda de inconstitucionalidad contra el Decreto &nbsp;2591 de 1991, por considerar que sus \u00abefectos &nbsp;legales [\u2026] &nbsp;son [\u2026] nulos por el hecho de haber caducado el decreto &nbsp;reglamentario. Por tanto, las restricciones impuestas al ejercicio y &nbsp;goce del derecho de tutela [\u2026] son ileg\u00edtimas\u00bb. &nbsp;<\/p>\n<p>2.2. &nbsp;El 29 de marzo de 2022, la Corte Constitucional inadmiti\u00f3 la &nbsp;demanda y les concedi\u00f3 tres (3) d\u00edas, para subsanar las &nbsp;falencias evidenciadas en la inadmisi\u00f3n. &nbsp;<\/p>\n<p>2.3. &nbsp;El 4 abril de 2022, los all\u00e1 demandantes presentaron un &nbsp;escrito de subsanaci\u00f3n de la demanda; no obstante, el 27 de &nbsp;abril siguiente fue rechazada. &nbsp;<\/p>\n<p>2.4. &nbsp;Al respecto, el promotor censura \u00abla &nbsp;omisi\u00f3n de realizar de oficio una revisi\u00f3n efectiva de &nbsp;control de convencionalidad entre el Decreto 2591\/91 y la CADH por &nbsp;parte de cualquier persona involucrada en la administraci\u00f3n de &nbsp;justicia del Estado Parte genera la responsabilidad internacional de &nbsp;dicho Estado por el incumplimiento de los art\u00edculos 1 (1) y 2 &nbsp;CADH. [\u2026]\u00bb.&nbsp;&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>II. RESPUESTAS &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;RECIBIDAS &nbsp;<\/p>\n<p>1. &nbsp;La Vicepresidencia de la Corte Constitucional realiz\u00f3 un &nbsp;recuento de las actuaciones surtidas y resalt\u00f3 que, el 4 de &nbsp;mayo del presente a\u00f1o, la se\u00f1ora Rosandy Colina Silgado &nbsp;present\u00f3 un recurso de s\u00faplica, el cual estaba en &nbsp;tr\u00e1mite. &nbsp;<\/p>\n<p>2. &nbsp;La se\u00f1ora Rosandy Colina Silgado respald\u00f3 las &nbsp;pretensiones del ac\u00e1 accionante. &nbsp;<\/p>\n<p>III. &nbsp;CONSIDERACIONES&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>1. &nbsp;En el sub &nbsp;examine, &nbsp;el tutelante reclam\u00f3 el amparo de sus derechos fundamentales, &nbsp;que considera vulnerados por la Corte Constitucional, al proferir el &nbsp;auto de 27 de abril del a\u00f1o en curso, &nbsp;por el cual rechaz\u00f3 la acci\u00f3n formulada contra &nbsp;el Decreto 2591 de 1991. &nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>2. &nbsp;Frente al particular, se advierte que la salvaguarda impetrada carece &nbsp;de vocaci\u00f3n de prosperidad, toda vez que, seg\u00fan lo &nbsp;informado por la autoridad accionada1, &nbsp;el 4 de mayo de la presente anualidad la se\u00f1ora Rosandy Colina &nbsp;Silgado interpuso recurso de s\u00faplica contra el prove\u00eddo &nbsp;del pasado 27 de abril de 2022, el cual se encontraba sujeto a &nbsp;tr\u00e1mite a la fecha de interposici\u00f3n de la presente &nbsp;salvaguarda -4 de mayo- y, por tanto, el asunto debe ser decidido por &nbsp;el juez competente y no por el de tutela.&nbsp; &nbsp;<\/p>\n<p>En &nbsp;relaci\u00f3n con lo anterior, la Sala ha se\u00f1alado que la &nbsp;tutela no es un mecanismo que se pueda utilizar&nbsp;\u00ab(\u2026) &nbsp;para reclamar prematuramente un pronunciamiento del juez &nbsp;constitucional, que le est\u00e1 vedado, por cuanto no puede &nbsp;arrogarse anticipadamente facultades que no le corresponden, con &nbsp;miras a decidir lo que debe resolver el funcionario competente (\u2026)\u00bb &nbsp;(ver &nbsp;cita en STC8255-2018 &nbsp;y STC11209-2020).&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>Igualmente, &nbsp;la Sala ha sostenido que es apresurado instaurar una acci\u00f3n de &nbsp;tutela, \u00absin &nbsp;siquiera conocer cu\u00e1l era la postura jur\u00eddica del &nbsp;examinador [natural], desatendi\u00e9ndola de antemano, am\u00e9n &nbsp;de soslayar el car\u00e1cter residual y subsidiario que la presente &nbsp;v\u00eda alberga, esto por un lado; y, por otro, en virtud de que &nbsp;el [togado correspondiente] es quien est\u00e1 encargado de revisar &nbsp;lo concerniente al tema aqu\u00ed planteado, conforme as\u00ed lo &nbsp;determinan las reglas de competencia\u00bb &nbsp;(ver cita en STC5325-2019).&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>3. &nbsp;Por las razones antes anotadas, se debe negar la salvaguarda &nbsp;impetrada, por improcedente. &nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>V. &nbsp;DECISI\u00d3N&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica y por mandato de la ley, NIEGA &nbsp;el &nbsp;amparo invocado, por improcedente.&nbsp;&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>Comun\u00edquese &nbsp;lo resuelto en esta providencia a los interesados, por el medio m\u00e1s &nbsp;expedito, de conformidad con lo previsto en el art\u00edculo 30 del &nbsp;Decreto 2591 de 1991, y oportunamente env\u00edese el expediente a &nbsp;la Corte Constitucional, para su eventual revisi\u00f3n, en caso de &nbsp;no ser impugnada.&nbsp; &nbsp;<\/p>\n<p>&nbsp; &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp;<\/p>\n<p>1\u0002 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;De &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;conformidad con lo previsto en el art\u00edculo 19 Decreto 2591 de &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;1991, \u00ablos &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;informes se consideran rendidos bajo juramento\u00bb. &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC6071-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; Magistrado &nbsp;ponente &nbsp; STC6071-2022 &nbsp; Radicaci\u00f3n &nbsp;n\u00b0 11001-02-30-000-2022-00691-00&nbsp; &nbsp; (Aprobado &nbsp;en sesi\u00f3n virtual de dieciocho de mayo dos mil veintid\u00f3s).&nbsp; &nbsp; &nbsp; &nbsp; Bogot\u00e1, &nbsp;D. C., dieciocho (18) de mayo de dos mil veintid\u00f3s (2022).&nbsp; &nbsp; &nbsp; &nbsp; Decide &nbsp;la Sala la acci\u00f3n de tutela instaurada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63635","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63635"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63635\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}