{"id":63707,"date":"2024-05-20T21:00:18","date_gmt":"2024-05-20T21:00:18","guid":{"rendered":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc6328-2022\/"},"modified":"2024-05-20T21:00:18","modified_gmt":"2024-05-20T21:00:18","slug":"stc6328-2022","status":"publish","type":"post","link":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/2024\/05\/20\/stc6328-2022\/","title":{"rendered":"STC6328 2022"},"content":{"rendered":"<p>STC6328-2022<\/p>\n<p>&nbsp; &nbsp; &nbsp; &nbsp;&nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>Magistrado &nbsp;ponente &nbsp;<\/p>\n<p>STC6328-2022 &nbsp;<\/p>\n<p>Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2022-01489-00 &nbsp;<\/p>\n<p>(Aprobado &nbsp;en sesi\u00f3n de veinticinco de mayo de dos mil veintid\u00f3s) &nbsp;<\/p>\n<p>Bogot\u00e1, &nbsp;D.C., veinticinco (25) de mayo de dos mil veintid\u00f3s (2022). &nbsp;<\/p>\n<p>Se &nbsp;resuelve la tutela que promovi\u00f3 Celso Guevara Rivera, quien &nbsp;adujo actuar como apoderado de Jairo de Jes\u00fas S\u00e1nchez &nbsp;Uribe, Sim\u00f3n Andr\u00e9s S\u00e1nchez Betancourt, Cristian &nbsp;Andr\u00e9s S\u00e1nchez Arbel\u00e1ez, Diana Patricia &nbsp;Betancourt, Nelly del Socorro Trujillo Montoya, Luis Gabriel &nbsp;Betancourt Trujillo y William Alberto S\u00e1nchez Uribe instaur\u00f3 &nbsp;contra la Sala Civil del Tribunal Superior de Bogot\u00e1, &nbsp;extensiva al Juzgado 40 Civil del Circuito de la misma ciudad y a las &nbsp;partes e intervinientes en el proceso de responsabilidad No. &nbsp;2019-00032-00. &nbsp;<\/p>\n<p>ANTECEDENTES &nbsp;<\/p>\n<p>1. &nbsp;El gestor &nbsp;solicit\u00f3 que se dejen sin valor y efecto las sentencias &nbsp;emitidas en primera (2 septiembre 2021) y segunda instancia (10 marzo &nbsp;2022) en el proceso en comento para que, en su lugar, se emita una &nbsp;providencia soportada en una adecuada valoraci\u00f3n probatoria. &nbsp;<\/p>\n<p>En &nbsp;sustento adujo que sus agenciados promovieron proceso de &nbsp;responsabilidad civil extracontractual contra Caracol Televisi\u00f3n &nbsp;S.A. por la publicaci\u00f3n, sin autorizaci\u00f3n, de la imagen &nbsp;de un menor que falleci\u00f3. Las pretensiones fuero desestimadas &nbsp;por el Juzgado 40 Civil del Circuito de Bogot\u00e1 (2 septiembre &nbsp;2021) y aunque instauraron recurso de apelaci\u00f3n, el Tribunal &nbsp;confirm\u00f3 la determinaci\u00f3n. A su juicio, las autoridades &nbsp;judiciales incurrieron en falta de motivaci\u00f3n y defecto &nbsp;f\u00e1ctico, toda vez que desconocieron lo se\u00f1alado en los &nbsp;alegatos de conclusi\u00f3n en donde se hizo el recuento de todas &nbsp;las emisiones que efectu\u00f3 la demandada, en las cuales aludi\u00f3 &nbsp;a las supuestas causas de muerte del menor, con lo cual afect\u00f3 &nbsp;su buen nombre e increment\u00f3 el dolor de la familia. &nbsp;<\/p>\n<p>2. &nbsp;2. El &nbsp;Juzgado 40 Civil del Circuito de Bogot\u00e1 hizo un recuento de &nbsp;las actuaciones surtidas en el proceso en comento; adem\u00e1s, &nbsp;defendi\u00f3 la legalidad de su actuaci\u00f3n. Zurich Colombia &nbsp;Seguros S.A., Chubb Seguros Colombia S.A. y Caracol Televisi\u00f3n &nbsp;S.A. coincidieron en se\u00f1alar que el amparo impetrado no cumple &nbsp;con los requisitos necesarios para la procedencia de la acci\u00f3n &nbsp;de tutela contra providencias judiciales. El Instituto Nacional de &nbsp;Medicina Legal y Ciencias Forenses manifest\u00f3 que no ha &nbsp;vulnerado derechos fundamentales de los gestores. Por su parte, el &nbsp;Tribunal convocado defendi\u00f3 la razonabilidad de la sentencia &nbsp;que emiti\u00f3 en el proceso referido.&nbsp; &nbsp;<\/p>\n<p>CONSIDERACIONES &nbsp;<\/p>\n<p>El &nbsp;amparo se negar\u00e1 toda vez que el accionante no ostenta &nbsp;legitimaci\u00f3n en la causa por activa dentro del presente &nbsp;asunto. A pesar de la informalidad que se impone en este tipo de &nbsp;tr\u00e1mite preferente y sumario, el legislador ha establecido &nbsp;unas directrices encaminadas a identificar a los sujetos que se &nbsp;hallan facultados para incoarlo, ello, en aras de velar por su &nbsp;adecuado y efectivo empleo. As\u00ed, el art\u00edculo 10\u00ba &nbsp;del Decreto 2591 de 1991 consagr\u00f3: LEGITIMIDAD &nbsp;E INTER\u00c9S. &nbsp;La acci\u00f3n de tutela podr\u00e1 ser ejercida, en todo momento &nbsp;y lugar, por cualquiera persona vulnerada o amenazada en uno de sus &nbsp;derechos fundamentales, quien actuar\u00e1 por s\u00ed misma o &nbsp;a trav\u00e9s de representante. Los poderes se presumir\u00e1n &nbsp;aut\u00e9nticos. &nbsp;Tambi\u00e9n &nbsp;se pueden agenciar derechos ajenos cuando el titular de los mismos no &nbsp;est\u00e9 en condiciones de promover su propia defensa. &nbsp;Cuando tal circunstancia ocurra, deber\u00e1 &nbsp;manifestarse en la solicitud.Tambi\u00e9n &nbsp;podr\u00e1 ejercerla el Defensor del Pueblo y los personeros &nbsp;municipales. &nbsp;(Resaltado &nbsp;propio) &nbsp;<\/p>\n<p>Tal &nbsp;es la trascendencia del asunto que esta Corte ha sentado sobre el &nbsp;particular que: &nbsp;<\/p>\n<p>(\u2026) &nbsp;[C]iertamente, aunque el art\u00edculo 10 del Decreto 2591 de 1991, &nbsp;establece que \u201ccualquier persona\u201d puede acudir a la &nbsp;referida acci\u00f3n, no debe desconocerse, que a rengl\u00f3n &nbsp;seguido condiciona su legitimaci\u00f3n a que ella sea la &nbsp;\u201cvulnerada o amenazada en uno de sus derechos fundamentales\u201d, &nbsp;no &nbsp;el de terceros, &nbsp;como as\u00ed tambi\u00e9n se menciona en el [canon] 86 de la &nbsp;Constituci\u00f3n Pol\u00edtica, al decir que a tal mecanismo &nbsp;s\u00f3lo puede acudir quien le hayan sido \u201cvulnerados o &nbsp;amenazados\u201d aquellos (\u2026)\u201d STC 13 dic. 2011, Rad. &nbsp;13001 22 13 000 2011 00284 02, reiterada en STC2657-2021 &nbsp;<\/p>\n<p>As\u00ed &nbsp;las cosas, revisado el escrito de tutela se observa que Celso &nbsp;Guevara Rivera manifest\u00f3 &nbsp;obrar en este asunto &nbsp;en calidad &nbsp;de &nbsp;apoderado &nbsp;de &nbsp;Jairo &nbsp;de Jes\u00fas S\u00e1nchez Uribe, Sim\u00f3n Andr\u00e9s &nbsp;S\u00e1nchez Betancourt, Cristian Andr\u00e9s S\u00e1nchez &nbsp;Arbel\u00e1ez, Diana Patricia Betancourt, Nelly del Socorro &nbsp;Trujillo Montoya, Luis Gabriel Betancourt Trujillo y William Alberto &nbsp;S\u00e1nchez Uribe; sin embargo, el accionante no ostenta la &nbsp;representaci\u00f3n de las prerrogativas fundamentales que invoca, &nbsp;toda vez que aunque \u00e9l act\u00faa como apoderado en el &nbsp;proceso de responsabilidad civil extracontractual cuestionado por &nbsp;esta senda, lo cierto es que no se vislumbra que hubiera sido &nbsp;facultado por los demandantes para promover el amparo constitucional. &nbsp;<\/p>\n<p>En &nbsp;efecto, los derechos que eventualmente puedan resultar lesionados con &nbsp;ocasi\u00f3n del pleito que se somete a revisi\u00f3n, pertenecen &nbsp;a quienes all\u00ed detentan la calidad de partes y no a sus &nbsp;mandatarios judiciales, quienes de ninguna manera act\u00faan ante &nbsp;la jurisdicci\u00f3n en defensa de atributos propios, sino en &nbsp;ejercicio de la postulaci\u00f3n que les asiste. En ese orden, si &nbsp;lo que pretend\u00eda el accionante era actuar en este tr\u00e1mite &nbsp;como representante de quienes fungen como sus prohijados en el &nbsp;proceso de responsabilidad mencionado, bien pudo hacerlo, pero con el &nbsp;lleno de los requisitos que para ese evento dispuso el legislador, en &nbsp;concreto, aportando el poder especial que para esta salvaguarda le &nbsp;fuere otorgado. &nbsp;<\/p>\n<p>Ahora, &nbsp;el eventual &nbsp;suceso &nbsp;de figurar como apoderado especial dentro del juicio de &nbsp;responsabilidad, no facultaba al abogado para la interposici\u00f3n &nbsp;de esta acci\u00f3n, pues como bien se ha expresado en otras &nbsp;ocasiones \u00abcuando &nbsp;la acci\u00f3n de tutela se ejerce a t\u00edtulo de otro, es &nbsp;necesario contar con poder especial para legitimar su &nbsp;interposici\u00f3n. &nbsp;La carencia de la citada personer\u00eda para iniciar la acci\u00f3n &nbsp;de amparo constitucional, no &nbsp;se suple &nbsp;con la presentaci\u00f3n del apoderamiento otorgado para un asunto &nbsp;diferente. La &nbsp;falta de poder especial &nbsp;para adelantar el proceso de tutela por parte de un apoderado &nbsp;judicial, aun cuando tenga poder espec\u00edfico o general en otros &nbsp;asuntos, no &nbsp;lo habilita &nbsp;para ejercer la acci\u00f3n de amparo constitucional a nombre de su &nbsp;mandante\u00bb &nbsp;(CSJ SC, 4 de mayo de 2012, rad. 00145-01, reiterada en &nbsp;STC10249-2018, 10 ago. 2018, rad. 00130-01) &nbsp;<\/p>\n<p>Finalmente, &nbsp;del escrito de tutela no se contempla o infiere circunstancia &nbsp;particular que tenga la virtud de impedir que los eventuales &nbsp;afectados acudan de manera directa a este mecanismo supra legal, &nbsp;suceso que eventualmente har\u00eda posible la participaci\u00f3n &nbsp;del censor bajo el manto de la agencia oficiosa, figura sobre la cual &nbsp;se tiene dicho: &nbsp;<\/p>\n<p>(\u2026) &nbsp;En lo atinente a la \u2018agencia oficiosa\u2019, bueno es recordar &nbsp;que el canon pertinente, art\u00edculo 10, Decreto 2591 de 1991, &nbsp;exige la demostraci\u00f3n de la imposibilidad &nbsp;de los agenciados de promover su propia defensa y la afirmaci\u00f3n &nbsp;de la raz\u00f3n de tal circunstancia en el escrito en que se pide &nbsp;la protecci\u00f3n, tal como con insistencia lo ha interpretado la &nbsp;Sala. &nbsp;(STC2657-2021). &nbsp;Resaltado de ahora. &nbsp;<\/p>\n<p>DECISI\u00d3N &nbsp;<\/p>\n<p>En &nbsp;m\u00e9rito de lo expuesto, la Corte Suprema de Justicia, en Sala &nbsp;de Casaci\u00f3n Civil, administrando justicia en nombre de la &nbsp;Rep\u00fablica y por autoridad de la Constituci\u00f3n, &nbsp;resuelve: &nbsp;NEGAR por improcedente la &nbsp;tutela instada. &nbsp;Inf\u00f3rmese &nbsp;a los participantes por el medio m\u00e1s expedito y rem\u00edtase &nbsp;el paginario a la Corte Constitucional para su eventual revisi\u00f3n, &nbsp;de no impugnarse esta resoluci\u00f3n. &nbsp;<\/p>\n<p>NOTIF\u00cdQUESE &nbsp;Y C\u00daMPLASE &nbsp;<\/p>\n<p>HILDA &nbsp;GONZ\u00c1LEZ NEIRA &nbsp;<\/p>\n<p>Presidente &nbsp;de Sala &nbsp;<\/p>\n<p>MARTHA &nbsp;PATRICIA GUZM\u00c1N \u00c1LVAREZ &nbsp;<\/p>\n<p>AROLDO &nbsp;WILSON QUIROZ MONSALVO &nbsp;<\/p>\n<p>LUIS &nbsp;ALONSO RICO PUERTA &nbsp;<\/p>\n<p>OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp;<\/p>\n<p>FRANCISCO &nbsp;TERNERA BARRIOS &nbsp; &nbsp; &nbsp;<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>STC6328-2022 &nbsp; &nbsp; &nbsp; &nbsp;&nbsp; OCTAVIO &nbsp;AUGUSTO TEJEIRO DUQUE &nbsp; Magistrado &nbsp;ponente &nbsp; STC6328-2022 &nbsp; Radicaci\u00f3n &nbsp;n\u00ba 11001-02-03-000-2022-01489-00 &nbsp; (Aprobado &nbsp;en sesi\u00f3n de veinticinco de mayo de dos mil veintid\u00f3s) &nbsp; Bogot\u00e1, &nbsp;D.C., veinticinco (25) de mayo de dos mil veintid\u00f3s (2022). &nbsp; Se &nbsp;resuelve la tutela que promovi\u00f3 Celso Guevara Rivera, quien &nbsp;adujo actuar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-63707","post","type-post","status-publish","format-standard","hentry","category-mayo-2022"],"_links":{"self":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/comments?post=63707"}],"version-history":[{"count":0,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/posts\/63707\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/media?parent=63707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/categories?post=63707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dmsjuridica.com\/buscador_20179478954\/salacivil\/wp-json\/wp\/v2\/tags?post=63707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}